{"id":2243,"count":2,"description":"","link":"https:\/\/legrandcontinent.eu\/it\/p\/anna-colin-lebedev\/","name":"Anna Colin Lebedev","slug":"anna-colin-lebedev","taxonomy":"staff","meta":[],"acf":{"name_title":"","first_name":"Anna Colin","last_name":"Lebedev","key_figure_template":"","cardinal_type":[],"picture":16775,"job_role":"Professoressa in scienze politiche","lgc_editorial_staff":false,"full_description":"Le sue ricerche si concentrano sulle societ\u00e0 post-sovietiche, con particolare attenzione ai conflitti armati e alle azioni di protesta.\r\n\r\nHa diretto il Centro franco-bielorusso di studi europei a Minsk tra il 2012 e il 2014. Attualmente dirige il master in \u00abManagement del rischio\/rischi, sicurezza e conflitti\u00bb presso l'Universit\u00e0 di Parigi Nanterre.","side_image":null,"side_text_1":"","side_text_2":"","page_content":"","linkedin_url":"","twitter_url":"","articles_authored":[27488],"articles_interviewed":null,"articles_speech_author":null,"books_authored":null,"events_authored":null,"videos_authored":null,"posts_related":null,"events_related":null,"elections_related":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Anna Colin Lebedev Archivi - Il Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/it\/p\/anna-colin-lebedev\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anna Colin Lebedev Archivi - Il Grand Continent\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/it\/p\/anna-colin-lebedev\/\" \/>\n<meta property=\"og:site_name\" content=\"Il Grand Continent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/p\/anna-colin-lebedev\/\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/p\/anna-colin-lebedev\/\",\"name\":\"Anna Colin Lebedev Archivi - Il Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/p\/anna-colin-lebedev\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/p\/anna-colin-lebedev\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anna Colin Lebedev\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/\",\"name\":\"Il Grand Continent\",\"description\":\"La scala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anna Colin Lebedev Archivi - Il Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/it\/p\/anna-colin-lebedev\/","og_locale":"it_IT","og_type":"article","og_title":"Anna Colin Lebedev Archivi - Il Grand Continent","og_url":"https:\/\/legrandcontinent.eu\/it\/p\/anna-colin-lebedev\/","og_site_name":"Il Grand Continent","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/legrandcontinent.eu\/it\/p\/anna-colin-lebedev\/","url":"https:\/\/legrandcontinent.eu\/it\/p\/anna-colin-lebedev\/","name":"Anna Colin Lebedev Archivi - Il Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/it\/#website"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/it\/p\/anna-colin-lebedev\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/it\/p\/anna-colin-lebedev\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/it\/"},{"@type":"ListItem","position":2,"name":"Anna Colin Lebedev"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/it\/#website","url":"https:\/\/legrandcontinent.eu\/it\/","name":"Il Grand Continent","description":"La scala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"first_name":"Anna Colin","last_name":"Lebedev","picture":{"url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2023\/12\/Anna-230x345-1.png","width":230,"height":345,"alt":""},"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/staff\/2243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/staff"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/taxonomies\/staff"}],"acf:post":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts\/27488"}],"wp:post_type":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts?staff=2243"},{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/sunday?staff=2243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}