{"id":686,"date":"2020-12-23T15:21:02","date_gmt":"2020-12-23T15:21:02","guid":{"rendered":"https:\/\/legrandcontinent.eu\/ita\/?p=686"},"modified":"2020-12-23T18:34:43","modified_gmt":"2020-12-23T18:34:43","slug":"leuropeizzazione-del-sistema-politico-americano-e-le-sue-conseguenze","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/it\/2020\/12\/23\/leuropeizzazione-del-sistema-politico-americano-e-le-sue-conseguenze\/","title":{"rendered":"L\u2019europeizzazione del sistema politico americano e le sue conseguenze"},"content":{"rendered":"\n<p class=\"has-drop-cap\">La chiave di lettura dominante della politica americana negli ultimi due decenni \u00e8 stata la <a href=\"https:\/\/simonandschusterpublishing.com\/why-were-polarized\/\" target=\"_blank\" rel=\"noreferrer noopener\">polarizzazione<\/a>. Gli stati Uniti sarebbero un paese diviso in due, tra Democratici e Repubblicani, coste e terre di mezzo, citt\u00e0 e zone extraurbane.<\/p>\n\n\n\n<p>La vittoria di Biden appare tuttavia difficile da conciliare con questo schema: la sua campagna elettorale ha insistito nel presentarlo come <a href=\"https:\/\/www.latimes.com\/politics\/story\/2020-08-12\/harris-biden-different-generation-similar-political-instinct\" target=\"_blank\" rel=\"noreferrer noopener\">centrista moderato<\/a>, mentre la polarizzazione implicherebbe uno svuotamento dell\u2019area di centro.&nbsp;<\/p>\n\n\n\n<p>Vi \u00e8 senz\u2019altro una componente <a href=\"https:\/\/www.pewresearch.org\/fact-tank\/2020\/11\/06\/2020-election-reveals-two-broad-voting-coalitions-fundamentally-at-odds\/\" target=\"_blank\" rel=\"noreferrer noopener\">anti-Trump<\/a> nel voto per Biden. Ma nemmeno questo rende conto di come il futuro Presidente degli Stati Uniti abbia potuto imporsi sull\u2019ala pi\u00f9 radicale del suo partito, rappresentata da candidati come Bernie Sanders, Elizabeth Warren, e ora Alexandria Ocasio Cortez.&nbsp;<\/p>\n\n\n\n<p>Per spiegare la vittoria di Biden \u2013 e anticiparne qualche conseguenza \u2013 \u00e8 necessario aprire le \u2018scatole nere\u2019 rappresentate dai due poli artificialmente creati dallo schema della polarizzazione. Cos\u00ec facendo, si scoprir\u00e0 immediatamente che in America esistono almeno <a href=\"https:\/\/www.theguardian.com\/commentisfree\/2020\/nov\/16\/american-politics-is-now-a-four-way-struggle-gridlock-lies-ahead\" target=\"_blank\" rel=\"noreferrer noopener\">quattro poli ideologici<\/a> distinti.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Per spiegare la vittoria di Biden \u2013 e anticiparne qualche conseguenza \u2013 \u00e8 necessario aprire le \u2018scatole nere\u2019 rappresentate dai due poli artificialmente creati dallo schema della polarizzazione.<\/p><cite>CARLO INVERNIZZI ACCETTI<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Ci\u00f2 disegna uno schema multi-polare che ricorda pi\u00f9 i sistemi politici pluralisti dell\u2019Europa continentale del secolo scorso rispetto al bi-polarismo caratteristico dei sistemi politici anglosassoni. Approfondire quest\u2019analogia con l\u2019Europa di ieri offre ulteriori spunti per capire cosa aspettarsi dagli Stati Uniti di domani.&nbsp;<\/p>\n\n\n\n<p>Partendo da sinistra, troviamo prima di tutto una corrente progressista all\u2019interno del partito Democratico Americano che si ispira esplicitamente alla <a href=\"https:\/\/moderndiplomacy.eu\/2020\/06\/12\/sanders-and-social-democracy\/\" target=\"_blank\" rel=\"noreferrer noopener\">tradizione socialdemocratica<\/a> Europea. Le sue proposte di spicco \u2013 come ad esempio il \u2018<a href=\"https:\/\/berniesanders.com\/issues\/medicare-for-all\/\" target=\"_blank\" rel=\"noreferrer noopener\">Medicare for All<\/a>\u2019 e il \u2018<a href=\"https:\/\/ocasio-cortez.house.gov\/gnd\/resolution\" target=\"_blank\" rel=\"noreferrer noopener\">Green New Deal<\/a>\u2019 \u2013 possono apparire radicali negli Stati Uniti, ma in realt\u00e0 corrispondono a una forma di welfarismo abbastanza classico da un punto vista Europeo.&nbsp;<\/p>\n\n\n\n<p>Spostandosi pi\u00f9 verso il centro, si incontra una corrente pi\u00f9 moderata dei Democratici che per molti versi ricorda i vecchi <a href=\"https:\/\/foreignpolicy.com\/2020\/03\/16\/joe-biden-election-liberal-moderate-christian-democrat\/\" target=\"_blank\" rel=\"noreferrer noopener\">partiti della Democrazia Cristiana Europea<\/a>. Oltre al fatto che Joe Biden ha dichiarato esplicitamente di trarre \u2018ispirazione\u2019 dalla sua fede cattolica nella sua offerta politica, in essa si ritrovano molti elementi dell\u2019ideologia caratteristica dei partiti democristiani di una volta: dal centrismo che si pone come \u2018terza via\u2019 tra la sinistra e destra estreme, fino all&#8217;obiettivo di ricomposizione dell\u2019armonia sociale secondo una concezione organicistica del corpo politico, condensata nello slogan \u2018<a href=\"https:\/\/www.ft.com\/content\/95268089-1178-4bbe-b41f-ce3e3d5dac8a\" target=\"_blank\" rel=\"noreferrer noopener\">Restore the Soul of America<\/a>\u2019.&nbsp;<\/p>\n\n\n\n<p>Passando poi dall\u2019altro lato del versante politico americano, si incontra prima di tutto una corrente di <a href=\"https:\/\/www.nhbr.com\/traditional-republican-values\/\" target=\"_blank\" rel=\"noreferrer noopener\">Repubblicani tradizionali<\/a>, rimasta sommersa durante gli ultimi quattro anni, ma che ora sembra destinata a riemergere insieme alle ambizioni politiche di figure come Mitt Romney o Mitch McConnell. Pi\u00f9 liberista in ambito economico e socialmente conservatrice rispetto ai Democratici moderati, questa corrente ideologica ha pi\u00f9 di un aspetto in comune con l\u2019orientamento storico dei <a href=\"https:\/\/www.cambridge.org\/core\/books\/liberal-parties-in-western-europe\/63066D0B89CB43A997874F0D3D687E01\" target=\"_blank\" rel=\"noreferrer noopener\">partiti liberali dell\u2019Europa continentale<\/a>.&nbsp;<\/p>\n\n\n\n<p>Per finire, all\u2019estrema destra del sistema politico statunitense di oggi troviamo una forma di <a href=\"https:\/\/www.jstor.org\/stable\/10.14321\/rhetpublaffa.22.3.0343#metadata_info_tab_contents\" target=\"_blank\" rel=\"noreferrer noopener\">nazionalismo populista<\/a> fino a poco tempo fa considerata estranea alla cultura politica degli Stati Uniti, ma fin troppo nota dall\u2019altro lato dell\u2019Atlantico. Nonostante vi sia ancora disaccordo tra gli esperti se il trumpismo possa essere adeguatamente descritto come forma di <a href=\"https:\/\/foreignpolicy.com\/2020\/07\/08\/trumps-mount-rushmore-speech-fascist-politics-zeev-sternhell\/\" target=\"_blank\" rel=\"noreferrer noopener\">proto- o neo-fascismo<\/a>, \u00e8 evidente che rappresenta una trasformazione radicale di ci\u00f2 che viene considerato politicamente accettabile nel nuovo continente.&nbsp;<\/p>\n\n\n\n<p>Nella misura in cui queste analogie permettono di parlare di una \u2018europeizzazione\u2019 del sistema politico americano, appare anche plausibile cercare nel repertorio della scienza politica europea categorie pi\u00f9 adeguate a descrivere la situazione attuale negli Stati Uniti.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Nella misura in cui queste analogie permettono di parlare di una \u2018europeizzazione\u2019 del sistema politico americano appare anche plausibile cercare nel repertorio della scienza politica europea categorie pi\u00f9 adeguate a descrivere la situazione attuale negli Stati Uniti.<\/p><cite>CARLO INVERNIZZI ACCETTI<\/cite><\/blockquote><\/figure>\n\n\n\n<p>In particolare, appare illuminante il concetto di \u201c<a href=\"https:\/\/www.degruyter.com\/princetonup\/view\/book\/9781400875337\/10.1515\/9781400875337-006.xml\" target=\"_blank\" rel=\"noreferrer noopener\">pluralismo polarizzato<\/a>\u201d coniato da Giovanni Sartori durante gli anni \u201960 per spiegare l\u2019<em>impasse<\/em> politica della Prima Repubblica italiana. La tesi di fondo \u00e8 che in contesti di alta frammentazione sociale e ideologica tendono a prodursi due conseguenze principali:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Una competizione politica \u201ccentrifuga\u201d, dato che le forze ai due estremi dello spettro politico hanno interesse a distinguersi dalle altre avanzando proposte sempre pi\u00f9 radicali, con poche probabilit\u00e0 di doverle mettere in pratica concretamente.&nbsp;<\/li><\/ol>\n\n\n\n<ol class=\"wp-block-list\" start=\"2\"><li>Una coalizione di governo \u201ccentripeta\u201d, dato che le varie forze moderate sono costrette a cooperare tra loro per assenza di alternative percorribili, facendo perno sulle poche cose che hanno in comune, cio\u00e8 una difesa dello status quo e del sistema istituzionale.&nbsp;<\/li><\/ol>\n\n\n\n<p>La combinazione di queste due tendenze spiega ci\u00f2 che Sartori descrisse come \u201cl\u2019immobilismo\u201d della Prima Repubblica italiana. Ora, qualcosa di molto simile sembra delinearsi anche negli Stati Uniti. Indipendentemente da ci\u00f2 che succeder\u00e0 al Senato dopo il ballottaggio in Georgia di gennaio, l\u2019ipotesi pi\u00f9 probabile rimane una <a href=\"https:\/\/theloop.ecpr.eu\/bidens-majority-is-so-narrow-that-he-could-effectively-end-up-in-a-power-sharing-arrangement-with-the-republicans-how-much-can-he-achieve\/\" target=\"_blank\" rel=\"noreferrer noopener\">linea di governo estremamente moderata<\/a>, assediata da una duplice <a href=\"https:\/\/www.adl.org\/blog\/at-the-extremes-the-2020-election-and-american-extremism-part-5\" target=\"_blank\" rel=\"noreferrer noopener\">opposizione radicale<\/a>, da destra e sinistra.&nbsp;<\/p>\n\n\n\n<p>Le prime nomine ministeriali ne danno un assaggio. Il Presidente eletto ha fatto ricorso a figure ben note dell\u2019<em>establishment<\/em> centrista, suscitando uguale indignazione tra i Trumpisti e i progressisti. Il futuro Segretario di Stato, <a href=\"https:\/\/www.politico.eu\/article\/nine-things-to-think-about-antony-blinken\/\" target=\"_blank\" rel=\"noreferrer noopener\">Antony Blinken<\/a>, era gi\u00e0 stato il vice di John Kerry durante l\u2019amministrazione Obama. La futura Ministra del Tesoro, <a href=\"https:\/\/markets.businessinsider.com\/news\/stocks\/janet-yellen-appointment-treasury-secretary-means-for-markets-2020-11-1029846210\" target=\"_blank\" rel=\"noreferrer noopener\">Janet Yellen<\/a>, \u00e8 stata a capo della Fed sia sotto Obama che sotto Trump.&nbsp;<\/p>\n\n\n\n<p>Qui vale la pena ricordare che nell\u2019analisi Sartoriana \u201cl\u2019immobilismo\u201d centrista della Prima Repubblica italiana non era supposto avere un effetto stabilizzante sul sistema politico. Al contrario, Sartori temeva che esso avrebbe finito col mettere in causa le istituzioni stesse, in quanto generava domande di cambiamento sempre pi\u00f9 radicali, alle quali non poteva dare risposta.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Qui vale la pena ricordare che nell\u2019analisi Sartoriana \u201cl\u2019immobilismo\u201d centrista della Prima Repubblica italiana non era supposto avere un effetto stabilizzante sul sistema politico. Al contrario, Sartori temeva che esso avrebbe finito col mettere in causa le istituzioni stesse, in quanto generava domande di cambiamento sempre pi\u00f9 radicali, alle quali non poteva dare risposta.<\/p><cite>CARLO INVERNIZZI ACCETTI<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Il paradosso \u00e8 quindi che il centrismo pu\u00f2 avere un effetto destabilizzante sul sistema istituzionale, nella misura in cui \u00e8 \u2013 nelle parole di Sartori \u2013 \u201csia un residuo che una causa di sempre crescente polarizzazzione\u201d in contesti di alta frammentazione ideologica.&nbsp;<\/p>\n\n\n\n<p>Lo stesso vale per gli Stati Uniti di oggi. Infatti, se il centrismo residuale dell\u2019amministrazione Biden sembrerebbe aver per il momento <a href=\"https:\/\/www.politico.com\/news\/2020\/11\/24\/stocks-wall-street-biden-transition-440288\" target=\"_blank\" rel=\"noreferrer noopener\">rassicurato gli interessi di mercato<\/a>, alla lunga rischia di mettere ulteriore <a href=\"https:\/\/time.com\/5899579\/danger-american-political-violence\/\" target=\"_blank\" rel=\"noreferrer noopener\">pressione sul sistema istituzionale<\/a>, contribuendo a rafforzare le ali estreme del sistema politico senza dargli alcuno sbocco sulle politiche di governo.<\/p>\n\n\n\n<p>Possiamo quindi aspettarci pi\u00f9 turbolenza dagli Stati Uniti, non malgrado, ma proprio perch\u00e9 un governo di centro moderato appare ora inevitabile.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La corrente portata da Joe Biden ricorda per molti versi i partiti cristiano-democratici in Europa. Eppure, invece, lungi dal ridurre la polarizzazione, questa posizione al centro del gioco politico pu\u00f2 essere, come nel caso della Prima Repubblica Italiana, un fattore di caos per il sistema istituzionale. Una prospettiva di Carlo Invernizzi Accetti.<\/p>\n","protected":false},"author":10,"featured_media":687,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-angles.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":0,"footnotes":""},"categories":[1571],"tags":[],"staff":[1587],"editorial_format":[2348],"serie":[],"audience":[],"geo":[],"class_list":["post-686","post","type-post","status-publish","format-standard","hentry","category-politica","staff-carlo-invernizzi-accetti","editorial_format-prospettive"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":687,"excerpt":"La corrente portata da Joe Biden ricorda per molti versi i partiti cristiano-democratici in Europa. Eppure, invece, lungi dal ridurre la polarizzazione, questa posizione al centro del gioco politico pu\u00f2 essere, come nel caso della Prima Repubblica Italiana, un fattore di caos per il sistema istituzionale. Una prospettiva di Carlo Invernizzi Accetti.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L\u2019europeizzazione del sistema politico americano e le sue conseguenze - Il Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/it\/2020\/12\/23\/leuropeizzazione-del-sistema-politico-americano-e-le-sue-conseguenze\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019europeizzazione del sistema politico americano e le sue conseguenze - Il Grand Continent\" \/>\n<meta property=\"og:description\" content=\"La corrente portata da Joe Biden ricorda per molti versi i partiti cristiano-democratici in Europa. Eppure, invece, lungi dal ridurre la polarizzazione, questa posizione al centro del gioco politico pu\u00f2 essere, come nel caso della Prima Repubblica Italiana, un fattore di caos per il sistema istituzionale. Una prospettiva di Carlo Invernizzi Accetti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/it\/2020\/12\/23\/leuropeizzazione-del-sistema-politico-americano-e-le-sue-conseguenze\/\" \/>\n<meta property=\"og:site_name\" content=\"Il Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-23T15:21:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-23T18:34:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2020\/12\/gc-ilbiden-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matheo Malik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2020\/12\/gc-ilbiden-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheo Malik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2020\/12\/23\/leuropeizzazione-del-sistema-politico-americano-e-le-sue-conseguenze\/\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/2020\/12\/23\/leuropeizzazione-del-sistema-politico-americano-e-le-sue-conseguenze\/\",\"name\":\"L\u2019europeizzazione del sistema politico americano e le sue conseguenze - Il Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2020\/12\/23\/leuropeizzazione-del-sistema-politico-americano-e-le-sue-conseguenze\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2020\/12\/23\/leuropeizzazione-del-sistema-politico-americano-e-le-sue-conseguenze\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2020\/12\/Joe-Biden.jpg\",\"datePublished\":\"2020-12-23T15:21:02+00:00\",\"dateModified\":\"2020-12-23T18:34:43+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2020\/12\/23\/leuropeizzazione-del-sistema-politico-americano-e-le-sue-conseguenze\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/it\/2020\/12\/23\/leuropeizzazione-del-sistema-politico-americano-e-le-sue-conseguenze\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2020\/12\/23\/leuropeizzazione-del-sistema-politico-americano-e-le-sue-conseguenze\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2020\/12\/Joe-Biden.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2020\/12\/Joe-Biden.jpg\",\"width\":1000,\"height\":563},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2020\/12\/23\/leuropeizzazione-del-sistema-politico-americano-e-le-sue-conseguenze\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019europeizzazione del sistema politico americano e le sue conseguenze\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/\",\"name\":\"Il Grand Continent\",\"description\":\"La scala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\",\"name\":\"Matheo Malik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"caption\":\"Matheo Malik\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019europeizzazione del sistema politico americano e le sue conseguenze - Il Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/it\/2020\/12\/23\/leuropeizzazione-del-sistema-politico-americano-e-le-sue-conseguenze\/","og_locale":"it_IT","og_type":"article","og_title":"L\u2019europeizzazione del sistema politico americano e le sue conseguenze - Il Grand Continent","og_description":"La corrente portata da Joe Biden ricorda per molti versi i partiti cristiano-democratici in Europa. Eppure, invece, lungi dal ridurre la polarizzazione, questa posizione al centro del gioco politico pu\u00f2 essere, come nel caso della Prima Repubblica Italiana, un fattore di caos per il sistema istituzionale. Una prospettiva di Carlo Invernizzi Accetti.","og_url":"https:\/\/legrandcontinent.eu\/it\/2020\/12\/23\/leuropeizzazione-del-sistema-politico-americano-e-le-sue-conseguenze\/","og_site_name":"Il Grand Continent","article_published_time":"2020-12-23T15:21:02+00:00","article_modified_time":"2020-12-23T18:34:43+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2020\/12\/gc-ilbiden-scaled.jpg","type":"image\/jpeg"}],"author":"Matheo Malik","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2020\/12\/gc-ilbiden-scaled.jpg","twitter_misc":{"Scritto da":"Matheo Malik","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/it\/2020\/12\/23\/leuropeizzazione-del-sistema-politico-americano-e-le-sue-conseguenze\/","url":"https:\/\/legrandcontinent.eu\/it\/2020\/12\/23\/leuropeizzazione-del-sistema-politico-americano-e-le-sue-conseguenze\/","name":"L\u2019europeizzazione del sistema politico americano e le sue conseguenze - Il Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/it\/2020\/12\/23\/leuropeizzazione-del-sistema-politico-americano-e-le-sue-conseguenze\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/it\/2020\/12\/23\/leuropeizzazione-del-sistema-politico-americano-e-le-sue-conseguenze\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2020\/12\/Joe-Biden.jpg","datePublished":"2020-12-23T15:21:02+00:00","dateModified":"2020-12-23T18:34:43+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/it\/2020\/12\/23\/leuropeizzazione-del-sistema-politico-americano-e-le-sue-conseguenze\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/it\/2020\/12\/23\/leuropeizzazione-del-sistema-politico-americano-e-le-sue-conseguenze\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/legrandcontinent.eu\/it\/2020\/12\/23\/leuropeizzazione-del-sistema-politico-americano-e-le-sue-conseguenze\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2020\/12\/Joe-Biden.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2020\/12\/Joe-Biden.jpg","width":1000,"height":563},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/it\/2020\/12\/23\/leuropeizzazione-del-sistema-politico-americano-e-le-sue-conseguenze\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/it\/"},{"@type":"ListItem","position":2,"name":"L\u2019europeizzazione del sistema politico americano e le sue conseguenze"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/it\/#website","url":"https:\/\/legrandcontinent.eu\/it\/","name":"Il Grand Continent","description":"La scala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45","name":"Matheo Malik","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","caption":"Matheo Malik"}}]}},"lgc_categories":[{"id":1571,"name":"Politica","slug":"politica"}],"lgc_author":{"id":1587,"name":"Carlo Invernizzi Accetti","slug":"carlo-invernizzi-accetti","description":null,"first_name":null,"last_name":null,"picture":null},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2020\/12\/Joe-Biden.jpg","width":1000,"height":563,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2020\/12\/Joe-Biden.jpg","width":1000,"height":563,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts\/686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/comments?post=686"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts\/686\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/media\/687"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/media?parent=686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/categories?post=686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/tags?post=686"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/staff?post=686"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/editorial_format?post=686"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/serie?post=686"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/audience?post=686"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/geo?post=686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}