{"id":6451,"date":"2023-03-21T19:00:26","date_gmt":"2023-03-21T19:00:26","guid":{"rendered":"https:\/\/legrandcontinent.eu\/ita\/?p=6451"},"modified":"2023-03-21T19:00:27","modified_gmt":"2023-03-21T19:00:27","slug":"larticolo-49-3-e-uneccezione-in-europa","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/it\/2023\/03\/21\/larticolo-49-3-e-uneccezione-in-europa\/","title":{"rendered":"L\u2019articolo 49-3 \u00e8 un\u2019eccezione in Europa?"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><em><br>I meccanismi di parlamentarismo razionalizzato in Italia\u00a0<\/em><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Rispetto alle dinamiche francesi che stiamo vivendo, l\u2019esperienza italiana \u00e8 molto diversa. Non soltanto perch\u00e9 non esiste l\u2019elezione diretta del Capo dello Stato ma anche perch\u00e9 le dinamiche tutte interne del parlamentarismo italiano rendono pi\u00f9 semplice far cadere un governo e ricomporre in Parlamento un accordo, che favorire governi di minoranza.&nbsp;<\/li>\n\n\n\n<li>La ragione \u00e8 presto detta: mentre in Francia l\u2019indirizzo politico di governo \u00e8 figlio della legittimazione diretta degli elettori, in Italia dipende dalla composizione delle volont\u00e0 formate dai partiti di maggioranza, che spesso mutano durante la legislatura, rendendo il cittadino meno arbitro dell\u2019indirizzo politico di quanto, invece, le parole spese dai partiti in campagna elettorale promettono.<\/li>\n\n\n\n<li>Pi\u00f9 \u00e8 solida la legittimazione politica ricevuta dagli elettori intorno a un indirizzo politico come avviene in Francia con l\u2019elezione diretta, pi\u00f9 \u00e8 difficile \u201cfar finta\u201d che si possa mutare in Parlamento quell\u2019indirizzo come se nulla fosse, e dunque appunto serve una procedura molto dura, ma anche molto chiara, come \u00e8 l\u2019articolo 49, comma 3. In Italia, invece, la forza dei partiti supera ogni volont\u00e0 degli elettori, e dunque il governo pu\u00f2 cadere \u2013 come spesso avviene \u2013 senza grande fatica. Anzi, storicamente, addirittura senza un voto esplicito in Parlamento, ma sulla base di semplici dimissioni.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Il meccanismo di sfiducia costruttiva tedesco: un metodo per trovare un equilibrio tra tutti gli interessi divergenti di un sistema parlamentare<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La sfiducia costruttiva di tradizione tedesca, ossia quella procedura che impedisce ad un parlamento di votare la sfiducia al governo in carica se non permette simultaneamente la creazione e il voto di fiducia per un altro governo, \u00e8 in generale la soluzione pi\u00f9 idonea quando il circuito tra Governo e Parlamento si inceppa.&nbsp;<\/li>\n\n\n\n<li>Eppure, l\u2019elemento stabilizzante appare pi\u00f9 l\u2019art. 68 riguardo alla mozione di fiducia che il 67 riguardo alla mozione di sfiducia costruttiva. Infatti \u00e8 pi\u00f9 la deterrenza di uno scioglimento anticipato che rafforza la posizione del governo e lo mantiene in carica, che la soluzione di una sfiducia costruttiva.&nbsp;<\/li>\n\n\n\n<li>\u00c8 nel timore di non riuscire ad ottenere \u00abl\u2019approvazione della maggioranza dei membri del Bundestag\u00bb su una mozione di fiducia presentata proprio dallo stesso Cancelliere federale che i parlamentari trovano il rischio maggiore per loro stessi di dover tornare alle urne, lasciando il loro seggio: entro ventuno giorni si ritrovano direttamente in campagna elettorale.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">La gestione della maggioranza relativa in Spagna\u00a0<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L\u2019esperienza spagnola \u00e8 molto simile a quella tedesca. Mentre in Germania solo il Cancelliere pu\u00f2 provocare lo scioglimento dell\u2019Assemblea se il Bundestag risponde negativamente a una questione di fiducia che gli viene posta, in Spagna non esiste questo limite: il potere del Presidente del Governo \u00e8 totale, essendo libero, \u00absotto la sua esclusiva responsabilit\u00e0\u00bb, e previa deliberazione del Consiglio dei Ministri, ai sensi dell&#8217;articolo 115 della Costituzione, di \u00abproporre lo scioglimento del Congresso, del Senato e delle Cortes Generales, che sar\u00e0 decretato dal Re\u00bb.<\/li>\n\n\n\n<li>In breve, la maggioranza di governo, con i suoi meriti e demeriti, pu\u00f2 essere garantita meglio in Spagna che in Germania.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Come pu\u00f2 il governo &#8220;forzare&#8221; una situazione in Parlamento in Italia, Germania e Spagna? Quali sono le principali differenze con il sistema francese? Con il costituzionalista italiano Francesco Clementi, facciamo un tour dell\u2019eccezione europea<\/p>\n","protected":false},"author":6720,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":3,"footnotes":""},"categories":[1648],"tags":[],"staff":[2122],"editorial_format":[2354],"serie":[],"audience":[],"geo":[],"class_list":["post-6451","post","type-post","status-publish","format-standard","hentry","category-diritto","staff-francesco-clementi","editorial_format-brevi"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":"","excerpt":"Come pu\u00f2 il governo \"forzare\" una situazione in Parlamento in Italia, Germania e Spagna? Quali sono le principali differenze con il sistema francese? Con il costituzionalista italiano Francesco Clementi, facciamo un tour dell\u2019eccezione europea","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L\u2019articolo 49-3 \u00e8 un\u2019eccezione in Europa? - Il Grand Continent<\/title>\n<meta name=\"description\" content=\"Quali sono le principali differenze tra i sistemi parlamentari di Germania, Spagna e Italia e quello francese? Un tour dell\u2019eccezione europea\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/it\/2023\/03\/21\/larticolo-49-3-e-uneccezione-in-europa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019articolo 49-3 \u00e8 un\u2019eccezione in Europa? - Il Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Quali sono le principali differenze tra i sistemi parlamentari di Germania, Spagna e Italia e quello francese? Un tour dell\u2019eccezione europea\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/it\/2023\/03\/21\/larticolo-49-3-e-uneccezione-in-europa\/\" \/>\n<meta property=\"og:site_name\" content=\"Il Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-21T19:00:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-21T19:00:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2023\/03\/Screenshot-2023-03-21-alle-19.54.07-990x629.png\" \/>\n\t<meta property=\"og:image:width\" content=\"990\" \/>\n\t<meta property=\"og:image:height\" content=\"629\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Francesco Maselli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2023\/03\/Screenshot-2023-03-21-alle-19.54.07.png\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Maselli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2023\/03\/21\/larticolo-49-3-e-uneccezione-in-europa\/\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/2023\/03\/21\/larticolo-49-3-e-uneccezione-in-europa\/\",\"name\":\"L\u2019articolo 49-3 \u00e8 un\u2019eccezione in Europa? - Il Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#website\"},\"datePublished\":\"2023-03-21T19:00:26+00:00\",\"dateModified\":\"2023-03-21T19:00:27+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/8d64a968e68e8332254b33c7afb28774\"},\"description\":\"Quali sono le principali differenze tra i sistemi parlamentari di Germania, Spagna e Italia e quello francese? Un tour dell\u2019eccezione europea\",\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2023\/03\/21\/larticolo-49-3-e-uneccezione-in-europa\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/it\/2023\/03\/21\/larticolo-49-3-e-uneccezione-in-europa\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2023\/03\/21\/larticolo-49-3-e-uneccezione-in-europa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019articolo 49-3 \u00e8 un\u2019eccezione in Europa?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/\",\"name\":\"Il Grand Continent\",\"description\":\"La scala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/8d64a968e68e8332254b33c7afb28774\",\"name\":\"Francesco Maselli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/994d5c9942a5785b20f067fb9d4945df?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/994d5c9942a5785b20f067fb9d4945df?s=96&d=mm&r=g\",\"caption\":\"Francesco Maselli\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019articolo 49-3 \u00e8 un\u2019eccezione in Europa? - Il Grand Continent","description":"Quali sono le principali differenze tra i sistemi parlamentari di Germania, Spagna e Italia e quello francese? Un tour dell\u2019eccezione europea","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/it\/2023\/03\/21\/larticolo-49-3-e-uneccezione-in-europa\/","og_locale":"it_IT","og_type":"article","og_title":"L\u2019articolo 49-3 \u00e8 un\u2019eccezione in Europa? - Il Grand Continent","og_description":"Quali sono le principali differenze tra i sistemi parlamentari di Germania, Spagna e Italia e quello francese? Un tour dell\u2019eccezione europea","og_url":"https:\/\/legrandcontinent.eu\/it\/2023\/03\/21\/larticolo-49-3-e-uneccezione-in-europa\/","og_site_name":"Il Grand Continent","article_published_time":"2023-03-21T19:00:26+00:00","article_modified_time":"2023-03-21T19:00:27+00:00","og_image":[{"width":990,"height":629,"url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2023\/03\/Screenshot-2023-03-21-alle-19.54.07-990x629.png","type":"image\/png"}],"author":"Francesco Maselli","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2023\/03\/Screenshot-2023-03-21-alle-19.54.07.png","twitter_misc":{"Scritto da":"Francesco Maselli","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/it\/2023\/03\/21\/larticolo-49-3-e-uneccezione-in-europa\/","url":"https:\/\/legrandcontinent.eu\/it\/2023\/03\/21\/larticolo-49-3-e-uneccezione-in-europa\/","name":"L\u2019articolo 49-3 \u00e8 un\u2019eccezione in Europa? - Il Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/it\/#website"},"datePublished":"2023-03-21T19:00:26+00:00","dateModified":"2023-03-21T19:00:27+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/8d64a968e68e8332254b33c7afb28774"},"description":"Quali sono le principali differenze tra i sistemi parlamentari di Germania, Spagna e Italia e quello francese? Un tour dell\u2019eccezione europea","breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/it\/2023\/03\/21\/larticolo-49-3-e-uneccezione-in-europa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/it\/2023\/03\/21\/larticolo-49-3-e-uneccezione-in-europa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/it\/2023\/03\/21\/larticolo-49-3-e-uneccezione-in-europa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/it\/"},{"@type":"ListItem","position":2,"name":"L\u2019articolo 49-3 \u00e8 un\u2019eccezione in Europa?"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/it\/#website","url":"https:\/\/legrandcontinent.eu\/it\/","name":"Il Grand Continent","description":"La scala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/8d64a968e68e8332254b33c7afb28774","name":"Francesco Maselli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/994d5c9942a5785b20f067fb9d4945df?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/994d5c9942a5785b20f067fb9d4945df?s=96&d=mm&r=g","caption":"Francesco Maselli"}}]}},"lgc_categories":[{"id":1648,"name":"Diritto","slug":"diritto"}],"lgc_author":{"id":2122,"name":"Francesco Clementi","slug":"francesco-clementi","description":null,"first_name":"Francesco","last_name":"Clementi","picture":null},"feature_image_summary":null,"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts\/6451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/users\/6720"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/comments?post=6451"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts\/6451\/revisions"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/media?parent=6451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/categories?post=6451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/tags?post=6451"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/staff?post=6451"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/editorial_format?post=6451"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/serie?post=6451"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/audience?post=6451"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/geo?post=6451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}