{"id":5876,"date":"2022-12-31T10:52:35","date_gmt":"2022-12-31T10:52:35","guid":{"rendered":"https:\/\/legrandcontinent.eu\/ita\/?p=5876"},"modified":"2023-09-27T15:00:40","modified_gmt":"2023-09-27T14:00:40","slug":"in-morte-di-papa-benedetto-xvi-papa-emerito","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/","title":{"rendered":"In morte di Papa Benedetto XVI, papa emerito"},"content":{"rendered":"\n<p class=\"has-drop-cap\">Papa Benedetto XVI \u00e8 morto oggi, alle 9:34 del 31 dicembre 2022, all\u2019et\u00e0 di 95 anni. \u00c8 stato il 265\u00b0 sovrano pontificio, dal 19 aprile 2005 alla sua rinuncia volontaria l\u201911 febbraio 2013, in un gesto quasi inedito, anche sulla scala bimillenaria della storia della Chiesa. Durante le prossime esequie, sar\u00e0 impossibile non notare che, per la prima volta, un papa verr\u00e0 sepolto dal suo successore e che la sua morte non sar\u00e0 immediatamente seguita da un conclave. Eletto a 78 anni come Papa di transizione &#8211; la stessa et\u00e0 in cui sal\u00ec sulla cattedra di San Pietro un altro cosiddetto &#8220;Papa di transizione&#8221;, Giovanni XXIII (1958-1963), che decise di aprire il Concilio Vaticano II, con conseguenze inversamente proporzionali alla durata del suo pontificato &#8211; Benedetto XVI ebbe il gravoso compito di succedere all&#8217;importante pontificato di Giovanni Paolo II (1978-2005), di cui era stato il braccio destro. Uno schema che si ripete durante i suoi anni sembra essere una successione di incomprensioni con il mondo dei media, che non era pi\u00f9 in grado di comprendere il suo modo di governare ad intra, un mondo dei media di cui lui stesso, a sua volta, diffidava fortemente.\u00a0<\/p>\n\n\n\n<p>Il pontificato di Benedetto XVI occupa solamente 8 anni della sua vita, mentre \u00e8 stato per 28 vescovo e cardinale, per 25 professore di teologia, e per 9 ha vissuto con lo statuto inedito e per certi versi problematico di papa emerito. Fatto emblematico della sua personalit\u00e0 riservata, quasi ritirata, Benedetto XVI \u00e8 quindi Papa emerito da pi\u00f9 tempo di quanto sia stato Pontefice in carica. Per comprendere meglio gli orientamenti principali del suo pontificato, dobbiamo prima capire l&#8217;uomo che \u00e8 stato per 78 anni della sua vita, Joseph Ratzinger.\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Joseph Ratzinger: la formazione di un prete<\/h2>\n\n\n\n<p>Joseph Ratzinger \u00e8 nato la notte del 16 aprile 1927 (un Sabato Santo, vigilia di Pasqua nel calendario liturgico) a Martkl-am-Inn, un piccolo villaggio di 600 abitanti nell&#8217;Alta Baviera, luogo di lavoro del padre, sottufficiale della gendarmeria, come terzo e ultimo figlio di genitori gi\u00e0 in et\u00e0 avanzata. Le sue origini sono piuttosto modeste: i nonni erano contadini (da parte del padre) e fornai (da parte della madre), in famiglie estremamente numerose; la madre, Maria (1884-1963), originaria dell&#8217;Alto Adige, prima di sposarsi faceva la cuoca. I suoi genitori si sono conosciuti alla fine del 1920 attraverso annunci su un giornale cattolico, ed entrambi erano noti per la loro grande fede; il padre (1877-1959), che si chiamava Joseph come lui, aveva cercato di unirsi ai Cappuccini a Passavia, anche se la sua famiglia ristretta comprendeva gi\u00e0 cinque sacerdoti e due suore. Allo stesso modo, la figlia maggiore Maria (1921-1991), rimasta nubile, divenne terziaria francescana nel 1941 e trascorse tutta la sua vita al servizio dei due fratelli, che a loro volta entrarono negli ordini. Il mondo in cui Joseph Ratzinger \u00e8 nato era un mondo impregnato di cristianesimo tradizionale, dove la fede permeava tutti gli atti della vita quotidiana.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Il mondo in cui Joseph Ratzinger \u00e8 nato era un mondo impregnato di cristianesimo tradizionale, dove la fede permeava tutti gli atti della vita quotidiana.&nbsp;<\/p><cite>Jean-Beno\u00eet Poulle<\/cite><\/blockquote><\/figure>\n\n\n\n<p>\u00c8 un bambino delicato, quasi sofferente, portato in giro da una famiglia che si sposta spesso in base ai trasferimenti del padre, a Tittmoning (1929), vicino al confine austriaco, poi ad Aschau am Inn (1932), dove frequenta la scuola elementare, e infine a Traunstein nel 1935. Impar\u00f2 a suonare l&#8217;organo e il violino e rimase un appassionato di musica per tutta la vita, venerando in particolare Mozart e Beethoven. Per lui fu difficile affrontare la rigida disciplina e l&#8217;obbligo di praticare sport al <em>Gymnasium<\/em> di Traunstein, anche se la scuola era moderna e innovativa per gli standard dell&#8217;epoca. Ricevette un&#8217;educazione classica molto approfondita, basata sulle lingue antiche, e scopr\u00ec la letteratura tedesca; scrisse lui stesso alcune poesie. Nel 1935, il fratello maggiore Georg (1924-2020) entr\u00f2 nel seminario minore diocesano di Traunstein; lui stesso vi entr\u00f2 nel 1939, su consiglio del suo parroco che aveva scorto in lui una vocazione precoce.\u00a0<\/p>\n\n\n\n<p>Nel frattempo, la sua famiglia assisteva con crescente preoccupazione alla presa di potere dei nazisti, per i quali nutriva una viscerale antipatia ideologica, sia per l&#8217;identitarismo bavarese, che equiparava tutto il pangermanesimo all&#8217;imperialismo prussiano a loro estraneo, sia per il disgusto verso la demagogia plebea e violenta del NSDAP. Sebbene inizialmente si fosse iscritto al partito nazista per la convenienza che offriva, Joseph Ratzinger senior and\u00f2 anticipatamente in pensione nel 1937. Le inclinazioni politiche della sua famiglia erano molto pi\u00f9 chiaramente a favore della nascente democrazia cristiana &#8211; in particolare ammiravano il cancelliere social-cristiano austriaco Ignaz Seipel (1876-1932). Analogamente, nella generazione precedente, uno degli zii paterni, Georg Ratzinger (1844-1889), era stato membro del Reichstag per il Partito Patriota Bavarese, editore del giornale <em>M\u00fcnchner Wochenblatts<\/em>, altra formazione sociale cattolica, ed era stato allievo del professor Ignaz von D\u00f6llinger (1799-1890), responsabile dello scisma vetero-cattolico del 1870 per aver rifiutato il dogma dell&#8217;infallibilit\u00e0 papale, strada che il prozio del futuro papa non segu\u00ec.\u00a0<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/SIPA_AP21359851_000003-scaled-e1672238890800.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2560\"\n        data-pswp-height=\"1664\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/SIPA_AP21359851_000003-scaled-e1672238890800-330x215.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/SIPA_AP21359851_000003-scaled-e1672238890800-690x449.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/SIPA_AP21359851_000003-scaled-e1672238890800-1340x871.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/SIPA_AP21359851_000003-scaled-e1672238890800-125x81.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">\u00a9 AP Photo\/Gregorio Borgia<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>Durante la Seconda guerra mondiale, dopo essere stato arruolato nella Giovent\u00f9 hitleriana al compimento del 14\u00b0 anno di et\u00e0, il giovane Joseph Ratzinger fu arruolato in un campo di addestramento militare delle SS, al quale si rifiut\u00f2 di partecipare perch\u00e9 voleva diventare sacerdote. Incorporato come operatore radio della <em>Luftwaffe <\/em>dal luglio 1943, nel settembre 1944 fu assegnato al servizio di lavoro obbligatorio del Reich per scavare trincee anticarro sul confine austro-ungarico, quindi alla <em>Wehrmacht <\/em>in dicembre, dove fu dichiarato inabile al servizio a causa di un&#8217;infezione al pollice, e infine disert\u00f2 nell&#8217;aprile 1945, pochi giorni prima della resa tedesca. Dopo la resa, fu fatto prigioniero per 40 giorni dalle truppe americane in un campo vicino a Ulm, dove secondo alcuni gioc\u00f2 a dadi con G\u00fcnter Grass, prima di poter tornare dai suoi genitori. Anche suo fratello Georg fu arruolato nella <em>Wehrmacht<\/em>, fu ferito e internato per qualche tempo in Italia. La guerra impression\u00f2 profondamente il giovane Ratzinger, che ne parl\u00f2 pochissimo per molto tempo. Anche se in seguito gli verr\u00e0 rimproverato di aver parlato poco del nazismo e della colpa collettiva tedesca, le sue testimonianze di allora non lasciano ambiguit\u00e0 sui suoi sentimenti verso il potere totalitario, che si uniranno alle sue domande sul mistero del Male assoluto nella storia.<\/p>\n\n\n\n<p>Dopo la guerra, entr\u00f2 nel seminario maggiore episcopale di Freising. Qui studi\u00f2 filosofia, storia, psicologia, le Scritture, ebraico e diritto canonico (l&#8217;unica materia in cui ebbe qualche difficolt\u00e0). Mentre il fratello, abile musicista, era soprannominato &#8220;<em>Orgel-Ratz&#8217;<\/em>&#8221; come organista del seminario, lui divenne &#8220;<em>B\u00fccher-Ratz&#8217;<\/em>&#8220;, il &#8220;Ratzinger dei libri&#8221;. A quel tempo, leggeva quasi tutto quello che gli capitava sotto mano, dalla letteratura tedesca (Kafka, Thomas Mann, Rilke, Hermann Hesse, che lo interessava come analista del decadentismo, e i suoi contemporanei Gertrud von Le Fort, Annette Kolb, Elisabeth Langg\u00e4sser, Franz Werfel e Erich Wiechert&#8230;) ma anche Dostoevskij, Aldous Huxley e, per quanto riguarda gli autori francesi che ama particolarmente, Claudel, Mauriac e Bernanos. Soprattutto, fu travolto dalla scoperta delle <em>Confessioni <\/em>di Sant&#8217;Agostino nel 1946. Dal punto di vista filosofico, oltre al neo-tomismo che costituiva la base del suo insegnamento dell&#8217;epoca, la sua formazione fu segnata da varie influenze, in particolare il neo-aristotelismo di Josef Pieper (1904-1997), la fenomenologia di Max Scheler (1874-1948) e di Edith Stein (1891-1942, deportata ad Auschwitz), il personalismo e l&#8217;esistenzialismo cristiano di Theodor Steinb\u00fcchel (1888-1949) o di Peter W\u00fcst (1884-1940), che prefer\u00ec a Heidegger, e persino il misticismo chassidico di Martin Buber. Gi\u00e0 in seminario emerge la sua predilezione per la teologia e le questioni intellettuali piuttosto che per il lavoro pastorale, per il quale sentiva di avere poco talento a causa della sua timidezza.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p> Anche se in seguito gli verr\u00e0 rimproverato di aver parlato poco del nazismo e della colpa collettiva tedesca, le sue testimonianze di allora non lasciano ambiguit\u00e0 sui suoi sentimenti verso il potere totalitario, che si uniranno alle sue domande sul mistero del male radicale nella storia.<\/p><cite>Jean-Beno\u00eet Poulle<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Nel maggio 1948 viene tonsurato dal cardinale Faulhaber, arcivescovo di Monaco-Frisinga, nella cappella arcivescovile e ammesso alla professione clericale. Nell&#8217;autunno 1949 entra a far parte del <em>Georgianum<\/em>, l&#8217;istituto di formazione sacerdotale della facolt\u00e0 teologica cattolica dell&#8217;Universit\u00e0 Ludwig Maximilian di Monaco. Al <em>Georgianum<\/em>, dove studi\u00f2 teologia fondamentale e dogmatica, fu influenzato da un insegnamento chiaramente progressista: si interess\u00f2 in particolare alle lezioni di Friedrich Wilhelm Maier, professore di Nuovo Testamento ed esegeta dalle idee avanzate, che aveva avuto problemi con Roma ed era stato addirittura bandito dall&#8217;insegnamento prima della guerra; fu anche influenzato da August Adam, professore di teologia morale, che all&#8217;epoca fu criticato come lassista in materia di morale sessuale per il suo libro sul <em>Primato dell&#8217;amore<\/em>. Anche il direttore del <em>Georgianum<\/em>, Joseph Pascher, super\u00f2 il suo iniziale scetticismo nei confronti del Movimento Liturgico, che promuoveva una maggiore centralit\u00e0 della liturgia, da riformare e semplificare, nella piet\u00e0 cattolica: Joseph Ratzinger lesse, ammir\u00f2 e conobbe uno dei suoi principali ispiratori, Romano Guardini (1885-1968), autore de <em>Lo spirito della liturgia<\/em>. Ma l&#8217;influenza decisiva rimase quella del supervisore del suo maestro, Gottlieb S\u00f6hngen (1892-1971), un sacerdote proveniente da una coppia interconfessionale, molto coinvolto nei primi vagiti dell&#8217;ecumenismo, decisamente a favore dell&#8217;esegesi storico-critica e a dir poco malvisto dalla Curia di Pio XII. Nel 1949, S\u00f6hngen gli propose di proseguire gli studi dottorali sotto la sua direzione, con una tesi su <em>Il popolo e la casa di Dio nella dottrina ecclesiale di sant&#8217;Agostino<\/em>, che si inseriva nei dibattiti dell&#8217;epoca sulla Chiesa come &#8220;corpo mistico&#8221;. Questo lavoro, che difese pubblicamente e brillantemente l&#8217;11 luglio 1953 &#8211; vincendo il premio per la tesi della sua facolt\u00e0 &#8211; gli fece conoscere le correnti del rinnovamento patristico e della Nuova Teologia, praticate da Henri de Lubac e Hans Urs von Balthasar, che avrebbe poi conosciuto.\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pr.-Dr. Joseph Ratzinger : l\u2019audacia di un teologo di fama<\/h2>\n\n\n\n<p>Dopo l&#8217;ordinazione diaconale (nell&#8217;autunno del 1950, quando si impegn\u00f2 al celibato) e dopo un periodo di formazione pratica di sei mesi, Joseph Ratzinger fu ordinato sacerdote il 29 giugno 1951 nella cattedrale di Freising dal cardinale Faulhaber, insieme ad altri 43 sacerdoti, tra cui suo fratello Georg. Divenne vicario della parrocchia del Preziosissimo Sangue a Bogenhausen, alla periferia di Monaco: i suoi compiti erano principalmente pastorali, ma anche didattici, con lezioni di religione al ginnasio e insegnamento al seminario di Freising. Suo fratello, anch&#8217;egli vicario parrocchiale, si dedic\u00f2 sempre pi\u00f9 alla musica liturgica e nel 1964 divenne direttore del Coro dei Ragazzi della Cattedrale di Ratisbona, uno dei pi\u00f9 prestigiosi al mondo. Ben presto Joseph Ratzinger fu coinvolto nell&#8217;insegnamento a tempo pieno: professore di dogmatica e teologia fondamentale presso il seminario episcopale, a 27 anni era anche <em>privat-docent<\/em> &nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-5876' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/#easy-footnote-bottom-1-5876' title='Un equivalente dell&amp;#8217;assistente universitario'><sup>1<\/sup><\/a><\/span><\/span> all&#8217;Universit\u00e0 di Monaco e cappellano degli studenti. S\u00f6hngen lo incoraggi\u00f2 a completare gli studi con una tesi di abilitazione che gli permettesse di rivendicare la cattedra, questa volta con una materia di teologia medievale: sarebbe stata, secondo il titolo rivisto del 1959, <em>La teologia della storia di San Bonaventura<\/em>. Negli scritti del &#8220;Dottore Serafico&#8221;, un francescano speculativo del XIII secolo, Joseph Ratzinger cerc\u00f2 di scoprire le influenze sotterranee delle idee gioachimite &nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-5876' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/#easy-footnote-bottom-2-5876' title='Dal nome dell&amp;#8217;abate calabrese Gioachino da Fiore, (ca. 1335-1202), le cui concezioni della storia e della fine dei tempi influenzeranno considerevolmente i movimenti millenaristici'><sup>2<\/sup><\/a><\/span><\/span> che, tramite una lettura profetica del Nuovo Testamento, annunciavano l&#8217;avvento di una &#8220;et\u00e0 dello Spirito&#8221;, o terza era, all&#8217;interno della storia. Poco prima dell&#8217;esame, il suo co-esaminatore, Michael Schmaus (1897-1993), uno dei teologi pi\u00f9 rinomati dell&#8217;universit\u00e0, annunci\u00f2 che la difesa non poteva aver luogo perch\u00e9 la tesi non soddisfaceva gli standard scientifici richiesti, n\u00e9 nella forma n\u00e9 nel contenuto. In effetti, Schmaus lo sospettava di modernismo, di fare una &#8220;teologia del sentimento&#8221; soggettivista e di evitare definizioni precise per mezzo di un&#8217;espressione raffinata e poetica. Alla fine, il giovane teologo fu comunque autorizzato a presentare una versione abbreviata e rielaborata della sua tesi e affront\u00f2 una burrascosa difesa nel febbraio 1957, al termine della quale fu comunque accettato. Questo episodio dimostra che Ratzinger era allora saldamente nella giovane guardia di un&#8217;universit\u00e0 che era nota come un bastione della teologia avanzata di fronte alla neoscolastica romana. All&#8217;inizio del 1958 diventa professore associato di teologia dogmatica e fondamentale all&#8217;Universit\u00e0 di Freising. A 30 anni era uno dei pi\u00f9 giovani teologi universitari del mondo.\u00a0<\/p>\n\n\n\n<p>Il suo articolo &#8220;I nuovi pagani e la Chiesa&#8221;, pubblicato l&#8217;anno successivo sulla rivista <em>Hochland<\/em>, in cui chiedeva la fine di un &#8220;cristianesimo sociologico&#8221; fatto di abitudini e la &#8220;de-mondanizzazione&#8221; della Chiesa, che avrebbe comportato necessariamente una diminuzione numerica, contribu\u00ec a classificarlo come un innovatore, o addirittura come un &#8220;cristiano di sinistra&#8221;, al punto che la sua gerarchia se ne preoccup\u00f2. Alla fine trov\u00f2 una via d&#8217;uscita nella cattedra di teologia fondamentale dell&#8217;Universit\u00e0 di Bonn, che accett\u00f2 nell&#8217;aprile del 1959. Nella capitale della Germania federale trov\u00f2 la libert\u00e0 intellettuale che gli era mancata a Monaco e divenne un professore molto apprezzato dai suoi studenti per la sua estrema erudizione, la sua finezza analitica, la sua modestia e la sua dedizione.&nbsp;<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/SIPA_AP21340183_000002-e1672238942475.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"1515\"\n        data-pswp-height=\"1995\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/SIPA_AP21340183_000002-e1672238942475-330x435.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/SIPA_AP21340183_000002-e1672238942475-690x909.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/SIPA_AP21340183_000002-e1672238942475-1340x1765.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/SIPA_AP21340183_000002-e1672238942475-125x165.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">\u00a9 AP Photo\/Gregorio Borgia<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>Soprattutto, fu l\u00ec che incontr\u00f2 il cardinale Joseph Frings, arcivescovo di Colonia e presidente della Conferenza episcopale tedesca, una delle figure di spicco della Chiesa del dopoguerra. L&#8217;anziano prelato, ormai quasi cieco, not\u00f2 la sua competenza teologica e lo assunse presto come <em>ghostwriter<\/em>. Frings era membro della commissione preparatoria del Concilio che il nuovo Papa Giovanni XXIII aveva annunciato il 25 gennaio 1959. In questo modo, Ratzinger influenz\u00f2 la stesura di alcuni dei testi preparatori dell&#8217;assemblea dei vescovi, chiedendo nuove scadenze per criticarli o modificarli, in particolare in una conferenza tenuta da Frings a Genova il 20 novembre 1961 (&#8220;Il Concilio Vaticano II di fronte al pensiero moderno&#8221;), che ebbe un certo impatto.&nbsp;<\/p>\n\n\n\n<p>Quando l&#8217;11 ottobre 1962 si apr\u00ec il Concilio Vaticano II, egli era presente a Roma a fianco del cardinale Frings, prima come consigliere informale durante la prima sessione, insieme al grande storico della Chiesa Hubert Jedin, e poi, durante le tre sessioni successive, come peritus, l&#8217;esperto teologico ufficiale dell&#8217;arcivescovo. Il suo contributo pi\u00f9 significativo ai lavori del Concilio, tuttavia, avvenne quando era solo un uomo nell&#8217;ombra, in relazione al primo schema preparatorio esaminato dai Padri conciliari,<em> De fontibus Revelationis<\/em>, &#8220;Sulle fonti della Rivelazione&#8221;: Per Joseph Ratzinger, in disaccordo con le formulazioni tradizionali, esiste un&#8217;unica fonte della Rivelazione cristiana, la stessa Parola di Dio, che la rende una realt\u00e0 viva, che precede tutte le sue attestazioni materiali nella Bibbia o nella Tradizione. \u00c8 questa visione che trionfer\u00e0 e dar\u00e0 origine a una delle quattro costituzioni dogmatiche del Concilio, <em>Dei Verbum<\/em> (&#8220;La Parola di Dio&#8221;).&nbsp;<\/p>\n\n\n\n<p>Durante i tre anni del Vaticano II, di cui Frings fu una delle grandi voci strategiche (fu uno dei nove presidenti dell&#8217;assemblea dei padri conciliari, poi uno dei quattro moderatori scelti dal Papa), Ratzinger fu uno dei teologi pi\u00f9 ascoltati dell&#8217;ala progressista, che riusc\u00ec, all&#8217;inevitabile costo di arretramenti tattici e testi di compromesso, a imporre le proprie concezioni nei grandi orientamenti votati dall&#8217;assemblea dei vescovi. Tra gli altri esperti, apprezzava il gesuita Karl Rahner (1904-1984), con il quale era gi\u00e0 abituato a collaborare intellettualmente, anche se in seguito le loro divergenze di opinione sarebbero aumentate. Fece anche amicizia con i grandi rappresentanti francesi della &#8220;Nouvelle Th\u00e9ologie&#8221; che in precedenza erano stati sospettati o condannati a Roma, come il domenicano Yves Congar&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-5876' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/#easy-footnote-bottom-3-5876' title='Congar annota nel suo &lt;em&gt;Diario del Concilio&lt;\/em&gt; che Ratzinger gli pare \u00abragionevole, modesto, imparziale e servizievole\u00bb'><sup>3<\/sup><\/a><\/span><\/span> o i gesuiti Jean Dani\u00e9lou e Henri de Lubac: proprio quest&#8217;ultimo gli present\u00f2 l&#8217;arcivescovo di Cracovia, Karol Wojtyla, la cui formazione fu segnata dalla filosofia personalista. A causa della sua giovane et\u00e0, non si pu\u00f2 fare a meno di paragonarlo a un altro teologo e <em>peritus <\/em>dalla carriera fulminante, lo svizzero tedesco Hans K\u00fcng (1928-2021), con cui aveva stretto amicizia, di un anno pi\u00f9 giovane di lui e gi\u00e0 professore a Tubinga; tuttavia, K\u00fcng appariva gi\u00e0 molto pi\u00f9 progressista, pi\u00f9 divisivo e anche appariscente nel suo modo di rivolgersi ai media, ai quali cercava di trasmettere la sua visione del Vaticano II come evento rivoluzionario. Per lui il Concilio era soprattutto un&#8217;assemblea deliberativa (<em>Concilium<\/em>), una sorta di Parlamento della Chiesa che aveva ricevuto dai fedeli il mandato di cambiare la sua &#8220;costituzione&#8221;, mentre Ratzinger lo vedeva come una <em>Communio<\/em>, un&#8217;assemblea ecclesiale unita da vincoli innanzitutto spirituali e mistici. Dopo il Concilio Vaticano II, le loro strade divergeranno ulteriormente, fino a rappresentare due visioni opposte della Chiesa cattolica e del suo futuro: Sebbene nel 1965 Ratzinger fosse ancora nel comitato di redazione di <em>Concilium<\/em>, la rivista cattolica liberale creata attorno a Hans K\u00fcng e al belga Edward Schillebeeckx per difendere il progetto di profonde riforme nella Chiesa, in seguito ne prese chiaramente le distanze; e nel 1972, insieme a Balthasar, Lubac e Dani\u00e9lou, fond\u00f2 la rivale conservatrice <em>Communio<\/em>, che rappresentava una linea moderata, impegnata a interpretare il Vaticano II nella continuit\u00e0 del magistero precedente. Fu anche attraverso <em>Communio <\/em>che Ratzinger entr\u00f2 in contatto pi\u00f9 stretto con il cardinale Wojtyla.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Nella capitale della Germania federale trov\u00f2 la libert\u00e0 intellettuale che gli era mancata a Monaco e divenne un professore molto apprezzato dai suoi studenti per la sua estrema erudizione, la sua finezza analitica, la sua modestia e la sua dedizione.<\/p><cite>Jean-Beno\u00eet Poulle<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Al di fuori della parentesi cruciale delle sessioni conciliari, l&#8217;atmosfera accademica di Bonn, segnata da accese polemiche e rivalit\u00e0 individuali, si fece pi\u00f9 cupa, soprattutto quando Ratzinger chiese che due suoi studenti di fede ortodossa potessero ottenere il dottorato dalla facolt\u00e0 cattolica, allora vietato. Decise quindi di lasciare Bonn per l&#8217;Universit\u00e0 di M\u00fcnster, pi\u00f9 a nord, e una cattedra di teologia dogmatica, dove rimase dal 1963 al 1965. Poi, dal 1966 al 1969, fu professore di dogmatica e storia del dogma all&#8217;Universit\u00e0 di Tubinga, probabilmente la pi\u00f9 famosa facolt\u00e0 teologica della Germania, grazie alla richiesta del suo direttore, Hans K\u00fcng in persona: Ratzinger gli aveva infatti fatto un favore facendo assumere a M\u00fcnster il suo assistente Walter Kasper&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-5876' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/#easy-footnote-bottom-4-5876' title='Nato nel 1933. Futuro cardinale (2001), segretario e poi presidente del Pontificio Consiglio per l&amp;#8217;Unit\u00e0 dei Cristiani (1999-2010), grande figura di un progressismo che sarebbe rimasto all&amp;#8217;interno delle strutture della Chiesa, Papa Francesco lo ha riconosciuto come uno dei suoi maestri e ispiratori.'><sup>4<\/sup><\/a><\/span><\/span> alla cattedra di teologia ecumenica.<\/p>\n\n\n\n<p>Fu a Tubinga che il Prof. Ratzinger si trov\u00f2 pi\u00f9 dolorosamente confrontato con il divario tra la riforma della Chiesa come avrebbe voluto e come la leggeva nei testi conciliari, e la realt\u00e0 di uno sconvolgimento molto pi\u00f9 brutale (Paolo VI diagnostic\u00f2 addirittura un processo di &#8220;autodemolizione della Chiesa&#8221;&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-5876' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/#easy-footnote-bottom-5-5876' title='Discorso dell&amp;#8217;8 dicembre 1968'><sup>5<\/sup><\/a><\/span><\/span>), a favore del quale si invocava lo &#8220;Spirito del Concilio&#8221;, quasi a rendere pi\u00f9 obsoleta la sua lettera. In particolare, in nome dell&#8217;apertura della teologia alle scienze sociali, la teoria marxista veniva sempre pi\u00f9 utilizzata come strumento di analisi del mondo ecclesiale, cosa che egli percepiva come un grande pericolo per la fede. A poco a poco, anche a Tubinga, l&#8217;atmosfera sembrava sempre pi\u00f9 irrespirabile. In particolare, ebbe difficolt\u00e0 a gestire le agitazioni studentesche durante gli eventi del maggio 1968, che hanno accelerato il suo allontanamento dai settori pi\u00f9 apertamente contestatori della Chiesa. Sconvolto da quelli che considerava i compromessi demagogici dei suoi colleghi, si dimise dalla cattedra di Tubinga per assumerne una nuova presso la nuova Universit\u00e0 di Ratisbona, meno prestigiosa ma molto pi\u00f9 conservatrice.\u00a0<\/p>\n\n\n\n<p>Tuttavia, Peter Seewald ha dimostrato che \u00e8 falso e semplicistico dipingere Ratzinger come un audace innovatore che improvvisamente \u00e8 diventato reazionario dopo essere stato traumatizzato dalla rivolta dei suoi studenti. In realt\u00e0, fin dal Concilio, espresse grandi riserve sulle posizioni pi\u00f9 all&#8217;avanguardia; e viceversa, nel 1970, firm\u00f2 con altri teologi tedeschi un memorandum alla Santa Sede in cui si chiedeva l&#8217;abolizione dell&#8217;obbligo del celibato sacerdotale. Altrettanto falsa \u00e8 la leggenda, propagandata in particolare da Hans K\u00fcng, secondo cui Paolo VI avrebbe ricevuto i due teologi in udienza privata negli anni Sessanta e, dopo essersi confrontato con un incorruttibile K\u00fcng, avrebbe offerto a Ratzinger altissime cariche nella Chiesa in cambio della sua sottomissione a una linea pi\u00f9 conservatrice&#8230;<\/p>\n\n\n\n<p>Il suo nomadismo accademico, insolitamente elevato anche per gli standard delle universit\u00e0 dell&#8217;epoca, se da un lato gli ha permesso di moltiplicare gli scambi fruttuosi, dall&#8217;altro gli ha impedito di radicarsi in una facolt\u00e0 e di diventare &#8220;fare scuola&#8221;, il che non pu\u00f2 che sollevare interrogativi tra i suoi biografi: quest&#8217;uomo, unanimemente descritto come straordinariamente cortese e affabile, modesto e riservato fino alla timidezza, non \u00e8 mai sembrato andare molto d&#8217;accordo o a lungo con i suoi colleghi pi\u00f9 stretti, e in molte occasioni ha mostrato un&#8217;intransigenza intellettuale che lo ha portato a preferire di andarsene piuttosto che accogliere i suoi avversari.<\/p>\n\n\n\n<p>Tuttavia, il 1968 \u00e8 tutt&#8217;altro che un ricordo puramente negativo per lui: \u00e8 l&#8217;anno in cui viene pubblicata la sua<em> Introduzione al cristianesimo<\/em> (<em>Einf\u00fchrung in das Christentum<\/em>), una sintesi delle sue lezioni di Tubinga che mette in campo un grande sforzo pedagogico per presentare la fede cristiana in un linguaggio chiaro e accessibile: un enorme successo editoriale in Germania (45.000 copie vendute in un anno) e poi all&#8217;estero, l&#8217;opera lo fa conoscere ben oltre gli specialisti di teologia, come un intellettuale impegnato nel dibattito pubblico.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/SIPA_00649980_000002-scaled-e1672239035211.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2560\"\n        data-pswp-height=\"1708\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/SIPA_00649980_000002-scaled-e1672239035211-330x220.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/SIPA_00649980_000002-scaled-e1672239035211-690x460.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/SIPA_00649980_000002-scaled-e1672239035211-1340x894.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/SIPA_00649980_000002-scaled-e1672239035211-125x83.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">\u00a9 GALAZKA\/SIPA<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<h2 class=\"wp-block-heading\">Joseph, cardinale Ratzinger : miti e realt\u00e0 di un \u201cgrande inquisitore\u201d<\/h2>\n\n\n\n<p>Nel corso del tempo, \u00e8 innegabile che ci sia stata una graduale svolta conservatrice nel pensiero di Joseph Ratzinger, che negli anni Settanta vedeva la sua cattedra pi\u00f9 come una difesa e un&#8217;illustrazione dell&#8217;ortodossia romana, in un momento in cui i fondamenti della sua fede sembravano essere messi in discussione. Le sue ansie per l&#8217;aggravarsi della crisi della Chiesa erano fondamentalmente le stesse di Paolo VI, che nel 1970 lo nomin\u00f2 membro della Commissione Teologica Internazionale. Da quel momento in poi ebbe l&#8217;orecchio dei circoli romani.&nbsp;<\/p>\n\n\n\n<p>Al tramonto del suo pontificato, Paolo VI lo scelse come arcivescovo di Monaco di Baviera, succedendo al cardinale D\u00f6pfner (altra grande voce progressista del Concilio), recentemente scomparso: fu consacrato il 28 maggio 1977 nella cattedrale della citt\u00e0; il 27 giugno dell&#8217;anno successivo, il Papa lo cre\u00f2 cardinale. Pur avendo acquisito visibilit\u00e0 e autorevolezza internazionale come membro del Sacro Collegio (\u00e8 stato relatore al Sinodo dei Vescovi del 1980 e delegato del Papa a vari congressi missionari), il suo breve episcopato a Monaco (quattro anni e mezzo) \u00e8 stato sostanzialmente segnato da una grande continuit\u00e0 con il suo predecessore e, in verit\u00e0, da poche decisioni degne di nota. Nella capitale bavarese, il fatto che molti vedranno quando diventer\u00e0 Papa \u00e8 gi\u00e0 evidente: non \u00e8 un uomo di governo, ma piuttosto un insegnante e un uomo di dottrina. \u00c8 riluttante a prendere decisioni difficili con autorit\u00e0.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Nel corso del tempo, \u00e8 innegabile che ci sia stata una graduale svolta conservatrice nel pensiero di Joseph Ratzinger, che negli anni Settanta vedeva la sua cattedra pi\u00f9 come una difesa e un&#8217;illustrazione dell&#8217;ortodossia romana, in un momento in cui i fondamenti della sua fede sembravano essere messi in discussione.<\/p><cite>Jean-Beno\u00eet Poulle<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Partecip\u00f2 come elettore ai due conclavi del 1978 che elessero prima l&#8217;effimero Giovanni Paolo I e poi, in ottobre, il cardinale Wojtyla, che divenne Papa Giovanni Paolo II. Con il pontefice polacco, l&#8217;arcivescovo di Monaco ha trovato un uomo che conosceva e che condivideva fondamentalmente la sua analisi del Concilio e del periodo postconciliare. Per questo motivo Giovanni Paolo II lo ha nominato Prefetto della Congregazione per la Dottrina della Fede (CDF) il 25 novembre 1981. Nel febbraio 1982, l&#8217;arcivescovo Ratzinger si dimise dalla sede di Monaco e part\u00ec per Roma. La Congregazione per la Dottrina della Fede \u00e8 senza dubbio il dicastero pi\u00f9 importante della Curia romana: creata nel 1965, sostituisce l&#8217;ex Sant&#8217;Uffizio, braccio disciplinare del potere papale, responsabile di assicurare la purezza della dottrina e dei costumi, erede a sua volta della &#8220;Sacra Congregazione dell&#8217;Inquisizione Romana e Universale&#8221; creata nel 1542 da Papa Paolo III. \u00c8 tanto pi\u00f9 centrale in quanto, fino al 1968, \u00e8 stata l&#8217;unica congregazione romana ad avere come prefetto il Papa stesso, essendo il suo capo esecutivo solo il &#8220;segretario&#8221; e poi &#8220;pro-prefetto&#8221; della <em>Suprema<\/em>. Il suo scopo \u00e8 controllare l&#8217;ortodossia della dottrina professata dai membri della Chiesa e vigilare sull&#8217;integrit\u00e0 della fede: prende posizione sui problemi teologici e dottrinali del momento e spesso decide pesanti sanzioni canoniche, che vanno dalla sospensione dell&#8217;insegnamento alla scomunica. In materia di morale, ha anche il potere di imporre sanzioni disciplinari al clero che commette <em>delicta graviora<\/em>, i reati pi\u00f9 importanti, tra cui gli abusi sessuali. Fu quindi nominato in una posizione estremamente delicata, che concentrava tutte le critiche al centralismo romano nel suo aspetto repressivo.&nbsp;<\/p>\n\n\n\n<p>Cos\u00ec, pi\u00f9 di ogni altro, il cardinale Ratzinger avrebbe incarnato la ripresa disciplinare della Chiesa cattolica, il ristabilimento dell&#8217;ordine voluto da Giovanni Paolo II dopo le aperture e le turbolenze del periodo post-conciliare. Per 23 anni, ha visto il Papa faccia a faccia ogni marted\u00ec a pranzo e ogni venerd\u00ec sera per affrontare i temi di attualit\u00e0, oltre a numerosi incontri informali, al punto da diventare uno dei suoi pi\u00f9 stretti collaboratori, forse addirittura il pi\u00f9 stretto. Ha svolto anche un ruolo importante come consulente, redattore e poi correttore di tutti i testi magisteriali di Giovanni Paolo II (encicliche, dichiarazioni, discorsi in udienza, ecc.), tanto che i testi pi\u00f9 importanti del pontificato, come le encicliche <em>Veritatis Splendor<\/em> (1994, sulla teologia morale) e <em>Fides et Ratio<\/em> (1998, su fede e ragione), gli devono molto. A capo di una congregazione che conta una ventina di cardinali e vescovi come membri e diversi teologi di fama come consulenti, \u00e8 lui decide in ultima istanza sull&#8217;applicazione di misure spesso decise collegialmente, e supervisiona anche l&#8217;attivit\u00e0 dei suoi uffici. \u00c8 anche, <em>ex officio<\/em>, presidente della Commissione Teologica Internazionale e della Pontificia Commissione Biblica.\u00a0<\/p>\n\n\n\n<p>Fin dai primi anni in cui ricopr\u00ec questo incarico, diede l&#8217;impressione di voler chiudere la parentesi liberale del periodo postconciliare, segnata dalla comprensione piuttosto che dalla condanna. Le sanzioni canoniche piovvero sui teologi pi\u00f9 innovativi, ai quali fu tolta la licenza di insegnare nelle universit\u00e0 cattoliche: l&#8217;americano Charles Curran a Washington, nel 1986, per aver difeso la liceit\u00e0 della contraccezione; il tedesco Eugen Drewermann a Paderborn, nel 1991, per la sua interpretazione psicoanalitica della Bibbia; il francescano svizzero Eugen Imbach, nel 2002, a Lucerna, per aver negato la possibilit\u00e0 dei miracoli&#8230; Importanti teologi del Vaticano II, come Edward Schillebeeckx, vengono convocati a Roma per spiegaresi e giustificare le loro posizioni. E se Hans K\u00fcng venne risparmiato dal suo ex-collega Ratzinger, \u00e8 solo perch\u00e9 aveva gi\u00e0 perso ogni missione canonica nel 1979&#8230;\u00a0<\/p>\n\n\n\n<p>Ma \u00e8 soprattutto contro la teologia della liberazione che combatte il prefetto della <em>Suprema<\/em>: secondo questa corrente latinoamericana, che si ispira a griglie analitiche marxiste, il messaggio evangelico \u00e8 soprattutto un invito a lottare contro le strutture di oppressione capitalistiche e coloniali. Per Ratzinger si trattava di un&#8217;intollerabile politicizzazione del messaggio di Cristo: la figura di spicco di questa corrente, il francescano brasiliano Leonardo Boff, fu interdetto dall&#8217;insegnamento e dalle pubblicazioni nel 1985, poi sospeso dal sacerdozio nel 1992: lasci\u00f2 quindi il sacerdozio e si spos\u00f2. Gli anni di Ratzinger della CDF sono stati segnati anche da una rinascita dell&#8217;ordine dei gesuiti, molti dei quali avevano professato posizioni avanzate sotto il generalato del loro superiore Pedro Arrupe (1965-1981).<\/p>\n\n\n\n<p>Questa forma di intransigenza, proprio mentre la figura mediatica di Giovanni Paolo II godeva di grande popolarit\u00e0 fino agli anni &#8217;90, dall&#8217;altro gli \u00e8 valsa molte critiche: la stampa francese lo ha soprannominato il <em>Panzerkardinal<\/em>, ed \u00e8 stato molto contestato anche all&#8217;interno della Chiesa tedesca &nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-5876' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/#easy-footnote-bottom-6-5876' title='si veda la Dichiarazione di Colonia del 1987'><sup>6<\/sup><\/a><\/span><\/span>. Tuttavia, per il movimento conservatore, egli \u00e8 un maestro di pensiero e incarna una sorta di via media nella ricezione del Concilio tra progressisti e tradizionalisti, che ha espresso in particolare nel suo <em>Dialogo sulla fede<\/em> 1985&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-7-5876' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/#easy-footnote-bottom-7-5876' title='Libro intervista con Vittorio Messori, conosciuto nel mondo con il titolo &lt;em&gt;Ratzinger Report&lt;\/em&gt;'><sup>7<\/sup><\/a><\/span><\/span>. Per lui \u00e8 urgente riaffermare i fondamenti intellettuali del cattolicesimo. Deplorava l&#8217;inadeguatezza di molti catechismi post-conciliari e, per porvi rimedio, ha diretto il <em>Catechismo della Chiesa Cattolica<\/em> pubblicato nel 1992. \u00c8 soprattutto la sua critica alla caotica attuazione della riforma liturgica, voluta dal Vaticano II ma imposta solo nel 1969, a trovare maggiore eco in questi ambienti: egli lamenta la perdita del senso del sacro nelle cerimonie eucaristiche e la povert\u00e0 di molte liturgie. Negli anni &#8217;90 ha preso piede il grande tema della critica alla &#8220;dittatura del relativismo&#8221; nelle societ\u00e0 contemporanee, che mette a tacere l&#8217;aspirazione dell&#8217;uomo alla verit\u00e0. Per combattere questo relativismo, nel 2000 la CDF ha pubblicato la dichiarazione <em>Dominus Jesus<\/em>, &#8220;sull&#8217;universalit\u00e0 e unicit\u00e0 della salvezza in Ges\u00f9 Cristo e nella sua Chiesa&#8221;: In contrasto con i tentativi ecumenici e il dialogo interreligioso in cui Giovanni Paolo II si era risolutamente impegnato (negli anni precedenti erano state firmate diverse dichiarazioni congiunte con le Chiese protestanti e ortodosse), veniva riaffermata la pretesa della Chiesa cattolica di essere l&#8217;unica via di salvezza: la sua ricezione era estremamente controversa nei settori liberali della Chiesa.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Questa forma di intransigenza, proprio mentre la figura mediatica di Giovanni Paolo II godeva di grande popolarit\u00e0 fino agli anni &#8217;90, dall&#8217;altro gli \u00e8 valsa molte critiche: la stampa francese lo ha soprannominato il <em>Panzerkardinal<\/em>.<\/p><cite>Jean-Beno\u00eet Poulle<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Il ruolo del cardinale Ratzinger cresce ancora negli anni 1990-2000, con l&#8217;aggravarsi della malattia di Giovanni Paolo II: dopo aver raggiunto il grado cerimoniale di cardinale-vescovo (1993), diventa vice-decano (1998) e poi decano (2002) del Collegio cardinalizio, mentre numerosi riconoscimenti premiano la sua carriera (dottorati honoris causa, elezione a membro straniero dell&#8217;Acad\u00e9mie des sciences morales et politiques in Francia, ecc.) L&#8217;immagine del braccio destro del Papa \u00e8 tanto pi\u00f9 appropriata in quanto Giovanni Paolo II ha avuto anche un braccio sinistro nella persona dei suoi successivi Segretari di Stato, Agostino Casaroli (1979-1990) e Angelo Sodano (1990-2005), senza dimenticare cardinali influenti come il francese Roger Etchegaray (1922-2016) o, alla fine, Giovanni-Battista Re (nato nel 1933), Prefetto della Congregazione dei Vescovi: Tutte queste figure incarnano una linea di apertura, o almeno pi\u00f9 diplomatica, che vuole fare da contrappunto alla sua intransigenza. Ma Ratzinger \u00e8 ormai una figura chiave: alla Via Crucis del 2005, da lui presieduta al posto di Giovanni Paolo II morente, ha destato grande impressione il suo discorso allarmistico sullo stato della Chiesa, &#8220;la barca di San Pietro&#8221; che &#8220;imbarca acqua da tutte le parti&#8221;&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-8-5876' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/#easy-footnote-bottom-8-5876' title='Meditazione del 25 marzo 2005: &lt;a href=&quot;https:\/\/www.vatican.va\/news_services\/liturgy\/2005\/documents\/ns_lit_doc_20050325_via-crucis-present_fr.html&quot;&gt;https:\/\/www.vatican.va\/news_services\/liturgy\/2005\/documents\/ns_lit_doc_200&lt;\/a&gt;&lt;a href=&quot;https:\/\/www.vatican.va\/news_services\/liturgy\/2005\/documents\/ns_lit_doc_20050325_via-crucis-present_fr.html&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;5&lt;\/a&gt;&lt;a href=&quot;https:\/\/www.vatican.va\/news_services\/liturgy\/2005\/documents\/ns_lit_doc_20050325_via-crucis-present_fr.html&quot;&gt;0325_via-crucis-present_fr.html&lt;\/a&gt;.'><sup>8<\/sup><\/a><\/span><\/span>.&nbsp;<\/p>\n\n\n\n<p>Dopo la morte di Giovanni Paolo II (marzo 2005), \u00e8 stato incaricato di presiedere i suoi funerali, durante i quali ha tenuto una straordinaria omelia, e poi, come cardinale decano, di organizzare il nuovo conclave. A causa della sua et\u00e0, non \u00e8 considerato un papabile, ma piuttosto un &#8220;grande elettore&#8221; ascoltato dai suoi pari. Ma molti cardinali al di fuori delle fazioni costituite, soprattutto extraeuropei, vennero presto toccati dalla sua premurosa accoglienza, ed egli ha rapidamente aggregato tutte le voci di coloro che sostenevano la continuit\u00e0 con il papa polacco. Il suo principale concorrente, per un campo progressista a sua volta molto diviso, era un certo Jorge Maria Bergoglio, allora 64enne. Ma Bergoglio, secondo un diario anonimo del conclave&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-9-5876' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/#easy-footnote-bottom-9-5876' title='Secondo la ricostruzione proposta da un anonimo &amp;#8220;diario del conclave&amp;#8221; di un cardinale elettore (forse Attilio Nicora), affidato da quest&amp;#8217;ultimo al cardinale Achille Silvestrini, non elettore, e poi da quest&amp;#8217;ultimo alla rivista italiana di geopolitica Limes'><sup>9<\/sup><\/a><\/span><\/span>, ha fatto capire ai suoi sostenitori che non voleva diventare Papa, e ha chiesto loro di votare anche per Ratzinger: al quarto turno di votazione, ha ricevuto 84 voti su 115, pi\u00f9 della maggioranza canonica dei due terzi, dopo solo 24 ore di conclave. La scelta dei suoi pari \u00e8 stata chiara e senza appello.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Papa Benedetto XVI : i malintesi di un pontificato restauratore&nbsp;<\/h2>\n\n\n\n<p>Il nome &#8220;Benedetto XVI&#8221; scelto dal nuovo papa \u00e8 un doppio riferimento al suo predecessore Benedetto XV (papa dal 1914 al 1922), noto per i suoi tentativi di pace durante la Prima Guerra Mondiale, e a San Benedetto da Norcia (480-547), fondatore del monachesimo occidentale e co-patrono d&#8217;Europa. In questo modo, Papa Ratzinger intende tornare a una forma di continuit\u00e0 e moderazione: chiamarsi &#8220;Giovanni Paolo III&#8221; sarebbe sembrato troppo pretenzioso, &#8220;Giovanni XXIV&#8221; o &#8220;Paolo VII&#8221; troppo progressista, &#8220;Pio XIII&#8221; troppo reazionario.&nbsp;<\/p>\n\n\n\n<p>Fin dall&#8217;inizio ha seguito le orme di Giovanni Paolo II e ha usato gli stessi codici nelle sue apparizioni pubbliche, ma c&#8217;era un grande contrasto tra la personalit\u00e0 eminentemente carismatica del Papa polacco e la sua personalit\u00e0 introversa e timida, che si presentava sul balcone di San Pietro come un &#8220;umile lavoratore nella vigna del Signore&#8221;. Le sue prime apparizioni colpiscono i commentatori e i giornalisti per la scarsa sostanza politica dei suoi discorsi, che sono soprattutto spirituali e invitano a ricentrarsi su Cristo. Non si pu\u00f2 fare a meno di fare un paragone con Giovanni Paolo II a suo svantaggio. Non potendo mantenere il suo ritmo quasi frenetico di viaggi internazionali (Benedetto XVI ne ha fatti 25 in otto anni, senza contare i 30 viaggi in Italia), ha rinunciato a viaggiare per presiedere le beatificazioni, anche se la maggior parte dei suoi viaggi all&#8217;estero ha avuto successo. Le folle cattoliche hanno imparato ad amarlo, come hanno dimostrato le Giornate Mondiali della Giovent\u00f9 di Colonia nel 2005, di Sydney nel 2008 e di Madrid nel 2011, oltre al viaggio in Francia del 2008. Ma a poco a poco si \u00e8 creato un malessere diffuso e un&#8217;incomprensione reciproca tra un Papa poco comunicativo e maldestro e un mondo mediatico molto ignorante sulla Chiesa cattolica e, a priori, ad essa ostile. Il suo pontificato viene quindi spesso analizzato come una successione di crisi mediatiche mal gestite, che hanno tutte peggiorato l&#8217;immagine della Chiesa cattolica nell&#8217;opinione pubblica mondiale. Se la figura di Benedetto XVI non pu\u00f2 essere ridotta a queste crisi, sarebbe altrettanto inutile ignorarle.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Le sue prime apparizioni colpiscono i commentatori e i giornalisti per la scarsa sostanza politica dei suoi discorsi, che sono soprattutto spirituali e invitano a ricentrarsi su Cristo. <\/p><cite>Jean-Beno\u00eet Poulle<\/cite><\/blockquote><\/figure>\n\n\n\n<p>In primo luogo, nel settembre 2006, c&#8217;\u00e8 stato il discorso di Ratisbona, in cui ha citato l&#8217;imperatore bizantino Manuele Paleologo sulla violenza intrinseca della conquista islamica, che ha suscitato un&#8217;indignazione nel mondo musulmano e ha rallentato il dialogo con l&#8217;Islam, nonostante i suoi sforzi per dissipare ogni incomprensione successiva.&nbsp;<\/p>\n\n\n\n<p>C&#8217;\u00e8 poi la vasta questione dei rapporti con il mondo tradizionalista, verso la quale Benedetto XVI ha compiuto un passo decisivo nell&#8217;estate del 2007 con il <em>motu proprio <\/em>(decreto) <em>Summorum Pontificum<\/em>, che ha liberalizzato l&#8217;uso della Messa tradizionale in vigore prima della riforma liturgica, d&#8217;ora in poi chiamata &#8220;Forma Straordinaria del Rito Romano&#8221;. Si tratta di una traduzione pratica di una delle sue idee chiave, l'&#8221;ermeneutica della continuit\u00e0&#8221;, che interpreta il Vaticano II come un concilio nella linea del magistero preesistente, che doveva permettere il ritorno a una tradizione autentica e viva, ma senza grandi stravolgimenti. Sia i progressisti che i tradizionalisti della Fraternit\u00e0 Sacerdotale San Pio X lo vedono piuttosto come un consiglio di rottura; per quanto riguarda questi ultimi, Benedetto XVI non vuole rimanere sull&#8217;amaro fallimento del protocollo d&#8217;intesa che aveva firmato nel 1988 come prefetto della CDF con il loro leader, l&#8217;arcivescovo Marcel Lefebvre (1905-1991), prima che il prelato ritirasse la firma e venisse scomunicato per aver consacrato 4 vescovi senza mandato da Roma: Nel gennaio 2009 ha tolto la scomunica ai quattro vescovi della FSSPX, preludio ai colloqui dottrinali, tra cui il vescovo britannico Richard Williamson, noto per i suoi commenti negazionisti e cospiratori, che hanno suscitato uno scandalo mondiale e danneggiato l&#8217;immagine del Papa, che allo stesso tempo era molto impegnato in un impegnativo dialogo intellettuale con l&#8217;ebraismo. Le discussioni dottrinali in vista della concessione dello status canonico alla FSSPX non hanno avuto successo.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/SIPA_REX40286919_000004-scaled-e1672245259832.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2560\"\n        data-pswp-height=\"1689\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/SIPA_REX40286919_000004-scaled-e1672245259832-330x218.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/SIPA_REX40286919_000004-scaled-e1672245259832-690x455.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/SIPA_REX40286919_000004-scaled-e1672245259832-1340x884.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/SIPA_REX40286919_000004-scaled-e1672245259832-125x82.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">\u00a9 AGF s.r.l. \/ Rex Features<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>Pochi mesi dopo, \u00e8 stato il &#8220;caso preservativi&#8221; durante il suo viaggio di andata in Africa, quando ha dichiarato che la loro distribuzione &#8220;aumenta il problema&#8221; dell&#8217;AIDS, suscitando l&#8217;indignazione delle organizzazioni che lottano contro questa pandemia. In un libro-intervista con il suo amico, il giornalista bavarese Peter Seewald, nel 2010, sembra tornare su questa idea e accettare che in alcuni casi l&#8217;uso del preservativo costituisca un primo passo verso una &#8220;umanizzazione della sessualit\u00e0&#8221;.<\/p>\n\n\n\n<p>Infine, l&#8217;ultimo e pi\u00f9 clamoroso scandalo scoppiato durante il suo pontificato \u00e8 stato quello degli abusi sessuali su minori nel 2010. Benedetto XVI ha una lunga familiarit\u00e0 con questo tema: come ex prefetto della CDF, responsabile per i <em>delicta graviora<\/em>, si era gi\u00e0 occupato di queste questioni e delle sanzioni contro i colpevoli. Sebbene inizialmente sia stato lento a prendere le misure della portata del fenomeno, in seguito ha perorato con Giovanni Paolo II una linea pi\u00f9 intransigente nel trattamento della pedocriminalit\u00e0 (la lettera <em>De delictis gravioribus<\/em> del 2001, che impone ai vescovi di segnalare tutti i casi a Roma), ma solo molto raramente ha vinto la causa contro il cardinale Sodano, seguace del vecchio metodo di spostare discretamente il colpevole. Solo alla morte del pontefice polacco \u00e8 stato possibile adottare sanzioni canoniche e far avanzare l&#8217;indagine penale contro il fondatore dei Legionari di Cristo, Marcial Maciel (1920-2008), che aveva commesso un numero spaventoso di crimini. Una volta diventato Papa, non si \u00e8 discostato da questa linea di &#8220;tolleranza zero&#8221; e, in particolare, ha convocato in Vaticano i vescovi dell&#8217;Irlanda (uno dei Paesi in cui i casi sono di pi\u00f9 alto profilo) nel 2010, scrivendo una lettera pastorale alle vittime. Ma non \u00e8 riuscito a impedire che nell&#8217;opinione pubblica occidentale si diffondesse l&#8217;idea che la Santa Sede fosse travolta da questi scandali o addirittura, nel peggiore dei casi, complice.&nbsp;<\/p>\n\n\n\n<p>Per quanto riguarda la sua opera magisteriale, Benedetto XVI ha pubblicato tre encicliche e ne ha scritta una quarta, <em>Lumen fidei<\/em>, pubblicata da Papa Francesco poco dopo la sua rinuncia; esse hanno come tema le tre virt\u00f9 teologali: carit\u00e0 (<em>Deus caritas est<\/em>, 2006), speranza (<em>Spe salvi,<\/em> 2006) e fede (<em>Lumen fidei<\/em>, 2013); la <em>Caritas in veritate<\/em> (2009) \u00e8 stata considerata l'&#8221;enciclica sociale&#8221; del Papa, e in essa sono gi\u00e0 state affrontate in modo significativo le questioni ambientali, ma va detto che rimane l&#8217;opera di un teologo che \u00e8 meno avanti del suo successore su questi temi, come se avesse difficolt\u00e0 a parlare della societ\u00e0 in quanto tale piuttosto che di Dio. Da qui l&#8217;impressione di un discorso soprattutto teologico ad intra; in questo ambito, alcuni scritti del Papa saranno comunque dei successi pubblici, come la sua trilogia su Ges\u00f9 di Nazareth (2007, 2011, 2012), che porta la doppia firma &#8220;Joseph Ratzinger-Benoit XVI&#8221;.&nbsp;<\/p>\n\n\n\n<p>\u00c8 soprattutto nel governo della Chiesa che Benedetto XVI ha i suoi problemi pi\u00f9 gravi. Questo intellettuale sembra avere difficolt\u00e0 a scegliere uomini di cui fidarsi: per succedere all&#8217;onnipotente cardinale Sodano, andato in pensione nel 2006, ha scelto come Segretario di Stato l&#8217;arcivescovo di Genova Tarcisio Bertone (classe 1934), che era gi\u00e0 stato il suo numero due come Segretario della CDF. Bertone \u00e8 un prelato senza alcuna esperienza diplomatica, che ha presto raccolto il malcontento intorno a s\u00e9 con le sue iniziative intempestive. Allo stesso modo, la riforma della curia, pianificata da tempo, ha portato a pochi cambiamenti degni di nota, ad eccezione della creazione nel 2011 del Pontificio Consiglio per la Nuova Evangelizzazione &#8211; un altro tema caro al Papa, che ha tenuto conto delle specificit\u00e0 dell&#8217;annuncio della fede cristiana nelle societ\u00e0 occidentali ampiamente secolarizzate. L&#8217;inerzia che ne deriva \u00e8 la causa di molti errori di comunicazione, i pi\u00f9 gravi dei quali degenerano a loro volta in scandali.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00c8 soprattutto nel governo della Chiesa che Benedetto XVI ha i suoi problemi pi\u00f9 gravi. Questo intellettuale sembra avere difficolt\u00e0 a scegliere uomini di cui fidarsi.<\/p><cite>Jean-Beno\u00eet Poulle<\/cite><\/blockquote><\/figure>\n\n\n\n<p>\u00c8 cos\u00ec che nel 2012 scoppi\u00f2 l&#8217;affare <em>Vatileaks<\/em>, dopo che la Santa Sede ha fatto trapelare alla televisione italiana documenti provenienti dalla corrispondenza del Papa con il nunzio a Washington, l&#8217;arcivescovo Carlo Vigano (che durante il pontificato di Francesco ha sconfinato in teorie del complotto francamente deliranti, ma che allora era uno stimato diplomatico), volendo quest&#8217;ultimo svolgere il ruolo di &#8220;informatore&#8221; sulle disfunzioni della curia. L&#8217;autore delle fughe di notizie \u00e8 nientemeno che il maggiordomo del Papa, Paolo Gabriele, anch&#8217;egli convinto di agire per il bene della Chiesa, ma i suoi probabili sponsor all&#8217;interno della Curia romana non vengono smascherati, nonostante una commissione cardinalizia istituita per rintracciare i suoi complici. Non si sa nemmeno quali siano i legami esatti tra lo scandalo <em>Vatileaks <\/em>e le turbolenze vissute sotto Benedetto XVI dai servizi finanziari del Vaticano, come lo IOR (Istituto per le Opere Religiose), che hanno portato alle dimissioni del suo direttore Ettore Gotti Tedeschi nello stesso anno.\u00a0<\/p>\n\n\n\n<p>Comunque sia, \u00e8 certo che sia stato il senso di stallo della Curia, oltre alle infermit\u00e0 di un uomo di 85 anni che faticava a muoversi e che aveva osservato da vicino le difficolt\u00e0 di governo legate alla malattia di Giovanni Paolo II, a portare alla decisione pi\u00f9 eclatante di Benedetto XVI: quella di rinunciare volontariamente al soglio di San Pietro l&#8217;11 febbraio 2013, come annunci\u00f2 in latino quel giorno ai cardinali riuniti in concistoro. La sua decisione sembra essere stata presa l&#8217;estate precedente e si \u00e8 espressa con un&#8217;anticipazione che all&#8217;epoca non \u00e8 stata compresa: visitando la citt\u00e0 dell&#8217;Aquila (Abruzzo), colpita dal terremoto, Benedetto XVI ha deposto il suo pallio di Arcivescovo di Roma sulla tomba di un suo predecessore del XIII secolo, Celestino V (1210-1296). Questo papa, un santo eremita spinto quasi per caso al soglio di Pietro nel 1294 e canonizzato poco dopo la sua morte, fu l&#8217;ultimo a dimettersi volontariamente dalla cattedra di San Pietro dopo pochi mesi, travolto dagli intrighi delle fazioni romane. Aveva allora la stessa et\u00e0 del suo lontano successore quando dovette prendere la stessa decisione.<\/p>\n\n\n\n<p>Cos\u00ec facendo, Benedetto XVI sembra indicare chiaramente il modo in cui ha vissuto il proprio pontificato: una carica mai desiderata&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-10-5876' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/#easy-footnote-bottom-10-5876' title='Aveva previsto il suo trasferimento in Baviera dopo il conclave del 2005, cominciando il trasloco della sua gigantesca biblioteca'><sup>10<\/sup><\/a><\/span><\/span>, accettata per dovere ma di cui non si sentiva degno, e alla fine troppo pesante per le sue forze, nonostante il rispetto, l&#8217;attaccamento e spesso la tenerezza che ha saputo conquistare da parte dei fedeli cattolici, cos\u00ec come aveva finalmente conquistato la considerazione del mondo intellettuale multireligioso. Spetter\u00e0 agli storici del pontificato dire se questa impressione di incompiutezza e fallimento fosse giustificata.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Benedetto XVI, papa emerito: le ambiguit\u00e0 di uno status inedito<\/h2>\n\n\n\n<p>Dopo le sue dimissioni, entrate in vigore il 28 febbraio 2013, Benedetto XVI si \u00e8 ritirato per qualche tempo nella residenza di Castel Gandolfo, il luogo di villeggiatura papale, per non dare l&#8217;impressione di interferire con la sua sola presenza nell&#8217;elezione del suo successore. Il 23 marzo ha ricevuto la visita di Papa Francesco. Si \u00e8 poi trasferito nel monastero <em>Mater Ecclesiae<\/em> nei giardini vaticani, a poca distanza da Santa Marta, una foresteria dove Francesco ha deciso di risiedere, rinunciando al Palazzo Apostolico ufficiale.&nbsp;<\/p>\n\n\n\n<p>Se i casi di rinuncia al soglio pontificio da parte del papa sono previsti dal diritto canonico, e quindi non pongono alcun problema formale di legalit\u00e0, la questione della sua opportunit\u00e0 si pone immediatamente, e suscita un vivace dibattito nel mondo cattolico. Il sentimento prevalente sembrava essere quello del rispetto e della comprensione per una decisione che apparteneva solo a lui, ma si sono sentite alcune voci dissenzienti, che hanno espresso apertamente che questa rinuncia era catastrofica per la Chiesa, in quanto sembrava un&#8217;ammissione di fallimento. A Benedetto \u00e8 stato quindi conferito lo status inedito (gli altri papi che avevano dovuto rinunciare alla tiara erano tornati a essere cardinali) di papa emerito, cos\u00ec come tutti i vescovi diocesani diventano vescovi emeriti dopo aver raggiunto l&#8217;et\u00e0 di 75 anni. Mantiene la tonaca bianca propria del pontefice romano, ma abbandona altri ornamenti (anello del pescatore) che appartengono solo al papa in carica. Alcuni canonisti e teologi hanno tuttavia sottolineato la natura inquietante e irregolare di questo status, fonte di confusione: secondo alcuni, Benedetto XVI avrebbe dovuto riprendere il nome di Joseph Ratzinger e assumere invece il titolo di arcivescovo o vescovo emerito di Roma&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-11-5876' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/#easy-footnote-bottom-11-5876' title='Significativo che la sera della propria elezione, papa Francesco si sia riferito a s\u00e9 stesso come vescovo di Roma e abbia chiesto di pregare per il &amp;#8220;nostro vescovo emerito&amp;#8221;'><sup>11<\/sup><\/a><\/span><\/span> per fugare ogni ambiguit\u00e0: in teologia cattolica, se con la consacrazione episcopale del 1977 ha effettivamente ricevuto il massimo grado del sacerdozio, che gli conferisce un carattere sacro (legato alla &#8220;potest\u00e0 d&#8217;ordine&#8221;), il primato pontificio dipende dalla potest\u00e0 di giurisdizione universale, che \u00e8 certamente annessa alla funzione di vescovo di Roma, ma alla quale si pu\u00f2 rinunciare. In altre parole, Benedetto XVI rimane vescovo a vita, ma non dovrebbe pi\u00f9 portare il titolo di papa &#8211; nemmeno &#8220;emerito&#8221; &#8211; che dipende da una giurisdizione che non ha pi\u00f9&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-12-5876' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/#easy-footnote-bottom-12-5876' title='\u00c8 interessante vedere che teologi progressisti e conservatori sono d&amp;#8217;accordo su questo punto: alle critiche di Andrea Grillo, professore di liturgia al Pontificio Ateneo di Sant&amp;#8217;Anselmo, si aggiungono per una volta quelle del conservatore Roberto de Mattei, in particolare qui, &lt;a href=&quot;http:\/\/chiesa.espresso.repubblica.it\/articolo\/135086875af.html?fr=y&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;http:\/\/chiesa.espresso.repubblica.it\/articolo\/135086875af.html?fr=y&lt;\/a&gt;'><sup>12<\/sup><\/a><\/span><\/span>.\u00a0<\/p>\n\n\n\n<p>Tuttavia, il ritiro del Papa emerito non \u00e8 completo: fino al 2016, partecipa ancora ad alcuni eventi pubblici solenni accanto al suo successore, come i concistori cardinalizi, l&#8217;apertura dell&#8217;Anno della Misericordia (2015) o la cerimonia di canonizzazione dei suoi predecessori Giovanni XIII e Giovanni Paolo II (soprannominata &#8220;messa dei quattro papi&#8221;). Il suo ultimo viaggio fuori dal Vaticano \u00e8 stato nel giugno 2020, a Ratisbona per visitare il fratello Georg, ormai in fin di vita.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Papa Francesco gli ha fatto spesso visita e l&#8217;intesa tra i due uomini in bianco \u00e8 stata molto esibita dalla comunicazione vaticana, quasi a voler offrire una sorta di brevetto di continuit\u00e0 a Francesco attraverso la garanzia del suo predecessore.<\/p><cite>Jean-Beno\u00eet Poulle<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Papa Francesco gli ha fatto spesso visita e l&#8217;intesa tra i due uomini in bianco \u00e8 stata molto esibita dalla comunicazione vaticana, quasi a voler offrire una sorta di brevetto di continuit\u00e0 a Francesco attraverso la garanzia del suo predecessore. Soprattutto, sorvegliato dal suo segretario privato Mons. G\u00e4nswein &#8211; che sotto Francesco \u00e8 rimasto prefetto della Casa Pontificia &#8211; Benedetto riceve ancora molte altre visite, soprattutto da parte dei suoi compatrioti bavaresi, onorificenze (dottorati <em>honoris causa<\/em>), e mantiene, contro ogni previsione, un&#8217;attivit\u00e0 intellettuale: ha una corrispondenza abbastanza estesa (anche sul tema degli abusi sessuali), e pubblica persino un libro-intervista con Peter Seewald nel 2016. Ha anche accettato di partecipare a due libri del cardinale guineano Robert Sarah (nato nel 1945), come prefazione e poi co-autore. Questo ex prefetto della Congregazione per il Culto Divino \u00e8 molto in vista negli ambienti dei fedeli conservatori che si oppongono a Papa Francesco per aver criticato i suoi orientamenti a favore di un allentamento della disciplina ecclesiastica: alcuni lo sognano addirittura come un papa sostituto, che si sbarazzi del le misure progressiste del pontefice argentino: uno dei libri sopra citati difende vigorosamente il celibato sacerdotale. Cos\u00ec facendo, Benedetto XVI rischia di essere strumentalizzato, suo malgrado,&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-13-5876' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/#easy-footnote-bottom-13-5876' title='Durante un sinodo sulla famiglia, alcuni conservatori, in allarme per i cambiamenti disciplinari imposti da Francesco, vengono a chiedergli consiglio: Ratzinger risponde: &amp;#8220;smettetela, non sono il Papa!&amp;#8221;'><sup>13<\/sup><\/a><\/span><\/span> come figura di riferimento dell&#8217;opposizione a Francesco, e alcuni sostenitori dell&#8217;attuale pontefice non esitano pi\u00f9 a chiedergli di rispettare una vera e propria cura del silenzio mediatico.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-14-5876' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/#easy-footnote-bottom-14-5876' title='Come lo stesso Andrea Grillo: &lt;a href=&quot;http:\/\/www.cittadellaeditrice.com\/munera\/una-postfazione-senza-discrezione-ratzinger-si-ostina-a-raccomandare-sarah\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;http:\/\/www.cittadellaeditrice.com\/munera\/una-postfazione-senza-discrezione-ratzinger-si-ostina-a-raccomandare-sarah\/&lt;\/a&gt; ; &lt;a href=&quot;https:\/\/www.adista.it\/articolo\/57240?utm_campaign=shareaholic&amp;amp;utm_medium=facebook&amp;amp;utm_source=socialnetwork&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/www.adista.it\/articolo\/57240?utm_campaign=shareaholic&amp;amp;utm_medium=facebook&amp;amp;utm_source=socialnetwork&lt;\/a&gt;'><sup>14<\/sup><\/a><\/span><\/span> Alla fine, \u00e8 il graduale indebolimento delle sue forze dovuto all&#8217;et\u00e0 che lo costringe a smettere di esprimersi e di accettare visite.&nbsp;<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/SIPA_SIPAUSA31258508_000001-scaled-e1672245218598.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2560\"\n        data-pswp-height=\"1689\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/SIPA_SIPAUSA31258508_000001-scaled-e1672245218598-330x218.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/SIPA_SIPAUSA31258508_000001-scaled-e1672245218598-690x455.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/SIPA_SIPAUSA31258508_000001-scaled-e1672245218598-1340x884.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/SIPA_SIPAUSA31258508_000001-scaled-e1672245218598-125x82.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">\u00a9 Newscom\/upiphotostwo<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>Con la morte del Papa emerito, probabilmente il pi\u00f9 anziano della storia della Chiesa&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-15-5876' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/#easy-footnote-bottom-15-5876' title='Ha superato Leone XIII, morto a 93 anni nel 1903, sebbene papa Agatone, nel VII\u00b0 secolo sarebbe morto a 104, ma la cosa non pu\u00f2 essere verificata'><sup>15<\/sup><\/a><\/span><\/span>, se ne va anche l&#8217;ultimo cardinale ad essere stato creato da Paolo VI, e probabilmente l&#8217;ultimo esperto ad aver partecipato al Concilio Vaticano II. Pi\u00f9 nel profondo, \u00e8 anche una certa esperienza del cattolicesimo e dell&#8217;Europa che muore con lui. Joseph Ratzinger \u00e8 cresciuto ancora in una societ\u00e0 cristiana, dove la religione era profondamente intrecciata alle attivit\u00e0 sociali, inquadrando ogni momento della vita; ha sperimentato allo stesso tempo l&#8217;instaurazione di un regime totalitario, che rappresentava sia la negazione che la caricatura di quel vecchio cristianesimo. Poi ha percepito i rapidi cambiamenti e la profonda secolarizzazione provocati dall&#8217;ingresso nella societ\u00e0 dei consumi. Se prima ha cercato di accompagnarli con l&#8217;aggiornamento del Concilio, che ha modificato il linguaggio con cui la Chiesa parlava al mondo, poi ha cercato di salvaguardare l&#8217;eredit\u00e0 intellettuale della Chiesa, soprattutto nei suoi legami con la ricerca della ragione come si vede nella storia della filosofia occidentale. In questo modo, il suo pontificato restauratore, pur essendo di portata globale, era inseparabile da una certa concezione di &#8220;Occidente&#8221; (anche se nel 2006 aveva paradossalmente rinunciato al tradizionale titolo papale di &#8220;Patriarca d&#8217;Occidente&#8221;), e da un progetto europeo ispirato soprattutto alle sue &#8220;radici cristiane&#8221;, nel senso che le radici sono ancora la fonte della linfa. A questo proposito, \u00e8 molto significativo il discorso tenuto al Coll\u00e8ge des Bernardins durante la sua visita in Francia nel settembre 2008: Benedetto XVI esalta la creazione delle universit\u00e0 dell&#8217;Europa medievale come un&#8217;ammirevole ricerca della Sapienza, che avrebbe conferito una forma di singolarit\u00e0 alla storia dell&#8217;Occidente e un&#8217;identit\u00e0 al continente europeo, da prendere a modello. Tuttavia, il suo pontificato si \u00e8 scontrato con la realt\u00e0 della disaffiliazione religiosa contemporanea, l&#8217;aumento senza precedenti del potere di coloro che non hanno una religione nella societ\u00e0, che ha dato origine a una preoccupazione assillante sul futuro della fede cristiana.\u00a0<\/p>\n\n\n\n<p><em>Fides quaerens intellectum<\/em> (&#8220;la fede che cerca l&#8217;intelligenza&#8221;): questa frase di Anselmo di Canterbury, inventore dell&#8217;argomentazione ontologica nel XII secolo, sembra riassumere la sua traiettoria intellettuale, alla ricerca delle ragioni del credere e delle cause dell&#8217;incredulit\u00e0. Insieme al Papa bavarese, se ne vanno una certa idea di Europa e una certa immagine della Chiesa.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nel corso della sua vita, ha cercato le ragioni della fede con lo stesso ardore delle cause della non-credenza, &#8211; a rischio di causare divisioni. Papa &#8220;intellettuale&#8221;, nel 2005 ha accettato un incarico che considerava troppo pesante per lui e che ha poi abbandonato. Dopo le sue dimissioni nel 2013, gli \u00e8 stato conferito uno status senza precedenti nella storia della Chiesa, quello di Papa emerito, e ha continuato a esercitare una notevole influenza. Benedetto XVI si \u00e8 spento all&#8217;et\u00e0 di 95 anni. Questo saggio biografico cerca di cogliere la sua eredit\u00e0 politica e teologica.<\/p>\n","protected":false},"author":2851,"featured_media":5885,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-angles.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":42,"footnotes":""},"categories":[2163],"tags":[],"staff":[2048],"editorial_format":[2348],"serie":[],"audience":[],"geo":[],"class_list":["post-5876","post","type-post","status-publish","format-standard","hentry","category-in-memoriam","staff-jean-benoit-poulle","editorial_format-prospettive"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":5885,"excerpt":"Nel corso della sua vita, ha cercato le ragioni della fede con lo stesso ardore delle cause della non-credenza, - a rischio di causare divisioni. Papa \"intellettuale\", nel 2005 ha accettato un incarico che considerava troppo pesante per lui e che ha poi abbandonato. Dopo le sue dimissioni nel 2013, gli \u00e8 stato conferito uno status senza precedenti nella storia della Chiesa, quello di Papa emerito, e ha continuato a esercitare una notevole influenza. Benedetto XVI si \u00e8 spento all'et\u00e0 di 95 anni. Questo saggio biografico cerca di cogliere la sua eredit\u00e0 politica e teologica.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>In morte di Papa Benedetto XVI, papa emerito - Il Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"In morte di Papa Benedetto XVI, papa emerito - Il Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Nel corso della sua vita, ha cercato le ragioni della fede con lo stesso ardore delle cause della non-credenza, - a rischio di causare divisioni. Papa &quot;intellettuale&quot;, nel 2005 ha accettato un incarico che considerava troppo pesante per lui e che ha poi abbandonato. Dopo le sue dimissioni nel 2013, gli \u00e8 stato conferito uno status senza precedenti nella storia della Chiesa, quello di Papa emerito, e ha continuato a esercitare una notevole influenza. Benedetto XVI si \u00e8 spento all&#039;et\u00e0 di 95 anni. Questo saggio biografico cerca di cogliere la sua eredit\u00e0 politica e teologica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/\" \/>\n<meta property=\"og:site_name\" content=\"Il Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-31T10:52:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-27T14:00:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/gc-papa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1321\" \/>\n\t<meta property=\"og:image:height\" content=\"763\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescostuffer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/gc-papa.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescostuffer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"42 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/\",\"name\":\"In morte di Papa Benedetto XVI, papa emerito - Il Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/SIPA_AP21004782_000005-scaled-e1672226669414.jpg\",\"datePublished\":\"2022-12-31T10:52:35+00:00\",\"dateModified\":\"2023-09-27T14:00:40+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/7559a86c160571d058b60bd26c75667b\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/SIPA_AP21004782_000005-scaled-e1672226669414.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/SIPA_AP21004782_000005-scaled-e1672226669414.jpg\",\"width\":2560,\"height\":1708,\"caption\":\"Pope Benedict XVI attends his weekly general audience at the Vatican, Wednesday, Dec. 22, 2010. In background is a bronze sculpture, the Resurrection, by artist Pericle Fazzini. (AP Photo\/Alessandra Tarantino)\/Italy_Pope_VAT105\/1012221403\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"In morte di Papa Benedetto XVI, papa emerito\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/\",\"name\":\"Il Grand Continent\",\"description\":\"La scala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/7559a86c160571d058b60bd26c75667b\",\"name\":\"francescostuffer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f7c0805792cd3b59aec4d5d3b527e8fa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f7c0805792cd3b59aec4d5d3b527e8fa?s=96&d=mm&r=g\",\"caption\":\"francescostuffer\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"In morte di Papa Benedetto XVI, papa emerito - Il Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/","og_locale":"it_IT","og_type":"article","og_title":"In morte di Papa Benedetto XVI, papa emerito - Il Grand Continent","og_description":"Nel corso della sua vita, ha cercato le ragioni della fede con lo stesso ardore delle cause della non-credenza, - a rischio di causare divisioni. Papa \"intellettuale\", nel 2005 ha accettato un incarico che considerava troppo pesante per lui e che ha poi abbandonato. Dopo le sue dimissioni nel 2013, gli \u00e8 stato conferito uno status senza precedenti nella storia della Chiesa, quello di Papa emerito, e ha continuato a esercitare una notevole influenza. Benedetto XVI si \u00e8 spento all'et\u00e0 di 95 anni. Questo saggio biografico cerca di cogliere la sua eredit\u00e0 politica e teologica.","og_url":"https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/","og_site_name":"Il Grand Continent","article_published_time":"2022-12-31T10:52:35+00:00","article_modified_time":"2023-09-27T14:00:40+00:00","og_image":[{"width":1321,"height":763,"url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/gc-papa.jpg","type":"image\/jpeg"}],"author":"francescostuffer","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/gc-papa.jpg","twitter_misc":{"Scritto da":"francescostuffer","Tempo di lettura stimato":"42 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/","url":"https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/","name":"In morte di Papa Benedetto XVI, papa emerito - Il Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/SIPA_AP21004782_000005-scaled-e1672226669414.jpg","datePublished":"2022-12-31T10:52:35+00:00","dateModified":"2023-09-27T14:00:40+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/7559a86c160571d058b60bd26c75667b"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/SIPA_AP21004782_000005-scaled-e1672226669414.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/SIPA_AP21004782_000005-scaled-e1672226669414.jpg","width":2560,"height":1708,"caption":"Pope Benedict XVI attends his weekly general audience at the Vatican, Wednesday, Dec. 22, 2010. In background is a bronze sculpture, the Resurrection, by artist Pericle Fazzini. (AP Photo\/Alessandra Tarantino)\/Italy_Pope_VAT105\/1012221403"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/it\/2022\/12\/31\/in-morte-di-papa-benedetto-xvi-papa-emerito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/it\/"},{"@type":"ListItem","position":2,"name":"In morte di Papa Benedetto XVI, papa emerito"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/it\/#website","url":"https:\/\/legrandcontinent.eu\/it\/","name":"Il Grand Continent","description":"La scala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/7559a86c160571d058b60bd26c75667b","name":"francescostuffer","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f7c0805792cd3b59aec4d5d3b527e8fa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f7c0805792cd3b59aec4d5d3b527e8fa?s=96&d=mm&r=g","caption":"francescostuffer"}}]}},"lgc_categories":[{"id":2163,"name":"In Memoriam","slug":"in-memoriam"}],"lgc_author":{"id":2048,"name":"Jean-Beno\u00eet Poulle","slug":"jean-benoit-poulle","description":null,"first_name":null,"last_name":null,"picture":null},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/SIPA_AP21004782_000005-scaled-e1672226669414.jpg","width":2560,"height":1708,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/12\/SIPA_AP21004782_000005-scaled-e1672226669414.jpg","width":2560,"height":1708,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts\/5876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/users\/2851"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/comments?post=5876"}],"version-history":[{"count":1,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts\/5876\/revisions"}],"predecessor-version":[{"id":43631,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts\/5876\/revisions\/43631"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/media\/5885"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/media?parent=5876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/categories?post=5876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/tags?post=5876"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/staff?post=5876"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/editorial_format?post=5876"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/serie?post=5876"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/audience?post=5876"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/geo?post=5876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}