{"id":33518,"date":"2025-05-26T16:00:00","date_gmt":"2025-05-26T14:00:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/it\/?p=33518"},"modified":"2025-05-30T20:03:19","modified_gmt":"2025-05-30T18:03:19","slug":"in-polonia-rafal-trzaskowski-contro-karol-nawrocki-ritratti-incrociati-dei-due-candidati-alle-elezioni-presidenziali-polacche-in-10-punti","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/it\/2025\/05\/26\/in-polonia-rafal-trzaskowski-contro-karol-nawrocki-ritratti-incrociati-dei-due-candidati-alle-elezioni-presidenziali-polacche-in-10-punti\/","title":{"rendered":"In Polonia, Rafa\u0142 Trzaskowski contro Karol Nawrocki: ritratti incrociati dei due candidati alle elezioni presidenziali polacche in 10 punti"},"content":{"rendered":"\n<div class=\"wp-block-lgc-keypoints key-block\"><div class=\"keys\"><h6 class=\"font-bold text-sm uppercase\">Punti chiave<\/h6>\n<ul class=\"wp-block-list\">\n<li>Il primo turno delle elezioni presidenziali polacche, tenutosi lo scorso 18 maggio, ha visto in testa Rafa\u0142 Trzaskowski, sindaco liberale di Varsavia e membro della Coalizione Civica del primo ministro Tusk, con il 31,4% dei voti.<\/li>\n\n\n\n<li>Domenica si confronter\u00e0 con Karol Nawrocki, candidato del partito nazional-conservatore PiS, che ha ottenuto il 29,5% dei voti al primo turno.\u00a0 Trzaskowski ha condotto tutta la campagna elettorale in testa, ma il risultato del primo turno ha mostrato quanto Nawrocki abbia ridotto il distacco.<\/li>\n\n\n\n<li>I sondaggi per il secondo turno davano ancora Trzaskowski vincitore fino a met\u00e0 maggio; nei tre sondaggi della scorsa settimana, uno consacra Trzaskowski, un altro d\u00e0 Nawrocki vincitore e l&#8217;ultimo mostra un pareggio.<\/li>\n<\/ul>\n<\/div><\/div>\n\n\n\n<p class=\"has-drop-cap\">Rafa\u0142 Trzaskowski, attuale sindaco di Varsavia e candidato della Coalizione Civica, formazione del primo ministro Donald Tusk, era dato per favorito nella corsa alle presidenziali polacche fino agli ultimi giorni della campagna elettorale, ma la sua vittoria al secondo turno \u00e8 tutt&#8217;altro che scontata. Sindaco di Varsavia, liberale filo-europeo, da domenica scorsa sta cercando di conquistare i conservatori di centro-destra senza rinunciare alle sue posizioni progressiste.<\/p>\n\n\n\n<p>Karol Nawrocki \u00e8 il candidato sostenuto dal partito nazional-conservatore Diritto e Giustizia (PiS), per le elezioni presidenziali polacche. Storico inizialmente sconosciuto al grande pubblico, ha progressivamente accresciuto la sua notoriet\u00e0 in una campagna non priva di scandali, in cui incarna posizioni conservatrici su questioni sociali e vicine agli ambienti MAGA.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/l1d2Z\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Mentre i polacchi si recano alle urne questa domenica, tracciamo un ritratto incrociato di queste figure che incarnano due futuri alternativi per il paese.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">1 \u2014 Origini sociali: un personaggio quasi sconosciuto proveniente dalla classe media contro un rappresentante dell&#8217;\u00e9lite polacca<\/h4>\n\n\n\n<h4 class=\"wp-block-heading\">Rafa\u0142 Trzaskowski<\/h4>\n\n\n\n<p>Rafa\u0142 Trzaskowski ha 53 anni. Figlio di un pianista jazz, ha studiato all&#8217;Universit\u00e0 di Varsavia, dove ha conseguito un dottorato in scienze umane sull&#8217;impatto dell&#8217;integrazione europea sui sistemi politici degli Stati membri dell&#8217;Unione.<\/p>\n\n\n\n<p>Oltre al suo mandato locale, Trzaskowski \u00e8 anche vicepresidente della Piattaforma Civica (PO), il partito guidato da Donald Tusk, e della Coalizione Civica (KO), di cui la Piattaforma \u00e8 la formazione principale insieme a diversi piccoli partiti piuttosto liberali.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Karol Nawrocki<\/h4>\n\n\n\n<p>Dall&#8217;altra parte, Karol Nawrocki, 42 anni, \u00e8 il candidato designato dal partito nazional-conservatore Diritto e Giustizia (PiS) per le elezioni presidenziali polacche.<\/p>\n\n\n\n<p>Proveniente da una famiglia della classe media della periferia di Danzica, non membro del partito nazional-conservatore, non ha alle spalle gli scandali e i reati di molti ministri del PiS, essendo stato finora praticamente sconosciuto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">2 \u2014 Formazione: due intellettuali anglofoni con visioni opposte<\/h2>\n\n\n\n<h4 class=\"wp-block-heading\">Rafa\u0142 Trzaskowski<\/h4>\n\n\n\n<p>Trzaskowski ha studiato a Parigi, a Oxford e al Collegio d\u2019Europa di Natolin, dove ha anche insegnato, cos\u00ec come all\u2019Universit\u00e0 di Varsavia.<\/p>\n\n\n\n<p>Nel 2005 ha pubblicato sulla rivista di Natolin \u00abUn esercizio di immaginazione\u00bb su un possibile trattato costituzionale europeo, insieme a J\u00fcrgen Habermas e Paul Magnette&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-33518' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/it\/2025\/05\/26\/in-polonia-rafal-trzaskowski-contro-karol-nawrocki-ritratti-incrociati-dei-due-candidati-alle-elezioni-presidenziali-polacche-in-10-punti\/#easy-footnote-bottom-1-33518' title='&lt;a href=&quot;http:\/\/incb.net\/incb\/wba\/wba0383-Nowa-Europa-Przeglad-natolinski-2005-nr-1-1-Warszawa-Centrum-Europejskie-Natolin-2005-Centrum-Europejskie-Natolin.html&quot;&gt;Nowa Europa. Przegl\u0105d natoli\u0144ski. 2005 nr 1(1). Warszawa: Centrum Europejskie Natolin 2005 &amp;#8211; wba0383&lt;\/a&gt;'><sup>1<\/sup><\/a><\/span><\/span>.Trzaskowski \u00e8 poliglotta: parla inglese, francese, spagnolo, italiano e russo. Ha lavorato come interprete di conferenze in inglese.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Karol Nawrocki<\/h4>\n\n\n\n<p>Nawrocki \u00e8 dottore in storia e titolare di un MBA. Anche lui anglofono, specialista del ruolo dell&#8217;URSS nella storia della Polonia post-1945, \u00e8 perseguito dalla Russia dal febbraio 2024 per il suo sostegno alla rimozione dei monumenti alla gloria dell&#8217;Armata Rossa sul territorio polacco.<\/p>\n\n\n\n<p>Il lavoro e la posizione di Nawrocki nel campo accademico polacco sono al servizio della narrativa nazionale.<\/p>\n\n\n\n<p>Il candidato ha diretto il controverso Museo della Seconda Guerra Mondiale di Danzica (2017-2021), prima di assumere la presidenza dell&#8217;Istituto della Memoria Nazionale, che \u00e8 sia un centro di ricerca sui crimini perpetrati contro la nazione polacca \u2013 principalmente nazisti e sovietici \u2013 sia un&#8217;istituzione che persegue i criminali identificati. Dal 2018, l&#8217;Istituto \u00e8 diventato la punta di diamante della politica di riscrittura della memoria avviata dal PiS, in particolare contro la nuova scuola polacca di storia della Shoah. Nawrocki lo dirige dal 2021, ovvero dopo il culmine della polemica, e si \u00e8 concentrato piuttosto sui crimini sovietici; resta comunque il fatto che le sue posizioni ideologiche sono favorevoli alle interpretazioni ideologiche del partito Diritto e Giustizia che lo ha sostenuto per le presidenziali.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Nel 2015, il candidato del PiS era l&#8217;attuale presidente Andrzej Duda: anch&#8217;egli sconosciuto all&#8217;inizio della campagna elettorale e in ritardo nei sondaggi, alla fine ha vinto.<\/p><cite>Olivier Lenoir<\/cite><\/blockquote><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">3 \u2014 Esperienza: un candidato esperto e un esordiente in politica<\/h2>\n\n\n\n<h4 class=\"wp-block-heading\">Rafa\u0142 Trzaskowski<\/h4>\n\n\n\n<p>Trzaskowski aveva gi\u00e0 prestato servizio come volontario nel 1989 durante le prime elezioni semi-libere dopo il comunismo. Dopo aver conseguito il dottorato nel 2004, ha rapidamente abbandonato il mondo accademico per intraprendere la carriera politica. Il suo primo mandato \u00e8 stato a Bruxelles nel 2009, dove \u00e8 stato eletto eurodeputato nelle liste della Piattaforma Civica, e quindi membro del Partito Popolare Europeo (PPE). \u00c8 poi tornato alla politica polacca come ministro della Funzione Pubblica e della Digitalizzazione dal 2013 al 2014, poi deputato polacco fino al 2018. \u00c8 stato allora che ha acquisito la sua vera notoriet\u00e0 nazionale e internazionale vincendo le elezioni comunali di Varsavia. \u00c8 quindi sindaco della capitale polacca dal 2018, carica alla quale \u00e8 stato rieletto nel 2024, al primo turno.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/YMf7r\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>In quanto sindaco di Varsavia, capitale che da due decenni vota per la Piattaforma Civica e la Coalizione Civica, Trzaskowski \u00e8 storicamente una figura di spicco dell&#8217;ala progressista di questi gruppi di centro-destra.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Karol Nawrocki<\/h4>\n\n\n\n<p>La carriera del candidato a sorpresa del PiS al servizio della narrativa nazionale pu\u00f2 interessare gran parte della popolazione polacca, sensibile alla sua storia tragica e al suo onore nazionale. All&#8217;inizio della campagna, Nawrocki ha risentito del suo profilo di novizio: mancava di esperienza politica, evitava le domande dei giornalisti, parlava poco. Alla fine del 2024, era fermo al 20-22% dei voti, contro il 40% del suo rivale liberale Trzaskowski.<\/p>\n\n\n\n<p>Da allora Nawrocki ha viaggiato in tutto il territorio polacco, aumentando la sua notoriet\u00e0, mentre il PiS attivava la sua temibile macchina elettorale. Ha raggiunto il 30% dei voti al primo turno, riducendo notevolmente il distacco da Trzaskowski (31%).<\/p>\n\n\n\n<p>I polacchi vivono con il ricordo della campagna presidenziale del 2015, quando il candidato del PiS era l&#8217;attuale presidente Andrzej Duda: anch&#8217;egli sconosciuto all&#8217;inizio della campagna, in ritardo nei sondaggi, alla fine ha vinto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">4 \u2014 Casting presidenziale: un potenziale successore di Tusk contro un nuovo \u00abcandidato tattico\u00bb per il PiS<\/h2>\n\n\n\n<h4 class=\"wp-block-heading\">Rafa\u0142 Trzaskowski<\/h4>\n\n\n\n<p>La battaglia presidenziale non \u00e8 nuova per Trzaskowski: era gi\u00e0 stato candidato del KO nel 2020, contro Andrzej Duda, e aveva perso al secondo turno con il 49% contro il 51%.<\/p>\n\n\n\n<p>Era stato inviato all&#8217;ultimo minuto nelle ultime settimane della campagna, mentre la candidata della KO era scesa sotto il 10% delle intenzioni di voto. Alla fine era riuscito a risalire la china, ma aveva perso al secondo turno contro l&#8217;attuale presidente Andrzej Duda, con il 49% dei voti. Trzaskowski \u00e8 quindi rimasto una figura di spicco della KO \u2013 che \u00e8 ancora oggi \u2013 in attesa del vero ritorno sulla scena politica nazionale di Donald Tusk.<\/p>\n\n\n\n<p>Ha quindi affrontato la campagna del 2025 con l&#8217;esperienza della precedente, ma anche con le preoccupazioni dell&#8217;ultimo miglio, in cui ogni voto conta.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Karol Nawrocki<\/h4>\n\n\n\n<p>Al di fuori dei mandati locali, il suo avversario non ha una particolare esperienza politica. Tuttavia, \u00e8 apparso come un candidato tattico per il PiS, rivolgendosi al suo elettorato piuttosto rurale e anziano, facendo leva sul loro sentimento nazionale grazie al suo ruolo presso l&#8217;Istituto della Memoria Nazionale e, soprattutto, non essendo coinvolto negli scandali che hanno coinvolto molti ex ministri o eletti del PiS, perseguiti dopo il cambio di governo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><br>5 \u2014 Visioni opposte sulle questioni sociali \u2014 dall&#8217;aborto ai diritti LGBT+, passando per il ruolo della religione<\/h2>\n\n\n\n<h4 class=\"wp-block-heading\">Rafa\u0142 Trzaskowski<\/h4>\n\n\n\n<p>Oltre ai progetti di rinverdimento urbano e di miglioramento della qualit\u00e0 della vita dei cittadini di Varsavia, il sindaco della capitale si \u00e8 affermato soprattutto su tre temi particolarmente controversi nella societ\u00e0 polacca<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00c8 un sostenitore dei diritti delle persone LGBT+ e nel 2019 ha proclamato una \u00abdichiarazione LGBT+ di Varsavia\u00bb. Partecipa ogni anno al gay pride e sostiene le unioni civili tra persone dello stesso sesso.<\/li>\n\n\n\n<li>Nel Paese pi\u00f9 cattolico d&#8217;Europa, ha fatto rimuovere i crocifissi dagli edifici comunali.<\/li>\n\n\n\n<li>\u00c8 un grande difensore dei diritti delle donne. Tra i vari progetti di legge approvati dal Sejm ma bloccati dal veto presidenziale di Andrzej Duda, ha dichiarato che, se fosse stato eletto presidente, avrebbe sostenuto i progetti sulla pillola del giorno dopo o sulla fecondazione in vitro, cos\u00ec come qualsiasi progetto sulla liberalizzazione dell&#8217;aborto.<\/li>\n<\/ul>\n\n\n\n<p>La destra nazional-conservatrice non esita a utilizzare questa posizione contro Trzaskowski e tende a ridurre le sue convinzioni a questi soli elementi.<\/p>\n\n\n\n<p>Durante un dibattito prima del primo turno, il suo avversario ha esposto una bandiera LGBT+ davanti a Trzaskowski, mentre lui stesso sventolava una bandiera polacca.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Karol Nawrocki<\/h4>\n\n\n\n<p>La nascita della figura politica di Nawrocki alla vigilia della campagna presidenziale gli ha soprattutto permesso di esprimere le sue convinzioni.<\/p>\n\n\n\n<p>Contrariamente al suo rivale progressista, il candidato del PiS mostra una posizione conservatrice su questioni sociali.<\/p>\n\n\n\n<p>Nawrocki \u00e8 decisamente contrario alla liberalizzazione dell&#8217;aborto, parlando di \u00abpromessa eugenetica\u00bb e aggiungendo di essere \u00abcristiano e cattolico\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-33518' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/it\/2025\/05\/26\/in-polonia-rafal-trzaskowski-contro-karol-nawrocki-ritratti-incrociati-dei-due-candidati-alle-elezioni-presidenziali-polacche-in-10-punti\/#easy-footnote-bottom-2-33518' title='&lt;a href=&quot;https:\/\/www.polsatnews.pl\/wiadomosc\/2025-01-08\/karol-nawrocki-w-gosciu-wydarzen\/&quot;&gt;Karol Nawrocki z\u0142o\u017cy\u0142 deklaracj\u0119 ws. Ukrainy w NATO. Wspomnia\u0142 o &amp;#8220;rozliczeniach&amp;#8221;&lt;\/a&gt;, PolsatNews.pl.'><sup>2<\/sup><\/a><\/span><\/span>. Si oppone anche alle unioni civili tra persone dello stesso sesso e al rimborso senza prescrizione medica della pillola del giorno dopo. Il PiS sta accumulando immagini di propaganda elettorale in cui Trzaskowski \u00e8 associato alle bandiere LGBT+, mentre Nawrocki si affida alla bandiera bianco-rossa<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">6 \u2014 L&#8217;Ucraina: pomo della discordia geopolitica tra Nawrocki e Trzaskowski<\/h2>\n\n\n\n<h4 class=\"wp-block-heading\">Rafa\u0142 Trzaskowski<\/h4>\n\n\n\n<p>Il candidato della KO \u00e8 particolarmente filo-ucraino: come ha ribadito nel weekend tra i due turni, \u00e8 favorevole all&#8217;ingresso dell&#8217;Ucraina nella NATO e nell&#8217;Unione. Ha inoltre incontrato Volodymyr Zelensky in diverse occasioni.<\/p>\n\n\n\n<p>Trzaskowski \u00e8 tuttavia contrario all&#8217;invio di truppe polacche in Ucraina \u2014 una posizione sostenuta dal primo ministro Tusk, che si concentra sulla difesa del confine polacco con la Russia a Kaliningrad e la Bielorussia \u2014 e ha segnato alcune inflessioni sulla posizione nei confronti degli ucraini in Polonia.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Karol Nawrocki<\/h4>\n\n\n\n<p>Il suo avversario ha adottato una posizione ambivalente sulla guerra russo-ucraina.<\/p>\n\n\n\n<p>Storico dell&#8217;antisovietismo polacco, ha definito la Russia \u00abuno Stato barbaro\u00bb, ma allo stesso tempo non ha esitato a rompere il relativo accordo bipartisan in Polonia sul sostegno all&#8217;Ucraina.<\/p>\n\n\n\n<p>Nawrocki ha infatti affermato che l&#8217;ingresso dell&#8217;Ucraina nell&#8217;Unione Europea e nella NATO a breve termine \u00e8 impossibile a suo avviso, a causa delle numerose controversie storiche con la Polonia, in particolare la questione dei massacri della Volinia&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-33518' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/it\/2025\/05\/26\/in-polonia-rafal-trzaskowski-contro-karol-nawrocki-ritratti-incrociati-dei-due-candidati-alle-elezioni-presidenziali-polacche-in-10-punti\/#easy-footnote-bottom-3-33518' title='Si tratta dell&amp;#8217;assassinio di circa 100.000 polacchi da parte dell&amp;#8217;Esercito Insurrezionale Ucraino (UPA) tra il 1942 e il 1944, che la Polonia definisce genocidio. Dalla guerra del 2022,il riconoscimento di questi massacri da parte dell&amp;#8217;Ucraina ha fatto progressi; a met\u00e0 gennaio 2025, Zelensky ha annunciato ufficialmente che avrebbe iniziato l&amp;#8217;esumazione delle vittime a partire dalla primavera, rispondendo a un&amp;#8217;attesa delle famiglie polacche che dura ormai da 80 anni.'><sup>3<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>Tuttavia, sembra aver sollevato un punto delicato: il sostegno all&#8217;Ucraina \u00e8 oggetto di un consenso bipartisan PiS-KO di lunga data e, dopo il suo intervento, si \u00e8 creato un certo malessere all&#8217;interno del PiS. Anche alcune figure di spicco del partito hanno espresso le loro riserve.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Nel 2020, gli elettori della Confederazione si erano divisi quasi equamente tra PiS e KO al secondo turno.<\/p><cite>Olivier Lenoir<\/cite><\/blockquote><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">7 \u2014 Sull&#8217;Europa, l&#8217;agenda liberale da un lato \u2014 un europeismo MAGA dall&#8217;altro<\/h2>\n\n\n\n<h4 class=\"wp-block-heading\">Rafa\u0142 Trzaskowski<\/h4>\n\n\n\n<p>La posizione del candidato della Coalizione Civica si inserisce in un pi\u00f9 ampio sostegno allo Stato di diritto, al progresso dei diritti sociali e alla posizione filoeuropea della Polonia.<\/p>\n\n\n\n<p>Ex eurodeputato e laureato a Natolin, a marzo ha dichiarato che \u00abl&#8217;Unione europea \u00e8 la nostra sicurezza\u00bb.<\/p>\n\n\n\n<p>In quanto sindaco della capitale, ha incontrato la maggior parte dei leader europei in visita a Varsavia, tra cui il presidente Emmanuel Macron lo scorso dicembre.\u00a0<\/p>\n\n\n\n<p>\u00c8 contrario al Patto sulla migrazione e l&#8217;asilo, in accordo con il governo Tusk che ha irrigidito la sua posizione sulla questione, mettendo in discussione in particolare il diritto di asilo dei migranti inviati dalla Bielorussia e dalla Russia al confine orientale della Polonia.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Karol Nawrocki<\/h4>\n\n\n\n<p>Nawrocki non \u00e8 euroscettico. Sembra piuttosto vicino alle dichiarazioni dell&#8217;ex primo ministro Mateusz Morawiecki durante il suo discorso a Heidelberg su un&#8217; Europa delle nazioni.<\/p>\n\n\n\n<p>Tuttavia, condanna il Patto verde europeo, la centralizzazione dei poteri a Bruxelles, il peso della coppia franco-tedesca \u2013 e in particolare del nemico storico tedesco, al quale chiede riparazioni di guerra \u2013 e si schiera al fianco dei conservatori e dei riformisti europei.<\/p>\n\n\n\n<p>\u00c8 stato investito alla fine di marzo dalla formazione europea presieduta da Morawiecki e, da allora, ha incontrato pi\u00f9 volte Giorgia Meloni. Ha anche invitato il rumeno George Simion a uno dei suoi ultimi comizi. Al di fuori dell&#8217;Europa, l&#8217;attuale presidente Duda intrattiene rapporti personali con il presidente Donald Trump, che ha incontrato pi\u00f9 volte, l&#8217;ultima delle quali alla CPAC lo scorso aprile. Nawrocki non poteva vantare tali legami, fino a quando non ha deciso di recarsi a Washington lo scorso maggio e incontrare anche lui Trump. Lui stesso, che milita sotto lo slogan \u00abLa Polonia prima di tutto\u00bb, ha dichiarato di riconoscersi nei valori MAGA. Durante la sua visita a Washington, ha affermato che il presidente americano gli avrebbe detto: \u00abVincerete\u00bb.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">8 \u2014 Due strategie di campagna: la \u00abforza tranquilla\u00bb di Trzaskowski e l&#8217;emergere di una figura controversa con Nawrocki<\/h2>\n\n\n\n<h4 class=\"wp-block-heading\">Rafa\u0142 Trzaskowski<\/h4>\n\n\n\n<p>In questo secondo turno, Trzaskowski dovrebbe ottenere la maggior parte dei voti trasferiti dalla sinistra e dal centro.<\/p>\n\n\n\n<p>Senza rinnegare le sue convinzioni progressiste, ha quindi scelto di orientare la sua campagna piuttosto verso destra, sperando di catturare una parte dell&#8217;elettorato conservatore. La candidatura di Trzaskowski alle presidenziali \u00e8 del resto il risultato delle primarie della Coalizione Civica, dove Trzaskowski ha trionfato sull&#8217;attuale ministro degli Esteri Rados\u0142aw Sikorski, considerato pi\u00f9 conservatore.<\/p>\n\n\n\n<p>Nel corso della campagna elettorale, ad esempio, ha:\u00a0<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>dichiarato di non sostenere l&#8217;adozione da parte delle coppie dello stesso sesso.<\/li>\n\n\n\n<li>condannato il Patto europeo sulla migrazione e proposto di subordinare gli assegni familiari agli ucraini residenti in Polonia, riservandoli a coloro che lavorano, vivono e pagano le tasse nel Paese.<\/li>\n\n\n\n<li>ha incentrato la sua campagna sulla sicurezza \u2013 interna ed esterna \u2013 tema principale delle elezioni, talvolta criticando il ritardo degli Stati membri dell&#8217;Unione in materia di investimenti nella difesa.<\/li>\n<\/ul>\n\n\n\n<p>Trzaskowski si presenta ormai a quasi tutti i comizi elettorali con la moglie Ma\u0142gorzata, accentuando l&#8217;immagine di forza tranquilla con una statura nazionale e internazionale riconosciuta. Anche il suo bulldog, di nome Babel, \u00e8 molto presente. I suoi slogan elettorali, \u00abTutta la Polonia avanti\u00bb e \u00abTutta la Polonia vincer\u00e0\u00bb, testimoniano la volont\u00e0 di un unione nazionale al di l\u00e0 delle divisioni, che \u00e8 il ruolo tradizionale del presidente polacco.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Karol Nawrocki<\/h4>\n\n\n\n<p>La scelta di un novizio in politica ha progressivamente fatto emergere diverse polemiche intorno al candidato.<\/p>\n\n\n\n<p>Da un lato, Nawrocki \u00e8 appassionato di boxe e alcuni documenti hanno rivelato la sua vicinanza a una banda di pugili e buttafuori di discoteche neonazisti o hooligan. Avrebbe partecipato a risse nella foresta che hanno visto scontrarsi 70 persone contro 70.<\/p>\n\n\n\n<p>D&#8217;altra parte, avrebbe acquistato un appartamento in modo relativamente fraudolento da una persona anziana bisognosa a Danzica. La polemica \u00e8 scoppiata alla fine della campagna elettorale e Nawrocki ha finito per dichiarare che avrebbe donato l&#8217;appartamento a una fondazione, senza per\u00f2 rispondere alle domande n\u00e9 placare lo scandalo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">9 \u2014 Vincere sulla destra: dopo il primo turno, uno spostamento del baricentro all&#8217;ombra di Mentzen, il candidato della Confederazione<\/h2>\n\n\n\n<p>Trzaskowski e Nawrocki hanno cercato per tutta la settimana di conquistare l&#8217;elettorato di Mentzen, il leader libertario-nazionalista che ha ottenuto il 15% al primo turno.<\/p>\n\n\n\n<p>Nel 2020, gli elettori della Confederazione si erano divisi quasi equamente tra il PiS e la KO al secondo turno.<\/p>\n\n\n\n<p>Quest&#8217;anno, i due candidati hanno partecipato separatamente a un evento sul canale Youtube di Mentzen, che ha sottoposto loro una dichiarazione in otto punti da firmare.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Rafa\u0142 Trzaskowski<\/h4>\n\n\n\n<p>L&#8217;incontro tra Mentzen e Trzaskowski era molto atteso.<\/p>\n\n\n\n<p>Il candidato della KO \u00e8 apparso calmo e aperto al dialogo, senza cedere a tutte le proposte di Mentzen: non ha firmato la dichiarazione in otto punti e si \u00e8 detto d&#8217;accordo solo con quattro di essi, ad esempio l&#8217;assenza di nuove tasse o di ostacoli all&#8217;uso del contante, rifiutando per\u00f2 di bloccare l&#8217;ingresso dell&#8217;Ucraina nella NATO. Hanno poi bevuto una birra in un bar di propriet\u00e0 di Mentzen, dove li attendeva il ministro degli Esteri Sikorski.<\/p>\n\n\n\n<p>Questa birra ha avuto grande risonanza mediatica, con molti elettori e leader della Confederazione che hanno affermato che dava l&#8217;impressione che la Coalizione Civica avesse assorbito la Confederazione. Mentzen ha dovuto giustificarsi in un lungo tweet domenica.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"pl\" dir=\"ltr\">Z Nawrockim te\u017c bym poszed\u0142 na piwo, ale nie zaprosi\u0142.<br><br>Nie rozumiem o co niekt\u00f3rym chodzi. Nie nale\u017c\u0119 do mafii, nie nale\u017c\u0119 do sekty. Id\u0119 prosto.<br><br>Nie dam si\u0119 zapisa\u0107 do \u017cadnego z waszych oboz\u00f3w.<br><br>A politycy powinni umie\u0107 normalnie ze sob\u0105 rozmawia\u0107.<\/p>&mdash; S\u0142awomir Mentzen (@SlawomirMentzen) <a href=\"https:\/\/twitter.com\/SlawomirMentzen\/status\/1926377833569398822?ref_src=twsrc%5Etfw\">May 24, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>Sebbene Trzaskowski sembri essere uscito rafforzato da questa vicenda, non \u00e8 detto che gli elettori lo seguano.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Karol Nawrocki<\/h4>\n\n\n\n<p>Nawrocki ha accettato senza riserve gli otto punti di Mentzen e ha firmato la dichiarazione, affermando anche che, se fosse stato presidente, avrebbe posto il veto all&#8217;ingresso dell&#8217;Ucraina nella NATO.<\/p>\n\n\n\n<p>La sua posizione \u00e8 chiara e costituisce un chiaro invito agli elettori della Confederazione.<\/p>\n\n\n\n<p>Tuttavia, \u00e8 anche apparso asservito a Mentzen, rifiutandosi di affermare la propria identit\u00e0 politica mentre le due formazioni si contendono la leadership della destra nazionalista polacca.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">10 \u2014 Una mobilitazione significativa negli ultimi giorni e un secondo turno che si preannuncia serrato<\/h2>\n\n\n\n<p>Entrambi i candidati hanno organizzato imponenti marce a Varsavia domenica scorsa, a pochi isolati di distanza l&#8217;uno dall&#8217;altro: la \u00abgrande marcia dei patrioti\u00bb per Trzaskowski, alla quale hanno partecipato, tra gli altri, Tusk, il presidente rumeno eletto Nicu\u0219or Dan e i perdenti del primo turno che si sono schierati con Trzaskowski, e \u00abla marcia per la Polonia\u00bb per Nawrocki.<\/p>\n\n\n\n<p>Secondo i servizi della citt\u00e0 di Varsavia, 140.000 persone avrebbero partecipato alla marcia della Coalizione Civica e 50.000 a quella del PiS, ma non \u00e8 nella capitale che si recluta l&#8217;elettorato nazional-conservatore.<\/p>\n\n\n\n<p>Il primo turno ha consacrato il duopolio PiS-KO, che governa la Polonia dal 2005.<\/p>\n\n\n\n<p>Tuttavia, con solo il 61% dei voti, non rappresenta pi\u00f9 di un terzo degli elettori.<\/p>\n\n\n\n<p>Se Trzaskowski dovrebbe attirare la maggior parte degli elettori di sinistra (circa il 10% dell&#8217;elettorato), le principali riserve di voti si trovano all&#8217;estrema destra, tra coloro che hanno votato per Mentzen (15%) o per l&#8217;antisemita monarchico Grzegorz Braun (6%).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tutto oppone, sul fondo, il liberale Rafa\u0142 Trzaskowski e il candidato del PiS Karol Nawrocki, che si affrontano domenica al secondo turno delle elezioni presidenziali.<\/p>\n<p>Eppure, negli ultimi giorni entrambi hanno partecipato alla stessa trasmissione: un&#8217;intervista sul canale Youtube del leader della Confederazione, Slawomir Mentzen, un libertario di estrema destra, terzo candidato alle presidenziali, che potrebbe detenere la chiave del voto.<\/p>\n<p>Ritratto incrociato in 10 punti a pochi giorni da un&#8217;elezione il cui esito sembra per ora impossibile da prevedere.<\/p>\n","protected":false},"author":47071,"featured_media":33439,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-studies.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":16,"_lgc_tts_audio_url":"","_lgc_tts_voice":"","_lgc_tts_publish":false,"_lgc_tts_history_item_id":"","_lgc_tts_generated_at":"","_lgc_tts_status":"","_lgc_tts_error":"","footnotes":""},"categories":[2314],"tags":[],"staff":[1611],"editorial_format":[2349],"serie":[],"audience":[],"geo":[],"class_list":["post-33518","post","type-post","status-publish","format-standard","hentry","category-il-momento-polacco","staff-olivier-lenoir","editorial_format-studi"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":33439,"excerpt":"Tutto oppone, sul fondo, il liberale Rafa\u0142 Trzaskowski e il candidato del PiS Karol Nawrocki, che si affrontano domenica al secondo turno delle elezioni presidenziali.\r\n \r\nEppure, negli ultimi giorni entrambi hanno partecipato alla stessa trasmissione: un'intervista sul canale Youtube del leader della Confederazione, Slawomir Mentzen, un libertario di estrema destra, terzo candidato alle presidenziali, che potrebbe detenere la chiave del voto.\r\n \r\nRitratto incrociato in 10 punti a pochi giorni da un'elezione il cui esito sembra per ora impossibile da prevedere.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>In Polonia, Rafa\u0142 Trzaskowski contro Karol Nawrocki: ritratti incrociati dei due candidati alle elezioni presidenziali polacche in 10 punti - Il Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/it\/2025\/05\/26\/in-polonia-rafal-trzaskowski-contro-karol-nawrocki-ritratti-incrociati-dei-due-candidati-alle-elezioni-presidenziali-polacche-in-10-punti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"In Polonia, Rafa\u0142 Trzaskowski contro Karol Nawrocki: ritratti incrociati dei due candidati alle elezioni presidenziali polacche in 10 punti - Il Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Tutto oppone, sul fondo, il liberale Rafa\u0142 Trzaskowski e il candidato del PiS Karol Nawrocki, che si affrontano domenica al secondo turno delle elezioni presidenziali.   Eppure, negli ultimi giorni entrambi hanno partecipato alla stessa trasmissione: un&#039;intervista sul canale Youtube del leader della Confederazione, Slawomir Mentzen, un libertario di estrema destra, terzo candidato alle presidenziali, che potrebbe detenere la chiave del voto.   Ritratto incrociato in 10 punti a pochi giorni da un&#039;elezione il cui esito sembra per ora impossibile da prevedere.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/it\/2025\/05\/26\/in-polonia-rafal-trzaskowski-contro-karol-nawrocki-ritratti-incrociati-dei-due-candidati-alle-elezioni-presidenziali-polacche-in-10-punti\/\" \/>\n<meta property=\"og:site_name\" content=\"Il Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-26T14:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-30T18:03:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/2\/2025\/05\/opl-990x571.png\" \/>\n\t<meta property=\"og:image:width\" content=\"990\" \/>\n\t<meta property=\"og:image:height\" content=\"571\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"jechareton\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/2\/2025\/05\/opl.png\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"jechareton\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2025\/05\/26\/in-polonia-rafal-trzaskowski-contro-karol-nawrocki-ritratti-incrociati-dei-due-candidati-alle-elezioni-presidenziali-polacche-in-10-punti\/\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/2025\/05\/26\/in-polonia-rafal-trzaskowski-contro-karol-nawrocki-ritratti-incrociati-dei-due-candidati-alle-elezioni-presidenziali-polacche-in-10-punti\/\",\"name\":\"In Polonia, Rafa\u0142 Trzaskowski contro Karol Nawrocki: ritratti incrociati dei due candidati alle elezioni presidenziali polacche in 10 punti - Il Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2025\/05\/26\/in-polonia-rafal-trzaskowski-contro-karol-nawrocki-ritratti-incrociati-dei-due-candidati-alle-elezioni-presidenziali-polacche-in-10-punti\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2025\/05\/26\/in-polonia-rafal-trzaskowski-contro-karol-nawrocki-ritratti-incrociati-dei-due-candidati-alle-elezioni-presidenziali-polacche-in-10-punti\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/2\/2025\/05\/opl.png\",\"datePublished\":\"2025-05-26T14:00:00+00:00\",\"dateModified\":\"2025-05-30T18:03:19+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/40ae0927228bed19c9f00c8d9eda4efb\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2025\/05\/26\/in-polonia-rafal-trzaskowski-contro-karol-nawrocki-ritratti-incrociati-dei-due-candidati-alle-elezioni-presidenziali-polacche-in-10-punti\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/it\/2025\/05\/26\/in-polonia-rafal-trzaskowski-contro-karol-nawrocki-ritratti-incrociati-dei-due-candidati-alle-elezioni-presidenziali-polacche-in-10-punti\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2025\/05\/26\/in-polonia-rafal-trzaskowski-contro-karol-nawrocki-ritratti-incrociati-dei-due-candidati-alle-elezioni-presidenziali-polacche-in-10-punti\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/2\/2025\/05\/opl.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/2\/2025\/05\/opl.png\",\"width\":3574,\"height\":2062},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2025\/05\/26\/in-polonia-rafal-trzaskowski-contro-karol-nawrocki-ritratti-incrociati-dei-due-candidati-alle-elezioni-presidenziali-polacche-in-10-punti\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"In Polonia, Rafa\u0142 Trzaskowski contro Karol Nawrocki: ritratti incrociati dei due candidati alle elezioni presidenziali polacche in 10 punti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/\",\"name\":\"Il Grand Continent\",\"description\":\"La scala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/40ae0927228bed19c9f00c8d9eda4efb\",\"name\":\"jechareton\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d6eba43b977e6d35baefa5ebd8664d07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d6eba43b977e6d35baefa5ebd8664d07?s=96&d=mm&r=g\",\"caption\":\"jechareton\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"In Polonia, Rafa\u0142 Trzaskowski contro Karol Nawrocki: ritratti incrociati dei due candidati alle elezioni presidenziali polacche in 10 punti - Il Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/it\/2025\/05\/26\/in-polonia-rafal-trzaskowski-contro-karol-nawrocki-ritratti-incrociati-dei-due-candidati-alle-elezioni-presidenziali-polacche-in-10-punti\/","og_locale":"it_IT","og_type":"article","og_title":"In Polonia, Rafa\u0142 Trzaskowski contro Karol Nawrocki: ritratti incrociati dei due candidati alle elezioni presidenziali polacche in 10 punti - Il Grand Continent","og_description":"Tutto oppone, sul fondo, il liberale Rafa\u0142 Trzaskowski e il candidato del PiS Karol Nawrocki, che si affrontano domenica al secondo turno delle elezioni presidenziali.   Eppure, negli ultimi giorni entrambi hanno partecipato alla stessa trasmissione: un'intervista sul canale Youtube del leader della Confederazione, Slawomir Mentzen, un libertario di estrema destra, terzo candidato alle presidenziali, che potrebbe detenere la chiave del voto.   Ritratto incrociato in 10 punti a pochi giorni da un'elezione il cui esito sembra per ora impossibile da prevedere.","og_url":"https:\/\/legrandcontinent.eu\/it\/2025\/05\/26\/in-polonia-rafal-trzaskowski-contro-karol-nawrocki-ritratti-incrociati-dei-due-candidati-alle-elezioni-presidenziali-polacche-in-10-punti\/","og_site_name":"Il Grand Continent","article_published_time":"2025-05-26T14:00:00+00:00","article_modified_time":"2025-05-30T18:03:19+00:00","og_image":[{"width":990,"height":571,"url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/2\/2025\/05\/opl-990x571.png","type":"image\/png"}],"author":"jechareton","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/2\/2025\/05\/opl.png","twitter_misc":{"Scritto da":"jechareton","Tempo di lettura stimato":"16 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/it\/2025\/05\/26\/in-polonia-rafal-trzaskowski-contro-karol-nawrocki-ritratti-incrociati-dei-due-candidati-alle-elezioni-presidenziali-polacche-in-10-punti\/","url":"https:\/\/legrandcontinent.eu\/it\/2025\/05\/26\/in-polonia-rafal-trzaskowski-contro-karol-nawrocki-ritratti-incrociati-dei-due-candidati-alle-elezioni-presidenziali-polacche-in-10-punti\/","name":"In Polonia, Rafa\u0142 Trzaskowski contro Karol Nawrocki: ritratti incrociati dei due candidati alle elezioni presidenziali polacche in 10 punti - Il Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/it\/2025\/05\/26\/in-polonia-rafal-trzaskowski-contro-karol-nawrocki-ritratti-incrociati-dei-due-candidati-alle-elezioni-presidenziali-polacche-in-10-punti\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/it\/2025\/05\/26\/in-polonia-rafal-trzaskowski-contro-karol-nawrocki-ritratti-incrociati-dei-due-candidati-alle-elezioni-presidenziali-polacche-in-10-punti\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/2\/2025\/05\/opl.png","datePublished":"2025-05-26T14:00:00+00:00","dateModified":"2025-05-30T18:03:19+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/40ae0927228bed19c9f00c8d9eda4efb"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/it\/2025\/05\/26\/in-polonia-rafal-trzaskowski-contro-karol-nawrocki-ritratti-incrociati-dei-due-candidati-alle-elezioni-presidenziali-polacche-in-10-punti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/it\/2025\/05\/26\/in-polonia-rafal-trzaskowski-contro-karol-nawrocki-ritratti-incrociati-dei-due-candidati-alle-elezioni-presidenziali-polacche-in-10-punti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/legrandcontinent.eu\/it\/2025\/05\/26\/in-polonia-rafal-trzaskowski-contro-karol-nawrocki-ritratti-incrociati-dei-due-candidati-alle-elezioni-presidenziali-polacche-in-10-punti\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/2\/2025\/05\/opl.png","contentUrl":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/2\/2025\/05\/opl.png","width":3574,"height":2062},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/it\/2025\/05\/26\/in-polonia-rafal-trzaskowski-contro-karol-nawrocki-ritratti-incrociati-dei-due-candidati-alle-elezioni-presidenziali-polacche-in-10-punti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/it\/"},{"@type":"ListItem","position":2,"name":"In Polonia, Rafa\u0142 Trzaskowski contro Karol Nawrocki: ritratti incrociati dei due candidati alle elezioni presidenziali polacche in 10 punti"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/it\/#website","url":"https:\/\/legrandcontinent.eu\/it\/","name":"Il Grand Continent","description":"La scala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/40ae0927228bed19c9f00c8d9eda4efb","name":"jechareton","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d6eba43b977e6d35baefa5ebd8664d07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d6eba43b977e6d35baefa5ebd8664d07?s=96&d=mm&r=g","caption":"jechareton"}}]}},"lgc_categories":[{"id":2314,"name":"Il momento Polacco","slug":"il-momento-polacco"}],"lgc_author":{"id":1611,"name":"Olivier Lenoir","slug":"olivier-lenoir","description":null,"first_name":"Olivier","last_name":"Lenoir","picture":{"url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2023\/09\/Lenoir.png","width":230,"height":263,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/2\/2025\/05\/opl.png","width":3574,"height":2062,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/2\/2025\/05\/opl.png","width":3574,"height":2062,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts\/33518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/users\/47071"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/comments?post=33518"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts\/33518\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/media\/33439"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/media?parent=33518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/categories?post=33518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/tags?post=33518"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/staff?post=33518"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/editorial_format?post=33518"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/serie?post=33518"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/audience?post=33518"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/geo?post=33518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}