{"id":32633,"date":"2025-05-02T21:26:17","date_gmt":"2025-05-02T19:26:17","guid":{"rendered":"https:\/\/legrandcontinent.eu\/it\/?p=32633"},"modified":"2025-05-02T21:36:01","modified_gmt":"2025-05-02T19:36:01","slug":"a-quale-cardinale-siete-piu-vicini-un-questionario-esclusivo-per-scegliere-il-vostro-papa-a-pochi-giorni-dal-conclave","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/it\/2025\/05\/02\/a-quale-cardinale-siete-piu-vicini-un-questionario-esclusivo-per-scegliere-il-vostro-papa-a-pochi-giorni-dal-conclave\/","title":{"rendered":"A quale cardinale siete pi\u00f9 vicini? Un questionario esclusivo per scegliere il vostro papa a pochi giorni dal conclave"},"content":{"rendered":"\n<p>In preparazione al conclave che avr\u00e0 inizio il 7 maggio, il Grand Continent si mobilita.<\/p>\n\n\n\n<p>Dopo il lancio dell&#8217;<a href=\"https:\/\/legrandcontinent.eu\/fr\/observatoire-conclave\/\">Osservatorio del Conclave<\/a> \u2014 la pi\u00f9 grande raccolta di dati aperti sui <a href=\"https:\/\/legrandcontinent.eu\/fr\/cardinaux\/\">135 cardinali elettori<\/a>, la storia, la geografia e la geopolitica di questa singolare istituzione in lingua francese \u2014, pubblichiamo uno strumento inedito.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium \">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/legrandcontinent.eu\/iframes\/papomat\/?locale=it\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Il \u00abpapometro\u00bb \u2014 dal latino \u00ab<em>habeo papam\u00bb<\/em> \u2014 \u00e8 il primo questionario che consente di definire in meno di 3 minuti quale tra i <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/04\/25\/conclave-19-papabiles\/\">papabili<\/a> e i grandi elettori corrisponde maggiormente alle vostre posizioni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ecologia, aborto, radici cristiane dell&#8217;Europa, accordi segreti con la Cina, ruolo delle donne nella Chiesa: quali sono i papabili pi\u00f9 vicini alle vostre posizioni?<\/p>\n","protected":false},"author":7,"featured_media":32634,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-angles.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":1,"footnotes":""},"categories":[2108],"tags":[],"staff":[],"editorial_format":[2348],"serie":[],"audience":[],"geo":[2083],"class_list":["post-32633","post","type-post","status-publish","format-standard","hentry","category-religione","editorial_format-prospettive","geo-mediterraneo"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":32634,"excerpt":"Ecologia, aborto, radici cristiane dell'Europa, accordi segreti con la Cina, ruolo delle donne nella Chiesa: quali sono i papabili pi\u00f9 vicini alle vostre posizioni?","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A quale cardinale siete pi\u00f9 vicini? Un questionario esclusivo per scegliere il vostro papa a pochi giorni dal conclave - Il Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/it\/2025\/05\/02\/a-quale-cardinale-siete-piu-vicini-un-questionario-esclusivo-per-scegliere-il-vostro-papa-a-pochi-giorni-dal-conclave\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A quale cardinale siete pi\u00f9 vicini? Un questionario esclusivo per scegliere il vostro papa a pochi giorni dal conclave - Il Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Ecologia, aborto, radici cristiane dell&#039;Europa, accordi segreti con la Cina, ruolo delle donne nella Chiesa: quali sono i papabili pi\u00f9 vicini alle vostre posizioni?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/it\/2025\/05\/02\/a-quale-cardinale-siete-piu-vicini-un-questionario-esclusivo-per-scegliere-il-vostro-papa-a-pochi-giorni-dal-conclave\/\" \/>\n<meta property=\"og:site_name\" content=\"Il Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-02T19:26:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-02T19:36:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2025\/05\/Grand-Continent-Papometre-bis.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1304\" \/>\n\t<meta property=\"og:image:height\" content=\"738\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gilles Gressani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2025\/05\/Grand-Continent-Papometre-bis.png\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilles Gressani\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2025\/05\/02\/a-quale-cardinale-siete-piu-vicini-un-questionario-esclusivo-per-scegliere-il-vostro-papa-a-pochi-giorni-dal-conclave\/\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/2025\/05\/02\/a-quale-cardinale-siete-piu-vicini-un-questionario-esclusivo-per-scegliere-il-vostro-papa-a-pochi-giorni-dal-conclave\/\",\"name\":\"A quale cardinale siete pi\u00f9 vicini? Un questionario esclusivo per scegliere il vostro papa a pochi giorni dal conclave - Il Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2025\/05\/02\/a-quale-cardinale-siete-piu-vicini-un-questionario-esclusivo-per-scegliere-il-vostro-papa-a-pochi-giorni-dal-conclave\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2025\/05\/02\/a-quale-cardinale-siete-piu-vicini-un-questionario-esclusivo-per-scegliere-il-vostro-papa-a-pochi-giorni-dal-conclave\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2025\/05\/Grand-Continent-Papometre.png\",\"datePublished\":\"2025-05-02T19:26:17+00:00\",\"dateModified\":\"2025-05-02T19:36:01+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/cf5b9f219cfb8e49b2923ff0e192682b\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2025\/05\/02\/a-quale-cardinale-siete-piu-vicini-un-questionario-esclusivo-per-scegliere-il-vostro-papa-a-pochi-giorni-dal-conclave\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/it\/2025\/05\/02\/a-quale-cardinale-siete-piu-vicini-un-questionario-esclusivo-per-scegliere-il-vostro-papa-a-pochi-giorni-dal-conclave\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2025\/05\/02\/a-quale-cardinale-siete-piu-vicini-un-questionario-esclusivo-per-scegliere-il-vostro-papa-a-pochi-giorni-dal-conclave\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2025\/05\/Grand-Continent-Papometre.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2025\/05\/Grand-Continent-Papometre.png\",\"width\":1338,\"height\":842},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2025\/05\/02\/a-quale-cardinale-siete-piu-vicini-un-questionario-esclusivo-per-scegliere-il-vostro-papa-a-pochi-giorni-dal-conclave\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A quale cardinale siete pi\u00f9 vicini? Un questionario esclusivo per scegliere il vostro papa a pochi giorni dal conclave\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/\",\"name\":\"Il Grand Continent\",\"description\":\"La scala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/cf5b9f219cfb8e49b2923ff0e192682b\",\"name\":\"Gilles Gressani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ca9dca3417a297a024262b1a2d6d035a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ca9dca3417a297a024262b1a2d6d035a?s=96&d=mm&r=g\",\"caption\":\"Gilles Gressani\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A quale cardinale siete pi\u00f9 vicini? Un questionario esclusivo per scegliere il vostro papa a pochi giorni dal conclave - Il Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/it\/2025\/05\/02\/a-quale-cardinale-siete-piu-vicini-un-questionario-esclusivo-per-scegliere-il-vostro-papa-a-pochi-giorni-dal-conclave\/","og_locale":"it_IT","og_type":"article","og_title":"A quale cardinale siete pi\u00f9 vicini? Un questionario esclusivo per scegliere il vostro papa a pochi giorni dal conclave - Il Grand Continent","og_description":"Ecologia, aborto, radici cristiane dell'Europa, accordi segreti con la Cina, ruolo delle donne nella Chiesa: quali sono i papabili pi\u00f9 vicini alle vostre posizioni?","og_url":"https:\/\/legrandcontinent.eu\/it\/2025\/05\/02\/a-quale-cardinale-siete-piu-vicini-un-questionario-esclusivo-per-scegliere-il-vostro-papa-a-pochi-giorni-dal-conclave\/","og_site_name":"Il Grand Continent","article_published_time":"2025-05-02T19:26:17+00:00","article_modified_time":"2025-05-02T19:36:01+00:00","og_image":[{"width":1304,"height":738,"url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2025\/05\/Grand-Continent-Papometre-bis.png","type":"image\/png"}],"author":"Gilles Gressani","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2025\/05\/Grand-Continent-Papometre-bis.png","twitter_misc":{"Scritto da":"Gilles Gressani","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/it\/2025\/05\/02\/a-quale-cardinale-siete-piu-vicini-un-questionario-esclusivo-per-scegliere-il-vostro-papa-a-pochi-giorni-dal-conclave\/","url":"https:\/\/legrandcontinent.eu\/it\/2025\/05\/02\/a-quale-cardinale-siete-piu-vicini-un-questionario-esclusivo-per-scegliere-il-vostro-papa-a-pochi-giorni-dal-conclave\/","name":"A quale cardinale siete pi\u00f9 vicini? Un questionario esclusivo per scegliere il vostro papa a pochi giorni dal conclave - Il Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/it\/2025\/05\/02\/a-quale-cardinale-siete-piu-vicini-un-questionario-esclusivo-per-scegliere-il-vostro-papa-a-pochi-giorni-dal-conclave\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/it\/2025\/05\/02\/a-quale-cardinale-siete-piu-vicini-un-questionario-esclusivo-per-scegliere-il-vostro-papa-a-pochi-giorni-dal-conclave\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2025\/05\/Grand-Continent-Papometre.png","datePublished":"2025-05-02T19:26:17+00:00","dateModified":"2025-05-02T19:36:01+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/cf5b9f219cfb8e49b2923ff0e192682b"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/it\/2025\/05\/02\/a-quale-cardinale-siete-piu-vicini-un-questionario-esclusivo-per-scegliere-il-vostro-papa-a-pochi-giorni-dal-conclave\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/it\/2025\/05\/02\/a-quale-cardinale-siete-piu-vicini-un-questionario-esclusivo-per-scegliere-il-vostro-papa-a-pochi-giorni-dal-conclave\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/legrandcontinent.eu\/it\/2025\/05\/02\/a-quale-cardinale-siete-piu-vicini-un-questionario-esclusivo-per-scegliere-il-vostro-papa-a-pochi-giorni-dal-conclave\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2025\/05\/Grand-Continent-Papometre.png","contentUrl":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2025\/05\/Grand-Continent-Papometre.png","width":1338,"height":842},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/it\/2025\/05\/02\/a-quale-cardinale-siete-piu-vicini-un-questionario-esclusivo-per-scegliere-il-vostro-papa-a-pochi-giorni-dal-conclave\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/it\/"},{"@type":"ListItem","position":2,"name":"A quale cardinale siete pi\u00f9 vicini? Un questionario esclusivo per scegliere il vostro papa a pochi giorni dal conclave"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/it\/#website","url":"https:\/\/legrandcontinent.eu\/it\/","name":"Il Grand Continent","description":"La scala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/cf5b9f219cfb8e49b2923ff0e192682b","name":"Gilles Gressani","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ca9dca3417a297a024262b1a2d6d035a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ca9dca3417a297a024262b1a2d6d035a?s=96&d=mm&r=g","caption":"Gilles Gressani"}}]}},"lgc_categories":[{"id":2108,"name":"Religione","slug":"religione"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2025\/05\/Grand-Continent-Papometre.png","width":1338,"height":842,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/2\/2025\/04\/SIPA_ap21373651_000130-1-scaled.jpg","width":2560,"height":1729,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts\/32633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/comments?post=32633"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts\/32633\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/media\/32634"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/media?parent=32633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/categories?post=32633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/tags?post=32633"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/staff?post=32633"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/editorial_format?post=32633"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/serie?post=32633"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/audience?post=32633"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/geo?post=32633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}