{"id":3253,"date":"2022-01-17T13:13:48","date_gmt":"2022-01-17T13:13:48","guid":{"rendered":"https:\/\/legrandcontinent.eu\/ita\/?p=3253"},"modified":"2022-01-17T13:19:13","modified_gmt":"2022-01-17T13:19:13","slug":"annientare-una-lettura-del-nuovo-romanzo-di-houellebecq","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/it\/2022\/01\/17\/annientare-una-lettura-del-nuovo-romanzo-di-houellebecq\/","title":{"rendered":"Annientare : una lettura del nuovo romanzo di Houellebecq"},"content":{"rendered":"\n<p class=\"has-drop-cap\">Quasi niente nella vita mi ha mai resa pi\u00f9 infelicemente felice di deprimermi come i libri di Houellebecq. Non posso limitarmi a definirmi una semplice fan: il piacere che provo a incattivirmi tra le sue pagine \u00e8 talmente smisurato e perverso da sfiorare l\u2019idolatria. Essendo donna lo dico con un certo orgoglio, quasi fosse un onore militare: essere fino ad oggi uscita viva dalla lettura dei suoi romanzi senza cedere alla tentazione di suicidarmi \u00e8 un\u2019impresa non scontata e di cui anzi vado fiera. Eppure ho cominciato a leggere l\u2019autore di<em> La possibilit\u00e9 d\u2019une \u00eele<\/em> (il mio preferito tra i suoi romanzi) relativamente tardi, da meno di un paio d\u2019anni &#8211; non si tratta per\u00f2 di un ritardo, credo invece che aver superato l\u2019et\u00e0 di Ges\u00f9 Cristo sia un prerequisito per leggere Houellebecq, autore tanto trascurabile quando si \u00e8 nel pieno della giovinezza quanto necessario quando si comincia ad invecchiare e, come tutti, ad aver paura di morire.&nbsp;<\/p>\n\n\n\n<p>Per prepararmi all\u2019uscita di <em>An\u00e9antir <\/em>con uno sguardo pi\u00f9 sincero, nei giorni scorsi ho ascoltato il podcast in tre episodi proposto da France Inter, che ripercorre le critiche a tutti i romanzi di Houellebecq proposte negli anni dall\u2019emissione \u201cLe masque et la plume\u201d. Tra posizione estreme, polari, di amore o di odio &#8211; e in questo senso mi sento pi\u00f9 che mai vicina all\u2019infatuazione di Fr\u00e9d\u00e9ric Beigbeder -, si \u00e8 comunque costretti a riconoscere come i romanzi di Michel Houellebecq siano forse i soli ad avere una dimensione europea, non solo per la loro ambizione di essere totali, un po\u2019 come <em>La montagna incantata <\/em>di Thomas Mann, ma per l\u2019attesa da parte dei lettori di tutto il continente. Se <em>An\u00e9antir <\/em>il 7 gennaio \u00e8 stato pubblicato contemporaneamente anche in Italia dalla Nave di Teseo, non c\u2019\u00e8 stato giornale europeo che non ne abbia parlato &#8211; Michel Houellebecq \u00e8 diventato per me all\u2019estero un oggetto di discussione franco, un po\u2019 come la cucina italiana, visto che posso chiederne conto praticamente a chiunque in ogni angolo di Europa.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Ho dunque vissuto l\u2019attesa della pubblicazione di <em>An\u00e9antir <\/em>come una passione sivigliana, con tanto di rituali solo miei e infinite conversazioni\/interrogatori con chi mi sta accanto. Il 7 gennaio mi sono persino scandalizzata quando in libreria mi \u00e8 stato chiesto se cercassi \u2018qualcosa di particolare\u2019: che cosa mai dovrebbe volere un lettore il giorno dell\u2019uscita del nuovo romanzo di Houellebecq?&nbsp;<\/p>\n\n\n\n<p>Va detto che in quanto prodotto-libro me lo aspettavo pi\u00f9 bello, <em>An\u00e9antir, <\/em>almeno per gli annunci che l\u2019hanno preceduto e per il suo prezzo, 26 euro: una copertina (fin troppo) rigida bianco latte senza alcuna illustrazione, solo nome dell\u2019autore in nero e titolo in rosso, come a segnalare che ci\u00f2 che d\u00e0 senso al denaro speso \u00e8 tutto al suo interno. In effetti, il primo capoverso che apre il libro \u00e8 pi\u00f9 sofisticato e tagliente che mai: quel \u00ab&nbsp;<em>la proximit\u00e9 du n\u00e9ant est inhabituelle&nbsp;\u00bb <\/em>mi rassicura e mi corrobora come un primo bicchiere di vino di molte bottiglie &#8211; Houellebecq \u00e8 tornato a spogliarci delle nostre nevrosi, anzi a scorticarci vivi, meglio mettersi comodi per lasciarsi scandalizzare&nbsp; meglio.&nbsp;<\/p>\n\n\n\n<p>Il tema centrale di <em>An\u00e9antir <\/em>mi \u00e8 particolarmente caro, avendo recentemente perso mio padre: siamo nel futuro prossimo, nel 2027, e Paul Raison, un alto funzionario del gabinetto del ministro dell\u2019Economia Bruno Juge (riferimento diretto all\u2019attuale ministro Bruno Le Maire), ha ormai raggiunto \u00ab&nbsp;<em>une sorte de d\u00e9sespoir standardis\u00e9<\/em>&nbsp;\u00bb. Da pi\u00f9 di dieci anni senza alcun contatto n\u00e9 fisico n\u00e9 emotivo con la moglie Prudence pur continuando a vivere sotto lo stesso tetto, Paul sta indagando un video <em>deep fake <\/em>che vede il suo ministro brutalmente ghigliottinato. E mentre altri attentati ancora pi\u00f9 inquietanti, reali ma non rivendicati, colpiscono la Francia ecco che suo padre, anch\u2019egli a suo tempo al Ministero come responsabile della sicurezza di Stato e ora un settantaseienne poco incline allo stile di vita salutistico con cui tutti siamo quasi stalkerizzati dai media, ha un AVC che lo lascia in coma. \u00c8 dunque un percorso in ginocchio lungo il sentiero del fine vita, squallido come la corsia di un ospedale che, malgrado tutti gli sforzi per risultare architettonicamente accettabile, resta un luogo fatto per morire, quello che attende Paul &#8211; insieme alla campagna presidenziale, ancora pi\u00f9 impazzita di un embolo.<\/p>\n\n\n\n<p>In <em>An\u00e9antir <\/em>c\u2019\u00e8 una metafora con cui Houellebecq sintetizza lo scandalo supremo della morte: a bordo di un mini van di lusso che percorre le strade solitarie dell\u2019Ovest americano, un uomo dal volto satanico si diverte a gettare dal finestrino uno a caso tra i passeggeri attempati che, malgrado il terrore e lo sgomento, non osano ribellarsi: quel signore \u00e8 Dio e l\u2019assoluta irrazionalit\u00e0 con cui sceglie di porre fine all\u2019esistenza degli impotenti viaggiatori \u00e8 la sintesi della meschinit\u00e0 della morte. C\u2019\u00e8 in effetti &#8211; e per fortuna &#8211; molta religione in <em>An\u00e9antir<\/em>, tra lo yoga e la meditazione della moglie di Paul al cristianesimo incrollabile di sua sorella C\u00e9cile, che fin da quando era bambina di fronte a un problema ha sempre risposto \u201cchiedo a Dio\u201d con la stessa evidenza con cui si passano a ritirare le camicie in tintoria. E ovviamente c\u2019\u00e8 molta politica, essendoci una campagna elettorale in gioco, ma di grandi ideologie o almeno di rimedi al populismo imperante non se ne vedono in una societ\u00e0 in cui ormai esistono solo ricchi o poveri senza pi\u00f9 traccia di una classe media. Stranamente c\u2019\u00e8 un po\u2019 meno sesso del solito, i desideri dei personaggi rimangono quasi sempre frustrati (anche se le prime prostituite compaiono gi\u00e0 a pagina 50), e un po\u2019 pi\u00f9 d\u2019amore, o almeno un grande bisogno di amore come unica speranza di senso &#8211; <em>\u00ab&nbsp;coucher seul est difficile lorsqu\u2019on en a perdu l\u2019habitude, on a froid et on a peur&nbsp;\u00bb<\/em>.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Come sempre &#8211; \u00e8 questa la ragione suprema per cui tanto amo Houellebecq -, c\u2019\u00e8 tantissima sociologia, un resoconto spietato del nostro modo di vivere contemporaneo, tra un certo ecologismo idiota buono solo a riempiere d\u2019ipocrisia le coscienze e di orti condivisi certi giardini parigini, tra un femminismo di facciata che talvolta nasconde perversioni sessuali e una pi\u00f9 generale infantilizzazione del linguaggio pubblico che ci vuole ormai ridotti al rango di beb\u00e8 smarriti in attesa del prossimo ordine da parte del nostro genitore\/Stato &#8211; mentre scrivo queste righe, a bordo di un TGV che da Nantes mi riporta a Parigi, il controllore sente la necessit\u00e0 di illustrare ai passeggeri quali spuntini sono permessi a bordo in questo contesto di crisi sanitaria, frutta s\u00ec, patatine no, e allora mi chiedo se non sia uscito anche lui da un romanzo di Houellebecq.<\/p>\n\n\n\n<p>Infine, ci\u00f2 che mi resta dopo aver letto <em>An\u00e9antir <\/em>\u00e8 un profondo sentimento di vergogna. Non solo per amare a tal punto il suo autore (il complesso della lettura perversamente alla moda l\u2019ho superato da tempo), ma soprattutto per dover riconoscere come sempre che ha ragione: coloro di cui parla in <em>An\u00e9antir <\/em>sono i miei amici, i miei colleghi, i miei amanti, sono io stessa &#8211; per fortuna da fuori non si vede, nessuno lo sapr\u00e0 mai, e io continuer\u00f2 ipocrita come tutti a fingere di essere migliore dei personaggi narrati da Michel Houellebecq.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Andrea Marcolongo ci racconta come ha letto il nuovo romanzo di Houellebecq.<\/p>\n","protected":false},"author":10,"featured_media":3254,"comment_status":"open","ping_status":"open","sticky":false,"template":"templates\/post-reviews.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":7,"footnotes":""},"categories":[1603],"tags":[],"staff":[1961],"editorial_format":[2351],"serie":[],"audience":[],"geo":[],"class_list":["post-3253","post","type-post","status-publish","format-standard","hentry","category-arti","staff-andrea-marcolongo","editorial_format-recensioni"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":3254,"excerpt":"Andrea Marcolongo ci racconta come ha letto il nuovo romanzo di Houellebecq.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Annientare : una lettura del nuovo romanzo di Houellebecq - Il Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/it\/2022\/01\/17\/annientare-una-lettura-del-nuovo-romanzo-di-houellebecq\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Annientare : una lettura del nuovo romanzo di Houellebecq - Il Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Andrea Marcolongo ci racconta come ha letto il nuovo romanzo di Houellebecq.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/it\/2022\/01\/17\/annientare-una-lettura-del-nuovo-romanzo-di-houellebecq\/\" \/>\n<meta property=\"og:site_name\" content=\"Il Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-17T13:13:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-17T13:19:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/01\/MicrosoftTeams-image-96.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"693\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Matheo Malik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/01\/MicrosoftTeams-image-96.png\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheo Malik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2022\/01\/17\/annientare-una-lettura-del-nuovo-romanzo-di-houellebecq\/\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/2022\/01\/17\/annientare-una-lettura-del-nuovo-romanzo-di-houellebecq\/\",\"name\":\"Annientare : una lettura del nuovo romanzo di Houellebecq - Il Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2022\/01\/17\/annientare-una-lettura-del-nuovo-romanzo-di-houellebecq\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2022\/01\/17\/annientare-una-lettura-del-nuovo-romanzo-di-houellebecq\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/01\/NT_oceani_str_145_EXE_Houellebecq_Annientare_piatto.jpg\",\"datePublished\":\"2022-01-17T13:13:48+00:00\",\"dateModified\":\"2022-01-17T13:19:13+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2022\/01\/17\/annientare-una-lettura-del-nuovo-romanzo-di-houellebecq\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/it\/2022\/01\/17\/annientare-una-lettura-del-nuovo-romanzo-di-houellebecq\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2022\/01\/17\/annientare-una-lettura-del-nuovo-romanzo-di-houellebecq\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/01\/NT_oceani_str_145_EXE_Houellebecq_Annientare_piatto.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/01\/NT_oceani_str_145_EXE_Houellebecq_Annientare_piatto.jpg\",\"width\":1754,\"height\":2516},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2022\/01\/17\/annientare-una-lettura-del-nuovo-romanzo-di-houellebecq\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Annientare : una lettura del nuovo romanzo di Houellebecq\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/\",\"name\":\"Il Grand Continent\",\"description\":\"La scala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\",\"name\":\"Matheo Malik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"caption\":\"Matheo Malik\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Annientare : una lettura del nuovo romanzo di Houellebecq - Il Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/it\/2022\/01\/17\/annientare-una-lettura-del-nuovo-romanzo-di-houellebecq\/","og_locale":"it_IT","og_type":"article","og_title":"Annientare : una lettura del nuovo romanzo di Houellebecq - Il Grand Continent","og_description":"Andrea Marcolongo ci racconta come ha letto il nuovo romanzo di Houellebecq.","og_url":"https:\/\/legrandcontinent.eu\/it\/2022\/01\/17\/annientare-una-lettura-del-nuovo-romanzo-di-houellebecq\/","og_site_name":"Il Grand Continent","article_published_time":"2022-01-17T13:13:48+00:00","article_modified_time":"2022-01-17T13:19:13+00:00","og_image":[{"width":1200,"height":693,"url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/01\/MicrosoftTeams-image-96.png","type":"image\/png"}],"author":"Matheo Malik","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/01\/MicrosoftTeams-image-96.png","twitter_misc":{"Scritto da":"Matheo Malik","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/it\/2022\/01\/17\/annientare-una-lettura-del-nuovo-romanzo-di-houellebecq\/","url":"https:\/\/legrandcontinent.eu\/it\/2022\/01\/17\/annientare-una-lettura-del-nuovo-romanzo-di-houellebecq\/","name":"Annientare : una lettura del nuovo romanzo di Houellebecq - Il Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/it\/2022\/01\/17\/annientare-una-lettura-del-nuovo-romanzo-di-houellebecq\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/it\/2022\/01\/17\/annientare-una-lettura-del-nuovo-romanzo-di-houellebecq\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/01\/NT_oceani_str_145_EXE_Houellebecq_Annientare_piatto.jpg","datePublished":"2022-01-17T13:13:48+00:00","dateModified":"2022-01-17T13:19:13+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/it\/2022\/01\/17\/annientare-una-lettura-del-nuovo-romanzo-di-houellebecq\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/it\/2022\/01\/17\/annientare-una-lettura-del-nuovo-romanzo-di-houellebecq\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/legrandcontinent.eu\/it\/2022\/01\/17\/annientare-una-lettura-del-nuovo-romanzo-di-houellebecq\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/01\/NT_oceani_str_145_EXE_Houellebecq_Annientare_piatto.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/01\/NT_oceani_str_145_EXE_Houellebecq_Annientare_piatto.jpg","width":1754,"height":2516},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/it\/2022\/01\/17\/annientare-una-lettura-del-nuovo-romanzo-di-houellebecq\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/it\/"},{"@type":"ListItem","position":2,"name":"Annientare : una lettura del nuovo romanzo di Houellebecq"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/it\/#website","url":"https:\/\/legrandcontinent.eu\/it\/","name":"Il Grand Continent","description":"La scala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45","name":"Matheo Malik","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","caption":"Matheo Malik"}}]}},"lgc_categories":[{"id":1603,"name":"Arti","slug":"arti"}],"lgc_author":{"id":1961,"name":"Andrea Marcolongo","slug":"andrea-marcolongo","description":"<span style=\"font-weight: 400\">Andrea Marcolongo \u00e8 giornalista e scrittrice.<\/span>\r\n\r\n\u00c8 vicepresidente degli<span style=\"font-weight: 400\"> \u00c9crivains de Marine, associazione affiliata al ministero della Difesa francese \u00abimpegnata per preservare la cultura del mare\u00bb. Per il suo impegno ha ricevuto il titolo onorifico di capitana di fregata. \u00c8 parte della giuria del \u00abPrix du Livre d'Histoire des Outre-mer\u00bb e del premio Grand Continent<\/span>","first_name":"Andrea","last_name":"Marcolongo","picture":{"url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2023\/10\/marcolongo.jpeg","width":230,"height":345,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/01\/NT_oceani_str_145_EXE_Houellebecq_Annientare_piatto.jpg","width":1754,"height":2516,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2022\/01\/NT_oceani_str_145_EXE_Houellebecq_Annientare_piatto.jpg","width":1754,"height":2516,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts\/3253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/comments?post=3253"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts\/3253\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/media\/3254"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/media?parent=3253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/categories?post=3253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/tags?post=3253"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/staff?post=3253"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/editorial_format?post=3253"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/serie?post=3253"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/audience?post=3253"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/geo?post=3253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}