{"id":28052,"date":"2024-12-16T17:46:07","date_gmt":"2024-12-16T16:46:07","guid":{"rendered":"https:\/\/legrandcontinent.eu\/it\/?p=28052"},"modified":"2024-12-16T17:46:10","modified_gmt":"2024-12-16T16:46:10","slug":"con-la-caduta-di-assad-la-strategia-delliran-sta-crollando-una-conversazione-con-ali-vaez","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/it\/2024\/12\/16\/con-la-caduta-di-assad-la-strategia-delliran-sta-crollando-una-conversazione-con-ali-vaez\/","title":{"rendered":"\u201cCon la caduta di Assad, la strategia dell&#8217;Iran sta crollando\u201d, una conversazione con Ali Vaez"},"content":{"rendered":"\n<p><em>\u00c8 Natale. Se state leggendo queste righe e volete fare un regalo ai vostri cari &#8211; o a voi stessi &#8211; sostenendo il lavoro di una redazione indipendente, <a href=\"https:\/\/legrandcontinent.eu\/it\/offerta\/\">prendete un momento per pensare di abbonarvi a Il Grand Continent.<\/a><\/em><\/p>\n\n\n\n<p><em>Marted\u00ec 17 dicembre, alle 19.30, la situazione politica in Siria sar\u00e0 al centro del nostro dibattito settimanale &#8211;\u00a0<\/em><a href=\"https:\/\/legrandcontinent.eu\/fr\/evenements\/comprendre-la-chute-de-bachar-el-assad-et-lavenir-de-la-syrie\"><em>cliccate qui per iscrivervi (gratuitamente) se siete a Parigi<\/em><\/a><em>.<\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Cosa significa <\/strong><a href=\"https:\/\/legrandcontinent.eu\/it\/category\/politica\/hts-al-jolani-la-siria-dopo-assad\/\"><strong>la caduta del regime di Bashar al-Assad<\/strong><\/a><strong> per la Repubblica Islamica dell&#8217;Iran?<\/strong><\/h3>\n\n\n\n<p>La strategia della Repubblica islamica nel Levante sta crollando. Per anni, l&#8217;Iran ha cercato di proiettare il proprio potere e la propria influenza nella regione coltivando alleati non statali. Di questa rete, Hezbollah era il <em>primus inter pares<\/em>, mentre la Siria di Assad ne era il principale alleato statale, per la cui sopravvivenza Teheran ha investito un volume impressionante di risorse finanziarie e umane. Dopo l&#8217;attacco di Hamas a Israele del 7 ottobre e l&#8217;inizio della campagna militare israeliana a Gaza, l&#8217;Iran e l&#8217;Asse della Resistenza erano colmi d\u2019arroganza.&nbsp;<\/p>\n\n\n\n<p>Un anno dopo, il regime \u00e8 strategicamente, diplomaticamente e militarmente sopraffatto.<\/p>\n\n\n\n<p>Possiamo prevedere accesi dibattiti e recriminazioni all&#8217;interno delle Guardie Rivoluzionarie e, pi\u00f9 in generale, del sistema su come si sia giunti a questa debacle e &#8211; forse pi\u00f9 cruciale ancora &#8211; sulla questione di sapere se accettare le perdite o cercare di raddoppiare gli sforzi &#8211; questo per\u00f2 da una posizione notevolmente indebolita.<\/p>\n\n\n\n<p>Dopo aver investito cos\u00ec tanto della sua reputazione, delle sue risorse e vite umane negli ultimi tredici anni per salvare il regime di Bashar al-Assad e con esso la direzione strategica della Siria, questo improvviso crollo dell&#8217;ordine baathista rappresenta una grave battuta d&#8217;arresto per l&#8217;Iran. Questo sentimento domina ampiamente il dibattito pubblico sulla questione nel Paese, e&nbsp; non viene nemmeno nascosto. In effetti, l&#8217;Iran aveva estremo bisogno della Siria per fornire supporto logistico a Hezbollah che il regime stava cercando di ricostruire in Libano: la caduta di Assad \u00e8 un&#8217;importante questione di sicurezza nazionale per Teheran.<\/p>\n\n\n\n<p>Gli iraniani hanno incoraggiato Hezbollah ad accettare il cessate il fuoco nonostante ai loro occhi favorisse gli interessi di Israele, perch\u00e9 lo consideravano essenziale per la ricostruzione delle forze di Hezbollah. Prima che il cessate il fuoco potesse essere utilizzato per aiutare Hezbollah a rimettersi in piedi, il ponte siriano \u00e8 crollato.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Dopo l&#8217;attacco di Hamas a Israele del 7 ottobre e l&#8217;inizio della campagna militare israeliana a Gaza, l&#8217;Iran e l&#8217;Asse della Resistenza erano colmi d\u2019arroganza. Un anno dopo, il regime \u00e8 strategicamente, diplomaticamente e militarmente sopraffatto.<\/p><cite>Ali Vaez<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>In Iran si discute delle cause e delle lezioni da trarre dalla caduta di Bashar al-Assad?<\/strong><\/h3>\n\n\n\n<p>Oggi il dibattito pubblico in Iran si articola attorno a tre temi principali.&nbsp;<\/p>\n\n\n\n<p>Innanzitutto, si discute su chi sia responsabile della perdita della Siria. Una parte ritiene che l&#8217;Iran sia colpevole di essersi fidato delle rassicurazioni della Turchia sul fatto che i ribelli armati siriani non avevano intenzione di organizzare una grande operazione contro il regime di Assad. Altri ritengono che i russi abbiano pugnalato alle spalle gli iraniani e abbiano stretto un accordo con l&#8217;HTS per preservare <a href=\"https:\/\/legrandcontinent.eu\/it\/2024\/12\/09\/fine-della-presenza-militare-russa-avanzata-israeliana-quale-equilibrio-per-la-siria-post-assad\/\">le loro basi navali in Siria<\/a> in cambio della non opposizione alla presa di controllo delle principali citt\u00e0 e della non difesa del regime di Assad.\u00a0<\/p>\n\n\n\n<p>In secondo luogo, parte del sistema si chiede quali lezioni si possano trarre per l&#8217;Iran. Alcuni, come il leader Ali Khamenei, ritengono che la Siria sia crollata perch\u00e9 il regime non aveva pi\u00f9 la volont\u00e0 di combattere. Altri ritengono che Bashar al-Assad non abbia preso misure sufficienti per ridurre il divario tra Stato e societ\u00e0. Da questo punto di vista, i casi siriano e iraniano sono paragonabili. In Iran, non c&#8217;\u00e8 un gruppo minoritario alauita che governa sulla maggioranza della popolazione sunnita, ma un <em>establishment<\/em> clericale minoritario che governa su una societ\u00e0 prevalentemente laica. In entrambi gli Stati, un grado avanzato di repressione e corruzione \u00e8 alla base di molte frustrazioni all&#8217;interno della societ\u00e0.&nbsp;<\/p>\n\n\n\n<p>Infine, un gruppo ritiene che la dottrina di sicurezza nazionale iraniana debba essere trasformata perch\u00e9 i suoi due pilastri &#8211; Hezbollah e Siria &#8211; sono stati recentemente notevolmente indeboliti. Anche l&#8217;accesso a Hezbollah attraverso la Siria \u00e8 venuto meno. In questo senso, l&#8217;Asse della Resistenza come lo conoscevamo non esiste pi\u00f9, perch\u00e9 non c&#8217;\u00e8 asse senza accesso. In questa situazione, alcuni ritengono che l&#8217;Iran debba concentrarsi maggiormente sulle sue capacit\u00e0 convenzionali; <a href=\"https:\/\/legrandcontinent.eu\/it\/2024\/12\/13\/le-conseguenze-della-caduta-del-regime-di-al-assad-per-la-strategia-di-influenza-della-cina-in-medio-oriente\/\">altri che sia necessario impegnarsi con una grande potenza come la Cina<\/a> per renderla garante della sua sicurezza; altri ancora che sia necessario sviluppare armi nucleari come deterrente finale.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>L&#8217;Asse della Resistenza come lo conoscevamo non esiste pi\u00f9, perch\u00e9 non c&#8217;\u00e8 asse senza accesso.<\/p><cite>Ali Vaez<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Questi vari dibattiti stanno creando divisioni all&#8217;interno della struttura politica del regime iraniano?<\/strong><\/h3>\n\n\n\n<p>Innanzitutto, si tratta di un&#8217;importante battuta d&#8217;arresto per l&#8217;apparato militare e di sicurezza iraniano, che sono le principali forze che resistono al cambiamento in Iran. In effetti, i militari hanno incolpato i civili per i fallimenti del Paese sul fronte economico, diplomatico e culturale. L&#8217;apparato di sicurezza, da parte sua, riteneva di avere avuto molto pi\u00f9 successo rispetto agli altri circoli di potere &#8211; nonostante delle risorse limitate &#8211; grazia allo sviluppo del programma nucleare, del programma balistico e di una rete di agenti nella regione. Oggi, la scomparsa dell&#8217;Asse della Resistenza dimostra che i successi dell&#8217;esercito erano solo illusori.<\/p>\n\n\n\n<p>Questo potrebbe essere positivo. Tuttavia, un attento esame dei termini del dibattito lascia poco spazio alla speranza. La maggior parte delle discussioni citate porta alla conclusione che l&#8217;Iran si \u00e8 gi\u00e0 trovato in una situazione simile &#8211; nel 2003. All&#8217;epoca, gli Stati Uniti avevano appena rovesciato un regime ad est (in Afghanistan) e uno ad ovest (in Iraq). Sembravano sul punto di invadere l&#8217;Iran, dal momento che l&#8217;amministrazione Bush aveva rifiutato a priori qualsiasi possibilit\u00e0 di negoziato. Ciononostante, a partire dal 2006, Teheran \u00e8 riuscita a ribaltare la situazione in Iraq e a riprendere il sopravvento sugli Stati Uniti.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>L&#8217;Iran poteva permettersi di temporizzare nel 2003, non nel 2025.<\/p><cite>Ali Vaez<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Molti ritengono quindi che l&#8217;Iran debba ancora una volta giocare d&#8217;anticipo e attendere o la frammentazione dei gruppi di opposizione siriani, o un eccesso di fiducia israeliana in qualche parte della regione o l&#8217;arrivo di un&#8217;amministrazione Trump che persegua politiche incoerenti: tutte circostanze che potrebbero consentire all&#8217;Iran di ribaltare la situazione. Tuttavia, questa retorica trascura una realt\u00e0 fondamentale: l&#8217;Iran poteva permettersi di temporizzare nel 2003, non nel 2025. Le sue vulnerabilit\u00e0 militari sono visibili, il suo scudo difensivo nella regione si \u00e8 incrinato e i suoi problemi economici sono molto profondi.<\/p>\n\n\n\n<p>Questo spiega perch\u00e9 la Guida Suprema si sta concentrando sull&#8217;unico pubblico che gli interessa per la sopravvivenza del regime, ovvero i suoi principali elettori, quel 10-15% della popolazione iraniana che crede ancora nel regime per motivi ideologici o finanziari, che ritiene che tutto vada bene, e che questa sia chiaramente una battuta d&#8217;arresto ma che potr\u00e0 essere superata.<\/p>\n\n\n\n<p>Un&#8217;analogia molto pi\u00f9 azzeccata \u00e8 quella della sconfitta dell&#8217;Unione Sovietica in Afghanistan. L&#8217;umiliazione causata dalla sconfitta sovietica ha fondamentalmente minato la credibilit\u00e0 del regime agli occhi dei suoi alleati e della sua stessa popolazione, prima di accelerarne il crollo. Ma la dipendenza da un segmento ristretto della societ\u00e0 \u00e8 proprio ci\u00f2 che ha fatto crollare il regime di Assad. Credere che la soluzione migliore sia affidarsi ancora di pi\u00f9 a una parte minoritaria della popolazione e perseguire politiche che sono state appena sconfessate pu\u00f2 solo portare al fallimento.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La dipendenza da un segmento ristretto della societ\u00e0 \u00e8 proprio ci\u00f2 che ha fatto crollare <br>il regime di Assad.<\/p><cite>Ali Vaez<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Il discredito dei militari in Iran pu\u00f2 spiegare l&#8217;accelerazione delle politiche identitarie, come la legge che rafforza l\u2019obbligo per le donne di indossare il velo, che dovrebbe essere applicata nei prossimi giorni?<\/strong><\/h3>\n\n\n\n<p>I leader della Repubblica islamica tendono a rispondere alle pressioni con l&#8217;inflessibilit\u00e0, sia nei confronti del proprio popolo che della comunit\u00e0 internazionale. Rafforzare il controllo sulla popolazione \u00e8 un modo per il regime di dimostrare la propria capacit\u00e0 di mantenere il potere. \u00c8 importante capire che ora c&#8217;\u00e8 una differenza tra i settori pi\u00f9 securitari del governo, che vogliono attuare la nuova legge sull&#8217;hijab per stroncare sul nascere qualsiasi forma di opposizione, e il governo iraniano, che vuole ridurre il divario tra Stato e societ\u00e0 &#8211; e quindi sta ritardando l&#8217;attuazione di questa legge. Il governo di Pezechkian \u00e8 consapevole che alienarsi intere fasce della popolazione iraniana potrebbe rappresentare una minaccia esistenziale per il regime e persino per lo Stato.<\/p>\n\n\n\n<p>L&#8217;unico modo per la Repubblica islamica di superare questo periodo sarebbe quello di inaugurare un periodo di cambiamenti radicali nella politica interna ed estera del Paese, alla maniera dell&#8217;era di Deng Xiaoping in Cina. Tuttavia, sembra improbabile che l&#8217;ottantaseienne Guida Suprema accetti di aprire il sistema politico e di attuare riforme a scapito di gran parte di un sistema ormai cleptocratico.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Sulla scia del discorso di Ali Khamenei di mercoled\u00ec, sono emersi paragoni tra il suo rifiuto di ammettere la sconfitta strategica e il discorso che Saddam Hussein fece dopo il ritiro delle truppe irachene dal Kuwait.<\/strong> <strong>Come analizza queste diverse forme di cecit\u00e0?<\/strong><\/h3>\n\n\n\n<p>L&#8217;Iran \u00e8 &#8211; ancora oggi &#8211; un Paese pi\u00f9 pluralista di quanto non lo fosse l&#8217;Iraq dopo la sconfitta nella prima guerra del Golfo.<\/p>\n\n\n\n<p>Il governo iraniano \u00e8 anche molto pi\u00f9 pragmatico, come dimostrano le sue interazioni con la futura amministrazione Trump. L&#8217;attuale vicepresidente iraniano, ad esempio, ha scritto un editoriale su <em>Foreign Affairs <\/em>invitando l&#8217;amministrazione Trump a negoziare con l&#8217;Iran. Esprimere pubblicamente il desiderio di negoziare con l&#8217;uomo che ha ordinato la morte di Qassem Soleimani, mentre il regime iraniano ha cercato di vendicare questa morte negli ultimi anni &#8211; anche tentando di assassinare Donald Trump e hackerando la sua campagna presidenziale &#8211; dimostra il grado di pragmatismo che prevale all&#8217;interno del sistema.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>L&#8217;unico modo per la Repubblica islamica di superare questo periodo sarebbe quello di inaugurare un periodo di cambiamenti radicali nella politica interna ed estera del Paese, <br>alla maniera dell&#8217;era di Deng Xiaoping in Cina.\u00a0<\/p><cite>Ali Vaez<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Come si \u00e8 posizionato l&#8217;Iran nei confronti dell&#8217;HTS, <\/strong><a href=\"https:\/\/legrandcontinent.eu\/it\/2024\/12\/12\/la-siria-e-di-nuovo-al-centro-della-riconfigurazione-geopolitica-del-medio-oriente-una-conversazione-con-hugo-micheron\/\"><strong>il movimento ribelle islamista che ha rovesciato il regime di Bashar al-Assad<\/strong><\/a><strong>?<\/strong><\/h3>\n\n\n\n<p>L&#8217;Iran non ha fatto in Siria con l&#8217;HTS quello che ha fatto in Afghanistan con i Talebani.<\/p>\n\n\n\n<p>In Afghanistan, quando la vittoria dei Talebani sembrava inevitabile, Teheran ha riaperto i canali di comunicazione con loro e li ha riforniti di armi e fondi per combattere lo Stato Islamico nel Khorasan.<\/p>\n\n\n\n<p>In Siria, la leadership iraniana ha sempre considerato i membri dell&#8217;HTS come pedine della Turchia. Non hanno quindi mai stretto legami con il gruppo e avranno bisogno di tempo per sfruttare la possibile frammentazione della ribellione siriana e stringere relazioni con i gruppi che ne fanno parte. Se la Siria precipiter\u00e0 nel caos, Teheran cercher\u00e0 di farlo. Ma il regime ha un&#8217;altra priorit\u00e0 al momento: aiutare Hezbollah a riarmarsi per dissuadere Israele dal lanciare un attacco diretto all&#8217;Iran. Si tratta di un&#8217;emergenza a breve termine, non di una questione a medio termine come lo sviluppo di una rete di influenza in Siria.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Perch\u00e9 l&#8217;Iran non ha cercato di sostenere il regime siriano?\u00a0<\/strong><\/h3>\n\n\n\n<p>Sappiamo che nemmeno il governo iracheno ha aperto le frontiere per permettere alle milizie irachene di venire in aiuto del regime di Assad. Allo stesso modo, sappiamo che qualche mese fa l&#8217;Iran ha informato il regime siriano che l&#8217;HTC si stava mobilitando e stava preparando una grande offensiva, ma il regime di Assad non ha preso sul serio questa informazione n\u00e9 ha agito di conseguenza. Una politica regionale basata su attori non statali o su Stati svuotati della loro sostanza dal dominio di un singolo attore \u00e8 un vero e proprio castello di carte che pu\u00f2 crollare in qualsiasi momento.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Nasrallah ha svolto un ruolo fondamentale nella strutturazione dell&#8217;Asse della Resistenza in Siria.<\/p><cite>Ali Vaez<\/cite><\/blockquote><\/figure>\n\n\n\n<p>L&#8217;altra spiegazione della disintegrazione dell&#8217;Asse della Resistenza \u00e8 un certo grado di paralisi nel processo decisionale, derivante dall&#8217;eliminazione di tutti gli attori chiave al suo interno &#8211; che si tratti dell&#8217;architetto Soleimani, eliminato nel 2020, di alcuni degli altissimi funzionari dei servizi di intelligence dei Guardiani e dei comandanti regionali che Israele ha eliminato all&#8217;inizio di quest&#8217;anno, e naturalmente della mente strategica delle attivit\u00e0, Hassan Nasrallah, eliminato il 28 settembre da Israele. Si tende a pensare all&#8217;Asse della Resistenza come a uno strumento per l&#8217;influenza iraniana in Siria e in Libano, ma Nasrallah ha svolto un ruolo fondamentale anche nella strutturazione dell&#8217;Asse in Siria.<\/p>\n\n\n\n\n<div class=\"double-picture my-12 lg:my-20\" \n    data-images-sizes=\"half\"\n    data-same-height=\"true\"\n    data-reference-image=\"left\"\n>    <!-- Images -->\n    <div class=\"lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-1\/2\">\n                            <a \n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/SIPA_shutterstock41238361_000017.jpg\" \n                    class=\"gallery-item no-underline  \" \n                    data-pswp-width=\"2550\" \n                    data-pswp-height=\"1700\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/SIPA_shutterstock41238361_000017.jpg\" alt=\"Discorso della Guida suprema iraniana, l'ayatollah Ali Khamenei, dopo la caduta di Bashar al-Assad. Teheran, 11 dicembre 2024. \u00a9 Zuma Press Wire\/Shutterstock\" >\n                        <\/picture>\n                        <figcaption class=\"lg:hidden pswp-caption-content\">Discorso della Guida suprema iraniana, l&#8217;ayatollah Ali Khamenei, dopo la caduta di Bashar al-Assad. Teheran, 11 dicembre 2024. \u00a9 Zuma Press Wire\/Shutterstock<\/figcaption>                    <\/figure>\n                <\/a>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-1\/2\">\n                            <a\n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/SIPA_shutterstock41238361_000006.jpg\" \n                    class=\"gallery-item no-underline  lg:!absolute lg:h-full lg:right-0 lg:left-2 overflow-hidden\" \n                    data-pswp-width=\"2550\" \n                    data-pswp-height=\"1700\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/SIPA_shutterstock41238361_000006.jpg\" alt=\"Discorso della Guida suprema iraniana, l'ayatollah Ali Khamenei, dopo la caduta di Bashar al-Assad. Teheran, 11 dicembre 2024. \u00a9 Zuma Press Wire\/Shutterstock\" class=\"lg:!h-full object-cover\">\n                        <\/picture>\n                        <figcaption class=\"lg:hidden pswp-caption-content\">Discorso della Guida suprema iraniana, l&#8217;ayatollah Ali Khamenei, dopo la caduta di Bashar al-Assad. Teheran, 11 dicembre 2024. \u00a9 Zuma Press Wire\/Shutterstock<\/figcaption>                    <\/figure>\n                <\/a>\n                    <\/div>\n    <\/div>\n    <!-- Captions -->\n    <div class=\"hidden lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-1\/2\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">\n                    <figcaption>Discorso della Guida suprema iraniana, l&#8217;ayatollah Ali Khamenei, dopo la caduta di Bashar al-Assad. Teheran, 11 dicembre 2024. \u00a9 Zuma Press Wire\/Shutterstock<\/figcaption>                <\/figure>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-1\/2\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">   \n                    <figcaption>Discorso della Guida suprema iraniana, l&#8217;ayatollah Ali Khamenei, dopo la caduta di Bashar al-Assad. Teheran, 11 dicembre 2024. \u00a9 Zuma Press Wire\/Shutterstock<\/figcaption>                <\/figure>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Quali sono gli elementi concreti del potere iraniano nella regione che scompariranno con la caduta di Bashar al-Assad?<\/strong><\/h3>\n\n\n\n<p>Le relazioni tra la famiglia Assad e la Repubblica islamica non sono mai state molto amichevoli.<\/p>\n\n\n\n<p>Bashar al-Assad \u00e8 ora a Mosca piuttosto che a Teheran. Dal punto di vista ideologico, c&#8217;era ben poco in comune tra il movimento baathista e la teocrazia iraniana. Tuttavia, la Siria, il pi\u00f9 antico alleato di Stato della Repubblica islamica, era anche la sua spina dorsale logistica. Se l&#8217;Iran fosse stato in grado di creare una via d&#8217;accesso per sostenere Hezbollah senza dipendere dal regime siriano, lo avrebbe gi\u00e0 fatto molto tempo fa.<\/p>\n\n\n\n<p>La strategia iraniana si \u00e8 rivelata un guscio vuoto perch\u00e9 si \u00e8 sempre concentrata sull&#8217;uso delle rivendicazioni per mobilitare gruppi ideologicamente allineati con essa nella loro opposizione agli Stati Uniti e a Israele e per rafforzare forti attori non statali a spese delle istituzioni statali. Una politica del genere pu\u00f2 funzionare per un po&#8217;. Ma senza soddisfare i bisogni della popolazione, senza un contratto sociale, senza prosperit\u00e0 e senza adesione al processo politico, le entit\u00e0 politiche su cui si basa l&#8217;Iran sono strutturalmente instabili.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Mentre Hezbollah si addestrava a combattere la guerra del passato, Israele si proiettava nella guerra del futuro, quella che sta conducendo dall&#8217;estate contro l&#8217;Iran e il suo Asse della Resistenza.<\/p><cite>Ali Vaez<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Ad esempio, l&#8217;Iran ha aiutato l&#8217;Iraq a respingere gli Stati Uniti, ma non ha aiutato l&#8217;Iraq a rafforzare le proprie istituzioni. Al contrario, l&#8217;Iran ha sostenuto il Primo Ministro Maliki, che ha perseguito una politica faziosa e ha trascinato l&#8217;Iraq nell&#8217;abisso, cosa che ha portato alla nascita dello Stato Islamico. In Libano, l&#8217;Iran ha aiutato Hezbollah ad avere la meglio politicamente e militarmente, ma non ha incoraggiato il governo libanese a trovare un primo ministro e un presidente negli ultimi due anni per cercare di risollevare la situazione economica. Tutti questi elementi hanno creato una rete forte in apparenza, ma debole se si scava sotto la superficie.&nbsp;<\/p>\n\n\n\n<p>Allo stesso tempo, per tutti questi anni, Israele non ha utilizzato il suo vantaggio militare qualitativo per intraprendere azioni coraggiose contro l&#8217;\u201casse\u201d. Il risultato \u00e8 stato una certa inerzia in termini di equilibrio della deterrenza per l&#8217;Iran e i suoi alleati. Mentre Hezbollah si addestrava a combattere la guerra del passato, Israele si proiettava nella guerra del futuro, quella che sta conducendo dall&#8217;estate contro l&#8217;Iran e il suo Asse della Resistenza. La profonda debolezza dell&#8217;Asse di Resistenza e una risposta militare israeliana molto pi\u00f9 audace hanno ribaltato la situazione.<\/p>\n\n\n\n<p>Naturalmente, gli ingredienti utilizzati dall&#8217;Iran per creare questa rete &#8211; l&#8217;odio per la politica israeliana e la frustrazione nei confronti dei piani occidentali per quella parte del mondo &#8211; non sono scomparsi. L&#8217;Iran cercher\u00e0 quindi sempre di creare e reclutare nuovi gruppi che perseguano una politica simile. Tuttavia, Teheran non ha n\u00e9 il tempo, n\u00e9 le risorse finanziarie e nemmeno il capitale umano per replicare questa politica.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Per molti, la caduta di Assad \u00e8 un&#8217;occasione d&#8217;oro per spingere il regime iraniano sull&#8217;orlo del baratro.<\/p><cite>Ali Vaez<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Potremmo dire che, cos\u00ec come l&#8217;operazione americana in Afghanistan \u00e8 fallita perch\u00e9 lo Stato afghano era un guscio vuoto, la strategia iraniana di influenza in Siria \u00e8 fallita perch\u00e9 lo Stato siriano era di fatto uno Stato fallito?<\/strong><\/h3>\n\n\n\n<p>\u00c8 un paragone interessante, ma ci sono due differenze fondamentali. Da un lato, gli Stati Uniti stavano cercando di costruire uno Stato in Afghanistan in un contesto che non conoscevano bene, mentre i leader iraniani hanno una profonda conoscenza e familiarit\u00e0 con Paesi come Iraq, Libano e Siria. D&#8217;altra parte, l&#8217;Afghanistan non era essenziale per la sicurezza nazionale degli Stati Uniti, mentre la stabilit\u00e0 in Iraq e Siria \u00e8 essenziale per la sicurezza dell&#8217;Iran. Non dimentichiamo che il crollo dello Stato iracheno ha portato alla nascita dello Stato Islamico, a cinquanta chilometri dai confini iraniani.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Come vede la situazione la futura amministrazione Trump<\/strong>?<\/h3>\n\n\n\n<p>Per molti, questa \u00e8 un&#8217;occasione d&#8217;oro per spingere il regime iraniano sull&#8217;orlo del baratro, considerando che con una combinazione di pressione militare israeliana, pressione economica americana e pressione diplomatica europea, il regime non sarebbe in grado di rimettersi in piedi. Alcuni responsabili dell&#8217;amministrazione Trump ritengono che entro il 2025 l&#8217;Occidente sar\u00e0 in grado non solo di ottenere concessioni sul fronte nucleare, ma anche di costringere l&#8217;Iran a ridurre o addirittura abbandonare il suo sostegno agli attori non statali in Medio Oriente, a smettere di trasferire droni e missili alla Russia e a trasformare completamente il comportamento del regime &#8211; se non il regime stesso.<\/p>\n\n\n\n<p>Tuttavia, se il regime \u00e8 attualmente debole nella regione, \u00e8 ancora piuttosto forte nel Paese stesso.<\/p>\n\n\n\n<p>In Siria c&#8217;era un&#8217;opposizione organizzata e armata, mentre in Iran non esiste un&#8217;alternativa valida al regime, n\u00e9 all&#8217;interno n\u00e9 all&#8217;esterno del Paese. Quindi il regime non \u00e8 ancora privo di opzioni. Molti ora prevedono una corsa alle armi nucleari come alternativa alla perdita della deterrenza regionale. In risposta a <a href=\"https:\/\/legrandcontinent.eu\/it\/2024\/11\/23\/il-nucleare-iraniano-a-che-punto-siamo\/\">una risoluzione approvata dagli europei durante l&#8217;ultima riunione del Consiglio dei governatori dell&#8217;Agenzia internazionale per l&#8217;energia atomica<\/a>, l&#8217;Iran ha aumentato il tasso di arricchimento al 60% presso l&#8217;impianto di Fordow, tanto che il tempo necessario per arricchire materiale fissile sufficiente per quattro o cinque armi nucleari \u00e8 stato ridotto da tre o quattro settimane a pochi giorni.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Molti ora prevedono una corsa alle armi nucleari come alternativa alla perdita della deterrenza regionale.<\/p><cite>Ali Vaez<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Infine, il problema di un approccio che si affida esclusivamente alle pressioni e mira a provocare un&#8217;implosione del regime piuttosto che a negoziare, \u00e8 che non fornisce le vie d&#8217;uscita necessarie per evitare un confronto che sarebbe disastroso. Un regime in difficolt\u00e0 potrebbe vedere lo scontro come la sua migliore possibilit\u00e0 di sopravvivenza, perch\u00e9 creerebbe un senso di unit\u00e0 nazionale che altrimenti non esisterebbe pi\u00f9. Il 2025 sar\u00e0 un anno estremamente pericoloso per le relazioni tra Iran e Occidente. C&#8217;\u00e8 pi\u00f9 rischio di errori di calcolo che di un miracoloso raggiungimento di un nuovo accordo tra Iran e Trump.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tra le vittime collaterali della guerra lampo di al-Jolani in Siria, l&#8217;Iran \u00e8 senza dubbio la pi\u00f9 colpita.<\/p>\n<p>A poco pi\u00f9 di un anno dal 7 ottobre, l&#8217;\u201cAsse della Resistenza\u201d sembra essere stato sconfitto &#8211; strategicamente, diplomaticamente e militarmente. Per i nemici di Teheran, la caduta di Assad \u00e8 un&#8217;occasione d&#8217;oro per spingere il decadente regime iraniano nell&#8217;abisso.<\/p>\n<p>Un punto della situazione e uno sguardo verso il futuro con Ali Vaez. <\/p>\n","protected":false},"author":29021,"featured_media":28055,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-interviews.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":15,"footnotes":""},"categories":[2299],"tags":[],"staff":[2124],"editorial_format":[2352],"serie":[],"audience":[],"geo":[2183],"class_list":["post-28052","post","type-post","status-publish","format-standard","hentry","category-hts-al-jolani-la-siria-dopo-assad","staff-pierre-ramond","editorial_format-interviste","geo-asie-intermedie"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":28055,"excerpt":"Tra le vittime collaterali della guerra lampo di al-Jolani in Siria, l'Iran \u00e8 senza dubbio la pi\u00f9 colpita.\r\n\r\nA poco pi\u00f9 di un anno dal 7 ottobre, l'\u201cAsse della Resistenza\u201d sembra essere stato sconfitto - strategicamente, diplomaticamente e militarmente. Per i nemici di Teheran, la caduta di Assad \u00e8 un'occasione d'oro per spingere il decadente regime iraniano nell'abisso.\r\n\r\nUn punto della situazione e uno sguardo verso il futuro con Ali Vaez. ","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u201cCon la caduta di Assad, la strategia dell&#039;Iran sta crollando\u201d, una conversazione con Ali Vaez - Il Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/it\/2024\/12\/16\/con-la-caduta-di-assad-la-strategia-delliran-sta-crollando-una-conversazione-con-ali-vaez\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cCon la caduta di Assad, la strategia dell&#039;Iran sta crollando\u201d, una conversazione con Ali Vaez - Il Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Tra le vittime collaterali della guerra lampo di al-Jolani in Siria, l&#039;Iran \u00e8 senza dubbio la pi\u00f9 colpita.  A poco pi\u00f9 di un anno dal 7 ottobre, l&#039;\u201cAsse della Resistenza\u201d sembra essere stato sconfitto - strategicamente, diplomaticamente e militarmente. Per i nemici di Teheran, la caduta di Assad \u00e8 un&#039;occasione d&#039;oro per spingere il decadente regime iraniano nell&#039;abisso.  Un punto della situazione e uno sguardo verso il futuro con Ali Vaez.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/it\/2024\/12\/16\/con-la-caduta-di-assad-la-strategia-delliran-sta-crollando-una-conversazione-con-ali-vaez\/\" \/>\n<meta property=\"og:site_name\" content=\"Il Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-16T16:46:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-16T16:46:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/gc-ita-share-vaez-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hannacorsinimurat\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/gc-ita-share-vaez-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"hannacorsinimurat\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2024\/12\/16\/con-la-caduta-di-assad-la-strategia-delliran-sta-crollando-una-conversazione-con-ali-vaez\/\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/2024\/12\/16\/con-la-caduta-di-assad-la-strategia-delliran-sta-crollando-una-conversazione-con-ali-vaez\/\",\"name\":\"\u201cCon la caduta di Assad, la strategia dell'Iran sta crollando\u201d, una conversazione con Ali Vaez - Il Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2024\/12\/16\/con-la-caduta-di-assad-la-strategia-delliran-sta-crollando-una-conversazione-con-ali-vaez\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2024\/12\/16\/con-la-caduta-di-assad-la-strategia-delliran-sta-crollando-una-conversazione-con-ali-vaez\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/SIPA_shutterstock41238361_000021.jpg\",\"datePublished\":\"2024-12-16T16:46:07+00:00\",\"dateModified\":\"2024-12-16T16:46:10+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/8912e0c6b01d20345b444fb3007edadd\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2024\/12\/16\/con-la-caduta-di-assad-la-strategia-delliran-sta-crollando-una-conversazione-con-ali-vaez\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/it\/2024\/12\/16\/con-la-caduta-di-assad-la-strategia-delliran-sta-crollando-una-conversazione-con-ali-vaez\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2024\/12\/16\/con-la-caduta-di-assad-la-strategia-delliran-sta-crollando-una-conversazione-con-ali-vaez\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/SIPA_shutterstock41238361_000021.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/SIPA_shutterstock41238361_000021.jpg\",\"width\":1700,\"height\":2550,\"caption\":\"Discorso della Guida suprema iraniana, l'ayatollah Ali Khamenei, dopo la caduta di Bashar al-Assad. Teheran, 11 dicembre 2024. \u00a9 Zuma Press Wire\/Shutterstock\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2024\/12\/16\/con-la-caduta-di-assad-la-strategia-delliran-sta-crollando-una-conversazione-con-ali-vaez\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cCon la caduta di Assad, la strategia dell&#8217;Iran sta crollando\u201d, una conversazione con Ali Vaez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/\",\"name\":\"Il Grand Continent\",\"description\":\"La scala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/8912e0c6b01d20345b444fb3007edadd\",\"name\":\"hannacorsinimurat\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4bf5af82268bb796a39092920c9faec1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4bf5af82268bb796a39092920c9faec1?s=96&d=mm&r=g\",\"caption\":\"hannacorsinimurat\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cCon la caduta di Assad, la strategia dell'Iran sta crollando\u201d, una conversazione con Ali Vaez - Il Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/it\/2024\/12\/16\/con-la-caduta-di-assad-la-strategia-delliran-sta-crollando-una-conversazione-con-ali-vaez\/","og_locale":"it_IT","og_type":"article","og_title":"\u201cCon la caduta di Assad, la strategia dell'Iran sta crollando\u201d, una conversazione con Ali Vaez - Il Grand Continent","og_description":"Tra le vittime collaterali della guerra lampo di al-Jolani in Siria, l'Iran \u00e8 senza dubbio la pi\u00f9 colpita.  A poco pi\u00f9 di un anno dal 7 ottobre, l'\u201cAsse della Resistenza\u201d sembra essere stato sconfitto - strategicamente, diplomaticamente e militarmente. Per i nemici di Teheran, la caduta di Assad \u00e8 un'occasione d'oro per spingere il decadente regime iraniano nell'abisso.  Un punto della situazione e uno sguardo verso il futuro con Ali Vaez.","og_url":"https:\/\/legrandcontinent.eu\/it\/2024\/12\/16\/con-la-caduta-di-assad-la-strategia-delliran-sta-crollando-una-conversazione-con-ali-vaez\/","og_site_name":"Il Grand Continent","article_published_time":"2024-12-16T16:46:07+00:00","article_modified_time":"2024-12-16T16:46:10+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/gc-ita-share-vaez-scaled.jpg","type":"image\/jpeg"}],"author":"hannacorsinimurat","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/gc-ita-share-vaez-scaled.jpg","twitter_misc":{"Scritto da":"hannacorsinimurat","Tempo di lettura stimato":"15 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/it\/2024\/12\/16\/con-la-caduta-di-assad-la-strategia-delliran-sta-crollando-una-conversazione-con-ali-vaez\/","url":"https:\/\/legrandcontinent.eu\/it\/2024\/12\/16\/con-la-caduta-di-assad-la-strategia-delliran-sta-crollando-una-conversazione-con-ali-vaez\/","name":"\u201cCon la caduta di Assad, la strategia dell'Iran sta crollando\u201d, una conversazione con Ali Vaez - Il Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/it\/2024\/12\/16\/con-la-caduta-di-assad-la-strategia-delliran-sta-crollando-una-conversazione-con-ali-vaez\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/it\/2024\/12\/16\/con-la-caduta-di-assad-la-strategia-delliran-sta-crollando-una-conversazione-con-ali-vaez\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/SIPA_shutterstock41238361_000021.jpg","datePublished":"2024-12-16T16:46:07+00:00","dateModified":"2024-12-16T16:46:10+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/8912e0c6b01d20345b444fb3007edadd"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/it\/2024\/12\/16\/con-la-caduta-di-assad-la-strategia-delliran-sta-crollando-una-conversazione-con-ali-vaez\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/it\/2024\/12\/16\/con-la-caduta-di-assad-la-strategia-delliran-sta-crollando-una-conversazione-con-ali-vaez\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/legrandcontinent.eu\/it\/2024\/12\/16\/con-la-caduta-di-assad-la-strategia-delliran-sta-crollando-una-conversazione-con-ali-vaez\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/SIPA_shutterstock41238361_000021.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/SIPA_shutterstock41238361_000021.jpg","width":1700,"height":2550,"caption":"Discorso della Guida suprema iraniana, l'ayatollah Ali Khamenei, dopo la caduta di Bashar al-Assad. Teheran, 11 dicembre 2024. \u00a9 Zuma Press Wire\/Shutterstock"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/it\/2024\/12\/16\/con-la-caduta-di-assad-la-strategia-delliran-sta-crollando-una-conversazione-con-ali-vaez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/it\/"},{"@type":"ListItem","position":2,"name":"\u201cCon la caduta di Assad, la strategia dell&#8217;Iran sta crollando\u201d, una conversazione con Ali Vaez"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/it\/#website","url":"https:\/\/legrandcontinent.eu\/it\/","name":"Il Grand Continent","description":"La scala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/8912e0c6b01d20345b444fb3007edadd","name":"hannacorsinimurat","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4bf5af82268bb796a39092920c9faec1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4bf5af82268bb796a39092920c9faec1?s=96&d=mm&r=g","caption":"hannacorsinimurat"}}]}},"lgc_categories":[{"id":2299,"name":"HTS, al-Jolani: la Siria dopo Assad","slug":"hts-al-jolani-la-siria-dopo-assad"}],"lgc_author":{"id":2124,"name":"Pierre Ramond","slug":"pierre-ramond","description":null,"first_name":"Pierre","last_name":"Ramond","picture":null},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/SIPA_shutterstock41238361_000021.jpg","width":1700,"height":2550,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/SIPA_shutterstock41238361_000021.jpg","width":1700,"height":2550,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts\/28052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/users\/29021"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/comments?post=28052"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts\/28052\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/media\/28055"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/media?parent=28052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/categories?post=28052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/tags?post=28052"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/staff?post=28052"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/editorial_format?post=28052"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/serie?post=28052"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/audience?post=28052"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/geo?post=28052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}