{"id":27644,"date":"2024-12-09T17:06:49","date_gmt":"2024-12-09T16:06:49","guid":{"rendered":"https:\/\/legrandcontinent.eu\/it\/?p=27644"},"modified":"2024-12-09T17:06:52","modified_gmt":"2024-12-09T16:06:52","slug":"la-riapertura-di-notre-dame-la-teologia-politica-di-un-luogo-di-memoria","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/it\/2024\/12\/09\/la-riapertura-di-notre-dame-la-teologia-politica-di-un-luogo-di-memoria\/","title":{"rendered":"La riapertura di Notre-Dame: la teologia politica di un luogo di memoria"},"content":{"rendered":"\n<p class=\"has-drop-cap\">Sabato 7 dicembre si \u00e8 tenuta la cerimonia di riapertura della cattedrale di Notre-Dame de Paris. Quattro anni e mezzo dopo l&#8217;incendio del 16 aprile 2019, che ha divorato l&#8217;intera struttura del tetto, quasi rovesciato tutte le torri e causato i danni pi\u00f9 gravi della tumultuosa storia della cattedrale, il restauro di questo monumento emblematico \u00e8 stato completato secondo il calendario stabilito da Emmanuel Macron.\u00a0<\/p>\n\n\n\n<p>Da questo punto di vista, la sfida dell\u2019imponente cantiere di ricostruzione \u00e8 stata vinta, un successo raro in un periodo che ne ha visti pochi. Tuttavia, la riapertura della cattedrale solleva molte altre questioni, considerando lo status eccezionale di Notre-Dame come simbolo nazionale e internazionale, nonch\u00e9 come il monumento pi\u00f9 visitato di Parigi, con quasi 14 milioni di visitatori all&#8217;anno prima della chiusura.\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Un rito liturgico<\/strong><\/h2>\n\n\n\n<p>La riapertura della cattedrale \u00e8 soprattutto un rito liturgico, con il quale il vescovo prende o riprende possesso del suo seggio, la cattedra, nella chiesa madre della sua diocesi&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-27644' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2024\/12\/09\/la-riapertura-di-notre-dame-la-teologia-politica-di-un-luogo-di-memoria\/#easy-footnote-bottom-1-27644' title='Sulla storia delle cattedrali, leggere Matthieu Lours, &lt;em&gt;Les Cath\u00e9drales dans le monde. Entre religion, nation et pouvoir, &lt;\/em&gt;Parigi, Gallimard, 2024.'><sup>1<\/sup><\/a><\/span><\/span>. L&#8217;arcivescovo di Parigi, Mons. Ulrich, ha visto aprirsi le porte di Notre-Dame dopo averle percosse tre volte con il suo pastorale episcopale, mentre i chierici e i laici diocesani, gi\u00e0 ammassati all&#8217;interno, gli rispondevano in un dialogo rituale che riprende i versi del Salmo 23. Questo antico rito ricorda la processione annuale della Domenica delle Palme, che commemora l&#8217;ingresso del Cristo nella gloria a Gerusalemme, e riecheggia le varie cerimonie di insediamento o intronizzazione con cui un monarca prendeva possesso di un luogo.<\/p>\n\n\n\n<p>Il giorno seguente, la Messa domenicale \u00e8 stata celebrata da Laurent Ulrich, in concelebrazione con oltre 170 vescovi francesi e stranieri, nonch\u00e9 con 113 sacerdoti in rappresentanza di tutto il clero diocesano parigino (uno per parrocchia o comunit\u00e0 cattolica orientale). Quest&#8217;anno, la domenica 8 dicembre coincide con la festa dell&#8217;Immacolata Concezione&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-27644' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2024\/12\/09\/la-riapertura-di-notre-dame-la-teologia-politica-di-un-luogo-di-memoria\/#easy-footnote-bottom-2-27644' title='Proclamata solennemente come dogma della Chiesa cattolica da Papa Pio IX nel 1854, l&amp;#8217;Immacolata Concezione, secondo la quale la Vergine Maria \u00e8 stata preservata dal peccato originale fin dal momento del suo concepimento, viene ancora troppo spesso confusa con il dogma della verginit\u00e0 perpetua di Maria. Proprio per aver sostenuto la proclamazione dell&amp;#8217;Immacolata Concezione, l&amp;#8217;allora arcivescovo di Parigi, Mons. Sibour, fu pugnalato a morte durante la Messa a Saint-Etienne du Mont da un prete illuminato che gridava \u201cabbasso la dea\u201d'><sup>2<\/sup><\/a><\/span><\/span>, che avr\u00e0 la precedenza sulla seconda domenica dell\u2019Avvento. La solennit\u00e0 dovrebbe rappresentare il punto pi\u00f9 alto dell&#8217;episcopato di Mons. Ulrich, un prelato di grande esperienza &#8211; gi\u00e0 vescovo di Chamb\u00e9ry dal 2002 al 2008, poi arcivescovo di Lille fino al 2022 &#8211; molto rappresentativo delle correnti dominanti e moderate dell&#8217;episcopato francese: la sua presenza sulla cattedra parigina avr\u00e0 corrisposto a un momento di pacificazione &#8211; e persino di intorpidimento, direbbero alcuni &#8211; dopo quella di Mons. Aupetit, figura molto pi\u00f9 autoritaria e divisiva sia all&#8217;interno del clero parigino che all&#8217;esterno. Arcivescovo di Parigi all&#8217;epoca dell&#8217;incendio, Michel Aupetit \u00e8 stato poi costretto a dimettersi nel 2021 a seguito di una vicenda indecente non chiarita adeguatamente &#8211; ma archiviata dai tribunali. Da allora, si \u00e8 ritirato dalla Chiesa di Francia.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La riapertura di una cattedrale \u00e8 un rito liturgico con cui il vescovo prende o riprende possesso della sua sede, la cattedra, nella chiesa madre della sua diocesi.<\/p><cite>Jean-Beno\u00eet Poulle<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Una cerimonia liturgica che ha tuttavia evidenti risonanze politiche e persino diplomatiche. Per questo motivo, oltre al Presidente francese Emmanuel Macron, eranno presenti una cinquantina di personalit\u00e0 straniere, tra cui una trentina di capi di Stato e di governo. Tra le teste coronate presenti alla cerimonia vi erano monarchi di Regno Unito, Spagna, Belgio, Lussemburgo, Monaco, Marocco, Giordania e Qatar, oltre a membri secondari di altre famiglie reali. Vi erano anche presenti il Presidente tedesco Frank Walter Steinmeier, il Presidente italiano Sergio Mattarella, Volodymyr Zelensky per l&#8217;Ucraina, il Presidente brasiliano Lula, ecc. Per quanto riguarda gli Stati Uniti, il Presidente eletto Donald Trump ha assunto il suo primo impegno internazionale alla testa di <a href=\"https:\/\/legrandcontinent.eu\/it\/2024\/11\/08\/trump-e-laccelerazione-reazionaria-1\/\">una folta delegazione (incluso Elon Musk)<\/a> &#8211; il Presidente in carica \u00e8 stato rappresentato dalla First Lady Jill Biden. La presenza del Presidente eletto si spiega anche dall&#8217;entit\u00e0 delle donazioni fatte dagli americani per il restauro della cattedrale, a testimonianza di un fortissimo attaccamento culturale a un simbolo della vecchia Europa, che probabilmente non si ritrova nella stessa misura in nessun&#8217;altra cattedrale&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-27644' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2024\/12\/09\/la-riapertura-di-notre-dame-la-teologia-politica-di-un-luogo-di-memoria\/#easy-footnote-bottom-3-27644' title='A parte il caso della Basilica di San Pietro a Roma, simbolo del primato petrino, che non \u00e8 la cattedrale della diocesi di Roma, essendo questo ruolo assegnato alla Basilica di San Giovanni in Laterano.'><sup>3<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n\n<div class=\"double-picture my-12 lg:my-20\" \n    data-images-sizes=\"half\"\n    data-same-height=\"true\"\n    data-reference-image=\"left\"\n>    <!-- Images -->\n    <div class=\"lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-1\/2\">\n                            <a \n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/SIPA_01187142_000002.jpg\" \n                    class=\"gallery-item no-underline  \" \n                    data-pswp-width=\"1280\" \n                    data-pswp-height=\"1920\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/SIPA_01187142_000002.jpg\" alt=\"Vista interna della Cattedrale di Notre-Dame prima della sua riapertura a Parigi, Francia, il 30 novembre 2024 \u00a9 Julio Piatti\" >\n                        <\/picture>\n                        <figcaption class=\"lg:hidden pswp-caption-content\">Vista interna della Cattedrale di Notre-Dame prima della sua riapertura a Parigi, Francia, il 30 novembre 2024 \u00a9 Julio Piatti<\/figcaption>                    <\/figure>\n                <\/a>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-1\/2\">\n                            <a\n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/SIPA_01187142_000012.jpg\" \n                    class=\"gallery-item no-underline  lg:!absolute lg:h-full lg:right-0 lg:left-2 overflow-hidden\" \n                    data-pswp-width=\"1920\" \n                    data-pswp-height=\"1280\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/SIPA_01187142_000012.jpg\" alt=\"Vista interna della Cattedrale di Notre-Dame prima della sua riapertura a Parigi, Francia, il 30 novembre 2024 \u00a9 Julio Piatti\" class=\"lg:!h-full object-cover\">\n                        <\/picture>\n                        <figcaption class=\"lg:hidden pswp-caption-content\">Vista interna della Cattedrale di Notre-Dame prima della sua riapertura a Parigi, Francia, il 30 novembre 2024 \u00a9 Julio Piatti<\/figcaption>                    <\/figure>\n                <\/a>\n                    <\/div>\n    <\/div>\n    <!-- Captions -->\n    <div class=\"hidden lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-1\/2\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">\n                    <figcaption>Vista interna della Cattedrale di Notre-Dame prima della sua riapertura a Parigi, Francia, il 30 novembre 2024 \u00a9 Julio Piatti<\/figcaption>                <\/figure>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-1\/2\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">   \n                    <figcaption>Vista interna della Cattedrale di Notre-Dame prima della sua riapertura a Parigi, Francia, il 30 novembre 2024 \u00a9 Julio Piatti<\/figcaption>                <\/figure>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<p>Invece, la presenza del governo dimissionario ha ricordato che, mentre Emmanuel Macron sperava di trasformare questo momento in un momento di unit\u00e0 nazionale, la realt\u00e0 pi\u00f9 prosaica \u00e8 quella di una crisi di governo di dimensioni senza precedenti, iniziata lo scorso giugno con la decisione di sciogliere l&#8217;Assemblea Nazionale. Con la pronuncia del suo discorso, il presidente Macron si \u00e8 inscritto nella lunga tradizione che ha fatto di Notre-Dame un santuario nazionale, emblematico dei legami tra lo spirituale e il temporale: sotto la monarchia francese, Notre-Dame \u00e8 stata teatro di celebrazioni di <em>Te Deum<\/em> della vittoria, con le sue volte coperte dagli stendardi strappati al nemico; \u00e8 stata sede di alcuni matrimoni&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-27644' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2024\/12\/09\/la-riapertura-di-notre-dame-la-teologia-politica-di-un-luogo-di-memoria\/#easy-footnote-bottom-4-27644' title='Ad esempio, il matrimonio tra Enrico di Navarra, il futuro Enrico IV, e Margherita di Valois, sorella di Carlo IX, il 18 agosto 1572: a causa delle diverse fedi degli sposi, il matrimonio fu celebrato nella piazza davanti alla chiesa. Notre-Dame \u00e8 quindi legata alla storia della tolleranza interreligiosa.'><sup>4<\/sup><\/a><\/span><\/span> e battesimi &nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-27644' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2024\/12\/09\/la-riapertura-di-notre-dame-la-teologia-politica-di-un-luogo-di-memoria\/#easy-footnote-bottom-5-27644' title='Ci viene in mente il battesimo del Principe Imperiale, figlio di Napoleone III, il 16 giugno 1856.'><sup>5<\/sup><\/a><\/span><\/span> reali e imperiali, ed \u00e8 stata trasformata in un tempio della Ragione durante la fase di scristianizzazione della Rivoluzione francese. Nel 1804, Notre-Dame, ridecorata nello stile dell&#8217;Antichit\u00e0, ha ospitato l&#8217;incoronazione dell&#8217;imperatore Napoleone I, questa volta alla presenza di un papa, Pio VII. Fin dai funerali del presidente assassinato Sadi Carnot nel 1894, sotto la Terza Repubblica, ha ospitato i funerali religiosi dei presidenti della Repubblica francese, o almeno le funzioni solenni in loro memoria quando desideravano essere sepolti in privato, come nel caso di Charles de Gaulle e Fran\u00e7ois Mitterrand. \u00c8 a Notre-Dame che il generale de Gaulle si rec\u00f2 per ascoltare un Te Deum in onore della liberazione di Parigi il 26 agosto 1944. Forse nessun altro luogo \u00e8 cos\u00ec strettamente associato nella memoria collettiva agli eventi della storia francese.<\/p>\n\n\n\n<p>Restaurata grazie a un progetto straordinario che \u00e8 anche una vetrina per le savoir-faire francese, la nuova Notre-Dame \u00e8 ora molto pi\u00f9 conosciuta. Il restauro della pavimentazione \u00e8 stato preceduto da un&#8217;importante campagna di scavi archeologici, che ha portato alla luce alcuni veri e propri reperti, tra cui i frammenti del paravento policromo del XIII secolo, distrutto e sepolto nel XVIII secolo quando questo imponente recinto tra la navata e il coro pass\u00f2 di moda. Radiografati da ogni angolazione, questi resti sono una bella testimonianza del virtuosismo della scultura parigina nel secolo di San Luigi. Sono state riportate alla luce anche le tombe dei canonici del capitolo della cattedrale, che avevano il privilegio di essere sepolti l\u00ec: tra queste c&#8217;\u00e8 probabilmente quella del poeta Joachim du Bellay (1522-1560). I risultati di questi scavi dell&#8217;INRAP (<em>Institut national de recherches arch\u00e9ologiques pr\u00e9ventives<\/em>) sono tanto pi\u00f9 degni di nota in quanto sono stati effettuati in tutta fretta, a causa dei vincoli imposti dal programma di riapertura. Tuttavia, alcuni conservatori del patrimonio hanno criticato la chiusura anticipata del sito archeologico, sostenendo che l&#8217;entit\u00e0 delle scoperte imponeva la prosecuzione dei lavori&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-27644' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2024\/12\/09\/la-riapertura-di-notre-dame-la-teologia-politica-di-un-luogo-di-memoria\/#easy-footnote-bottom-6-27644' title='&lt;a href=&quot;https:\/\/www.latribunedelart.com\/notre-dame-des-fouilles-archeologiques-sacrifiees-pour-tenir-les-delais&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/www.latribunedelart.com\/notre-dame-des-fouilles-archeologiques-sacrifiees-pour-tenir-les-delais&lt;\/a&gt;'><sup>6<\/sup><\/a><\/span><\/span>. A questa prima controversia se n&#8217;\u00e8 aggiunta un&#8217;altra, di ben pi\u00f9 alto profilo, riguardante la creazione di vetrate contemporanee per sostituire quelle realizzate durante il restauro di Viollet-le-Duc nel XIX secolo, che erano scoppiate sotto l&#8217;effetto del calore. \u00c8 vero che &#8211; e qui sta il punto chiave &#8211; le vetrate medievali, in particolare i magnifici rosoni, si sono conservate durante l&#8217;incendio. Tuttavia, se inizialmente i restauri di Viollet-le-Duc sono stati giudicati duramente dal pubblico del tempo, oggi vengono riabilitati come opere d&#8217;arte, n\u00e9 pi\u00f9 n\u00e9 meno che testimonianze di epoche precedenti. Soprattutto, la Carta Internazionale di Venezia (1964), oggi vincolante per i restauratori, li obbliga a ripristinare \u201cl&#8217;ultimo stato conosciuto\u201d&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-7-27644' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2024\/12\/09\/la-riapertura-di-notre-dame-la-teologia-politica-di-un-luogo-di-memoria\/#easy-footnote-bottom-7-27644' title='Si tratta di una differenza sostanziale rispetto ai restauri effettuati da Viollet-le-Duc, che hanno cercato di riscoprire il significato del progetto originale e di ricostruire il monumento in uno stato ottimale, che in alcuni casi non era mai esistito.'><sup>7<\/sup><\/a><\/span><\/span>, e quindi vieta qualsiasi modifica sostanziale del monumento, come il \u201cgesto contemporaneo\u201d che il Presidente Macron auspicava per la nuova guglia &#8211; infine respinta. Questa nuova \u201cdisputa tra Antichi e Moderni\u201d potrebbe aver influito anche sulla sistemazione degli arredi liturgici di Notre-Dame, che sono di esclusiva competenza del suo locatario perpetuo &#8211; la Diocesi di Parigi &#8211; anche se va notato che quest&#8217;ultima ha optato per una relativa sobriet\u00e0, anche se certo al limite del buon gusto&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-8-27644' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2024\/12\/09\/la-riapertura-di-notre-dame-la-teologia-politica-di-un-luogo-di-memoria\/#easy-footnote-bottom-8-27644' title='Il coro di Notre-Dame era gi\u00e0 stato ristrutturato su impulso del cardinale Lustiger, in seguito alla riforma liturgica del 1969 seguita al Concilio Vaticano II. Fu questo nuovo altare, e non l&amp;#8217;altare maggiore barocco in fondo al coro, a essere completamente distrutto dal crollo della struttura del tetto.'><sup>8<\/sup><\/a><\/span><\/span>. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>L&#8217;assenza del Papa: una ferita narcisistica per la Francia?<\/strong><\/h2>\n\n\n\n<p>Sembra che il Presidente Macron nutrisse da tempo la speranza di vedere Papa Francesco presiedere questa cerimonia e la messa del giorno successivo: l&#8217;invito, prima accennato dietro le quinte, gli \u00e8 stato poi ufficialmente esteso. Ma la visita in Francia non \u00e8 una priorit\u00e0 nell&#8217;agenda papale, come ha detto pi\u00f9 volte lo stesso Francesco.\u00a0<\/p>\n\n\n\n<p>\u00c8 vero che il Papa ha gi\u00e0 visitato Strasburgo (2014) e Marsiglia (2023), dove era stato accolto da Emmanuel Macron. Eppure, sembra che veda queste citt\u00e0 soprattutto come parte dell&#8217;Europa: nel caso della prima &#8211; dove \u00e8 venuto a parlare al Parlamento europeo &#8211; e nel caso della seconda, sulle sponde del Mediterraneo &#8211; dove \u00e8 venuto a presiedere eventi culturali a lui dedicati. Terra di antica cristianit\u00e0, la Francia, come la Germania, non \u00e8 una delle \u201cperiferie\u201d geografiche, sociali o esistenziali che stanno a cuore a Papa Francesco. Sembra anche che il Papa non voglia oscurare con la sua sola presenza una celebrazione incentrata su un monumento nazionale &#8211; almeno questa \u00e8 la spiegazione diplomaticamente avanzata dal presidente della Conferenza episcopale francese, l&#8217;arcivescovo di Reims \u00c9ric de Moulins-Beaufort. Per una frangia di cattolici francesi, e senza dubbio anche per alcuni esponenti del clero, oltre che per il governo, l&#8217;assenza del Papa dalla riapertura della cattedrale \u00e8 stata tanto pi\u00f9 sentita in quanto la settimana successiva si sarebbe recato ad Ajaccio in Corsica, questa volta per partecipare a un colloquio sulla piet\u00e0 popolare&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-9-27644' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2024\/12\/09\/la-riapertura-di-notre-dame-la-teologia-politica-di-un-luogo-di-memoria\/#easy-footnote-bottom-9-27644' title='Considerata con condiscendenza dalla generazione dei riformatori che chiedevano uno stile di vita \u201cadulto\u201d, la \u201creligione popolare\u201d \u00e8 stata anche oggetto di un intenso dibattito intellettuale e storiografico negli anni Settanta. Papa Francesco la sta prendendo in considerazione, tuttavia, nella prospettiva della sua \u201cteologia del popolo\u201d: ha un certo attaccamento alla piet\u00e0 mariana.'><sup>9<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n\n<div class=\"double-picture my-12 lg:my-20\" \n    data-images-sizes=\"half\"\n    data-same-height=\"true\"\n    data-reference-image=\"left\"\n>    <!-- Images -->\n    <div class=\"lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-1\/2\">\n                            <a \n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/SIPA_01187142_000003.jpg\" \n                    class=\"gallery-item no-underline  \" \n                    data-pswp-width=\"1920\" \n                    data-pswp-height=\"1280\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/SIPA_01187142_000003.jpg\" alt=\"Vista interna della Cattedrale di Notre-Dame prima della sua riapertura a Parigi, Francia, il 30 novembre 2024 \u00a9 Julio Piatti\" >\n                        <\/picture>\n                        <figcaption class=\"lg:hidden pswp-caption-content\">Vista interna della Cattedrale di Notre-Dame prima della sua riapertura a Parigi, Francia, il 30 novembre 2024 \u00a9 Julio Piatti<\/figcaption>                    <\/figure>\n                <\/a>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-1\/2\">\n                            <a\n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/SIPA_01187142_000010.jpg\" \n                    class=\"gallery-item no-underline  lg:!absolute lg:h-full lg:right-0 lg:left-2 overflow-hidden\" \n                    data-pswp-width=\"1280\" \n                    data-pswp-height=\"1920\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/SIPA_01187142_000010.jpg\" alt=\"Vista interna della Cattedrale di Notre-Dame prima della sua riapertura a Parigi, Francia, il 30 novembre 2024 \u00a9 Julio Piatti\" class=\"lg:!h-full object-cover\">\n                        <\/picture>\n                        <figcaption class=\"lg:hidden pswp-caption-content\">Vista interna della Cattedrale di Notre-Dame prima della sua riapertura a Parigi, Francia, il 30 novembre 2024 \u00a9 Julio Piatti<\/figcaption>                    <\/figure>\n                <\/a>\n                    <\/div>\n    <\/div>\n    <!-- Captions -->\n    <div class=\"hidden lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-1\/2\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">\n                    <figcaption>Vista interna della Cattedrale di Notre-Dame prima della sua riapertura a Parigi, Francia, il 30 novembre 2024 \u00a9 Julio Piatti<\/figcaption>                <\/figure>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-1\/2\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">   \n                    <figcaption>Vista interna della Cattedrale di Notre-Dame prima della sua riapertura a Parigi, Francia, il 30 novembre 2024 \u00a9 Julio Piatti<\/figcaption>                <\/figure>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<p>A prima vista, il Papa sembra coerente nel dare la priorit\u00e0 a un&#8217;isola &#8211; essa stessa una periferia geografica e sociale &#8211; piuttosto che alla cattedrale di una metropoli di livello mondiale. Ma alcuni segnali potrebbero aver rafforzato il sentimento di irritazione: il protocollo papale per questo breve viaggio sar\u00e0 lo stesso adottato da Francesco nei suoi viaggi in Italia, come se una parte dell&#8217;amministrazione della Santa Sede non avesse mai pienamente integrato l&#8217;appartenenza della Corsica alla Francia\u2026 \u00c8 vero che \u00e8 la prima volta che un papa visita la Corsica, anche se l&#8217;isola ha avuto per secoli stretti legami con la Santa Sede, come dimostra il fatto che le sue 6 diocesi storiche&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-10-27644' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2024\/12\/09\/la-riapertura-di-notre-dame-la-teologia-politica-di-un-luogo-di-memoria\/#easy-footnote-bottom-10-27644' title='Le diocesi di Ajaccio, Al\u00e9ria, Mariana e Accia (fuse nel 1563), Nebbiu e Sagone, corrispondenti agli antichi\u00a0&lt;em&gt;pagi\u00a0&lt;\/em&gt;dell&amp;#8217;isola; abolite durante la Rivoluzione francese, furono sostituite da un&amp;#8217;unica diocesi di Ajaccio.'><sup>10<\/sup><\/a><\/span><\/span>erano immediatamente assoggettate alla Santa Sede. In termini temporali, il papa, monarca dello Stato Pontificio, \u00e8 stato anche il suzerain della Corsica durante l&#8217;Alto Medioevo, prima ancora delle dominazioni pisana, genovese e poi francese. Infine, dal XV al XVII secolo, i papi poterono contare su una guardia corsa per garantire la loro sicurezza, accanto alla successiva guardia svizzera&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-11-27644' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2024\/12\/09\/la-riapertura-di-notre-dame-la-teologia-politica-di-un-luogo-di-memoria\/#easy-footnote-bottom-11-27644' title='Anna Esposito, &amp;#8220;La presenza dei Corsi nella Roma del Quattrocento. Prime indagini nei protocolli notarili&amp;#8221;, &lt;em&gt;M\u00e9langes de l\u2019\u00c9cole fran\u00e7aise de Rome\u00a0: Moyen\u00a0\u00c2ge, &lt;\/em&gt;Roma, vol. 98, N\u00b0 98-2, 1986, p.\u00a0607-621.'><sup>11<\/sup><\/a><\/span><\/span>. La Guardia Corsa fu sciolta nel 1664 su pressione di Luigi XIV, a seguito di un incidente diplomatico &#8211; una rissa mortale era scoppiata tra le guardie corse e i valletti dell&#8217;ambasciata francese a Roma &#8211; e il Re Sole chiese addirittura che fosse eretta una piramide espiatoria che dichiarasse la nazione corsa \u201cinadatta e incapace di servire la Sede Apostolica\u201d. Il risultato di tutto ci\u00f2 \u00e8 stato un sentimento diffuso di un rapporto speciale tra il Papa e i Corsi, che la visita di Papa Francesco avrebbe riacceso.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Bisogna farci l&#8217;abitudine: la Francia conta molto poco per Papa Francesco, come riflesso dal suo basso profilo nella diplomazia vaticana e, soprattutto, dal suo alto grado di secolarizzazione, che ha portato a una crisi di reclutamento tra il suo clero.<\/p><cite>Jean-Beno\u00eet Poulle<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Soprattutto, sembra che il nuovo vescovo di Ajaccio, il cardinale Fran\u00e7ois Bustillo, goda di grande credibilit\u00e0 presso il Papa. Nato in Navarra, naturalizzato francese, ma ancora conteggiato come spagnolo nel Collegio cardinalizio, questo francescano conventuale sembra aver fatto una grande impressione nella Curia per la sua vicinanza al gregge, la sua semplicit\u00e0 e anche le sue capacit\u00e0 relazionali. Nella Curia, pu\u00f2 contare sull&#8217;appoggio del cardinale Dominique Mamberti, c\u00f2rso di nascita, prefetto della Segnatura Apostolica, la \u201ccorte di cassazione\u201d della Santa Sede. Fran\u00e7ois Bustillo \u00e8 stato nominato cardinale in una sede che non ne ha mai visto uno, mentre n\u00e9 Parigi, n\u00e9 Lione, n\u00e9 Bordeaux hanno ricevuto il cappello cardinalizio dall&#8217;elezione di Papa Francesco. L\u2019unico che l\u2019ha potuto portare (dal 2022) \u00e8 stato l&#8217;arcivescovo di Marsiglia Jean-Marc Aveline &#8211; eppure, questo gesto \u00e8 da interpretarsi non tanto come premiazione della sua cattedra, quanto del suo profilo molto \u201cbergogliano\u201d. Bisogna farci l&#8217;abitudine: la Francia conta molto poco per Papa Francesco, come riflesso dal suo basso profilo nella diplomazia vaticana e, soprattutto, dal suo alto grado di secolarizzazione, che ha portato a una crisi di reclutamento tra il suo clero. L&#8217;assenza di Francesco da Parigi per la riapertura della cattedrale sembra ancora di pi\u00f9 un&#8217;occasione mancata se si considera che \u00e8 probabile che la prima pietra della cattedrale sia stata posata nel 1163, da un papa, Alessandro III (papa dal 1159 al 1181), che all&#8217;epoca era in visita in Francia; vale la pena di notare che le difficolt\u00e0 odierne per organizzare un viaggio in Francia non sono certe le stesse che nel Medioevo\u2026 Momento di armonia, culmine di un progetto colossale che ha visto i francesi di ogni fede appassionarsi al destino di questo \u201cluogo della memoria\u201d e contribuire molto generosamente al suo restauro, la cerimonia di riapertura di Notre-Dame riflette comunque una forma di delusione per il loro Presidente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo cinque anni di chiusura, un monumento francese ha riaperto  le sue porte questo sabato 7 dicembre. <\/p>\n<p>In piena crisi, con la Repubblica senza primo ministro e il Papa in visita in Corsica tra una settimana, qual \u00e8 il significato politico di un gesto che \u00e8 prima di tutto un rito liturgico?<\/p>\n<p>Sulle nostre pagine, Jean-Beno\u00eet Poulle analizza un momento storico.<\/p>\n","protected":false},"author":29021,"featured_media":27650,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-studies.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":13,"footnotes":""},"categories":[2108],"tags":[],"staff":[2048],"editorial_format":[2349],"serie":[],"audience":[],"geo":[2086],"class_list":["post-27644","post","type-post","status-publish","format-standard","hentry","category-religione","staff-jean-benoit-poulle","editorial_format-studi","geo-europa"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":27650,"excerpt":"Dopo cinque anni di chiusura, un monumento francese ha riaperto  le sue porte questo sabato 7 dicembre. \r\n\r\nIn piena crisi, con la Repubblica senza primo ministro e il Papa in visita in Corsica tra una settimana, qual \u00e8 il significato politico di un gesto che \u00e8 prima di tutto un rito liturgico?\r\n\r\nSulle nostre pagine, Jean-Beno\u00eet Poulle analizza un momento storico.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La riapertura di Notre-Dame: la teologia politica di un luogo di memoria - Il Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/it\/2024\/12\/09\/la-riapertura-di-notre-dame-la-teologia-politica-di-un-luogo-di-memoria\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La riapertura di Notre-Dame: la teologia politica di un luogo di memoria - Il Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Dopo cinque anni di chiusura, un monumento francese ha riaperto le sue porte questo sabato 7 dicembre.   In piena crisi, con la Repubblica senza primo ministro e il Papa in visita in Corsica tra una settimana, qual \u00e8 il significato politico di un gesto che \u00e8 prima di tutto un rito liturgico?  Sulle nostre pagine, Jean-Beno\u00eet Poulle analizza un momento storico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/it\/2024\/12\/09\/la-riapertura-di-notre-dame-la-teologia-politica-di-un-luogo-di-memoria\/\" \/>\n<meta property=\"og:site_name\" content=\"Il Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-09T16:06:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-09T16:06:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/gc-ita-share-ND-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1437\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hannacorsinimurat\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/gc-ita-share-ND-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"hannacorsinimurat\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2024\/12\/09\/la-riapertura-di-notre-dame-la-teologia-politica-di-un-luogo-di-memoria\/\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/2024\/12\/09\/la-riapertura-di-notre-dame-la-teologia-politica-di-un-luogo-di-memoria\/\",\"name\":\"La riapertura di Notre-Dame: la teologia politica di un luogo di memoria - Il Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2024\/12\/09\/la-riapertura-di-notre-dame-la-teologia-politica-di-un-luogo-di-memoria\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2024\/12\/09\/la-riapertura-di-notre-dame-la-teologia-politica-di-un-luogo-di-memoria\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/SIPA_ap22922849_000013-scaled-1.jpg\",\"datePublished\":\"2024-12-09T16:06:49+00:00\",\"dateModified\":\"2024-12-09T16:06:52+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/8912e0c6b01d20345b444fb3007edadd\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2024\/12\/09\/la-riapertura-di-notre-dame-la-teologia-politica-di-un-luogo-di-memoria\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/it\/2024\/12\/09\/la-riapertura-di-notre-dame-la-teologia-politica-di-un-luogo-di-memoria\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2024\/12\/09\/la-riapertura-di-notre-dame-la-teologia-politica-di-un-luogo-di-memoria\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/SIPA_ap22922849_000013-scaled-1.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/SIPA_ap22922849_000013-scaled-1.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Il battistero progettato dall'artista e designer francese Guillaume Bardet \u00e8 fotografato mentre il presidente francese Emmanuel Macron visita gli interni restaurati della Cattedrale di Notre-Dame a Parigi, venerd\u00ec 29 novembre 2024. \u00a9 Christophe Petit Tesson\/AP\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2024\/12\/09\/la-riapertura-di-notre-dame-la-teologia-politica-di-un-luogo-di-memoria\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La riapertura di Notre-Dame: la teologia politica di un luogo di memoria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/\",\"name\":\"Il Grand Continent\",\"description\":\"La scala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/8912e0c6b01d20345b444fb3007edadd\",\"name\":\"hannacorsinimurat\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4bf5af82268bb796a39092920c9faec1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4bf5af82268bb796a39092920c9faec1?s=96&d=mm&r=g\",\"caption\":\"hannacorsinimurat\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La riapertura di Notre-Dame: la teologia politica di un luogo di memoria - Il Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/it\/2024\/12\/09\/la-riapertura-di-notre-dame-la-teologia-politica-di-un-luogo-di-memoria\/","og_locale":"it_IT","og_type":"article","og_title":"La riapertura di Notre-Dame: la teologia politica di un luogo di memoria - Il Grand Continent","og_description":"Dopo cinque anni di chiusura, un monumento francese ha riaperto le sue porte questo sabato 7 dicembre.   In piena crisi, con la Repubblica senza primo ministro e il Papa in visita in Corsica tra una settimana, qual \u00e8 il significato politico di un gesto che \u00e8 prima di tutto un rito liturgico?  Sulle nostre pagine, Jean-Beno\u00eet Poulle analizza un momento storico.","og_url":"https:\/\/legrandcontinent.eu\/it\/2024\/12\/09\/la-riapertura-di-notre-dame-la-teologia-politica-di-un-luogo-di-memoria\/","og_site_name":"Il Grand Continent","article_published_time":"2024-12-09T16:06:49+00:00","article_modified_time":"2024-12-09T16:06:52+00:00","og_image":[{"width":2560,"height":1437,"url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/gc-ita-share-ND-scaled.jpg","type":"image\/jpeg"}],"author":"hannacorsinimurat","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/gc-ita-share-ND-scaled.jpg","twitter_misc":{"Scritto da":"hannacorsinimurat","Tempo di lettura stimato":"13 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/it\/2024\/12\/09\/la-riapertura-di-notre-dame-la-teologia-politica-di-un-luogo-di-memoria\/","url":"https:\/\/legrandcontinent.eu\/it\/2024\/12\/09\/la-riapertura-di-notre-dame-la-teologia-politica-di-un-luogo-di-memoria\/","name":"La riapertura di Notre-Dame: la teologia politica di un luogo di memoria - Il Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/it\/2024\/12\/09\/la-riapertura-di-notre-dame-la-teologia-politica-di-un-luogo-di-memoria\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/it\/2024\/12\/09\/la-riapertura-di-notre-dame-la-teologia-politica-di-un-luogo-di-memoria\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/SIPA_ap22922849_000013-scaled-1.jpg","datePublished":"2024-12-09T16:06:49+00:00","dateModified":"2024-12-09T16:06:52+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/8912e0c6b01d20345b444fb3007edadd"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/it\/2024\/12\/09\/la-riapertura-di-notre-dame-la-teologia-politica-di-un-luogo-di-memoria\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/it\/2024\/12\/09\/la-riapertura-di-notre-dame-la-teologia-politica-di-un-luogo-di-memoria\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/legrandcontinent.eu\/it\/2024\/12\/09\/la-riapertura-di-notre-dame-la-teologia-politica-di-un-luogo-di-memoria\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/SIPA_ap22922849_000013-scaled-1.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/SIPA_ap22922849_000013-scaled-1.jpg","width":2560,"height":1707,"caption":"Il battistero progettato dall'artista e designer francese Guillaume Bardet \u00e8 fotografato mentre il presidente francese Emmanuel Macron visita gli interni restaurati della Cattedrale di Notre-Dame a Parigi, venerd\u00ec 29 novembre 2024. \u00a9 Christophe Petit Tesson\/AP"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/it\/2024\/12\/09\/la-riapertura-di-notre-dame-la-teologia-politica-di-un-luogo-di-memoria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/it\/"},{"@type":"ListItem","position":2,"name":"La riapertura di Notre-Dame: la teologia politica di un luogo di memoria"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/it\/#website","url":"https:\/\/legrandcontinent.eu\/it\/","name":"Il Grand Continent","description":"La scala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/8912e0c6b01d20345b444fb3007edadd","name":"hannacorsinimurat","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4bf5af82268bb796a39092920c9faec1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4bf5af82268bb796a39092920c9faec1?s=96&d=mm&r=g","caption":"hannacorsinimurat"}}]}},"lgc_categories":[{"id":2108,"name":"Religione","slug":"religione"}],"lgc_author":{"id":2048,"name":"Jean-Beno\u00eet Poulle","slug":"jean-benoit-poulle","description":null,"first_name":null,"last_name":null,"picture":null},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/SIPA_ap22922849_000013-scaled-1.jpg","width":2560,"height":1707,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/12\/SIPA_ap22922849_000013-scaled-1.jpg","width":2560,"height":1707,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts\/27644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/users\/29021"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/comments?post=27644"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts\/27644\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/media\/27650"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/media?parent=27644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/categories?post=27644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/tags?post=27644"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/staff?post=27644"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/editorial_format?post=27644"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/serie?post=27644"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/audience?post=27644"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/geo?post=27644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}