{"id":26363,"date":"2024-11-09T06:00:00","date_gmt":"2024-11-09T05:00:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/it\/?p=26363"},"modified":"2024-11-08T21:22:56","modified_gmt":"2024-11-08T20:22:56","slug":"il-manifesto-del-movimento-trumpista","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/it\/2024\/11\/09\/il-manifesto-del-movimento-trumpista\/","title":{"rendered":"Il vero manifesto del movimento trumpista\u00a0"},"content":{"rendered":"\n<p class=\"intro\">Poco pi\u00f9 di un anno fa, l&#8217;8 agosto 2023, Oliver Anthony pubblicava sul suo canale YouTube il video di una canzone originale intitolata <em>Rich Men North of Richmond<\/em>. In piedi in un bosco, circondato dai suoi cani, l&#8217;ex precario, che pochi mesi prima si era trasferito con la famiglia in un terreno di 36 ettari per allevare bestiame, era il portavoce di un&#8217;America disagiata, condannata a lavorare molte ore per un salario appena sufficiente a sopravvivere. All&#8217;epoca, l&#8217;inflazione era al livello pi\u00f9 basso degli ultimi due anni e mezzo, ma milioni di americani stavano ancora subendo gli effetti di un forte aumento dei prezzi nel 2021 e nel 2022.<\/p>\n\n\n\n<p class=\"intro\"><em>Rich Men North of Richmond <\/em>ebbe un successo immediato. La musica, che fu suonata centinaia di milioni di volte, spingendo Oliver al primo posto della Billboard Hot 100, ebbe una risonanza particolarmente forte con la classe operaia americana. I temi dei testi, il profilo di Oliver Anthony, fino ad allora completamente sconosciuto, il clima economico e le crescenti difficolt\u00e0 di decine di milioni di americani a sbarcare il lunario hanno fatto di questa musica l&#8217;inno di un intero movimento. Ora che Donald Trump \u00e8 stato appena eletto presidente per un secondo mandato, <em>Rich Men North of Richmond<\/em> \u00e8 stata riproposta in streaming e sta tornando in auge tra gli elettori repubblicani.<\/p>\n\n\n\n<p class=\"intro\">Dimenticata dalla maggior parte degli elettori durante una campagna elettorale scossa dall&#8217;attentato contro Trump e dal ritiro tardivo di Biden, <em>Rich Men North of Richmond <\/em>\u00e8 riemerso in ottobre durante il <em>town hall <\/em>(queste famose assemblee cittadine molto popolari negli USA) dell&#8217;allora candidato repubblicano a Oaks, in Pennsylvania. Due persone erano appena svenute tra il pubblico a causa del caldo, e Trump era rimasto sul palco dopo aver suggerito di sostituire la tradizionale sessione di domande e risposte con una delle sue attivit\u00e0 preferite: ascoltare della musica. Per 39 minuti, Trump ha ondeggiato in silenzio sulle sue canzoni preferite. Contemporaneamente, i paramedici sono intervenuti nella sala per evacuare le due persone svenute.<\/p>\n\n\n\n<p class=\"intro\"><em>Rich Men North of Richmond <\/em>ha occupato un posto di rilievo nella playlist del repubblicano, tra <em>An American Trilogy<\/em> di Elvis Presley e <em>November Rain<\/em> dei Gun N&#8217; Roses, con la quale Trump ha deciso di lasciare il palco. La musica di Oliver Anthony era anche l&#8217;unico brano contemporaneo, l&#8217;unica canzone il cui testo era abbinato ad un significato eminentemente politico a soli 22 giorni dalle elezioni. Dopo la sua vittoria alle urne, \u00e8 molto probabile che <em>Rich Men North of Richmond <\/em>venga aggiunta da Trump alla playlist che riserva ai suoi ospiti nei ricevimenti a Mar-a-Lago, in Florida, o nel suo golf club a Bedminster, nel New Jersey.<\/p>\n\n\n\n<p class=\"intro\">Sebbene le parole di Anthony non si applichino a Trump &#8211; che all&#8217;inizio della sua carriera ha ricevuto dal padre l&#8217;equivalente di circa 400 milioni di dollari &#8211; sono diventate l&#8217;inno di gran parte del suo elettorato. Per lo pi\u00f9 bianchi &#8211; anche se Trump ha migliorato significativamente il suo punteggio tra gli elettori ispanici e afroamericani &#8211; che vivono in aree rurali, deindustrializzate e lontane dai centri economici che sono i veri polmoni dell&#8217;America, gli elettori di Trump hanno votato per il candidato repubblicano non perch\u00e9 pu\u00f2 affermare di essere \u201cuno di loro\u201d, ma perch\u00e9 sono stati sedotti dalla sua retorica di rottura. L&#8217;America di Oliver \u00e8 anche l&#8217;America di Vance, il primo della generazione dei<em> millennials<\/em> ad essere eletto vicepresidente. In <em>Hillbilly Elegy<\/em>, Vance ha dipinto il ritratto di una societ\u00e0 dimenticata, trascurata dalle \u00e9lite di Washington, sia democratiche che repubblicane. Inizialmente contrario a Trump, Vance, di estrazione operaia, si \u00e8 poi arreso di fronte al candidato repubblicano, riconoscendo la sua capacit\u00e0 quasi mistica di parlare ad un&#8217;America che ha scoperto per la prima volta nel 2015, a quasi 70 anni.<\/p>\n\n\n\n<p class=\"intro\">Di fronte ad un \u201csalario che non vale niente\u201d denunciato da Anthony, Trump promette un ritorno alla prosperit\u00e0 economica degli anni Cinquanta e Sessanta. Di fronte a una classe che \u201cvuole controllarci tutti\u201d, ha annunciato l&#8217;intenzione di smantellare lo Stato federale e di \u201cprosciugare la palude\u201d di Washington e delle sue \u00e9lite corrotte. In opposizione alle \u201ctasse fino alla morte\u201d dei Democratici, il Presidente eletto si impegna ad attuare \u201cimportanti tagli fiscali per i lavoratori\u201d ed a porre fine alle tasse sulle mance. Infine, mentre Anthony \u00e8 costretto a \u201cvivere in un mondo nuovo con un\u2019anima antica\u201d, Trump promette un ritorno ai valori tradizionali e la fine del \u201cwokismo\u201d sposato dai Democratici.<\/p>\n\n\n\n<p>Vendo la mia anima, lavoro tutto il giorno<\/p>\n\n\n\n<p>Faccio gli straordinari per un salario che non vale niente<\/p>\n\n\n\n<p>Cos\u00ec posso stare seduto qui a perdere tempo<\/p>\n\n\n\n<p>Andare a casa ed affogare i miei dispiaceri<\/p>\n\n\n\n<p class=\"comment\">La musica country presenta spesso personaggi delle classi operaie, sia in prima che in terza persona. Attraverso un post su Facebook del cantante, le informazioni filtrate sulla sua vita hanno rafforzato l&#8217;ipotesi che si trattasse di una canzone autobiografica. Dopo aver abbandonato la scuola superiore nel 2010 all&#8217;et\u00e0 di 17 anni, Anthony ha conseguito un diploma di scuola superiore equivalente (GED). Ha lavorato come precario industriale nella Carolina del Nord e in Virginia. Nel 2013, in una cartiera della Carolina del Nord, ha subito un incidente sul lavoro che gli ha provocato una frattura del cranio, rendendolo incapace di lavorare per sei mesi. Dal 2014 al 2023 ha lavorato come venditore esterno nel settore manifatturiero, visitando fabbriche e cantieri. Durante questo periodo, secondo quanto riferito, ha avuto diversi periodi di alcolismo. Nel 2023 si \u00e8 stabilito con la moglie e i due figli su diversi ettari di terreno per allevare il bestiame.<\/p>\n\n\n\n<p>Che peccato che il mondo sia arrivato a questo<\/p>\n\n\n\n<p>Per persone come te, per persone come me<\/p>\n\n\n\n<p>Se solo potessi svegliarmi e non fosse vero<\/p>\n\n\n\n<p>Ma \u00e8 cos\u00ec, oh s\u00ec, \u00e8 cos\u00ec<\/p>\n\n\n\n<p>Vivere in un nuovo mondo<\/p>\n\n\n\n<p>Con un\u2019anima antica<\/p>\n\n\n\n<p>Quei ricchi a nord di Richmond<\/p>\n\n\n\n<p class=\"comment\">Il riferimento a Richmond non \u00e8 insignificante. Durante la guerra civile americana (1861-1865), Richmond era la capitale della Confederazione. Se il messaggio di Oliver Anthony \u00e8 rivolto alle \u00e9lite ricche che non si preoccupano dei veri americani, \u00e8 sintomatico che si trovino \u201ca nord\u201d della capitale confederata. Sebbene canti con un marcato accento del Sud, sta chiaramente giocando su un intertesto storico molto carico. Pi\u00f9 in generale, l&#8217;immagine di semplicit\u00e0 radicata nell&#8217;America rurale e nella religione che propone \u00e8 un modo per riattivare lo stereotipo di un Sud profondamente dignitoso e cortese &#8211; le \u201cbuone maniere del Sud\u201d sono state oggetto di molte appropriazioni, dalla Guerra Civile ad oggi&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-26363' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2024\/11\/09\/il-manifesto-del-movimento-trumpista\/#easy-footnote-bottom-1-26363' title='Ted Ownby (dir.), &lt;em&gt;Manners and Southern History&lt;\/em&gt;, Jackson, University Press of Mississippi, 2012'><sup>1<\/sup><\/a><\/span><\/span> -, completamente opposto ad un Nord urbano, inquietante e violento. Alcuni pensieri paleoconservatori hanno enfatizzato il tradizionalismo del Sud &#8211; o della Confederazione &#8211; come un modo per difendere il localismo e i diritti degli Stati federati (\u201c<em>states\u2019 rights<\/em>\u201d) contro lo Stato federale, che si sarebbe sviluppato in maniera tirannica dopo la guerra civile.<\/p>\n\n\n\n<p>Dio sa che vogliono controllarci tutti<\/p>\n\n\n\n<p>Vogliono sapere quello che pensi, vogliono sapere quello che fai<\/p>\n\n\n\n<p>Pensano che tu non lo sappia, ma io so che lo sai<\/p>\n\n\n\n<p>Perch\u00e9 il tuo dollaro non vale nulla e ti tassano fino alla morte<\/p>\n\n\n\n<p>Per colpa di quei ricchi a nord di Richmond<\/p>\n\n\n\n<p class=\"comment\">Se il minarchismo &#8211; l&#8217;idea di una limitazione assoluta dello Stato &#8211; \u00e8 al centro del pensiero libertario, \u00e8 presente anche nella nebulosa paleoconservatrice. In ogni caso, i due movimenti hanno diversi punti di convergenza. Uno dei temi pi\u00f9 ricorrenti in questo discorso, evidenziato nelle canzoni, \u00e8 quello dell&#8217;oppressione fiscale per mano di personalit\u00e0 lontane. Viene spesso presentata come una lotta essenzialmente americana, e lo \u00e8 stata fin dalla guerra d\u2019indipendenza: non \u00e8 un caso che il movimento insurrezionale populista che ha trasformato il Partito Repubblicano dal 2009 in poi sia stato chiamato \u201cTea Party\u201d.<\/p>\n\n\n\n<p>Se solo i politici pensassero ai minatori<\/p>\n\n\n\n<p>E non ai minori di un&#8217;isola lontana.<\/p>\n\n\n\n<p>Signore, ci sono persone per strada che non hanno nulla da mangiare<\/p>\n\n\n\n<p>E persone obese che si rimpinzano con i sussidi sociali<\/p>\n\n\n\n<p class=\"comment\">Questo passaggio \u00e8 stato il pi\u00f9 discusso negli Stati Uniti. I primi due versi giocano su una pi\u00f9 chiara omonimia in inglese: <em>miner<\/em> (il minatore) e <em>minor <\/em>(il minorenne). Si tratta di un riferimento molto esplicito alla vicenda di Jeffrey Epstein, il famoso miliardario con un&#8217;isola privata nelle Isole Vergini americane dove aveva fatto subire abusi sessuali a numerose ragazze adolescenti. Le protezioni di cui il finanziere ha beneficiato per lungo tempo, cos\u00ec come il suo suicidio in carcere, hanno alimentato un forte risentimento contro le \u00e9lite dipinte come criminali e intoccabili. Alcuni commentatori hanno anche suggerito che Oliver Anthony si riferisse implicitamente alle teorie cospirative di QAnon, che spiegano che alcuni leader democratici rapiscono bambini per prelevare il loro sangue.<\/p>\n\n\n\n<p>Dio, se sei alto 1,60 m e pesi 136 kg<\/p>\n\n\n\n<p>Il fisco non dovrebbe pagare per i tuoi sacchetti di dolciumi<\/p>\n\n\n\n<p>I giovani sono sotto terra<\/p>\n\n\n\n<p>Perch\u00e9 questo dannato Paese continua a schiacciarli<\/p>\n\n\n\n<p class=\"comment\">Oliver Anthony si riferisce probabilmente all&#8217;epidemia di overdose di oppiacei e di suicidi che ha colpito gli Stati Uniti per diversi decenni. Ma la canzone denuncia anche il welfare state per aver trasformato gli americani in beneficiari di assistenza sociale. Qui troviamo un tema comune a tutto il partito repubblicano: il denaro pubblico sarebbe ingiustamente tassato sulle spalle dei lavoratori americani e contribuirebbe a cancellare il valore del lavoro.<\/p>\n\n\n\n<p>Signore, che peccato che il mondo sia arrivato a questo punto<\/p>\n\n\n\n<p>Per persone come te, per persone come me<\/p>\n\n\n\n<p>Se solo potessi svegliarmi e non fosse vero<\/p>\n\n\n\n<p>Ma \u00e8 cos\u00ec, oh s\u00ec, \u00e8 cos\u00ec<\/p>\n\n\n\n<p class=\"comment\">Questo riferimento a Dio &#8211; il quarto nella canzone &#8211; non \u00e8 insignificante. Nella sua autobiografia, Oliver Anthony ha spiegato di aver riscoperto la fede molto recentemente. Pochi giorni dopo che <em>Rich Men North of Richmond<\/em> \u00e8 diventato virale, ha organizzato un concerto in un mercato vicino a casa sua, davanti ad una folla molto pi\u00f9 numerosa del solito. Per aprire lo spettacolo, Anthony ha tirato fuori una Bibbia e ha letto il Salmo 37 sulla redenzione dei peccati. Questo ritorno al cristianesimo \u00e8 stato ampiamente commentato nell&#8217;ambiente conservatore, che lo ha visto come un ulteriore segno che il cantante poteva inserirsi nel suo mondo.<\/p>\n\n\n\n<p class=\"comment\">In un messaggio postato su Instagram subito dopo la vittoria di Trump, \u00e8 rimasto evasivo sulla sua appartenenza politica &#8211; non nascondendo per\u00f2 una certa benevolenza per personaggi come Robert Kennedy Jr. ed Elon Musk &#8211; ed ha invitato a disconnettersi dalla televisione e dai social. Chiude il suo breve testo con queste parole: \u201cVotate per diventare la migliore versione di voi stessi mangiando bene e dormendo bene. Prego perch\u00e9 trascorriate ogni giorno perseguendo la vita, la libert\u00e0 e la ricerca della felicit\u00e0; i diritti che ci sono stati dati dal nostro Creatore. Votiamo per smettere di adorare i loro falsi idoli. Dobbiamo ricominciare a vivere nel mondo reale, non in quello virtuale\u201d.<\/p>\n\n\n\n<p>Vivere in un mondo nuovo<\/p>\n\n\n\n<p>Con un\u2019anima antica<\/p>\n\n\n\n<p>Quei ricchi a nord di Richmond<\/p>\n\n\n\n<p>Dio sa che vogliono controllarci tutti<\/p>\n\n\n\n<p>Vogliono sapere quello che pensi, vogliono sapere quello che fai<\/p>\n\n\n\n<p>Pensano che non lo sappiate, ma io so che lo sapete<\/p>\n\n\n\n<p>Perch\u00e9 il tuo dollaro non vale nulla e ti tassano fino alla morte<\/p>\n\n\n\n<p>A causa di questi ricchi a nord di Richmond<\/p>\n\n\n\n<p class=\"comment\">Ancora una volta, questo passaggio fa riferimento alle teorie libertarie e paleoconservatrici. Dalla guerra civile in poi, e ancor pi\u00f9 dopo la seconda guerra mondiale, si dice che lo Stato americano abbia abbandonato i valori su cui era stato fondato a favore del controllo e della sorveglianza dei suoi cittadini. Queste idee sono state oggetto del libro di Robert Nozick del 1974 <em>Anarchia, Stato e Utopia<\/em>. Sostenendo di essere stato influenzato da Locke, Kant e Hayek, difende una visione ancora pi\u00f9 radicale della riduzione dello Stato rispetto a Hayek. Le ultime pagine del libro elogiano le comunit\u00e0 che riescono a diventare completamente autonome da uno Stato oppressivo. Nella sua musica, come in ci\u00f2 che descrive della sua vita, Oliver Anthony sembra molto vicino a questa aspirazione.<\/p>\n\n\n\n<p>Vendo la mia anima, lavoro tutto il giorno<\/p>\n\n\n\n<p>Faccio gli straordinari per un salario che non vale niente<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Vivere in un nuovo mondo\/Con un\u2019anima antica&#8221;.<\/p>\n<p>Il manifesto del movimento che ha appena portato Donald Trump alla Casa Bianca non \u00e8 un articolo di giornale o un discorso importante, ma una canzone country &#8211; <em> Rich Men North of Richmond<\/em> &#8211; pubblicata su Youtube da un cantante all&#8217;epoca quasi anonimo, Oliver Anthony, poco pi\u00f9 di un anno fa. Ascoltata milioni di volte, quasi sconosciuta in Europa, raccoglie tutti i temi che strutturano la nuova coalizione di Trump.<\/p>\n<p>Per capire Trump nel 2024, bisogna ascoltarla e leggere tra le righe.<\/p>\n","protected":false},"author":29021,"featured_media":26362,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-speeches.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":11,"footnotes":""},"categories":[2263],"tags":[],"staff":[1596,2169],"editorial_format":[2350],"serie":[],"audience":[],"geo":[2161],"class_list":["post-26363","post","type-post","status-publish","format-standard","hentry","category-trump-origini-intelletuali-di-una-rivoluzione-culturale","staff-baptiste-roger-lacan","staff-marin-saillofest","editorial_format-discorsi","geo-americhe"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":26362,"excerpt":"\"Vivere in un nuovo mondo\/Con un\u2019anima antica\".\r\n\r\nIl manifesto del movimento che ha appena portato Donald Trump alla Casa Bianca non \u00e8 un articolo di giornale o un discorso importante, ma una canzone country - <em> Rich Men North of Richmond<\/em> - pubblicata su Youtube da un cantante all'epoca quasi anonimo, Oliver Anthony, poco pi\u00f9 di un anno fa. Ascoltata milioni di volte, quasi sconosciuta in Europa, raccoglie tutti i temi che strutturano la nuova coalizione di Trump.\r\n\r\nPer capire Trump nel 2024, bisogna ascoltarla e leggere tra le righe.\r\n","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Il vero manifesto del movimento trumpista\u00a0 - Il Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/it\/2024\/11\/09\/il-manifesto-del-movimento-trumpista\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il vero manifesto del movimento trumpista\u00a0 - Il Grand Continent\" \/>\n<meta property=\"og:description\" content=\"&quot;Vivere in un nuovo mondo\/Con un\u2019anima antica&quot;.  Il manifesto del movimento che ha appena portato Donald Trump alla Casa Bianca non \u00e8 un articolo di giornale o un discorso importante, ma una canzone country - Rich Men North of Richmond - pubblicata su Youtube da un cantante all&#039;epoca quasi anonimo, Oliver Anthony, poco pi\u00f9 di un anno fa. Ascoltata milioni di volte, quasi sconosciuta in Europa, raccoglie tutti i temi che strutturano la nuova coalizione di Trump.  Per capire Trump nel 2024, bisogna ascoltarla e leggere tra le righe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/it\/2024\/11\/09\/il-manifesto-del-movimento-trumpista\/\" \/>\n<meta property=\"og:site_name\" content=\"Il Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-09T05:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/11\/gc-ilanthony-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hannacorsinimurat\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/11\/gc-ilanthony-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"hannacorsinimurat\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2024\/11\/09\/il-manifesto-del-movimento-trumpista\/\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/2024\/11\/09\/il-manifesto-del-movimento-trumpista\/\",\"name\":\"Il vero manifesto del movimento trumpista\u00a0 - Il Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2024\/11\/09\/il-manifesto-del-movimento-trumpista\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2024\/11\/09\/il-manifesto-del-movimento-trumpista\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/2\/2024\/11\/oliver-anthony-press-credit-Draven-Riffe-2023-billboard-1548.jpg\",\"datePublished\":\"2024-11-09T05:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/8912e0c6b01d20345b444fb3007edadd\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2024\/11\/09\/il-manifesto-del-movimento-trumpista\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/it\/2024\/11\/09\/il-manifesto-del-movimento-trumpista\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2024\/11\/09\/il-manifesto-del-movimento-trumpista\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/2\/2024\/11\/oliver-anthony-press-credit-Draven-Riffe-2023-billboard-1548.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/2\/2024\/11\/oliver-anthony-press-credit-Draven-Riffe-2023-billboard-1548.jpg\",\"width\":1548,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2024\/11\/09\/il-manifesto-del-movimento-trumpista\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il vero manifesto del movimento trumpista\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/\",\"name\":\"Il Grand Continent\",\"description\":\"La scala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/8912e0c6b01d20345b444fb3007edadd\",\"name\":\"hannacorsinimurat\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4bf5af82268bb796a39092920c9faec1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4bf5af82268bb796a39092920c9faec1?s=96&d=mm&r=g\",\"caption\":\"hannacorsinimurat\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il vero manifesto del movimento trumpista\u00a0 - Il Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/it\/2024\/11\/09\/il-manifesto-del-movimento-trumpista\/","og_locale":"it_IT","og_type":"article","og_title":"Il vero manifesto del movimento trumpista\u00a0 - Il Grand Continent","og_description":"\"Vivere in un nuovo mondo\/Con un\u2019anima antica\".  Il manifesto del movimento che ha appena portato Donald Trump alla Casa Bianca non \u00e8 un articolo di giornale o un discorso importante, ma una canzone country - Rich Men North of Richmond - pubblicata su Youtube da un cantante all'epoca quasi anonimo, Oliver Anthony, poco pi\u00f9 di un anno fa. Ascoltata milioni di volte, quasi sconosciuta in Europa, raccoglie tutti i temi che strutturano la nuova coalizione di Trump.  Per capire Trump nel 2024, bisogna ascoltarla e leggere tra le righe.","og_url":"https:\/\/legrandcontinent.eu\/it\/2024\/11\/09\/il-manifesto-del-movimento-trumpista\/","og_site_name":"Il Grand Continent","article_published_time":"2024-11-09T05:00:00+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/11\/gc-ilanthony-scaled.jpg","type":"image\/jpeg"}],"author":"hannacorsinimurat","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2024\/11\/gc-ilanthony-scaled.jpg","twitter_misc":{"Scritto da":"hannacorsinimurat","Tempo di lettura stimato":"11 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/it\/2024\/11\/09\/il-manifesto-del-movimento-trumpista\/","url":"https:\/\/legrandcontinent.eu\/it\/2024\/11\/09\/il-manifesto-del-movimento-trumpista\/","name":"Il vero manifesto del movimento trumpista\u00a0 - Il Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/it\/2024\/11\/09\/il-manifesto-del-movimento-trumpista\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/it\/2024\/11\/09\/il-manifesto-del-movimento-trumpista\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/2\/2024\/11\/oliver-anthony-press-credit-Draven-Riffe-2023-billboard-1548.jpg","datePublished":"2024-11-09T05:00:00+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/8912e0c6b01d20345b444fb3007edadd"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/it\/2024\/11\/09\/il-manifesto-del-movimento-trumpista\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/it\/2024\/11\/09\/il-manifesto-del-movimento-trumpista\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/legrandcontinent.eu\/it\/2024\/11\/09\/il-manifesto-del-movimento-trumpista\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/2\/2024\/11\/oliver-anthony-press-credit-Draven-Riffe-2023-billboard-1548.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/2\/2024\/11\/oliver-anthony-press-credit-Draven-Riffe-2023-billboard-1548.jpg","width":1548,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/it\/2024\/11\/09\/il-manifesto-del-movimento-trumpista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/it\/"},{"@type":"ListItem","position":2,"name":"Il vero manifesto del movimento trumpista\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/it\/#website","url":"https:\/\/legrandcontinent.eu\/it\/","name":"Il Grand Continent","description":"La scala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/8912e0c6b01d20345b444fb3007edadd","name":"hannacorsinimurat","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4bf5af82268bb796a39092920c9faec1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4bf5af82268bb796a39092920c9faec1?s=96&d=mm&r=g","caption":"hannacorsinimurat"}}]}},"lgc_categories":[{"id":2263,"name":"Trump: origini intelletuali di una rivoluzione culturale","slug":"trump-origini-intelletuali-di-una-rivoluzione-culturale"}],"lgc_author":{"id":1596,"name":"Baptiste Roger-Lacan","slug":"baptiste-roger-lacan","description":"Baptiste Roger-Lacan \u00e8 viceredattore in capo. Ha un dottorato in storia ed \u00e8 specialista delle destre e dei controrivoluzionari europei dal XIX secolo ai giorni nostri.","first_name":null,"last_name":null,"picture":{"url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2023\/10\/Baptiste.png","width":230,"height":345,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/2\/2024\/11\/oliver-anthony-press-credit-Draven-Riffe-2023-billboard-1548.jpg","width":1548,"height":1024,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/2\/2024\/11\/oliver-anthony-press-credit-Draven-Riffe-2023-billboard-1548.jpg","width":1548,"height":1024,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts\/26363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/users\/29021"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/comments?post=26363"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts\/26363\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/media\/26362"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/media?parent=26363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/categories?post=26363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/tags?post=26363"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/staff?post=26363"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/editorial_format?post=26363"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/serie?post=26363"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/audience?post=26363"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/geo?post=26363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}