{"id":16175,"date":"2023-12-06T12:45:00","date_gmt":"2023-12-06T11:45:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/it\/?p=16175"},"modified":"2023-12-06T14:50:59","modified_gmt":"2023-12-06T13:50:59","slug":"a-washington-la-causa-persa-del-sostegno-allucraina","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/it\/2023\/12\/06\/a-washington-la-causa-persa-del-sostegno-allucraina\/","title":{"rendered":"A Washington, la causa persa del sostegno all\u2019Ucraina"},"content":{"rendered":"\n<p>Al forum sull\u2019industria della difesa che si terr\u00e0 oggi e domani a Washington sono attesi i rappresentanti di decine di aziende ucraine \u2013 sia pubbliche che private \u2013 e un numero ancora maggiore di industriali americani. Sono attesi anche alcuni alti funzionari statunitensi, tra cui Jake Sullivan, Lloyd Austin e Gina Raimondo&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-16175' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2023\/12\/06\/a-washington-la-causa-persa-del-sostegno-allucraina\/#easy-footnote-bottom-1-16175' title='Paul McLeary, \u00ab &lt;a href=&quot;https:\/\/www.politico.com\/news\/2023\/12\/05\/ukraine-officials-visit-washington-weapons-00130093&quot;&gt;Ukrainian leaders head to the US as Kyiv prepares for winter fighting&lt;\/a&gt; \u00bb, &lt;em&gt;Politico&lt;\/em&gt;, 5 dicembre 2023.'><sup>1<\/sup><\/a><\/span><\/span>. L\u2019obiettivo dichiarato della Casa Bianca \u00e8 \u00abesplorare le opportunit\u00e0 di coproduzione e altre forme di cooperazione industriale in Ucraina\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-16175' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2023\/12\/06\/a-washington-la-causa-persa-del-sostegno-allucraina\/#easy-footnote-bottom-2-16175' title='&lt;a href=&quot;https:\/\/www.whitehouse.gov\/briefing-room\/statements-releases\/2023\/11\/17\/statement-from-nsc-spokesperson-adrienne-watson-announcing-u-s-ukraine-defense-industrial-base-conference\/&quot;&gt;Statement from NSC Spokesperson Adrienne Watson Announcing U.S.-Ukraine Defense Industrial Base Conference&lt;\/a&gt;, White House, 17 novembre 2023.'><sup>2<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>Mentre il Pentagono si trover\u00e0 presto a corto di fondi per l\u2019invio di attrezzature e munizioni all\u2019Ucraina, al Congresso non si vedono progressi all\u2019orizzonte.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>I rappresentanti repubblicani si rifiutano di stanziare maggiori risorse per Kiev finch\u00e9 i democratici non saranno disposti a fare concessioni sulla politica dell\u2019amministrazione in merito al confine meridionale con il Messico (in particolare per quanto riguarda la procedura di asilo).<\/li>\n\n\n\n<li>In risposta a una lettera della Casa Bianca che avvertiva il Congresso che Washington avrebbe esaurito le risorse \u00abentro la fine dell\u2019anno\u00bb per l\u2019Ucraina, il presidente repubblicano della Camera Mike Johnson ha dichiarato che \u00abqualsiasi programma di sicurezza nazionale aggiuntivo deve iniziare dal nostro confine\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-16175' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2023\/12\/06\/a-washington-la-causa-persa-del-sostegno-allucraina\/#easy-footnote-bottom-3-16175' title='&lt;a href=&quot;https:\/\/twitter.com\/SpeakerJohnson\/status\/1731689607803146328&quot;&gt; Mike Johnson su X (Twitter)&lt;\/a&gt;, 4 dicembre 2023.'><sup>3<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>Oltre all\u2019Ucraina, i rappresentanti repubblicani stanno bloccando anche nuovi finanziamenti per Israele, Taiwan e l\u2019Indo-Pacifico.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/4B8GQ\/1\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Mentre la maggioranza democratica al Senato ha presentato marted\u00ec 5 dicembre un testo da 111 miliardi di dollari \u2013 15,1 miliardi di dollari per il sostegno militare all\u2019Ucraina, 10,6 miliardi di dollari per Israele, 43,6 miliardi di dollari per la base di difesa degli Stati Uniti, 1,42 miliardi di dollari per l\u2019assunzione di giudici per l\u2019immigrazione&#8230;&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-16175' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2023\/12\/06\/a-washington-la-causa-persa-del-sostegno-allucraina\/#easy-footnote-bottom-4-16175' title='Un riassunto \u00e8 disponibile qui: &lt;a href=&quot;https:\/\/www.appropriations.senate.gov\/imo\/media\/doc\/national_security_and_border_act_summary.pdf&quot;&gt;National Security and Border Act, 2024 Summary&lt;\/a&gt;. Testo completo: &lt;a href=&quot;https:\/\/www.appropriations.senate.gov\/imo\/media\/doc\/national_security_and_border_act_text.pdf?utm_source=newsletter&amp;amp;utm_medium=email&amp;amp;utm_campaign=newsletter_axiossneakpeek&amp;amp;stream=top&quot;&gt;National Security and Border Act Text&lt;\/a&gt;.'><sup>4<\/sup><\/a><\/span><\/span> \u2013 il leader della minoranza Mitch McConnell ha dato istruzioni di votare contro in un voto procedurale previsto per mercoled\u00ec&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-16175' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2023\/12\/06\/a-washington-la-causa-persa-del-sostegno-allucraina\/#easy-footnote-bottom-5-16175' title='Liz Goodwin, Leigh Ann Caldwell e Marianna Sotomayor, \u00ab &lt;a href=&quot;https:\/\/www.washingtonpost.com\/politics\/2023\/12\/05\/senate-ukraine-immigration-defeat\/&quot;&gt;Senate lawmakers careen toward failed vote on Ukraine&lt;\/a&gt; \u00bb, &lt;em&gt;The Washington Post&lt;\/em&gt;, 5 dicembre 2023.'><sup>5<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/xvw8v\/1\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>\u00c8 nel mezzo di questo scontro che Volodymyr Zelensky e diversi funzionari ucraini stanno cercando, dall\u2019inizio della settimana, di convincere i membri repubblicani del parlamento che il sostegno americano \u00e8 vitale per loro.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ruslan Stefantchouk, presidente della Rada (il parlamento ucraino), Andryi Yermak, capogabinetto di Zelensky, e Rustem Umerov, ministro della Difesa, sono tutti a Capitol Hill, dove stanno tenendo colloqui con i membri del Congresso.<\/li>\n\n\n\n<li>Volodymyr Zelensky avrebbe dovuto parlare ai senatori a distanza durante un briefing riservato marted\u00ec 5 dicembre. Tuttavia, ha disdetto all\u2019ultimo minuto senza fornire spiegazioni, lasciando la parola ai funzionari dell\u2019amministrazione democratica.<\/li>\n\n\n\n<li>I senatori repubblicani hanno abbandonato la riunione per protestare contro la mancanza di discussioni sul confine. Il rappresentante eletto del Missouri, Josh Hawley, ha dichiarato che si \u00e8 trattato della riunione riservata \u00abpi\u00f9 accesa\u00bb a cui avesse mai partecipato&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-16175' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2023\/12\/06\/a-washington-la-causa-persa-del-sostegno-allucraina\/#easy-footnote-bottom-6-16175' title='Frank Thorp V, Kate Santaliz et Lori Rampani, \u00ab &lt;a href=&quot;https:\/\/www.nbcnews.com\/politics\/congress\/republicans-storm-briefing-congress-battles-israel-ukraine-aid-package-rcna128245&quot;&gt;Republicans storm out of briefing as Congress battles over Israel and Ukraine aid package&lt;\/a&gt; \u00bb, &lt;em&gt;NBC News&lt;\/em&gt;, 6 dicembre 2023.'><sup>6<\/sup><\/a><\/span><\/span>.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/1GwUD\/1\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>L\u2019amministrazione Biden ha recentemente cercato di raccogliere il sostegno dei repubblicani diffondendo dati sull\u2019impatto economico degli aiuti all\u2019Ucraina per ogni Stato&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-7-16175' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2023\/12\/06\/a-washington-la-causa-persa-del-sostegno-allucraina\/#easy-footnote-bottom-7-16175' title='&lt;a href=&quot;https:\/\/www.acq.osd.mil\/news\/spotlight\/Ukraine%20Infographic_22NOV2023_v2.pdf&quot;&gt;UKRAINE SECURITY ASSISTANCE&lt;\/a&gt;, U.S. Department of Defense, 22 novembre 2023.'><sup>7<\/sup><\/a><\/span><\/span>. Sebbene i fondi stanziati finora consistano nella sostituzione di munizioni ed equipaggiamenti donati con altri nuovi, pi\u00f9 di 27 miliardi sarebbero stati investiti negli Stati Uniti, una parte significativa dei quali in stati vinti da Trump nel 2020.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oggi si apre a Washington una conferenza di due giorni sull\u2019industria della difesa organizzata da Ucraina e Stati Uniti. Nel periodo precedente al summit, alti funzionari ucraini e membri dell\u2019amministrazione Biden hanno supplicato i rappresentanti repubblicani di mantenere il sostegno militare a Kiev, senza successo.<\/p>\n","protected":false},"author":10633,"featured_media":16176,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":4,"footnotes":""},"categories":[2173],"tags":[],"staff":[],"editorial_format":[2354],"serie":[],"audience":[],"geo":[2161],"class_list":["post-16175","post","type-post","status-publish","format-standard","hentry","category-la-guerra-in-ucraina-giorno-per-giorno","editorial_format-brevi","geo-americhe"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":16176,"excerpt":"Oggi si apre a Washington una conferenza di due giorni sull\u2019industria della difesa organizzata da Ucraina e Stati Uniti. Nel periodo precedente al summit, alti funzionari ucraini e membri dell\u2019amministrazione Biden hanno supplicato i rappresentanti repubblicani di mantenere il sostegno militare a Kiev, senza successo.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A Washington, la causa persa del sostegno all\u2019Ucraina - Il Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/it\/2023\/12\/06\/a-washington-la-causa-persa-del-sostegno-allucraina\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Washington, la causa persa del sostegno all\u2019Ucraina - Il Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Oggi si apre a Washington una conferenza di due giorni sull\u2019industria della difesa organizzata da Ucraina e Stati Uniti. Nel periodo precedente al summit, alti funzionari ucraini e membri dell\u2019amministrazione Biden hanno supplicato i rappresentanti repubblicani di mantenere il sostegno militare a Kiev, senza successo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/it\/2023\/12\/06\/a-washington-la-causa-persa-del-sostegno-allucraina\/\" \/>\n<meta property=\"og:site_name\" content=\"Il Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-06T11:45:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-06T13:50:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2023\/12\/Screenshot-2023-12-06-alle-14.41.42.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1724\" \/>\n\t<meta property=\"og:image:height\" content=\"1028\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"aburatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"aburatti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2023\/12\/06\/a-washington-la-causa-persa-del-sostegno-allucraina\/\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/2023\/12\/06\/a-washington-la-causa-persa-del-sostegno-allucraina\/\",\"name\":\"A Washington, la causa persa del sostegno all\u2019Ucraina - Il Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2023\/12\/06\/a-washington-la-causa-persa-del-sostegno-allucraina\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2023\/12\/06\/a-washington-la-causa-persa-del-sostegno-allucraina\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2023\/12\/Screenshot-2023-12-06-alle-14.41.42.png\",\"datePublished\":\"2023-12-06T11:45:00+00:00\",\"dateModified\":\"2023-12-06T13:50:59+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/b70352884e4ad6f2a76729e9051dd9f6\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2023\/12\/06\/a-washington-la-causa-persa-del-sostegno-allucraina\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/it\/2023\/12\/06\/a-washington-la-causa-persa-del-sostegno-allucraina\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2023\/12\/06\/a-washington-la-causa-persa-del-sostegno-allucraina\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2023\/12\/Screenshot-2023-12-06-alle-14.41.42.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2023\/12\/Screenshot-2023-12-06-alle-14.41.42.png\",\"width\":1724,\"height\":1028},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2023\/12\/06\/a-washington-la-causa-persa-del-sostegno-allucraina\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Washington, la causa persa del sostegno all\u2019Ucraina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/\",\"name\":\"Il Grand Continent\",\"description\":\"La scala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/b70352884e4ad6f2a76729e9051dd9f6\",\"name\":\"aburatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fa34e55e0507c2ca67b9a65ed781903d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fa34e55e0507c2ca67b9a65ed781903d?s=96&d=mm&r=g\",\"caption\":\"aburatti\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Washington, la causa persa del sostegno all\u2019Ucraina - Il Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/it\/2023\/12\/06\/a-washington-la-causa-persa-del-sostegno-allucraina\/","og_locale":"it_IT","og_type":"article","og_title":"A Washington, la causa persa del sostegno all\u2019Ucraina - Il Grand Continent","og_description":"Oggi si apre a Washington una conferenza di due giorni sull\u2019industria della difesa organizzata da Ucraina e Stati Uniti. Nel periodo precedente al summit, alti funzionari ucraini e membri dell\u2019amministrazione Biden hanno supplicato i rappresentanti repubblicani di mantenere il sostegno militare a Kiev, senza successo.","og_url":"https:\/\/legrandcontinent.eu\/it\/2023\/12\/06\/a-washington-la-causa-persa-del-sostegno-allucraina\/","og_site_name":"Il Grand Continent","article_published_time":"2023-12-06T11:45:00+00:00","article_modified_time":"2023-12-06T13:50:59+00:00","og_image":[{"width":1724,"height":1028,"url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2023\/12\/Screenshot-2023-12-06-alle-14.41.42.png","type":"image\/png"}],"author":"aburatti","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"aburatti","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/it\/2023\/12\/06\/a-washington-la-causa-persa-del-sostegno-allucraina\/","url":"https:\/\/legrandcontinent.eu\/it\/2023\/12\/06\/a-washington-la-causa-persa-del-sostegno-allucraina\/","name":"A Washington, la causa persa del sostegno all\u2019Ucraina - Il Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/it\/2023\/12\/06\/a-washington-la-causa-persa-del-sostegno-allucraina\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/it\/2023\/12\/06\/a-washington-la-causa-persa-del-sostegno-allucraina\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2023\/12\/Screenshot-2023-12-06-alle-14.41.42.png","datePublished":"2023-12-06T11:45:00+00:00","dateModified":"2023-12-06T13:50:59+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/b70352884e4ad6f2a76729e9051dd9f6"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/it\/2023\/12\/06\/a-washington-la-causa-persa-del-sostegno-allucraina\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/it\/2023\/12\/06\/a-washington-la-causa-persa-del-sostegno-allucraina\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/legrandcontinent.eu\/it\/2023\/12\/06\/a-washington-la-causa-persa-del-sostegno-allucraina\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2023\/12\/Screenshot-2023-12-06-alle-14.41.42.png","contentUrl":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2023\/12\/Screenshot-2023-12-06-alle-14.41.42.png","width":1724,"height":1028},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/it\/2023\/12\/06\/a-washington-la-causa-persa-del-sostegno-allucraina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/it\/"},{"@type":"ListItem","position":2,"name":"A Washington, la causa persa del sostegno all\u2019Ucraina"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/it\/#website","url":"https:\/\/legrandcontinent.eu\/it\/","name":"Il Grand Continent","description":"La scala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/b70352884e4ad6f2a76729e9051dd9f6","name":"aburatti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fa34e55e0507c2ca67b9a65ed781903d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fa34e55e0507c2ca67b9a65ed781903d?s=96&d=mm&r=g","caption":"aburatti"}}]}},"lgc_categories":[{"id":2173,"name":"La guerra in Ucraina giorno per giorno","slug":"la-guerra-in-ucraina-giorno-per-giorno"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2023\/12\/Screenshot-2023-12-06-alle-14.41.42.png","width":1724,"height":1028,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts\/16175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/users\/10633"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/comments?post=16175"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts\/16175\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/media\/16176"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/media?parent=16175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/categories?post=16175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/tags?post=16175"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/staff?post=16175"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/editorial_format?post=16175"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/serie?post=16175"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/audience?post=16175"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/geo?post=16175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}