{"id":15284,"date":"2023-11-23T17:13:00","date_gmt":"2023-11-23T16:13:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/it\/?p=15284"},"modified":"2023-11-23T18:03:39","modified_gmt":"2023-11-23T17:03:39","slug":"la-vittoria-di-wilders-nei-paesi-bassi-i-partiti-a-destra-del-ppe-stanno-per-governare-in-5-paesi-europei","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/it\/2023\/11\/23\/la-vittoria-di-wilders-nei-paesi-bassi-i-partiti-a-destra-del-ppe-stanno-per-governare-in-5-paesi-europei\/","title":{"rendered":"Vittoria di Wilders nei Paesi Bassi: i partiti a destra del PPE stanno per governare in 5 Paesi europei"},"content":{"rendered":"\n<p>Il Partito per la Libert\u00e0 (PVV), che fa parte del gruppo Identit\u00e0 e Democrazia (ID) al Parlamento europeo, \u00e8 uscito nettamente vincitore dalle elezioni parlamentari olandesi tenutesi mercoled\u00ec 22 novembre.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Il suo partito, dalla forte posizione islamofoba, si batte principalmente contro l\u2019immigrazione. Ha anche incluso nel suo programma l\u2019organizzazione di un referendum sull\u2019uscita dei Paesi Bassi dall\u2019Unione Europea.&nbsp;<\/li>\n\n\n\n<li>Il Primo Ministro ungherese Viktor Orb\u00e1n si \u00e8 congratulato con Geert Wilders per la sua vittoria, inserendola subito in una prospettiva pi\u00f9 ampia: \u00abIl vento del cambiamento \u00e8 qui\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-15284' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2023\/11\/23\/la-vittoria-di-wilders-nei-paesi-bassi-i-partiti-a-destra-del-ppe-stanno-per-governare-in-5-paesi-europei\/#easy-footnote-bottom-1-15284' title='&lt;a href=&quot;https:\/\/twitter.com\/PM_ViktorOrban\/status\/1727429763734864213&quot;&gt;Dichiarazione di Viktor Orban su X (ex Twitter)&lt;\/a&gt;, 22 novembre 2023.'><sup>1<\/sup><\/a><\/span><\/span>.\u00a0<\/li>\n\n\n\n<li>Anche Marine Le Pen ha accolto con favore la vittoria del suo alleato nel gruppo ID, che ha visto come una prova che \u00absempre pi\u00f9 Paesi all\u2019interno dell\u2019Unione Europea mettono in discussione il suo funzionamento [&#8230;] e vogliono controllare un\u2019immigrazione massiccia e anarchica\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-15284' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/it\/2023\/11\/23\/la-vittoria-di-wilders-nei-paesi-bassi-i-partiti-a-destra-del-ppe-stanno-per-governare-in-5-paesi-europei\/#easy-footnote-bottom-2-15284' title='&lt;a href=&quot;https:\/\/www.radiofrance.fr\/franceinter\/podcasts\/l-invite-de-8h20-le-grand-entretien\/l-invite-de-8h20-le-grand-entretien-du-jeudi-23-novembre-2023-9486252&quot;&gt;Interview de Marine Le Pen&lt;\/a&gt;, France Inter, 23 novembre 2023.'><sup>2<\/sup><\/a><\/span><\/span>.\u00a0<\/li>\n<\/ul>\n\n\n\n<p>La maggior parte dei partiti posizionati a destra del PPE si riuniscono al Parlamento europeo nei gruppi Identit\u00e0 e Democrazia (ID) e Conservatori e Riformisti Europei (ECR), ma ci sono alcune eccezioni.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Alcuni partiti senza deputati eletti (come Reconqu\u00eate in Francia) non confluiscono nei partiti europei.<\/li>\n\n\n\n<li>Il Fidesz di Viktor Orb\u00e1n non \u00e8 iscritto ad alcun partito da quando ha annunciato le sue dimissioni dal gruppo del PPE nel marzo 2021.&nbsp;<\/li>\n\n\n\n<li>Anche il caso del Primo Ministro Robert Fico in Slovacchia \u2013\u00a0 che si \u00e8 distinto per la sua retorica anti-migranti, pro-Putin e anti-LGBT \u2013\u00a0 pone un problema per la classificazione dei partiti europei, in quanto il suo partito appartiene al gruppo S&amp;D del Parlamento europeo.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/Quj0c\/1\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>L\u2019elenco degli Stati membri in cui questi partiti occupano una posizione di governo o di capo di Stato ha subito diversi cambiamenti da settembre.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Il 30 settembre, la Slovacchia si \u00e8 unita all\u2019elenco in seguito alle elezioni parlamentari che hanno portato alla formazione di una coalizione tra lo Smer-SD del Primo Ministro Robert Fico e il Partito Nazionale Slovacco (SNS).<\/li>\n\n\n\n<li>Al contrario, il PiS \u2013&nbsp; leader storico del partito CRE nel Parlamento europeo \u2013&nbsp; \u00e8 sul punto di perdere il potere in Polonia, con la coalizione di opposizione che ha ottenuto abbastanza voti per governare nelle elezioni legislative del 15 ottobre. Sebbene il Presidente Andrzej Duda abbia comunque affidato a Mateusz Morawiecki, membro del PiS, il compito di formare un governo, \u00e8 probabile che fallisca e lasci la strada aperta all\u2019opposizione guidata da Donald Tusk.&nbsp;<\/li>\n\n\n\n<li>La vittoria di ieri di Geert Wilders dovrebbe consentirgli di governare nei Paesi Bassi.&nbsp;<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/8UF8r\/2\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L\u2019AfD ha anche ottenuto successi storici in Germania nelle due elezioni regionali tenutesi l\u20198 ottobre in Baviera e Assia. Il partito di estrema destra rimane al secondo posto nei sondaggi federali.<\/li>\n<\/ul>\n\n\n\n<p>Questi risultati elettorali sono le prime tendenze da monitorare attentamente in vista del rinnovo del Parlamento europeo nel giugno 2024. Il gruppo di partiti classificati a destra del PPE potrebbe essere rafforzato in misura ancora da determinare, anche attraverso un aumento del partito Fratelli d\u2019Italia di Giorgia Meloni nel gruppo CRE \u2013&nbsp; che attualmente pu\u00f2 contare solo su 8 eurodeputati.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il partito di estrema destra di Geert Wilders ha ottenuto una vittoria schiacciante nelle elezioni parlamentari olandesi di ieri, con un punteggio che dovrebbe garantirgli un posto nel governo. Questa \u00e8 l\u2019occasione per fare il punto sugli sconvolgimenti politici avvenuti nell\u2019Unione Europea quest\u2019autunno, a poco pi\u00f9 di sei mesi dalle elezioni europee del 2024.<\/p>\n","protected":false},"author":10633,"featured_media":15288,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":3,"footnotes":""},"categories":[2178],"tags":[],"staff":[],"editorial_format":[2354],"serie":[],"audience":[],"geo":[2086],"class_list":["post-15284","post","type-post","status-publish","format-standard","hentry","category-dati-critici","editorial_format-brevi","geo-europa"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":15288,"excerpt":"Il partito di estrema destra di Geert Wilders ha ottenuto una vittoria schiacciante nelle elezioni parlamentari olandesi di ieri, con un punteggio che dovrebbe garantirgli un posto nel governo. Questa \u00e8 l\u2019occasione per fare il punto sugli sconvolgimenti politici avvenuti nell\u2019Unione Europea quest\u2019autunno, a poco pi\u00f9 di sei mesi dalle elezioni europee del 2024.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vittoria di Wilders nei Paesi Bassi: i partiti a destra del PPE stanno per governare in 5 Paesi europei - Il Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/it\/2023\/11\/23\/la-vittoria-di-wilders-nei-paesi-bassi-i-partiti-a-destra-del-ppe-stanno-per-governare-in-5-paesi-europei\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vittoria di Wilders nei Paesi Bassi: i partiti a destra del PPE stanno per governare in 5 Paesi europei - Il Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Il partito di estrema destra di Geert Wilders ha ottenuto una vittoria schiacciante nelle elezioni parlamentari olandesi di ieri, con un punteggio che dovrebbe garantirgli un posto nel governo. Questa \u00e8 l\u2019occasione per fare il punto sugli sconvolgimenti politici avvenuti nell\u2019Unione Europea quest\u2019autunno, a poco pi\u00f9 di sei mesi dalle elezioni europee del 2024.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/it\/2023\/11\/23\/la-vittoria-di-wilders-nei-paesi-bassi-i-partiti-a-destra-del-ppe-stanno-per-governare-in-5-paesi-europei\/\" \/>\n<meta property=\"og:site_name\" content=\"Il Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-23T16:13:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-23T17:03:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2023\/11\/Screenshot-2023-11-23-alle-17.58.20.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1314\" \/>\n\t<meta property=\"og:image:height\" content=\"1436\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"aburatti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"aburatti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2023\/11\/23\/la-vittoria-di-wilders-nei-paesi-bassi-i-partiti-a-destra-del-ppe-stanno-per-governare-in-5-paesi-europei\/\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/2023\/11\/23\/la-vittoria-di-wilders-nei-paesi-bassi-i-partiti-a-destra-del-ppe-stanno-per-governare-in-5-paesi-europei\/\",\"name\":\"Vittoria di Wilders nei Paesi Bassi: i partiti a destra del PPE stanno per governare in 5 Paesi europei - Il Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2023\/11\/23\/la-vittoria-di-wilders-nei-paesi-bassi-i-partiti-a-destra-del-ppe-stanno-per-governare-in-5-paesi-europei\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2023\/11\/23\/la-vittoria-di-wilders-nei-paesi-bassi-i-partiti-a-destra-del-ppe-stanno-per-governare-in-5-paesi-europei\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2023\/11\/Screenshot-2023-11-23-alle-17.58.20.png\",\"datePublished\":\"2023-11-23T16:13:00+00:00\",\"dateModified\":\"2023-11-23T17:03:39+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/b70352884e4ad6f2a76729e9051dd9f6\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2023\/11\/23\/la-vittoria-di-wilders-nei-paesi-bassi-i-partiti-a-destra-del-ppe-stanno-per-governare-in-5-paesi-europei\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/it\/2023\/11\/23\/la-vittoria-di-wilders-nei-paesi-bassi-i-partiti-a-destra-del-ppe-stanno-per-governare-in-5-paesi-europei\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2023\/11\/23\/la-vittoria-di-wilders-nei-paesi-bassi-i-partiti-a-destra-del-ppe-stanno-per-governare-in-5-paesi-europei\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2023\/11\/Screenshot-2023-11-23-alle-17.58.20.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2023\/11\/Screenshot-2023-11-23-alle-17.58.20.png\",\"width\":1314,\"height\":1436},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/2023\/11\/23\/la-vittoria-di-wilders-nei-paesi-bassi-i-partiti-a-destra-del-ppe-stanno-per-governare-in-5-paesi-europei\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/legrandcontinent.eu\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vittoria di Wilders nei Paesi Bassi: i partiti a destra del PPE stanno per governare in 5 Paesi europei\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/it\/\",\"name\":\"Il Grand Continent\",\"description\":\"La scala pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/b70352884e4ad6f2a76729e9051dd9f6\",\"name\":\"aburatti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fa34e55e0507c2ca67b9a65ed781903d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fa34e55e0507c2ca67b9a65ed781903d?s=96&d=mm&r=g\",\"caption\":\"aburatti\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vittoria di Wilders nei Paesi Bassi: i partiti a destra del PPE stanno per governare in 5 Paesi europei - Il Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/it\/2023\/11\/23\/la-vittoria-di-wilders-nei-paesi-bassi-i-partiti-a-destra-del-ppe-stanno-per-governare-in-5-paesi-europei\/","og_locale":"it_IT","og_type":"article","og_title":"Vittoria di Wilders nei Paesi Bassi: i partiti a destra del PPE stanno per governare in 5 Paesi europei - Il Grand Continent","og_description":"Il partito di estrema destra di Geert Wilders ha ottenuto una vittoria schiacciante nelle elezioni parlamentari olandesi di ieri, con un punteggio che dovrebbe garantirgli un posto nel governo. Questa \u00e8 l\u2019occasione per fare il punto sugli sconvolgimenti politici avvenuti nell\u2019Unione Europea quest\u2019autunno, a poco pi\u00f9 di sei mesi dalle elezioni europee del 2024.","og_url":"https:\/\/legrandcontinent.eu\/it\/2023\/11\/23\/la-vittoria-di-wilders-nei-paesi-bassi-i-partiti-a-destra-del-ppe-stanno-per-governare-in-5-paesi-europei\/","og_site_name":"Il Grand Continent","article_published_time":"2023-11-23T16:13:00+00:00","article_modified_time":"2023-11-23T17:03:39+00:00","og_image":[{"width":1314,"height":1436,"url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2023\/11\/Screenshot-2023-11-23-alle-17.58.20.png","type":"image\/png"}],"author":"aburatti","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"aburatti","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/it\/2023\/11\/23\/la-vittoria-di-wilders-nei-paesi-bassi-i-partiti-a-destra-del-ppe-stanno-per-governare-in-5-paesi-europei\/","url":"https:\/\/legrandcontinent.eu\/it\/2023\/11\/23\/la-vittoria-di-wilders-nei-paesi-bassi-i-partiti-a-destra-del-ppe-stanno-per-governare-in-5-paesi-europei\/","name":"Vittoria di Wilders nei Paesi Bassi: i partiti a destra del PPE stanno per governare in 5 Paesi europei - Il Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/it\/2023\/11\/23\/la-vittoria-di-wilders-nei-paesi-bassi-i-partiti-a-destra-del-ppe-stanno-per-governare-in-5-paesi-europei\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/it\/2023\/11\/23\/la-vittoria-di-wilders-nei-paesi-bassi-i-partiti-a-destra-del-ppe-stanno-per-governare-in-5-paesi-europei\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2023\/11\/Screenshot-2023-11-23-alle-17.58.20.png","datePublished":"2023-11-23T16:13:00+00:00","dateModified":"2023-11-23T17:03:39+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/b70352884e4ad6f2a76729e9051dd9f6"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/it\/2023\/11\/23\/la-vittoria-di-wilders-nei-paesi-bassi-i-partiti-a-destra-del-ppe-stanno-per-governare-in-5-paesi-europei\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/it\/2023\/11\/23\/la-vittoria-di-wilders-nei-paesi-bassi-i-partiti-a-destra-del-ppe-stanno-per-governare-in-5-paesi-europei\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/legrandcontinent.eu\/it\/2023\/11\/23\/la-vittoria-di-wilders-nei-paesi-bassi-i-partiti-a-destra-del-ppe-stanno-per-governare-in-5-paesi-europei\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2023\/11\/Screenshot-2023-11-23-alle-17.58.20.png","contentUrl":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2023\/11\/Screenshot-2023-11-23-alle-17.58.20.png","width":1314,"height":1436},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/it\/2023\/11\/23\/la-vittoria-di-wilders-nei-paesi-bassi-i-partiti-a-destra-del-ppe-stanno-per-governare-in-5-paesi-europei\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legrandcontinent.eu\/it\/"},{"@type":"ListItem","position":2,"name":"Vittoria di Wilders nei Paesi Bassi: i partiti a destra del PPE stanno per governare in 5 Paesi europei"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/it\/#website","url":"https:\/\/legrandcontinent.eu\/it\/","name":"Il Grand Continent","description":"La scala pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/b70352884e4ad6f2a76729e9051dd9f6","name":"aburatti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/legrandcontinent.eu\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fa34e55e0507c2ca67b9a65ed781903d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fa34e55e0507c2ca67b9a65ed781903d?s=96&d=mm&r=g","caption":"aburatti"}}]}},"lgc_categories":[{"id":2178,"name":"Dati critici","slug":"dati-critici"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/it\/wp-content\/uploads\/sites\/12\/2023\/11\/Screenshot-2023-11-23-alle-17.58.20.png","width":1314,"height":1436,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts\/15284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/users\/10633"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/comments?post=15284"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/posts\/15284\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/media\/15288"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/media?parent=15284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/categories?post=15284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/tags?post=15284"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/staff?post=15284"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/editorial_format?post=15284"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/serie?post=15284"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/audience?post=15284"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/it\/wp-json\/wp\/v2\/geo?post=15284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}