{"id":4371,"count":0,"description":"Cr\u00e9\u00e9 cardinal \u00e0 la surprise g\u00e9n\u00e9rale en 2023 par le pape Fran\u00e7ois \u2014 qui a \u00e9galement pr\u00e9fac\u00e9 son deuxi\u00e8me livre, <i><span style=\"font-weight: 400\">Le coeur ne se divise pas \u2014 <\/span><\/i><span style=\"font-weight: 400\">le cardinal Bustillo est r\u00e9put\u00e9 proche des gens ordinaires au sujet de la crise de l\u2019Eglise et mod\u00e9r\u00e9ment r\u00e9formateur.<\/span>","link":"https:\/\/legrandcontinent.eu\/fr\/p\/cardinal-francois-xavier-bustillo\/","name":"Cardinal Fran\u00e7ois-Xavier Bustillo","slug":"cardinal-francois-xavier-bustillo","taxonomy":"staff","meta":[],"acf":{"name_title":"Cardinal","first_name":"Fran\u00e7ois-Xavier","last_name":"Bustillo","key_figure_template":"cardinale","cardinal_type":["elettore"],"picture":273945,"job_role":"Ev\u00eaque d\u2019Ajaccio","lgc_editorial_staff":false,"full_description":"","side_image":273950,"side_text_1":"In Ipso Vita erat","side_text_2":"En Lui \u00e9tait la Vie","page_content":"<ol>\r\n \t<li style=\"font-weight: 400\"><span style=\"font-weight: 400\"><strong>Date de naissance (\u00e2ge) :<\/strong> N\u00e9 le 23 novembre 1968 (56 ans)<\/span><\/li>\r\n \t<li style=\"font-weight: 400\"><span style=\"font-weight: 400\"><strong>Lieu de naissance :<\/strong> Pampelune, Espagne<\/span><\/li>\r\n \t<li style=\"font-weight: 400\"><span style=\"font-weight: 400\"><strong>Nationalit\u00e9 :<\/strong> Franco-espagnol<\/span><\/li>\r\n \t<li style=\"font-weight: 400\"><span style=\"font-weight: 400\"><strong>Formation :<\/strong> Petit s\u00e9minaire basque ;\u00a0 Institut catholique de Toulouse (licence en th\u00e9ologie)<\/span><\/li>\r\n \t<li style=\"font-weight: 400\"><span style=\"font-weight: 400\"><strong>Fonctions dans l\u2019\u00c9glise :<\/strong> Ev\u00eaque d\u2019Ajaccio<\/span><\/li>\r\n \t<li style=\"font-weight: 400\"><span style=\"font-weight: 400\"><strong>\u00c9tat ou ordre :\u00a0<\/strong>Franciscain conventuel<\/span><\/li>\r\n \t<li style=\"font-weight: 400\"><span style=\"font-weight: 400\"><strong>Rang : <\/strong>Cardinal-pr\u00eatre du titre de Sainte-Marie Immacul\u00e9e de Lourdes \u00e0 Boccea<\/span><\/li>\r\n \t<li style=\"font-weight: 400\"><span style=\"font-weight: 400\"><strong>Cardinal \u00e9lecteur depuis le :<\/strong> 30 septembre 2023 (cr\u00e9\u00e9 par Fran\u00e7ois) <\/span><\/li>\r\n \t<li style=\"font-weight: 400\"><span style=\"font-weight: 400\"><strong>Cardinal \u00e9lecteur jusqu\u2019au :<\/strong> 26 novembre 2048<\/span><i>\u00a0<\/i><\/li>\r\n<\/ol>\r\n<h2><\/h2>\r\n<h2><b>Carri\u00e8re<\/b><\/h2>\r\n<span style=\"font-weight: 400\">N\u00e9 \u00e0 Pampelune, fils d\u2019un militaire, Espagnol de naissance, il entre tr\u00e8s jeune (10 ans) au petit s\u00e9minaire de la vall\u00e9e de Baztan, en Navarre basque. Apr\u00e8s son baccalaur\u00e9at, il rejoint \u00e0 17 ans les franciscains conventuels de Padoue, en V\u00e9n\u00e9tie. C\u2019est dans cet ordre qu\u2019il fait sa profession solennelle en 1992, puis qu\u2019il est ordonn\u00e9 pr\u00eatre deux ans plus tard. Dipl\u00f4m\u00e9 de l\u2019Institut th\u00e9ologique Saint-Antoine Docteur de Padoue, il est aussi envoy\u00e9 se former en France, o\u00f9 il est licenci\u00e9 en th\u00e9ologie de l\u2019Institut catholique de Toulouse. \u00c0 Narbonne, il cofonde un nouveau couvent franciscain, et devient simultan\u00e9ment cur\u00e9 de paroisse (1994-2007). Il obtient en 2006 la nationalit\u00e9 fran\u00e7aise. Il devient ensuite sup\u00e9rieur provincial des franciscains conventuels pour la France et la Belgique (2006-2018), puis gardien du couvent franciscain de Lourdes (2018-2021), tout en occupant d\u2019autres fonctions d\u2019encadrement dans les dioc\u00e8se de Narbonne-Carcassonne puis de Tarbes-Lourdes, notamment de d\u00e9l\u00e9gu\u00e9 \u00e9piscopal \u00e0 la protection des mineurs dans ce dernier dioc\u00e8se.<\/span>\r\n\r\n<span style=\"font-weight: 400\">En mai 2021, il est nomm\u00e9 \u00e9v\u00eaque d\u2019Ajaccio, et re\u00e7oit la cons\u00e9cration \u00e9piscopale de Jean-Marc Aveline, archev\u00eaque de Marseille. En 2023, le pape Fran\u00e7ois annonce qu\u2019il est cr\u00e9\u00e9 cardinal, \u00e0 la surprise g\u00e9n\u00e9rale, puisqu\u2019il n\u2019y a jamais eu de cardinaux titulaires du si\u00e8ge d\u2019Ajaccio, longtemps r\u00e9put\u00e9 mineur (les cardinaux de la famille Bonaparte ayant des si\u00e8ges plus prestigieux). Le pape Fran\u00e7ois lui offre un dernier et \u00e9clatant signe de faveur en lui rendant visite \u00e0 Ajaccio pour son ultime visite apostolique, \u00e0 l\u2019occasion d\u2019un colloque sur la religion populaire en M\u00e9diterran\u00e9e, un th\u00e8me cher au c\u0153ur du pape, qui a \u00e9galement pr\u00e9fac\u00e9 son deuxi\u00e8me livre, <\/span><i><span style=\"font-weight: 400\">Le coeur ne se divise pas<\/span><\/i><span style=\"font-weight: 400\">. \u00c0 la Curie romaine, il est membre du Dicast\u00e8re pour le clerg\u00e9.\u00a0<\/span>\r\n<h2><b>Profil<\/b><\/h2>\r\n<span style=\"font-weight: 400\">Pr\u00e9lat \u00e0 la faveur soudaine, renomm\u00e9 pour sa simplicit\u00e9 et sa spiritualit\u00e9 int\u00e9rieure, le cardinal Bustillo a beaucoup r\u00e9fl\u00e9chi aux enjeux de la pr\u00e9sence de l\u2019Eglise dans les nations d\u2019origine chr\u00e9tiennes s\u00e9cularis\u00e9es, et revendique la fid\u00e9lit\u00e9 cr\u00e9atrice et une attitude confiante et proche des gens ordinaires au sujet de la crise de l\u2019Eglise ; il a un ancrage r\u00e9solument m\u00e9diterran\u00e9en qui ne peut que plaire au pape Fran\u00e7ois, lequel a offert son premier livre, <\/span><i><span style=\"font-weight: 400\">T\u00e9moins, pas fonctionnaires<\/span><\/i><span style=\"font-weight: 400\">, \u00e0 tous les cardinaux en 2022. Sa ligne peut \u00eatre consid\u00e9r\u00e9e comme \u201cunitaire\u201d et mod\u00e9r\u00e9ment r\u00e9formatrice. Mais il ne compte pas que des amis au sein de l\u2019Eglise de France, o\u00f9 il a pu \u00eatre accus\u00e9 de faire cavalier seul.\u00a0<\/span>","linkedin_url":"","twitter_url":"","articles_authored":"","articles_interviewed":"","articles_speech_author":"","books_authored":"","events_authored":"","videos_authored":"","posts_related":"","events_related":"","elections_related":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cardinal Fran\u00e7ois-Xavier Bustillo | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/p\/cardinal-francois-xavier-bustillo\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cardinal Fran\u00e7ois-Xavier Bustillo | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Cr\u00e9\u00e9 cardinal \u00e0 la surprise g\u00e9n\u00e9rale en 2023 par le pape Fran\u00e7ois \u2014 qui a \u00e9galement pr\u00e9fac\u00e9 son deuxi\u00e8me livre, Le coeur ne se divise pas \u2014 le cardinal Bustillo est r\u00e9put\u00e9 proche des gens ordinaires au sujet de la crise de l\u2019Eglise et mod\u00e9r\u00e9ment r\u00e9formateur.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/p\/cardinal-francois-xavier-bustillo\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/p\/cardinal-francois-xavier-bustillo\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/p\/cardinal-francois-xavier-bustillo\/\",\"name\":\"Cardinal Fran\u00e7ois-Xavier Bustillo | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/p\/cardinal-francois-xavier-bustillo\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/p\/cardinal-francois-xavier-bustillo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cardinal Fran\u00e7ois-Xavier Bustillo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cardinal Fran\u00e7ois-Xavier Bustillo | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/p\/cardinal-francois-xavier-bustillo\/","og_locale":"fr_FR","og_type":"article","og_title":"Cardinal Fran\u00e7ois-Xavier Bustillo | Le Grand Continent","og_description":"Cr\u00e9\u00e9 cardinal \u00e0 la surprise g\u00e9n\u00e9rale en 2023 par le pape Fran\u00e7ois \u2014 qui a \u00e9galement pr\u00e9fac\u00e9 son deuxi\u00e8me livre, Le coeur ne se divise pas \u2014 le cardinal Bustillo est r\u00e9put\u00e9 proche des gens ordinaires au sujet de la crise de l\u2019Eglise et mod\u00e9r\u00e9ment r\u00e9formateur.","og_url":"https:\/\/legrandcontinent.eu\/fr\/p\/cardinal-francois-xavier-bustillo\/","og_site_name":"Le Grand Continent","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/legrandcontinent.eu\/fr\/p\/cardinal-francois-xavier-bustillo\/","url":"https:\/\/legrandcontinent.eu\/fr\/p\/cardinal-francois-xavier-bustillo\/","name":"Cardinal Fran\u00e7ois-Xavier Bustillo | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/p\/cardinal-francois-xavier-bustillo\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/p\/cardinal-francois-xavier-bustillo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Cardinal Fran\u00e7ois-Xavier Bustillo"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"first_name":"Fran\u00e7ois-Xavier","last_name":"Bustillo","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/04\/Francois-Xavier-Bustillo-scaled.jpg","width":2560,"height":1819,"alt":""},"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff\/4371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/taxonomies\/staff"}],"wp:post_type":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts?staff=4371"},{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/sunday?staff=4371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}