{"id":4365,"count":0,"description":"<span style=\"font-weight: 400\">Missionnaire polyglotte, attach\u00e9 \u00e0 une \u00c9glise diasporique, le cardinal Bytchok est un symbole des orientations bergogliennes en tant que \u00abfaiseur de pont\u00bb, mais il demeure un outsider.<\/span>","link":"https:\/\/legrandcontinent.eu\/fr\/p\/cardinal-mykola-bytchok\/","name":"Cardinal Mykola Bytchok","slug":"cardinal-mykola-bytchok","taxonomy":"staff","meta":[],"acf":{"name_title":"Cardinal","first_name":"Mykola","last_name":"Bytchok","key_figure_template":"cardinale","cardinal_type":["elettore"],"picture":273930,"job_role":"\u00c9v\u00eaque de l\u2019\u00e9parchie gr\u00e9co-catholique ukrainienne de Melbourne","lgc_editorial_staff":false,"full_description":"","side_image":273931,"side_text_1":"","side_text_2":"Tr\u00e8s Sainte M\u00e8re de Dieu, sauve-nous","page_content":"<ol>\r\n \t<li style=\"font-weight: 400\"><span style=\"font-weight: 400\"><strong>Date de naissance (\u00e2ge) :<\/strong> N\u00e9 le 13 f\u00e9vrier 1980 (45 ans)<\/span><\/li>\r\n \t<li style=\"font-weight: 400\"><span style=\"font-weight: 400\"><strong>Lieu de naissance :<\/strong> Ternopil, Ukraine<\/span><\/li>\r\n \t<li style=\"font-weight: 400\"><span style=\"font-weight: 400\"><strong>Nationalit\u00e9 :<\/strong> Ukraino-Australien<\/span><\/li>\r\n \t<li style=\"font-weight: 400\"><span style=\"font-weight: 400\"><strong>Formation :<\/strong> S\u00e9minaire r\u00e9demptoriste, licence en th\u00e9ologie pastorale<\/span><\/li>\r\n \t<li style=\"font-weight: 400\"><span style=\"font-weight: 400\"><strong>Fonctions dans l\u2019\u00c9glise : <\/strong>\u00c9v\u00eaque de l\u2019\u00e9parchie gr\u00e9co-catholique ukrainienne Saints-Pierre-et-Paul de Melbourne<\/span><\/li>\r\n \t<li style=\"font-weight: 400\"><span style=\"font-weight: 400\"><strong>\u00c9tat ou ordre :\u00a0<\/strong>R\u00e9demptoriste<\/span><\/li>\r\n \t<li style=\"font-weight: 400\"><span style=\"font-weight: 400\"><strong>Rang :<\/strong>Cardinal-pr\u00eatre du titre de Sainte-Sophie a Via Boccea<\/span><\/li>\r\n \t<li style=\"font-weight: 400\"><span style=\"font-weight: 400\"><strong>Cardinal \u00e9lecteur depuis le :<\/strong> 7 d\u00e9cembre 2024 (cr\u00e9\u00e9 par Fran\u00e7ois) <\/span><\/li>\r\n \t<li style=\"font-weight: 400\"><span style=\"font-weight: 400\"><strong>Cardinal \u00e9lecteur jusqu\u2019au :<\/strong> 13 f\u00e9vrier 2060<\/span><i>\u00a0<\/i><\/li>\r\n<\/ol>\r\n<h2><\/h2>\r\n<h2><b>Carri\u00e8re<\/b><\/h2>\r\n<span style=\"font-weight: 400\">N\u00e9 \u00e0 Ternopil en Ukraine occidentale, il rejoint tr\u00e8s jeune la congr\u00e9gation des R\u00e9demptoristes, s\u2019engageant dans leur ordre d\u00e8s juillet 1997. Apr\u00e8s son noviciat et une formation sacerdotale en Pologne et en Ukraine, il y prononce ses v\u0153ux perp\u00e9tuels en 2003. Il est ordonn\u00e9 pr\u00eatre le 3 mai 2005. Il est d\u2019abord envoy\u00e9 comme missionnaire en Russie, aupr\u00e8s des catholiques russe de rite oriental, \u00e0 Prokopievsk (Sib\u00e9rie occidentale). Il revient en Ukraine, \u00e0 Ivano-Frankivsk (Ouest) o\u00f9 il est cur\u00e9 de paroisse, sup\u00e9rieur du monast\u00e8re Saint-Joseph des r\u00e9demptoristes,\u00a0 et \u00e9conome de la province r\u00e9demptoriste de Lviv. Entre 2015 et 2020, il s\u00e9journe aux Etats-Unis, o\u00f9 il est vicaire de la paroisse ukrainienne de Saint-Jean-Baptiste de Newark (New Jersey), un dioc\u00e8se dont l\u2019archev\u00eaque, le cardinal Tobin, partage la ligne du pape Fran\u00e7ois. En 2020, le pape Fran\u00e7ois le nomme \u00e9v\u00eaque d\u2019une \u00e9parchie (dioc\u00e8se de rite catholique oriental) dans le monde occidental, l\u2019\u00e9parchie St-Pierre-et-Paul de Melbourne, qui a juridiction sur tous les fid\u00e8les de rite gr\u00e9co-catholique ukrainien en Australie, Nouvelle-Z\u00e9lande et dans le reste de l\u2019Oc\u00e9anie. Il re\u00e7oit la cons\u00e9cration \u00e9piscopale dans la cath\u00e9drale de Lviv en juin 2020 des mains de Mgr. Shevchuk, primat de l\u2019Eglise gr\u00e9co-catholique ukrainienne. En d\u00e9cembre 2024, le pape Fran\u00e7ois le cr\u00e9e cardinal, ce qui fait de lui le plus jeune cardinal, et le plus jeune (44 ans) \u00e0 sa date de cr\u00e9ation depuis pr\u00e8s d\u2019un si\u00e8cle (1927). Cette nomination \u00e9tonnante peut \u00eatre interpr\u00e9t\u00e9e comme un coup m\u00e9diatique du pape Fran\u00e7ois, \u00e0 qui il a \u00e9t\u00e9 reproch\u00e9 de n\u2019avoir pas cr\u00e9\u00e9 cardinal Mgr. Shevchuk, archev\u00eaque majeur de Kiev, pour des raisons oecum\u00e9niques (les orthodoxes ne voyant pas d\u2019un bon \u0153il les \u00c9glises \u201cuniates\u201d) et g\u00e9opolitiques (ne pas froisser la Russie). Le cardinalat de Mgr. Bytchok, moins expos\u00e9, est donc un geste de sollicitude pastorale en direction des Ukrainiens de la diaspora, et en m\u00eame temps un discret message de soutien \u00e0 l\u2019Ukraine par des voies d\u00e9tourn\u00e9es. En janvier 2025, il est nomm\u00e9 membre du Dicast\u00e8re pour la culture et l'\u00c9ducation \u00e0 la Curie romaine ; il a \u00e9galement re\u00e7u des distinctions dans l\u2019Ordre de Malte.<\/span>\r\n<h2><b>Profil<\/b><\/h2>\r\n<span style=\"font-weight: 400\">Missionnaire polyglotte, attach\u00e9 \u00e0 une \u00c9glise diasporique, qui est \u00e0 la fois p\u00e9riph\u00e9rique par sa situation aux antipodes, son rite oriental et ses effectifs r\u00e9duits (pr\u00e8s de 7000 fid\u00e8les r\u00e9partis dans 11 paroisses et tr\u00e8s \u00e9parpill\u00e9s), et centrale par les d\u00e9chirements et l\u2019exil auxquels elle renvoie, le cardinal Bytchok incarne beaucoup d\u2019orientations bergogliennes. Ukrainien de naissance, de c\u0153ur et de langue liturgique, il a une exp\u00e9rience missionnaire en Russie comme aux Etats-Unis, avant l\u2019Australie : c\u2019est dire \u00e0 quel point le pape Fran\u00e7ois, en l\u2019\u00e9levant de mani\u00e8re inattendue \u00e0 la pourpre cardinalice, a promu un faiseur de ponts. Cela est peut-\u00eatre aussi sa limite : d\u2019un cardinal symbole, on ne fait pas un cardinal central, mais un outsider.<\/span>","linkedin_url":"","twitter_url":"","articles_authored":"","articles_interviewed":"","articles_speech_author":"","books_authored":"","events_authored":"","videos_authored":"","posts_related":"","events_related":"","elections_related":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cardinal Mykola Bytchok | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/p\/cardinal-mykola-bytchok\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cardinal Mykola Bytchok | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Missionnaire polyglotte, attach\u00e9 \u00e0 une \u00c9glise diasporique, le cardinal Bytchok est un symbole des orientations bergogliennes en tant que \u00abfaiseur de pont\u00bb, mais il demeure un outsider.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/p\/cardinal-mykola-bytchok\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/p\/cardinal-mykola-bytchok\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/p\/cardinal-mykola-bytchok\/\",\"name\":\"Cardinal Mykola Bytchok | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/p\/cardinal-mykola-bytchok\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/p\/cardinal-mykola-bytchok\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cardinal Mykola Bytchok\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cardinal Mykola Bytchok | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/p\/cardinal-mykola-bytchok\/","og_locale":"fr_FR","og_type":"article","og_title":"Cardinal Mykola Bytchok | Le Grand Continent","og_description":"Missionnaire polyglotte, attach\u00e9 \u00e0 une \u00c9glise diasporique, le cardinal Bytchok est un symbole des orientations bergogliennes en tant que \u00abfaiseur de pont\u00bb, mais il demeure un outsider.","og_url":"https:\/\/legrandcontinent.eu\/fr\/p\/cardinal-mykola-bytchok\/","og_site_name":"Le Grand Continent","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/legrandcontinent.eu\/fr\/p\/cardinal-mykola-bytchok\/","url":"https:\/\/legrandcontinent.eu\/fr\/p\/cardinal-mykola-bytchok\/","name":"Cardinal Mykola Bytchok | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/p\/cardinal-mykola-bytchok\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/p\/cardinal-mykola-bytchok\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Cardinal Mykola Bytchok"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"first_name":"Mykola","last_name":"Bytchok","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/04\/Mykola-Bychok-scaled.jpg","width":2560,"height":1705,"alt":""},"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff\/4365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/taxonomies\/staff"}],"wp:post_type":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts?staff=4365"},{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/sunday?staff=4365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}