{"id":9808,"date":"2018-04-15T19:53:10","date_gmt":"2018-04-15T17:53:10","guid":{"rendered":"https:\/\/legrandcontinent.eu\/?p=9808"},"modified":"2019-04-07T04:16:53","modified_gmt":"2019-04-07T02:16:53","slug":"le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/","title":{"rendered":"Le Danemark p\u00e9riph\u00e9rique"},"content":{"rendered":"\n<p class=\"has-drop-cap\"><em>Traditionnellement marqu\u00e9 par un Etat-Providence fort et une structure politico-administrative unitaire, le Danemark a longtemps garanti le principe d\u2019\u00e9galit\u00e9 territoriale \u00e0 ses diff\u00e9rents d\u00e9partements, notamment gr\u00e2ce \u00e0 des m\u00e9canismes de solidarit\u00e9 financi\u00e8re intrar\u00e9gionaux. <\/em><br><\/p>\n\n\n\n<p><em>Mais depuis le dernier quart du XXe si\u00e8cle, les dynamiques spatiales de la mondialisation \u00e9conomique ont finalement atteint le Danemark en entra\u00eenant la m\u00e9tropolisation des grandes aires urbaines (Copenhague et Aarhus principalement), et fait appara\u00eetre des zones p\u00e9riph\u00e9riques o\u00f9 revenu par habitant, lignes ferroviaires et cr\u00e9ation d\u2019emplois ne cessent de reculer&#160;: c\u2019est la \u2039\u2039 banane pourrie \u203a\u203a. <\/em><br><\/p>\n\n\n\n<p><em>Ce nouveau mod\u00e8le in\u00e9galitaire de d\u00e9veloppement a contribu\u00e9 \u00e0 l\u2019\u00e9mergence dans le champ politique et les m\u00e9dias de la notion d\u2019\u2039\u2039 Udkantsdanmark \u203a\u203a, le \u2039\u2039 Danemark p\u00e9riph\u00e9rique \u203a\u203a qui ressemble tr\u00e8s fortement aux pol\u00e9miques et d\u00e9bats hexagonaux sur la \u2039\u2039 France p\u00e9riph\u00e9rique \u203a\u203a. <\/em><br><\/p>\n\n\n\n<p><em>Cet article se propose de montrer comment les territoires fran\u00e7ais et danois sont soumis aux m\u00eames dynamiques spatiales \u00e0 l\u2019\u00e9chelle europ\u00e9enne et construisent la m\u00eame interrogation politique sur l\u2019avenir de l\u2019\u00e9galit\u00e9 sociale et territoriale dans les d\u00e9mocraties occidentales.<\/em><\/p>\n\n\n\n<p>En France, nous connaissons dans le domaine de l\u2019anthropologie et de la g\u00e9ographie sociale la notion d\u2019\u2039\u2039 exils int\u00e9rieurs \u203a\u203a, exploit\u00e9e par les analyses d\u00e9mographiques d\u2019<a href=\"https:\/\/legrandcontinent.eu\/2018\/01\/08\/il-a-une-vie-apres-la-democratie-entretien-avec-emmanuel-todd\/\">Emmanuel Todd<\/a> et de <a href=\"https:\/\/legrandcontinent.eu\/2017\/04\/09\/nous-avons-rencontre-herve-le-bras\/\">Herv\u00e9 Le Bras<\/a>&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-1-9808' title='Herv\u00e9 Le Bras, Emmanuel Todd, &lt;em&gt;Le myst\u00e8re fran\u00e7ais&lt;\/em&gt;, Le Seuil, Paris, 2013. Voir le chapitre 6, &lt;em&gt;L\u2019exil des classes populaires&lt;\/em&gt;.'><sup>1<\/sup><\/a><\/span><\/span>. Elle caract\u00e9rise les nouvelles stratifications de la soci\u00e9t\u00e9 fran\u00e7aise par la relocalisation en zones p\u00e9riph\u00e9riques de nombreuses cat\u00e9gories populaires. Ce ph\u00e9nom\u00e8ne serait imputable aux dynamiques spatiales cr\u00e9\u00e9es par la mondialisation et la m\u00e9tropolisation&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-2-9808' title='Ph\u00e9nom\u00e8ne d\u00e9signant la concentration des fonctions de commandement politico-\u00e9conomique dans les principaux centres urbains, entra\u00eenant la tertiarisation de l\u2019emploi.'><sup>2<\/sup><\/a><\/span><\/span>&#160;: loin des centres de la d\u00e9cision \u00e9conomique et politique, les ouvriers ont quitt\u00e9 les villes pour les zones p\u00e9ri-urbaines et rurales (r\u00e9cemment accompagn\u00e9s par les employ\u00e9s), \u2039\u2039 les professions culturellement domin\u00e9es [se r\u00e9fugiant] \u00e0 la campagne \u203a\u203a&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-3-9808' title='Herv\u00e9 Le Bras, Emmanuel Todd, &lt;em&gt;Le myst\u00e8re fran\u00e7ais&lt;\/em&gt;, Le Seuil, Paris, 2013, p. 168.'><sup>3<\/sup><\/a><\/span><\/span>. La migration int\u00e9rieure r\u00e9v\u00e8lerait les disparit\u00e9s territoriales qui distinguent d\u2019une part les centres urbains o\u00f9 se cr\u00e9e la richesse \u00e9conomique, compos\u00e9s des (nouvelles) classes moyennes sup\u00e9rieures (la \u2039\u2039 gentrification \u203a\u203a&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-4-9808' title='Sur ce sujet, voir Anne Clerval, &lt;em&gt;Paris sans le peuple&lt;\/em&gt;, La D\u00e9couverte, Paris, 2013.'><sup>4<\/sup><\/a><\/span><\/span>) et de classes populaires majoritairement d\u2019origine \u00e9trang\u00e8re r\u00e9cente&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-5-9808' title='Il faut nuancer ce sch\u00e9ma dans la mesure o\u00f9 il existe aussi des ph\u00e9nom\u00e8nes de pr\u00e9carisation au sein m\u00eames des classes dites moyennes sup\u00e9rieures urbaines, comme les \u00e9tudiants soumis \u00e0 la baisse des salaires.'><sup>5<\/sup><\/a><\/span><\/span><span style=\"font-size: 13.3333px\">,<\/span> d\u2019autre part les espaces en voie de marginalisation socio-\u00e9conomique o\u00f9 se reconstitueraient des classes sociales majoritairement compos\u00e9es d\u2019ouvriers et d\u2019employ\u00e9s refoul\u00e9s hors des grandes villes.<br><\/p>\n\n\n\n<p>Cette partition latente de la g\u00e9ographie sociale et anthropologique fran\u00e7aise pr\u00e9suppose de remettre en cause la viabilit\u00e9 m\u00eame de la notion de \u2039\u2039 classe moyenne \u203a\u203a et la persistance d\u2019un \u2039\u2039 mod\u00e8le r\u00e9publicain \u203a\u203a cens\u00e9 garantir universellement la capacit\u00e9 des individus \u00e0 \u2039\u2039 monter \u203a\u203a sur l\u2019\u00e9chelle sociale. Ainsi, \u00e0 l\u2019instar d\u2019autres pays occidentaux, l\u2019id\u00e9al pavillonnaire et individuel d\u2019une grande partie de la population fran\u00e7aise, ayant acc\u00e9d\u00e9 \u00e0 la classe moyenne apr\u00e8s la Seconde Guerre mondiale, tendrait \u00e0 dispara\u00eetre \u00e0 cause de cette fragilisation socio-\u00e9conomique. La transformation dans le d\u00e9bat public et la sph\u00e8re m\u00e9diatique de ces enjeux a d\u00e9bouch\u00e9, depuis le d\u00e9but des ann\u00e9es 2010, sur le r\u00e9emploi, \u00e9lectoral et pol\u00e9mique, de l\u2019expression de \u2039\u2039 France p\u00e9riph\u00e9rique \u203a\u203a&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-6-9808' title='Christophe Guilluy, &lt;em&gt;La France p\u00e9riph\u00e9rique. Comment on a sacrifi\u00e9 les classes populaires&lt;\/em&gt;, Paris, Flammarion, 2014, 192 p.'><sup>6<\/sup><\/a><\/span><\/span>, dont la r\u00e9ception acad\u00e9mique, tr\u00e8s discut\u00e9e&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-7-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-7-9808' title='Voici un exemple de recension critique qui exprime des r\u00e9serves et met en valeurs les critiques faites \u00e0 Guilluy&amp;#160;: &lt;a href=&quot;http:\/\/www.laviedesidees.fr\/Une-France-contre-l-autre.html#nb8&quot;&gt;http:\/\/www.laviedesidees.fr\/Une-France-contre-l-autre.html&lt;\/a&gt;.'><sup>7<\/sup><\/a><\/span><\/span>, continue de structurer la vie politique fran\u00e7aise dans son rapport \u00e0 la mondialisation et \u00e0 la construction communautaire.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/PB184279.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"1600\"\n        data-pswp-height=\"1200\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/PB184279-330x248.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/PB184279-690x518.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/PB184279-1340x1005.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/PB184279-125x94.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Dans le village d&rsquo;Abild (R\u00e9gion Danemark du Sud) o\u00f9 l&rsquo;on craint de fermer l&rsquo;\u00e9cole communale, une pancarte proclame, par un jeu de mot, u0022D\u00e9veloppement plut\u00f4t que r\u00e9gressionu0022<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>Dans la mesure o\u00f9 ces migrations internes et cette fragilisation sociale sont directement li\u00e9es aux effets de la mondialisation (d\u00e9sindustrialisation et m\u00e9tropolisation)&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-8-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-8-9808' title='Pour comprendre les effets de la m\u00e9tropolisation&amp;#160;: &lt;a href=&quot;https:\/\/humanite.fr\/anne-clerval-paris-le-discours-sur-la-mixite-sociale-remplace-la-lutte-des-classes&quot;&gt;https:\/\/humanite.fr\/anne-clerval-paris-le-discours-sur-la-mixite-sociale-remplace-la-lutte-des-classes&lt;\/a&gt;.'><sup>8<\/sup><\/a><\/span><\/span>, il est \u00e9galement possible d\u2019observer les m\u00eames dynamiques dans les autres pays occidentaux, au Royaume-Uni, au Benelux, en Scandinavie ou aux \u00c9tats-Unis. Au Danemark, tant sur le plan m\u00e9diatique que dans la sph\u00e8re acad\u00e9mique, il existe un \u2039\u2039 Danemark p\u00e9riph\u00e9rique \u203a\u203a dont les \u00e9volutions socio-\u00e9conomiques des cinquante derni\u00e8res ann\u00e9es demeurent analogues \u00e0 celle des territoires m\u00e9tropolitains fran\u00e7ais, conform\u00e9ment au constat de Todd et de Le Bras. <\/p>\n\n\n\n<p>C\u2019est un Danemark angoiss\u00e9&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-9-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-9-9808' title='L\u2019angoisse d\u2019une part importante de la population danoise face \u00e0 la construction europ\u00e9enne ou \u00e0 la mondialisation et le bouleversement du spectre politique danois avec l\u2019arriv\u00e9e du populisme d\u2019extr\u00eame-droite d\u00e8s les ann\u00e9es 1990 est \u00e0 rapprocher du \u2039\u2039 malaise politique fran\u00e7ais \u203a\u203a analys\u00e9 par Todd&amp;#160;: Emmanuel Todd, \u00ab&amp;#160;Aux origines du malaise politique fran\u00e7ais. Les classes sociales et leur repr\u00e9sentation&amp;#160;\u00bb, &lt;em&gt;Le D\u00e9bat&lt;\/em&gt;, 1995\/1 (n\u00b0 83), p. 82-103.'><sup>9<\/sup><\/a><\/span><\/span> que la mondialisation d\u00e9savantage toujours plus en y faisant r\u00e9gresser la cr\u00e9ation d\u2019emplois, un Danemark nostalgique de l\u2019\u00e2ge d\u2019or de la social-d\u00e9mocratie et qui opte parfois pour le discours social et identitaire du <em>Dansk Folkeparti<\/em>&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-10-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-10-9808' title='Principale formation de l\u2019extr\u00eame-droite danoise fond\u00e9e en 1995 sur la dissolution du Parti du Progr\u00e8s, parti lib\u00e9ral anti-taxe (de sensibilit\u00e9 reaganienne) devenu islamophobe et anti-immigration dans les ann\u00e9es 1980. Sa particularit\u00e9 est d\u2019avoir adopter d\u00e8s la fin des ann\u00e9es 1990 un discours social de d\u00e9fense de l\u2019Etat-Providence associ\u00e9 \u00e0 une politique restrictive envers l\u2019immigration. Il s\u2019agit d\u2019un populisme extr\u00eame-droitier arch\u00e9typal \u00e0 l\u2019\u00e9chelle de l\u2019Europe occidentale dans la mesure o\u00f9 sa strat\u00e9gie \u00e9lectorale repose, comme pour le lep\u00e9nisme social, sur l\u2019emprunt \u00e0 la gauche des th\u00e8mes de la d\u00e9mocratie et de la souverainet\u00e9 populaire au moment o\u00f9 les formations de gauche gouvernementale abandonnent ces th\u00e8mes et se convertissent au lib\u00e9ralisme \u00e9conomique. Aux \u00e9lections g\u00e9n\u00e9rales de 2015, DF est arriv\u00e9e en seconde position derri\u00e8re les sociaux-d\u00e9mocrates avec 21,1&amp;#160;% des voix.'><sup>10<\/sup><\/a><\/span><\/span>, ou choisit plus rarement de faire confiance \u00e0 la gauche anti-lib\u00e9rale&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-11-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-11-9808' title='Pour l\u2019analyse du paysage politico-\u00e9lectoral danois, voir&amp;#160;: &lt;a href=&quot;https:\/\/www.academia.edu\/14321855\/Denmark_s_Nativist_Threat_-_Jacobin&quot;&gt;https:\/\/www.academia.edu\/14321855\/Denmark_s_Nativist_Threat_-_Jacobin&lt;\/a&gt;.'><sup>11<\/sup><\/a><\/span><\/span>, voire aux formations traditionnelles qui promettent le retour de la prosp\u00e9rit\u00e9.<br><\/p>\n\n\n\n<p>La ressemblance avec la France est si forte que m\u00eame l\u2019apparition du concept de \u2039\u2039 Danemark p\u00e9riph\u00e9rique \u203a\u203a y a connu un destin analogue&#160;: la notion de \u2039\u2039 <em>Udkantsdanmark<\/em> \u203a\u203a est devenu un th\u00e8me r\u00e9current dans les m\u00e9dias danois au d\u00e9but des ann\u00e9es 2010 (m\u00eame s\u2019il est apparu pour la premi\u00e8re fois en 1992 dans le <em>Weekendavisen<\/em>&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-12-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-12-9808' title='Voir l\u2019article du g\u00e9ographe Nicolas Escach dans &lt;em&gt;Le Monde diplomatique&lt;\/em&gt;, l\u2019une des rares publications francophones sur le sujet&amp;#160;: &lt;a href=&quot;https:\/\/www.monde-diplomatique.fr\/2017\/04\/ESCACH\/57351&quot;&gt;https:\/\/www.monde-diplomatique.fr\/2017\/04\/ESCACH\/57351&lt;\/a&gt;.'><sup>12<\/sup><\/a><\/span><\/span>). La recherche universitaire s\u2019est timidement pench\u00e9e dessus afin de nuancer le tableau n\u00e9gatif souvent dress\u00e9 des p\u00e9riph\u00e9ries danoises&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-13-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-13-9808' title='Cet article se fonde en grande partie sur un m\u00e9moire d\u2019anthropologie en danois&amp;#160;: Line Schmidt Hendriksen, &lt;em&gt;At leve med \u2019Udkantsdanmark\u2019 \u2013 diskursens magt i problematikken omkring udkantsdanmark&lt;\/em&gt;, octobre 2012, Anthropologie, Aarhus Universitet.'><sup>13<\/sup><\/a><\/span><\/span>.<br><\/p>\n\n\n\n<p>Le pr\u00e9sent article propose de comprendre comment deux pays d\u2019Europe occidentale ayant connu des \u00e9volutions sociales analogues, la France et le Danemark, ont pu faire \u00e9merger dans les \u2039\u2039 d\u00e9bats publics \u203a\u203a les m\u00eames concepts \u00e0 la m\u00eame \u00e9poque et refl\u00e9ter des \u00e9volutions socio-spatiales similaires. Les soci\u00e9t\u00e9s fran\u00e7aise et danoise, aux yeux comparatifs d\u2019un anthropologue, d\u2019un sociologue ou d\u2019un g\u00e9ographe, partagent \u00e9tonnamment \u00e0 peu pr\u00e8s les m\u00eames traits g\u00e9n\u00e9raux, au point qu\u2019il serait possible de d\u00e9crire les \u00e9volutions sociales g\u00e9n\u00e9rales en interchangeant les adjectifs \u2039\u2039 danois \u203a\u203a et \u2039\u2039 fran\u00e7ais. \u203a\u203a Certes, la diff\u00e9rence d\u2019\u00e9chelle, modifiant le champ d\u2019action des politiques territoriales et leur compr\u00e9hension&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-14-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-14-9808' title='La France m\u00e9tropolitaine s\u2019\u00e9tend sur 551 500 km&lt;sup&gt;2&lt;\/sup&gt; alors que le Danemark m\u00e9tropolitain ne fait que 43 094 km&lt;sup&gt;2&lt;\/sup&gt;.'><sup>14<\/sup><\/a><\/span><\/span>, constitue une limite bien r\u00e9elle \u00e0 cette comparaison. Mais, et c\u2019est le c\u0153ur de l\u2019analyse, les disparit\u00e9s sociales, spatiales et \u00e9conomiques engendr\u00e9es par la pression qu\u2019exercent le n\u00e9olib\u00e9ralisme et la mondialisation en tant que mod\u00e8les in\u00e9galitaires de d\u00e9veloppement, peuvent appara\u00eetre relativement bien \u00ab&#160;amorties&#160;\u00bb au Danemark gr\u00e2ce au r\u00f4le toujours puissant de l\u2019\u00c9tat-Providence&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-15-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-15-9808' title='La pression sur l\u2019\u00c9tat-Providence est \u00e9galement li\u00e9e \u00e0 un facteur politique&amp;#160;: la coalition gouvernementale de droite lib\u00e9rale, mais aussi le centre-gauche, cherche \u00e0 r\u00e9duire les d\u00e9penses publiques et la place traditionnellement forte des politiques sociales au Danemark.'><sup>15<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/DSC00321.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"1600\"\n        data-pswp-height=\"1200\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/DSC00321-330x248.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/DSC00321-690x518.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/DSC00321-1340x1005.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/DSC00321-125x94.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Maisons abandonn\u00e9es ou \u00e0 vendre, magasins ferm\u00e9s sont plus courants dans le Danemark p\u00e9riph\u00e9rique qu&rsquo;ailleurs<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>Il s\u2019agit donc bien de comprendre en quoi l\u2019\u00c9tat social a continu\u00e9, en France comme au Danemark&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-16-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-16-9808' title='Voir le passage sur les structures familiales danoises dans notre entretien avec Emmanuel Todd&amp;#160;: &lt;a href=&quot;https:\/\/legrandcontinent.eu\/2018\/01\/17\/hybris-allemand-entretien-avec-emmanuel-todd\/&quot;&gt;https:\/\/legrandcontinent.eu\/2018\/01\/17\/hybris-allemand-entretien-avec-emmanuel-todd\/&lt;\/a&gt;.'><sup>16<\/sup><\/a><\/span><\/span><a href=\"#_ftn16\"><\/a>, d\u2019exercer, ne serait-ce que partiellement ou sectoriellement, un mod\u00e8le r\u00e9sistant aux dynamiques in\u00e9galitaires. Contrairement aux repr\u00e9sentations collectives qui tendent \u00e0 s\u00e9parer en deux mondes de \u2039\u2039 raisonnables et modernes \u203a\u203a pays nordiques \u2039\u2039 qui auraient fait les r\u00e9formes \u203a\u203a et la France \u2039\u2039 latine \u203a\u203a, \u2039\u2039 incapable de modernit\u00e9 et de r\u00e9forme&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-17-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-17-9808' title='Michel Hastings, \u00ab&amp;#160;Dieu est-il nordique&amp;#160;?&amp;#160;\u00bb, &lt;em&gt;Revue internationale de politique compar\u00e9e&lt;\/em&gt;, vol. 13,2006\/3, p. 377-390.'><sup>17<\/sup><\/a><\/span><\/span> \u203a\u203a, il n\u2019y a qu\u2019un sch\u00e9ma \u00e9conomique appliqu\u00e9 aux deux pays&#160;: la r\u00e9duction des d\u00e9penses publiques et la pression politique exerc\u00e9e par le n\u00e9olib\u00e9ralisme et le libre-\u00e9change sur les consciences collectives&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-18-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-18-9808' title='M\u00eame si le Danemark, \u00e0 la suite de son refus du trait\u00e9 de Maastricht, a pu conserver sa propre devise (la couronne) \u00e0 un taux structurellement plus faible, sa participation au m\u00e9canisme de taux de change europ\u00e9en lui interdit de fluctuer au-del\u00e0 de 2,25&amp;#160;%. Sa capacit\u00e9 de d\u00e9valuation, et donc d\u2019autonomie mon\u00e9taire, demeure limit\u00e9e et indirectement soumise aux trait\u00e9s europ\u00e9ens comme la France.'><sup>18<\/sup><\/a><\/span><\/span><span style=\"font-size: 13.3333px\">.<\/span><br><\/p>\n\n\n\n<p>Ce nouveau sch\u00e9ma fait appara\u00eetre une autre ligne de d\u00e9marcation, entre d\u2019un c\u00f4t\u00e9 la France et les pays scandinaves o\u00f9 l\u2019\u00c9tat-Providence n\u2019a pas \u00e9t\u00e9 enti\u00e8rement d\u00e9mantel\u00e9, et les pays de l\u2019anglosph\u00e8re et l\u2019Allemagne de l\u2019autre o\u00f9 les politiques n\u00e9olib\u00e9rales ont \u00e9rod\u00e9 plus fortement les revenus de la classe moyenne. En miroir du d\u00e9bat fran\u00e7ais, il faudra alors conclure l\u2019\u00e9tude en se demandant si la \u2039\u2039 classe moyenne \u203a\u203a et la coh\u00e9sion sociale, constitutifs du mod\u00e8le danois d\u2019\u00c9tat-Providence construit au cours du XX<sup>e<\/sup> si\u00e8cle, demeurent encore des concepts pertinents pour notre \u00e9poque.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Le Danemark \u00ab&#160;bris\u00e9&#160;\u00bb et la France des \u00ab&#160;oubli\u00e9s&#160;\u00bb&#160;: d\u00e9finitions et probl\u00e8mes<\/strong><\/h3>\n\n\n\n<p>\u00ab&#160;<em>Udkantsdanmark<\/em>&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-19-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-19-9808' title='Prononcer&amp;#160;: Oulkaintsdainmark.'><sup>19<\/sup><\/a><\/span><\/span> d\u2019un c\u00f4t\u00e9, France p\u00e9riph\u00e9rique de l\u2019autre. Le \u00ab&#160;<em>Danmark Kn\u00e6kker<\/em>&#160;\u00bb [qui se brise] et la \u00ab&#160;France des oubli\u00e9s&#160;\u00bb. Ces formulations, essentiellement pr\u00e9sentes dans le champ m\u00e9diatique et les d\u00e9bats politiques, manquent de nuance en raison de leur \u00e9cho m\u00e9diatique et de leur usage \u00e9lectoral par le Front National. Ils masquent ind\u00e9niablement des trajectoires sociales diversifi\u00e9es au sein de ces zones \u00e0 la p\u00e9riph\u00e9rie des centres urbains. Cependant, ils d\u00e9signent bien une dynamique r\u00e9elle issue de l\u2019int\u00e9gration in\u00e9galitaire des territoires \u00e0 la mondialisation.<br><\/p>\n\n\n\n<p>Au Danemark, la cat\u00e9gorie spatiale de la \u00ab&#160;p\u00e9riph\u00e9rie&#160;\u00bb ne recouvre pas seulement un usage m\u00e9diatique, c\u2019est aussi un concept refl\u00e9t\u00e9 dans la recherche scandinave en sciences sociales et dans les rapports publics et minist\u00e9riels. Urbanistes, anthropologues et g\u00e9ographes \u00e9voquent des \u2039\u2039 villages gagnants \u203a\u203a (<em>Vinderlandsbyer<\/em>) et \u2039\u2039 des villages perdants \u203a\u203a (<em>Taberlandsbyer<\/em>)&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-20-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-20-9808' title='J\u00f8rgen M\u00f8ller, Jan K. Staunstrup, &lt;em&gt;Landsbyerne i Nordjylland&amp;#160;: et fors\u00f8mt planl\u00e6gnings- og udviklingsobjekt med betydelige potentialer for fremtidig udvikling&lt;\/em&gt;, Center for Regional Udvikling (CRU), Aalborg Universitet, 2008'><sup>20<\/sup><\/a><\/span><\/span>rappelant la fameuse distinction entre gagnants et perdants de la mondialisation r\u00e9investie \u00e0 l\u2019\u00e9chelle locale pour montrer l\u2019int\u00e9gration in\u00e9gale des territoires danois \u00e0 la globalisation \u00e9conomique et la m\u00e9tropolisation.<br><\/p>\n\n\n\n<p>Le <em>Landdistriktsredeg\u00f8relse<\/em> de 2004 (rapport annuel sur les territoires du minist\u00e8re danois des affaires commerciales) d\u00e9finit une commune \u00ab&#160;p\u00e9riph\u00e9rique&#160;\u00bb [<em>udkant<\/em>] selon les crit\u00e8res suivants&#160;: son groupement de population principale (\u00ab&#160;ville&#160;\u00bb [<em>by<\/em>]) poss\u00e8de moins de 3 000 habitants et se situe \u00e0 plus de 40 kilom\u00e8tres des cinq \u00ab&#160;principaux centres urbains&#160;\u00bb (les m\u00e9tropoles selon la g\u00e9ographie fran\u00e7aise) que sont la r\u00e9gion Capitale (<em>Region Hovedstaden<\/em>, Copenhague), Aarhus, Odense, Esbjerg et Aalborg. Cette classification g\u00e9ographique permet de cerner assez bien statistiquement la production de dynamiques spatiales in\u00e9galitaires.<br><\/p>\n\n\n\n<p>En raison d\u2019une cure de rigueur par la droite lib\u00e9rale en 2007, le nombre de communes a \u00e9t\u00e9 r\u00e9duit de 271 \u00e0 98, formant des communaut\u00e9s de villes \u00e0 l\u2019int\u00e9rieur de chaque division communale. Cette division affaiblit la visibilit\u00e9 g\u00e9ographique de l\u2019<em>Udkantsdanmark<\/em>, et surtout sa diversit\u00e9 sociale. Selon un article de 2010 du Jyllandsposten, il y aurait 16 communes p\u00e9riph\u00e9riques repr\u00e9sentant 8&#160;% de la population totale du Danemark. Ces d\u00e9limitations, assez arbitraires, ne cessent d\u2019\u00e9voluer, \u00e0 l\u2019exemple de la commune de Slagelse, situ\u00e9e \u00e0 l\u2019est de l\u2019\u00eele de Sj\u00e6lland \u00e0 100 kilom\u00e8tres de Copenhague, tant\u00f4t classifi\u00e9e comme \u2039\u2039 <em>udkant<\/em> \u203a\u203a, tant\u00f4t rapproch\u00e9e de la m\u00e9tropole. Dans un article du Berlingske en date de 2012, il \u00e9tait estim\u00e9 que 30 communes danoises \u00e9taient p\u00e9riph\u00e9ris\u00e9es et que ce ph\u00e9nom\u00e8ne de fragilisation socio-spatiale toucherait d\u00e9sormais l\u2019ensemble des communes autour de l\u2019agglom\u00e9ration de Copenhague&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-21-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-21-9808' title='&lt;a href=&quot;https:\/\/www.business.dk\/arbejdsmarked\/udkantsdanmark-aeder-snart-koebenhavn&quot;&gt;https:\/\/www.business.dk\/arbejdsmarked\/udkantsdanmark-aeder-snart-koebenhavn&lt;\/a&gt;.'><sup>21<\/sup><\/a><\/span><\/span>, dans un p\u00e9rim\u00e8tre qui correspondrait en France \u00e0 la fois au \u2039\u2039 p\u00e9ri-urbain subi \u203a\u203a et aux espaces ruraux au-del\u00e0 des zones p\u00e9riurbaines.<br><\/p>\n\n\n\n<p>Il n\u2019existe pas en France de d\u00e9finition institutionnellement admise du concept de France p\u00e9riph\u00e9rique, ce qui pose un frein \u00e0 la m\u00e9thode de comparaison, de sorte qu\u2019il s\u2019agit de comparer des dynamiques analogues et non des ph\u00e9nom\u00e8nes quantifiables de mani\u00e8re pr\u00e9cise. La d\u00e9finition de Christophe Guilluy, marqu\u00e9e par un exc\u00e8s de sch\u00e9matisme, est la suivante&#160;: il s\u2019agit de l\u2019ensemble des espaces situ\u00e9s en dehors des 25 plus grandes m\u00e9tropoles fran\u00e7aises (soit plus de 60&#160;% de la population fran\u00e7aise), regroupant espaces ruraux ainsi que petites et moyennes villes. La France p\u00e9riph\u00e9rique est constitu\u00e9e par des classes moyennes et moyennes inf\u00e9rieures en voie de fragilisation socio-\u00e9conomique (\u00e0 l\u2019exclusion des classes moyennes inf\u00e9rieures des grandes m\u00e9tropoles)&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-22-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-22-9808' title='H. Le Bras, E. Todd, &lt;em&gt;Le myst\u00e8re fran\u00e7ais&lt;\/em&gt;, &lt;em&gt;op. cit.&lt;\/em&gt;'><sup>22<\/sup><\/a><\/span><\/span>.<br><\/p>\n\n\n\n<p>Comme le Danemark p\u00e9riph\u00e9rique concerne un nombre plus restreint de communes, une comparaison France-Danemark doit inviter \u00e0 la prudence en raison de la diff\u00e9rence d\u2019\u00e9chelle et de crit\u00e8res dans le choix des indicateurs&#160;: la France p\u00e9riph\u00e9rique int\u00e8gre des villes petites et moyennes&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-23-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-23-9808' title='Pour le lien entre taille des villes et vote FN&amp;#160;: &lt;a href=&quot;http:\/\/www.ifop.com\/?option=com_publication&amp;amp;type=publication&amp;amp;id=676&quot;&gt;http:\/\/www.ifop.com\/?option=com_publication&amp;amp;type=publication&amp;amp;id=676&lt;\/a&gt;.'><sup>23<\/sup><\/a><\/span><\/span>, l\u00e0 o\u00f9 le Danemark marginalis\u00e9, selon J\u00f8rgen M\u00f8ller, ne concerne que les communes (rassemblements de \u2039\u2039 villes \u203a\u203a, \u00e9quivalent des petites villes et des villages en France) de moins de 20 000 habitants, soit un peu plus de 10&#160;% de la population totale&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-24-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-24-9808' title='J\u00f8rgen M\u00f8ller, 2013'><sup>24<\/sup><\/a><\/span><\/span>. En effet, l\u00e0 o\u00f9 Guilluy, au risque de masquer la diversit\u00e9 des \u00e9volutions locales, n\u2019h\u00e9site pas \u00e0 classer comme p\u00e9riph\u00e9riques des espaces diversifi\u00e9s dits en voie de fragilisation, la classification de M\u00f8ller exclut lesdites zones interm\u00e9diaires en voie de p\u00e9riph\u00e9risation (\u00e0 l\u2019exemple des communes \u00e0 80 kilom\u00e8tres de Copenhague) et ne retient que les espaces \u00e0 tr\u00e8s faibles revenus par rapport \u00e0 la moyenne nationale. Mais il y a bien une dynamique analogue&#160;: il existe donc le m\u00eame ph\u00e9nom\u00e8ne de stratification spatiale et sociale des zones en marges des centres urbains comme effet de la m\u00e9tropolisation.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Une g\u00e9ographie sociologique de l\u2019in\u00e9galit\u00e9 des territoires au Danemark<\/strong><\/h3>\n\n\n\n<p><em>Classes populaires dans les centres urbains<\/em><\/p>\n\n\n\n<p>Au Danemark, quand on parle des cat\u00e9gories populaires, on pense souvent aux immigr\u00e9s. Les classes moyennes inf\u00e9rieures des grandes m\u00e9tropoles tendent \u00e0 s\u2019installer dans \u2039\u2039 les quartiers \u203a\u203a (<em>Ghettoerne<\/em>) o\u00f9 se concentrent principalement la population d\u2019origine \u00e9trang\u00e8re, d\u2019immigration r\u00e9cente, et les faibles revenus&#160;: les quartiers de Bispebjerg et Husum \u00e0 Copenhague, puis la banlieue Ouest (Ish\u00f8j et H\u00f8je Taastrup principalement). On trouve aussi Gjellerup \u00e0 Aarhus, ou encore Vollsmose \u00e0 Odense, C\u2019est l\u2019\u00e9quivalent socio-urbain de la Seine-Saint-Denis pour l\u2019agglom\u00e9ration parisienne, ou de Villeurbanne pr\u00e8s de Lyon. C\u2019est le Danemark dit \u00ab&#160;multiethnique&#160;\u00bb, qui, comme les \u00ab&#160;cit\u00e9s&#160;\u00bb ou les \u00ab&#160;quartiers&#160;\u00bb fran\u00e7ais, poss\u00e8de ses \u00ab&#160;ghettos&#160;\u00bb (terme m\u00e9diatique et non scientifique) \u00e0 l\u2019exemple de Mj\u00f8lnerparken \u00e0 N\u00f8rrebro, o\u00f9 habitaient en 2016 82,6&#160;% de personnes d\u2019origine africaine et asiatique&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-25-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-25-9808' title='Liste over ghettoomr\u00e5der pr. 1. december 2016. Transport-, Bygnings- og Boligministeriet. Offentliggjort 1. december 2016.Selon Danmarks Statistik, une personne r\u00e9sidant au Danemark, n\u00e9e \u00e9trang\u00e8re \u00e0 l\u2019\u00e9tranger, est consid\u00e9r\u00e9e comme une personne immigr\u00e9e. Elle appartient \u00e0 la \u2039\u2039 premi\u00e8re g\u00e9n\u00e9ration de l\u2019immigration \u203a\u203a comme on dit en France et au Danemark. Les citoyens danois dont les deux parents sont n\u00e9s \u00e9trangers \u00e0 l\u2019\u00e9tranger sont dits danois avec une origine ethnique \u00e9trang\u00e8re. Ils forment l\u2019\u00e9quivalent d\u2019une seconde g\u00e9n\u00e9ration issue de l\u2019immigration. Enfin, les danois n\u2019ayant qu\u2019un parent n\u00e9 \u00e9tranger \u00e0 l\u2019\u00e9tranger (donc \u00e9galement de la deuxi\u00e8me g\u00e9n\u00e9ration), ou appartenant \u00e0 l\u2019\u00e9quivalent de la troisi\u00e8me g\u00e9n\u00e9ration, sont consid\u00e9r\u00e9s comme ethniquement danois. En raison du droit du sol et de l\u2019inexistence de statistiques ethniques au Danemark, il n\u2019est pas possible de calculer avec exactitude l\u2019ensemble de la population d\u2019origine \u00e9trang\u00e8re car les personnes issues de l\u2019immigration ancienne appartiennent \u00e0 la cat\u00e9gorie des danois d\u2019origine \u2039\u2039 ethnique \u203a\u203a danoise.'><sup>25<\/sup><\/a><\/span><\/span>, alors que cette population ne repr\u00e9sentait au dernier recensement de <em>Danmarks Statistik<\/em> (automne 2017) que 8,8&#160;% de l\u2019ensemble de la population r\u00e9sidant au Danemark&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-26-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-26-9808' title='&lt;a href=&quot;https:\/\/www.dst.dk\/da\/Statistik\/emner\/befolkning-og-valg\/indvandrere-og-efterkommere\/indvandrere-og-efterkommere&quot;&gt;https:\/\/www.dst.dk\/da\/Statistik\/emner\/befolkning-og-valg\/indvandrere-og-efterkommere\/indvandrere-og-efterkommere&lt;\/a&gt;'><sup>26<\/sup><\/a><\/span><\/span>.<br><\/p>\n\n\n\n<p>Ces zones corr\u00e8lent forte immigration, faibles revenus et ch\u00f4mage au c\u0153ur des grandes m\u00e9tropoles. La commune (<em>kommune<\/em>) d\u2019Ish\u00f8j regroupe plusieurs villes (<em>byer<\/em>), dont celle d\u2019Ish\u00f8j. Elle est connue pour accueillir depuis les ann\u00e9es 1960 une immigration de travailleurs invit\u00e9s (<em>g\u00e6starbejdere<\/em>), en provenance de l\u2019ancienne Yougoslavie, de Turquie et du Pakistan. 35&#160;% de la population \u00e9tait d\u2019origine \u00e9trang\u00e8re en 2015&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-27-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-27-9808' title='Folketal den 1. i kvartalet efter kommune, k\u00f8n, alder, civilstand, herkomst, oprindelsesland og statsborgerskab. Danmarks Statistik. 2015K1.'><sup>27<\/sup><\/a><\/span><\/span>, quand la seule ville d\u2019Ish\u00f8j en comprenait 76&#160;%. La commune appartient au <em>Stork\u00f8benhavn<\/em> (le \u2039\u2039 Grand Copenhague \u203a\u203a, la m\u00e9tropole capitale \u00e9quivalant \u00e0 la cat\u00e9gorie urbaine et administrative du \u2039\u2039 Grand Paris \u203a\u203a plus une partie du p\u00e9riurbain francilien de l\u2019ancienne \u2039\u2039 Grande couronne \u203a\u203a). Le taux de ch\u00f4mage de la commune \u00e9tait de 10,3&#160;% en 2012 par rapport aux 3,8&#160;% de la population totale du pays \u00e0 la m\u00eame \u00e9poque&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-28-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-28-9808' title='Voir la carte pr\u00e9sent\u00e9e dans cet article&amp;#160;: &lt;a href=&quot;https:\/\/www.avisen.dk\/Pages\/Guests\/Articles\/ShowTemplatedArticle.aspx?ArticleID=158865&quot;&gt;https:\/\/www.avisen.dk\/Pages\/Guests\/Articles\/ShowTemplatedArticle.aspx?ArticleID=158865&lt;\/a&gt;.'><sup>28<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/7987661-hoeje-gladsaxe-boligblokke.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"800\"\n        data-pswp-height=\"533\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/7987661-hoeje-gladsaxe-boligblokke-330x220.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/7987661-hoeje-gladsaxe-boligblokke-690x460.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/7987661-hoeje-gladsaxe-boligblokke.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/7987661-hoeje-gladsaxe-boligblokke-125x83.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Le complexe r\u00e9sidentiel de H\u00f8je-Gladsaxe (1966) dans la banlieue nord-ouest de Copenhague incarne la r\u00e9ception au Danemark de l&rsquo;id\u00e9al corbus\u00e9en de l&rsquo;habitat fonctionnel. Equivalent des \u2039\u2039 cit\u00e9s \u203a\u203a fran\u00e7aises, la s\u00e9gr\u00e9gation socio-spatiale y entra\u00eene la concentration d&rsquo;une population d&rsquo;origine \u00e9trang\u00e8re, de bas revenus et d&rsquo;un taux de ch\u00f4mage \u00e9lev\u00e9. Photo&#160;&#160;: John Wideb\u00e6k Hertz<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>La commune d\u2019Aller\u00f8d, situ\u00e9e dans la banlieue Nord de Copenhague, zone habit\u00e9e par les classes moyennes sup\u00e9rieures (l\u2019\u00e9quivalent des Hauts-de-Seine), ne connaissait un taux de ch\u00f4mage que de 2,9&#160;% pour 5,2&#160;% d\u2019habitants d\u2019origine africaine et asiatique&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-29-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-29-9808' title='&lt;a href=&quot;https:\/\/www.dr.dk\/nyheder\/politik\/kort-se-hvor-mange-indvandrere-og-efterkommere-der-bor-i-din-kommune&quot;&gt;https:\/\/www.dr.dk\/nyheder\/politik\/kort-se-hvor-mange-indvandrere-og-efterkommere-der-bor-i-din-kommune&lt;\/a&gt;.'><sup>29<\/sup><\/a><\/span><\/span>. En premier lieu, il appara\u00eet que la faiblesse structurelle du ch\u00f4mage au Danemark permet de limiter la disparit\u00e9 des territoires en termes de bassin d\u2019emploi. En second lieu, ces chiffres montrent tout autant l\u2019existence de disparit\u00e9s socio-spatiales que la pr\u00e9sence d\u2019un continuum socio-urbain dans l\u2019ensemble des m\u00e9tropoles danoises, car tous les territoires appartenant aux cinq grands centres urbains connaissent des diff\u00e9rences <em>relatives<\/em> d\u2019int\u00e9gration socio-\u00e9conomique, plus faibles que la s\u00e9gr\u00e9gation socio-spatiale observables dans d\u2019autres grandes m\u00e9tropoles europ\u00e9ennes. Cela s\u2019explique par essentiellement par trois facteurs&#160;:<br><\/p>\n\n\n\n<p>1\/ D\u2019un point de vue architectural et urbain, on constate un nombre restreint de grands ensembles constitu\u00e9s par des logements sociaux alors m\u00eame que la densit\u00e9 du parc social est traditionnellement tr\u00e8s forte (<em>Gladsaxe<\/em>, une des rares r\u00e9alisations \u2039\u2039 corbus\u00e9ennes \u203a\u203a au Danemark, ou la \u2039\u2039 cit\u00e9 \u203a\u203a de Tingbjerg au Nord-Ouest de Copenhague par exemple, sont autant de \u2039\u2039 Sarcelles danois \u203a\u203a o\u00f9 l\u2019urbanisme produit des effets de s\u00e9gr\u00e9gation socio-spatiale). Il y a une permanence du logement individuel (des \u2039\u2039 <em>detached houses<\/em> \u203a\u203a, comme le pavillon en France) mais surtout une pr\u00e9gnance des complexes r\u00e9sidentiels de moyenne densit\u00e9 urbaine&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-30-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-30-9808' title='J\u00f8rn Orum-Nielsen, &lt;em&gt;Dwelling&amp;#160;: at home, in community, on earth&amp;#160;: the significance of tradition in contemporary housing&lt;\/em&gt;, Danish Architectural Press, 1996, 261 p.'><sup>30<\/sup><\/a><\/span><\/span> construits dans les traditions architecturales danoises au cours du XX<sup>e<\/sup> si\u00e8cle. C\u2019est sur ce dernier point que se diff\u00e9rencie la r\u00e9ussite d\u2019un \u2039\u2039 mod\u00e8le socio-urbain \u203a\u203a danois qui a su, malgr\u00e9 la pression exerc\u00e9e par la croissance urbaine, articuler urbanisation de masse avec une construction de qualit\u00e9 et une int\u00e9gration au tissu socio-\u00e9conomique&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-31-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-31-9808' title='&lt;em&gt;Ibid.&lt;\/em&gt;'><sup>31<\/sup><\/a><\/span><\/span><span style=\"font-size: 13.3333px\">,<\/span> \u00e0 l\u2019inverse des grands ensembles et des villes nouvelles franciliennes et du mod\u00e8le multipolaire.<br><\/p>\n\n\n\n<p>2\/ Le volontarisme des politiques urbaines et architecturales (les \u2039\u2039 <em>urban renewals<\/em> \u203a\u203a) men\u00e9es au cours des derni\u00e8res d\u00e9cennies d\u2019int\u00e9gration des espaces dits, \u00e0 tort \u2039\u2039 ghettois\u00e9s \u203a\u203a, \u00e0 l\u2019exemple des r\u00e9am\u00e9nagements tr\u00e8s m\u00e9diatis\u00e9s qui entourent <em>M\u00f8lnerparken<\/em> avec le parc <em>Superkilen<\/em> devenu quasi-touristique&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-32-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-32-9808' title='&lt;a href=&quot;http:\/\/www.visitcopenhagen.com\/copenhagen\/superkilen-park-gdk707822&quot;&gt;http:\/\/www.visitcopenhagen.com\/copenhagen\/superkilen-park-gdk707822&lt;\/a&gt;.'><sup>32<\/sup><\/a><\/span><\/span><span style=\"font-size: 13.3333px\"> <\/span>et <em>Mimersparken<\/em>, terrain de jeu rempla\u00e7ant une ancienne gare de triage&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-33-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-33-9808' title='&lt;a href=&quot;https:\/\/realdania.dk\/projekter\/mimersparken&quot;&gt;https:\/\/realdania.dk\/projekter\/mimersparken&lt;\/a&gt;.'><sup>33<\/sup><\/a><\/span><\/span><span style=\"font-size: 13.3333px\">. <\/span>Cependant, certains de ces projets ont \u00e9t\u00e9 accus\u00e9s de \u2039\u2039 gentrifier \u203a\u203a et de faire augmenter le prix des loyers pour chasser les classes populaires des centres. Comme en France, les m\u00e9dias danois n\u2019ont cess\u00e9 de pointer les probl\u00e8mes sociaux des \u2039\u2039 quartiers \u203a\u203a en oubliant la diversit\u00e9 des trajectoires sociales de ses habitants&#160;: le mod\u00e8le d\u2019int\u00e9gration danois fonctionne mieux qu\u2019il n\u2019appara\u00eet dans son traitement m\u00e9diatique&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-34-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-34-9808' title='Les danois d\u2019origine pakistanaise, arriv\u00e9s \u00e0 partir de 1967 sur le territoire, connaissaient, d\u00e8s 2003, un taux de ch\u00f4mage tr\u00e8s proche des danois d\u2019origine danoise (6,8&amp;#160;% pour 5,4&amp;#160;% de la population totale) et un taux de syndicalisation de 47&amp;#160;% t\u00e9moignant d\u2019une acculturation politique r\u00e9ussie. Source&amp;#160;: &lt;a href=&quot;http:\/\/www.politis-europe.uni-oldenburg.de\/download\/Denmark.pdf&quot;&gt;http:\/\/www.politis-europe.uni-oldenburg.de\/download\/Denmark.pdf&lt;\/a&gt;.'><sup>34<\/sup><\/a><\/span><\/span>. Cette efficacit\u00e9 des politiques urbaines repose, <em>in fine<\/em>, sur&#160;:<br><\/p>\n\n\n\n<p>3\/ La permanence d\u2019un financement important des services publics et, plus g\u00e9n\u00e9ralement, de l\u2019\u00c9tat-Providence danois&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-35-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-35-9808' title='&lt;a href=&quot;https:\/\/data.oecd.org\/fr\/gga\/depenses-des-administrations-publiques.htm#indicator-chart&quot;&gt;https:\/\/data.oecd.org\/fr\/gga\/depenses-des-administrations-publiques.htm#indicator-chart&lt;\/a&gt;'><sup>35<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p><em>En p\u00e9riph\u00e9rie<\/em><\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/DanemarkPeripheriqueFonce-01.png\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"5140\"\n        data-pswp-height=\"3865\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/DanemarkPeripheriqueFonce-01-330x248.png\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/DanemarkPeripheriqueFonce-01-690x519.png\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/DanemarkPeripheriqueFonce-01-1340x1008.png\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/DanemarkPeripheriqueFonce-01-125x94.png\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Le Danemark p\u00e9riph\u00e9rique<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>Mais qu\u2019en est-il dans le Danemark \u2039\u2039 <em>udkant<\/em> \u203a\u203a&#160;? Les dynamiques socio-spatiales sont-elles comparables \u00e0 celles de la France contemporaine&#160;? Quand on regarde la carte du ch\u00f4mage, une seconde zone appara\u00eet en plus des quartiers populaires urbains&#160;: les zones p\u00e9riph\u00e9riques, couvrant les communes dites \u2039\u2039 <em>udkant<\/em> \u203a\u203a (loin des grandes m\u00e9tropoles) et les espaces ruraux&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-36-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-36-9808' title='&lt;a href=&quot;https:\/\/data.oecd.org\/fr\/gga\/depenses-des-administrations-publiques.htm#indicator-chart&quot;&gt;https:\/\/data.oecd.org\/fr\/gga\/depenses-des-administrations-publiques.htm#indicator-chart&lt;\/a&gt;'><sup>36<\/sup><\/a><\/span><\/span>. Il y a donc, sch\u00e9matiquement, deux types d\u2019espaces o\u00f9 vivent de faibles revenus, comme en France&#160;: d\u2019une part les \u2039\u2039 quartiers \u203a\u203a et d\u2019autre part les zones p\u00e9riph\u00e9riques, dites \u2039\u2039 rurales \u203a\u203a et \u2039\u2039 p\u00e9riurbaines \u203a\u203a dans le vocabulaire g\u00e9ographique fran\u00e7ais. Cependant, il existe aussi sur le territoire danois une forte diversit\u00e9 au sein m\u00eame de ces territoires, comme en t\u00e9moigne la dualit\u00e9 entre les communes \u2039\u2039 gagnantes \u203a\u203a et les communes \u2039\u2039 perdantes \u203a\u203a&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-37-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-37-9808' title='&lt;em&gt;Mellem udvikling og afvikling \u2013 en minianalyse af de danske landdistrikter og landsbyer&lt;\/em&gt; in J\u00f8rgen M\u00f8ller, Jan K. Staunstrup, &lt;em&gt;Landsbyerne i Nordjylland&amp;#160;: et fors\u00f8mt planl\u00e6gnings- og udviklingsobjekt med betydelige potentialer for fremtidig udvikling&lt;\/em&gt;, Center for Regional Udvikling (CRU), Aalborg Universitet, 2008'><sup>37<\/sup><\/a><\/span><\/span>.<br><\/p>\n\n\n\n<p>Dans l\u2019un des tr\u00e8s rares articles en fran\u00e7ais sur la question&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-38-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-38-9808' title='&lt;a href=&quot;https:\/\/www.monde-diplomatique.fr\/2017\/04\/ESCACH\/57351&quot;&gt;https:\/\/www.monde-diplomatique.fr\/2017\/04\/ESCACH\/57351&lt;\/a&gt;'><sup>38<\/sup><\/a><\/span><\/span>, le g\u00e9ographe Nicolas Escach \u00e9voque l\u2019exemple de la ville de Vejby o\u00f9 depuis les ann\u00e9es 1990&#160;: \u00ab&#160;<em>les jeunes partent, les usines et les magasins ferment, les exploitations agricoles ne sont pas reprises et les services publics s\u2019\u00e9tiolent<\/em>&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-39-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-39-9808' title='&lt;em&gt;Ibid.&lt;\/em&gt;'><sup>39<\/sup><\/a><\/span><\/span>&#160;\u00bb. Avec un chiffre&#160;: la m\u00e9tropole de Copenhague repr\u00e9sente plus de 41&#160;% de la richesse produite au Danemark en 2014 alors qu\u2019elle regroupe environ 30&#160;% de la population totale du Danemark. En effet, le Danemark et la France, malgr\u00e9 leur diff\u00e9rence d\u2019\u00e9chelle, appartiennent aux quelques pays occidentaux qui poss\u00e8dent une structure territoriale traditionnellement macroc\u00e9phale, coupl\u00e9e \u00e0 un fort \u00c9tat social et unitaire. La centralisation et la concentration excessives furent de temps \u00e0 autres d\u00e9nonc\u00e9es par les responsables politiques&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-40-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-40-9808' title='Kaare Dybvad, &lt;em&gt;Udkantsmyten. Hvordan centraliseringen af Danmark \u00f8del\u00e6gger vores \u00f8konomi og social sammenh\u00e6ngskraft, &lt;\/em&gt;People\u2019s Press, Copenhague, 2015.'><sup>40<\/sup><\/a><\/span><\/span>, de sorte \u00e0 aboutir \u00e0 des politiques de d\u00e9centralisation et de d\u00e9concentration dont l\u2019ampleur limit\u00e9e r\u00e9v\u00e8le le d\u00e9clin des services publics en zones p\u00e9riph\u00e9riques ainsi que la m\u00e9fiance croissante des populations locales envers la capacit\u00e9 de l\u2019\u00c9tat \u00e0 relocaliser l\u2019emploi et contrer les dynamiques n\u00e9gatives de m\u00e9tropolisation.<br><\/p>\n\n\n\n<p>Malgr\u00e9 la mise en place de politiques d\u2019\u00c9tat-Providence et de r\u00e9\u00e9quilibrage territorial et \u00e9conomique, Escach prend l\u2019exemple de l\u2019\u00e9chec relatif des r\u00e9formes de la fonction publique&#160;: le plan de d\u00e9localisation de postes de la fonction publique en 2015 de la r\u00e9gion Hovedstaden (Copenhague) \u00e0 38 communes \u00e9loign\u00e9es ne fut pas vraiment suivi des effets escompt\u00e9s&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-41-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-41-9808' title='&lt;a href=&quot;https:\/\/www.monde-diplomatique.fr\/2017\/04\/ESCACH\/57351&quot;&gt;https:\/\/www.monde-diplomatique.fr\/2017\/04\/ESCACH\/57351&lt;\/a&gt;'><sup>41<\/sup><\/a><\/span><\/span>. J\u00f8rgen M\u00f8ller, sp\u00e9cialiste de l\u2019am\u00e9nagement du territoire, enseignant \u00e0 l\u2019universit\u00e9 d\u2019Aalborg, \u00e9voque la fragilit\u00e9 sociale des populations de ces zones&#160;: certains habitants accumulent faible niveau \u00e9ducatif, \u00e9loignement du march\u00e9 du travail et faibles revenus&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-42-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-42-9808' title='J\u00f8rgen M\u00f8ller, Jan K. Staunstrup, &lt;em&gt;Landsbyerne i Nordjylland&amp;#160;: et fors\u00f8mt planl\u00e6gnings- og udviklingsobjekt med betydelige potentialer for fremtidig udvikling&lt;\/em&gt;'><sup>42<\/sup><\/a><\/span><\/span><span style=\"font-size: 13.3333px\">.<\/span> Les populations pr\u00e9caires, \u00e0 la diff\u00e9rence de la diversit\u00e9 des classes populaires urbaines, sont tr\u00e8s majoritairement d\u2019origine danoise, \u00e0 tel point qu\u2019on a d\u00e9sign\u00e9 p\u00e9jorativement ces lieux comme des \u2039\u2039 <em>White Trashomr\u00e5der<\/em> \u203a\u203a (par r\u00e9f\u00e9rence aux White trash am\u00e9ricains, la population blanche pauvre, ou l\u2019expression \u2039\u2039 petits blancs \u203a\u203a fran\u00e7ais)&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-43-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-43-9808' title='&lt;em&gt;Ibid.&lt;\/em&gt;'><sup>43<\/sup><\/a><\/span><\/span><span style=\"font-size: 13.3333px\">.<\/span><br><\/p>\n\n\n\n<p>Il existe, \u00e0 contre-courant de cette repr\u00e9sentation m\u00e9diatique des \u2039\u2039 petits blancs \u203a\u203a suspect\u00e9s de n\u2019avoir jamais vu de personnes de couleurs, de nombreux territoires du Danemark p\u00e9riph\u00e9rique o\u00f9 le taux de population d\u2019origine \u00e9trang\u00e8re est plus \u00e9lev\u00e9 que la moyenne nationale, comme Aabenraa o\u00f9 le volume des personnes d\u2019ascendance \u00e9trang\u00e8re dans la population totale \u00e9tait, en 2017, de 0,3 point sup\u00e9rieur \u00e0 la moyenne nationale&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-44-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-44-9808' title='&lt;a href=&quot;https:\/\/www.dr.dk\/nyheder\/politik\/kort-se-hvor-mange-indvandrere-og-efterkommere-der-bor-i-din-kommune&quot;&gt;https:\/\/www.dr.dk\/nyheder\/politik\/kort-se-hvor-mange-indvandrere-og-efterkommere-der-bor-i-din-kommune&lt;\/a&gt;'><sup>44<\/sup><\/a><\/span><\/span><span style=\"font-size: 13.3333px\">.<\/span> Cette situation n\u2019est pas sans \u00e9voquer les populations des espaces ruraux et p\u00e9riurbains qui rejettent l\u2019\u00c9tat social associ\u00e9 \u00e0 la centralisation, sans pour autant adh\u00e9rer aux valeurs du lib\u00e9ralisme \u00e9conomique. Cette m\u00e9fiance vient de la perception que les politiques sociales ne seraient destin\u00e9es qu\u2019aux m\u00e9tropoles urbaines et aux personnes d\u2019origine \u00e9trang\u00e8re y r\u00e9sidant&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-45-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-45-9808' title='Laurent Davezies, Christophe Guilluy, Jacques Donzelot and Alice B\u00e9ja, &lt;em&gt;La France p\u00e9riph\u00e9rique et marginalis\u00e9e&amp;#160;: les raisons du ressentiment&lt;\/em&gt;, Esprit, No. 393 (3\/4) (Mars-avril 2013), p. 27.'><sup>45<\/sup><\/a><\/span><\/span><span style=\"font-size: 13.3333px\">.<\/span> Il en r\u00e9sulte un \u2039\u2039 s\u00e9paratisme culturel&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-46-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-46-9808' title='Expression de Christophe Guilluy.'><sup>46<\/sup><\/a><\/span><\/span> \u203a\u203a de cette France qui rappelle la \u2039\u2039 culture des marges \u203a\u203a (expression d\u2019Escach) d\u00e9signant la cr\u00e9ation de codes et de r\u00e9f\u00e9rences culturels propres \u00e0 ces espaces danois p\u00e9riph\u00e9ris\u00e9s.<br><\/p>\n\n\n\n<p>Le \u2039\u2039 s\u00e9paratisme social \u203a\u203a relev\u00e9 par par J\u00e9r\u00f4me Fourquet dans le cas fran\u00e7ais&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-47-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-47-9808' title='&lt;a href=&quot;https:\/\/jean-jaures.org\/nos-productions\/1985-2017-quand-les-classes-favorisees-ont-fait-secession&quot;&gt;https:\/\/jean-jaures.org\/nos-productions\/1985-2017-quand-les-classes-favorisees-ont-fait-secession&lt;\/a&gt;'><sup>47<\/sup><\/a><\/span><\/span>s\u2019appliquerait volontiers au Danemark. Les enqu\u00eates anthropologiques&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-48-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-48-9808' title='Line Schmidt Hendriksen, &lt;em&gt;At leve med \u2019Udkantsdanmark\u2019 \u2013 diskursens magt i problematikken omkring udkantsdanmark&lt;\/em&gt;, &lt;em&gt;op. cit.&lt;\/em&gt;'><sup>48<\/sup><\/a><\/span><\/span> de terrain r\u00e9v\u00e8lent le sentiment d\u2019inf\u00e9riorit\u00e9 et d\u2019\u00e9loignement des populations locales de \u2039\u2039 la grande ville \u203a\u203a, Copenhague. Il appara\u00eet donc sur le territoire danois des espaces p\u00e9riph\u00e9riques d\u00e9sign\u00e9s dans la presse danoise comme la \u00ab&#160;Banane pourrie&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-49-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-49-9808' title='&lt;a href=&quot;https:\/\/www-idunn-no.ep.fjernadgang.kb.dk\/plan\/2009\/03-04\/art18&quot;&gt;https:\/\/www-idunn-no.ep.fjernadgang.kb.dk\/plan\/2009\/03-04\/art18&lt;\/a&gt;'><sup>49<\/sup><\/a><\/span><\/span>&#160;\u00bb o\u00f9 les revenus des m\u00e9nages sont faibles. Il s\u2019agit notamment d\u2019\u00eeles, comme le Lolland ou le Falster, ou encore des communes de Thy ou de Mors dans le Jutland du Nord. Toutes ces diff\u00e9rentes localit\u00e9s poss\u00e8dent comme caract\u00e8re commun de se situer \u00e0 une longue distance des cinq grandes m\u00e9tropoles danoises, souvent au moins de 60 \u00e0 80 kilom\u00e8tres, et font appara\u00eetre des espaces en voie de fragilisation socio-spatiale&#160;: la bordure Sud-Ouest dans la r\u00e9gion du Jutland-du-Sud, dont l\u2019activit\u00e9 \u00e9conomique traditionnelle r\u00e9side dans l\u2019agriculture, et les marges Nord de la p\u00e9ninsule jutlandaise.<br><\/p>\n\n\n\n<p>Sur la carte, elles sont situ\u00e9es sur la bordure Ouest du Danemark, en forme de croissant. Ces deux espaces se distinguent de la m\u00e9tropole du Jutland de l\u2019Est regroupant environ 1 380 000 habitants (soit 25&#160;% de la population danoise), laquelle est articul\u00e9e autour de Aarhus, la plus grande ville du pays apr\u00e8s Copenhague (rappelant la vall\u00e9e du Rh\u00f4ne et le littoral m\u00e9diterran\u00e9en en France). Au sud de la m\u00e9tropole de la capitale, on trouve un autre arc que constitue notamment le chapelet d\u2019\u00eeles au sud-est du pays&#160;: Langeland, Lolland, Falster, M\u00f8n, \u00e0 plus de 100 kilom\u00e8tres de Copenhague. <\/p>\n\n\n\n<p>Tous ces territoires, formant un grand arc du Nord du Jutland \u00e0 l\u2019extr\u00e9mit\u00e9 Est bordant la Mer baltique, de Skagen \u00e0 Gedser, ressemblent bien \u00e0 une gigantesque \u2039\u2039 banane \u203a\u203a en \u2039\u2039 pourrissement \u203a\u203a \u00e9conomique.<br><\/p>\n\n\n\n<p>Finalement, la partition latente du territoire danois en deux, d\u2019une part une banane pourrie du Nord au Sud-Est en passant par le Sud-Ouest, et d\u2019autre part une dynamique de m\u00e9tropolisation dans un arc central, de l\u2019Est jutlandais \u00e0 l\u2019\u00d8resund, fait appara\u00eetre le renversement suivant&#160;: les espaces o\u00f9 les difficult\u00e9s sociales s\u2019accumulent ne sont pas les grandes m\u00e9tropoles (hormis les banlieues populaires d\u2019Aarhus ou de Copenhague), l\u00e0 o\u00f9 jusqu\u2019aux ann\u00e9es 1990 habitaient une majorit\u00e9 d\u2019ouvriers et d\u2019employ\u00e9s, mais les espaces ruraux, dont les activit\u00e9s traditionnelles sont l\u2019agriculture et la p\u00eache. C\u2019est comme si la carte des disparit\u00e9s s\u2019\u00e9tait partiellement invers\u00e9e sous l\u2019effet de la mondialisation et de la m\u00e9tropolisation. <\/p>\n\n\n\n<p>Copenhague, traditionnellement habit\u00e9e par des classes populaires (surtout des ouvriers depuis la fin du XIX<sup>e<\/sup> si\u00e8cle), conna\u00eet comme Paris une flamb\u00e9e des prix de l\u2019immobilier et une gentrification compl\u00e8te de ses derni\u00e8res \u2039\u2039 poches de r\u00e9sistance \u203a\u203a populaires.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Les privatisations partielles des infrastructures publiques&#160;: la Banane pourrie hors r\u00e9ticularit\u00e9 territoriale<\/strong><\/h3>\n\n\n\n<p> Un secteur fut particuli\u00e8rement touch\u00e9 par les vagues de privatisation&#160;: le rail. La <em>Danske Statsbaner <\/em>[DSB], compagnie nationale des chemins de fer danois, op\u00e9rait la plupart des voies depuis sa fondation en 1885. La privatisation partielle fut d\u00e9cid\u00e9e au milieu des ann\u00e9es 1990, et les petites lignes de province furent vendues \u00e0 des compagnies priv\u00e9es, dont la multinationale Arriva, poss\u00e9dant d\u00e9sormais 17&#160;% du r\u00e9seau danois&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-50-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-50-9808' title='&lt;a href=&quot;https:\/\/web.archive.org\/web\/20080914193347\/http:\/www.arriva.co.uk\/arriva\/en\/business_activities\/transport_services\/denmark\/&quot;&gt;https:\/\/web.archive.org\/web\/20080914193347\/http:\/\/www.arriva.co.uk\/arriva\/en\/business_activities\/transport_services\/denmark\/&lt;\/a&gt;'><sup>50<\/sup><\/a><\/span><\/span>. <\/p>\n\n\n\n<p>Les deux cartes comparatives montrent, entre 1938 et 2018, le d\u00e9clin du nombre de lignes op\u00e9r\u00e9es par DSB ainsi que l\u2019abandon des r\u00e9seaux secondaires desservant les espaces ruraux.<br><\/p>\n\n\n\n<p>En effet, la privatisation des petites lignes a conduit \u00e0 leur pure et simple disparition, mais surtout, l\u2019\u00e9volution du rail danois illustre la logique de m\u00e9tropolisation&#160;: le r\u00e9seau actuel de DSB met en communication les deux grandes m\u00e9tropoles copenhaguoise et jutlandaise, et les espaces p\u00e9riph\u00e9riques ne sont plus reli\u00e9s entre eux puisqu\u2019ils ne desservent que les grands centres urbains. Avec l\u2019externalisation progressive, les usagers ont vu les prix augmenter et les probl\u00e8mes de retard et de suppressions de trains exploser&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-51-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-51-9808' title='&lt;a href=&quot;https:\/\/www.aoh.dk\/artikel\/dsb-og-banedanmark-fr-kritik-togene-krer-ikke-til-tiden?related=text&quot;&gt;https:\/\/www.aoh.dk\/artikel\/dsb-og-banedanmark-fr-kritik-togene-krer-ikke-til-tiden?related=text&lt;\/a&gt;'><sup>51<\/sup><\/a><\/span><\/span>. Sur tout l\u2019espace de la Banane pourrie, les lignes ferroviaires r\u00e9gionales ont enti\u00e8rement disparu et les dessertes actuelles ne conduisent qu\u2019au Grand Copenhague ou au Grand Aarhus. Il n\u2019existe plus aujourd\u2019hui de transports publics, ni de ligne ferroviaire reliant les diff\u00e9rents territoires de la Banane pourrie, qui s\u2019est enti\u00e8rement \u2039\u2039 d\u00e9r\u00e9ticularis\u00e9e \u203a\u203a. Le contraste est saisissant avec le maintien du monopole public sur les autoroutes qui ont conserv\u00e9 jusqu\u2019\u00e0 aujourd\u2019hui leur totale gratuit\u00e9 et leur facilit\u00e9 d\u2019acc\u00e8s.<br><\/p>\n\n\n\n<p>Il appara\u00eet, par un renversement de la cause et de l\u2019effet, que les \u00e9l\u00e9ments de persistance de la coh\u00e9sion sociale et territoriale au Danemark ne tiennent donc pas au fameux \u2039\u2039 mod\u00e8le danois \u203a\u203a de flexis\u00e9curit\u00e9 adopt\u00e9 dans les ann\u00e9es 1990, mais bien au mod\u00e8le d\u2019\u00c9tat-Providence mis en place au cours du XX<sup>e<\/sup> si\u00e8cle. Revendiqu\u00e9 au nom de sa capacit\u00e9 \u00e0 conserver la \u2039\u2039 coh\u00e9sion sociale \u203a\u203a (il constitue un exemple r\u00e9current de la strat\u00e9gie de communication social-lib\u00e9rale d\u2019Emmanuel Macron), le \u2039\u2039 mod\u00e8le danois \u203a\u203a de flexis\u00e9curit\u00e9 accompagne en fait la d\u00e9sagr\u00e9gation territoriale et \u00e9tatique de l\u2019\u00c9tat-Providence puisqu\u2019il autorise la mise en concurrence de certains services publics comme le rail.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Mod\u00e8le occidental de la soci\u00e9t\u00e9 de classe moyenne et \u00c9tat-Providence&#160;: \u00e9chec ou persistance de l\u2019id\u00e9al d\u00e9mocratique et social danois&#160;?<\/strong><\/h3>\n\n\n\n<p>L\u2019existence de marges danoises accumulant les difficult\u00e9s sociales, parfois occult\u00e9e par une pr\u00e9sentation d\u00e9form\u00e9e du probl\u00e8me des \u2039\u2039 ghettos \u203a\u203a&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-52-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-52-9808' title='L\u2019usage impropre du terme de ghetto pour d\u00e9signer des espaces urbains diversifi\u00e9s sur le plan culturel et social indique la d\u00e9formation m\u00e9diatique de la question de l\u2019immigration.'><sup>52<\/sup><\/a><\/span><\/span>d\u2019immigr\u00e9s comme celui des \u2039\u2039 cit\u00e9s \u203a\u203a en France, remet-elle en cause, par la nouvelle stratification sociale qu\u2019elle engendre, le mod\u00e8le danois, occidental et d\u00e9mocratique, d\u2019une classe moyenne g\u00e9n\u00e9ralis\u00e9e qui aurait trouv\u00e9 un \u00e9quilibre entre d\u00e9terminations individuelles (la \u2039\u2039 <em>detached house<\/em> \u203a\u203a, l\u2019autonomisation financi\u00e8re des individus par l\u2019\u00c9tat-Providence) et d\u00e9terminations collectives (consentement \u00e0 l\u2019imp\u00f4t et \u00e0 l\u2019usage des services publics, taux de participation aux associations)&#160;?<br><\/p>\n\n\n\n<p>Le Danemark est-il toujours ce pays d\u2019une \u00e9conomie mixte harmonieuse, associant libert\u00e9 \u00e9conomique, \u00e9galit\u00e9 sociale et continuit\u00e9 territoriale&#160;? En France, la marginalisation des classes populaires loin des grandes m\u00e9tropoles s\u2019accompagnerait-elle de l\u2019\u00e9chec du mod\u00e8le r\u00e9publicain \u00e0 la fran\u00e7aise, cens\u00e9 offrir \u00e0 tous les m\u00eames opportunit\u00e9s sociales&#160;? En d\u2019autres termes, si la possibilit\u00e9 m\u00eame d\u2019une permanence de la classe moyenne est remise en cause en France, pouvons-nous faire le m\u00eame constat au Danemark&#160;?<br><\/p>\n\n\n\n<p>S\u2019il est \u00e9vident que la mondialisation et le libre-\u00e9change, concentrant les flux d\u2019activit\u00e9 dans les centres au d\u00e9triment des marges, ainsi que le n\u00e9olib\u00e9ralisme et l\u2019aust\u00e9rit\u00e9 budg\u00e9taire (produits m\u00e9caniquement par les trait\u00e9s europ\u00e9ens imposant de r\u00e9duire sans cesse les d\u00e9penses publiques des \u00c9tats membres&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-53-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-53-9808' title='Les politiques de privatisation men\u00e9es par les sociaux-d\u00e9mocrates dans les ann\u00e9es 1990 sont un exemple de conformation aux exigences libre-concurrentielles pr\u00f4n\u00e9es par la Commission europ\u00e9enne.'><sup>53<\/sup><\/a><\/span><\/span>), sont autant de ph\u00e9nom\u00e8nes qui fragilisent le mod\u00e8le d\u2019\u00e9galit\u00e9 sociale et de r\u00e9ticularit\u00e9 territoriale tels qu\u2019ils existent traditionnellement en France et au Danemark. Ceux-ci ont en commun d\u2019user traditionnellement d\u2019un \u00c9tat unitaire, au poids \u00e9conomique fort et redistributeur, ce que le libre-\u00e9change et les doctrines ordolib\u00e9rales pr\u00e9valant dans l\u2019espace europ\u00e9en condamnent structurellement et institutionnellement&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-54-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-54-9808' title='Voir les trait\u00e9s europ\u00e9ens.'><sup>54<\/sup><\/a><\/span><\/span><span style=\"font-size: 13.3333px\">.<\/span><br><\/p>\n\n\n\n<p>Il faut faire l\u2019hypoth\u00e8se, dans le cas danois, d\u2019une fragilisation du mod\u00e8le de soci\u00e9t\u00e9 \u2039\u2039 moyennis\u00e9 \u203a\u203a tel qu\u2019il prend sa source dans le projet social et culturel des sociaux-d\u00e9mocrates dans les ann\u00e9es 1930, dont les politiques visaient \u00e0 autonomiser les individus par l\u2019\u00c9tat-Providence&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-55-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-55-9808' title='L\u2019id\u00e9e que le socialisme danois fut le moyen d\u2019autonomiser les individus renvoie aux analyses d\u2019Emmanuel Todd sur la famille nucl\u00e9aire absolue danoise dans l\u2019entretien que nous lui avons consacr\u00e9 en janvier dernier ainsi qu\u2019\u00e0 celles de l\u2019historien Francis Sejersted sur l\u2019\u00c9tat-Providence scandinave (&lt;em&gt;Demokratisk kapitalisme&lt;\/em&gt;, Oslo, Pax, 1993)'><sup>55<\/sup><\/a><\/span><\/span><span style=\"font-size: 13.3333px\"> <\/span>et fournir un acc\u00e8s d\u00e9mocratique&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-56-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-56-9808' title='Cette d\u00e9mocratisation d\u2019un mode de vie fond\u00e9 sur l\u2019\u00e9quilibre entre travail et loisirs se refl\u00e8te dans la culture visuelle danoise des ann\u00e9es 1930-1960&amp;#160;: le design danois, moderniste et fonctionnel, se pense comme une esth\u00e9tique d\u00e9mocratique apportant l\u2019art dans la vie quotidienne de tous. En ce sens, le design danois a r\u00e9alis\u00e9 l\u2019id\u00e9al anthropologique du Bauhaus.'><sup>56<\/sup><\/a><\/span><\/span><span style=\"font-size: 13.3333px\"> <\/span>\u00e0 la propri\u00e9t\u00e9 et aux loisirs&#160;: la \u2039\u2039 <em>sommerhus<\/em> \u203a\u203a, maison d\u2019\u00e9t\u00e9 individuelle&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-57-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-57-9808' title='Voir l\u2019article &lt;em&gt;La ruine scandinave&lt;\/em&gt;'><sup>57<\/sup><\/a><\/span><\/span>, dispers\u00e9e sur l\u2019ensemble du pays. Les territoires du Danemark des marges, soumis au d\u00e9clin \u00e9conomique et \u00e0 des ph\u00e9nom\u00e8nes de d\u00e9classement social, sont justement devenus les lieux symboliques d\u2019un id\u00e9al social-d\u00e9mocrate vieilli et fragilis\u00e9.<br><\/p>\n\n\n\n<p>La France p\u00e9riph\u00e9rique des ouvriers et des employ\u00e9s conna\u00eet le m\u00eame ph\u00e9nom\u00e8ne de fragilisation sociale, avec une pr\u00e9carisation \u00e9conomique plus forte qu\u2019au Danemark (comme en t\u00e9moigne une radicalit\u00e9 politique oscillant entre abstention et vote Front National, l\u00e0 o\u00f9 le comportement \u00e9lectoral du Danemark p\u00e9riph\u00e9rique semble moins contestataire). L\u2019exemple de la \u2039\u2039 France pavillonnaire \u203a\u203a (espaces p\u00e9riph\u00e9riques dont la densit\u00e9 urbaine faible se caract\u00e9rise par la pr\u00e9sence de \u2039\u2039 <em>detached houses<\/em> \u203a\u203a) est frappant&#160;: en plus de la discrimination socio-spatiale croissante (la marginalisation), elle subit une discrimination socio-symbolique&#160;: son \u2039\u2039 s\u00e9paratisme culturel \u203a\u203a&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-58-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-58-9808' title='Expression de Christophe Guilluy.'><sup>58<\/sup><\/a><\/span><\/span><span style=\"font-size: 13.3333px\">,<\/span> comparable \u00e0 la \u2039\u2039 culture des marges&#160;\u00bb qu\u2019Escach rel\u00e8ve au Danemark,  reposant sur un syst\u00e8me de r\u00e9f\u00e9rences et de valeurs diff\u00e9renci\u00e9 des m\u00e9tropoles, refl\u00e8te le \u2039\u2039 racisme de l\u2019intelligence \u203a\u203a&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-59-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-59-9808' title='Conception bourdieusien&amp;#160;: &lt;a href=&quot;https:\/\/www.monde-diplomatique.fr\/2004\/04\/BOURDIEU\/11113&quot;&gt;https:\/\/www.monde-diplomatique.fr\/2004\/04\/BOURDIEU\/11113&lt;\/a&gt;.'><sup>59<\/sup><\/a><\/span><\/span> <span style=\"font-size: 13.3333px\"><\/span>des classes moyennes sup\u00e9rieures \u00e9duqu\u00e9es sur les populations locales.<br><\/p>\n\n\n\n<p>Au Danemark, les m\u00eames pr\u00e9jug\u00e9s, moins pr\u00e9gnants en raison de la \u2039\u2039 moyennisation anthropologique \u203a\u203a de la soci\u00e9t\u00e9 danoise et de sa forte structuration \u00e9galitaire&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-60-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-60-9808' title='Jean-Pascal Daloz, \u00ab&amp;#160;Sur la modestie ostensible des acteurs politiques au nord du 55&lt;sup&gt;e&lt;\/sup&gt; parall\u00e8le&amp;#160;\u00bb, &lt;em&gt;Revue internationale de politique&lt;\/em&gt; &lt;em&gt;compar\u00e9e&lt;\/em&gt;, vol. 13,2006\/3, p. 413-427'><sup>60<\/sup><\/a><\/span><\/span>, ont conduit de nombreux m\u00e9dias \u00e0 pr\u00e9senter le Danemark p\u00e9riph\u00e9rique de mani\u00e8re exag\u00e9r\u00e9ment n\u00e9gative&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-61-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-61-9808' title='L. S. Hendriksen, &lt;em&gt;At leve med \u2019Udkantsdanmark\u2019&lt;\/em&gt;, &lt;em&gt;op. cit.&lt;\/em&gt;'><sup>61<\/sup><\/a><\/span><\/span>&#160;: le quotidien d\u2019information <em>Politiken<\/em>, \u00e9quivalent danois du <em>Monde<\/em>, en constitue un exemple quasi-caricatural. Lu par un lectorat dipl\u00f4m\u00e9 de l\u2019enseignement sup\u00e9rieur, vivant dans les centres urbains, il se revendique de centre-gauche et a soutenu la candidature de Macron aux \u00e9lections pr\u00e9sidentielles fran\u00e7aises, ou encore la \u00ab&#160;flexis\u00e9curisation&#160;\u00bb de l\u2019\u00c9tat-providence danois. Traquant la moindre entorse \u00e0 la diversit\u00e9 culturelle tout en relayant de mani\u00e8re non critique l\u2019emploi de termes discriminatoires envers les danois d\u2019origine \u00e9trang\u00e8re, il se consacre d\u00e9sormais davantage \u00e0 faire la publicit\u00e9 des nouvelles adresses gastronomiques des quartiers gentrifi\u00e9s de Copenhague qu\u2019\u00e0 r\u00e9aliser des chroniques sur les effets de la mondialisation dans les espaces marginalis\u00e9s du monde occidental.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/Superkilen.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2532\"\n        data-pswp-height=\"1900\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/Superkilen-330x248.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/Superkilen-690x518.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/Superkilen-1340x1006.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/Superkilen-125x94.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">La r\u00e9novation urbaine du parc de Superkilen (2012) \u00e0 N\u00f8rrebro illustre, comme la politique de la ville en France, les ambigu\u00eft\u00e9s sociologiques inh\u00e9rentes \u00e0 la gentrification qui refoule vers la banlieue les classes populaires urbaines et les immigr\u00e9s. Historiquement li\u00e9 \u00e0 l&rsquo;histoire du communisme danois et \u00e0 l&rsquo;accueil des populations d&rsquo;origine \u00e9trang\u00e8re, le r\u00e9am\u00e9nagement du lieu sur le th\u00e8me du multiculturalisme et du socialisme (la couleur rouge) s&rsquo;accompagne in\u00e9vitablement d&rsquo;une mont\u00e9e des prix de l&rsquo;immobilier dans le secteur.<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<h3 class=\"wp-block-heading\">La persistance de l&rsquo;Etat-providence <\/h3>\n\n\n\n<p>Il faudrait n\u00e9anmoins conclure sur les facteurs de persistance de l\u2019\u00c9tat-Providence danois, c\u2019est-\u00e0-dire sur les crit\u00e8res permettant d\u2019\u00e9valuer le maintien de la coh\u00e9sion sociale et de la r\u00e9ticularit\u00e9 territoriale. Il semble justement que le syst\u00e8me social, subissant la m\u00eame pression globalisatrice, fonctionne mieux au Danemark qu\u2019en France. C\u2019est essentiellement la forte mobilit\u00e9 sociale et spatiale danoise, la plus \u00e9lev\u00e9e des pays de l\u2019OCDE&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-63-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-63-9808' title='&lt;a href=&quot;https:\/\/milescorak.files.wordpress.com\/2013\/07\/income-inequality-equality-of-opportunity-and-intergenerational-mobility.pdf&quot;&gt;https:\/\/milescorak.files.wordpress.com\/2013\/07\/income-inequality-equality-of-opportunity-and-intergenerational-mobility.pdf&lt;\/a&gt;[\/note&lt;span style=&quot;font-size: 13.3333px&quot;&gt; &lt;\/span&gt;(loin devant la France), qui peut l\u2019expliquer. La persistance de structures anthropo-culturelles, marqu\u00e9es par la pr\u00e9gnance de la valeur d\u2019\u00e9galit\u00e9, peuvent expliquer \u00e9galement le sentiment, valid\u00e9 par les observations de terrain que je m\u00e8ne au Danemark pour l\u2019ann\u00e9e universitaire 2017-2018&amp;nbsp;&lt;span class=&#039;whitespace-nowrap&#039;&gt;&lt;span id=&#039;easy-footnote-62-9808&#039; class=&#039;easy-footnote-margin-adjust&#039;&gt;&lt;\/span&gt;&lt;span class=&#039;easy-footnote&#039;&gt;&lt;a href=&#039;https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-62-9808&#039; title=&#039;&#039;&gt;&lt;sup&gt;62&lt;\/sup&gt;&lt;\/a&gt;&lt;\/span&gt;&lt;\/span&gt;Mon s\u00e9jour universitaire 2017-2018 \u00e0 l\u2019Universit\u00e9 de Copenhague est notamment consacr\u00e9 \u00e0 des observations de terrain dans plusieurs communes danoises, concentr\u00e9es sur le lien entre caract\u00e8res architecturaux, urbanisme, identit\u00e9s culturelles et structures \u00e9conomiques locales.'><sup>63<\/sup><\/a><\/span><\/span><span style=\"font-size: 13.3333px\">,<\/span> que la mondialisation est \u2039\u2039 contenue \u203a\u203a et moins \u2039\u2039 ravageuse \u203a\u203a au Danemark que dans le reste de l\u2019Europe.<br><\/p>\n\n\n\n<p>Au-del\u00e0 de l\u2019inventivit\u00e9 politique propre \u00e0 ce pays nordique (Escach, de son c\u00f4t\u00e9, met l\u2019accent sur la capacit\u00e9 des territoires danois marginalis\u00e9s \u00e0 r\u00e9inventer des mod\u00e8les de d\u00e9veloppement&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-64-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-64-9808' title='&lt;a href=&quot;https:\/\/www.monde-diplomatique.fr\/2017\/04\/ESCACH\/57351&quot;&gt;https:\/\/www.monde-diplomatique.fr\/2017\/04\/ESCACH\/57351&lt;\/a&gt;'><sup>64<\/sup><\/a><\/span><\/span>), il est \u00e9vident que la politique de \u2039\u2039 d\u00e9cohabitation \u203a\u203a&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-65-9808' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#easy-footnote-bottom-65-9808' title='C\u00e9cile Van de Velde, &lt;em&gt;Devenir adulte. Sociologie compar\u00e9e de la jeunesse en Europe&lt;\/em&gt;, Paris, Presses universitaires de France, 2008.'><sup>65<\/sup><\/a><\/span><\/span> des jeunes individus est un dispositif clef de la mobilit\u00e9 sociale danoise. <a href=\"https:\/\/legrandcontinent.eu\/2017\/07\/15\/modele-danois\/\">Comme je l\u2019\u00e9voquais dans un article pr\u00e9c\u00e9dent<\/a> sur la famille et l\u2019\u00c9tat au Danemark, les \u00e9tudiants peuvent b\u00e9n\u00e9ficier du <em>SU<\/em>, allocation universelle et inconditionnelle au montant unique de 810 euros par mois pendant 6 ans. L\u2019\u00e9galit\u00e9 de sa structuration \u00e9conomique permet de limiter les effets de reproduction sociale en donnant \u00e0 tous la capacit\u00e9 de ne plus habiter chez ses parents et d\u2019obtenir un cursus \u00e9ducatif sup\u00e9rieur.<br><\/p>\n\n\n\n<p>En effet, les pays scandinaves, de mani\u00e8re g\u00e9n\u00e9rale, poss\u00e8dent le taux de mobilit\u00e9 sociale le plus \u00e9lev\u00e9 des pays de l\u2019OCDE, tr\u00e8s sup\u00e9rieur \u00e0 la France o\u00f9 celle-ci s\u2019est enray\u00e9e&#160;: c\u2019est ce qui permet aux habitants de tous les espaces danois, de b\u00e9n\u00e9ficier d\u2019opportunit\u00e9s \u00e9conomiques ou \u00e9ducatives en se d\u00e9pla\u00e7ant facilement dans les centres urbains, l\u00e0 o\u00f9 les espaces marginaux fran\u00e7ais ont tendance \u00e0 renfermer la territorialisation des individus sur eux-m\u00eames \u00e0 cause de l\u2019incapacit\u00e9 financi\u00e8re croissante \u00e0 se d\u00e9placer, o\u00f9 \u00e0 aller trouver ailleurs l\u2019opportunit\u00e9 d\u2019une vie meilleure.<br><\/p>\n\n\n\n<p>En ce sens, il faut faire l\u2019hypoth\u00e8se que le TGV produit des \u00ab&#160;effets couloirs&#160;\u00bb dans les espaces qu\u2019il traverse sans desservir (comme le Morvan en Bourgogne sur la ligne Paris-Lyon), alors que le syst\u00e8me ferroviaire danois maintient une certaine r\u00e9ticularit\u00e9 territoriale en conservant la desserte de petites localit\u00e9s sur les grandes lignes reliant les deux m\u00e9tropoles entre elles (il n\u2019existe pas \u2014 encore \u2014 de ligne directe et rapide entre Copenhague et Aarhus). Certes, la mobilit\u00e9 spatiale induite par le <em>SU<\/em> ne peut r\u00e9soudre les disparit\u00e9s territoriales, mais il permet n\u00e9anmoins d\u2019en r\u00e9duire les effets sociaux n\u00e9gatifs. J\u00f8rgen M\u00f8ller \u00e9voque le <em>brain drain<\/em> de la jeunesse du Danemark p\u00e9riph\u00e9rique dont le niveau \u00e9ducatif acquis dans les universit\u00e9s des grandes villes ne leur permet pas de travailler dans les zones marginalis\u00e9es o\u00f9 les emplois sont souvent sous-qualifi\u00e9s. Comme nous l\u2019\u00e9voquions dans <a href=\"https:\/\/legrandcontinent.eu\/2018\/01\/08\/il-a-une-vie-apres-la-democratie-entretien-avec-emmanuel-todd\/\">notre entretien avec Emmanuel Todd<\/a>, l\u2019\u00c9tat social danois maintient sa capacit\u00e9 \u00e0 autonomiser financi\u00e8rement le passage des jeunes \u00e9tudiants \u00e0 la vie adulte (selon le mod\u00e8le anthropologique de la famille nucl\u00e9aire absolue), de sorte qu\u2019il pr\u00e9serve l\u2019id\u00e9al d\u00e9mocratique de la classe moyenne et de l\u2019\u00ab&#160;ascenseur social&#160;\u00bb, l\u00e0 o\u00f9 le mod\u00e8le universaliste r\u00e9publicain fragilise davantage l\u2019\u00e9galit\u00e9 des chances par l\u2019\u00e9clatement de la classe moyenne.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Bibliographie<\/h4>\n\n\n\n<p>Publications acad\u00e9miques (g\u00e9ographie, am\u00e9nagement du territoire) utilisant les concepts de \u2039\u2039 Banane pourrie \u203a\u203a et de \u2039\u2039 Danemark p\u00e9riph\u00e9rique \u203a\u203a&#160;:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>J\u00f8rgen M\u00f8ller, Jan K. Staunstrup, <em>Landsbyerne i Nordjylland&#160;: et fors\u00f8mt planl\u00e6gnings- og udviklingsobjekt med betydelige potentialer for fremtidig udvikling<\/em>, Center for Regional Udvikling (CRU), Aalborg Universitet, 2008.<\/li><li>Nicolas Escach, \u00ab&#160;Renaissance des d\u00e9serts danois&#160;\u00bb, <em>Le Monde diplomatique<\/em>, avril 2017, p. 21.<\/li><li>Jan Holm Ingemann,<em> Den postagrare ruralitet og den r\u00e5dne banan, et institutionelt \u00f8konomisk perspektiv, <\/em>Aalborg Universitet, Institut for \u00d8konomi, Politik og Forvaltning, 2010.<\/li><\/ul>\n\n\n\n<p>Publications sur la recomposition des territoires fran\u00e7ais&#160;:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Anne Clerval, <em>Paris sans le peuple<\/em>, Paris, La D\u00e9couverte, 2013.<\/li><li>Christophe Guilluy, <em>La France p\u00e9riph\u00e9rique. Comment on a sacrifi\u00e9 les classes populaires<\/em>, Paris, Flammarion, 2014.<\/li><li>Herv\u00e9 Le Bras, Emmanuel Todd, <em>Le myst\u00e8re fran\u00e7ais<\/em>, Paris, Le Seuil, 2013.<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Cet article se propose de montrer comment les territoires fran\u00e7ais et danois sont soumis aux m\u00eames dynamiques spatiales \u00e0 l\u2019\u00e9chelle europ\u00e9enne et construisent la m\u00eame interrogation politique sur l\u2019avenir de l\u2019\u00e9galit\u00e9 sociale et territoriale dans les d\u00e9mocraties occidentales.<\/p>\n","protected":false},"author":4,"featured_media":9816,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-angles.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":0,"footnotes":""},"categories":[1734],"tags":[],"staff":[1619],"editorial_format":[4944],"serie":[],"audience":[],"geo":[547],"class_list":["post-9808","post","type-post","status-publish","format-standard","hentry","category-doctrines","staff-dorian-bianco","editorial_format-actu-longues","geo-nordiques"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":9816,"excerpt":"Cet article se propose de montrer comment les territoires fran\u00e7ais et danois sont soumis aux m\u00eames dynamiques spatiales \u00e0 l\u2019\u00e9chelle europ\u00e9enne et construisent la m\u00eame interrogation politique sur l\u2019avenir de l\u2019\u00e9galit\u00e9 sociale et territoriale dans les d\u00e9mocraties occidentales.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le Danemark p\u00e9riph\u00e9rique | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Danemark p\u00e9riph\u00e9rique | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Cet article se propose de montrer comment les territoires fran\u00e7ais et danois sont soumis aux m\u00eames dynamiques spatiales \u00e0 l\u2019\u00e9chelle europ\u00e9enne et construisent la m\u00eame interrogation politique sur l\u2019avenir de l\u2019\u00e9galit\u00e9 sociale et territoriale dans les d\u00e9mocraties occidentales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-15T17:53:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-07T02:16:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/IMG_0789.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"614\" \/>\n\t<meta property=\"og:image:height\" content=\"344\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"gegeurope\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"gegeurope\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"38 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/\",\"name\":\"Le Danemark p\u00e9riph\u00e9rique | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/IMG_0789.jpg\",\"datePublished\":\"2018-04-15T17:53:10+00:00\",\"dateModified\":\"2019-04-07T02:16:53+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/25753fbf57948f81eb98a2daaf0a1f44\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/IMG_0789.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/IMG_0789.jpg\",\"width\":614,\"height\":344},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Danemark p\u00e9riph\u00e9rique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/25753fbf57948f81eb98a2daaf0a1f44\",\"name\":\"gegeurope\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/332bc77b348876050983d79aac818e16?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/332bc77b348876050983d79aac818e16?s=96&d=mm&r=g\",\"caption\":\"gegeurope\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Danemark p\u00e9riph\u00e9rique | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/","og_locale":"fr_FR","og_type":"article","og_title":"Le Danemark p\u00e9riph\u00e9rique | Le Grand Continent","og_description":"Cet article se propose de montrer comment les territoires fran\u00e7ais et danois sont soumis aux m\u00eames dynamiques spatiales \u00e0 l\u2019\u00e9chelle europ\u00e9enne et construisent la m\u00eame interrogation politique sur l\u2019avenir de l\u2019\u00e9galit\u00e9 sociale et territoriale dans les d\u00e9mocraties occidentales.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/","og_site_name":"Le Grand Continent","article_published_time":"2018-04-15T17:53:10+00:00","article_modified_time":"2019-04-07T02:16:53+00:00","og_image":[{"width":614,"height":344,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/IMG_0789.jpg","type":"image\/jpeg"}],"author":"gegeurope","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"gegeurope","Dur\u00e9e de lecture estim\u00e9e":"38 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/","url":"https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/","name":"Le Danemark p\u00e9riph\u00e9rique | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/IMG_0789.jpg","datePublished":"2018-04-15T17:53:10+00:00","dateModified":"2019-04-07T02:16:53+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/25753fbf57948f81eb98a2daaf0a1f44"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/IMG_0789.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/IMG_0789.jpg","width":614,"height":344},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2018\/04\/15\/le-danemark-peripherique-symbole-dune-europe-occidentale-a-deux-vitesses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Le Danemark p\u00e9riph\u00e9rique"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/25753fbf57948f81eb98a2daaf0a1f44","name":"gegeurope","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/332bc77b348876050983d79aac818e16?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/332bc77b348876050983d79aac818e16?s=96&d=mm&r=g","caption":"gegeurope"}}]}},"lgc_categories":[{"id":1734,"name":"Livres","slug":"doctrines"}],"lgc_author":{"id":1619,"name":"Dorian Bianco","slug":"dorian-bianco","description":null,"first_name":null,"last_name":null,"picture":null},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/IMG_0789.jpg","width":614,"height":344,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2018\/04\/IMG_0789.jpg","width":614,"height":344,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/9808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=9808"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/9808\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/9816"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=9808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=9808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=9808"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=9808"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=9808"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=9808"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=9808"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=9808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}