{"id":74944,"date":"2020-06-08T11:07:11","date_gmt":"2020-06-08T09:07:11","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=74944"},"modified":"2020-06-08T11:07:12","modified_gmt":"2020-06-08T09:07:12","slug":"chine-la-reforme-de-la-sante-publique-et-lillusion-de-la-demande-interne","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2020\/06\/08\/chine-la-reforme-de-la-sante-publique-et-lillusion-de-la-demande-interne\/","title":{"rendered":"Chine&#160;: la r\u00e9forme de la sant\u00e9 publique et l&rsquo;illusion de la demande interne"},"content":{"rendered":"\n<p>En d\u00e9but de semaine, le pr\u00e9sident Xi a tenu une\u00a0<a href=\"https:\/\/mp.weixin.qq.com\/s\/raEaJF_gzbZ45WSflrYh6w\">r\u00e9union<\/a>\u00a0lors de laquelle il a insist\u00e9 sur la n\u00e9cessit\u00e9 de r\u00e9former le syst\u00e8me de sant\u00e9 et de construire \u00ab&#160;un syst\u00e8me de sant\u00e9 publique \u00e0 m\u00eame de prot\u00e9ger la vie des gens&#160;\u00bb. En particulier, Xi a soulign\u00e9 le besoin urgent de renforcer la capacit\u00e9 de surveillance et d\u2019alerte pr\u00e9coce des \u00e9pid\u00e9mies et des urgences de sant\u00e9 publique, et d\u2019arriver \u00e0 un meilleur m\u00e9canisme de surveillance des maladies de causes inconnues et des incidents sanitaires anormaux. Les d\u00e9clarations du pr\u00e9sident mettent \u00e9galement l\u2019accent sur le besoin d\u2019allier expertise scientifique et mobilisation de ressources pour lutter efficacement contre les \u00e9pid\u00e9mies, comme l\u2019a montr\u00e9 l\u2019exp\u00e9rience de la gestion de la crise du COVID.\u00a0<em>Notons que la Chine est cens\u00e9e avoir r\u00e9form\u00e9 son syst\u00e8me d\u2019alerte avanc\u00e9 en cas de menace \u00e9pid\u00e9mique apr\u00e8s l\u2019\u00e9pid\u00e9mie de SARS en 2003. Que va-t-il sortir de ces appels \u00e0 r\u00e9forme&#160;?<\/em><\/p>\n\n\n\n<p><a href=\"https:\/\/apnews.com\/3c061794970661042b18d5aeaaed9fae?pnespid=lvV3oOZWGA_N0M0XUCVLfom9ofe6OPhefpS_vQUv\">Associated Press<\/a>&nbsp;a publi\u00e9 cette semaine des r\u00e9v\u00e9lations int\u00e9ressantes sur les origines du dysfonctionnement de l\u2019administration chinoise au d\u00e9but de l\u2019\u00e9pid\u00e9mie. Selon les informations obtenues par l\u2019agence am\u00e9ricaine, l\u2019OMS qui a chant\u00e9 les louanges de la Chine sur la sc\u00e8ne internationale \u00e9tait frustr\u00e9e en priv\u00e9e du peu d\u2019informations re\u00e7ues et de la lenteur \u00e0 laquelle les nouvelles donn\u00e9es sur la maladie lui \u00e9taient transmises. La Chine aurait ainsi attendu plus d\u2019une semaine avant de transmettre le g\u00e9nome d\u00e9cod\u00e9 aux autorit\u00e9s sanitaire internationales. L\u2019article pose plusieurs questions sur la strat\u00e9gie risqu\u00e9e de l\u2019OMS de cajoler la Chine pour acc\u00e9der \u00e0 davantage d\u2019informations sur l\u2019\u00e9pid\u00e9mie. Enfin, les r\u00e9v\u00e9lations d\u2019AP offrent des indices sur certaines raisons qui peuvent expliquer l\u2019absence de partage d\u2019informations et la censure de diff\u00e9rents r\u00e9sultats de s\u00e9quen\u00e7age d\u00e9but janvier&#160;: la rivalit\u00e9 entre certains laboratoires et le Centre De Contr\u00f4le des maladies (CDC). En effet, les scientifiques de ce dernier sont en rivalit\u00e9 tant entre eux qu\u2019avec les autres scientifiques, dans une course afin de publier les r\u00e9sultats au plus vite. Ainsi le CDC aurait voulu s\u2019assurer que ses \u00e9quipes (ou l\u2019une d\u2019entre elles) publient les r\u00e9sultats en premier.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-large  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/yYe9H\/2\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<h4 class=\"wp-block-heading\">L&rsquo;illusion de la consommation<\/h4>\n\n\n\n<p>En mars, de nombreux \u00e9conomistes ou chefs d\u2019entreprises anticipaient un rebond net de la consommation une fois l\u2019\u00e9pid\u00e9mie pass\u00e9e. Cette consommation impulsive aurait alors permis de relancer l\u2019\u00e9conomie. On se rend aujourd\u2019hui compte que cette reprise massive \u00e9tait&nbsp;<a href=\"https:\/\/mp.weixin.qq.com\/s\/2q5szAE22ZLrpM5V1mKtVg\">illusoire<\/a>. Les chiffres des vacances du 1er mai (5 jours de vacances) sont un bon exemple&#160;: le nombre de touriste repr\u00e9sentaittseulement 60&#160;% de celui de l\u2019ann\u00e9e derni\u00e8re, et le nombre de passager dans les transports seulement 45&#160;% du chiffre de l\u2019ann\u00e9e pr\u00e9c\u00e9dente. Selon Huxiu, le probl\u00e8me est plus g\u00e9n\u00e9ral&#160;: la demande chinoise montre des signes de fatigue. Depuis deux ans d\u00e9j\u00e0, on observe que la croissance de la consommation ralentit depuis deux ans d\u00e9j\u00e0. Cette faiblesse peut s\u2019expliquer d\u2019une part par la dette des m\u00e9nages chinois, qui est parmi les plus \u00e9lev\u00e9e au monde. Elle atteint d\u00e9sormais des niveaux comparables \u00e0 celle des m\u00e9nages am\u00e9ricains avant la crise financi\u00e8re de 2008. D\u2019autre part, l\u2019explosion du e-commerce a eu pour effet de capter une grande partie des d\u00e9penses de la population.<\/p>\n\n\n\n<p>Ainsi, l\u2019\u00e9pid\u00e9mie a port\u00e9 un coup d\u00e9cisif \u00e0 une consommation d\u00e9j\u00e0 amoindrie. Selon une \u00e9tude d\u2019un centre de recherche de l\u2019universit\u00e9 Renmin, 70&#160;% des salari\u00e9s chinois pensent que leur salaire va baisser \u00e0 la suite de l\u2019\u00e9pid\u00e9mie et la majorit\u00e9 d\u2019entre eux pense pouvoir maintenir leur niveau de consommation pendant seulement 3 mois. Une chute de la consommation serait dommageable aux millions de TPE et micro-entreprises chinoises, qui repr\u00e9sentent 85&#160;% du total des entreprises. Pour cette raison, P\u00e9kin a fait le choix de distribuer les coupons de consommation dont nous avons d\u00e9j\u00e0 parl\u00e9 dans d\u2019anciens Passe Muraille. Selon Huxiu, cette strat\u00e9gie est meilleure car elle permet de soutenir la consommation, l\u00e0 o\u00f9 des \u201csubventions\u201d \u00e0 l\u2019am\u00e9ricaine ne garantissent pas une consommation accrue des m\u00e9nages.<\/p>\n\n\n\n<p>Ces coupons sont d\u00e9sormais utilis\u00e9s dans la&nbsp;<a href=\"https:\/\/mp.weixin.qq.com\/s\/FEiVUAC5XKj_Wm5uHhhI_w\">majorit\u00e9<\/a>&nbsp;des villes chinoises. P\u00e9kin a rejoint la danse le 6 juin avec des milliards de RMB distribu\u00e9s notamment aux particuliers, coupons devant \u00eatre utilis\u00e9s dans des magasins ou des restaurants participants \u00e0 l\u2019op\u00e9ration. Si Hangzhou fut la ville pionni\u00e8re des coupons consommation, de nombreuses villes ont adopt\u00e9 cet outil pour booster la consommation en particulier lors de la crise financi\u00e8re de 2008-2009 \u2013 voir notamment le tableau dans l\u2019article. Les r\u00e9sultats seraient probants&#160;: \u00e0 Hangzhou, lors de la premi\u00e8re vague de coupons lanc\u00e9s le 27 mars, une moyenne de 35 yuan investis a \u201cprovoqu\u00e9\u201d pr\u00e8s de 130 yuan de d\u00e9pens\u00e9s par les particuliers, soit un effet d\u2019entra\u00eenement de 3,5. N\u00e9anmoins le recours aux coupons consommation ne fait pas l\u2019unanimit\u00e9, ou plut\u00f4t suscite des interrogations.<\/p>\n\n\n\n<p>En effet, certains chercheurs et \u00e9conomistes se posent des question sur l\u2019utilit\u00e9 \u00e0 long terme de ces outils. Pour certains, les coupons risquent simplement d\u2019accro\u00eetre la consommation \u00e0 court terme, dans la mesure o\u00f9 les d\u00e9penses qui auraient pu \u00eatre r\u00e9parties sur l\u2019ann\u00e9e le sont d\u00e9sormais dans une p\u00e9riode de temps plus courte. Ainsi, ces coupons ne seraient qu\u2019un moyen pour les gouvernements locaux de stabiliser l\u2019\u00e9conomie locale, de lutter contre le ch\u00f4mage. Dans tous les cas, P\u00e9kin mise une grande partie de sa relance de la consommation sur ces coupons.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Les relations Chine-Europe face aux comm\u00e9morations du massacre de Tiananmen<\/h4>\n\n\n\n<p>Cette semaine est marqu\u00e9e par les comm\u00e9morations du massacre de Tiananmen du 4 juin 1989, anniversaire choisi pour le lancement d\u2019une&nbsp;<a href=\"https:\/\/www.ipac.global\/\">alliance internationale<\/a>&nbsp;pour la Chine, multipartisane et interparlementaire. Entendant prot\u00e9ger l\u2019int\u00e9grit\u00e9 des d\u00e9mocraties et des droits humains, le groupe compte, entre autres, deux d\u00e9put\u00e9s europ\u00e9ens, deux su\u00e9dois et deux allemands. Dans la m\u00eame veine, le Mus\u00e9e national des droits humains de Taiwan s\u2019est vu&nbsp;<a href=\"https:\/\/focustaiwan.tw\/politics\/202006040013?fbclid=IwAR0gO6qIGJCb2jjKkTxco_6bNS1f0QnLihekTOYPC6c72lCp51Hl3Ewbbuk\">attribu\u00e9<\/a>&nbsp;une r\u00e9compense sp\u00e9ciale dans le cadre du Prix Karl Wilhelm Fricke, une organisation parlementaire allemande.<\/p>\n\n\n\n<p>Les revendications du 4 juin 1989 ont non seulement fait \u00e9cho aux manifestations pro-d\u00e9mocratie \u00e0 Hong Kong, mais ont \u00e9galement permis le parall\u00e8le avec les protestations aux \u00c9tats-Unis suivant l\u2019assassinat de George Floyd par la police locale. En effet, les m\u00e9dias de propagande chinois ont d\u2019une part&nbsp;<a href=\"https:\/\/www.reuters.com\/article\/us-usa-china-media-idUSKBN23824K?fbclid=IwAR0rHwAilIrvo_q08Gau-x_frfpVEautRnm1aO4fcQaL4loEvR7-7UJ_6n4\">abondamment couvert<\/a>&nbsp;l\u2019\u00e9v\u00e9nement dans le but de discr\u00e9diter les attaques contre la politique de s\u00e9curit\u00e9 hongkongaise en Occident (\u00e0 la fois sur les&nbsp;<a href=\"https:\/\/twitter.com\/MFA_China\/status\/1267431278954942464\">r\u00e9seaux sociaux<\/a>&nbsp;et dans la&nbsp;<a href=\"http:\/\/world.people.com.cn\/n1\/2020\/0605\/c1002-31736312.html\">presse chinoise<\/a>), mais ceux-ci en ont d\u2019autre part profit\u00e9 pour&nbsp;<a href=\"https:\/\/twitter.com\/HuXijin_GT\/status\/1268576790257078273\">comparer<\/a>&nbsp;la r\u00e9pression de 1989 avec les conflits populaires am\u00e9ricains actuels dans un effort de (ce qui semble \u00eatre une) justification.<\/p>\n\n\n\n<p>Dans un contexte qui se tend toujours plus, le vice-ministre des Affaires \u00c9trang\u00e8res chinois Le Yucheng s\u2019est&nbsp;<a href=\"https:\/\/www.fmprc.gov.cn\/web\/wjdt_674879\/wjbxw_674885\/t1785337.shtml\">entretenu<\/a>&nbsp;avec la secr\u00e9taire g\u00e9n\u00e9rale du Service europ\u00e9en d\u2019action ext\u00e9rieure Helga Schmidt. L\u2019appel a \u00e9t\u00e9 l\u2019occasion pour le c\u00f4t\u00e9 chinois de d\u00e9plorer une nouvelle fois la politisation de la pand\u00e9mie et de rappeler l\u2019agenda charg\u00e9 des relations sino-europ\u00e9ennes pour les prochains mois. Toujours lors d\u2019une&nbsp;<a href=\"https:\/\/www.fmprc.gov.cn\/web\/wjdt_674879\/wjbxw_674885\/t1785333.shtml\">conversation t\u00e9l\u00e9phonique<\/a>, les affaires \u00e9trang\u00e8res chinoises ont \u00e9galement r\u00e9it\u00e9r\u00e9 leur soutien \u00e0 la coop\u00e9ration internationale et \u00e0 l\u2019OMS, accueilli positivement l\u2019engagement de l\u2019Allemagne envers le maintien des relations diplomatiques avec la Chine, et fait la part belle aux questions \u00e9conomiques.<\/p>\n\n\n\n<p>Toutefois, le sommet UE-Chine de Leipzig, dont l\u2019Allemagne redoutait le report pendant sa pr\u00e9sidence du Conseil de l\u2019Union europ\u00e9enne, devra finalement bien se trouver une&nbsp;<a href=\"https:\/\/www.politico.eu\/article\/eu-china-summit-postponed-due-to-coronavirus-concerns\/\">nouvelle date<\/a>. C\u00f4t\u00e9&nbsp;<a href=\"https:\/\/twitter.com\/n_roettgen\/status\/1268600564432199680\">allemand<\/a>, on justifie ce report par le manque de transparence dans la crise du COVID-19 et les tentatives de coercition de la Chine vis-\u00e0-vis de Hong Kong. Quoi qu\u2019il en soit, l\u2019excuse du virus est per\u00e7ue comme&nbsp;<a href=\"https:\/\/www.lemonde.fr\/idees\/article\/2020\/06\/05\/les-europeens-face-a-la-muraille-de-chine_6041878_3232.html\">fallacieuse<\/a>&nbsp;par certains observateurs qui pr\u00e9f\u00e8rent accuser le climat politique particuli\u00e8rement difficile en ce moment.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/jF6OK\/1\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Le ton avec le Royaume-Uni l\u2019illustre bien, le pays ayant \u00e9t\u00e9 pri\u00e9 de\u00a0<a href=\"https:\/\/www.fmprc.gov.cn\/mfa_eng\/xwfw_665399\/s2510_665401\/2511_665403\/t1785528.shtml\">se retirer<\/a>\u00a0et d\u2019abandonner ses vell\u00e9it\u00e9s colonialistes dignes de la \u00ab&#160;guerre froide&#160;\u00bb (ironique quand on sait que le terme a \u00e9t\u00e9\u00a0<a href=\"https:\/\/eastisred.fr\/passe-muraille-n64-semaine-du-25-mai\/\">utilis\u00e9 r\u00e9cemment<\/a>\u00a0par la Chine pour qualifier son diff\u00e9rend avec les \u00c9tats-Unis). Si Boris Johnson\u00a0<a href=\"https:\/\/www.nytimes.com\/2020\/06\/03\/world\/europe\/boris-johnson-uk-hong-kong-china.html\">s\u2019engage<\/a>\u00a0sur la mise en place d\u2019un syst\u00e8me de citoyennet\u00e9 sp\u00e9cial pour les ressortissants hongkongais, la diplomatie chinoise a\u00a0<a href=\"http:\/\/chnun.chinamission.org.cn\/eng\/hyyfy\/t1783532.htm\"><em>rappel\u00e9<\/em><\/a>\u00a0que les promesses d\u2019autonomie de Hong Kong par la Chine relevaient plus du droit chinois et hongkongais que de la D\u00e9claration conjointe sino-britannique. Un argument\u00a0<a href=\"https:\/\/www.ft.com\/content\/27d82ae3-6a4f-4b44-ada1-90692721ac7a\">contest\u00e9<\/a>\u00a0par le Royaume-Uni.<\/p>\n\n\n\n<p>L\u2019Australie, qui a pris des risques politiques et \u00e9conomiques ces derni\u00e8res semaines, profiterait tout aussi bien d\u2019une position europ\u00e9enne plus ferme sur Hong Kong, mais ses relations avec l\u2019UE sont teint\u00e9es d\u2019un&nbsp;<a href=\"https:\/\/www.politico.eu\/article\/as-australia-clashes-with-china-the-eu-lays-low-pandemic-coronavirus\/?fbclid=IwAR0kStI5QzP0B3Y564sHoNS6g_d050LjukpDeXjlK7dGzdAaQvYFJG-VDVk\">d\u00e9sint\u00e9r\u00eat<\/a>&nbsp;particuli\u00e8rement criant dans le contexte de son conflit avec la Chine.<\/p>\n\n\n\n<p>\u00c0 l\u2019inverse, le t\u00e9l\u00e9phone diplomatique (qui semble avoir repris du service cette semaine) a permis \u00e0 la Chine de\u00a0<a href=\"https:\/\/www.fmprc.gov.cn\/web\/wjdt_674879\/wjbxw_674885\/t1786178.shtml\">vendre<\/a>\u00a0\u00ab&#160;l\u2019histoire touchante de deux pays [la Chine et l\u2019Italie] ayant combattu la pand\u00e9mie main dans la main&#160;\u00bb un \u00ab&#160;mod\u00e8le de coop\u00e9ration&#160;\u00bb pour le monde. La Chine a de nouveau propos\u00e9 son aide et salu\u00e9 le cinquanti\u00e8me anniversaire des relations sino-italiennes. Une occasion, selon elle, d\u2019approfondir des liens soud\u00e9s par les nouvelles routes de la soie.<\/p>\n\n\n\n<p>Cette nouvelle publicit\u00e9 exacerbe encore le foss\u00e9 communicationnel entre l\u2019UE et la Chine. Selon la vice-pr\u00e9sidente et commissaire charg\u00e9e des valeurs et de la transparence&nbsp;<a href=\"https:\/\/www.politico.eu\/article\/vera-jourova-china-filled-void-of-eu-communication-during-crisis\/\">V\u00e9ra Jourov\u00e1<\/a>, l\u2019UE a failli dans sa propre campagne de relations publiques, l\u00e0 o\u00f9 la Chine a non seulement fait l\u2019apologie de son aide aux pays europ\u00e9ens, mais a \u00e9galement produit de la d\u00e9sinformation, sur laquelle un rapport devrait \u00eatre publi\u00e9 la semaine prochaine.<\/p>\n\n\n\n<p>Mais d\u00e9j\u00e0 cette semaine,\u00a0<em>China Daily\u00a0<\/em>a publi\u00e9 sa propre\u00a0<a href=\"https:\/\/global.chinadaily.com.cn\/a\/202004\/02\/WS5e859531a310128217283f57.html\">vid\u00e9o<\/a>\u00a0d\u00e9non\u00e7ant le sentiment anti-chinois qui a marqu\u00e9 le paysage audiovisuel hors de Chine depuis le d\u00e9but de la crise. Si les revendications sont\u00a0<a href=\"https:\/\/www.politico.com\/news\/2020\/05\/20\/anti-china-sentiment-coronavirus-poll-269373\">l\u00e9gitimes<\/a>, le document reste un produit de propagande pure port\u00e9 par des \u00ab&#160;experts&#160;\u00bb occidentaux et un contenu lacunaire et biais\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En d\u00e9but de semaine, le pr\u00e9sident Xi a tenu une r\u00e9union lors de laquelle il a insist\u00e9 sur la n\u00e9cessit\u00e9 de r\u00e9former le syst\u00e8me de sant\u00e9 et de construire \u00ab&#160;&#160;un syst\u00e8me de sant\u00e9 publique \u00e0 m\u00eame de prot\u00e9ger la vie des gens&#160;&#160;\u00bb. En plus, cette semaine est marqu\u00e9e par les comm\u00e9morations du massacre de Tiananmen du 4 juin 1989, anniversaire choisi pour le lancement d\u2019une alliance internationale pour la Chine, multipartisane et interparlementaire.<\/p>\n","protected":false},"author":175,"featured_media":72256,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-studies.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":0,"footnotes":""},"categories":[1727,1731],"tags":[],"staff":[2352],"editorial_format":[4849],"serie":[],"audience":[],"geo":[531],"class_list":["post-74944","post","type-post","status-publish","format-standard","hentry","category-economie","category-politique","staff-pierre-sel-eastisred","editorial_format-etudes","geo-chine"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":72256,"excerpt":"En d\u00e9but de semaine, le pr\u00e9sident Xi a tenu une r\u00e9union lors de laquelle il a insist\u00e9 sur la n\u00e9cessit\u00e9 de r\u00e9former le syst\u00e8me de sant\u00e9 et de construire \u00ab un syst\u00e8me de sant\u00e9 publique \u00e0 m\u00eame de prot\u00e9ger la vie des gens \u00bb. En plus, cette semaine est marqu\u00e9e par les comm\u00e9morations du massacre de Tiananmen du 4 juin 1989, anniversaire choisi pour le lancement d\u2019une alliance internationale pour la Chine, multipartisane et interparlementaire.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Chine : la r\u00e9forme de la sant\u00e9 publique et l&#039;illusion de la demande interne | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2020\/06\/08\/chine-la-reforme-de-la-sante-publique-et-lillusion-de-la-demande-interne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chine : la r\u00e9forme de la sant\u00e9 publique et l&#039;illusion de la demande interne | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"En d\u00e9but de semaine, le pr\u00e9sident Xi a tenu une r\u00e9union lors de laquelle il a insist\u00e9 sur la n\u00e9cessit\u00e9 de r\u00e9former le syst\u00e8me de sant\u00e9 et de construire \u00ab&#160;un syst\u00e8me de sant\u00e9 publique \u00e0 m\u00eame de prot\u00e9ger la vie des gens&#160;\u00bb. En plus, cette semaine est marqu\u00e9e par les comm\u00e9morations du massacre de Tiananmen du 4 juin 1989, anniversaire choisi pour le lancement d\u2019une alliance internationale pour la Chine, multipartisane et interparlementaire.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2020\/06\/08\/chine-la-reforme-de-la-sante-publique-et-lillusion-de-la-demande-interne\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-08T09:07:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-08T09:07:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/05\/Grafica-2020-05-11-alle-09.52.28.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1482\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Giovanni Collot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/05\/Grafica-2020-05-11-alle-09.52.28.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giovanni Collot\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2020\/06\/08\/chine-la-reforme-de-la-sante-publique-et-lillusion-de-la-demande-interne\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2020\/06\/08\/chine-la-reforme-de-la-sante-publique-et-lillusion-de-la-demande-interne\/\",\"name\":\"Chine : la r\u00e9forme de la sant\u00e9 publique et l'illusion de la demande interne | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2020\/06\/08\/chine-la-reforme-de-la-sante-publique-et-lillusion-de-la-demande-interne\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2020\/06\/08\/chine-la-reforme-de-la-sante-publique-et-lillusion-de-la-demande-interne\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/05\/Grafica-2020-05-11-alle-09.52.28.jpg\",\"datePublished\":\"2020-06-08T09:07:11+00:00\",\"dateModified\":\"2020-06-08T09:07:12+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2020\/06\/08\/chine-la-reforme-de-la-sante-publique-et-lillusion-de-la-demande-interne\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2020\/06\/08\/chine-la-reforme-de-la-sante-publique-et-lillusion-de-la-demande-interne\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2020\/06\/08\/chine-la-reforme-de-la-sante-publique-et-lillusion-de-la-demande-interne\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/05\/Grafica-2020-05-11-alle-09.52.28.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/05\/Grafica-2020-05-11-alle-09.52.28.jpg\",\"width\":2560,\"height\":1482},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2020\/06\/08\/chine-la-reforme-de-la-sante-publique-et-lillusion-de-la-demande-interne\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chine&#160;: la r\u00e9forme de la sant\u00e9 publique et l&rsquo;illusion de la demande interne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef\",\"name\":\"Giovanni Collot\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g\",\"caption\":\"Giovanni Collot\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chine : la r\u00e9forme de la sant\u00e9 publique et l'illusion de la demande interne | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2020\/06\/08\/chine-la-reforme-de-la-sante-publique-et-lillusion-de-la-demande-interne\/","og_locale":"fr_FR","og_type":"article","og_title":"Chine : la r\u00e9forme de la sant\u00e9 publique et l'illusion de la demande interne | Le Grand Continent","og_description":"En d\u00e9but de semaine, le pr\u00e9sident Xi a tenu une r\u00e9union lors de laquelle il a insist\u00e9 sur la n\u00e9cessit\u00e9 de r\u00e9former le syst\u00e8me de sant\u00e9 et de construire \u00ab&#160;un syst\u00e8me de sant\u00e9 publique \u00e0 m\u00eame de prot\u00e9ger la vie des gens&#160;\u00bb. En plus, cette semaine est marqu\u00e9e par les comm\u00e9morations du massacre de Tiananmen du 4 juin 1989, anniversaire choisi pour le lancement d\u2019une alliance internationale pour la Chine, multipartisane et interparlementaire.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2020\/06\/08\/chine-la-reforme-de-la-sante-publique-et-lillusion-de-la-demande-interne\/","og_site_name":"Le Grand Continent","article_published_time":"2020-06-08T09:07:11+00:00","article_modified_time":"2020-06-08T09:07:12+00:00","og_image":[{"width":2560,"height":1482,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/05\/Grafica-2020-05-11-alle-09.52.28.jpg","type":"image\/jpeg"}],"author":"Giovanni Collot","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/05\/Grafica-2020-05-11-alle-09.52.28.jpg","twitter_misc":{"\u00c9crit par":"Giovanni Collot","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2020\/06\/08\/chine-la-reforme-de-la-sante-publique-et-lillusion-de-la-demande-interne\/","url":"https:\/\/legrandcontinent.eu\/fr\/2020\/06\/08\/chine-la-reforme-de-la-sante-publique-et-lillusion-de-la-demande-interne\/","name":"Chine : la r\u00e9forme de la sant\u00e9 publique et l'illusion de la demande interne | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2020\/06\/08\/chine-la-reforme-de-la-sante-publique-et-lillusion-de-la-demande-interne\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2020\/06\/08\/chine-la-reforme-de-la-sante-publique-et-lillusion-de-la-demande-interne\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/05\/Grafica-2020-05-11-alle-09.52.28.jpg","datePublished":"2020-06-08T09:07:11+00:00","dateModified":"2020-06-08T09:07:12+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2020\/06\/08\/chine-la-reforme-de-la-sante-publique-et-lillusion-de-la-demande-interne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2020\/06\/08\/chine-la-reforme-de-la-sante-publique-et-lillusion-de-la-demande-interne\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2020\/06\/08\/chine-la-reforme-de-la-sante-publique-et-lillusion-de-la-demande-interne\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/05\/Grafica-2020-05-11-alle-09.52.28.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/05\/Grafica-2020-05-11-alle-09.52.28.jpg","width":2560,"height":1482},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2020\/06\/08\/chine-la-reforme-de-la-sante-publique-et-lillusion-de-la-demande-interne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Chine&#160;: la r\u00e9forme de la sant\u00e9 publique et l&rsquo;illusion de la demande interne"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef","name":"Giovanni Collot","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g","caption":"Giovanni Collot"}}]}},"lgc_categories":[{"id":1727,"name":"\u00c9conomie","slug":"economie"},{"id":1731,"name":"Politique","slug":"politique"}],"lgc_author":{"id":2352,"name":"Pierre Sel","slug":"pierre-sel-eastisred","description":"Pierre Sel est co-fondateur d'EastIsRed (<a href=\"http:\/\/www.eastisred.fr\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.eastisred.fr&amp;source=gmail&amp;ust=1587453602547000&amp;usg=AFQjCNEu8KzjVJs7jTP66E_3nPhiSuHkRQ\">www.eastisred.fr<\/a>), soci\u00e9t\u00e9 de veille sur la Chine. Dans le cadre de ses recherches, il travaille sur le syst\u00e8me de cr\u00e9dit social chinois.","first_name":null,"last_name":null,"picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/09\/gc-pierre-sel.png","width":280,"height":280,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/05\/Grafica-2020-05-11-alle-09.52.28.jpg","width":2560,"height":1482,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/74944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=74944"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/74944\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/72256"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=74944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=74944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=74944"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=74944"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=74944"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=74944"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=74944"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=74944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}