{"id":74133,"date":"2020-05-30T15:32:32","date_gmt":"2020-05-30T13:32:32","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=74133"},"modified":"2020-05-30T15:34:24","modified_gmt":"2020-05-30T13:34:24","slug":"la-nouvelle-loi-de-securite-nationale-de-pekin-et-lavenir-de-hong-kong","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2020\/05\/30\/la-nouvelle-loi-de-securite-nationale-de-pekin-et-lavenir-de-hong-kong\/","title":{"rendered":"La nouvelle loi de s\u00e9curit\u00e9 nationale de P\u00e9kin et l\u2019avenir de Hong Kong"},"content":{"rendered":"\n<p>Le 28 mai P\u00e9kin a vot\u00e9 l&rsquo;approbation d&rsquo;une nouvelle loi sur la s\u00e9curit\u00e9 nationale qui, selon beaucoup, signifie la fin du cadre \u00ab&#160;Un pays, deux syst\u00e8mes&#160;\u00bb de Hong Kong&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-74133' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2020\/05\/30\/la-nouvelle-loi-de-securite-nationale-de-pekin-et-lavenir-de-hong-kong\/#easy-footnote-bottom-1-74133' title='BRADSHER Keith, &lt;a href=&quot;https:\/\/www.nytimes.com\/2020\/05\/28\/world\/asia\/china-hong-kong-crackdown.html&quot;&gt;China Approves Plan to Rein In Hong Kong, Defying Worldwide Outcry,&lt;\/a&gt; The New York Times, 28 mai 2020'><sup>1<\/sup><\/a><\/span><\/span>. D\u2019autres l\u2019ont qualifi\u00e9e de violation totale de l\u2019autonomie de la cit\u00e9 par la R\u00e9publique populaire de Chine. Dans cet article, nous esp\u00e9rons faire la lumi\u00e8re sur la nouvelle loi, sur certaines des nuances juridiques et sur ce qu\u2019elle signifie pour l\u2019avenir de Hong Kong.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Quelles sont les nouvelles lois sur la s\u00e9curit\u00e9 nationale&#160;? Et pourquoi sont-elles si controvers\u00e9es&#160;?<\/h4>\n\n\n\n<p>P\u00e9kin vient de voter officiellement un nouvel ensemble de lois sur la s\u00e9curit\u00e9 nationale, qui comprend l\u2019introduction d\u2019infractions p\u00e9nales pour des faits&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-74133' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2020\/05\/30\/la-nouvelle-loi-de-securite-nationale-de-pekin-et-lavenir-de-hong-kong\/#easy-footnote-bottom-2-74133' title='&lt;a href=&quot;https:\/\/www.scmp.com\/news\/hong-kong\/politics\/article\/3085412\/two-sessions-2020-how-far-will-beijing-go-push-article-23&quot;&gt;Two Sessions 2020&amp;#160;: Beijing \u2018out of patience\u2019 after long wait for Hong Kong national security law, plans to proscribe secession, foreign interference and terrorism in city, South China Morning Post,&lt;\/a&gt; 21 mai 2020'><sup>2<\/sup><\/a><\/span><\/span> relevants de la s\u00e9cession, la subversion, l\u2019ing\u00e9rence \u00e9trang\u00e8re et le terrorisme. Les lois devraient entrer en vigueur \u00e0 aout. <\/p>\n\n\n\n<p>Cela interdit effectivement un large spectre d\u2019activit\u00e9s politiques, qui comprendrait une grande partie de ce que nous avons vu jusqu\u2019\u00e0 pr\u00e9sent dans le mouvement de Hong Kong. L\u2019application des lois sur la s\u00e9dition et la subversion diminue le droit des Hongkongais \u00e0 la libert\u00e9 d\u2019expression et \u00e0 la libert\u00e9 de la presse. Toute relation avec des organisations politiques \u00e9trang\u00e8res pourrait \u00eatre consid\u00e9r\u00e9e comme une ing\u00e9rence \u00e9trang\u00e8re. Les affrontements avec la police, m\u00eame en cas de l\u00e9gitime d\u00e9fense contre leur violence inexplicable, pourraient \u00eatre qualifi\u00e9s d\u2019activit\u00e9s terroristes.<\/p>\n\n\n\n<p>Cependant, les clauses de s\u00e9curit\u00e9 nationale ne sont pas nouvelles \u00e0 Hong Kong. Nombre d\u2019entre elles se trouvent dans l\u2019article 23 de la loi fondamentale de Hong Kong, la mini-constitution de la cit\u00e9, mais les efforts d\u00e9ploy\u00e9s pour faire passer ces lois ont finalement \u00e9t\u00e9 abandonn\u00e9s apr\u00e8s qu\u2019un demi-million de personnes aient protest\u00e9 contre son adoption en 2003. Qu\u2019est-ce qui est diff\u00e9rent cette fois-ci&#160;? Pourquoi cette nouvelle a-t-elle provoqu\u00e9 un tel tumulte&#160;? Pourquoi le l\u00e9gislateur pro-d\u00e9mocratie Dennis Kwok a-t-il qualifi\u00e9 cette nouvelle de \u00ab&#160;<a href=\"https:\/\/www.washingtonpost.com\/world\/asia_pacific\/china-signals-plan-to-take-full-control-of-hong-kong-realigning-citys-status\/2020\/05\/21\/2c3850ee-9b48-11ea-ad79-eef7cd734641_story.html\">la pire chose la plus qui soit arriv\u00e9e \u00e0 Hong Kong<\/a> depuis la r\u00e9trocession&#160;\u00bb&#160;?<\/p>\n\n\n\n<p>Apr\u00e8s cette derni\u00e8re ann\u00e9e de protestations, P\u00e9kin est arriv\u00e9 \u00e0 la conclusion qu\u2019on ne peut plus faire confiance au gouvernement de Hong Kong (et \u00e0 son Conseil l\u00e9gislatif) pour l\u2019adoption et l\u2019application des lois sur la s\u00e9curit\u00e9 nationale.<\/p>\n\n\n\n<p>En d\u2019autres termes, l\u2019administration Xi en a assez de Hong Kong et ne se contente plus de laisser le chef de l\u2019ex\u00e9cutif de Hong Kong, Carrie Lam, \u00ab&#160;g\u00e9rer&#160;\u00bb le mouvement de protestation de Hong Kong. Au lieu d\u2019observer de loin, l\u2019administration Xi a d\u00e9cid\u00e9 d\u2019intervenir directement dans les processus l\u00e9gislatifs de Hong Kong et a l\u2019intention de battre les Hongkongais en soumission en utilisant \u00ab&#160;l\u2019\u00e9tat de droit&#160;\u00bb.<\/p>\n\n\n\n<p>N\u2019ayant plus aucune confiance dans le processus l\u00e9gislatif de Hong Kong, l\u2019administration de Xi veut confier la t\u00e2che de promulguer les lois de s\u00e9curit\u00e9 nationale de Hong Kong au Comit\u00e9 permanent du Congr\u00e8s national du peuple (NPCSC).<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Qu\u2019est-ce que le NPCSC&#160;? Quel est son r\u00f4le dans le syst\u00e8me politique et juridique de Hong Kong&#160;?<\/h4>\n\n\n\n<p>Le Comit\u00e9 permanent de l\u2019Assembl\u00e9e nationale populaire (NPCSC) est le plus haut organe du pouvoir d\u2019\u00c9tat de la R\u00e9publique populaire de Chine, et est domin\u00e9 par des membres du Parti communiste chinois. On peut consid\u00e9rer qu\u2019il dispose \u00e0 la fois des pouvoirs d\u2019un corps l\u00e9gislatif et d\u2019une cour constitutionnelle de derni\u00e8re instance dans le cas de Hong Kong&#160;; il a le pouvoir de r\u00e9diger certaines lois et d\u2019interpr\u00e9ter la constitution de Hong Kong pour d\u00e9cider si ces lois sont l\u00e9gales.<\/p>\n\n\n\n<p>Contrairement au Conseil l\u00e9gislatif de Hong Kong (LegCo), qui aurait du mal \u00e0 promulguer les lois de s\u00e9curit\u00e9 nationale en raison d\u2019un climat politique tendu et d\u2019une r\u00e9sistance pan-d\u00e9mocratique, le NPCSC &#8211; domin\u00e9 par les membres du PCC &#8211; devrait rapidement r\u00e9diger et approuver ces nouvelles lois de s\u00e9curit\u00e9 nationale pour Hong Kong. Cela signifie que P\u00e9kin serait en mesure de contourner toute r\u00e9sistance locale de Hong Kong qui serait alors impliqu\u00e9e dans ce processus.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/zkGm3\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Mais P\u00e9kin peut-il adopter directement des lois pour Hong Kong&#160;?<\/h4>\n\n\n\n<p>De fa\u00e7on g\u00e9n\u00e9rale, ce n\u2019est pas possible. Cependant, le NPCSC dispose d\u2019une arme secr\u00e8te&#160;: <a href=\"https:\/\/www.basiclaw.gov.hk\/pda\/en\/basiclawtext\/chapter_2.html\">l\u2019article 18 de la loi fondamentale de Hong Kong<\/a>. Cet article permet \u00e0 la RPC d\u2019appliquer directement ses lois \u00e0 Hong Kong, avec une r\u00e9serve cependant. L\u2019article permet uniquement de qualifier certaines lois de la RPC&#160;: les lois relatives \u00e0 la d\u00e9fense, aux affaires \u00e9trang\u00e8res, ou \u00e0 \u00ab&#160;d\u2019autres questions en hors des limites de l\u2019autonomie&#160;\u00bb de Hong Kong.<\/p>\n\n\n\n<p>La question juridique est de savoir si cette liste de lois sur la s\u00e9curit\u00e9 nationale peut \u00eatre class\u00e9e de mani\u00e8re satisfaisante dans l\u2019un de ces trois domaines. Heureusement, des lois telles que celles sur la s\u00e9cession, la subversion et m\u00eame le terrorisme ne sont g\u00e9n\u00e9ralement pas reconnues comme des questions de d\u00e9fense ou d\u2019affaires \u00e9trang\u00e8res (elles rel\u00e8vent plut\u00f4t d\u2019une cat\u00e9gorie diff\u00e9rente appel\u00e9e lois sur l\u2019ordre public). En outre, l\u2019article 23 stipule que les lois de s\u00e9curit\u00e9 nationale sont du ressort du gouvernement de Hong Kong et ne sont donc pas consid\u00e9r\u00e9es comme \u00ab&#160;d\u2019autres questions ne relevant pas des limites de l\u2019autonomie [de Hong Kong]&#160;\u00bb.<\/p>\n\n\n\n<p>Par cons\u00e9quent, la l\u00e9galit\u00e9 de l\u2019adoption par P\u00e9kin de ces lois de s\u00e9curit\u00e9 nationale en vertu de l\u2019article 18 est suspecte. Par contre, cela n\u2019emp\u00eachera pas de toute fa\u00e7on le NPCSC de les voter.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Ces lois peuvent-elles \u00eatre l\u00e9galement contest\u00e9es \u00e0 Hong Kong&#160;?<\/h4>\n\n\n\n<p>Les textes lois peuvent \u00eatre effectivement contest\u00e9s devant les tribunaux de Hong Kong pour en remettre en cause la l\u00e9galit\u00e9. Plus pr\u00e9cis\u00e9ment, elles peuvent \u00eatre contest\u00e9es sur la question de savoir si elles exc\u00e8dent les pouvoirs qui leur sont conf\u00e9r\u00e9s par la Loi fondamentale de Hong Kong. Il y a de bonnes raisons de croire qu\u2019une telle contestation peut m\u00eame aboutir. Toutefois, en vertu de l\u2019article 158, le NPCSC d\u00e9tient le pouvoir final d\u2019interpr\u00e9ter la loi comme il le souhaite, de sorte qu\u2019il peut toujours annuler la d\u00e9cision du tribunal.<\/p>\n\n\n\n<p>Le fait que le NPCSC d\u00e9tienne le pouvoir final d\u2019interpr\u00e9ter la Loi fondamentale r\u00e9duit toutes les garanties constitutionnelles de la Loi fondamentale de Hong Kong \u00ab&#160;\u00e0 de simples promesses dont la r\u00e9alisation est \u00e0 la merci du Parti communiste chinois&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-74133' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2020\/05\/30\/la-nouvelle-loi-de-securite-nationale-de-pekin-et-lavenir-de-hong-kong\/#easy-footnote-bottom-3-74133' title='&lt;a href=&quot;http:\/\/researchblog.law.hku.hk\/2016\/11\/cora-chan-on-legal-limits-of-beijings.html&quot;&gt;The Legal Limits on Beijing&amp;rsquo;s Powers to Interpret Hong Kong&amp;rsquo;s Basic Law,&lt;\/a&gt; HKU Legal Scholarship Blog, 3 novembre 2016'><sup>3<\/sup><\/a><\/span><\/span>&#160;\u00bb. En d\u2019autres termes, Hong Kong n\u2019a jamais vraiment eu de v\u00e9ritable \u00c9tat de droit constitutionnel et son ordre juridique m\u00eame a toujours \u00e9t\u00e9 subordonn\u00e9 aux caprices politiques de P\u00e9kin.<\/p>\n\n\n\n<p>Donc, en substance, les lois pourraient \u00eatre contest\u00e9es. Mais le NPCSC serait en mesure d\u2019annuler toute d\u00e9cision de justice d\u00e9favorable en \u00e9mettant sa propre interpr\u00e9tation finale en vertu de l\u2019article 158, ce qu\u2019il fera presque certainement puisque c\u2019est le m\u00eame organe qui \u00e9crira et promulguera la loi.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">De quoi d\u2019autre devons-nous nous pr\u00e9occuper&#160;?<\/h4>\n\n\n\n<p>Selon un projet de r\u00e9solution du NPCSC sur la nouvelle loi de s\u00e9curit\u00e9 nationale, le gouvernement de Hong Kong sera charg\u00e9 de \u00ab&#160;mettre en place une organisation et un m\u00e9canisme op\u00e9rationnel pour prot\u00e9ger la s\u00e9curit\u00e9 nationale&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-74133' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2020\/05\/30\/la-nouvelle-loi-de-securite-nationale-de-pekin-et-lavenir-de-hong-kong\/#easy-footnote-bottom-4-74133' title='&lt;a href=&quot;https:\/\/www.scmp.com\/news\/hong-kong\/politics\/article\/3085617\/two-sessions-2020-national-security-law-hong-kong-will&quot;&gt;Two Sessions 2020&amp;#160;: new law will \u2018prevent, frustrate and punish\u2019 acts in Hong Kong that threaten national security, top official says, &lt;\/a&gt;South China Morning Post, 22 mai 2020'><sup>4<\/sup><\/a><\/span><\/span>. Mais si le gouvernement de Hong Kong venait \u00e0 \u00e9chouer, le gouvernement central chinois pourra \u00e9galement, en fonction des besoins, cr\u00e9er son propre office de la s\u00e9curit\u00e9 nationale qui op\u00e9rera \u00e0 Hong Kong afin de faire appliquer ces lois&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-74133' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2020\/05\/30\/la-nouvelle-loi-de-securite-nationale-de-pekin-et-lavenir-de-hong-kong\/#easy-footnote-bottom-5-74133' title='&lt;a href=&quot;https:\/\/news.rthk.hk\/rthk\/en\/component\/k2\/1527697-20200522.htm&quot;&gt;&amp;lsquo;Allowing mainland agents a complete disruption&amp;rsquo;, &lt;\/a&gt;RT HK, 22 mai 2020'><sup>5<\/sup><\/a><\/span><\/span>. Cela signifierait que les agences chinoises charg\u00e9es de l\u2019application des lois et de la s\u00e9curit\u00e9 pourraient intervenir directement dans la cit\u00e9.<\/p>\n\n\n\n<p>Les d\u00e9tails de cet arrangement n\u2019ont pas encore \u00e9t\u00e9 d\u00e9voil\u00e9s, mais cette initiative s\u2019inscrit dans le cadre de l\u2019audace croissante de P\u00e9kin qui contourne totalement les institutions de Hong Kong pour exercer un contr\u00f4le plus direct.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Qu\u2019est-ce que cela signifie pour l\u2019avenir de Hong Kong&#160;?<\/h4>\n\n\n\n<p>Avec l\u2019adoption de ces lois, tant les protestations de masse que les actions individuelles de r\u00e9sistance politique pourront avoir des cons\u00e9quences beaucoup plus lourdes. Toute activit\u00e9 politique jug\u00e9e s\u00e9ditieuse ou d\u00e9favorable au gouvernement central sera beaucoup plus risqu\u00e9e pour les militants de Hong Kong. Les Hongkongais sont d\u00e9j\u00e0 nombreux \u00e0 installer des VPN pour prot\u00e9ger leur identit\u00e9 en ligne.<\/p>\n\n\n\n<p>Mais les cons\u00e9quences vont bien au-del\u00e0 de la simple substance des lois de s\u00e9curit\u00e9 nationale. Nous ne sommes pas encore en 2003. La combinaison du pouvoir de P\u00e9kin de promulguer directement des lois pour Hong Kong et d\u2019interpr\u00e9ter ces lois aussi largement qu\u2019ils le souhaitent sonne le glas du principe \u00ab&#160;un pays, deux syst\u00e8mes&#160;\u00bb, et de tout semblant d\u2019autonomie politique et juridique dont la r\u00e9gion jouit encore.<\/p>\n\n\n\n<p>Si le projet de loi sur l\u2019extradition de l\u2019ann\u00e9e derni\u00e8re \u00e9tait un portail juridique qui avait envoy\u00e9 des individus sur le continent pour contourner l\u2019\u00c9tat de droit, l\u2019ind\u00e9pendance judiciaire et les proc\u00e9dures l\u00e9gales de Hong Kong, alors ces nouvelles lois sur la s\u00e9curit\u00e9 nationale sont un portail juridique qui envoie directement la l\u00e9gislation de P\u00e9kin \u00e0 Hong Kong par d\u00e9cret. En d\u2019autres termes, au lieu d\u2019extrader les Hongkongais vers la Chine continentale pour qu\u2019ils soient jug\u00e9s, le syst\u00e8me juridique de P\u00e9kin sera simplement amen\u00e9 \u00e0 Hong Kong.<\/p>\n\n\n\n<p>Mais si nous avons appris quelque chose de la longue histoire de construction du mouvement \u00e0 Hong Kong&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-74133' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2020\/05\/30\/la-nouvelle-loi-de-securite-nationale-de-pekin-et-lavenir-de-hong-kong\/#easy-footnote-bottom-6-74133' title='&lt;a href=&quot;https:\/\/lausan.hk\/2019\/hong-kong-political-strikes-brief-history\/&quot;&gt;Hong Kong political strikes&amp;#160;: a brief history,&lt;\/a&gt; Lausan, 3 aout 2019'><sup>6<\/sup><\/a><\/span><\/span>, c\u2019est que nous pouvons nous attendre \u00e0 ce que les Hongkongais continuent \u00e0 r\u00e9sister.<\/p>\n\n\n\n<p>Les r\u00e8gles du jeu ont chang\u00e9 et le mouvement de Hong Kong doit en faire autant. Le sort des Hongkongais \u00e9tant d\u00e9sormais plus intimement li\u00e9 \u00e0 celui des personnes marginalis\u00e9es et opprim\u00e9es en Chine continentale, les Hongkongais doivent r\u00e9aligner leurs luttes sur celles des Chinois de Chine continentale qui sont tout aussi opprim\u00e9s par l\u2019\u00c9tat chinois.<\/p>\n\n\n\n<p>Ce n\u2019est pas le moment de se tourner vers l\u2019Occident. C\u2019est le moment de la solidarit\u00e9 avec les travailleurs chinois, les militants chinois et tous ceux qui sont opprim\u00e9s en Chine.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>P\u00e9kin vient d\u2019imposer \u00e0 Hong Kong de nouvelles lois sur la s\u00e9curit\u00e9 nationale qui, selon beaucoup, signifient la fin du cadre \u00ab&#160;&#160;Un pays, deux syst\u00e8mes&#160;&#160;\u00bb de Hong Kong. D\u2019autres l\u2019ont qualifi\u00e9 de violation totale de l\u2019autonomie de la cit\u00e9 par la R\u00e9publique populaire de Chine. Cet article fait la lumi\u00e8re sur la nouvelle loi, sur certaines des nuances juridiques et sur ce qu\u2019elle signifie pour l\u2019avenir de Hong Kong.<\/p>\n","protected":false},"author":175,"featured_media":74134,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-studies.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":0,"footnotes":""},"categories":[1731],"tags":[],"staff":[2409,2408],"editorial_format":[4849],"serie":[],"audience":[],"geo":[531],"class_list":["post-74133","post","type-post","status-publish","format-standard","hentry","category-politique","staff-lausan","staff-vincent-wong","editorial_format-etudes","geo-chine"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":74134,"excerpt":"P\u00e9kin vient d\u2019imposer \u00e0 Hong Kong de nouvelles lois sur la s\u00e9curit\u00e9 nationale qui, selon beaucoup, signifient la fin du cadre \u00ab Un pays, deux syst\u00e8mes \u00bb de Hong Kong. D\u2019autres l\u2019ont qualifi\u00e9 de violation totale de l\u2019autonomie de la cit\u00e9 par la R\u00e9publique populaire de Chine. Cet article fait la lumi\u00e8re sur la nouvelle loi, sur certaines des nuances juridiques et sur ce qu\u2019elle signifie pour l\u2019avenir de Hong Kong.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La nouvelle loi de s\u00e9curit\u00e9 nationale de P\u00e9kin et l\u2019avenir de Hong Kong | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2020\/05\/30\/la-nouvelle-loi-de-securite-nationale-de-pekin-et-lavenir-de-hong-kong\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La nouvelle loi de s\u00e9curit\u00e9 nationale de P\u00e9kin et l\u2019avenir de Hong Kong | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"P\u00e9kin vient d\u2019imposer \u00e0 Hong Kong de nouvelles lois sur la s\u00e9curit\u00e9 nationale qui, selon beaucoup, signifient la fin du cadre \u00ab&#160;Un pays, deux syst\u00e8mes&#160;\u00bb de Hong Kong. D\u2019autres l\u2019ont qualifi\u00e9 de violation totale de l\u2019autonomie de la cit\u00e9 par la R\u00e9publique populaire de Chine. Cet article fait la lumi\u00e8re sur la nouvelle loi, sur certaines des nuances juridiques et sur ce qu\u2019elle signifie pour l\u2019avenir de Hong Kong.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2020\/05\/30\/la-nouvelle-loi-de-securite-nationale-de-pekin-et-lavenir-de-hong-kong\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-30T13:32:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-30T13:34:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/05\/Grafica-2020-05-30-alle-15.27.57.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1476\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Giovanni Collot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/05\/Grafica-2020-05-30-alle-15.27.57.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giovanni Collot\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2020\/05\/30\/la-nouvelle-loi-de-securite-nationale-de-pekin-et-lavenir-de-hong-kong\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2020\/05\/30\/la-nouvelle-loi-de-securite-nationale-de-pekin-et-lavenir-de-hong-kong\/\",\"name\":\"La nouvelle loi de s\u00e9curit\u00e9 nationale de P\u00e9kin et l\u2019avenir de Hong Kong | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2020\/05\/30\/la-nouvelle-loi-de-securite-nationale-de-pekin-et-lavenir-de-hong-kong\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2020\/05\/30\/la-nouvelle-loi-de-securite-nationale-de-pekin-et-lavenir-de-hong-kong\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/05\/Grafica-2020-05-30-alle-15.27.57.jpg\",\"datePublished\":\"2020-05-30T13:32:32+00:00\",\"dateModified\":\"2020-05-30T13:34:24+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2020\/05\/30\/la-nouvelle-loi-de-securite-nationale-de-pekin-et-lavenir-de-hong-kong\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2020\/05\/30\/la-nouvelle-loi-de-securite-nationale-de-pekin-et-lavenir-de-hong-kong\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2020\/05\/30\/la-nouvelle-loi-de-securite-nationale-de-pekin-et-lavenir-de-hong-kong\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/05\/Grafica-2020-05-30-alle-15.27.57.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/05\/Grafica-2020-05-30-alle-15.27.57.jpg\",\"width\":2560,\"height\":1476},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2020\/05\/30\/la-nouvelle-loi-de-securite-nationale-de-pekin-et-lavenir-de-hong-kong\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La nouvelle loi de s\u00e9curit\u00e9 nationale de P\u00e9kin et l\u2019avenir de Hong Kong\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef\",\"name\":\"Giovanni Collot\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g\",\"caption\":\"Giovanni Collot\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La nouvelle loi de s\u00e9curit\u00e9 nationale de P\u00e9kin et l\u2019avenir de Hong Kong | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2020\/05\/30\/la-nouvelle-loi-de-securite-nationale-de-pekin-et-lavenir-de-hong-kong\/","og_locale":"fr_FR","og_type":"article","og_title":"La nouvelle loi de s\u00e9curit\u00e9 nationale de P\u00e9kin et l\u2019avenir de Hong Kong | Le Grand Continent","og_description":"P\u00e9kin vient d\u2019imposer \u00e0 Hong Kong de nouvelles lois sur la s\u00e9curit\u00e9 nationale qui, selon beaucoup, signifient la fin du cadre \u00ab&#160;Un pays, deux syst\u00e8mes&#160;\u00bb de Hong Kong. D\u2019autres l\u2019ont qualifi\u00e9 de violation totale de l\u2019autonomie de la cit\u00e9 par la R\u00e9publique populaire de Chine. Cet article fait la lumi\u00e8re sur la nouvelle loi, sur certaines des nuances juridiques et sur ce qu\u2019elle signifie pour l\u2019avenir de Hong Kong.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2020\/05\/30\/la-nouvelle-loi-de-securite-nationale-de-pekin-et-lavenir-de-hong-kong\/","og_site_name":"Le Grand Continent","article_published_time":"2020-05-30T13:32:32+00:00","article_modified_time":"2020-05-30T13:34:24+00:00","og_image":[{"width":2560,"height":1476,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/05\/Grafica-2020-05-30-alle-15.27.57.jpg","type":"image\/jpeg"}],"author":"Giovanni Collot","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/05\/Grafica-2020-05-30-alle-15.27.57.jpg","twitter_misc":{"\u00c9crit par":"Giovanni Collot","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2020\/05\/30\/la-nouvelle-loi-de-securite-nationale-de-pekin-et-lavenir-de-hong-kong\/","url":"https:\/\/legrandcontinent.eu\/fr\/2020\/05\/30\/la-nouvelle-loi-de-securite-nationale-de-pekin-et-lavenir-de-hong-kong\/","name":"La nouvelle loi de s\u00e9curit\u00e9 nationale de P\u00e9kin et l\u2019avenir de Hong Kong | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2020\/05\/30\/la-nouvelle-loi-de-securite-nationale-de-pekin-et-lavenir-de-hong-kong\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2020\/05\/30\/la-nouvelle-loi-de-securite-nationale-de-pekin-et-lavenir-de-hong-kong\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/05\/Grafica-2020-05-30-alle-15.27.57.jpg","datePublished":"2020-05-30T13:32:32+00:00","dateModified":"2020-05-30T13:34:24+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2020\/05\/30\/la-nouvelle-loi-de-securite-nationale-de-pekin-et-lavenir-de-hong-kong\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2020\/05\/30\/la-nouvelle-loi-de-securite-nationale-de-pekin-et-lavenir-de-hong-kong\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2020\/05\/30\/la-nouvelle-loi-de-securite-nationale-de-pekin-et-lavenir-de-hong-kong\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/05\/Grafica-2020-05-30-alle-15.27.57.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/05\/Grafica-2020-05-30-alle-15.27.57.jpg","width":2560,"height":1476},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2020\/05\/30\/la-nouvelle-loi-de-securite-nationale-de-pekin-et-lavenir-de-hong-kong\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"La nouvelle loi de s\u00e9curit\u00e9 nationale de P\u00e9kin et l\u2019avenir de Hong Kong"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef","name":"Giovanni Collot","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g","caption":"Giovanni Collot"}}]}},"lgc_categories":[{"id":1731,"name":"Politique","slug":"politique"}],"lgc_author":{"id":2409,"name":"Lausan","slug":"lausan","description":null,"first_name":null,"last_name":null,"picture":null},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/05\/Grafica-2020-05-30-alle-15.27.57.jpg","width":2560,"height":1476,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/74133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=74133"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/74133\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/74134"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=74133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=74133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=74133"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=74133"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=74133"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=74133"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=74133"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=74133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}