{"id":7204,"date":"2017-12-20T11:00:03","date_gmt":"2017-12-20T10:00:03","guid":{"rendered":"https:\/\/legrandcontinent.eu\/?p=7204"},"modified":"2021-03-17T18:47:29","modified_gmt":"2021-03-17T17:47:29","slug":"nous-avons-rencontre-alain-lamassoure","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2017\/12\/20\/nous-avons-rencontre-alain-lamassoure\/","title":{"rendered":"Que faire de l&rsquo;Europe&#160;? Une conversation avec Alain Lamassoure"},"content":{"rendered":"\n<p class=\"has-drop-cap\"><em>Nous avons eu la chance de rencontrer Alain Lamassoure, personnalit\u00e9 incontournable du paysage politique europ\u00e9en. Membre du groupe PPE (Parti populaire europ\u00e9en) il est depuis 18 ans d\u00e9put\u00e9 au Parlement europ\u00e9en, au sein duquel il a exerc\u00e9 de hautes responsabilit\u00e9s &#8211; pr\u00e9sident de la commission des Budgets. Il est maintenant pr\u00e9sident de la commission sp\u00e9ciale TAXE sur le blanchiment d&rsquo;argent, l\u2019optimisation et l&rsquo;\u00e9vasion fiscale. Membre du mouvement Europ\u00e9en France, il revient avec nous sur sa vision du projet f\u00e9d\u00e9raliste europ\u00e9en ainsi que sur le r\u00f4le de la France dans l&rsquo;avenir de la construction europ\u00e9enne.<\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Pourquoi l\u2019id\u00e9e d\u2019\u00c9tats-Unis d\u2019Europe, longtemps un moteur de la construction europ\u00e9enne, semble-t-elle en panne&#160;?<\/h3>\n\n\n\n<p>La forme politique des \u00c9tats-Unis d\u2019Am\u00e9rique ne peut pas s\u2019appliquer \u00e0 l\u2019Europe. L\u2019id\u00e9e des \u00c9tats-Unis d\u2019Europe r\u00e9sulte d\u2019un malentendu historique et politique sur la formule \u201cUnited States of America\u201d. Elle n\u2019est pas exacte car les Etats am\u00e9ricains ne sont pas des Etats. Le Nevada, par exemple, n\u2019est pas un \u00c9tat-nation et le Texas n\u2019a \u00e9t\u00e9 ind\u00e9pendant que deux ans. Les Canadiens sont plus exacts lorsqu\u2019ils parlent de province. <\/p>\n\n\n\n<p>Ind\u00e9niablement, les \u00c9tats am\u00e9ricains ont ainsi beaucoup moins de consistance historique et d\u2019identit\u00e9 que les L\u00e4nder allemands dont beaucoup furent des royaumes comme la Saxe, la Bavi\u00e8re ou le Hanovre.<br>En retrouvant par hasard l\u2019Atlas de g\u00e9ographie politique dans lequel mon grand-p\u00e8re apprenait la g\u00e9ographie politique \u00e0 la fin du XIXe si\u00e8cle et en le comparant \u00e0 l\u2019Atlas politique de l\u2019Europe d\u2019aujourd\u2019hui, j\u2019ai constat\u00e9 qu\u2019il existe aujourd\u2019hui sur la carte politique de l\u2019Europe vingt-quatre Etats qui n\u2019existaient pas quand mon grand-p\u00e8re \u00e9tait \u00e0 l\u2019\u00e9cole primaire. Les pays baltes \u00e9videmment, mais aussi la Finlande, la Norv\u00e8ge ou l\u2019Irlande n\u2019\u00e9taient pas ind\u00e9pendantes.<br><\/p>\n\n\n\n<p>Pour moi, cela veut dire que nous avons aujourd\u2019hui deux types de nations dans l\u2019Union Europ\u00e9enne. D\u2019une part, des nations comme la n\u00f4tre, extraordinairement attach\u00e9es \u00e0 leur identit\u00e9 et \u00e0 leur souverainet\u00e9 \u2013 employons le mot m\u00eame si il ne veut plus dire grand-chose \u2013 et aux manifestations anciennes de celle-ci, leur langue, leur histoire et leur traditions. Et puis les autres, comme la Tch\u00e9quie, la Slovaquie ou la Slov\u00e9nie, qui sont d\u2019autant plus attach\u00e9s \u00e0 leur ind\u00e9pendance et \u00e0 leur identit\u00e9 qu\u2019elles sont toutes r\u00e9centes. Pour ces derniers, le f\u00e9d\u00e9ralisme n\u2019est pas tr\u00e8s s\u00e9duisant.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Donc aucun des pays membres ne souhaite les \u00c9tats-Unis d\u2019Europe&#160;?<\/h3>\n\n\n\n<p>C\u2019est exactement cela. Mais ce qui est encore plus important c\u2019est qu\u2019aucun parti politique de gouvernement europ\u00e9en n\u2019y est favorable. Sauf peut-\u00eatre les Verts, qui ne sont pas exactement un parti de gouvernement mais un parti d\u2019appoint pour des coalitions gouvernementales. Donc ce saut f\u00e9d\u00e9ral sur le mod\u00e8le am\u00e9ricain n\u2019aura pas lieu. Et nous n\u2019en avons pas besoin.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Par quelle formule remplaceriez-vous cette id\u00e9e&#160;?<\/h3>\n\n\n\n<p>Je regrette la disparition du terme de communaut\u00e9 qui refl\u00e8te cette formule politique diff\u00e9rente que nous cherchons \u00e0 inventer. J\u2019esp\u00e8re qu\u2019on y reviendra parce que le mot de communaut\u00e9 \u00e9tait un mot admirable. Du reste, c\u2019est un mot fran\u00e7ais, et m\u00eame les Britanniques ont \u00e9t\u00e9 oblig\u00e9s de prendre le m\u00eame mot \u2013 community, plut\u00f4t que commonwealth, trop connot\u00e9. Les Allemands l\u2019avaient traduit assez exactement par Gemeinschaft. Pour moi, cela traduit quelque chose de chaleureux de l\u2019id\u00e9al europ\u00e9en, comme si nous \u00e9tions une famille de peuples.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>L\u2019id\u00e9e des \u00c9tats-Unis d\u2019Europe r\u00e9sulte d\u2019un malentendu historique et politique sur la formule &lsquo;United States of America&rsquo;.<\/p><cite>Alain Lamassoure<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Quelle serait donc selon vous la bonne \u00e9chelle pour appr\u00e9hender l\u2019Europe politique&#160;?<\/h3>\n\n\n\n<p>Nous avons besoin de poursuivre ce qui a \u00e9t\u00e9 con\u00e7u dans le trait\u00e9 de Lisbonne, qui est en r\u00e9alit\u00e9 une r\u00e9\u00e9criture avec une pr\u00e9sentation diff\u00e9rente et des changements minimes du trait\u00e9 de constitution de 2005. C\u2019est-\u00e0-dire qu\u2019il nous faut r\u00e9aliser l\u2019\u00e9quivalent \u00e0 l\u2019\u00e9chelon du continent de ce qu\u2019est une communaut\u00e9 d\u2019agglom\u00e9ration au niveau local. C\u2019est une comparaison dont j\u2019ai pu v\u00e9rifier l\u2019exactitude en cr\u00e9ant, il y a une vingtaine d\u2019ann\u00e9es, la communaut\u00e9 d\u2019agglom\u00e9ration de Bayonne-Biarritz-Anglet au nord du Pays basque.<br><\/p>\n\n\n\n<p>Mais d\u2019abord, pourquoi ont-\u00e9t\u00e9 cr\u00e9\u00e9es des communaut\u00e9s d\u2019agglom\u00e9rations&#160;? Parce que les fran\u00e7ais sont tr\u00e8s attach\u00e9s \u00e0 leurs 36 000 communes. Cependant, ces communes ont \u00e9t\u00e9 d\u00e9finies en 1791 par l\u2019Assembl\u00e9e constituante en partant des paroisses de l\u2019\u00e9poque et \u00e0 un moment o\u00f9 la France avait une population de 24 millions d\u2019habitants \u00e0 80&#160;% rurale. Deux si\u00e8cles plus tard 80&#160;% des Fran\u00e7ais vivent en ville. Pour ces Fran\u00e7ais urbains, l\u2019espace de vie quotidien n\u2019est plus la commune mais l\u2019agglom\u00e9ration. Qu\u2019entend-on exactement par ce terme&#160;? Pour l\u2019INSEE, c\u2019est un ensemble de communes voisines telle que chaque matin plus de la moiti\u00e9 de la population active de chaque commune va travailler dans une autre commune de l\u2019ensemble.<br><\/p>\n\n\n\n<p>Dans la mesure o\u00f9 la vie quotidienne des gens se r\u00e9partit sur plusieurs communes, il faut red\u00e9finir le cadre et le fonctionnement des initiatives et des services publics. Par exemple, en repensant les transports pour emmener les gens au travail ou \u00e0 l\u2019\u00e9cole ou en repensant les services de collecte de d\u00e9chets \u00e0 l\u2019\u00e9chelon de l\u2019agglom\u00e9ration. Les grands am\u00e9nagement culturels et sportifs doivent \u00e9galement \u00eatre dimensionn\u00e9s selon la zone d\u2019achalandage que repr\u00e9sente la population de l\u2019agglom\u00e9ration. Le cas des infrastructures sportives est int\u00e9ressant car il montre \u00e9galement que cela ne signe pas la disparition des communes et ne les emp\u00eache pas d\u2019entretenir le stade de l\u2019\u00e9quipe de football ou de rugby historique ou les terrain de jeu locaux pour enfants.<br><\/p>\n\n\n\n<p>Pour moi, nous avons besoin du m\u00eame type d\u2019approche \u00e0 l\u2019\u00e9chelle continentale.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L\u2019\u00e9chelon national n\u2019est donc plus pertinent&#160;?<\/h3>\n\n\n\n<p>Plus compl\u00e8tement. Alors qu\u2019au XXe si\u00e8cle, un certain nombre de grands probl\u00e8mes pouvaient \u00eatre trait\u00e9s dans le cadre national, au XXIe si\u00e8cle le niveau pertinent est parfois devenu continental. Cela englobe aussi bien ce qu\u2019on appelait, au XIXe si\u00e8cle, les arts de la paix, le commerce, la recherche, les \u00e9changes universitaires, les mouvements financiers&#160;; que les arts de la guerre, la diplomatie, la s\u00e9curit\u00e9 ext\u00e9rieure, la protection des fronti\u00e8res communes. Ce qui est passionnant avec ce que nous appelons la construction europ\u00e9enne, c&rsquo;est d\u2019\u00eatre amen\u00e9s \u00e0 mettre en place une entit\u00e9 politique qui n\u2019existe pas encore. Ce processus a commenc\u00e9 il y a 70 ans avec le discours de Robert Schuman, une longue p\u00e9riode pour une vie humaine mais un soupir pour l\u2019Histoire. Pour moi, cela va durer encore 30 ans car l\u2019Union europ\u00e9enne est une cath\u00e9drale et il faudra un si\u00e8cle pour l\u2019achever.<br><\/p>\n\n\n\n<p>L\u2019\u00c9tat Nation a commenc\u00e9 \u00e0 fonctionner comme tel au XIXe si\u00e8cle, apr\u00e8s s\u2019\u00eatre invent\u00e9 pendant deux ou trois si\u00e8cles. Sous Louis XIV, la France \u00e9tait d\u00e9j\u00e0 une nation. Mais c\u2019\u00e9tait une monarchie dot\u00e9e d\u2019une administration. Ce n\u2019\u00e9tait pas un Etat, au sens o\u00f9 nous l\u2019entendons aujourd\u2019hui. Au conseil du roi, ce dernier, selon son bon plaisir, invitait le nonce apostolique, l\u2019ambassadeur d\u2019Espagne, tel ou tel favori \u2026 Le pouvoir judiciaire n\u2019avait aucune ind\u00e9pendance. C\u2019est seulement deux si\u00e8cles plus tard que les nations se sont constitu\u00e9es en \u00c9tats.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La plupart des \u00c9tats-nations sont n\u00e9s de guerres et de r\u00e9volutions. L\u2019Europe fait-elle face \u00e0 des difficult\u00e9s particuli\u00e8res pour se construire&#160;?<\/h3>\n\n\n\n<p>L\u2019Union europ\u00e9enne est n\u00e9e de l\u2019\u00e2ge d\u00e9mocratique, mais le fait que les \u00c9tats membres soient des d\u00e9mocraties complique le processus de construction. \u00c0 chaque fois que nous ajoutons un \u00e9tage \u00e0 l\u2019\u00e9difice institutionnel, il nous faut l\u2019unanimit\u00e9. Paradoxalement, pour d\u00e9finir le cap de l\u2019Union europ\u00e9enne il suffit de r\u00e9unir une majorit\u00e9, mais lorsqu\u2019il faut transformer ou ajouter un dispositif ou une structure institutionnelle, c\u2019est l\u2019unanimit\u00e9 qui pr\u00e9vaut. On pourrait m\u00eame parler de double unanimit\u00e9 puisqu\u2019entre le moment o\u00f9 une d\u00e9cision est prise et le moment o\u00f9 elle est mise en place, de l\u2019eau aura coul\u00e9 sous les ponts et un certain nombre de gouvernements et de majorit\u00e9s auront chang\u00e9, remettant tout en question. En effet, sur 27 membres, six ou sept d&rsquo;entre eux ont des \u00e9lections g\u00e9n\u00e9rales chaque ann\u00e9e.<br><\/p>\n\n\n\n<p>Cette r\u00e9alit\u00e9 des d\u00e9mocraties fait que la construction europ\u00e9enne prend du temps et comme il n\u2019y a pas de pr\u00e9c\u00e9dent historique ou d\u2019\u00e9quivalent dans le monde, nous sommes en terrain compl\u00e8tement inconnu. Cela explique nos t\u00e2tonnements et, n\u00e9cessairement, certaines de nos erreurs. Il faut cesser de penser que l\u2019invention de l\u2019Union europ\u00e9enne peut \u00eatre un processus lin\u00e9aire.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Ce qui est passionnant avec ce que nous appelons la construction europ\u00e9enne, c&rsquo;est d\u2019\u00eatre amen\u00e9s \u00e0 mettre en place une entit\u00e9 politique qui n\u2019existe pas encore.<\/p><cite>Alain Lamassoure<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">L\u2019euro est-il un exemple de cette construction t\u00e2tonnante&#160;?<\/h3>\n\n\n\n<p>Bien s\u00fbr, c\u2019est m\u00eame l\u2019exemple le plus \u00e9vident. L\u2019entr\u00e9e dans la zone euro fut la d\u00e9couverte d\u2019un continent inconnu. On disait du mod\u00e8le actuel de l\u2019euro, qui repose sur l\u2019union mon\u00e9taire de pays diff\u00e9rents aux profils \u00e9conomiques vari\u00e9s, conservant des budgets nationaux beaucoup plus importants que le petit budget commun, sans pr\u00e9voir d\u2019union sociale ou fiscale, qu\u2019il n\u2019\u00e9tait pas optimal et qu\u2019il ne pouvait pas fonctionner. Pourtant, nous d\u00e9montrons par l\u2019action concr\u00e8te que tout cela fonctionne admirablement bien. Ce n\u2019est pas optimal, bien s\u00fbr. Mais qu\u2019est-ce qui est optimal dans le monde&#160;?<br><\/p>\n\n\n\n<p>Ceci dit, Mundel a raison lorsqu\u2019il affirme que cela ne peut fonctionner qu\u2019en respectant un certain de nombre de conditions. Malheureusement, on ne cherche \u00e0 les remplir que lorsqu\u2019on est en crise. Une des caract\u00e9ristiques des d\u00e9mocraties est que des d\u00e9cisions courageuses ne sont prises que si l\u2019on ne peut absolument pas faire autrement. Dans le cas de la zone euro, nous avons d\u2019abord sous-estim\u00e9 les dangers nouveaux propres \u00e0 cette structure nouvelle et puis, quand on s\u2019est trouv\u00e9 en danger avec l\u2019affaire grecque nous avons surestim\u00e9 la gravit\u00e9 le danger en s\u2019imaginant que la faillite de l\u2019\u00c9tat grec l\u2019obligerait \u00e0 sortir de la zone, marquant la fin de la monnaie unique.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Que pensez-vous du sentiment europhobe aujourd\u2019hui&#160;?<\/h3>\n\n\n\n<p>Nous assistons aujourd\u2019hui \u00e0 une diminution de l\u2019europhobie au profit \u2013 et ce n\u2019est pas un progr\u00e8s \u2013 de la x\u00e9nophobie et de la haine de l\u2019Autre, c\u2019est \u00e0 dire en r\u00e9alit\u00e9 de nouvelles formes de racismes. C\u2019est un ph\u00e9nom\u00e8ne qui est tr\u00e8s grave mais tr\u00e8s int\u00e9ressant \u00e0 \u00e9tudier historiquement, d\u2019autant plus qu\u2019aucun de nous ne l\u2019a vu venir. Ce ph\u00e9nom\u00e8ne n\u2019est pas limit\u00e9 \u00e0 l\u2019Union europ\u00e9enne, c\u2019est vrai aussi en Norv\u00e8ge, en Suisse, et hors d\u2019Europe. L\u2019\u00e9lection de Donald Trump en a montr\u00e9 la r\u00e9surgence aux Etats-Unis. Presque toutes nos nations sont malades de cette angoisse identitaire. Le point de d\u00e9part de cette crise est que chaque pays, tout d\u2019un coup, ne sait plus o\u00f9 il habite, et a peur de voir dispara\u00eetre ses valeurs, son mode de vie, sa tradition, sa langue, sa religion, au profit de traditions, de langues, de religions ou de d\u00e9couvertes scientifiques venues de l\u2019ext\u00e9rieur.<br><\/p>\n\n\n\n<p>En France, \u00e0 part le g\u00e9ographe Christophe Guilly, dont les travaux sur les nouvelles in\u00e9galit\u00e9s sont passionnants, presque aucun de nos intellectuels n\u2019a vu monter cette crainte. Les autres r\u00e9duisent la mont\u00e9e du Front National \u00e0 l\u2019importance du ch\u00f4mage depuis les ann\u00e9es 1970. Et il est certain que c\u2019est un ph\u00e9nom\u00e8ne contributif. Il faut cependant voir qu\u2019en Autriche ou au Pays-Bas, le ch\u00f4mage est presque inexistant. La m\u00eame remarque s\u2019applique aux pays scandinaves ou \u00e0 la Suisse. L\u2019explication \u00e9conomique ne suffit donc pas \u00e0 expliquer la mont\u00e9e des tensions identitaires en Europe.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Vous avez sans doute une explication&#160;?<\/h3>\n\n\n\n<p>Je pense qu\u2019aujourd\u2019hui l\u2019Europe souffre de ne pas avoir d\u2019ennemi commun. Je ne dis pas qu\u2019il faut en inventer un, bien s\u00fbr. Mais pour moi, la solidit\u00e9 de l\u2019\u00c9tat-nation, le ciment qui a fait tenir cette structure politique, vient largement de la crainte du voisin. Plus g\u00e9n\u00e9ralement, toutes les structures politiques sont n\u00e9es de conflits ou de la crainte de ceux-ci. L\u2019Europe, au contraire, est n\u00e9e de la volont\u00e9 de non seulement faire la paix entre voisins, mais de r\u00e9ussir une v\u00e9ritable r\u00e9conciliation entre des peuples qui semblaient condamn\u00e9s \u00e0 se faire \u00e9ternellement la guerre. Aujourd\u2019hui, deux tiers des Allemands et deux tiers des Fran\u00e7ais se d\u00e9signent mutuellement lorsqu\u2019on leur pose la question&#160;: \u201cQuel est \u00e0 votre avis le peuple le plus proche du peuple fran\u00e7ais&#160;?\u201d.<br><\/p>\n\n\n\n<p>Cet exploit a permis le renforcement des liens \u00e9conomiques et culturels entre pays europ\u00e9ens et \u00e0 permis l\u2019enrichissement global du continent. Mais, il n\u2019a pas r\u00e9solu le probl\u00e8me du ciment qui fait tenir cet \u00e9difice. C\u2019est \u00e0 nous de l\u2019inventer car le but n\u2019est absolument pas d\u2019inventer un ennemi commun. M\u00eame si je remarque que dans une partie de la classe politique europ\u00e9enne la tentation est grande de le faire, que l\u2019on d\u00e9signe la Russie, l\u2019Iran, ou l\u2019Islam. Trouver cette coh\u00e9sion sans passer par la d\u00e9signation d\u2019un ennemi ext\u00e9rieur ou int\u00e9rieur, c\u2019est aussi le moyen de sortir de l\u2019angoisse identitaire.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Que dire de la politique \u00e9trang\u00e8re de l\u2019Union europ\u00e9enne&#160;?<\/h3>\n\n\n\n<p>C\u2019est pr\u00e9cis\u00e9ment l\u00e0 que nous construisons l\u2019Europe \u00e0 l\u2019envers. Normalement, la fondation d\u2019un ensemble \u00e9tatique passe par la mise en place d\u2019une arm\u00e9e, pour les p\u00e9riodes de guerres, et de structures diplomatiques, pour les p\u00e9riodes de paix. L\u2019Union europ\u00e9enne a commenc\u00e9 par l\u2019agriculture, ce qui n\u2019\u00e9tait pas facile \u00e0 r\u00e9aliser et rev\u00eatait une v\u00e9ritable importance, notamment symbolique puisque la majorit\u00e9 des soldats qui se sont entretu\u00e9s sur le sol europ\u00e9en au cours des si\u00e8cles \u00e9taient des paysans. En somme, plut\u00f4t que d\u2019envoyer les paysans guerroyer, on leur donne les moyens de produire ensemble. Mais pour unir politiquement et durablement des peuples voisins ce n\u2019est pas id\u00e9al.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Et quel est le r\u00f4le de la France aujourd\u2019hui&#160;? Est-elle encore une moyenne puissance qui profite de son assise europ\u00e9enne&#160;?<\/h3>\n\n\n\n<p>Dans le cas de la France, la politique \u00e9trang\u00e8re et le commandement des arm\u00e9es sont les activit\u00e9s qui b\u00e9n\u00e9ficient le plus \u00e0 l\u2019image du pr\u00e9sident de la r\u00e9publique fran\u00e7aise. Les coups d\u2019\u00e9clat m\u00e9diatiques comme serrer la main tr\u00e8s fort au pr\u00e9sident des \u00c9tats-Unis ou tenir la drag\u00e9e haute \u00e0 Vladimir Poutine font la une des journaux. Si le pr\u00e9sident envoie des bataillons dans les sables du Sahara, il est sur le point de remporter un nouvel Austerlitz. Il n\u2019y a qu\u2019\u00e0 voir l\u2019importance symbolique que rev\u00eatent encore les c\u00e9r\u00e9monies militaires du 14 juillet. Pour moi, ce battage n\u2019a aucun sens.<br><\/p>\n\n\n\n<p>\u00c0 la place je voudrais poser une question terrifiante. En quoi, depuis la fin de la guerre froide, le monde serait-il diff\u00e9rent si la France n\u2019avait pas exist\u00e9&#160;? Quelle crise aurait \u00e9t\u00e9 \u00e9vit\u00e9&#160;? Quelle guerre n\u2019aurait pas eu lieu ou se serait termin\u00e9e plus t\u00f4t&#160;? Seule, la diplomatie fran\u00e7aise n\u2019a plus d\u2019influence. Sauf peut-\u00eatre s\u2019il se passe quelque chose au Burkina Faso. Mais m\u00eame lorsque le Mali menace de s\u2019effondrer nous envoyons 4000 hommes pour maintenir une forme de statu-quo. Cela n\u2019a aucun impact.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Et les autres puissances europ\u00e9ennes&#160;?<\/h3>\n\n\n\n<p>L\u2019Allemagne n\u2019a m\u00eame pas de politique \u00e9trang\u00e8re, tandis que l\u2019Angleterre ne sait plus o\u00f9 se situer sur la carte du monde.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Quelle cons\u00e9quence, alors, pour l\u2019Union&#160;?<\/h3>\n\n\n\n<p>En nous r\u00e9conciliant, nous nous sommes vaccin\u00e9s contre la guerre. Contre la guerre entre Europ\u00e9ens \u00e9videmment, mais aussi contre la guerre dans le reste du monde. Toutes les op\u00e9rations auxquelles participe l\u2019arm\u00e9e fran\u00e7aise, dont je ne me moque pas tant elle est un mod\u00e8le de professionnalisme et de courage, ne sont pas des op\u00e9rations militaires mais des op\u00e9rations de gendarmerie. D\u00e8s qu\u2019il s\u2019agit de v\u00e9ritables op\u00e9ration militaires, comme bombarder Bachar El Assad, nous ne pouvons plus agir seul.<br><\/p>\n\n\n\n<p>Le retrait am\u00e9ricain nous a forc\u00e9s \u00e0 faire volte-face car sans les am\u00e9ricains, les Rafales auraient \u00e9t\u00e9 oblig\u00e9s de s\u2019approcher trop pr\u00e8s pour toucher leur cibles, prenant le risque d\u2019\u00eatre touch\u00e9s par les missiles sol-air fournis par les Syriens. Nous aurions sans doute perdu deux ou trois Rafales alors que politiquement la France n\u2019accepte d\u2019aller faire des op\u00e9rations ext\u00e9rieures qu\u2019\u00e0 la condition qu\u2019il y ait z\u00e9ro mort. \u00c0 condition, \u00e9galement, qu\u2019aucune image des morts caus\u00e9s par l\u2019arm\u00e9e fran\u00e7aise sur le terrain ne soit diffus\u00e9e. C\u2019est inou\u00ef de se dire que nous n\u2019avons jamais vu, \u00e0 la t\u00e9l\u00e9vision fran\u00e7aise, le moindre mort au Mali ou en Syrie, alors que nous avons probablement tu\u00e9 des centaines personnes, comme c\u2019\u00e9tait n\u00e9cessaire.<br><\/p>\n\n\n\n<p>Pour r\u00e9sumer, depuis la fin de la guerre froide, nous n\u2019avons voulu mener que des guerres \u201cpropres\u201d, et d\u00e8s que le conflit prenait de l\u2019ampleur, nous attendions pour nous engager de recevoir la b\u00e9n\u00e9diction et le soutien des Am\u00e9ricains. Face au chaos du Moyen-Orient et \u00e0 l\u2019aventurisme militaire russe, les Europ\u00e9ens ont longtemps v\u00e9cu dans l\u2019illusion que si la situation devenait trop explosive, les Am\u00e9ricains feraient le n\u00e9cessaire. Pourtant, \u00e0 partir de la crise libyenne, Obama nous a tr\u00e8s courtoisement fait comprendre que le soutien am\u00e9ricain n\u2019\u00e9tait pas automatique. Il a fait la m\u00eame chose en Syrie ou au Mali. Mais c\u2019\u00e9tait dit avec tant de gentillesse que les Europ\u00e9ens n&rsquo;ont pas voulu voir que le soutien am\u00e9ricain ne serait plus syst\u00e9matique. La brutalit\u00e9 de Trump a le m\u00e9rite de nous mettre face \u00e0 nos responsabilit\u00e9s et surtout, d\u2019avoir convaincu les Allemands que les Am\u00e9ricains ne s\u2019occuperaient plus de ce qu\u2019ils consid\u00e8rent comme notre backyard.<br><\/p>\n\n\n\n<p>Cette situation, in\u00e9dite depuis 1945, exige la mise en place d\u2019une v\u00e9ritable d\u00e9fense europ\u00e9enne commune. Tous les Europ\u00e9ens, m\u00eame les Allemands, en conviennent d\u00e9sormais.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Je pense qu\u2019aujourd\u2019hui l\u2019Europe souffre de ne pas avoir d\u2019ennemi commun.<\/p><cite>Alain Lamassoure<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Quels seraient les principes qui guideraient cette d\u00e9fenses commune&#160;?<\/h3>\n\n\n\n<p>C\u2019est bien ce qui m\u2019inqui\u00e8te. En mati\u00e8re de politique de d\u00e9fense, nous sommes en train de mettre la charrue avant les b\u0153ufs. Nous devrions d\u2019abord nous accorder sur les principes d\u2019une politique \u00e9trang\u00e8re commune. Les trait\u00e9s europ\u00e9ens le rendent possible en cr\u00e9ant des organes pour le mettre en \u0153uvre&#160;: le haut repr\u00e9sentant pour les relations ext\u00e9rieures, le service d\u2019action ext\u00e9rieure de l\u2019Union, l\u2019agence europ\u00e9enne de d\u00e9fense, etc.<br><\/p>\n\n\n\n<p>Malheureusement, nous avons jusqu\u2019ici \u00e9t\u00e9 victimes des egos des pr\u00e9sidents fran\u00e7ais et des premiers ministres britanniques. Nous verrons si le Brexit et l\u2019\u00e9lection du pr\u00e9sident Macron peuvent y changer quelques choses. Le probl\u00e8me fran\u00e7ais, pour l\u2019instant, \u00e0 l\u2019Elys\u00e9e comme au Quai d\u2019Orsay, c\u2019est que seule compte la France. Nous n\u2019arrivons pas s\u00e9rieusement \u00e0 formuler l\u2019id\u00e9e de diplomatie europ\u00e9enne.<br><\/p>\n\n\n\n<p>Lorsque le pr\u00e9sident de la R\u00e9publique s\u2019est rendu en Arabie Saoudite, la presse \u00e9blouie dit \u00ab&#160;C\u2019est formidable&#160;\u00bb. Pourtant, la France a une influence nulle en Arabie Saoudite tant qu\u2019elle est seule. Si par contre un fran\u00e7ais vient, fort du soutien de l\u2019Europe, les Saoudiens \u00e9couteront. C\u2019est ce qui s&rsquo;est pass\u00e9 avec la Russie en ao\u00fbt 2008 lorsque Vladimir Poutine d\u00e9cida d\u2019envahir la G\u00e9orgie. \u00c0 l\u2019\u00e9poque, le Conseil de l\u2019Union europ\u00e9enne fonctionnait encore avec la pr\u00e9sidence tournante que la France occupait \u00e0 ce moment-l\u00e0. Nicolas Sarkozy, qui fut un excellent pr\u00e9sident du Conseil europ\u00e9en, sut r\u00e9agir avec \u00e9nergie. En vingt-quatre heures, il \u00e9tait \u00e0 Moscou apr\u00e8s s\u2019\u00eatre assur\u00e9 du soutien de ses principaux partenaires. Cette initiative europ\u00e9enne permit d\u2019arr\u00eater l\u2019arm\u00e9e russe car personne n\u2019a int\u00e9r\u00eat \u00e0 avoir l\u2019Europe enti\u00e8re contre soi.<br><\/p>\n\n\n\n<p>Au contraire, d\u00e8s que nous arrivons en ordre dispers\u00e9, comme dans les conflits isra\u00e9lo-palestinien, syrien ou ukrainien, nous \u00e9chouons. C\u2019est pour cela que je pense que l\u2019un des principaux enjeux sera de d\u00e9finir les espaces dans lesquels nous devons intervenir prioritairement. Je pense que ce sont d\u2019abord les conflits qui subsistent sur notre continent&#160;: le probl\u00e8me des identit\u00e9s nationales dans l\u2019ex-Yougoslavie, la guerre en Ukraine. Puis, il faut que nous arrivions \u00e0 parler d\u2019une seule voix sur la question isra\u00e9lo-palestinienne, qui s\u2019inscrit dans le probl\u00e8me plus g\u00e9n\u00e9ral que pose l\u2019instabilit\u00e9 actuelle du Moyen-Orient. Enfin, il nous faut repenser nos relations avec le continent africain.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La France seule, selon vous, ne peut parvenir \u00e0 grand chose. Avec l\u2019\u00e9lection d\u2019Emmanuel Macron, qui a fait campagne en affichant ses convictions europ\u00e9ennes, pensez-vous que la France puisse avoir l\u2019ambition de jouer \u00e0 nouveau un r\u00f4le moteur dans la construction europ\u00e9enne&#160;?<\/h3>\n\n\n\n<p>C\u2019est un objectif l\u00e9gitime et qui, \u00e0 mon avis, r\u00e9pond \u00e0 l\u2019attente de tous nos partenaires. Nous avons travers\u00e9s une p\u00e9riode terrifiante pendant les cinq ann\u00e9es de mandat du pr\u00e9sident Hollande. La chaise de la France est rest\u00e9e vide. Et je ne suis pas suspect de propos partisans en disant cela, puisque j\u2019ai \u00e9t\u00e9 ministre des affaires europ\u00e9ennes dans un gouvernement de cohabitation avec le pr\u00e9sident Mitterrand.<br><\/p>\n\n\n\n<p>Nous avons eu des divergences tr\u00e8s fortes avec le pr\u00e9sident Mitterrand sur la guerre de Bosnie, mais sur le trait\u00e9 de Maastricht, sur l\u2019\u00e9largissement aux pays scandinaves et \u00e0 l\u2019Autriche, ou sur la mise en \u0153uvre du trait\u00e9 de Schengen, nous avons tr\u00e8s bien coop\u00e9r\u00e9. Le pr\u00e9sident Mitterrand a \u00e9t\u00e9 un tr\u00e8s grand Europ\u00e9en qui a fait son testament devant le parlement europ\u00e9en pendant la pr\u00e9sidence fran\u00e7aise par un discours absolument admirable, grandiose. \u00c0 une p\u00e9riode cruciale, il a su donner \u00e0 l\u2019Europe l\u2019\u00e9lan dont elle avait besoin avec Helmut Kohl et Jacques Delors. Jacques Chirac \u00e9tait un Europ\u00e9en plus distrait. Nicolas Sarkozy, quant \u00e0 lui, a \u00e9t\u00e9 un Europ\u00e9en in\u00e9galement convaincu mais fort dans les \u00e9preuves. Angela Merkel et Jean-Claude Trichet, puis Mario Draghi, ont vraiment surmont\u00e9 la crise dite de la zone euro. Mais il n\u2019ont pas particuli\u00e8rement fait avancer la construction europ\u00e9enne. Fran\u00e7ois Hollande n\u2019a jamais voulu jouer son r\u00f4le, notamment lors de la crise migratoire qui a failli tout emporter. Il n\u2019est m\u00eame pas venu physiquement aux deux sommets consacr\u00e9s \u00e0 ce sujet alors que l\u2019Allemagne appelait au secours. La d\u00e9cision unilat\u00e9rale d\u2019Angela Merkel d\u2019ouvrir les fronti\u00e8res \u00e0 plus d\u2019un million de r\u00e9fugi\u00e9s et de suspendre la directive de Dublin r\u00e9pondait au silence de la France et \u00e0 l\u2019impuissance des Europ\u00e9ens. Apr\u00e8s ce mandat d\u00e9cevant, l\u2019\u00e9lection d\u2019un pr\u00e9sident jeune et europ\u00e9en fut une divine surprise en Europe&#160;!<br>Mais Emmanuel Macron doit se souvenir que l\u2019Europe doit \u00eatre europ\u00e9enne, comme le disait le g\u00e9n\u00e9ral de Gaulle. Il faut que nous Fran\u00e7ais cessions d\u2019imaginer que l\u2019Europe sera une grande France. Non, c\u2019est un syst\u00e8me politique compl\u00e8tement diff\u00e9rent du syst\u00e8me fran\u00e7ais. Bien s\u00fbr, il est vrai que l\u2019architecte en chef de l\u2019Union a souvent \u00e9t\u00e9 fran\u00e7ais, d\u00e8s l\u2019\u00e9poque des p\u00e8res fondateurs que sont Jean Monnet et Robert Schuman. Pour des raisons historiques \u00e9videntes, les Allemands nous ont souvent laiss\u00e9 l\u2019initiative politique. Il faut toutefois reconna\u00eetre qu\u2019ils sont bien meilleurs que nous dans la r\u00e9alisation et dans le respect des normes que nous nous donnons. Ainsi, l\u2019Europe est bien franco-allemande.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mais vous semblez dire que la France a une responsabilit\u00e9 particuli\u00e8re&#8230;<\/h3>\n\n\n\n<p>Tout \u00e0 fait, celle d\u2019imaginer l\u2019\u00e9tape d\u2019apr\u00e8s. Et ce qui me chagrine le plus dans le d\u00e9bat sur l\u2019Europe en France est que l\u2019Union europ\u00e9enne est un enfant que la France a reni\u00e9. Depuis ma naissance, en 1944, la seule \u0153uvre collective dont le pays o\u00f9 je suis n\u00e9 puisse \u00eatre fier est le r\u00f4le moteur qu\u2019il a jou\u00e9 dans la construction europ\u00e9enne. Personne ne peut nous enlever la mani\u00e8re dont nous avons invent\u00e9 cette machine extraordinaire \u00e0 r\u00e9concilier les peuples. Donc il faut que le pr\u00e9sident de la r\u00e9publique garde en t\u00eate qu\u2019il a une responsabilit\u00e9 au nom de la France de relancer la politique europ\u00e9enne. Par exemple, les conventions pour faire le point sur l\u2019Europe qu\u2019il a \u00e9voqu\u00e9es sont une bonne id\u00e9e.<br><\/p>\n\n\n\n<p>L\u2019autre responsabilit\u00e9 fran\u00e7aise qu\u2019Emmanuel Macron doit garder \u00e0 l\u2019esprit c\u2019est que la France ne sera suivie que si elle est exemplaire. Il vaut mieux faire envie que piti\u00e9, et aujourd\u2019hui la France fait piti\u00e9. La France r\u00e9ussit \u00e0 avoir encore un \u00e9norme d\u00e9ficit commercial, qui ne cesse de s\u2019aggraver. Son taux de croissance est nettement inf\u00e9rieur \u00e0 la moyenne europ\u00e9enne. Nous sommes aussi les plus mauvais \u00e9l\u00e8ves du point de vue de la tenue des comptes publics de la zone Euro et probablement de l\u2019Union europ\u00e9enne, avec un d\u00e9ficit sup\u00e9rieur \u00e0 celui de la Gr\u00e8ce. C\u2019est un d\u00e9fi absolument redoutable parce qu\u2019il faut que la France redevienne, sinon le meilleur \u00e9l\u00e8ve, au moins un \u00e9l\u00e8ve irr\u00e9prochable. Avec une population de 67 millions d\u2019habitants, nous avons un million de fonctionnaires en plus que les Allemands qui sont 82 millions. On ne peut pourtant pas dire que l\u2019Allemagne soit plus mal administr\u00e9e que nous alors m\u00eame que c\u2019est une nation f\u00e9d\u00e9rale, avec des \u00e9chelons administratifs assez importants au niveau des r\u00e9gions que nous ne devrions m\u00eame pas avoir.<br><\/p>\n\n\n\n<p>L\u2019objectif de r\u00e9duction de 160 000 fonctionnaires sur cinq ans n\u2019est pas s\u00e9rieux au regard de ces r\u00e9alit\u00e9s. Je crains que le pr\u00e9sident et son premier ministre, dont je soutiens par ailleurs l\u2019action comme en t\u00e9moigne mon d\u00e9part des R\u00e9publicains, n\u2019aient gravement sous estim\u00e9 l\u2019ampleur des r\u00e9formes qu\u2019il faut faire en France. Les m\u00e9dias ne facilitent pas les choses lorsqu\u2019ils affirment que nous souffrons de l\u2019aust\u00e9rit\u00e9 impos\u00e9e par Bruxelles et par l\u2019Allemagne alors que la France n\u2019a jamais engag\u00e9 de politique d\u2019aust\u00e9rit\u00e9. Depuis quinze ans, nos salaires continuent d\u2019augmenter plus vite que la productivit\u00e9, et c\u2019est pour cela que nous creusons notre d\u00e9ficit ext\u00e9rieur.<br><\/p>\n\n\n\n<p>Pour revenir \u00e0 Emmanuel Macron, il est \u00e9vident que l\u2019Europe a besoin de la France et que l\u2019Europe se r\u00e9jouit qu\u2019il y ait un pr\u00e9sident fran\u00e7ais qui prenne des initiatives et qui bouscule un peu les Allemands comme le faisait gentiment Nicolas Sarkozy, et comme le faisaient \u00e0 leur mani\u00e8re Mitterrand ou Giscard. Mais ne jouons pas trop au coq de basse-cour avec nos partenaires qui n\u2019accepteront pas un leadership fran\u00e7ais, qui n\u2019ont pas accept\u00e9 un leadership allemand, surtout si la France persiste \u00e0 ne faire aucun effort pour respecter les normes qu\u2019elle a contribu\u00e9 \u00e0 instaurer.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019id\u00e9e des \u00c9tats-Unis d\u2019Europe r\u00e9sulte d\u2019un malentendu historique et politique sur la formule \u201cUnited States of America\u201d.<\/p>\n","protected":false},"author":4,"featured_media":103135,"comment_status":"closed","ping_status":"open","sticky":false,"template":"templates\/post-studies.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":19,"footnotes":""},"categories":[1734,1731],"tags":[],"staff":[1550],"editorial_format":[4849],"serie":[],"audience":[],"geo":[534],"class_list":["post-7204","post","type-post","status-publish","format-standard","hentry","category-doctrines","category-politique","staff-matheo-malik","editorial_format-etudes","geo-bulles"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":103135,"excerpt":"L\u2019id\u00e9e des \u00c9tats-Unis d\u2019Europe r\u00e9sulte d\u2019un malentendu historique et politique sur la formule \u201cUnited States of America\u201d.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Que faire de l&#039;Europe ? Une conversation avec Alain Lamassoure | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2017\/12\/20\/nous-avons-rencontre-alain-lamassoure\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Que faire de l&#039;Europe ? Une conversation avec Alain Lamassoure | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"L\u2019id\u00e9e des \u00c9tats-Unis d\u2019Europe r\u00e9sulte d\u2019un malentendu historique et politique sur la formule \u201cUnited States of America\u201d.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2017\/12\/20\/nous-avons-rencontre-alain-lamassoure\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-20T10:00:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-17T17:47:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2017\/12\/5201259789_3cf5744210_b-e1616003192350.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"990\" \/>\n\t<meta property=\"og:image:height\" content=\"665\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"gegeurope\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"gegeurope\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"19 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2017\/12\/20\/nous-avons-rencontre-alain-lamassoure\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2017\/12\/20\/nous-avons-rencontre-alain-lamassoure\/\",\"name\":\"Que faire de l'Europe ? Une conversation avec Alain Lamassoure | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2017\/12\/20\/nous-avons-rencontre-alain-lamassoure\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2017\/12\/20\/nous-avons-rencontre-alain-lamassoure\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2017\/12\/5201259789_3cf5744210_b-e1616003192350.jpg\",\"datePublished\":\"2017-12-20T10:00:03+00:00\",\"dateModified\":\"2021-03-17T17:47:29+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/25753fbf57948f81eb98a2daaf0a1f44\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2017\/12\/20\/nous-avons-rencontre-alain-lamassoure\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2017\/12\/20\/nous-avons-rencontre-alain-lamassoure\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2017\/12\/20\/nous-avons-rencontre-alain-lamassoure\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2017\/12\/5201259789_3cf5744210_b-e1616003192350.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2017\/12\/5201259789_3cf5744210_b-e1616003192350.jpg\",\"width\":990,\"height\":665},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2017\/12\/20\/nous-avons-rencontre-alain-lamassoure\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Que faire de l&rsquo;Europe&#160;? Une conversation avec Alain Lamassoure\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/25753fbf57948f81eb98a2daaf0a1f44\",\"name\":\"gegeurope\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/332bc77b348876050983d79aac818e16?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/332bc77b348876050983d79aac818e16?s=96&d=mm&r=g\",\"caption\":\"gegeurope\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Que faire de l'Europe ? Une conversation avec Alain Lamassoure | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2017\/12\/20\/nous-avons-rencontre-alain-lamassoure\/","og_locale":"fr_FR","og_type":"article","og_title":"Que faire de l'Europe ? Une conversation avec Alain Lamassoure | Le Grand Continent","og_description":"L\u2019id\u00e9e des \u00c9tats-Unis d\u2019Europe r\u00e9sulte d\u2019un malentendu historique et politique sur la formule \u201cUnited States of America\u201d.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2017\/12\/20\/nous-avons-rencontre-alain-lamassoure\/","og_site_name":"Le Grand Continent","article_published_time":"2017-12-20T10:00:03+00:00","article_modified_time":"2021-03-17T17:47:29+00:00","og_image":[{"width":990,"height":665,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2017\/12\/5201259789_3cf5744210_b-e1616003192350.jpg","type":"image\/jpeg"}],"author":"gegeurope","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"gegeurope","Dur\u00e9e de lecture estim\u00e9e":"19 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2017\/12\/20\/nous-avons-rencontre-alain-lamassoure\/","url":"https:\/\/legrandcontinent.eu\/fr\/2017\/12\/20\/nous-avons-rencontre-alain-lamassoure\/","name":"Que faire de l'Europe ? Une conversation avec Alain Lamassoure | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2017\/12\/20\/nous-avons-rencontre-alain-lamassoure\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2017\/12\/20\/nous-avons-rencontre-alain-lamassoure\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2017\/12\/5201259789_3cf5744210_b-e1616003192350.jpg","datePublished":"2017-12-20T10:00:03+00:00","dateModified":"2021-03-17T17:47:29+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/25753fbf57948f81eb98a2daaf0a1f44"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2017\/12\/20\/nous-avons-rencontre-alain-lamassoure\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2017\/12\/20\/nous-avons-rencontre-alain-lamassoure\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2017\/12\/20\/nous-avons-rencontre-alain-lamassoure\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2017\/12\/5201259789_3cf5744210_b-e1616003192350.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2017\/12\/5201259789_3cf5744210_b-e1616003192350.jpg","width":990,"height":665},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2017\/12\/20\/nous-avons-rencontre-alain-lamassoure\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Que faire de l&rsquo;Europe&#160;? Une conversation avec Alain Lamassoure"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/25753fbf57948f81eb98a2daaf0a1f44","name":"gegeurope","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/332bc77b348876050983d79aac818e16?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/332bc77b348876050983d79aac818e16?s=96&d=mm&r=g","caption":"gegeurope"}}]}},"lgc_categories":[{"id":1734,"name":"Livres","slug":"doctrines"},{"id":1731,"name":"Politique","slug":"politique"}],"lgc_author":{"id":1550,"name":"Math\u00e9o Malik","slug":"matheo-malik","description":"<span style=\"font-weight: 400\">Math\u00e9o Malik, r\u00e9dacteur en chef du Grand Continent, est secr\u00e9taire g\u00e9n\u00e9ral du Groupe d\u2019\u00e9tudes g\u00e9opolitiques.<\/span>","first_name":"Math\u00e9o","last_name":"Malik","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/08\/malik.png","width":521,"height":521,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2017\/12\/5201259789_3cf5744210_b-e1616003192350.jpg","width":990,"height":665,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/7204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=7204"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/7204\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/103135"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=7204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=7204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=7204"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=7204"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=7204"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=7204"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=7204"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=7204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}