{"id":65444,"date":"2020-03-27T18:24:53","date_gmt":"2020-03-27T17:24:53","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=65444"},"modified":"2020-03-27T19:41:33","modified_gmt":"2020-03-27T18:41:33","slug":"hier-il-y-avait-bien-plus-grave-pour-leurope-que-le-conseil-europeen","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/27\/hier-il-y-avait-bien-plus-grave-pour-leurope-que-le-conseil-europeen\/","title":{"rendered":"Hier, il y avait bien plus grave pour l\u2019Europe que le Conseil europ\u00e9en"},"content":{"rendered":"\n<p><em>Washington. <\/em>Deux choses tr\u00e8s importantes se sont produites hier, et aucune n&rsquo;a eu lieu au Conseil europ\u00e9en. Tout d&rsquo;abord, le nombre de demandes d&rsquo;allocations ch\u00f4mage aux \u00c9tats-Unis, alors que le ch\u00f4mage atteint 3 millions de nouvelles personnes, a \u00e9t\u00e9 un v\u00e9ritable choc pour l&rsquo;Am\u00e9rique. Ensuite, le pr\u00e9sident am\u00e9ricain a chang\u00e9 de ton et pr\u00e9conise d\u00e9sormais une strat\u00e9gie de confinement tr\u00e8s courte avec l&rsquo;objectif explicite d&rsquo;\u00eatre \u00ab&#160;ouvert aux affaires&#160;\u00bb et d&rsquo;avoir \u00ab&#160;une foule \u00e9norme dans les \u00e9glises pour P\u00e2ques&#160;\u00bb (dimanche 12 avril).<\/p>\n\n\n\n<p>\u00ab&#160;Ce n&rsquo;est pas un pays qui a \u00e9t\u00e9 construit pour cela. Il n&rsquo;a pas \u00e9t\u00e9 construit pour \u00eatre ferm\u00e9&#160;\u00bb, a d\u00e9clar\u00e9 M. Trump. \u00ab&#160;L&rsquo;Am\u00e9rique sera de nouveau, et bient\u00f4t, ouverte au commerce. Tr\u00e8s bient\u00f4t. Bien plus t\u00f4t que les trois ou quatre mois que quelqu&rsquo;un sugg\u00e9rait. Beaucoup plus t\u00f4t. Nous ne pouvons pas laisser le rem\u00e8de \u00eatre pire que le probl\u00e8me lui-m\u00eame.&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-65444' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2020\/03\/27\/hier-il-y-avait-bien-plus-grave-pour-leurope-que-le-conseil-europeen\/#easy-footnote-bottom-1-65444' title='ZURCHER Anthony, &lt;a href=&quot;https:\/\/www.bbc.com\/news\/world-us-canada-52009108&quot;&gt;Coronavirus&amp;#160;: Trump wants US open for business amid pandemic,&lt;\/a&gt; BBC, 24 mars 2020'><sup>1<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p>Ce message a \u00e9t\u00e9 r\u00e9p\u00e9t\u00e9 tout au long de la journ\u00e9e et doit donc \u00eatre pris au s\u00e9rieux. En outre, il fait \u00e9cho \u00e0 de nombreux commentaires formul\u00e9s par des chefs d&rsquo;entreprise, des m\u00e9decins et des \u00e9conomistes, sur le co\u00fbt \u00e9conomique inacceptable d&rsquo;une strat\u00e9gie de confinement dur et long, comme celle de Paul Romer&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-65444' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2020\/03\/27\/hier-il-y-avait-bien-plus-grave-pour-leurope-que-le-conseil-europeen\/#easy-footnote-bottom-2-65444' title='ROMER Paul, GARBER Alan M., &lt;a href=&quot;https:\/\/www.nytimes.com\/2020\/03\/23\/opinion\/coronavirus-depression.html&quot;&gt;Will Our Economy Die From Coronavirus&amp;#160;?,&lt;\/a&gt; The New York Times, 23 mars 2020'><sup>2<\/sup><\/a><\/span><\/span> par exemple ou celle de Tom Freidman&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-65444' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2020\/03\/27\/hier-il-y-avait-bien-plus-grave-pour-leurope-que-le-conseil-europeen\/#easy-footnote-bottom-3-65444' title='FRIEDMAN Thomas L., &lt;a href=&quot;https:\/\/www.nytimes.com\/2020\/03\/22\/opinion\/coronavirus-economy.html&quot;&gt;A Plan to Get America Back to Work,&lt;\/a&gt; The New York Times, 22 mars 2020'><sup>3<\/sup><\/a><\/span><\/span>, qui faisait \u00e9cho au professeur Katz&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-65444' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2020\/03\/27\/hier-il-y-avait-bien-plus-grave-pour-leurope-que-le-conseil-europeen\/#easy-footnote-bottom-4-65444' title='KATZ David L., &lt;a href=&quot;https:\/\/www.nytimes.com\/2020\/03\/20\/opinion\/coronavirus-pandemic-social-distancing.html&quot;&gt;Is Our Fight Against Coronavirus Worse Than the Disease&amp;#160;?&lt;\/a&gt;, The New York Times, 20 mars 2020'><sup>4<\/sup><\/a><\/span><\/span> qui sugg\u00e8re de passer d&rsquo;une strat\u00e9gie d&rsquo;interdiction horizontale \u00e0 une interdiction plus verticale\/chirurgicale, limit\u00e9e aux populations les plus \u00e0 risque ou non test\u00e9es.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-65444' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2020\/03\/27\/hier-il-y-avait-bien-plus-grave-pour-leurope-que-le-conseil-europeen\/#easy-footnote-bottom-5-65444' title='KLEIN Ezra, &lt;a href=&quot;https:\/\/www.vox.com\/2020\/3\/23\/21188900\/coronavirus-stock-market-recession-depression-trump-jobs-unemployment&quot;&gt;How the Covid-19 recession could become a depression&lt;\/a&gt;, Vox, 23 mars 2020'><sup>5<\/sup><\/a><\/span><\/span> Ce changement et la limitation de la p\u00e9riode de confinement et de sa port\u00e9e signifieraient probablement l&rsquo;acceptation de 120 millions d&rsquo;infections aux \u00c9tats-Unis, 35 millions au plus fort du 7 juin et environ 1,2 million de d\u00e9c\u00e8s au total.<\/p>\n\n\n\n<p>Ne f\u00fbt-ce que pour \u00eatre envisag\u00e9e, cette strat\u00e9gie repose sur la disponibilit\u00e9 des kits de d\u00e9pistage et la capacit\u00e9 \u00e0 les d\u00e9ployer \u00e0 grande \u00e9chelle. Et ce alors m\u00eame que l&rsquo;administration am\u00e9ricaine a refus\u00e9 d&rsquo;invoquer le <em>Defense Production Act<\/em> pour contraindre les fabricants am\u00e9ricains \u00e0 produire des \u00e9quipements m\u00e9dicaux et \u00e0 les tester (en raison, semble-t-il, du <em>lobbying<\/em> de la Chambre de commerce am\u00e9ricaine et des dirigeants de grandes entreprises&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-65444' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2020\/03\/27\/hier-il-y-avait-bien-plus-grave-pour-leurope-que-le-conseil-europeen\/#easy-footnote-bottom-6-65444' title='SANGER David E., SWANSON Ana, HABERMAN Maggie, &lt;a href=&quot;https:\/\/www.nytimes.com\/2020\/03\/22\/us\/politics\/coronavirus-trump-defense-production-act.html&quot;&gt;Trump Bets Business Will Answer Call to Fight Virus, but Strategy Bewilders Firms&lt;\/a&gt;, The New York Times, 22 mars 2020'><sup>6<\/sup><\/a><\/span><\/span>). L\u2019administration semble parier sur l&rsquo;espoir de voir des kits de tests rapides et largement disponibles produits en masse par Cepheid, une soci\u00e9t\u00e9 pharmaceutique am\u00e9ricaine.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-7-65444' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2020\/03\/27\/hier-il-y-avait-bien-plus-grave-pour-leurope-que-le-conseil-europeen\/#easy-footnote-bottom-7-65444' title='SINGH Kanishka, &lt;a href=&quot;https:\/\/www.reuters.com\/article\/us-health-coronavirus-usa-fda\/fda-approves-first-rapid-coronavirus-test-with-45-minutes-detection-time-idUSKBN218105&quot;&gt;U.S. FDA approves first rapid coronavirus test with 45 minutes detection time,&lt;\/a&gt; Reuters, 21 mars 2020'><sup>7<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/myfil\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Si cette strat\u00e9gie de tests \u00e0 grande \u00e9chelle, d&rsquo;interdiction verticale et de r\u00e9ouverture rapide de l&rsquo;\u00e9conomie est poursuivie aux \u00c9tats-Unis, elle fera des ravages en Europe. En effet, ce qui est le plus frappant dans les conclusions du Conseil europ\u00e9en jusqu&rsquo;\u00e0 pr\u00e9sent n&rsquo;est pas l&rsquo;absence d&rsquo;accord sur les <em>coronabonds<\/em>, mais l&rsquo;absence d&rsquo;accord sur une r\u00e9ponse commune en mati\u00e8re de sant\u00e9, de confinement, de quarantaine et de tests, qui reste enti\u00e8rement dirig\u00e9e par les gouvernements nationaux et leurs conseils scientifiques nationaux respectifs. Si les \u00c9tats-Unis s&rsquo;\u00e9cartent du consensus international actuel sur le confinement, ils d\u00e9chireront l&rsquo;Europe.<\/p>\n\n\n\n<p>En particulier, les pays ayant des capacit\u00e9s de d\u00e9pistage et des syst\u00e8mes de sant\u00e9 diff\u00e9rents voudront adopter des strat\u00e9gies diff\u00e9rentes. L&rsquo;Allemagne, par exemple, a la capacit\u00e9 de r\u00e9aliser 500 000 tests par semaine et a jusqu&rsquo;\u00e0 pr\u00e9sent le taux de mortalit\u00e9 le plus bas (la France affirme qu&rsquo;elle peut atteindre 25 000 tests par jour en quelques semaines, mais ne l&rsquo;a toujours pas fait). La volont\u00e9 et la capacit\u00e9 de l&rsquo;Allemagne \u00e0 relancer l&rsquo;\u00e9conomie contrasteront fortement avec celles du reste de l&rsquo;Europe, ce qui risque de cr\u00e9er des tensions tr\u00e8s vives.<\/p>\n\n\n\n<p>C&rsquo;est probablement le plus grand risque pour l&rsquo;unit\u00e9 europ\u00e9enne dans les semaines \u00e0 venir&#160;: non pas l&rsquo;accord sur une r\u00e9ponse \u00e9conomique commune, non pas un accord sur la mutualisation de la dette, mais simplement la poursuite d&rsquo;une r\u00e9ponse sanitaire qui ne privil\u00e9gie pas ind\u00fbment la reprise de l&rsquo;activit\u00e9 \u00e9conomique au d\u00e9triment du sauvetage de vies europ\u00e9ennes. Les d\u00e9saccords au sein du Conseil europ\u00e9en ne feront que s&rsquo;accro\u00eetre dans les semaines \u00e0 venir, de sorte que la fen\u00eatre d&rsquo;opportunit\u00e9 pour une \u00e9mission commune de dette est probablement d\u00e9j\u00e0 derri\u00e8re nous. La conclusion simple \u00e0 en tirer est que la Banque centrale europ\u00e9enne sera \u00e0 nouveau seule \u00e0 r\u00e9agir sur le plan \u00e9conomique. Cette situation est tr\u00e8s sous-optimale mais difficilement \u00e9vitable \u00e0 ce stade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deux choses tr\u00e8s importantes se sont produites hier, et aucune n&rsquo;a eu lieu au Conseil europ\u00e9en. Tout d&rsquo;abord, le nombre de demandes d&rsquo;allocations ch\u00f4mage aux \u00c9tats-Unis a \u00e9t\u00e9 un v\u00e9ritable choc pour l&rsquo;Am\u00e9rique. Ensuite, le pr\u00e9sident am\u00e9ricain a chang\u00e9 de ton et pr\u00e9conise d\u00e9sormais une strat\u00e9gie de confinement tr\u00e8s courte avec l&rsquo;objectif explicite d&rsquo;\u00eatre \u00ab&#160;ouvert aux affaires&#160;\u00bb. Si les \u00c9tats-Unis s&rsquo;\u00e9cartent du consensus international actuel sur le confinement, ils pourraient d\u00e9chirer l&rsquo;Europe.<\/p>\n","protected":false},"author":175,"featured_media":65445,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":0,"footnotes":""},"categories":[1727,2210],"tags":[2281],"staff":[1970],"editorial_format":[4942],"serie":[],"audience":[],"geo":[525,534],"class_list":["post-65444","post","type-post","status-publish","format-standard","hentry","category-economie","category-sante-publique","tag-coronavirus","staff-shahin-vallee","editorial_format-actu-breves","geo-ameriques","geo-bulles"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":65445,"excerpt":"Deux choses tr\u00e8s importantes se sont produites hier, et aucune n'a eu lieu au Conseil europ\u00e9en. Tout d'abord, le nombre de demandes d'allocations ch\u00f4mage aux \u00c9tats-Unis a \u00e9t\u00e9 un v\u00e9ritable choc pour l'Am\u00e9rique. Ensuite, le pr\u00e9sident am\u00e9ricain a chang\u00e9 de ton et pr\u00e9conise d\u00e9sormais une strat\u00e9gie de confinement tr\u00e8s courte avec l'objectif explicite d'\u00eatre \"ouvert aux affaires\". Si les \u00c9tats-Unis s'\u00e9cartent du consensus international actuel sur le confinement, ils pourraient d\u00e9chirer l'Europe.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hier, il y avait bien plus grave pour l\u2019Europe que le Conseil europ\u00e9en | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/27\/hier-il-y-avait-bien-plus-grave-pour-leurope-que-le-conseil-europeen\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hier, il y avait bien plus grave pour l\u2019Europe que le Conseil europ\u00e9en | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Deux choses tr\u00e8s importantes se sont produites hier, et aucune n&#039;a eu lieu au Conseil europ\u00e9en. Tout d&#039;abord, le nombre de demandes d&#039;allocations ch\u00f4mage aux \u00c9tats-Unis a \u00e9t\u00e9 un v\u00e9ritable choc pour l&#039;Am\u00e9rique. Ensuite, le pr\u00e9sident am\u00e9ricain a chang\u00e9 de ton et pr\u00e9conise d\u00e9sormais une strat\u00e9gie de confinement tr\u00e8s courte avec l&#039;objectif explicite d&#039;\u00eatre &quot;ouvert aux affaires&quot;. Si les \u00c9tats-Unis s&#039;\u00e9cartent du consensus international actuel sur le confinement, ils pourraient d\u00e9chirer l&#039;Europe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/27\/hier-il-y-avait-bien-plus-grave-pour-leurope-que-le-conseil-europeen\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-27T17:24:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-27T18:41:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/03\/Capture-d\u2019e\u0301cran-2020-03-27-a\u0300-19.43.22.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2870\" \/>\n\t<meta property=\"og:image:height\" content=\"1650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Giovanni Collot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/03\/Capture-d\u2019e\u0301cran-2020-03-27-a\u0300-19.43.22.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giovanni Collot\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/27\/hier-il-y-avait-bien-plus-grave-pour-leurope-que-le-conseil-europeen\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/27\/hier-il-y-avait-bien-plus-grave-pour-leurope-que-le-conseil-europeen\/\",\"name\":\"Hier, il y avait bien plus grave pour l\u2019Europe que le Conseil europ\u00e9en | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/27\/hier-il-y-avait-bien-plus-grave-pour-leurope-que-le-conseil-europeen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/27\/hier-il-y-avait-bien-plus-grave-pour-leurope-que-le-conseil-europeen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/03\/Capture-d\u2019e\u0301cran-2020-03-27-a\u0300-20.43.19.png\",\"datePublished\":\"2020-03-27T17:24:53+00:00\",\"dateModified\":\"2020-03-27T18:41:33+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/27\/hier-il-y-avait-bien-plus-grave-pour-leurope-que-le-conseil-europeen\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/27\/hier-il-y-avait-bien-plus-grave-pour-leurope-que-le-conseil-europeen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/27\/hier-il-y-avait-bien-plus-grave-pour-leurope-que-le-conseil-europeen\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/03\/Capture-d\u2019e\u0301cran-2020-03-27-a\u0300-20.43.19.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/03\/Capture-d\u2019e\u0301cran-2020-03-27-a\u0300-20.43.19.png\",\"width\":1466,\"height\":1108,\"caption\":\"nombre de tests et letalit\u00e9 pour coronavirus Europe \u00c9tats-Unis pand\u00e9mie politique sant\u00e9\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/27\/hier-il-y-avait-bien-plus-grave-pour-leurope-que-le-conseil-europeen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hier, il y avait bien plus grave pour l\u2019Europe que le Conseil europ\u00e9en\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef\",\"name\":\"Giovanni Collot\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g\",\"caption\":\"Giovanni Collot\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hier, il y avait bien plus grave pour l\u2019Europe que le Conseil europ\u00e9en | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/27\/hier-il-y-avait-bien-plus-grave-pour-leurope-que-le-conseil-europeen\/","og_locale":"fr_FR","og_type":"article","og_title":"Hier, il y avait bien plus grave pour l\u2019Europe que le Conseil europ\u00e9en | Le Grand Continent","og_description":"Deux choses tr\u00e8s importantes se sont produites hier, et aucune n'a eu lieu au Conseil europ\u00e9en. Tout d'abord, le nombre de demandes d'allocations ch\u00f4mage aux \u00c9tats-Unis a \u00e9t\u00e9 un v\u00e9ritable choc pour l'Am\u00e9rique. Ensuite, le pr\u00e9sident am\u00e9ricain a chang\u00e9 de ton et pr\u00e9conise d\u00e9sormais une strat\u00e9gie de confinement tr\u00e8s courte avec l'objectif explicite d'\u00eatre \"ouvert aux affaires\". Si les \u00c9tats-Unis s'\u00e9cartent du consensus international actuel sur le confinement, ils pourraient d\u00e9chirer l'Europe.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/27\/hier-il-y-avait-bien-plus-grave-pour-leurope-que-le-conseil-europeen\/","og_site_name":"Le Grand Continent","article_published_time":"2020-03-27T17:24:53+00:00","article_modified_time":"2020-03-27T18:41:33+00:00","og_image":[{"width":2870,"height":1650,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/03\/Capture-d\u2019e\u0301cran-2020-03-27-a\u0300-19.43.22.png","type":"image\/png"}],"author":"Giovanni Collot","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/03\/Capture-d\u2019e\u0301cran-2020-03-27-a\u0300-19.43.22.png","twitter_misc":{"\u00c9crit par":"Giovanni Collot","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/27\/hier-il-y-avait-bien-plus-grave-pour-leurope-que-le-conseil-europeen\/","url":"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/27\/hier-il-y-avait-bien-plus-grave-pour-leurope-que-le-conseil-europeen\/","name":"Hier, il y avait bien plus grave pour l\u2019Europe que le Conseil europ\u00e9en | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/27\/hier-il-y-avait-bien-plus-grave-pour-leurope-que-le-conseil-europeen\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/27\/hier-il-y-avait-bien-plus-grave-pour-leurope-que-le-conseil-europeen\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/03\/Capture-d\u2019e\u0301cran-2020-03-27-a\u0300-20.43.19.png","datePublished":"2020-03-27T17:24:53+00:00","dateModified":"2020-03-27T18:41:33+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/27\/hier-il-y-avait-bien-plus-grave-pour-leurope-que-le-conseil-europeen\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2020\/03\/27\/hier-il-y-avait-bien-plus-grave-pour-leurope-que-le-conseil-europeen\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/27\/hier-il-y-avait-bien-plus-grave-pour-leurope-que-le-conseil-europeen\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/03\/Capture-d\u2019e\u0301cran-2020-03-27-a\u0300-20.43.19.png","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/03\/Capture-d\u2019e\u0301cran-2020-03-27-a\u0300-20.43.19.png","width":1466,"height":1108,"caption":"nombre de tests et letalit\u00e9 pour coronavirus Europe \u00c9tats-Unis pand\u00e9mie politique sant\u00e9"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/27\/hier-il-y-avait-bien-plus-grave-pour-leurope-que-le-conseil-europeen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Hier, il y avait bien plus grave pour l\u2019Europe que le Conseil europ\u00e9en"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef","name":"Giovanni Collot","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g","caption":"Giovanni Collot"}}]}},"lgc_categories":[{"id":1727,"name":"\u00c9conomie","slug":"economie"},{"id":2210,"name":"Sant\u00e9 publique","slug":"sante-publique"}],"lgc_author":{"id":1970,"name":"Shahin Vall\u00e9e","slug":"shahin-vallee","description":"Ancien conseiller du Pr\u00e9sident du Conseil europ\u00e9en (Herman Von Rompuy) et ancien conseiller du Ministre de l'\u00c9conomie (Emmanuel Macron), Shahin Vall\u00e9e est chercheur en \u00e9conomie politique au Deutsche Gesellschaft f\u00fcr Ausw\u00e4rtige Politik (DGAP)","first_name":"Shahin ","last_name":"Vall\u00e9e","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/SUMMIT_GRAND_CONTINENT_1173_Shahin-Vallee_umbertocostamagna\u00a92023.png","width":1307,"height":1340,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/03\/Capture-d\u2019e\u0301cran-2020-03-27-a\u0300-20.43.19.png","width":1466,"height":1108,"alt":"nombre de tests et letalit\u00e9 pour coronavirus Europe \u00c9tats-Unis pand\u00e9mie politique sant\u00e9"},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/65444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=65444"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/65444\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/65445"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=65444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=65444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=65444"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=65444"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=65444"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=65444"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=65444"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=65444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}