{"id":62888,"date":"2020-03-11T19:57:52","date_gmt":"2020-03-11T18:57:52","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=62888"},"modified":"2020-03-19T10:48:58","modified_gmt":"2020-03-19T09:48:58","slug":"la-teleconference-du-conseil-europeen-sur-les-coronavirus-un-exercice-de-coordination-decevant","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/11\/la-teleconference-du-conseil-europeen-sur-les-coronavirus-un-exercice-de-coordination-decevant\/","title":{"rendered":"T\u00e9l\u00e9conf\u00e9rence du Conseil europ\u00e9en sur le coronavirus&#160;: un exercice de coordination d\u00e9cevant"},"content":{"rendered":"\n<p><em>Bruxelles. <\/em>Le Conseil europ\u00e9en a tenu mardi 10 mars une t\u00e9l\u00e9conf\u00e9rence sur le coronavirus. Celle-ci a \u00e9t\u00e9 salu\u00e9e comme un exercice de coordination europ\u00e9enne mais s\u2019est en r\u00e9alit\u00e9 av\u00e9r\u00e9e totalement d\u00e9cevante.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-62888' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2020\/03\/11\/la-teleconference-du-conseil-europeen-sur-les-coronavirus-un-exercice-de-coordination-decevant\/#easy-footnote-bottom-1-62888' title='ZALAN Eszter, &lt;a href=&quot;https:\/\/euobserver.com\/economic\/147690&quot;&gt;EU steps up coronavirus fight in first online summit,&lt;\/a&gt; &lt;em&gt;Le Grand Continent&lt;\/em&gt;, 11 mars 2020.'><sup>1<\/sup><\/a><\/span><\/span> La contagion financi\u00e8re et la contagion virale ont beaucoup en commun. Si elles ne sont pas combattues par une action coordonn\u00e9e et radicale, elles ont tendance \u00e0 se propager.<\/p>\n\n\n\n<p>Le Conseil europ\u00e9en n&rsquo;a pas reconnu l&rsquo;ampleur de la crise sanitaire et n&rsquo;a pas propos\u00e9 de strat\u00e9gie commune en mati\u00e8re de d\u00e9pistage, de quarantaine, de confinement et de distanciation sociale. Ces mesures devraient \u00eatre prises imm\u00e9diatement dans toute l&rsquo;Union europ\u00e9enne et \u00eatre adapt\u00e9es pour prot\u00e9ger les syst\u00e8mes de sant\u00e9 les plus faibles. L&rsquo;Union doit comprendre qu&rsquo;elle est collectivement aussi faible que le maillon le plus faible, au plus faible syst\u00e8me de sant\u00e9.<\/p>\n\n\n\n<p>Le Conseil europ\u00e9en n&rsquo;a pas fait mieux que la r\u00e9union des ministres de la Sant\u00e9 du 6 mars, qui n&rsquo;a pas r\u00e9ussi \u00e0 parvenir \u00e0 une entente sur la lev\u00e9e de l&rsquo;interdiction des exportations de fournitures m\u00e9dicales (masques, kits d&rsquo;aide respiratoire). Cela renvoie une terrible image, attestant d\u2019un manque de solidarit\u00e9 \u00e0 un moment o\u00f9 la mise en commun des ressources devrait \u00eatre centrale. Le Conseil semble \u00e9galement ignorer que l&rsquo;\u00e9pid\u00e9mie pourrait se d\u00e9clarer en plusieurs vagues si tous les \u00c9tats membres ne prennent pas les mesures ad\u00e9quates.<\/p>\n\n\n\n<p>La r\u00e9ponse \u00e9conomique est tout \u00e0 fait insuffisante et si Madame Lagarde a tent\u00e9 de lancer un appel audacieux en faveur d&rsquo;une r\u00e9ponse budg\u00e9taire europ\u00e9enne coordonn\u00e9e, il est en revanche rest\u00e9 sans r\u00e9ponse. En effet, rien dans les conclusions du Conseil europ\u00e9en ne laisse penser qu&rsquo;une telle r\u00e9ponse soit proche. Il n&rsquo;y a en fait pas m\u00eame de mandat ni d&rsquo;orientation pour l&rsquo;Eurogroupe de la semaine prochaine afin de concevoir une r\u00e9ponse appropri\u00e9e en mati\u00e8re de politique \u00e9conomique.<\/p>\n\n\n\n<p>La Commission europ\u00e9enne a par la suite annonc\u00e9 une \u00ab&#160;Initiative d&rsquo;investissement en r\u00e9ponse au coronavirus&#160;\u00bb qui atteindrait 25 milliards d&rsquo;euros de fonds europ\u00e9ens et se concentrerait sur les soins de sant\u00e9 et les PME. Le montant et le fonds ne sont qu&rsquo;un ordre de grandeur, ne serait-ce que pour importer. La r\u00e9ponse efficace viendra d&rsquo;abord des sources budg\u00e9taires nationales.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-62888' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2020\/03\/11\/la-teleconference-du-conseil-europeen-sur-les-coronavirus-un-exercice-de-coordination-decevant\/#easy-footnote-bottom-2-62888' title='VALL\u00c9E Shahin, &lt;a href=&quot;https:\/\/legrandcontinent.eu\/fr\/2020\/03\/08\/repondre-aux-chocs-economiques-du-coronavirus-une-conversation-avec-laurence-boone\/&quot;&gt;R\u00e9pondre aux chocs \u00e9conomiques du Coronavirus, une conversation avec Laurence Boone,&lt;\/a&gt; &lt;em&gt;Le Grand Continent&lt;\/em&gt;, 8 mars 2020.'><sup>2<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p>L&rsquo;Eurogroupe de la semaine prochaine sera tr\u00e8s important. La Commission europ\u00e9enne est pr\u00eate \u00e0 revoir un certain nombre d&rsquo;instruments, dont les aides d&rsquo;\u00c9tat, pour compenser les retomb\u00e9es de la crise. Mais la question centrale est de savoir si elle sera pr\u00eate \u00e0 invoquer des \u00ab&#160;circonstances exceptionnelles&#160;\u00bb, afin d&rsquo;assouplir les restrictions du Pacte [de Stabilit\u00e9 et de Croissance, NdlR] et de fournir quelques mesures politiques cl\u00e9s, qui pourraient \u00eatre prises collectivement avec la b\u00e9n\u00e9diction de l&rsquo;Eurogroupe. Il peut s&rsquo;agir de l&rsquo;obligation de payer les indemnit\u00e9s de maladie, de l&rsquo;all\u00e8gement des hypoth\u00e8ques, des cotisations de s\u00e9curit\u00e9 sociale et\u202f\/\u202fou de r\u00e9ductions d&rsquo;imp\u00f4ts.<\/p>\n\n\n\n<p>La BCE pourrait jouer un r\u00f4le important dans la mise en place de cette r\u00e9ponse fiscale commune, notamment lors de la conf\u00e9rence de presse de demain, o\u00f9 elle devra expliquer ce qu&rsquo;elle souhaite et comment ces mesures pourraient \u00eatre mises en \u0153uvre.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Perspectives&nbsp;<\/strong>&#160;:<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>Jeudi 12 mars&#160;: conf\u00e9rence de presse \u00e0 la suite de la r\u00e9union du Conseil des gouverneurs de la Banque centrale europ\u00e9enne.<\/li><li>Lundi 16 mars&#160;: prochaine rencontre de l\u2019Eurogroupe.<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>La t\u00e9l\u00e9conf\u00e9rence sur le coronavirus d&rsquo;hier, qui \u00e9tait consid\u00e9r\u00e9e comme le premier exercice de coordination entre les dirigeants europ\u00e9ens sur les \u00e9pid\u00e9mies, s\u2019est en r\u00e9alit\u00e9 av\u00e9r\u00e9e totalement d\u00e9cevante. Le Conseil n&rsquo;a pas su reconna\u00eetre l&rsquo;ampleur de la crise sanitaire et proposer une strat\u00e9gie commune, et son approche \u00e9conomique est loin d&rsquo;\u00eatre satisfaisante. L&rsquo;Eurogroupe et, plus important encore, la BCE, ont un r\u00f4le fondamental \u00e0 jouer pour y rem\u00e9dier. <\/p>\n","protected":false},"author":175,"featured_media":62864,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":0,"footnotes":""},"categories":[1727],"tags":[2281],"staff":[1970],"editorial_format":[4942],"serie":[],"audience":[],"geo":[534],"class_list":["post-62888","post","type-post","status-publish","format-standard","hentry","category-economie","tag-coronavirus","staff-shahin-vallee","editorial_format-actu-breves","geo-bulles"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":62864,"excerpt":"La t\u00e9l\u00e9conf\u00e9rence sur le coronavirus d'hier, qui \u00e9tait consid\u00e9r\u00e9e comme le premier exercice de coordination entre les dirigeants europ\u00e9ens sur les \u00e9pid\u00e9mies, s\u2019est en r\u00e9alit\u00e9 av\u00e9r\u00e9e totalement d\u00e9cevante. Le Conseil n'a pas su reconna\u00eetre l'ampleur de la crise sanitaire et proposer une strat\u00e9gie commune, et son approche \u00e9conomique est loin d'\u00eatre satisfaisante. L'Eurogroupe et, plus important encore, la BCE, ont un r\u00f4le fondamental \u00e0 jouer pour y rem\u00e9dier. ","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>T\u00e9l\u00e9conf\u00e9rence du Conseil europ\u00e9en sur le coronavirus\u202f: un exercice de coordination d\u00e9cevant | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/11\/la-teleconference-du-conseil-europeen-sur-les-coronavirus-un-exercice-de-coordination-decevant\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T\u00e9l\u00e9conf\u00e9rence du Conseil europ\u00e9en sur le coronavirus\u202f: un exercice de coordination d\u00e9cevant | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"La t\u00e9l\u00e9conf\u00e9rence sur le coronavirus d&#039;hier, qui \u00e9tait consid\u00e9r\u00e9e comme le premier exercice de coordination entre les dirigeants europ\u00e9ens sur les \u00e9pid\u00e9mies, s\u2019est en r\u00e9alit\u00e9 av\u00e9r\u00e9e totalement d\u00e9cevante. Le Conseil n&#039;a pas su reconna\u00eetre l&#039;ampleur de la crise sanitaire et proposer une strat\u00e9gie commune, et son approche \u00e9conomique est loin d&#039;\u00eatre satisfaisante. L&#039;Eurogroupe et, plus important encore, la BCE, ont un r\u00f4le fondamental \u00e0 jouer pour y rem\u00e9dier.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/11\/la-teleconference-du-conseil-europeen-sur-les-coronavirus-un-exercice-de-coordination-decevant\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-11T18:57:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-19T09:48:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/03\/Capture-d\u2019\u00e9cran-2020-03-11-\u00e0-13.38.14-e1583938823774.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2586\" \/>\n\t<meta property=\"og:image:height\" content=\"1402\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Giovanni Collot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/03\/Capture-d\u2019\u00e9cran-2020-03-11-\u00e0-13.38.14-e1583938823774.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giovanni Collot\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/11\/la-teleconference-du-conseil-europeen-sur-les-coronavirus-un-exercice-de-coordination-decevant\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/11\/la-teleconference-du-conseil-europeen-sur-les-coronavirus-un-exercice-de-coordination-decevant\/\",\"name\":\"T\u00e9l\u00e9conf\u00e9rence du Conseil europ\u00e9en sur le coronavirus\u202f: un exercice de coordination d\u00e9cevant | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/11\/la-teleconference-du-conseil-europeen-sur-les-coronavirus-un-exercice-de-coordination-decevant\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/11\/la-teleconference-du-conseil-europeen-sur-les-coronavirus-un-exercice-de-coordination-decevant\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/03\/Capture-d\u2019\u00e9cran-2020-03-11-\u00e0-13.38.14-e1583938823774.png\",\"datePublished\":\"2020-03-11T18:57:52+00:00\",\"dateModified\":\"2020-03-19T09:48:58+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/11\/la-teleconference-du-conseil-europeen-sur-les-coronavirus-un-exercice-de-coordination-decevant\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/11\/la-teleconference-du-conseil-europeen-sur-les-coronavirus-un-exercice-de-coordination-decevant\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/11\/la-teleconference-du-conseil-europeen-sur-les-coronavirus-un-exercice-de-coordination-decevant\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/03\/Capture-d\u2019\u00e9cran-2020-03-11-\u00e0-13.38.14-e1583938823774.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/03\/Capture-d\u2019\u00e9cran-2020-03-11-\u00e0-13.38.14-e1583938823774.png\",\"width\":2586,\"height\":1402,\"caption\":\"Plus de 80 000 cas confirm\u00e9s en Chine 20 000 cas entre Europe Russie Etats-Unis et Egypte Afrique, Nig\u00e9ria, Br\u00e9sil\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/11\/la-teleconference-du-conseil-europeen-sur-les-coronavirus-un-exercice-de-coordination-decevant\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"T\u00e9l\u00e9conf\u00e9rence du Conseil europ\u00e9en sur le coronavirus&#160;: un exercice de coordination d\u00e9cevant\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef\",\"name\":\"Giovanni Collot\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g\",\"caption\":\"Giovanni Collot\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T\u00e9l\u00e9conf\u00e9rence du Conseil europ\u00e9en sur le coronavirus\u202f: un exercice de coordination d\u00e9cevant | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/11\/la-teleconference-du-conseil-europeen-sur-les-coronavirus-un-exercice-de-coordination-decevant\/","og_locale":"fr_FR","og_type":"article","og_title":"T\u00e9l\u00e9conf\u00e9rence du Conseil europ\u00e9en sur le coronavirus\u202f: un exercice de coordination d\u00e9cevant | Le Grand Continent","og_description":"La t\u00e9l\u00e9conf\u00e9rence sur le coronavirus d'hier, qui \u00e9tait consid\u00e9r\u00e9e comme le premier exercice de coordination entre les dirigeants europ\u00e9ens sur les \u00e9pid\u00e9mies, s\u2019est en r\u00e9alit\u00e9 av\u00e9r\u00e9e totalement d\u00e9cevante. Le Conseil n'a pas su reconna\u00eetre l'ampleur de la crise sanitaire et proposer une strat\u00e9gie commune, et son approche \u00e9conomique est loin d'\u00eatre satisfaisante. L'Eurogroupe et, plus important encore, la BCE, ont un r\u00f4le fondamental \u00e0 jouer pour y rem\u00e9dier.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/11\/la-teleconference-du-conseil-europeen-sur-les-coronavirus-un-exercice-de-coordination-decevant\/","og_site_name":"Le Grand Continent","article_published_time":"2020-03-11T18:57:52+00:00","article_modified_time":"2020-03-19T09:48:58+00:00","og_image":[{"width":2586,"height":1402,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/03\/Capture-d\u2019\u00e9cran-2020-03-11-\u00e0-13.38.14-e1583938823774.png","type":"image\/png"}],"author":"Giovanni Collot","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/03\/Capture-d\u2019\u00e9cran-2020-03-11-\u00e0-13.38.14-e1583938823774.png","twitter_misc":{"\u00c9crit par":"Giovanni Collot","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/11\/la-teleconference-du-conseil-europeen-sur-les-coronavirus-un-exercice-de-coordination-decevant\/","url":"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/11\/la-teleconference-du-conseil-europeen-sur-les-coronavirus-un-exercice-de-coordination-decevant\/","name":"T\u00e9l\u00e9conf\u00e9rence du Conseil europ\u00e9en sur le coronavirus\u202f: un exercice de coordination d\u00e9cevant | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/11\/la-teleconference-du-conseil-europeen-sur-les-coronavirus-un-exercice-de-coordination-decevant\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/11\/la-teleconference-du-conseil-europeen-sur-les-coronavirus-un-exercice-de-coordination-decevant\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/03\/Capture-d\u2019\u00e9cran-2020-03-11-\u00e0-13.38.14-e1583938823774.png","datePublished":"2020-03-11T18:57:52+00:00","dateModified":"2020-03-19T09:48:58+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/11\/la-teleconference-du-conseil-europeen-sur-les-coronavirus-un-exercice-de-coordination-decevant\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2020\/03\/11\/la-teleconference-du-conseil-europeen-sur-les-coronavirus-un-exercice-de-coordination-decevant\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/11\/la-teleconference-du-conseil-europeen-sur-les-coronavirus-un-exercice-de-coordination-decevant\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/03\/Capture-d\u2019\u00e9cran-2020-03-11-\u00e0-13.38.14-e1583938823774.png","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/03\/Capture-d\u2019\u00e9cran-2020-03-11-\u00e0-13.38.14-e1583938823774.png","width":2586,"height":1402,"caption":"Plus de 80 000 cas confirm\u00e9s en Chine 20 000 cas entre Europe Russie Etats-Unis et Egypte Afrique, Nig\u00e9ria, Br\u00e9sil"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2020\/03\/11\/la-teleconference-du-conseil-europeen-sur-les-coronavirus-un-exercice-de-coordination-decevant\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"T\u00e9l\u00e9conf\u00e9rence du Conseil europ\u00e9en sur le coronavirus&#160;: un exercice de coordination d\u00e9cevant"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef","name":"Giovanni Collot","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g","caption":"Giovanni Collot"}}]}},"lgc_categories":[{"id":1727,"name":"\u00c9conomie","slug":"economie"}],"lgc_author":{"id":1970,"name":"Shahin Vall\u00e9e","slug":"shahin-vallee","description":"Ancien conseiller du Pr\u00e9sident du Conseil europ\u00e9en (Herman Von Rompuy) et ancien conseiller du Ministre de l'\u00c9conomie (Emmanuel Macron), Shahin Vall\u00e9e est chercheur en \u00e9conomie politique au Deutsche Gesellschaft f\u00fcr Ausw\u00e4rtige Politik (DGAP)","first_name":"Shahin ","last_name":"Vall\u00e9e","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/01\/SUMMIT_GRAND_CONTINENT_1173_Shahin-Vallee_umbertocostamagna\u00a92023.png","width":1307,"height":1340,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/03\/Capture-d\u2019\u00e9cran-2020-03-11-\u00e0-13.38.14-e1583938823774.png","width":2586,"height":1402,"alt":"carte dimension mondiale pand\u00e9mie potentielle covid-19 crise sant\u00e9 OMS Chine"},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/62888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=62888"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/62888\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/62864"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=62888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=62888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=62888"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=62888"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=62888"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=62888"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=62888"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=62888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}