{"id":61137,"date":"2020-02-26T16:56:33","date_gmt":"2020-02-26T15:56:33","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=61137"},"modified":"2020-04-11T00:38:14","modified_gmt":"2020-04-10T22:38:14","slug":"au-dela-de-sophia-de-la-lutte-contre-le-trafic-de-migrants-a-lembargo-sur-la-libye","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2020\/02\/26\/au-dela-de-sophia-de-la-lutte-contre-le-trafic-de-migrants-a-lembargo-sur-la-libye\/","title":{"rendered":"Au-del\u00e0 de Sophia&#160;: de la lutte contre le trafic de migrants \u00e0 l&#8217;embargo sur la Libye"},"content":{"rendered":"\n<p><em>Bruxelles<\/em>. C&rsquo;\u00e9tait un accord inattendu, presque inesp\u00e9r\u00e9 par le Haut repr\u00e9sentant Josep Borrell lui-m\u00eame, du moins jusqu&rsquo;\u00e0 lundi dernier. Et pourtant, le 17 f\u00e9vrier, pr\u00e8s d&rsquo;un mois apr\u00e8s la conf\u00e9rence de Berlin, le Conseil des affaires \u00e9trang\u00e8res a d\u00e9cid\u00e9 de mettre fin d\u00e9finitivement \u00e0 l&rsquo;op\u00e9ration EUNAVFOR MED Sophia \u2014 du nom d&rsquo;une petite fille n\u00e9e \u00e0 bord d&rsquo;un navire de la mission \u2014 dont le mandat expirerait fin mars. \u00c0 sa place, un accord unanime a \u00e9t\u00e9 trouv\u00e9 sur les principes qui sous-tendront ce qui sera une nouvelle mission. La mission pourrait \u00eatre appel\u00e9e \u00ab&#160;Operation EU Active Surveillance&#160;\u00bb et impliquera des moyens a\u00e9riens, satellitaires et navals en M\u00e9diterran\u00e9e orientale. L&rsquo;objectif principal sera de contribuer \u00e0 l&rsquo;\u00e9change d&rsquo;informations et \u00e0 la mise en \u0153uvre de l&#8217;embargo sur les armes \u00e0 destination de la Libye, puis de surveiller la contrebande de p\u00e9trole. L&#8217;embargo, impos\u00e9 en 2011 par la r\u00e9solution n\u00b01970 du Conseil de s\u00e9curit\u00e9 des Nations unies mais viol\u00e9 syst\u00e9matiquement par la suite, a \u00e9t\u00e9 pr\u00e9sent\u00e9 \u00e0 Berlin comme l&rsquo;un des piliers essentiels pour parvenir \u00e0 un cessez-le-feu permanent et \u00e0 l&rsquo;amorce d&rsquo;un processus de paix. L&rsquo;op\u00e9ration semble donc \u00eatre l&rsquo;occasion pour l&rsquo;Europe de montrer qu&rsquo;elle a trouv\u00e9 un plan commun, en retrouvant une cr\u00e9dibilit\u00e9 sur le dossier libyen et en s&rsquo;effor\u00e7ant d&rsquo;\u00e9viter d&rsquo;\u00eatre rel\u00e9gu\u00e9e \u00e0 une position de non pertinence.<\/p>\n\n\n\n<p>Toutefois, les contours et les objectifs de la nouvelle mission, qui devrait \u00eatre op\u00e9rationnelle d&rsquo;ici la fin mars, restent flous, raison pour laquelle il est probablement trop t\u00f4t pour pr\u00e9voir la forme qu&rsquo;elle prendra r\u00e9ellement. En tout \u00e9tat de cause, ce qui ressort de l&rsquo;imbrication des priorit\u00e9s europ\u00e9ennes et des int\u00e9r\u00eats nationaux en mati\u00e8re de gestion des migrations et du sc\u00e9nario libyen sugg\u00e8re qu&rsquo;il ne s&rsquo;agit pas d&rsquo;un accord neutre du point de vue politique. Cela est d\u00fb \u00e0 la fois \u00e0 l&rsquo;effet diff\u00e9rent que le contr\u00f4le ou la mise en \u0153uvre de l&#8217;embargo aurait sur les diff\u00e9rentes parties du conflit libyen, et \u00e0 l&rsquo;imposition de choix hautement s\u00e9curitaires qui sont loin d&rsquo;une logique humanitaire dans le traitement des migrations en M\u00e9diterran\u00e9e. De la base de l&rsquo;accord se d\u00e9gagent \u00e9galement des points de discontinuit\u00e9 importants en ce qui concerne Sophia qui, apr\u00e8s avoir \u00e9t\u00e9 r\u00e9duite \u00e0 une flotte sans navires, est d\u00e9finitivement laiss\u00e9e sur la touche.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Ce qu&rsquo;il reste de Sophia<\/h4>\n\n\n\n<p>La mission EUNAVFOR MED a \u00e9t\u00e9 mise en \u0153uvre en 2015 dans le cadre de la strat\u00e9gie europ\u00e9enne visant \u00e0 r\u00e9pondre \u00e0 la \u00ab&#160;crise des r\u00e9fugi\u00e9s&#160;\u00bb. Son objectif \u00e9tait de s&rsquo;attaquer aux causes profondes du probl\u00e8me de la migration en d\u00e9truisant le r\u00e9seau d&rsquo;entreprises li\u00e9es au trafic de migrants et \u00e0 la traite des \u00eatres humains en M\u00e9diterran\u00e9e centrale. Sophia a \u00e9t\u00e9 d\u00e9ploy\u00e9e sur l&rsquo;une des routes migratoires les plus cruciales et, en pr\u00e8s de quatre ans d&rsquo;activit\u00e9, elle a sauv\u00e9 quelque 50 000 personnes en mer, agissant conform\u00e9ment au droit international. Cependant, il serait trompeur de surestimer le caract\u00e8re humanitaire d&rsquo;EUNAVFOR MED, d&rsquo;autant que tout a \u00e9t\u00e9 fait pour retirer de l&rsquo;op\u00e9ration l&rsquo;accusation d&rsquo;\u00eatre un facteur d&rsquo;attraction pour les migrants et pour souligner le d\u00e9tachement \u00e9vident des op\u00e9rations de recherche et de sauvetage (SAR) qui a caract\u00e9ris\u00e9 l&rsquo;op\u00e9ration Mare Nostrum (octobre 2013 \u2013 octobre 2014)&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-61137' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2020\/02\/26\/au-dela-de-sophia-de-la-lutte-contre-le-trafic-de-migrants-a-lembargo-sur-la-libye\/#easy-footnote-bottom-1-61137' title='EUNPACK, &lt;a href=&quot;http:\/\/www.eunpack.eu\/sites\/default\/files\/publications\/D6.1%20The%20EU%20facing%20crises%20in%20its%20neighbourhood%20evidence%20from%20Libya%20and%20Ukraine.pdf&quot;&gt;How the EU is facing crises in its neighbourhood&lt;\/a&gt;, 31 mars 2017, p. 30.'><sup>1<\/sup><\/a><\/span><\/span>. Entre 2016 et 2017, Sophia a \u00e9t\u00e9 mandat\u00e9e par la Commission et le Conseil pour contribuer \u00e0 l&rsquo;efficacit\u00e9 de l&#8217;embargo sur les armes \u00e0 destination et en provenance de la Libye et pour former ses garde-c\u00f4tes et sa marine. La contribution \u00e0 l&#8217;embargo s&rsquo;est r\u00e9v\u00e9l\u00e9e largement inefficace car l&rsquo;autorisation d&rsquo;inspecter, et \u00e9ventuellement de saisir, les navires impliqu\u00e9s dans le trafic d&rsquo;armes est soumise \u00e0 des conditions extr\u00eamement strictes et exclut les navires appartenant \u00e0 l&rsquo;\u00c9tat. Des violations claires de l&#8217;embargo ont \u00e9t\u00e9 r\u00e9cemment confirm\u00e9es \u00e0 la fois par le rapport du groupe d&rsquo;experts des Nations unies et par le chef adjoint de la mission UNSMIL qui, en raison \u00e9galement de la position peu touch\u00e9e par le trafic o\u00f9 se trouve la mission, a qualifi\u00e9 l&#8217;embargo de \u00ab&#160;plaisanterie&#160;\u00bb. Plus efficace a \u00e9t\u00e9 la phase de formation qui, en raison des accusations de violations graves et syst\u00e9matiques perp\u00e9tr\u00e9es par les garde-c\u00f4tes, notamment dans le cadre des centres de d\u00e9tention, a cependant jet\u00e9 de nombreuses ombres sur l&rsquo;op\u00e9ration et sur sa compatibilit\u00e9 avec le droit international et humanitaire&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-61137' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2020\/02\/26\/au-dela-de-sophia-de-la-lutte-contre-le-trafic-de-migrants-a-lembargo-sur-la-libye\/#easy-footnote-bottom-2-61137' title='Conseil de S\u00e9curit\u00e9, &lt;a href=&quot;https:\/\/unsmil.unmissions.org\/sites\/default\/files\/sg_report_on_unsmil_s_2019_628e.pdf&quot;&gt;United Nations Support Mission in Libya Report of the Secretary-General, &lt;\/a&gt;26 aout 2019.'><sup>2<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>L&rsquo;ann\u00e9e derni\u00e8re, les contradictions internes \u00e0 Sophia, exasp\u00e9r\u00e9es par les questions de s\u00e9curit\u00e9 nationale et le plan de fermeture du port mis en place par le ministre italien de l&rsquo;int\u00e9rieur de l&rsquo;\u00e9poque, Matteo Salvini, ont conduit \u00e0 sa dissolution. En janvier 2019, l&rsquo;Allemagne a quitt\u00e9 la composante navale de la Mission, puis celle-ci a \u00e9t\u00e9 suspendue en mars avec l&rsquo;interruption des patrouilles maritimes. Sophia a ainsi \u00e9t\u00e9 r\u00e9duite \u00e0 un programme de surveillance a\u00e9rienne et de soutien aux garde-c\u00f4tes libyens&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-61137' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2020\/02\/26\/au-dela-de-sophia-de-la-lutte-contre-le-trafic-de-migrants-a-lembargo-sur-la-libye\/#easy-footnote-bottom-3-61137' title='European Council on Refugees and Exiles, &lt;a href=&quot;https:\/\/www.ecre.org\/operation-sophia-ships-remain-suspended-while-support-of-libyan-coast-guard-continues\/&quot;&gt;Operation Sophia&amp;#160;: Ships Remain Suspended while Support of Libyan \u2018Coast Guard\u2019 Continues&lt;\/a&gt;, 27 septembre 2019.'><sup>3<\/sup><\/a><\/span><\/span>. Le compromis politique inh\u00e9rent \u00e0 la suppression de la pr\u00e9sence navale en M\u00e9diterran\u00e9e semblait presque un moyen de contourner les responsabilit\u00e9s europ\u00e9ennes en mati\u00e8re d&rsquo;op\u00e9rations de recherche et de sauvetage, en exploitant les tensions internes de l&rsquo;EUNAVFOR MED, aujourd&rsquo;hui mourante&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-61137' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2020\/02\/26\/au-dela-de-sophia-de-la-lutte-contre-le-trafic-de-migrants-a-lembargo-sur-la-libye\/#easy-footnote-bottom-4-61137' title='Istituto Affari Internazionali, &lt;a href=&quot;https:\/\/www.iai.it\/sites\/default\/files\/iaicom1933.pdf&quot;&gt;A EU Naval Mission Without a Navy&amp;#160;: The Paradox of Operation Sophia,&lt;\/a&gt; 13 mai 2019.'><sup>4<\/sup><\/a><\/span><\/span>. Apr\u00e8s tout, avec la r\u00e9organisation des garde-c\u00f4tes et avec les accords tiss\u00e9s de mani\u00e8re plus ou moins informelle par l&rsquo;Italie, les d\u00e9barquements en provenance de Libye sont maintenant tomb\u00e9s \u00e0 des niveaux inf\u00e9rieurs \u00e0 la p\u00e9riode kadhafienne&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-61137' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2020\/02\/26\/au-dela-de-sophia-de-la-lutte-contre-le-trafic-de-migrants-a-lembargo-sur-la-libye\/#easy-footnote-bottom-5-61137' title='Istituto per gli Studi di Politica Internazionale, &lt;a href=&quot;https:\/\/www.ispionline.it\/it\/pubblicazione\/migrazioni-nel-mediterraneo-tutti-i-numeri-24892&quot;&gt;Migrazioni nel Mediterraneo&amp;#160;: tutti i numeri,&lt;\/a&gt; 22 f\u00e9vrier 2020.'><sup>5<\/sup><\/a><\/span><\/span>, transformant d&rsquo;une part le pays en un \u00e9norme centre de d\u00e9tention et, d&rsquo;autre part, rendant la pr\u00e9sence europ\u00e9enne en M\u00e9diterran\u00e9e centrale superflue \u00e0 des fins de s\u00e9curit\u00e9. Ce compromis semble rester la base de l&rsquo;accord conclu la semaine derni\u00e8re.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Naviguer en haute mer&#160;: les enjeux de la nouvelle mission<\/h4>\n\n\n\n<p>En ce qui concerne la question des migrations, la nouvelle op\u00e9ration continue sur la voie consolid\u00e9e depuis mars dernier&#160;: elle s&rsquo;\u00e9loignera de la M\u00e9diterran\u00e9e centrale pour se diriger vers la Cyr\u00e9na\u00efque, d&rsquo;o\u00f9 les d\u00e9parts de migrants sont nettement moins nombreux. Une fois de plus, malgr\u00e9 le fait que le ph\u00e9nom\u00e8ne a \u00e9t\u00e9 largement ni\u00e9, on tente d&rsquo;\u00e9viter les accusations selon lesquelles la pr\u00e9sence d&rsquo;op\u00e9rations navales encouragerait les d\u00e9parts, en pr\u00e9cisant qu&rsquo;aucune fin humanitaire n&rsquo;est pr\u00e9vue. Les navires se trouveront en fait \u00e0 au moins 100 km des c\u00f4tes libyennes, \u00ab&#160;l\u00e0 o\u00f9 les chances de mener des op\u00e9rations de sauvetage sont plus faibles&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-61137' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2020\/02\/26\/au-dela-de-sophia-de-la-lutte-contre-le-trafic-de-migrants-a-lembargo-sur-la-libye\/#easy-footnote-bottom-6-61137' title='Consiglio dell\u2019Unione Europea, &lt;a href=&quot;http:\/\/www.statewatch.org\/news\/2020\/feb\/eu-eeas-note-coreper-operation-sophia-rescue-5995-20.pdf&quot;&gt;Cover note on the Meeting of the Council (Foreign Affairs) on 17 February 2020&lt;\/a&gt;, 12 f\u00e9vrier 2020.'><sup>6<\/sup><\/a><\/span><\/span>. Afin de parvenir \u00e0 un accord en contournant l&rsquo;opposition autrichienne soutenue par la Hongrie et la Slovaquie, il a \u00e9galement \u00e9t\u00e9 pr\u00e9vu que, dans le cas o\u00f9 il y aurait des preuves que l&rsquo;op\u00e9ration constitue un facteur d&rsquo;attraction, la composante navale pourrait \u00eatre suspendue&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-7-61137' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2020\/02\/26\/au-dela-de-sophia-de-la-lutte-contre-le-trafic-de-migrants-a-lembargo-sur-la-libye\/#easy-footnote-bottom-7-61137' title='Consiglio dell\u2019Unione Europea, &lt;a href=&quot;https:\/\/www.consilium.europa.eu\/media\/42603\/st06117-en20_v2.pdf&quot;&gt;Outcome of the Council meeting Foreign Affairs 17 February 2020&lt;\/a&gt;, 17 f\u00e9vrier 2020.'><sup>7<\/sup><\/a><\/span><\/span>. Cependant, la base sur laquelle de telles preuves pourraient \u00eatre reconnues reste \u00e0 d\u00e9terminer, ce n&rsquo;est d&rsquo;ailleurs pas un hasard si de nombreuses organisations humanitaires ont manifest\u00e9 leur inqui\u00e9tude face \u00e0 une op\u00e9ration qui, en \u00e9loignant les personnes en d\u00e9tresse en mer, est contraire \u00e0 l&rsquo;esprit du droit international&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-8-61137' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2020\/02\/26\/au-dela-de-sophia-de-la-lutte-contre-le-trafic-de-migrants-a-lembargo-sur-la-libye\/#easy-footnote-bottom-8-61137' title='Human Rights Watch, &lt;a href=&quot;https:\/\/www.hrw.org\/news\/2020\/02\/18\/eu-turns-its-back-migrants-distress&quot;&gt;EU Turns Its Back on Migrants in Distress, New Naval Mission Designed to Avoid Sea Rescues&lt;\/a&gt;, 18 f\u00e9vrier 2020.'><sup>8<\/sup><\/a><\/span><\/span>. Les cons\u00e9quences tir\u00e9es du positionnement le plus \u00e0 l&rsquo;est de la composante navale pourraient cependant \u00eatre, au moins en partie, risqu\u00e9es. Au-del\u00e0 de l&rsquo;accord politique conclu jusqu&rsquo;\u00e0 pr\u00e9sent, il ne peut en effet \u00eatre exclu que, comme cela s&rsquo;est produit avec l&rsquo;op\u00e9ration Triton, la zone d&rsquo;action soit \u00e9tendue, \u00e0 une date ult\u00e9rieure, vers la M\u00e9diterran\u00e9e centrale, pr\u00e9cis\u00e9ment dans le but de rendre l&#8217;embargo plus efficace. En outre, il faudra attendre au moins la prochaine r\u00e9union du Conseil des affaires \u00e9trang\u00e8res pour comprendre s&rsquo;il s&rsquo;agira d&rsquo;une action de surveillance ou d&rsquo;application de l&#8217;embargo, ce qui aura \u00e9galement un impact non n\u00e9gligeable sur le co\u00fbt de la mission elle-m\u00eame. En outre, des d\u00e9penses particuli\u00e8rement \u00e9lev\u00e9es pourraient \u00e0 la longue user l&rsquo;accord de principe conclu par les \u00c9tats membres, surtout si l&rsquo;op\u00e9ration ne donne pas les r\u00e9sultats escompt\u00e9s.<\/p>\n\n\n\n<p>Enfin, la Mission ne sera pas neutre au vu des \u00e9quilibres g\u00e9opolitiques r\u00e9gionaux. En effet, si de la M\u00e9diterran\u00e9e orientale proviennent \u00e0 la fois des armes turques en soutien \u00e0 Fayez al-Serraj et des armes \u00e9miriennes et saoudiennes en soutien au g\u00e9n\u00e9ral Khalifa Haftar, ce dernier re\u00e7oit la plupart des armes par voie a\u00e9rienne et terrestre, notamment des fronti\u00e8res avec l&rsquo;\u00c9gypte et le Tchad&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-9-61137' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2020\/02\/26\/au-dela-de-sophia-de-la-lutte-contre-le-trafic-de-migrants-a-lembargo-sur-la-libye\/#easy-footnote-bottom-9-61137' title='Panel of Experts on Libya, &lt;a href=&quot;https:\/\/undocs.org\/S\/2019\/914&quot;&gt;Final report of the Panel of Experts on Libya submitted in accordance with resolution 2441 (2018)&lt;\/a&gt;, 9 dicembre 2019.'><sup>9<\/sup><\/a><\/span><\/span>. Par cons\u00e9quent, l&rsquo;op\u00e9ration aurait pour r\u00e9sultat de renforcer l&#8217;embargo, en particulier en ce qui concerne al-Serraj, et mettrait \u00e9galement l&rsquo;Union dans un conflit fort avec la Turquie. Cela aggrave encore les tensions qui ont suivi le protocole d&rsquo;accord conclu entre le pr\u00e9sident Erdogan et le gouvernement d&rsquo;al-Serraj sur le partage des hydrocarbures en M\u00e9diterran\u00e9e orientale et qui, dans une tentative de redessiner les fronti\u00e8res sous-marines, touche aux int\u00e9r\u00eats de nombreux \u00c9tats europ\u00e9ens. Les r\u00e9actions enflamm\u00e9es d&rsquo;Erdogan \u00e0 la suite de l&rsquo;accord sur la nouvelle op\u00e9ration ne se sont pas fait attendre.<\/p>\n\n\n\n<p>De nombreuses questions restent ouvertes sur ce que sera l&rsquo;engagement de l&rsquo;Union en M\u00e9diterran\u00e9e&#160;; ce qui est certain, c&rsquo;est que l&rsquo;imbrication d&rsquo;int\u00e9r\u00eats largement nationaux sur le dossier libyen et sur la question des migrations risque d&rsquo;exasp\u00e9rer des tensions plus ou moins latentes. La tentative de l&rsquo;Europe de jouer un r\u00f4le cr\u00e9dible sur la Libye s&rsquo;accompagne d&rsquo;un renoncement explicite \u00e0 une approche humanitaire de la gestion des migrations. En ce sens, le choix d&rsquo;une perspective v\u00e9ritablement europ\u00e9enne, telle qu&rsquo;une op\u00e9ration SAR dirig\u00e9e par l&rsquo;Union europ\u00e9enne, semble aujourd&rsquo;hui plus \u00e9loign\u00e9 que jamais et trahit la difficult\u00e9 de l&rsquo;Union \u00e0 fixer le cap \u00e0 long TERME. \u00ab&#160;On fait ce qu&rsquo;on peut&#160;\u00bb, a d\u00e9clar\u00e9 M. Borrell lorsqu&rsquo;il est parvenu \u00e0 un accord. Est-ce que cela suffira&#160;?<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/07\/GEG_securite_mediterraneeoccidentale.png\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"4677\"\n        data-pswp-height=\"3307\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/07\/GEG_securite_mediterraneeoccidentale-330x233.png\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/07\/GEG_securite_mediterraneeoccidentale-690x488.png\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/07\/GEG_securite_mediterraneeoccidentale-1340x947.png\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/07\/GEG_securite_mediterraneeoccidentale-125x88.png\" \/>\r\n        <\/picture>\r\n                            \n            <\/a>\n<\/figure>\n\n\n<h4 class=\"wp-block-heading\"><strong>Perspectives&#160;:&nbsp;<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>Des d\u00e9cisions importantes visant \u00e0 \u00e9tablir plus en d\u00e9tail l&rsquo;organisation de la mission seront prises lors du prochain Conseil des affaires \u00e9trang\u00e8res du 23 mars 2020.<\/li><li>La politique \u00e9trang\u00e8re d&rsquo;Erdogan dans les prochaines semaines sera probablement li\u00e9e \u00e0 cette question et pourrait avoir un impact sur les prochains choix du Conseil.<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Le 17 f\u00e9vrier, pr\u00e8s d&rsquo;un mois apr\u00e8s la conf\u00e9rence de Berlin, le Conseil des affaires \u00e9trang\u00e8res a d\u00e9cid\u00e9 de mettre fin d\u00e9finitivement \u00e0 l&rsquo;op\u00e9ration EUNAVFOR MED Sophia. \u00c0 sa place, un accord unanime a \u00e9t\u00e9 trouv\u00e9 sur les principes qui sous-tendront ce qui sera une nouvelle mission, qui pourrait \u00eatre appel\u00e9e \u00ab&#160;&#160;Operation EU Active Surveillance&#160;&#160;\u00bb et impliquera des moyens a\u00e9riens, satellitaires et navals en M\u00e9diterran\u00e9e orientale. <\/p>\n","protected":false},"author":175,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":0,"footnotes":""},"categories":[1731],"tags":[],"staff":[2178],"editorial_format":[4942],"serie":[],"audience":[],"geo":[534,543],"class_list":["post-61137","post","type-post","status-publish","format-standard","hentry","category-politique","staff-alice-fill","editorial_format-actu-breves","geo-bulles","geo-mediterranee"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":"","excerpt":"Le 17 f\u00e9vrier, pr\u00e8s d'un mois apr\u00e8s la conf\u00e9rence de Berlin, le Conseil des affaires \u00e9trang\u00e8res a d\u00e9cid\u00e9 de mettre fin d\u00e9finitivement \u00e0 l'op\u00e9ration EUNAVFOR MED Sophia. \u00c0 sa place, un accord unanime a \u00e9t\u00e9 trouv\u00e9 sur les principes qui sous-tendront ce qui sera une nouvelle mission, qui pourrait \u00eatre appel\u00e9e \u00ab Operation EU Active Surveillance \u00bb et impliquera des moyens a\u00e9riens, satellitaires et navals en M\u00e9diterran\u00e9e orientale. ","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Au-del\u00e0 de Sophia : de la lutte contre le trafic de migrants \u00e0 l&#039;embargo sur la Libye | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2020\/02\/26\/au-dela-de-sophia-de-la-lutte-contre-le-trafic-de-migrants-a-lembargo-sur-la-libye\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Au-del\u00e0 de Sophia : de la lutte contre le trafic de migrants \u00e0 l&#039;embargo sur la Libye | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Le 17 f\u00e9vrier, pr\u00e8s d&#039;un mois apr\u00e8s la conf\u00e9rence de Berlin, le Conseil des affaires \u00e9trang\u00e8res a d\u00e9cid\u00e9 de mettre fin d\u00e9finitivement \u00e0 l&#039;op\u00e9ration EUNAVFOR MED Sophia. \u00c0 sa place, un accord unanime a \u00e9t\u00e9 trouv\u00e9 sur les principes qui sous-tendront ce qui sera une nouvelle mission, qui pourrait \u00eatre appel\u00e9e \u00ab&#160;Operation EU Active Surveillance&#160;\u00bb et impliquera des moyens a\u00e9riens, satellitaires et navals en M\u00e9diterran\u00e9e orientale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2020\/02\/26\/au-dela-de-sophia-de-la-lutte-contre-le-trafic-de-migrants-a-lembargo-sur-la-libye\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-26T15:56:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-10T22:38:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/07\/GEG_securite_mediterraneeoccidentale-990x700.png\" \/>\n\t<meta property=\"og:image:width\" content=\"990\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Giovanni Collot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/07\/GEG_securite_mediterraneeoccidentale.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giovanni Collot\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2020\/02\/26\/au-dela-de-sophia-de-la-lutte-contre-le-trafic-de-migrants-a-lembargo-sur-la-libye\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2020\/02\/26\/au-dela-de-sophia-de-la-lutte-contre-le-trafic-de-migrants-a-lembargo-sur-la-libye\/\",\"name\":\"Au-del\u00e0 de Sophia : de la lutte contre le trafic de migrants \u00e0 l'embargo sur la Libye | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"datePublished\":\"2020-02-26T15:56:33+00:00\",\"dateModified\":\"2020-04-10T22:38:14+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2020\/02\/26\/au-dela-de-sophia-de-la-lutte-contre-le-trafic-de-migrants-a-lembargo-sur-la-libye\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2020\/02\/26\/au-dela-de-sophia-de-la-lutte-contre-le-trafic-de-migrants-a-lembargo-sur-la-libye\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2020\/02\/26\/au-dela-de-sophia-de-la-lutte-contre-le-trafic-de-migrants-a-lembargo-sur-la-libye\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Au-del\u00e0 de Sophia&#160;: de la lutte contre le trafic de migrants \u00e0 l&#8217;embargo sur la Libye\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef\",\"name\":\"Giovanni Collot\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g\",\"caption\":\"Giovanni Collot\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Au-del\u00e0 de Sophia : de la lutte contre le trafic de migrants \u00e0 l'embargo sur la Libye | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2020\/02\/26\/au-dela-de-sophia-de-la-lutte-contre-le-trafic-de-migrants-a-lembargo-sur-la-libye\/","og_locale":"fr_FR","og_type":"article","og_title":"Au-del\u00e0 de Sophia : de la lutte contre le trafic de migrants \u00e0 l'embargo sur la Libye | Le Grand Continent","og_description":"Le 17 f\u00e9vrier, pr\u00e8s d'un mois apr\u00e8s la conf\u00e9rence de Berlin, le Conseil des affaires \u00e9trang\u00e8res a d\u00e9cid\u00e9 de mettre fin d\u00e9finitivement \u00e0 l'op\u00e9ration EUNAVFOR MED Sophia. \u00c0 sa place, un accord unanime a \u00e9t\u00e9 trouv\u00e9 sur les principes qui sous-tendront ce qui sera une nouvelle mission, qui pourrait \u00eatre appel\u00e9e \u00ab&#160;Operation EU Active Surveillance&#160;\u00bb et impliquera des moyens a\u00e9riens, satellitaires et navals en M\u00e9diterran\u00e9e orientale.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2020\/02\/26\/au-dela-de-sophia-de-la-lutte-contre-le-trafic-de-migrants-a-lembargo-sur-la-libye\/","og_site_name":"Le Grand Continent","article_published_time":"2020-02-26T15:56:33+00:00","article_modified_time":"2020-04-10T22:38:14+00:00","og_image":[{"width":990,"height":700,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/07\/GEG_securite_mediterraneeoccidentale-990x700.png","type":"image\/png"}],"author":"Giovanni Collot","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/07\/GEG_securite_mediterraneeoccidentale.png","twitter_misc":{"\u00c9crit par":"Giovanni Collot","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2020\/02\/26\/au-dela-de-sophia-de-la-lutte-contre-le-trafic-de-migrants-a-lembargo-sur-la-libye\/","url":"https:\/\/legrandcontinent.eu\/fr\/2020\/02\/26\/au-dela-de-sophia-de-la-lutte-contre-le-trafic-de-migrants-a-lembargo-sur-la-libye\/","name":"Au-del\u00e0 de Sophia : de la lutte contre le trafic de migrants \u00e0 l'embargo sur la Libye | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"datePublished":"2020-02-26T15:56:33+00:00","dateModified":"2020-04-10T22:38:14+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2020\/02\/26\/au-dela-de-sophia-de-la-lutte-contre-le-trafic-de-migrants-a-lembargo-sur-la-libye\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2020\/02\/26\/au-dela-de-sophia-de-la-lutte-contre-le-trafic-de-migrants-a-lembargo-sur-la-libye\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2020\/02\/26\/au-dela-de-sophia-de-la-lutte-contre-le-trafic-de-migrants-a-lembargo-sur-la-libye\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Au-del\u00e0 de Sophia&#160;: de la lutte contre le trafic de migrants \u00e0 l&#8217;embargo sur la Libye"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef","name":"Giovanni Collot","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g","caption":"Giovanni Collot"}}]}},"lgc_categories":[{"id":1731,"name":"Politique","slug":"politique"}],"lgc_author":{"id":2178,"name":"Alice Fill","slug":"alice-fill","description":"Alice Fill est doctorante \u00e0 l\u2019\u00c9cole Normale Sup\u00e9rieure (ENS), Chaire de G\u00e9opolitique du risque. Elle est sp\u00e9cialiste des migrations et a \u00e9crit sa th\u00e8se sur \u00ab Digital transformation of the migration regime in Africa : developments and setbacks between Human Rights and Migration Governance \u00bb.","first_name":"Alice","last_name":"Fill","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/08\/gc-AliceFill.jpg","width":914,"height":914,"alt":""}},"feature_image_summary":null,"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/61137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=61137"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/61137\/revisions"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=61137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=61137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=61137"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=61137"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=61137"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=61137"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=61137"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=61137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}