{"id":5696,"date":"2018-07-15T22:00:47","date_gmt":"2018-07-15T20:00:47","guid":{"rendered":"https:\/\/lldl.eu\/?p=5696"},"modified":"2019-05-18T18:03:52","modified_gmt":"2019-05-18T16:03:52","slug":"quelle-place-pour-lotan-dans-la-politique-etrangere-turque","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2018\/07\/15\/quelle-place-pour-lotan-dans-la-politique-etrangere-turque\/","title":{"rendered":"Quelle place pour l\u2019Otan dans la politique \u00e9trang\u00e8re turque&#160;?"},"content":{"rendered":"\n<p><em>Ankara<\/em> &#8211; La Turquie est membre de l&rsquo;Otan depuis 1952 et repr\u00e9sente la deuxi\u00e8me arm\u00e9e de l&rsquo;alliance en terme d&rsquo;effectifs militaires. Cependant, depuis la tentative de coup d&rsquo;\u00c9tat du 15 juillet 2016, son arm\u00e9e a \u00e9t\u00e9 fortement affaiblie&#160;: un tiers de ses g\u00e9n\u00e9raux a \u00e9t\u00e9 limog\u00e9 et les purges dans l\u2019administration ont \u00e9t\u00e9 massives. Si la question de l&rsquo;\u00e9tat de droit peut \u00eatre consid\u00e9r\u00e9e comme secondaire pour l&rsquo;Otan, la Turquie suscitait beaucoup d&rsquo;interrogations et d&rsquo;inqui\u00e9tudes tant sur le plan de l&rsquo;\u00e9tat de la d\u00e9mocratie que sur les orientations internationales prises par le gouvernement. R\u00e9cemment r\u00e9\u00e9lu \u00e0 la t\u00eate du pays, Recep Tayyip Erdo\u011fan (accompagn\u00e9 de son ministre de la d\u00e9fense Hulusi Akar, du ministre des affaires \u00e9trang\u00e8res, Mevlut \u00c7avu\u015fo\u011flu  et du tr\u00e8s influent porte parole de la pr\u00e9sidence, Ibrahim Kal\u0131n), s&rsquo;est pr\u00e9sent\u00e9 lors du sommet comme un alli\u00e9 stable. Et malgr\u00e9 les revirements tactiques de ces derni\u00e8res ann\u00e9es, notamment le rapprochement et la normalisation des relations avec la Russie, qui n&rsquo;ont pas de quoi rassurer une alliance atlantique en qu\u00eate de visibilit\u00e9 strat\u00e9gique, l&rsquo;ancrage de la Turquie dans l&rsquo;Otan ne semble plus \u00eatre remis en cause (<strong>4<\/strong>).<\/p>\n\n\n\n<p>La Turquie est finalement en qu\u00eate d&rsquo;autonomie strat\u00e9gique. Dans ce contexte, le choix d&rsquo;acheter \u00e0 la Russie des batteries de missiles antia\u00e9riennes S-400 en est un bon exemple. Lors du sommet, Mevl\u00fct \u00c7avu\u015fo\u011flu  se justifie en d\u00e9clarant que \u00ab&#160;c&rsquo;\u00e9tait un besoin urgent et comme nous n&rsquo;avons pas pu r\u00e9pondre \u00e0 ce besoin \u00e0 travers nos alli\u00e9s, nous les avons achet\u00e9 \u00e0 la Russie car c&rsquo;est elle qui a fourni la meilleure offre&#160;\u00bb (<strong>1<\/strong>). Toutefois, peu de critiques sont apparues ces 11 et 12 juillet alors m\u00eame que la menace du spectre russe continue de planer sur les r\u00e9unions de l&rsquo;Otan (<strong>2<\/strong>). Avec le rapprochement diplomatique, \u00e9conomique et maintenant militaire entre Ankara et Moscou, il devient incontestable que la Turquie n&rsquo;est plus totalement d\u00e9pendante de l&rsquo;Otan. Elle devient plus autonome tout en prenant le risque de creuser le foss\u00e9 strat\u00e9gique entre alli\u00e9s.<\/p>\n\n\n\n<p>Pourtant, entre l&rsquo;Otan et la Turquie l&rsquo;interd\u00e9pendance reste pr\u00e9sente. Sur le plan strat\u00e9gique et militaire la Turquie est une alli\u00e9e incontournable et indispensable. De son c\u00f4t\u00e9, d\u00e9j\u00e0 rejet\u00e9e par l&rsquo;Union Europ\u00e9enne, Ankara ne peut pas se permettre de se faire exclure de l&rsquo;alliance militaire. Sans les occidentaux, elle ne pourra faire face \u00e0 la Russie ni disposer d&rsquo;un relatif soutient  militaire dans sa lutte contre le terrorisme. \u00c0 ce titre, la s\u00e9curisation de sa fronti\u00e8re de plus de 800 km avec la Syrie repr\u00e9sente un enjeu s\u00e9curitaire international majeur pour la la lutte contre le terrorisme. \u00c0 cet \u00e9gard, l&rsquo;article 23 de la d\u00e9claration finale du sommet pr\u00e9voit des mesures pour permettre \u00e0 la Turquie d&rsquo;assurer sa s\u00e9curit\u00e9 (<strong>3<\/strong>).<\/p>\n\n\n\n<p>L&rsquo;Alliance atlantique est \u00e9galement d\u00e9pendante de la Turquie car cette derni\u00e8re repr\u00e9sente un pivot strat\u00e9gique id\u00e9al. En effet, outre les enjeux de la participation financi\u00e8re ch\u00e8re \u00e0 Donald Trump, les sujets qui pr\u00e9occupent  vraiment l&rsquo;Otan sont la Russie et l&#8217;embrasement du Moyen Orient. De plus, par la Turquie, seule puissance musulmane de l&rsquo;Otan, l&rsquo;alliance dispose d&rsquo;une base militaire \u00e0 Incirlik, dans le Sud du pays et donc d\u2019une ouverture sur le Moyen Orient.<\/p>\n\n\n\n<p>Le rapprochement turco-russe n&rsquo;est finalement pas un changement de paradigme de la politique \u00e9trang\u00e8re turque qui reste ancr\u00e9e \u00e0 l&rsquo;Ouest pour des raisons \u00e9conomiques et militaires. En revanche les occidentaux doivent comprendre qu&rsquo;Ankara est en qu\u00eate d&rsquo;autonomie strat\u00e9gique et de marge de manoeuvre, notamment pour face \u00e0 l&rsquo;urgence de la crise syrienne, pour assurer sa s\u00e9curit\u00e9 \u00e0 la fronti\u00e8re et pour acqu\u00e9rir un statut de puissance r\u00e9gionale.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Perspectives&#160;:<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>La question des contributions financi\u00e8res des \u00c9tats membres de l&rsquo;alliance ayant occup\u00e9 une place pr\u00e9dominante lors de ce sommet, le pr\u00e9sident turc a privil\u00e9gi\u00e9 les rencontres bilat\u00e9rales, comme il a pu le faire avec Angela Merkel, Emmanuel Macron ou encore Giuseppe Conte.<\/li><li>Signe d&rsquo;un renouveau de la coop\u00e9ration entre les \u00c9tats-Unis et la Turquie, \u00e0 la mi-juin, et apr\u00e8s plusieurs mois de tensions, ces deux pays ont valid\u00e9 un accord militaire pour le contr\u00f4le des abords de la ville syrienne de Manbij. Apr\u00e8s plusieurs interventions militaires et notamment avec la bataille d&rsquo;Afrin, les Turcs ont fait la d\u00e9monstration qu&rsquo;ils \u00e9taient pr\u00eats \u00e0 intervenir sur le sol syrien pour emp\u00eacher l&rsquo;implantation territoriale du PYD. Manbij \u00e9tait annonc\u00e9e comme le prochain objectif et, afin de s&rsquo;assurer un r\u00f4le dans le conflit syrien, les \u00c9tats-Unis qui soutiennent les forces kurdes du PYD dans le Nord de la Syrie, ont d\u00fb faire des concessions et n\u00e9gocier avec les turcs les conditions de l&rsquo;avanc\u00e9e en cours vers cette ville.<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Sources&#160;:<\/strong><\/h4>\n\n\n\n<ol class=\"wp-block-list\"><li><a href=\"https:\/\/www.aa.com.tr\/tr\/dunya\/disisleri-bakani-cavusoglundan-s-400-aciklamasi\/1200815\">D\u0131\u015fi\u015fleri Bakan\u0131 \u00c7avu\u015fo\u011flu&rsquo;ndan S-400 a\u00e7\u0131klamas\u0131, <\/a>Agence Anadolu, 11\/07\/2018.<\/li><li>OTAN, <a href=\"https:\/\/www.nato.int\/cps\/en\/natohq\/official_texts_156624.htm\">Brussels Summit Declaration,<\/a> 11\/07\/2018.<\/li><li>OTAN, <a href=\"https:\/\/www.nato.int\/cps\/en\/natohq\/official_texts_156624.htm\">Brussels Summit Declaration, <\/a>11\/07\/2018. Art. 23 \u201cAssurance measures continue to provide the fundamental baseline requirement for assurance and deterrence.  In addition, tailored assurance measures for Turkey to respond to the growing security challenges from the south contribute to the security of the Alliance as a whole, and will be fully implemented.  We have increased the strength of the NATO Response Force, and the Very High Readiness Joint Task Force (VJTF) is ready to deploy on short notice\u201d.<\/li><li><a href=\"https:\/\/thearabweekly.com\/erdogan-faces-challenge-repairing-ties-nato\">Erdogan faces challenge of repairing ties with NATO, <\/a>The Arab Weekly, 08\/07\/2018.<\/li><\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Le 26e sommet de chefs d&rsquo;\u00c9tats et de gouvernement de l&rsquo;Otan a \u00e9t\u00e9 le premier sommet international pour le pr\u00e9sident turc depuis sa r\u00e9\u00e9lection. Entre embarras discret de l&rsquo;Otan \u00e0 l&rsquo;\u00e9gard de son alli\u00e9 turc et volont\u00e9 du pr\u00e9sident Erdo\u011fan de se pr\u00e9senter comme un acteur stable, ce sommet est repr\u00e9sentatif de l&rsquo;ambivalence des relations entre la Turquie et l&rsquo;Alliance atlantique.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":0,"footnotes":""},"categories":[1731],"tags":[],"staff":[1617],"editorial_format":[4942],"serie":[],"audience":[],"geo":[543],"class_list":["post-5696","post","type-post","status-publish","format-standard","hentry","category-politique","staff-david-billeau","editorial_format-actu-breves","geo-mediterranee"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":"","excerpt":"Le 26e sommet de chefs d'\u00c9tats et de gouvernement de l'Otan a \u00e9t\u00e9 le premier sommet international pour le pr\u00e9sident turc depuis sa r\u00e9\u00e9lection. Entre embarras discret de l'Otan \u00e0 l'\u00e9gard de son alli\u00e9 turc et volont\u00e9 du pr\u00e9sident Erdo\u011fan de se pr\u00e9senter comme un acteur stable, ce sommet est repr\u00e9sentatif de l'ambivalence des relations entre la Turquie et l'Alliance atlantique.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quelle place pour l\u2019Otan dans la politique \u00e9trang\u00e8re turque ? | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2018\/07\/15\/quelle-place-pour-lotan-dans-la-politique-etrangere-turque\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quelle place pour l\u2019Otan dans la politique \u00e9trang\u00e8re turque ? | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Le 26e sommet de chefs d&#039;\u00c9tats et de gouvernement de l&#039;Otan a \u00e9t\u00e9 le premier sommet international pour le pr\u00e9sident turc depuis sa r\u00e9\u00e9lection. Entre embarras discret de l&#039;Otan \u00e0 l&#039;\u00e9gard de son alli\u00e9 turc et volont\u00e9 du pr\u00e9sident Erdo\u011fan de se pr\u00e9senter comme un acteur stable, ce sommet est repr\u00e9sentatif de l&#039;ambivalence des relations entre la Turquie et l&#039;Alliance atlantique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2018\/07\/15\/quelle-place-pour-lotan-dans-la-politique-etrangere-turque\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-15T20:00:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-18T16:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2018\/07\/15\/quelle-place-pour-lotan-dans-la-politique-etrangere-turque\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2018\/07\/15\/quelle-place-pour-lotan-dans-la-politique-etrangere-turque\/\",\"name\":\"Quelle place pour l\u2019Otan dans la politique \u00e9trang\u00e8re turque ? | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"datePublished\":\"2018-07-15T20:00:47+00:00\",\"dateModified\":\"2019-05-18T16:03:52+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2018\/07\/15\/quelle-place-pour-lotan-dans-la-politique-etrangere-turque\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2018\/07\/15\/quelle-place-pour-lotan-dans-la-politique-etrangere-turque\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2018\/07\/15\/quelle-place-pour-lotan-dans-la-politique-etrangere-turque\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quelle place pour l\u2019Otan dans la politique \u00e9trang\u00e8re turque&#160;?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quelle place pour l\u2019Otan dans la politique \u00e9trang\u00e8re turque ? | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2018\/07\/15\/quelle-place-pour-lotan-dans-la-politique-etrangere-turque\/","og_locale":"fr_FR","og_type":"article","og_title":"Quelle place pour l\u2019Otan dans la politique \u00e9trang\u00e8re turque ? | Le Grand Continent","og_description":"Le 26e sommet de chefs d'\u00c9tats et de gouvernement de l'Otan a \u00e9t\u00e9 le premier sommet international pour le pr\u00e9sident turc depuis sa r\u00e9\u00e9lection. Entre embarras discret de l'Otan \u00e0 l'\u00e9gard de son alli\u00e9 turc et volont\u00e9 du pr\u00e9sident Erdo\u011fan de se pr\u00e9senter comme un acteur stable, ce sommet est repr\u00e9sentatif de l'ambivalence des relations entre la Turquie et l'Alliance atlantique.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2018\/07\/15\/quelle-place-pour-lotan-dans-la-politique-etrangere-turque\/","og_site_name":"Le Grand Continent","article_published_time":"2018-07-15T20:00:47+00:00","article_modified_time":"2019-05-18T16:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2018\/07\/15\/quelle-place-pour-lotan-dans-la-politique-etrangere-turque\/","url":"https:\/\/legrandcontinent.eu\/fr\/2018\/07\/15\/quelle-place-pour-lotan-dans-la-politique-etrangere-turque\/","name":"Quelle place pour l\u2019Otan dans la politique \u00e9trang\u00e8re turque ? | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"datePublished":"2018-07-15T20:00:47+00:00","dateModified":"2019-05-18T16:03:52+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2018\/07\/15\/quelle-place-pour-lotan-dans-la-politique-etrangere-turque\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2018\/07\/15\/quelle-place-pour-lotan-dans-la-politique-etrangere-turque\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2018\/07\/15\/quelle-place-pour-lotan-dans-la-politique-etrangere-turque\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Quelle place pour l\u2019Otan dans la politique \u00e9trang\u00e8re turque&#160;?"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":""}]}},"lgc_categories":[{"id":1731,"name":"Politique","slug":"politique"}],"lgc_author":{"id":1617,"name":"David Billeau","slug":"david-billeau","description":null,"first_name":null,"last_name":null,"picture":null},"feature_image_summary":null,"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/5696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=5696"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/5696\/revisions"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=5696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=5696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=5696"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=5696"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=5696"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=5696"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=5696"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=5696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}