{"id":53064,"date":"2019-11-20T07:55:10","date_gmt":"2019-11-20T06:55:10","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=53064"},"modified":"2019-11-27T13:28:32","modified_gmt":"2019-11-27T12:28:32","slug":"le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/","title":{"rendered":"Le choix des gouvernants de l\u2019Union, pour un meilleur \u00e9quilibre entre d\u00e9mocratie et <em>diplocratie<\/em>"},"content":{"rendered":"\n<p class=\"has-drop-cap\">La fin de la s\u00e9quence politique ouverte par <a href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/05\/27\/regardez-les-elections-europeennes\/\">les \u00e9lections europ\u00e9ennes de mai 2019<\/a>, puis <a href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/07\/20\/comprendre-les-nominations-a-la-tete-de-lunion\/\">le choix des titulaires des postes de responsabilit\u00e9 au sein de l\u2019Union<\/a> et la <a href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/09\/13\/une-commission-geopolitique-les-profils-de-la-commission-von-der-leyen-pt-1\/\">composition de la Commission europ\u00e9enne<\/a>, offre une salutaire occasion d\u2019analyser les logiques politiques qui ont pr\u00e9sid\u00e9 au choix des \u00ab&#160;gouvernants&#160;\u00bb europ\u00e9ens pour le cycle 2019-2024. Compte tenu des <a href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/07\/17\/von-der-leyen-sur-le-fil\/\">tensions<\/a> et crises auxquels elle a donn\u00e9 lieu, cette s\u00e9quence doit aussi conduire \u00e0 d\u00e9gager des enseignements et clarifications propices \u00e0 un meilleur fonctionnement de l\u2019Union, particuli\u00e8rement n\u00e9cessaire compte tenu des d\u00e9fis aigus qu\u2019elle doit relever.<\/p>\n\n\n\n<p>Trait\u00e9s europ\u00e9ens et usages politiques indiquent que deux sources de l\u00e9gitimit\u00e9 doivent \u00eatre combin\u00e9es dans la d\u00e9signation des \u00ab&#160;gouvernants&#160;\u00bb de l\u2019Union&#160;: d\u2019une part la l\u00e9gitimit\u00e9 \u00e9tatique, d\u00e8s lors que les Etats sont \u00e0 l\u2019origine de la construction europ\u00e9enne et voient leurs repr\u00e9sentants si\u00e9ger au sein du Conseil europ\u00e9en et du Conseil&#160;; d\u2019autre part la l\u00e9gitimit\u00e9 civique, principalement incarn\u00e9e \u00e0 Strasbourg et \u00e0 Bruxelles par les parlementaires europ\u00e9ens, puisqu\u2019ils sont \u00e9lus au suffrage universel direct depuis 1979&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-53064' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/#easy-footnote-bottom-1-53064' title='Pour de plus amples d\u00e9veloppements sur ce registre, voir Yves Bertoncini et Thierry Chopin, &lt;em&gt;Politique europ\u00e9enne. Etats, pouvoirs et citoyens de l\u2019Union europ\u00e9enne&lt;\/em&gt;, Manuel, Presses de Sciences Po\/Dalloz 2010.'><sup>1<\/sup><\/a><\/span><\/span>. D\u2019un point de vue historique, il est notable que le primat de la l\u00e9gitimit\u00e9 \u00e9tatique a d\u00fb peu \u00e0 peu composer avec la primaut\u00e9 de la l\u00e9gitimit\u00e9 civique, y compris pour la d\u00e9signation de l\u2019ensemble des gouvernants de l\u2019Union d\u00e8s lors que ce sont les \u00e9lections europ\u00e9ennes qui donnent le coup d\u2019envoi des n\u00e9gociations sur l\u2019ensemble des nominations.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Deux sources de l\u00e9gitimit\u00e9 doivent \u00eatre combin\u00e9es dans la d\u00e9signation des gouvernants de l\u2019Union&#160;: la l\u00e9gitimit\u00e9 \u00e9tatique et la l\u00e9gitimit\u00e9 civique<\/p><cite>Yves Bertoncini, Thierry Chopin<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Ces n\u00e9gociations font d\u00e8s lors l\u2019objet de rapports de force institutionnels, puisque Conseil europ\u00e9en et Parlement europ\u00e9en incarnent l\u2019un et l\u2019autre les deux l\u00e9gitimit\u00e9s fondatrices de l\u2019Union, mais aussi de rapports de force diplomatiques et partisans, qui sont pour une bonne part une autre forme d\u2019expression de ces deux l\u00e9gitimit\u00e9s. Si la d\u00e9signation des Pr\u00e9sidents du Conseil europ\u00e9en et du Parlement europ\u00e9en s\u2019apparente \u00e0 des choix \u00ab&#160;internes&#160;\u00bb \u00e0 ces deux institutions, il n\u2019en va pas de m\u00eame pour la Pr\u00e9sidence et les membres de la Commission europ\u00e9enne, qui doivent n\u00e9cessairement faire l\u2019objet de leur  double approbation. Toutes ces nominations et \u00e9lections participent <em>de facto<\/em> d\u2019une n\u00e9gociation globale, que ces acteurs (Etats, partis, institutions, etc.) s\u2019efforcent de conclure sur la base d\u2019un \u00e9quilibre d\u2019ensemble.<\/p>\n\n\n\n<p>Dans ce contexte, il appara\u00eet d\u2019autant plus utile de tirer toutes les le\u00e7ons <a href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/07\/23\/il-ny-a-pas-de-coalition-europeenne\/\">des difficult\u00e9s survenues<\/a> au cours du second semestre 2019 afin de cr\u00e9er les conditions politiques et juridiques permettant une co-d\u00e9signation plus harmonieuse des gouvernants de l\u2019Union et donc de conforter la l\u00e9gitimit\u00e9 mais aussi l\u2019efficacit\u00e9 de l\u2019Union.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Le choix des gouvernants europ\u00e9ens, de Westphalie \u00e0 Westminster <\/h2>\n\n\n\n<p>Les \u00e9lections europ\u00e9ennes des 23-26 mai 2019 ont donn\u00e9 lieu \u00e0 des \u00e9volutions marquantes en termes de taux de participation et de rapports de force partisans et ont accouch\u00e9 d\u2019<a href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/07\/23\/il-ny-a-pas-de-coalition-europeenne\/\">une nouvelle donne politique<\/a> au regard des cycle politiques pr\u00e9c\u00e9dents. Une mise en perspective historique permet de mieux appr\u00e9hender ces \u00e9volutions dans leur dimension parlementaire, mais aussi s\u2019agissant de <a href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/07\/20\/comprendre-les-nominations-a-la-tete-de-lunion\/\">la d\u00e9signation des principaux gouvernants de l\u2019Union<\/a>, et en particulier <a href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/07\/09\/ursula-von-der-leyen-un-portrait\/\">la nouvelle Pr\u00e9sidente de la Commission europ\u00e9enne<\/a>.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/GEG_participation_europeennes-scaled.png\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"2560\"\n        data-pswp-height=\"2060\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/GEG_participation_europeennes-330x266.png\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/GEG_participation_europeennes-690x555.png\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/GEG_participation_europeennes-1340x1078.png\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" alt=\"Combien des personnes ont-elles vot\u00e9 en UE Europe 2019 par rapport \u00e0 2014 ?\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/GEG_participation_europeennes-125x101.png\" \/>\r\n        <\/picture>\r\n                            \n            <\/a>\n<\/figure>\n\n\n<h3 class=\"wp-block-heading\">Vers <strong>un renforcement de la d\u00e9mocratie europ\u00e9enne&#160;?<\/strong><\/h3>\n\n\n\n<p>Seules les \u00e9lections d\u00e9signant les membres du Parlement europ\u00e9en au  suffrage universel depuis 1979 permettent d\u2019\u00e9tablir un lien direct entre  citoyens et d\u00e9tenteurs de pouvoirs au niveau communautaire. Le fait que  les d\u00e9put\u00e9s europ\u00e9ens soient \u00e9lus <em>via<\/em> des scrutins proportionnels et sur des bases largement nationales emp\u00eache cependant le plus souvent depuis lors la formation d\u2019une majorit\u00e9 politique claire  au sein de l\u2019h\u00e9micycle strasbourgeois. A cet \u00e9gard, trois \u00e9l\u00e9ments frappants caract\u00e9risent les \u00e9lections europ\u00e9ennes des 23-26 mai 2019.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Un taux de participation en forte hausse<\/h4>\n\n\n\n<p>Ces \u00e9lections europ\u00e9ennes ont d\u2019abord \u00e9t\u00e9 caract\u00e9ris\u00e9es par <a href=\"https:\/\/www.lemonde.fr\/idees\/article\/2019\/05\/28\/elections-europeennes-l-europe-reste-prisonniere-d-une-pure-juxtaposition-de-politiques-nationales_5468341_3232.html\">un taux de participation nettement plus \u00e9lev\u00e9 que d&rsquo;habitude<\/a> (+10 points par rapport aux \u00e9lections de 2014). La participation aux \u00e9lections europ\u00e9ennes a augment\u00e9 pour la premi\u00e8re fois dans l&rsquo;histoire (voir Graphique 1) et a \u00e9t\u00e9 la plus \u00e9lev\u00e9e en 25 ans (50,95&#160;%)&#160;; cet accroissement de la participation \u00e9lectorale a eu lieu dans la plupart des \u00c9tats membres et \u00e9galement en France (50,97&#160;%).<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-medium\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Graphe-chopin.png\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"943\"\n        data-pswp-height=\"700\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Graphe-chopin-330x245.png\"\r\n                media=\"(max-width:  374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Graphe-chopin-690x512.png\"\r\n                media=\"(max-width:  989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Graphe-chopin.png\"\r\n                media=\"(max-width: 1319px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Graphe-chopin-690x512.png\"\r\n                media=\"(max-width: 1599px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Graphe-chopin.png\"\r\n                media=\"(min-width: 1600px)\" \/>\r\n                <img decoding=\"async\" alt=\"Un taux de participation en forte hausse\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Graphe-chopin-125x93.png\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Graphique 1 \u2022 Yves Bertoncini, Thierry Chopin pour le Grand Continent<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>Les raisons de cette augmentation de la participation doivent faire l&rsquo;objet d&rsquo;une analyse plus approfondie, mais il semble clair que, au-del\u00e0 des facteurs nationaux internes et propres \u00e0 chaque Etat membre, des facteurs exog\u00e8nes ont jou\u00e9 un r\u00f4le important. Apr\u00e8s 10 ans de crises politiques en Europe (crise de la zone euro, crise migratoire, Brexit, etc.), les questions europ\u00e9ennes ont commenc\u00e9 \u00e0 impacter les opinions publiques et \u00e0 impr\u00e9gner les d\u00e9bats politiques nationaux, notamment en France. Les nouveaux d\u00e9fis internationaux lanc\u00e9s aux Europ\u00e9ens (d\u00e9fis climatiques\/environnementaux, d\u00e9fis migratoires, d\u00e9fis de s\u00e9curit\u00e9 collective avec les politiques agressives de Poutine, Trump, Erdogan, mont\u00e9e en puissance de la Chine, etc.) ont \u00e9galement pu inciter les \u00e9lecteurs \u00e0 consid\u00e9rer l&rsquo;Union europ\u00e9enne comme l&rsquo;\u00e9chelon le plus pertinent pour agir dans le contexte mondial.<\/p>\n\n\n\n<p>Dans ce contexte, il n\u2019est gu\u00e8re \u00e9tonnant que les parlementaires europ\u00e9ens \u00e9lus en 2019 consid\u00e8rent qu\u2019ils b\u00e9n\u00e9ficient d\u2019une l\u00e9gitimit\u00e9 renforc\u00e9e, et qui doit leur permettre d\u2019\u00eatre mieux entendus, aussi bien au moment de la d\u00e9signation des gouvernants de l\u2019Union que par la suite. On peut donc pr\u00e9voir qu\u2019ils se montreront offensifs sur des th\u00e8mes qu\u2019ils jugent en phase avec les attentes de leurs \u00e9lecteurs (pr\u00e9servation de l\u2019environnement et du climat, protection des consommateurs et des donn\u00e9es, promotion de la mobilit\u00e9 et des \u00e9changes, etc.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Des \u00e9lections davantage centr\u00e9es sur des enjeux europ\u00e9ens<\/h4>\n\n\n\n<p>Si les \u00e9lections europ\u00e9ennes restent des \u00e9lections domestiques (o\u00f9 les facteurs nationaux et internes continuent de jouer un r\u00f4le important), il s\u2019est aussi agi cette fois-ci d\u2019\u00e9lections davantage <em>europ\u00e9ennes<\/em>, notamment marqu\u00e9es par une europ\u00e9anisation assez forte <a href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/05\/17\/les-mots-de-la-campagne\/\">des th\u00e8mes de campagne<\/a> (autour du climat, de  l\u2019immigration, des valeurs, de la s\u00e9curit\u00e9, etc.). Finalement, tout s\u2019est pass\u00e9 comme si la politique europ\u00e9enne s\u2019\u00e9tait invit\u00e9e dans l\u2019ar\u00e8ne politique nationale, ind\u00e9pendamment des dynamiques des campagnes \u00e9lectorales (particuli\u00e8rement tardives et atones en France).<\/p>\n\n\n\n<p>Cette europ\u00e9anisation a tout d\u2019abord d\u00e9coul\u00e9 de la polarisation du d\u00e9bat   incarn\u00e9e par l\u2019opposition mise en sc\u00e8ne entre les pro-europ\u00e9ens, dont   Emmanuel Macron a revendiqu\u00e9 le leadership et les leaders nationalistes   de droite de l\u2019autre (notamment Matt\u00e9o Salvini et Viktor Orban). Cette   opposition sch\u00e9matique entre pro et anti-europ\u00e9ens, et <em>in fine<\/em> sur l\u2019hypoth\u00e9tique d\u00e9sint\u00e9gration potentielle de \u00ab&#160;l\u2019Europe&#160;\u00bb, a confirm\u00e9 la victoire des premiers&#160;: les opinions politiques sont m\u00eame devenues plus favorables \u00e0 l\u2019appartenance \u00e0 l\u2019Union, y compris depuis le r\u00e9f\u00e9rendum britannique, et on ne trouve dans aucun pays europ\u00e9en une majorit\u00e9 europhobe d\u00e9sireuse de quitter l\u2019Union.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/GEG_Soutien-UE.png\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"5030\"\n        data-pswp-height=\"4449\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/GEG_Soutien-UE-330x292.png\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/GEG_Soutien-UE-690x610.png\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/GEG_Soutien-UE-1340x1185.png\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/GEG_Soutien-UE-125x111.png\" \/>\r\n        <\/picture>\r\n                            \n            <\/a>\n<\/figure>\n\n\n<p>Il semble que ces \u00e9lections europ\u00e9ennes se soient davantage caract\u00e9ris\u00e9es davantage par un d\u00e9bat sur l\u2019Europe que l\u2019on souhaite. Les th\u00e8mes-cl\u00e9s qui ont motiv\u00e9 les \u00e9lecteurs ont ainsi \u00e9t\u00e9 les suivants&#160;: le changement climatique, l\u2019immigration, la croissance \u00e9conomique, la d\u00e9mocratie et l\u2019avenir de l\u2019Union. Ils renvoient pour la plupart \u00e0 des enjeux qui exigent une r\u00e9ponse non seulement nationale mais aussi \u00e0 l\u2019\u00e9chelle de l\u2019Union en tant que niveau d\u2019action publique pertinent pour relever ces d\u00e9fis. C\u2019est sans doute l\u00e0 l\u2019une des raisons sous-jacentes de la hausse du taux de participation lors de ces \u00e9lections. En outre, il est frappant de constater que <a href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/07\/23\/il-ny-a-pas-de-coalition-europeenne\/\">des coalitions informelles<\/a> pourraient \u00eatre form\u00e9es au sein du nouveau Parlement europ\u00e9en entre des partis mod\u00e9r\u00e9s et des partis populistes sur des questions sp\u00e9cifiques. A titre d\u2019exemple, les partis appartenant au PPE et \u00e0 la droite populiste ont tendance \u00e0 soutenir des valeurs plus traditionnelles et conservatrices, contrairement \u00e0 l\u2019approche lib\u00e9rale sur le plan culturel des socio-d\u00e9mocrates, des verts et de la gauche radicale&#160;; ils pourraient ainsi former des majorit\u00e9s <em>ad hoc<\/em> l\u00e0 o\u00f9 leurs positions id\u00e9ologiques sont plus proches, en particulier sur des sujets tels que l&rsquo;immigration&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-53064' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/#easy-footnote-bottom-2-53064' title='Voir Thierry Chopin, Nicol\u00f2 Fraccaroli, Nils Hernborg, Jean-Francois Jamet&lt;strong&gt;,&lt;\/strong&gt; \u00ab&amp;#160;The Battle for Europe\u2019s Future&amp;#160;: Political cleavages and the balance of power ahead of the European Parliament elections&amp;#160;\u00bb, &lt;em&gt;Policy paper&lt;\/em&gt;, n\u00b0237, Jacques Delors Institute, April 24th 2019 Url&amp;#160;: &lt;a href=&quot;https:\/\/institutdelors.eu\/publications\/the-battle-for-europes-future-political-cleavages-and-the-balance-of-power-ahead-of-the-european-parliament-elections\/?lang=en&quot;&gt;https:\/\/institutdelors.eu\/publications\/the-battle-for-europes-future-political-cleavages-and-the-balance-of-power-ahead-of-the-european-parliament-elections\/?lang=en&lt;\/a&gt;'><sup>2<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Des \u00e9lections renfor\u00e7ant le pluralisme partisan<\/h4>\n\n\n\n<p>En troisi\u00e8me lieu, les \u00e9lections europ\u00e9ennes de mai 2019 ont \u00e9t\u00e9 marqu\u00e9es par un changement notable des rapports de force politiques au sein du Parlement europ\u00e9en (voir Graphique 2).<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-medium\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Chopin-graphe-2.png\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"943\"\n        data-pswp-height=\"908\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Chopin-graphe-2-330x318.png\"\r\n                media=\"(max-width:  374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Chopin-graphe-2-690x664.png\"\r\n                media=\"(max-width:  989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Chopin-graphe-2.png\"\r\n                media=\"(max-width: 1319px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Chopin-graphe-2-690x664.png\"\r\n                media=\"(max-width: 1599px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Chopin-graphe-2.png\"\r\n                media=\"(min-width: 1600px)\" \/>\r\n                <img decoding=\"async\" alt=\"Session constitutive PPE S&amp;D ECR Renew Europe GUE NGL Verts ALE ID NI\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Chopin-graphe-2-125x120.png\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Graphique 2 \u2022 Yves Bertoncini, Thierry Chopin pour le Grand Continent<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>Les deux principaux groupes politiques du Parlement europ\u00e9en (PPE et S&amp;D) y ont en effet perdu leur majorit\u00e9 absolue (ils ont d\u00e9sormais 45&#160;% des si\u00e8ges contre 55&#160;% entre 2014 et 2019) sur fond de pouss\u00e9e des Lib\u00e9raux et des Verts. La grande coalition PPE-S&amp;D qui a historiquement gouvern\u00e9 l\u2019Assembl\u00e9e de Strasbourg (\u00e0 l\u2019exception de la p\u00e9riode entre 1999-2004, o\u00f9 a \u00e9merg\u00e9 une coalition entre PPE et Lib\u00e9raux) <a href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/04\/29\/lallemagne-ingouvernable-lere-des-tres-grandes-coalitions\/\">doit d\u00e9sormais s\u2019\u00e9largir \u00e0 d\u2019autres partenaires<\/a>.<\/p>\n\n\n\n<p>Cette nouvelle donne politique peut \u00eatre analys\u00e9e de mani\u00e8re ambivalente&#160;: d\u2019un c\u00f4t\u00e9 comme une \u00ab&#160;fragmentation&#160;\u00bb qui conduira \u00e0 ce que les coalitions n\u00e9cessaires pour voter les d\u00e9cisions l\u00e9gislatives et budg\u00e9taires pendant les cinq ann\u00e9es de la l\u00e9gislature soient plus difficile \u00e0 b\u00e2tir&#160;;  de l\u2019autre comme une \u00ab&#160;respiration&#160;\u00bb, et donc un \u00e9l\u00e9ment positif du point de vue d\u2019une repr\u00e9sentation plus fid\u00e8le de la r\u00e9alit\u00e9 politique europ\u00e9enne et du pluralisme d\u00e9mocratique et partisan au sein de l\u2019Union. Dans ce nouveau contexte, le PPE et les sociaux-d\u00e9mocrates pourront b\u00e2tir une majorit\u00e9 arithm\u00e9tique avec les Lib\u00e9raux de Renew, mais aussi chercher \u00e0 s\u2019\u00e9largir aux Verts&#160;: <a href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/07\/23\/il-ny-a-pas-de-coalition-europeenne\/\">cette coalition informelle<\/a> \u00e0 4 serait \u00e0 la fois plus en phase avec les aspirations environnementalistes exprim\u00e9es par les citoyens de l\u2019Union et elle permettrait en outre au duo principal (PPE \/ S&amp;D) de ne pas d\u00e9pendre exclusivement de Renew pour la construction des majorit\u00e9s \u00e0 g\u00e9om\u00e9trie variable n\u00e9cessaires au Parlement europ\u00e9en.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Cette nouvelle donne politique peut \u00eatre analys\u00e9e de mani\u00e8re ambivalente&#160;: d\u2019un c\u00f4t\u00e9 comme une <em>fragmentation<\/em>,  de l\u2019autre comme une <em>respiration<\/em>.<\/p><cite>Yves Bertoncini, Thierry Chopin<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Enfin, concernant les partis eurosceptiques et europhobes, leur progression (de 20 \u00e0 25&#160;%) reste limit\u00e9e et ils sont toujours divis\u00e9s entre 3 groupes auxquels s\u2019ajoutent les non-inscrits. Les eurod\u00e9put\u00e9s eurosceptiques et europhobes n\u2019auront qu\u2019un faible impact institutionnel au Parlement europ\u00e9en (en raison de l\u2019absence de minorit\u00e9 de blocage) m\u00eame s\u2019il convient de souligner que <a href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/05\/14\/berlusconi-relance-sa-proposition-dune-alliance-ppe-extreme-droite-au-parlement-europeen\/\">des coalitions possibles entre eurosceptiques et PPE seront envisageables<\/a> sur certains votes (par exemple en mati\u00e8re d\u2019immigration). <\/p>\n\n\n\n<p>N\u00e9anmoins, l\u2019impact politique des chefs d\u2019Etat et de gouvernement eurosceptiques au Conseil europ\u00e9en peut \u00eatre plus important, et ce pour plusieurs raisons&#160;: les d\u00e9cisions strat\u00e9giques y sont plus souvent prises \u00e0 l\u2019unanimit\u00e9&#160;; en raison de l\u2019impact du discours eurosceptique sur le discours politique des partis mod\u00e9r\u00e9s (notamment en mati\u00e8re d\u2019immigration)&#160;; en raison enfin d\u2019un contexte international dans lequel ces forces politiques b\u00e9n\u00e9ficient de soutiens non europ\u00e9ens, comme Trump et Poutine par exemple.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Le triomphe de la <em>diplocratie<\/em> en Europe&#160;?<\/strong><\/h3>\n\n\n\n<p>Les tensions relatives \u00e0 la d\u00e9signation de la Pr\u00e9sidente, puis <a href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/09\/13\/une-commission-geopolitique-les-profils-de-la-commission-von-der-leyen-pt-1\/\">des membres de la Commission europ\u00e9enne<\/a>, ne sont pas in\u00e9dites compte tenu de la complexit\u00e9 d\u2019une n\u00e9gociation quinquennale incluant aussi l\u2019\u00e9lection des Pr\u00e9sidents du Conseil europ\u00e9en et du Parlement europ\u00e9en, la d\u00e9signation du Haut repr\u00e9sentant pour la politique \u00e9trang\u00e8re \u2013 et plus ponctuellement cette ann\u00e9e la d\u00e9signation de la nouvelle Pr\u00e9sidente de la Banque Centrale europ\u00e9enne. Ces tensions ont cependant donn\u00e9 lieu \u00e0 des rapports de force particuli\u00e8rement vifs, dont l\u2019issue a laiss\u00e9 des traces dommageables chez l\u2019ensemble des acteurs concern\u00e9s.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Un Rubik\u2019s Cube combinant dimensions partisane, diplomatique et personnelle<\/h4>\n\n\n\n<p>La d\u00e9signation du candidat id\u00e9al \u00e0 la Pr\u00e9sidence de la Commission bute  classiquement sur une difficult\u00e9 intrins\u00e8que, puisqu\u2019il s\u2019agit d\u2019une \u00e9quation \u00e0 plusieurs inconnues. Il s\u2019agit en effet de prendre en compte l&rsquo;appartenance partisane, l&rsquo;origine nationale et le profil personnel du ou de la futur(e) \u00e9lu(e). Le choix de l\u2019int\u00e9ress\u00e9(e) est d\u2019autant plus engageant qu\u2019il fait partie d\u2019un paquet de nominations \u00e9galement soumises \u00e0 cette recherche d\u2019\u00e9quilibres multifactoriels, et qu\u2019il peut en partie pr\u00e9juger du choix des laur\u00e9ats aux autres fonctions. D\u00e9signer un(e) Allemand(e) \u00e0 la pr\u00e9sidence de la Commission emp\u00eache par exemple <em>de facto<\/em> d\u2019en voir un(e) autre \u00e0 la pr\u00e9sidence de la BCE.<\/p>\n\n\n\n<p>Ce rapport de force se joue donc dans un cadre complexe, o\u00f9 il faut r\u00e9ussir \u00e0 trouver une place pour tous en respectant les grands \u00e9quilibres partisans, diplomatiques, g\u00e9ographiques (entre pays du Sud, du Nord, de l\u2019Est, et de l\u2019Ouest ou encore entre petits pays, moyens pays et grands pays). On doit \u00e9videmment s\u2019efforcer de choisir des personnalit\u00e9s expertes et comp\u00e9tentes, et il convient aussi d&rsquo;essayer de respecter le principe d\u2019\u00e9galit\u00e9 homme\/femme. Chaque Etat ou parti place donc ses \u00ab&#160;pions&#160;\u00bb \u00e0 plusieurs postes pour peser sur les termes de l&rsquo;\u00e9quation finale. C\u2019est d\u2019ailleurs aussi pour cela que le syst\u00e8me des <em>Spitzenkandidaten<\/em> (chefs de file) est mal vu et accept\u00e9 par nombre de chefs d&rsquo;Etat et de gouvernement&#160;: il est per\u00e7u comme une contrainte suppl\u00e9mentaire, qui leur ferme certaines options pour les autres postes eux-aussi convoit\u00e9s. <\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Un triple rapport de force interinstitutionnel, partisan et diplomatique<\/h4>\n\n\n\n<p>La nomination de la nouvelle Pr\u00e9sidente de la Commission a proc\u00e9d\u00e9 classiquement d\u2019un triple rapport de force&#160;: un rapport de force institutionnel, un rapport de force partisan et un rapport de force diplomatique.<\/p>\n\n\n\n<p>Le rapport de force institutionnel entre Conseil europ\u00e9en et Parlement europ\u00e9en a \u00e9t\u00e9 d\u2019autant plus vif qu\u2019il a port\u00e9 \u00e0 la fois sur le nom du ou de la rempla\u00e7ant(e) de Jean-Claude Juncker mais aussi sur les r\u00e8gles du jeu \u00e0 appliquer \u00e0 sa d\u00e9signation. 2014 a vu l\u2019apparition d\u2019un syst\u00e8me des <em>Spitzenkandidaten<\/em>, sur la base d\u2019une interpr\u00e9tation offensive du Trait\u00e9 de Lisbonne par les partis politiques, et qui a fonctionn\u00e9 avec l&rsquo;accord de tous&#160;: le chef de file du parti arriv\u00e9 en t\u00eate, en l\u2019occurrence Jean-Claude Juncker pour le PPE, avait donc pris la t\u00eate de la Commission de mani\u00e8re plut\u00f4t consensuelle. Ce syst\u00e8me des \u00ab&#160;Spitzenkanditen&#160;\u00bb a cette fois \u00e9t\u00e9 remis en cause&#160;: si Angela Merkel l\u2019a par exemple soutenu, Emmanuel Macron et une dizaine d\u2019autres chefs de gouvernement l\u2019ont contest\u00e9. Cette opposition a traduit un conflit politique&#160;: fallait-il faire pr\u00e9valoir une l\u00e9gitimit\u00e9 parlementaire et donc civique (une logique de type \u00ab&#160;Westminster&#160;\u00bb), d\u00e8s lors que ces <em>Spitzenkandidaten<\/em> se sont pr\u00e9sent\u00e9s au suffrage des \u00e9lecteurs&#160;? Ou fallait-il faire pr\u00e9valoir une logique plus diplomatique (une logique \u00ab&#160;Westpahlienne&#160;\u00bb), et donc une solution qui doit survenir \u00e0 l\u2019\u00e9chelon des Etats, c&rsquo;est-\u00e0-dire des chefs d&rsquo;Etat et de gouvernement, qui ont toujours eu la main avant 2014. Ce rapport de force institutionnel a d\u00e9bouch\u00e9 sur un arbitrage sous-optimal en termes de clart\u00e9 d\u00e9mocratique &#8211; le syst\u00e8me des \u00ab&#160;Spitzenkanidaten&#160;\u00bb \u00e9tant clairement pr\u00e9f\u00e9rable \u00e0 cet \u00e9gard (voir \u00a7 2.1). <\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La nomination de la nouvelle Pr\u00e9sidente de la Commission a proc\u00e9d\u00e9 classiquement d\u2019un triple rapport de force&#160;: un rapport de force institutionnel, un rapport de force partisan et un rapport de force diplomatique.<\/p><cite>Yves Bertoncini, Thierry Chopin<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Les traditionnels rapports de force partisans sont par ailleurs devenus plus incertains \u00e0 l\u2019\u00e9t\u00e9 2019, au Conseil europ\u00e9en&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-53064' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/#easy-footnote-bottom-3-53064' title='A l\u2019automne 2019, le  Conseil europ\u00e9en accueille 10 membres du PPE, 7 membres du PSE, 7 membres de la famille lib\u00e9rale-d\u00e9mocrate, 1 eurosceptique (Pologne) et  deux ind\u00e9pendants (Italie et Lituanie) \u2014 cette composition \u00e9tant appel\u00e9e  \u00e0 \u00e9voluer au fil des \u00e9lections  nationales tout au long de la p\u00e9riode  2019-2024.'><sup>3<\/sup><\/a><\/span><\/span> comme au Parlement europ\u00e9en. Le PPE a certes \u00e0 nouveau gagn\u00e9 les \u00e9lections europ\u00e9ennes, sortant en t\u00eate dans 15 des 28 pays de l\u2019UE et disposant d\u2019un total de 182 si\u00e8ges au Parlement europ\u00e9en, mais il est en recul par rapport \u00e0 la p\u00e9riode 2014-2019 (voir Graphique 2). Les sociaux-d\u00e9mocrates sont aussi en baisse mais sont assez nettement deuxi\u00e8mes, avec 154 si\u00e8ges. Enfin, les lib\u00e9raux d\u00e9mocrates de Renew ont vu leur influence progresser et passer la barre des 100 d\u00e9put\u00e9s (108), avec l&rsquo;apport des Britanniques (voir Tableau 1). Ils font valoir leur r\u00f4le de pivot dans le Parlement europ\u00e9en, sachant que le PPE ne peut parvenir seul \u00e0 le \u00ab&#160;gouverner&#160;\u00bb, aujourd&rsquo;hui comme hier. Il s\u2019agit donc pour Renew de d\u00e9fendre un \u00e9largissement de la coalition PPE-S&amp;D, ainsi que l\u2019id\u00e9e qu\u2019il n\u2019\u00e9tait pas n\u00e9cessairement logique que ce soit le PPE qui pr\u00e9side la Commission. Les Verts peuvent quant \u00e0 eux pr\u00e9tendre \u00e0 un r\u00f4le d\u2019appoint alternatif, en faisant valoir qu\u2019ils sont port\u00e9s par une dynamique civique autant qu\u2019\u00e9lectorale. <\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-medium\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/chopin3.png\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"917\"\n        data-pswp-height=\"405\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/chopin3-330x146.png\"\r\n                media=\"(max-width:  374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/chopin3-690x305.png\"\r\n                media=\"(max-width:  989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/chopin3.png\"\r\n                media=\"(max-width: 1319px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/chopin3-690x305.png\"\r\n                media=\"(max-width: 1599px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/chopin3.png\"\r\n                media=\"(min-width: 1600px)\" \/>\r\n                <img decoding=\"async\" alt=\"Composition du Parlement europ\u00e9en 2019 avant et apr\u00e8s le Brexit\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/chopin3-125x55.png\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Tableau 1 \u2022 Source&#160;&#160;: Chopin, T. et alii, \u00ab&#160;&#160;The European Parliament after Brexit&#160;&#160;: What would it look like&#160;&#160;\u00bb, BlogBrexit, London School of Economics, June 5th 2019<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>Le rapport de force partisan s\u2019est superpos\u00e9 \u00e0 un rapport de force diplomatique et personnel entre Emmanuel Macron et Angela Merkel, dans le cadre d\u2019une \u00e9quation plus large. Les pays du Sud, notamment les Espagnols, ont refus\u00e9 la d\u00e9signation de <a href=\"https:\/\/legrandcontinent.eu\/fr\/2018\/09\/02\/manfred-weber-tisse-sa-toile\/\">Manfred Weber<\/a>, parce qu\u2019il est CSU et peut-\u00eatre parce qu\u2019il est Allemand. Le pr\u00e9sident fran\u00e7ais l\u2019a \u00e9galement rejet\u00e9, non pas seulement en r\u00e9cusant le profil de l\u2019int\u00e9ress\u00e9 mais aussi en contestant la l\u00e9gitimit\u00e9 du syst\u00e8me des candidats chefs de file (ou <em>Spitzenkandidaten<\/em>). Angela Merkel l\u2019a d\u00e9fendu, \u00e0 la fois parce qu\u2019il pouvait permettre \u00e0 un compatriote d\u2019obtenir la pr\u00e9sidence de la Commission et parce qu\u2019il \u00e9tait issu de la CSU, parti \u00ab&#160;cousin&#160;\u00bb de la CDU. Le groupe de Visegrad a lui aussi jou\u00e9 sa carte&#160;: ses 4 pays membres n\u2019ont pas voulu que <a href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/10\/08\/green-new-deal-quatre-questions-a-frans-timmermans\/\">Frans Timmermans<\/a> soit Pr\u00e9sident de la Commission car il a \u00e9t\u00e9 en premi\u00e8re ligne dans la d\u00e9fense de l\u2019Etat de droit en Hongrie et en Pologne en tant que Vice-Pr\u00e9sident de la Commission sortante.<\/p>\n\n\n\n<p>Au total, outre le d\u00e9saccord sur les r\u00e8gles du jeu, la discordance des rapports de force institutionnels, partisans et diplomatiques a fortement compliqu\u00e9 le processus de d\u00e9signation des gouvernants de l\u2019UE pour le cycle 2019-2024 \u2013 aucune force partisane et aucune alliance diplomatique n\u2019\u00e9tant clairement dominante au Conseil europ\u00e9en et au Parlement europ\u00e9en. Le fait que le Pr\u00e9sident fran\u00e7ais ait voulu exercer un r\u00f4le de leadership diplomatique alors qu\u2019il n\u2019est qu\u2019un \u00ab&#160;junior partner&#160;\u00bb sur le plan partisan a aussi contribu\u00e9 \u00e0 tendre les relations entre les principaux d\u00e9cideurs&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-53064' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/#easy-footnote-bottom-4-53064' title='Pour de plus amples d\u00e9veloppements sur ce registre, voir Yves Bertoncini et Thierry Chopin \u00ab&amp;#160;Macron l&amp;rsquo;Europ\u00e9en&amp;#160;: de l&amp;rsquo;hymne \u00e0 la joie \u00e0 l&amp;#8217;embarras des choix&amp;#160;\u00bb Le d\u00e9bat\/Gallimard Janvier 2020.'><sup>4<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>Dans ce contexte, les chefs d\u2019Etat et de gouvernement ont eu besoin de deux r\u00e9unions au sommet pour accoucher dans la douleur d\u2019un <em>casting<\/em> respectant peu ou prou les nouveaux \u00e9quilibres partisans \u00e9tablis au printemps 2019 (avec 2 PPE, 2 S&amp;D et 1 Lib\u00e9ral-d\u00e9mocrate), tout en s\u2019effor\u00e7ant de distribuer les postes \u00e0 des nationaux issus de pays de taille diff\u00e9rente (voir Tableau 2). C\u2019est du point de vue diplomatico-g\u00e9ographique que ce casting appara\u00eet peu \u00e9quilibr\u00e9, puisqu\u2019aucun ressortissant d\u2019Europe centrale ou d\u2019Europe nordique n\u2019en fait partie \u2013 alors qu\u2019il a \u00e9t\u00e9 soulign\u00e9 qu\u2019avait davantage \u00e9t\u00e9 pris en compte l\u2019objectif de parit\u00e9 femme-homme. On retrouve ici l\u2019 \u00ab&#160;<a href=\"https:\/\/legrandcontinent.eu\/fr\/2017\/09\/30\/denis-crouzet-historiens-europe\/\">Europe carolingienne<\/a>&#160;\u00bb du c\u0153ur historique de l\u2019Europe communautaire des pays fondateurs (avec l\u2019appoint de l\u2019Espagne).<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Capture-d\u2019e\u0301cran-2019-11-20-a\u0300-06.19.44.png\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"1772\"\n        data-pswp-height=\"552\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Capture-d\u2019e\u0301cran-2019-11-20-a\u0300-06.19.44-330x103.png\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Capture-d\u2019e\u0301cran-2019-11-20-a\u0300-06.19.44-690x215.png\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Capture-d\u2019e\u0301cran-2019-11-20-a\u0300-06.19.44-1340x417.png\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" alt=\"comment les grands pays et les petits pays se repartissent les top jobs\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Capture-d\u2019e\u0301cran-2019-11-20-a\u0300-06.19.44-125x39.png\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Tableau 2 \u2022 Le casting des \u00ab&#160;&#160;tops jobs&#160;&#160;\u00bb europ\u00e9ens 2019&#160;&#160;: \u00e9quilibres partisans et diplomatiques<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<h3 class=\"wp-block-heading\"><strong>Une pr\u00e9sidente de la Commission affaiblie&#160;?<\/strong><\/h3>\n\n\n\n<p>La combinaison des rapports de force interinstitutionnels, partisans et  diplomatiques qui se sont exprim\u00e9s \u00e0 l\u2019\u00e9t\u00e9 2019 a pes\u00e9 sur les processus  d\u2019audition et de confirmation d\u2019<a href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/07\/09\/ursula-von-der-leyen-un-portrait\/\">Ursula Von Der Leyen<\/a> et des membres de son \u00e9quipe, au point d\u2019affaiblir la nouvelle Pr\u00e9sidente de la Commission.<\/p>\n\n\n\n<p>Le choix-surprise d\u2019Ursula Von Der Leyen, apr\u00e8s un premier Conseil  europ\u00e9en infructueux, place tout d\u2019abord cette derni\u00e8re dans une position institutionnelle<em> a priori<\/em> moins forte que celle de Jean-Claude Juncker&#160;: d\u2019une part parce que, \u00e0 l\u2019inverse de son pr\u00e9d\u00e9cesseur, elle n\u2019a pas \u00e9t\u00e9 chef de gouvernement et donc intronis\u00e9e par ses ex-pairs du Conseil europ\u00e9en, dont elle conna\u00eet peu les membres&#160;; d\u2019autre part parce qu\u2019elle n\u2019a pas \u00e9t\u00e9 d\u00e9sign\u00e9e sur la base de la  proc\u00e9dure des <em>Spitzenkandidaten<\/em>, promue et reconnue par le Parlement europ\u00e9en, ce qui lui aurait donn\u00e9 une l\u00e9gitimit\u00e9 accrue, y compris  vis-\u00e0-vis du Conseil europ\u00e9en.<\/p>\n\n\n\n<p>L\u2019\u00e9lection \u00e9triqu\u00e9e d\u2019Ursula Von Der Leyen par le Parlement europ\u00e9en traduit \u00e9galement <a href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/07\/23\/il-ny-a-pas-de-coalition-europeenne\/\">la fragilit\u00e9 de son assise partisane<\/a>. Apr\u00e8s une premi\u00e8re audition jug\u00e9e globalement peu convaincante par les parlementaires, Ursula Von Der Leyen n\u2019a en effet \u00e9t\u00e9 \u00e9lue qu\u2019\u00e0 9 voix pr\u00e8s, soit 385 voix (contre 422 voix pour Jean-Claude Juncker en 2014). Surtout, elle doit sa courte \u00e9lection \u00e0 l\u2019apport de voix eurosceptiques (parlementaires hongrois du PPE, polonais du PIS, italiens \u00ab&#160;5 \u00e9toiles&#160;\u00bb notamment) et elle a, \u00e0 ce stade, \u00e9chou\u00e9 \u00e0 convaincre nombre des membres potentiels de sa majorit\u00e9 \u00ab&#160;mainstream&#160;\u00bb (puisque PPE, S&amp;D et Renew comptent 444 voix \u00e0 eux trois, auxquelles pourraient s\u2019ajouter celles des 74 Verts).<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-medium\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/07\/Graphique.png\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"946\"\n        data-pswp-height=\"606\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/07\/Graphique-330x211.png\"\r\n                media=\"(max-width:  374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/07\/Graphique-690x442.png\"\r\n                media=\"(max-width:  989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/07\/Graphique.png\"\r\n                media=\"(max-width: 1319px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/07\/Graphique-690x442.png\"\r\n                media=\"(max-width: 1599px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/07\/Graphique.png\"\r\n                media=\"(min-width: 1600px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/07\/Graphique-125x80.png\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Graphique 3 \u2022 Fran\u00e7ois Hublet pour le Grand Continent<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>La l\u00e9gitimit\u00e9 diplomatique d\u2019Ursula Von Der Leyen peut \u00e9galement \u00eatre sujette \u00e0 questionnement&#160;: fait in\u00e9dit, elle a en effet \u00e9t\u00e9 d\u00e9sign\u00e9e par le Conseil europ\u00e9en sans l\u2019approbation formelle de son chef de gouvernement (Angela Merkel s\u2019\u00e9tant abstenue pour des raisons de politique int\u00e9rieure&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-53064' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/#easy-footnote-bottom-5-53064' title='Angela Merkel n\u2019a pas souhait\u00e9 froisser ses partenaires de coalition, la CSU qui soutenait Manfred Weber et le SPD qui soutenait Franz   Timmermans.'><sup>5<\/sup><\/a><\/span><\/span>)&#160;; elle a ensuite \u00e9t\u00e9 frontalement mise en cause par celui qui s\u2019\u00e9tait pr\u00e9sent\u00e9 comme son \u00ab&#160;parrain&#160;\u00bb au moment de la r\u00e9vocation parlementaire de Sylvie Goulard, puisqu\u2019Emmanuel Macron a sembl\u00e9 douter de sa capacit\u00e9 \u00e0 tenir ses engagements&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-53064' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/#easy-footnote-bottom-6-53064' title='Apr\u00e8s le rejet parlementaire de Sylvie Goulard, Emmanuel Macron a notamment d\u00e9clar\u00e9&amp;#160;: \u00ab&amp;#160;Je ne comprends pas comment, quand la Pr\u00e9sidente de la Commission nomm\u00e9e, a une discussion avec les trois pr\u00e9sidents de groupe, et qu&amp;rsquo;ils se mettent d&amp;rsquo;accord sur quelque chose, \u00e7a peut bouger comme \u00e7a&amp;#160;\u00bb.'><sup>6<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p><em>Last but not least<\/em> et fait sans pr\u00e9c\u00e9dent, deux nouvelles \u00ab&#160;vice-pr\u00e9sidences ex\u00e9cutives&#160;\u00bb de la Commission ont \u00e9t\u00e9 impos\u00e9es par le Conseil europ\u00e9en \u00e0 Ursula Von Der Leyen, et confi\u00e9es \u00e0 Margaret Vestager et <a href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/10\/08\/green-new-deal-quatre-questions-a-frans-timmermans\/\">Frans Timmermans<\/a>, candidats chefs de file aux \u00e9lections europ\u00e9ennes de mai 2019&#160;; ce \u00ab&#160;triumvirat&#160;\u00bb a \u00e9t\u00e9 compl\u00e9t\u00e9 par la nomination de Valdis Dombrovskis comme 3\u00e8me Vice-Pr\u00e9sident ex\u00e9cutif, \u00e0 l\u2019initiative de la nouvelle Pr\u00e9sidente. Il reste \u00e0 confirmer que cette organisation hi\u00e9rarchique de la Commission permettra \u00e0 sa Pr\u00e9sidente d\u2019exercer la pl\u00e9nitude de son autorit\u00e9 et \u00e0 son Coll\u00e8ge d\u2019\u00eatre aussi coh\u00e9rent et proactif que n\u00e9cessaire, y compris pour s\u2019affirmer vis-\u00e0-vis du Conseil et du Parlement europ\u00e9ens.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Fait in\u00e9dit, la Pr\u00e9sidente de la Commission a en effet \u00e9t\u00e9 d\u00e9sign\u00e9e par le Conseil europ\u00e9en sans l\u2019approbation formelle de son chef de gouvernement.<\/p><cite>Yves Bertoncini, Thierry Chopin<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Dans ce contexte, la r\u00e9vocation de trois commissaires d\u00e9sign\u00e9s par les Etats membres et Ursula Von Der Leyen est elle aussi r\u00e9v\u00e9latrice des difficult\u00e9s qu\u2019elle aura \u00e0 affronter. Deux d\u2019entre eux ont \u00e9t\u00e9 r\u00e9cus\u00e9s par la commission juridique du Parlement europ\u00e9en au motif de \u00ab&#160;conflits d\u2019int\u00e9r\u00eats&#160;\u00bb&#160;: ils avaient \u00e9t\u00e9 d\u00e9sign\u00e9s par la Hongrie et la Roumanie et appartenaient aux groupes politiques PPE et S&amp;D. Affili\u00e9e au groupe \u00ab&#160;Renew&#160;\u00bb, la candidate d\u00e9sign\u00e9e par la France a quant \u00e0 elle \u00e9t\u00e9 r\u00e9cus\u00e9e sur la base d\u2019objections \u00e9thiques li\u00e9es \u00e0 l\u2019emploi pr\u00e9sum\u00e9 fictif d\u2019un assistant au Parlement europ\u00e9en et \u00e0 sa r\u00e9mun\u00e9ration substantielle par un Think-Tank am\u00e9ricain. Il est de fait apparu difficile de convaincre les parlementaires europ\u00e9ens que Sylvie Goulard pouvait \u00eatre Commissaire europ\u00e9en alors qu\u2019elle ne pouvait pas \u00eatre Ministre dans son pays. Mais le rejet d\u2019un double standard plus s\u00e9v\u00e8re pour les candidats d\u2019Europe centrale a \u00e9galement pes\u00e9 dans sa r\u00e9vocation, de m\u00eame que la volont\u00e9 d\u2019infliger un revers \u00e0 une membre du groupe \u00ab&#160;Renew&#160;\u00bb et, \u00e0 travers elle, \u00e0 son mentor Emmanuel Macron, qui a reni\u00e9 par principe le syst\u00e8me des <em>Spitzenkandidaten<\/em> et a pr\u00e9f\u00e9r\u00e9 humilier publiquement Manfred Weber plut\u00f4t que de lui laisser tenter sa chance.<\/p>\n\n\n\n<p>Si l\u2019entr\u00e9e en fonction de la Commission von der Leyen n\u2019a pu avoir lieu \u00e0 la date pr\u00e9vue, elle se mettra en place sur la place d\u2019\u00e9quilibres partisans et diplomatiques savamment dos\u00e9s (voir Graphique 4) et qui traduisent une forme de r\u00e9\u00e9quilibrage politique vers le centre au regard de la Commission Juncker et, plus encore, des Commissions Barroso.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-medium\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Capture-d\u2019\u00e9cran-2019-11-27-\u00e0-13.36.23.png\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"1718\"\n        data-pswp-height=\"1390\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Capture-d\u2019\u00e9cran-2019-11-27-\u00e0-13.36.23-330x267.png\"\r\n                media=\"(max-width:  374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Capture-d\u2019\u00e9cran-2019-11-27-\u00e0-13.36.23-690x558.png\"\r\n                media=\"(max-width:  989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Capture-d\u2019\u00e9cran-2019-11-27-\u00e0-13.36.23-990x801.png\"\r\n                media=\"(max-width: 1319px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Capture-d\u2019\u00e9cran-2019-11-27-\u00e0-13.36.23-690x558.png\"\r\n                media=\"(max-width: 1599px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Capture-d\u2019\u00e9cran-2019-11-27-\u00e0-13.36.23-990x801.png\"\r\n                media=\"(min-width: 1600px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Capture-d\u2019\u00e9cran-2019-11-27-\u00e0-13.36.23-125x101.png\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Graphique 4 \u2022 Le Grand Continent<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<h2 class=\"wp-block-heading\"><strong>R\u00e9-concilier l\u00e9gitimit\u00e9s \u00e9tatique et civique afin de conforter les gouvernants de l\u2019U<\/strong>nion<\/h2>\n\n\n\n<p>Il convient de tirer toutes les le\u00e7ons de la s\u00e9quence des nominations europ\u00e9ennes de l\u2019ann\u00e9e 2019 afin de consolider le processus de d\u00e9signation des gouvernants de l\u2019UE, en combinant de mani\u00e8re plus harmonieuse les deux fondements de leur l\u00e9gitimit\u00e9, \u00e0 savoir les Etats et les citoyens&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-7-53064' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/#easy-footnote-bottom-7-53064' title='Yves Bertoncini (dir.) \u00ab&amp;#160;L\u2019UE en notre nom. Renforcer l\u2019ancrage d\u00e9mocratique de nos repr\u00e9sentants europ\u00e9ens&amp;#160;\u00bb, Rapport, TerraNova, mai  2019&lt;a href=&quot;http:\/\/tnova.fr\/rapports\/l-europe-en-notre-nom-renforcer-la-democratie-europeenne&quot;&gt; http:\/\/tnova.fr\/rapports\/l-europe-en-notre-nom-renforcer-la-democratie-europeenne&lt;\/a&gt;'><sup>7<\/sup><\/a><\/span><\/span>. Cette consolidation pourra notamment \u00eatre act\u00e9e \u00e0 la faveur de la \u00ab&#160;Conf\u00e9rence&#160;\u00bb qui se r\u00e9unira \u00e0 partir du printemps 2020, pour autant que ses promoteurs respectent deux conditions politiques pr\u00e9alables.<\/p>\n\n\n\n<p>D\u2019une part, il convient de ne pas opposer d\u00e9mocratie et <em>diplocratie<\/em>, d\u00e8s lors que les chefs d\u2019Etat et de gouvernement sont \u00e9videmment eux aussi porteurs d\u2019une l\u00e9gitimit\u00e9 d\u00e9mocratique forte&#160;; cette opposition serait d\u2019autant plus st\u00e9rile que les chefs d\u2019Etat et de gouvernement jouissent en outre d\u2019une grande proximit\u00e9 et visibilit\u00e9 civiques compte tenu des pouvoirs qu\u2019ils exercent et de leur mode d\u2019\u00e9lection alors que les parlementaires europ\u00e9ens sont confront\u00e9s aux limites de la subsidiarit\u00e9 et \u00e0 un d\u00e9ficit d\u2019ancrage \u00e9lectoral.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Les nouveaux d\u00e9fis internationaux lanc\u00e9s aux Europ\u00e9ens ont \u00e9galement pu inciter les \u00e9lecteurs \u00e0 consid\u00e9rer l&rsquo;Union europ\u00e9enne comme l&rsquo;\u00e9chelon le plus pertinent pour agir dans le contexte mondial.<\/p><cite>Yves Bertoncini, Thierry Chopin<\/cite><\/blockquote><\/figure>\n\n\n\n<p>D\u2019autre part il faudrait s\u2019efforcer d\u2019arriver \u00e0 un point d\u2019\u00e9quilibre entre les l\u00e9gitimit\u00e9s \u00e9tatique et civique, c\u2019est-\u00e0-dire pousser \u00e0 son terme le processus d\u2019affirmation de la l\u00e9gitimit\u00e9 civique des gouvernants de l\u2019Union, via plusieurs r\u00e9formes et ajustements compl\u00e9mentaires portant respectivement sur le syst\u00e8me des <em>Spitzenkandidaten<\/em>, la nomination des membres de la Commission europ\u00e9enne et le mode d\u2019\u00e9lection des parlementaires europ\u00e9ens&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-8-53064' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/#easy-footnote-bottom-8-53064' title='Les propositions d\u00e9velopp\u00e9es ci-apr\u00e8s sont pour l\u2019essentiel issues du Rapport \u00ab&amp;#160;L\u2019UE en notre nom. Renforcer l\u2019ancrage d\u00e9mocratique de nos   repr\u00e9sentants europ\u00e9ens&amp;#160;\u00bb, TerraNova, mai 2019, op.cit.'><sup>8<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Conforter le syst\u00e8me des <em>Spitzenkandidaten<\/em> pour \u00e9lire le Pr\u00e9sident de la Commission<\/strong><\/h3>\n\n\n\n<p>Le pr\u00e9sident de la Commission a vocation \u00e0 \u00eatre le leader d\u2019une majorit\u00e9 parlementaire et le repr\u00e9sentant (d\u00e9sign\u00e9 \u00e0 l\u2019avance) du groupe politique ayant obtenu le plus grand nombre de si\u00e8ges au Parlement europ\u00e9en lors des \u00e9lections europ\u00e9ennes. Il est loisible d\u2019estimer que ce constat d\u00e9coule d\u2019une interpr\u00e9tation offensive de l\u2019article 17.7 du Trait\u00e9 sur l\u2019Union europ\u00e9enne, qui semblait s\u2019\u00eatre impos\u00e9e avec l\u2019\u00e9lection de Jean-Claude Juncker en 2014 mais a \u00e9t\u00e9 mise en cause par le Conseil europ\u00e9en \u00e0 l\u2019issue des \u00e9lections europ\u00e9ennes de 2019. Une fois n\u2019\u00e9tant pas coutume, il est essentiel de souligner que cette simple pratique est pr\u00e9f\u00e9rable en termes de l\u00e9gitimit\u00e9 comme d\u2019efficacit\u00e9.<\/p>\n\n\n\n<p>D&rsquo;abord on peut d\u00e9sormais d\u00e9montrer comment la mise en \u0153uvre du syst\u00e8me des <em>Spitzenkandidaten<\/em> ainsi que l\u2019am\u00e9lioration des modalit\u00e9s de sa mise en \u0153uvre, afin de favoriser son appropriation par les \u00e9lecteurs europ\u00e9ens, constitue un \u00e9l\u00e9ment clef de tout agenda visant \u00e0 r\u00e9\u00e9quilibrer les logiques diplocratique et civique pour le choix du\/de la Pr\u00e9sident(e) de la Commission.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Il faut parvenir \u00e0 ancrer le syst\u00e8me des <em>Spitzenkandidaten<\/em> dans la r\u00e9alit\u00e9 politique de l\u2019Union.<\/p><cite>Yves Bertoncini, Thierry Chopin<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Mais c\u2019est aussi pour des raisons d\u2019efficacit\u00e9 qu\u2019il faut parvenir \u00e0 ancrer le syst\u00e8me des <em>Spitzenkandidaten<\/em> dans la r\u00e9alit\u00e9 politique de l\u2019Union, apr\u00e8s les difficult\u00e9s survenues suite \u00e0 l\u2019\u00e9lection surprise d\u2019Ursula von der Leyen&#160;: c\u2019est en effet parce que sa ou son successeur aura pris ses fonctions apr\u00e8s avoir fait campagne aupr\u00e8s des Europ\u00e9ens et r\u00e9uni une double majorit\u00e9 au Conseil et au Parlement europ\u00e9ens qu\u2019il pourra b\u00e9n\u00e9ficier de la force politique n\u00e9cessaire pour pr\u00e9sider la Commission et dynamiser l\u2019Union.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Privil\u00e9gier les choix sous contr\u00f4le citoyen plut\u00f4t que les tractations \u00e0 huis clos entre Etats<\/h4>\n\n\n\n<p>Conforter le syst\u00e8me des <em>Spitzenkandidaten<\/em> constitue un moyen de renforcer l\u2019ancrage civique de l\u2019\u00e9lection du\/de la Pr\u00e9sident(e) de la Commission, qui acc\u00e9dera \u00e0 son poste apr\u00e8s avoir fait campagne et avoir soumis son programme aux \u00e9lecteurs de l\u2019Union. Ce qui est r\u00e9gressif du point de vue d\u00e9mocratique est d\u2019en rester aux tractations vaticanesques en vigueur au Conseil europ\u00e9en, et qui sont d\u2019autant moins claires qu\u2019elles incluent aussi d\u2019autres nominations europ\u00e9ennes. Il est bien s\u00fbr logique que l\u2019ensemble de ces nominations respecte les \u00e9quilibres politiques de l\u2019Union, en termes de rapports de force entre partis, d\u2019\u00e9quilibres g\u00e9ographiques ou d\u00e9mographiques, d\u2019\u00e9quilibre femme-homme, etc., mais rien n\u2019emp\u00eache qu\u2019elles aient lieu comme en 2014 apr\u00e8s que le\/la Pr\u00e9sident(e) de la Commission europ\u00e9enne aura \u00e9t\u00e9 d\u00e9sign\u00e9(e) sur la base du syst\u00e8me des <em>Spitzenkandidaten<\/em>.<\/p>\n\n\n\n<p>Les objections oppos\u00e9es aux <em>Spitzenkandidaten<\/em> par certains chefs d\u2019Etat et de gouvernement ou observateurs sont de fait doublement \u00e9tonnantes.<\/p>\n\n\n\n<p>D\u2019une part parce ce syst\u00e8me n\u2019a pas pour effet m\u00e9canique de garantir que la Pr\u00e9sidence de la Commission soit d\u00e9volue au PPE&#160;: l\u2019arriv\u00e9e en t\u00eate du PPE n\u2019a rien d\u2019automatique, mais traduit simplement une pr\u00e9f\u00e9rence manifest\u00e9e par les \u00e9lecteurs dans les urnes, qui peut tout \u00e0 fait dispara\u00eetre \u00e0 court ou moyen termes, et qui doit sinon \u00eatre reconnue d\u00e9mocratiquement.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"\"\n        data-pswp-height=\"\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img \/>\r\n        <\/picture>\r\n                            \n            <\/a>\n<\/figure>\n\n\n<p>D\u2019autre part et surtout parce que le syst\u00e8me des <em>Spitzenkandidaten<\/em> pr\u00e9voit seulement que le leader du parti arriv\u00e9 en t\u00eate soit charg\u00e9 d\u2019essayer de former une coalition majoritaire susceptible de l\u2019investir comme Pr\u00e9sident de la Commission, puis d\u2019investir les membres de son Coll\u00e8ge. Comme dans tout syst\u00e8me parlementaire, rien n\u2019interdit donc aux groupes politiques arriv\u00e9s en 2\u00e8me, 3\u00e8me et 4\u00e8me positions de refuser de conclure un accord de coalition avec celui qui est arriv\u00e9 en t\u00eate et de tenter de former \u00e0 leur tour une majorit\u00e9 alternative&#160;: en cas de premier \u00e9chec, il revient au chef de file du groupe politique arriv\u00e9 second de tenter \u00e0 son tour de former une telle coalition majoritaire, etc.<\/p>\n\n\n\n<p>Dans ce contexte, il importe de rappeler qu\u2019il est plus que probable que Manfred Weber aurait \u00e9chou\u00e9 \u00e0 constituer une telle coalition sur son nom et sur son programme \u00e0 l\u2019\u00e9t\u00e9 2019&#160;: d\u2019une part en raison de son positionnement politique p\u00e9riph\u00e9rique (CSU) au regard des nouveaux rapports de force partisans, d\u2019autre part au regard de son d\u00e9ficit d\u2019exp\u00e9rience ex\u00e9cutive \u2013 et ce d\u2019autant plus qu\u2019il lui aurait fallu r\u00e9unir une majorit\u00e9 \u00e0 la fois au Parlement europ\u00e9en et au Conseil europ\u00e9en. Il aurait donc beaucoup mieux valu le laisser tenter sa chance, puis <a href=\"https:\/\/legrandcontinent.eu\/fr\/2018\/11\/11\/weber-timmermans-le-combat-des-favoris-aura-bien-lieu\/\">la donner ensuite \u00e0 Franz Timmermans<\/a>, puis \u00e0 Margaret Vestager \u2013 plut\u00f4t que d\u2019ouvrir un conflit interinstitutionnel qui a d\u2019ores et d\u00e9j\u00e0 eu des cons\u00e9quences n\u00e9gatives pour le fonctionnement et la coh\u00e9sion de l\u2019Union.<\/p>\n\n\n\n<p>Il est d\u2019ailleurs tr\u00e8s paradoxal que ces deux autres <em>Spitzenkandidaten<\/em> aient vu leur l\u00e9gitimit\u00e9 reconnue par les chefs d\u2019Etat et de gouvernement, puisqu\u2019ils ont ensuite exig\u00e9 leur nomination comme Vice-pr\u00e9sidents de la Commission europ\u00e9enne\u2026 Il reste donc \u00e0 souhaiter que le Conseil europ\u00e9en ne contestera plus l\u2019existence m\u00eame du syst\u00e8me des <em>Spitzenkandidaten<\/em>, et que ses membres prendront au s\u00e9rieux son usage en 2024, y compris en stimulant les candidatures de leur choix en vue de la comp\u00e9tition ouverte dont l\u2019un des protagonistes acc\u00e9dera \u00e0 la pr\u00e9sidence de la Commission.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Renforcer l\u2019ancrage d\u00e9mocratique des <em>Spitzenkandidaten<\/em><\/h4>\n\n\n\n<p>La l\u00e9gitimit\u00e9 politique et l\u2019ancrage civique des Pr\u00e9sident(e)s de la Commission seront d\u2019autant plus forts que les chefs de file se disputant les suffrages des \u00e9lecteurs europ\u00e9ens auront \u00e9t\u00e9 d\u00e9sign\u00e9s sur la base de primaires ouvertes. Cela suppose que ces chefs de file soient d\u00e9sign\u00e9s \u00e0 l\u2019issue d\u2019une v\u00e9ritable comp\u00e9tition interne plut\u00f4t que par consensus&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-9-53064' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/#easy-footnote-bottom-9-53064' title='Martin Schulz puis Franz Timmermans, chefs de file du parti S&amp;amp;D en 2014 et 2019, ont \u00e9t\u00e9 d\u00e9sign\u00e9s sans avoir \u00e0 affronter de concurrents lors des votes internes de ce parti.'><sup>9<\/sup><\/a><\/span><\/span>, mais surtout que cette d\u00e9signation proc\u00e8de d\u2019un vote des militants des partis concern\u00e9s voire des citoyens de l\u2019Union. Le vote des militants des partis serait un progr\u00e8s au regard d\u2019une d\u00e9signation op\u00e9r\u00e9e par des d\u00e9l\u00e9gu\u00e9s des partis nationaux, et qui proc\u00e8de de tractations souvent imp\u00e9n\u00e9trables pour les observateurs ext\u00e9rieurs&#160;: sa mise en place supposerait de pond\u00e9rer le poids des partis nationaux impliqu\u00e9s, pour \u00e9viter que celui ou ceux ayant le plus grand nombre de militants ne p\u00e8se trop fortement sur le r\u00e9sultat final. Les Verts europ\u00e9ens sont les premiers \u00e0 avoir eu l\u2019audace de recourir \u00e0 un vote direct de leurs sympathisants, et ce d\u00e8s 2014&#160;: il s\u2019agit d\u2019une pratique \u00e0 d\u00e9velopper et \u00e0 g\u00e9n\u00e9raliser en vue des prochains scrutins europ\u00e9ens, afin d\u2019affermir les liens entre les citoyens de l\u2019Union et celui ou celle qui pr\u00e9side le Coll\u00e8ge des commissaires.<\/p>\n\n\n\n<p>Le d\u00e9roulement des campagnes li\u00e9es aux \u00e9lections europ\u00e9ennes doit aussi \u00eatre am\u00e9lior\u00e9 d\u2019un point de vue civique. Cela suppose notamment que les programmes et autres \u00ab&#160; manifestes&#160;\u00bb adopt\u00e9s par les partis politiques europ\u00e9ens soient massivement traduits et diffus\u00e9s sur tout le territoire de l\u2019Union. Cela suppose plus globalement que les partis politiques europ\u00e9ens et les fondations charg\u00e9es de d\u00e9finir leur ligne id\u00e9ologique et leurs principales propositions soient dot\u00e9s de davantage de moyens budg\u00e9taires et humains dans le cadre du prochain cadre financier pluriannuel de l\u2019Union. Cela suppose enfin un usage beaucoup plus syst\u00e9matique des logos des partis politiques europ\u00e9ens sur les outils de campagne des partis nationaux, des tracts aux bulletins de vote, afin qu\u2019il soit clairement perceptible que l\u2019\u00e9lection des membres de l\u2019Assembl\u00e9e de Strasbourg s\u2019inscrit dans un cadre europ\u00e9en, et n\u2019est pas seulement la r\u00e9sultante de scrutins centr\u00e9s sur des consid\u00e9rations domestiques.<\/p>\n\n\n\n<p>L\u2019ancrage d\u00e9mocratique du\/de la Pr\u00e9sident(e) de la Commission sera enfin renforc\u00e9 s\u2019il est \u00e9lu sur la base d\u2019un vote public nominatif des parlementaires europ\u00e9ens. Si le vote est d\u00e9j\u00e0 nominatif lorsqu\u2019il porte sur l\u2019investiture de l\u2019ensemble du Coll\u00e8ge, il ne l\u2019est pas pour la Pr\u00e9sidence de la Commission et de ne l\u2019a donc pas \u00e9t\u00e9 pour l\u2019investiture d\u2019Ursula von der Leyen, ce qui ne permet pas de bien cerner les contours du socle majoritaire sur lequel elle compte principalement s\u2019appuyer pour gouverner l\u2019Union. Il ne tient qu\u2019au Parlement europ\u00e9en de modifier en ce sens son r\u00e8glement int\u00e9rieur \u00e0 l\u2019horizon 2024 afin d\u2019apporter ce surcro\u00eet de l\u00e9gitimit\u00e9 d\u00e9mocratique et d\u2019efficacit\u00e9 politique.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Introduire une \u00ab&#160;dose&#160;\u00bb de d\u00e9put\u00e9s transnationaux au Parlement europ\u00e9en<\/strong><\/h4>\n\n\n\n<p>Parce qu\u2019il a pour effet de rendre vacants les 73 si\u00e8ges de d\u00e9put\u00e9s europ\u00e9ens jusqu\u2019\u00e0 lors attribu\u00e9s au Royaume-Uni, le Brexit a relanc\u00e9 le d\u00e9bat sur la possible \u00e9lection d\u2019une fraction des membres de l\u2019assembl\u00e9e strasbourgeoise sur la base de listes transnationales&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-10-53064' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/#easy-footnote-bottom-10-53064' title='Voir par exemple Thierry Chopin et Lukas Macek, \u00ab&amp;#160;Pour l\u2019introduction de listes transnationales aux \u00e9lections europ\u00e9ennes sous la forme d\u2019une prime de majorit\u00e9&amp;#160;\u00bb, &lt;em&gt;Telos&lt;\/em&gt;, 21 f\u00e9vrier 2018.'><sup>10<\/sup><\/a><\/span><\/span>. La mise en place de ces listes pourrait utilement contribuer \u00e0 europ\u00e9aniser un peu plus le d\u00e9bat et la campagne \u00e9lectorale et \u00e0 compl\u00e9ter l\u2019agr\u00e9gation de visions nationales qui priment le plus souvent, et m\u00eame \u00e0 consolider le processus de s\u00e9lection du\/de la Pr\u00e9sident(e) de la Commission.<\/p>\n\n\n\n<p>Les leaders de ces <a href=\"https:\/\/legrandcontinent.eu\/fr\/2018\/02\/07\/nous-avons-rencontre-yanis-varoufakis\/\">listes transnationales<\/a> seraient en effet des candidats naturels \u00e0 la pr\u00e9sidence du Coll\u00e8ge bruxellois, puisque ces listes seraient soumises au choix de l\u2019ensemble des citoyens de l\u2019Union, et pas seulement \u00e0 des fractions nationales d\u2019entre eux. Il serait ainsi possible d\u2019\u00e9tablir un lien plus direct entre la d\u00e9signation des Spitzenkandidaten et les suffrages des \u00e9lecteurs, en d\u00e9samor\u00e7ant l\u2019objection selon laquelle les candidats chefs de file ne sont gu\u00e8res connus au-del\u00e0 des fronti\u00e8res de leurs pays dans le cadre du syst\u00e8me \u00e9lectoral actuel.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La mise en place des listes transnationales pourrait utilement contribuer \u00e0 europ\u00e9aniser un peu plus le d\u00e9bat et la campagne \u00e9lectorale et \u00e0 compl\u00e9ter l\u2019agr\u00e9gation de visions nationales qui priment le plus souvent, et m\u00eame \u00e0 consolider le processus de s\u00e9lection du\/de la Pr\u00e9sident(e) de la Commission<\/p><cite>Yves Bertoncini, Thierry Chopin<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Pour que cette innovation soit acceptable et l\u00e9gitime, il conviendrait naturellement de prendre en compte l\u2019ensemble des voix qui se sont port\u00e9es sur les listes soutenues par les principaux partis europ\u00e9ens, qu\u2019elles supportent ses 27 listes nationales ou sa liste transnationale. Les listes transnationales ne r\u00e9uniront en effet qu\u2019un nombre plus limit\u00e9 d\u2019\u00e9lus, sauf \u00e0 supprimer l\u2019ancrage national ou local des d\u00e9put\u00e9s europ\u00e9ens actuels &#8211; ce qui serait r\u00e9gressif du point de vue de leur ancrage civique &#8211; ou \u00e0 doubler leur nombre &#8211; ce qui serait probl\u00e9matique pour le fonctionnement du Parlement europ\u00e9en\u2026<\/p>\n\n\n\n<p>La mise en place de listes transnationales ne sera par ailleurs concevable aux yeux de l\u2019ensemble des pays de l\u2019Union que si des r\u00e8gles garantissent la pr\u00e9sence d\u2019un nombre minimal de nationalit\u00e9s, afin d\u2019\u00e9viter la surrepr\u00e9sentation des candidats issus des pays les plus peupl\u00e9s. Si le projet d\u2019une liste transnationale compos\u00e9e de 27 candidats \u00e9tait par exemple retenu, il faudrait ainsi pr\u00e9voir qu\u2019au moins un repr\u00e9sentant de chacun des 27 pays membres y figurent ou, a minima, qu\u2019au moins la moiti\u00e9 des pays membres y voient des nationaux repr\u00e9sent\u00e9s, selon une alternance emp\u00eachant ceux issus des pays les plus peupl\u00e9s de figurer syst\u00e9matiquement aux places \u00e9ligibles en t\u00eate de liste.<\/p>\n\n\n\n<p>C\u2019est \u00e0 ces conditions que la cr\u00e9ation de listes transnationales pourra \u00eatre act\u00e9e dans la perspective des \u00e9lections europ\u00e9ennes du printemps 2024, et qu\u2019elle contribuera elle aussi \u00e0 renforcer la l\u00e9gitimit\u00e9 du choix des gouvernants de l\u2019Union.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Conforter la l\u00e9gitimit\u00e9 repr\u00e9sentative hybride des membres de la Commission europ\u00e9enne<\/strong><\/h3>\n\n\n\n<p>La Pr\u00e9sidente de la Commission europ\u00e9enne n\u2019est pas le seul \u00e0 devoir sa nomination \u00e0 un vote d\u2019investiture du Parlement europ\u00e9en, d\u00e8s lors que les autres membres du Coll\u00e8ge bruxellois sont choisis par \u00ab&#160;le Conseil, d\u2019un commun accord avec le pr\u00e9sident \u00e9lu&#160;\u00bb. Et que la Commission est ensuite soumise \u00ab&#160;en tant que coll\u00e8ge \u00e0 un vote de confiance du Parlement europ\u00e9en&#160;\u00bb &#8211; qui peut par ailleurs censurer ce coll\u00e8ge tout au long de la l\u00e9gislature. Les difficult\u00e9s survenues lors de leur d\u00e9signation \u00e0 l\u2019automne 2019 et les projets de r\u00e9forme de la Commission mentionn\u00e9s \u00e7a et l\u00e0 doivent aussi inciter \u00e0 conforter l\u2019\u00e9quilibre entre leur l\u00e9gitimit\u00e9 civique et leur l\u00e9gitimit\u00e9 \u00e9tatique.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Renforcer la l\u00e9gitimit\u00e9 parlementaire des membres de la Commission<\/h4>\n\n\n\n<p>Comme l\u2019ont montr\u00e9 les ajustements survenus depuis 2004, les auditions parlementaires individuelles des Commissaires d\u00e9sign\u00e9(e)s ont un impact tr\u00e8s concret sur le r\u00e9sultat du processus de nomination&#160;: soit via le rejet de tel ou tel commissaire propos\u00e9 si lui est reproch\u00e9 un d\u00e9ficit de comp\u00e9tence ou d\u2019\u00e9thique pour exercer son mandat&#160;; soit via la r\u00e9attribution des portefeuilles, sur la base du profil personnel des commissaires, mais aussi de leur affiliation partisane. Ces auditions, puis les votes de confirmation, contribuent \u00e0 donner une r\u00e9elle l\u00e9gitimit\u00e9 parlementaire aux membres de la Commission europ\u00e9enne \u2013 et constituent une bonne pratique d\u00e9mocratique qui gagnerait \u00e0 \u00eatre appliqu\u00e9e pour la d\u00e9signation des membres des gouvernements nationaux.<\/p>\n\n\n\n<p>La l\u00e9gitimit\u00e9 parlementaire des Commissaires serait encore plus forte si  l\u2019ensemble d\u2019entre eux avait obligation de se pr\u00e9senter aux \u00e9lections  europ\u00e9ennes. Seuls certains d\u2019entre eux ont choisi de le faire jusqu\u2019alors, sur une base volontaire, mais leur nombre reste minoritaire (Jean-Claude Juncker lui-m\u00eame ne s\u2019\u00e9tait par exemple pas pr\u00e9sent\u00e9 sur une liste en 2014). L\u2019\u00e9lection pr\u00e9alable comme d\u00e9put\u00e9 est une condition <em>sine qua non<\/em> pour faire partie du gouvernement dans des pays comme le Royaume-Uni. <\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La l\u00e9gitimit\u00e9 parlementaire des Commissaires serait encore plus forte si  l\u2019ensemble d\u2019entre eux avait obligation de se pr\u00e9senter aux \u00e9lections  europ\u00e9ennes<\/p><cite>Yves Bertoncini, Thierry Chopin<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Elle pourrait avantageusement \u00eatre en usage au niveau europ\u00e9en, via une  \u00e9volution imm\u00e9diate des pratiques politiques ou une modification  ult\u00e9rieure des trait\u00e9s&#160;: elle conduirait en effet les int\u00e9ress\u00e9s \u00e0 se confronter plus directement aux citoyens de l\u2019Union puis \u00e0 cultiver leurs liens avec eux tout au long de leur mandat, y compris s\u2019ils souhaitent obtenir sa reconduction. Rendre obligatoire le choix des membres de la Commission europ\u00e9enne parmi les candidats aux \u00e9lections europ\u00e9ennes (ou \u00e9lus au Parlement europ\u00e9en) requiert une r\u00e9vision de l\u2019article 17 du TUE&#160;; mais ce choix peut aussi relever d\u2019une \u00ab&#160;bonne pratique politique&#160;\u00bb  de nature facultative et mise en \u0153uvre sans r\u00e9vision des trait\u00e9s.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Conserver la l\u00e9gitimit\u00e9 \u00e9tatique des membres de la Commission<\/h4>\n\n\n\n<p>La l\u00e9gitimit\u00e9 \u00e9tatique des membres de la Commission est plus ancienne&#160;: depuis les origines de la construction europ\u00e9enne, le Coll\u00e8ge bruxellois a en effet \u00e9t\u00e9 compos\u00e9 de nationaux issus de l\u2019ensemble des Etats membres (voir Tableau 3). Jusqu\u2019en 2004, les Etats les plus peupl\u00e9s ont eu le privil\u00e8ge de compter deux nationaux au sein de la Commission (Allemagne, Espagne, France, Italie et Royaume-Uni), contre seulement un pour les autres Etats. C\u2019est le grand \u00ab&#160;\u00e9largissement&#160;\u00bb des ann\u00e9es 2004-2007 qui a conduit \u00e0 adopter le principe d\u2019un national par Etat-membre pour \u00e9viter un effectif trop pl\u00e9thorique &#8211; d\u2019o\u00f9 une Commission compos\u00e9e de 28 membres pendant la p\u00e9riode 2014-2019.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Capture-d\u2019e\u0301cran-2019-11-20-a\u0300-05.38.22.png\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"1924\"\n        data-pswp-height=\"1214\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Capture-d\u2019e\u0301cran-2019-11-20-a\u0300-05.38.22-330x208.png\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Capture-d\u2019e\u0301cran-2019-11-20-a\u0300-05.38.22-690x435.png\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Capture-d\u2019e\u0301cran-2019-11-20-a\u0300-05.38.22-1340x846.png\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" alt=\"Nombre de commissaires\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Capture-d\u2019e\u0301cran-2019-11-20-a\u0300-05.38.22-125x79.png\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Tableau 3 \u2022 Thierry Chopin, Yves Bertoncini pour le Grand Continent<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>Auparavant, le Trait\u00e9 de Nice avait pr\u00e9vu que le nombre de Commissaires serait inf\u00e9rieur au nombre d\u2019Etats membres puis le Trait\u00e9 de Lisbonne a, lui, pr\u00e9vu que le nombre des Commissaires correspondrait au 2\/3 du nombre d\u2019Etats membres, sur la base d\u2019un syst\u00e8me de rotation \u00e9galitaire &#8211; sauf si le Conseil europ\u00e9en en d\u00e9cidait autrement \u00e0 l\u2019unanimit\u00e9. C\u2019est pr\u00e9cis\u00e9ment la d\u00e9cision que le Conseil europ\u00e9en a \u00e9t\u00e9 amen\u00e9 \u00e0 prendre afin de tenir compte de la victoire du \u00ab&#160;non&#160;\u00bb lors du r\u00e9f\u00e9rendum organis\u00e9 en Irlande pour ratifier le Trait\u00e9 de Lisbonne \u2013 d\u00e8s lors qu\u2019il \u00e9tait apparu que les votants avaient notamment exprim\u00e9 leur souhait de conserver un point d\u2019acc\u00e8s ais\u00e9ment identifiable au sein de la Commission.<\/p>\n\n\n\n<p>Il est important de souligner que ce retour au <em>statu quo ante<\/em> a aussi traduit le souhait de la plupart des \u00c9tats membres d\u2019\u00eatre repr\u00e9sent\u00e9s au sein du coll\u00e8ge bruxellois, compte tenu des importants pouvoirs de cette institution (en particulier le monopole de l\u2019initiative l\u00e9gislative et le contr\u00f4le de l\u2019ex\u00e9cution du droit de l\u2019Union). Il para\u00eet <em>de facto<\/em> essentiel d\u2019un point de vue politique que ce Coll\u00e8ge puisse compter en son sein des commissaires en prise directe avec l\u2019ensemble des pays de l\u2019Union, qui soient capables de  s\u2019adresser dans leurs langues \u00e0 tous ses citoyens, en amont et en aval des d\u00e9cisions prises par la Commission et par l\u2019Union. <\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La Commission devrait donc continuer \u00e0 b\u00e9n\u00e9ficier d\u2019une double l\u00e9gitimit\u00e9 repr\u00e9sentative plut\u00f4t logique sur le fond et ais\u00e9e \u00e0 exposer&#160;: elle d\u00e9coule \u00e0 la fois d\u2019un vote d\u2019investiture d\u2019une majorit\u00e9 du  Parlement europ\u00e9en et de la nomination d\u2019un national par Etat membre.<\/p><cite>Yves Bertoncini, Thierry Chopin<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Mettre l\u2019accent sur la r\u00e9duction du nombre de commissaires fait l\u2019impasse sur cette n\u00e9cessit\u00e9 d\u00e9mocratique d\u2019autant plus imp\u00e9rieuse \u00e0 l\u2019heure o\u00f9 l\u2019Union suscite des controverses tr\u00e8s vives entre ses Etats membres et ses peuples, et qui requi\u00e8rent une pr\u00e9sence accrue des Commissaires europ\u00e9ens dans le d\u00e9bat public, aussi bien dans leur pays d\u2019origine qu\u2019au sein des autres Etats-membres. L\u2019objectif d\u2019une r\u00e9duction du nombre de Commissaires est par ailleurs souvent per\u00e7u comme une tentative des plus grands Etats membres de r\u00e9duire l\u2019influence des pays les moins peupl\u00e9s, qui ne disposent d\u2019une repr\u00e9sentation \u00e9galitaire qu\u2019au sein du Coll\u00e8ge bruxellois (et non au Parlement europ\u00e9en et au Conseil).<\/p>\n\n\n\n<p>La Commission devrait donc continuer \u00e0 b\u00e9n\u00e9ficier d\u2019une double l\u00e9gitimit\u00e9 repr\u00e9sentative plut\u00f4t logique sur le fond et ais\u00e9e \u00e0 exposer&#160;: elle d\u00e9coule \u00e0 la fois d\u2019un vote d\u2019investiture d\u2019une majorit\u00e9 du  Parlement europ\u00e9en et de la nomination d\u2019un national par Etat membre. Ce <em>statu quo<\/em> ne menacera pas l\u2019efficacit\u00e9 de cette institution, dans la mesure o\u00f9 elle d\u00e9cide \u00e0 la majorit\u00e9 simple, et non \u00e0 l\u2019unanimit\u00e9 ou \u00e0 la majorit\u00e9 qualifi\u00e9e. Qu\u2019il y ait 18 ou 28 membres en son sein ne fait donc pas r\u00e9ellement obstacle \u00e0 la prise de d\u00e9cision&#160;: si un consensus est le plus souvent recherch\u00e9 par le\/la Pr\u00e9sident(e) de la Commission, il\/elle a en effet tout loisir de recourir au vote pour surmonter tout blocage \u00e9ventuel. Et il lui appartient de continuer \u00e0 r\u00e9partir les responsabilit\u00e9s et les portefeuilles de mani\u00e8re fonctionnelle entre les membres de son \u00e9quipe \u2013 nombre de gouvernements nationaux comptant eux aussi entre 25 et 30 membres\u2026<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Donner au pr\u00e9sident de la Commission le pouvoir de nommer les membres de son \u00e9quipe<\/h4>\n\n\n\n<p>Un ultime ajustement juridique pourra renforcer l\u2019ancrage civique de la Commission en parachevant ce processus de l\u00e9gitimation hybride. Apr\u00e8s avoir re\u00e7u lors du Trait\u00e9 de Nice le pouvoir de cong\u00e9dier les membres du coll\u00e8ge (article 17.6 du TUE), le pr\u00e9sident de la Commission devrait aussi avoir la facult\u00e9 de nommer personnellement les commissaires, au lieu que ce soit le Conseil, f\u00fbt-ce sur la base d\u2019un commun accord avec lui (au titre de l\u2019article 17.7 du TUE).  Cette l\u00e9g\u00e8re modification conforterait l\u2019importance du choix du pr\u00e9sident de la Commission par les citoyens, sur la base du syst\u00e8me des <em>Spitzenkandidaten<\/em>. Elle renforcerait la probabilit\u00e9 de voir nommer les bons commissaires aux bons postes, plut\u00f4t que de voir d\u00e9signer \u00e0 Bruxelles des personnalit\u00e9s que les autorit\u00e9s nationales souhaitent parfois \u00e9loigner autant que promouvoir.<\/p>\n\n\n\n<p>Le pr\u00e9sident de la Commission nommera naturellement les commissaires en  \u00e9troite relation avec les gouvernements nationaux. Il devrait choisir  ses vice-pr\u00e9sidents en respectant les \u00e9quilibres politiques de l\u2019UE  (grands\/plus petits \u00c9tats membres, Nord\/Sud\/Est\/Ouest et femme-homme en  particulier). Mais les \u00c9tats membres pourraient sans doute mieux  accepter une telle hi\u00e9rarchie politique interne <em>de facto<\/em>, alors qu\u2019ils sont peu dispos\u00e9s \u00e0 accepter une hi\u00e9rarchie <em>de jure<\/em> &#8211; et cela b\u00e9n\u00e9ficiera sans doute \u00e0 l\u2019efficacit\u00e9 du Coll\u00e8ge bruxellois.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Au-del\u00e0 du casting&#160;: gouverner l\u2019Union via un accord de mandature europ\u00e9en<\/strong><\/h3>\n\n\n\n<p>La l\u00e9gitimit\u00e9 des membres de la Commission et l\u2019efficacit\u00e9 de l\u2019Union pourront utilement \u00eatre renforc\u00e9s par la mise en place d\u2019un contrat de l\u00e9gislature&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-11-53064' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/#easy-footnote-bottom-11-53064' title=' Voir Pascal Lamy, Genevi\u00e8ve Pons, Christine Verger, \u00ab&amp;#160;Elections europ\u00e9enne&amp;#160;: pour un contrat de coalition \u00e0 quatre&amp;#160;\u00bb, &lt;em&gt;Policy paper&lt;\/em&gt; n\u00b0240, Institut Jacques Delors, 6 juin 2019.'><sup>11<\/sup><\/a><\/span><\/span> entre ces deux institutions, mais aussi et surtout sur la base d\u2019un contrat de mandature entre Parlement europ\u00e9en, Commission et Conseil europ\u00e9en.<\/p>\n\n\n\n<p>Les pr\u00e9misses d\u2019un tel contrat de mandature existaient d\u00e9j\u00e0 en 2014&#160;: la mise en place du syst\u00e8me des <em>Spitzenkandidaten<\/em> avait alors conduit les groupes politiques majoritaires au Parlement europ\u00e9en \u00e0 lier l\u2019investiture du Pr\u00e9sident de la Commission \u00e0 un accord entre ces deux institutions portant sur les principales priorit\u00e9s politiques \u00e0 mettre en \u0153uvre \u00e0 l\u2019horizon 2019 (dont le plan d\u2019investissement dit \u00ab&#160;Plan Juncker&#160;\u00bb)&#160;; les \u00ab&#160;orientations politiques&#160;\u00bb adopt\u00e9es par le Conseil europ\u00e9en en juin 2014 constituaient elles aussi un forme d\u2019accord interinstitutionnel entre cette institution et le Pr\u00e9sident de la Commission qu\u2019elle a d\u00e9sign\u00e9&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-12-53064' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/#easy-footnote-bottom-12-53064' title='Pour de plus amples pr\u00e9cisions sur ce sujet, voir \u00ab&amp;#160;Pour un quiquennat europ\u00e9en&amp;#160;\u00bb, Rapport, Terra Nova, 2017.'><sup>12<\/sup><\/a><\/span><\/span>. De m\u00eame, l\u2019\u00e9t\u00e9 2019 aura \u00e0 nouveau conduit \u00e0 l\u2019adoption de deux programmes d\u2019action parall\u00e8le&#160;: l\u2019\u00ab&#160;agenda 2019-2024&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-13-53064' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/#easy-footnote-bottom-13-53064' title='Voir \u00ab&amp;#160;Un nouveau programme strat\u00e9gique 2019-2024&amp;#160;\u00bb, Conseil Europ\u00e9en, juin 2019&amp;#160;:&lt;a href=&quot;https:\/\/www.consilium.europa.eu\/media\/39916\/a-new-strategic-agenda-2019-2024-fr.pdf&quot;&gt; https:\/\/www.consilium.europa.eu\/media\/39916\/a-new-strategic-agenda-2019-2024-fr.pdf&lt;\/a&gt;'><sup>13<\/sup><\/a><\/span><\/span> d\u00e9fini par le Conseil europ\u00e9en en juin 2019, puis le programme formalis\u00e9 par le discours d\u2019investiture d\u2019Ursula Von Der Leyen&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-14-53064' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/#easy-footnote-bottom-14-53064' title='Voir \u00ab&amp;#160;Une Union plus ambitieuse \u2013 Orientations politiques pour la Commission 2019-2024&amp;#160;\u00bb, Juillet 2019&lt;br&gt;&lt;a href=&quot;https:\/\/ec.europa.eu\/commission\/sites\/beta-political\/files\/political-guidelines-next-commission_fr.pdf&quot;&gt;https:\/\/ec.europa.eu\/commission\/sites\/beta-political\/files\/political-guidelines-next-commission_fr.pdf&lt;\/a&gt;'><sup>14<\/sup><\/a><\/span><\/span> devant le Parlement europ\u00e9en. Fait plus in\u00e9dit et cons\u00e9quence du pluralisme partisan accru, les groupes PPE, S&amp;D et Renew du Parlement europ\u00e9en, bient\u00f4t rejoints par les Verts, ont mis en place 5 groupes de travail th\u00e9matiques s\u2019effor\u00e7ant de d\u00e9gager des orientations communes \u2013 sans succ\u00e8s probant.<\/p>\n\n\n\n<p>La n\u00e9gociation et la publication de ces accords programmatiques sont de beaucoup pr\u00e9f\u00e9rables \u00e0 la pr\u00e9valence de tractations opaques sur le casting des \u00ab&#160;top jobs&#160;\u00bb entre les principaux partis europ\u00e9ens ou \u00e0 l\u2019expression de rapports de force purement institutionnels entre Conseil europ\u00e9en et Parlement europ\u00e9en quant \u00e0 la pr\u00e9\u00e9minence de leur l\u00e9gitimit\u00e9 de \u00ab&#160;faiseurs de rois&#160;\u00bb. Il s\u2019agit donc d\u2019une part de p\u00e9renniser l\u2019adoption de ces accords programmatiques, mais aussi et surtout de promouvoir l\u2019adoption d\u2019un v\u00e9ritable contrat de mandature associant Commission, Parlement et Conseil europ\u00e9ens, et qui dissipe la confusion n\u00e9e de la coexistence de deux accords n\u00e9goci\u00e9s en parall\u00e8le. Seul un tel contrat de mandature interinstitutionnel fournira un cap politique et un contenu op\u00e9rationnel plus clairs aux yeux des praticiens et citoyens de l\u2019Union, et qui soit \u00e9labor\u00e9 sur la base des rapports de force d\u00e9finis par les \u00e9lecteurs lors de l\u2019\u00e9t\u00e9 pr\u00e9c\u00e9dant l\u2019investiture de la Commission. Si elle ne fera naturellement pas dispara\u00eetre les tensions li\u00e9es au choix des gouvernants de l\u2019Union, l\u2019adoption d\u2019un tel accord de mandature lui donnera un fondement politique plus substantiel et moins clivant que la discussion relative aux d\u00e9cideurs appel\u00e9s \u00e0 le mettre en \u0153uvre.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>D\u00e9mocratiser la \u00ab&#160;gouvernance&#160;\u00bb de l\u2019Union europ\u00e9enne<\/strong><\/h2>\n\n\n\n<p>La d\u00e9signation des gouvernants de l\u2019Union pour le cycle 2019-2024 a donn\u00e9 lieu \u00e0 un heurt de l\u00e9gitimit\u00e9s dont il serait pr\u00e9f\u00e9rable de tirer toutes les le\u00e7ons afin de conforter la solidit\u00e9 et l\u2019efficacit\u00e9 du syst\u00e8me politique communautaire dans un monde adverse. Si ce syst\u00e8me politique a \u00e9t\u00e9 construit sur le primat d\u2019une l\u00e9gitimit\u00e9 \u00e9tatique de type \u00ab&#160;Westphalien&#160;\u00bb, il a progressivement \u00e9t\u00e9 r\u00e9form\u00e9 pour mieux tenir compte d\u2019une l\u00e9gitimit\u00e9 civique de type \u00ab&#160;Westmint\u00e9rien&#160;\u00bb, via un mouvement historique de d\u00e9mocratisation qu\u2019il s\u2019agit de parachever. Cette dynamique politique para\u00eet d\u2019autant plus claire \u00e0 l\u2019aune du spectaculaire surcro\u00eet de participation enregistr\u00e9 lors des \u00e9lections europ\u00e9ennes du printemps 2019, auquel il faut donner un d\u00e9bouch\u00e9 non seulement politique, mais aussi institutionnel, y compris dans le cadre de la \u00ab&#160;Conf\u00e9rence&#160;\u00bb convoqu\u00e9e au printemps 2020.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Construit sur le primat d\u2019une l\u00e9gitimit\u00e9 \u00e9tatique de type \u00ab&#160;Westphalien&#160;\u00bb, il a progressivement \u00e9t\u00e9 r\u00e9form\u00e9 pour mieux tenir compte d\u2019une l\u00e9gitimit\u00e9 civique de type \u00ab&#160;Westmint\u00e9rien&#160;\u00bb, via un mouvement historique de d\u00e9mocratisation qu\u2019il s\u2019agit de parachever.<\/p><cite>Yves Bertoncini, Thierry Chopin<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Si les propositions formul\u00e9es ci-avant ont pour objectif de consolider la l\u00e9gitimit\u00e9 hybride des gouvernants de l\u2019Union, elles pourraient \u00eatre utilement compl\u00e9t\u00e9es par d\u2019autres r\u00e9formes visant elles aussi \u00e0 donner des visages aux Europ\u00e9ens qui d\u00e9cident en notre nom, via la cr\u00e9ation de pr\u00e9sidences stables au Conseil et au Parlement europ\u00e9en ou encore l\u2019identification plus ais\u00e9e de majorit\u00e9s alternatives au niveau communautaire&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-15-53064' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/#easy-footnote-bottom-15-53064' title='Favoriser l\u2019expression de majorit\u00e9s alternatives au Parlement europ\u00e9en suppose d\u2019att\u00e9nuer l\u00e9g\u00e8rement la dimension proportionnelle du mode d\u2019\u00e9lection des d\u00e9put\u00e9s europ\u00e9ens et de privil\u00e9gier des r\u00e8gles de vote davantage majoritaires dans l\u2019h\u00e9micycle \u2013 voir Yves Bertoncini (dir),  Rapport Terranova 2019, op.cit. et Yves Bertoncini et Thierry Chopin, &lt;em&gt;Politique europ\u00e9enne, op. cit.&lt;\/em&gt;'><sup>15<\/sup><\/a><\/span><\/span>. D\u2019autres am\u00e9liorations, \u00e0 la fois constitutionnelles et politiques, ont vocation \u00e0 compl\u00e9ter cet agenda de r\u00e9conciliation des l\u00e9gitimit\u00e9 \u00e9tatique et civique de l\u2019Union, par exemple en tendant vers un bicam\u00e9risme \u00e9galitaire entre le Conseil et le Parlement europ\u00e9en dans l\u2019exercice du pouvoir l\u00e9gislatif. Il va enfin de soi que l\u2019agenda de d\u00e9mocratisation qu\u2019il s\u2019agit de promouvoir doit aussi pr\u00e9voir d\u2019apporter un surcro\u00eet de transparence \u00e0 l\u2019ensemble des institutions communautaires, bien au-del\u00e0 du seul processus de d\u00e9signation des gouvernants de l\u2019Union.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une perspective remarquablement inform\u00e9e pour comprendre le rapport de force qui se joue dans les institutions europ\u00e9ennes sign\u00e9e Yves Bertoncini et Thierry Chopin, suivie de pr\u00e9conisations pr\u00e9cises pour relancer le d\u00e9bat sur leur perfectionnement.<\/p>\n","protected":false},"author":7,"featured_media":53157,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-angles.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":0,"footnotes":""},"categories":[1731],"tags":[],"staff":[2154,2155],"editorial_format":[4944],"serie":[],"audience":[],"geo":[534],"class_list":["post-53064","post","type-post","status-publish","format-standard","hentry","category-politique","staff-thierry-chopin","staff-yves-bertoncini","editorial_format-actu-longues","geo-bulles"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":53157,"excerpt":"Une perspective remarquablement inform\u00e9e pour comprendre le rapport de force qui se joue dans les institutions europ\u00e9ennes sign\u00e9e Yves Bertoncini et Thierry Chopin, suivie de pr\u00e9conisations pr\u00e9cises pour relancer le d\u00e9bat sur leur perfectionnement.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le choix des gouvernants de l\u2019Union, pour un meilleur \u00e9quilibre entre d\u00e9mocratie et diplocratie | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le choix des gouvernants de l\u2019Union, pour un meilleur \u00e9quilibre entre d\u00e9mocratie et diplocratie | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Une perspective remarquablement inform\u00e9e pour comprendre le rapport de force qui se joue dans les institutions europ\u00e9ennes sign\u00e9e Yves Bertoncini et Thierry Chopin, suivie de pr\u00e9conisations pr\u00e9cises pour relancer le d\u00e9bat sur leur perfectionnement.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-20T06:55:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-27T12:28:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/page0-1005-full-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1116\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gilles Gressani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilles Gressani\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"47 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/\",\"name\":\"Le choix des gouvernants de l\u2019Union, pour un meilleur \u00e9quilibre entre d\u00e9mocratie et diplocratie | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/page0-1005-full-scaled.jpg\",\"datePublished\":\"2019-11-20T06:55:10+00:00\",\"dateModified\":\"2019-11-27T12:28:32+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/cf5b9f219cfb8e49b2923ff0e192682b\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/page0-1005-full-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/page0-1005-full-scaled.jpg\",\"width\":2560,\"height\":1116,\"caption\":\"Europa Building Brussels, architecte Samyn and Partners, 2018 Thierry Chopin Yves Bertoncini\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le choix des gouvernants de l\u2019Union, pour un meilleur \u00e9quilibre entre d\u00e9mocratie et diplocratie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/cf5b9f219cfb8e49b2923ff0e192682b\",\"name\":\"Gilles Gressani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ca9dca3417a297a024262b1a2d6d035a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ca9dca3417a297a024262b1a2d6d035a?s=96&d=mm&r=g\",\"caption\":\"Gilles Gressani\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le choix des gouvernants de l\u2019Union, pour un meilleur \u00e9quilibre entre d\u00e9mocratie et diplocratie | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/","og_locale":"fr_FR","og_type":"article","og_title":"Le choix des gouvernants de l\u2019Union, pour un meilleur \u00e9quilibre entre d\u00e9mocratie et diplocratie | Le Grand Continent","og_description":"Une perspective remarquablement inform\u00e9e pour comprendre le rapport de force qui se joue dans les institutions europ\u00e9ennes sign\u00e9e Yves Bertoncini et Thierry Chopin, suivie de pr\u00e9conisations pr\u00e9cises pour relancer le d\u00e9bat sur leur perfectionnement.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/","og_site_name":"Le Grand Continent","article_published_time":"2019-11-20T06:55:10+00:00","article_modified_time":"2019-11-27T12:28:32+00:00","og_image":[{"width":2560,"height":1116,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/page0-1005-full-scaled.jpg","type":"image\/jpeg"}],"author":"Gilles Gressani","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilles Gressani","Dur\u00e9e de lecture estim\u00e9e":"47 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/","url":"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/","name":"Le choix des gouvernants de l\u2019Union, pour un meilleur \u00e9quilibre entre d\u00e9mocratie et diplocratie | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/page0-1005-full-scaled.jpg","datePublished":"2019-11-20T06:55:10+00:00","dateModified":"2019-11-27T12:28:32+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/cf5b9f219cfb8e49b2923ff0e192682b"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/page0-1005-full-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/page0-1005-full-scaled.jpg","width":2560,"height":1116,"caption":"Europa Building Brussels, architecte Samyn and Partners, 2018 Thierry Chopin Yves Bertoncini"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/20\/le-choix-des-gouvernants-de-lunion-pour-un-meilleur-equilibre-entre-democratie-et-diplocratie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Le choix des gouvernants de l\u2019Union, pour un meilleur \u00e9quilibre entre d\u00e9mocratie et diplocratie"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/cf5b9f219cfb8e49b2923ff0e192682b","name":"Gilles Gressani","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ca9dca3417a297a024262b1a2d6d035a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ca9dca3417a297a024262b1a2d6d035a?s=96&d=mm&r=g","caption":"Gilles Gressani"}}]}},"lgc_categories":[{"id":1731,"name":"Politique","slug":"politique"}],"lgc_author":{"id":2154,"name":"Thierry Chopin","slug":"thierry-chopin","description":"Thierry Chopin est docteur en science politique de l\u2019Ecole des hautes \u00e9tudes en sciences sociales (EHESS) et a obtenu son Habilitation \u00e0 diriger des recherches (HDR) \u00e0 l\u2019Institut d\u2019\u00e9tudes politiques de Paris (Sciences Po).","first_name":"Thierry","last_name":"Chopin","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/09\/thierry-chopin.jpg","width":400,"height":400,"alt":"Conseiller sp\u00e9cial, institutions et d\u00e9mocratie"}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/page0-1005-full-scaled.jpg","width":2560,"height":1116,"alt":"Illustration d'une opposition entre diplomatie et diplocratie"},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/page0-1005-full-scaled.jpg","width":2560,"height":1116,"alt":"Illustration d'une opposition entre diplomatie et diplocratie"},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/53064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=53064"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/53064\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/53157"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=53064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=53064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=53064"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=53064"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=53064"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=53064"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=53064"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=53064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}