{"id":52064,"date":"2019-11-09T21:02:34","date_gmt":"2019-11-09T20:02:34","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=52064"},"modified":"2019-11-10T12:55:19","modified_gmt":"2019-11-10T11:55:19","slug":"les-espoirs-perdus-de-la-reunification","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/09\/les-espoirs-perdus-de-la-reunification\/","title":{"rendered":"Les espoirs perdus de la R\u00e9unification"},"content":{"rendered":"\n<p class=\"has-drop-cap\">Le jour o\u00f9 le mur de Berlin tombe, le 9 novembre\n1989, j\u2019\u00e9tais trop jeune pour demander \u00e0 mon p\u00e8re ouest-allemand de m\u2019emmener \u00e0\nBerlin vivre cette r\u00e9volution qui avait la gr\u00e2ce de ne pas \u00eatre souill\u00e9e par le\nsang. Mais j\u2019ai pleur\u00e9 avec mes parents devant le poste de t\u00e9l\u00e9vision qui\nmontrait des foules d\u2019Allemands de l\u2019Est et de l\u2019Ouest s\u2019embrasser \u00e0 nouveau,\npleurer et rire en creusant des trous \u00e0 la pioche dans le mur qui les avait\ns\u00e9par\u00e9s depuis des d\u00e9cennies.<\/p>\n\n\n\n<p>Quelle \u00e9motion dut saisir le chancelier Helmut Kohl lorsqu\u2019un mois plus tard lors d\u2019un discours \u00e0 Dresde, la capitale de Saxe, une mar\u00e9e humaine brandissant des drapeaux de la R\u00e9publique f\u00e9d\u00e9rale d\u2019Allemagne l\u2019accueillit en h\u00e9ros aux cris de \u00ab&#160;Einheit&#160;! Einheit&#160;!&#160;\u00bb (Unit\u00e9&#160;! Unit\u00e9&#160;!). <\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00ab&#160;Sans la perspective d\u2019une r\u00e9unification rapide, la RDA se serait vid\u00e9e de ses habitants selon la logique&#160;: <em>si le Deutsch Mark ne vient pas \u00e0 nous, nous irons \u00e0 lui<\/em>&#160;\u00bb.<\/p><cite>G\u00e9raldine Schwarz<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Kohl leur promit la R\u00e9unification. Il r\u00e9pondait probablement aussi \u00e0 la tentation d\u2019entrer \u00e0 jamais dans l\u2019Histoire comme le chancelier qui avait r\u00e9uni ces deux Allemagnes qui s\u2019\u00e9taient fait la guerre froide pendant 40 ans, des pions des grandes puissances. Mais il r\u00e9pondait surtout \u00e0 cet appel irr\u00e9sistible des Allemands de l\u2019Est qui faisaient vibrer la corde patriotique de nombreux Allemands. \u00c0 l\u2019Ouest tous n\u2019\u00e9taient pas enthousiastes \u00e0 l\u2019id\u00e9e d\u2019une R\u00e9unification. Certains disaient&#160;: \u00ab&#160;\u00e7a va co\u00fbter trop cher, un gouffre financier va tous nous engloutir.&#160;\u00bb <\/p>\n\n\n\n<p>\u00c0 l\u2019Est la plupart des anciens dissidents du r\u00e9gime qui avaient fond\u00e9 des formations politiques citoyennes mettaient en garde contre une r\u00e9unification trop rapide. Ils estimaient que la population n\u2019\u00e9tait pas pr\u00eate et qu\u2019il valait mieux y aller en douceur&#160;: d\u2019abord r\u00e9former la RDA d\u2019un point de vue \u00e9conomique et politique, afin de pouvoir ensuite n\u00e9gocier d\u2019\u00e9gal \u00e0 \u00e9gal avec l\u2019Ouest les modalit\u00e9s de la r\u00e9unification. <\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/DOC-MUR-DE-BERLIN-Capture-2.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"1920\"\n        data-pswp-height=\"1080\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/DOC-MUR-DE-BERLIN-Capture-2-330x186.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/DOC-MUR-DE-BERLIN-Capture-2-690x388.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/DOC-MUR-DE-BERLIN-Capture-2-1340x754.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" alt=\"G\u00e9raldine Schwarz le Grand Continent\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/DOC-MUR-DE-BERLIN-Capture-2-125x70.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Jesse Mazuch<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>Mais la population est-allemande ne croyait pas qu\u2019on puisse r\u00e9former un syst\u00e8me pourri de l\u2019int\u00e9rieur et, en cela, ils avaient probablement raison. Priv\u00e9s de libert\u00e9s et de confort mat\u00e9riel pendant 40 ans, ils aspiraient clairement au mod\u00e8le occidental. Et au Deutsch Mark. D\u00e8s le lendemain de la chute du Mur, ils commenc\u00e8rent \u00e0 s\u2019exiler en masse vers la RFA. Sans la perspective d\u2019une r\u00e9unification rapide, la RDA se serait vid\u00e9e de ses habitants selon la logique&#160;: \u00ab&#160;si le Deutsch Mark ne vient pas \u00e0 nous, nous irons \u00e0 lui&#160;\u00bb.<\/p>\n\n\n\n<p>En mars 1990, lors des premi\u00e8res \u00e9lections libres de RDA, les Allemands de l\u2019Est choisirent \u00e0 plus de 40&#160;% le parti de Helmut Kohl, la CDU, donc une r\u00e9unification rapide et la disparition de leur pays. Aucune des formations des anciens dissidents n\u2019atteint la barre des 5&#160;% n\u00e9cessaires pour entrer au parlement. Ceux qui ont port\u00e9 la r\u00e9volution sont \u00e9cart\u00e9s du destin de leur pays.<\/p>\n\n\n\n<p>Traiter ce processus d\u2019\u00ab&#160;annexion&#160;\u00bb, comme je l\u2019ai plusieurs fois entendu en France ces derniers temps, c\u2019est faire insulte aux Allemands de l\u2019Est qui ont choisi d\u00e9lib\u00e9r\u00e9ment d\u2019enterrer la RDA, c\u2019est les priver de leur r\u00f4le d\u2019acteurs actifs de la chute de la RDA. C\u2019est les infantiliser au lieu de leur rendre leur r\u00f4le et leur responsabilit\u00e9 dans l\u2019Histoire. <\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00ab&#160;Certes, l\u2019\u00c9tat garantissait un emploi, mais beaucoup \u00e9taient non productifs et maintenus artificiellement au prix de subventions telles que l\u2019\u00e9conomie \u00e9tait au bord de l\u2019implosion lorsque le Mur est tomb\u00e9.&#160;\u00bb<\/p><cite>G\u00e9raldine Schwarz<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Ce rejet radical donne la mesure de la souffrance endur\u00e9e sous une dictature qui interdisait de penser, de parler, de cr\u00e9er, de critiquer, de voyager. L\u2019endoctrinement commen\u00e7ait d\u00e8s le plus jeune \u00e2ge. \u00c0 l\u2019\u00e9cole, tout \u00e9tait enseign\u00e9 selon le dogme de Moscou. Pendant les loisirs, des organisations de masse encadraient les jeunes pour en faire de bons petits soldats du communisme. Certes, l\u2019\u00c9tat garantissait un emploi, mais beaucoup \u00e9taient non productifs et maintenus artificiellement au prix de subventions telles que l\u2019\u00e9conomie \u00e9tait au bord de l\u2019implosion lorsque le Mur est tomb\u00e9. Secr\u00e8tement, l\u2019\u00c9tat communiste lourdement endett\u00e9 empruntait de l\u2019argent \u00e0 son pire ennemi&#160;: l\u2019Allemagne de l\u2019Ouest. Le tout puissant parti communiste SED mentait \u00e0 ses citoyens et trahissait son id\u00e9al de soci\u00e9t\u00e9 sans classes. <\/p>\n\n\n\n<p>La discrimination r\u00e9gnait dans l&rsquo;acc\u00e8s aux \u00e9tudes, aux biens de consommation, aux logements et aux h\u00f4pitaux. Il valait mieux \u00eatre membre du parti et paysan ou ouvrier plut\u00f4t que pasteur ou intellectuel. Mais surtout, l\u2019\u00c9tat communiste exer\u00e7ait une terreur psychologique avec un appareil d\u2019espionnage tentaculaire, la Stasi, qui recrutait des centaines de milliers d\u2019informateurs au sein m\u00eame de la soci\u00e9t\u00e9 pour qu\u2019ils espionnent leurs coll\u00e8gues, leurs amis, leurs voisins, leur famille. La police politique condamna nombre d\u2019Allemands de l\u2019Est \u00e0 la schizophr\u00e9nie et \u00e0 l\u2019isolement int\u00e9rieur. Combien de familles, d\u2019amiti\u00e9s, de vies furent bris\u00e9es&#160;? Combien d\u2019innocents jet\u00e9s en prison&#160;? Combien de jeunes tu\u00e9s au pied du Mur sur ordre de l\u2019\u00c9tat pour avoir voulu fuir \u00e0 l\u2019Ouest&#160;?<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/DOC-MUR-DE-BERLIN-Capture-6.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"1920\"\n        data-pswp-height=\"1080\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/DOC-MUR-DE-BERLIN-Capture-6-330x186.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/DOC-MUR-DE-BERLIN-Capture-6-690x388.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/DOC-MUR-DE-BERLIN-Capture-6-1340x754.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" alt=\"G\u00e9raldine Schwarz le Grand Continent\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/DOC-MUR-DE-BERLIN-Capture-6-125x70.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Jesse Mazuch<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>Minimiser cette violence, r\u00e9\u00e9crire l\u2019histoire, rendre hommage \u00e0 des dictateurs comme Fidel Castro ou faire l\u2019apologie du communisme sans jamais avoir quitt\u00e9 sa bulle de confort occidental, c\u2019est offenser gravement les victimes des dictatures communistes, \u00e0 commencer par nos concitoyens d\u2019Europe de l\u2019Est.<\/p>\n\n\n\n<p>La chute du Mur et la R\u00e9unification furent avant tout une lib\u00e9ration. Mais cette lib\u00e9ration avait un prix. Un d\u00e9fi historique attendait l\u2019Allemagne r\u00e9unifi\u00e9e&#160;: convertir une \u00e9conomie planifi\u00e9e o\u00f9 tout appartenait \u00e0 l\u2019\u00c9tat en une \u00e9conomie de march\u00e9 \u2013 c\u2019est-\u00e0-dire, privatiser en masse. En juin 1990, avant la R\u00e9unification, le parlement librement \u00e9lu de RDA cr\u00e9a la <em>Treuhandanstalt<\/em> pour g\u00e9rer les privatisations. Helmut Kohl demanda aux entreprises ouest-allemandes d\u2019envoyer du personnel \u00e0 l\u2019Est pour pr\u00eater main forte.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00ab&#160;Un d\u00e9fi historique attendait l\u2019Allemagne r\u00e9unifi\u00e9e&#160;: convertir une \u00e9conomie planifi\u00e9e o\u00f9 tout appartenait \u00e0 l\u2019\u00c9tat en une \u00e9conomie de march\u00e9 \u2013 c\u2019est-\u00e0-dire, privatiser en masse.&#160;\u00bb<\/p><cite>G\u00e9raldine Schwarz<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Mon p\u00e8re, Volker Schwarz, fut l\u2019un des premiers \u00e0 se porter volontaire. Non pas pour \u00ab&#160;annexer&#160;\u00bb l\u2019Est mais parce qu\u2019il estimait avoir une dette \u00e0 l\u2019\u00e9gard des Allemands de l\u2019Est qui avaient pay\u00e9 un prix bien plus fort que les Allemands de l\u2019Ouest pour les crimes du IIIe Reich en se retrouvant sous domination sovi\u00e9tique. N\u00e9 en 1943, mon p\u00e8re a connu les affres de l\u2019apr\u00e8s-guerre dans un pays an\u00e9anti, puis le prodige d&rsquo;une renaissance \u00e9conomique et d\u00e9mocratique. Ce miracle ouest-allemand lui a donn\u00e9 une libert\u00e9 et un confort mat\u00e9riel dont les Allemands de l&rsquo;Est ont \u00e9t\u00e9 priv\u00e9s.<\/p>\n\n\n\n<p>\u00c0 son arriv\u00e9e \u00e0 Berlin-Est, en septembre 1990, il d\u00e9couvre que ce ne sera pas facile de convaincre des investisseurs, tant les usines \u00e9taient en piteux \u00e9tat, au niveau des b\u00e2timents, de l\u2019\u00e9quipement, de l\u2019organisation et de l\u2019impact \u00e9cologique. En outre, personne ne voulait plus de produits sign\u00e9s RDA, les clients d\u2019Europe de l\u2019Est n\u2019avaient plus d\u2019argent \u00e0 cause de l\u2019effondrement du bloc sovi\u00e9tique, et les Allemands de l\u2019Est eux-m\u00eames ne voulaient plus de Trabant, ils voulaient une Volkswagen&#160;! <\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/DOC-MUR-DE-BERLIN-Capture-5.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"1920\"\n        data-pswp-height=\"1080\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/DOC-MUR-DE-BERLIN-Capture-5-330x186.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/DOC-MUR-DE-BERLIN-Capture-5-690x388.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/DOC-MUR-DE-BERLIN-Capture-5-1340x754.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" alt=\"G\u00e9raldine Schwarz le Grand Continent\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/DOC-MUR-DE-BERLIN-Capture-5-125x70.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Jesse Mazuch<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>Sous la houlette de la <em>Treuhandanstalt<\/em>, un tiers des entreprises d\u2019ex-RDA furent liquid\u00e9s. Sur quatre millions d\u2019emplois, environ un tiers furent sauv\u00e9s. Contrairement \u00e0 nombre de leurs voisins d\u2019Europe de l\u2019Est qui virent leur niveau de vie plonger sous le seuil de pauvret\u00e9, les Allemands de l\u2019Est re\u00e7urent d\u2019importantes allocations. Mais cela ne suffit pas \u00e0 compenser le choc. La RDA pr\u00e9f\u00e9rait maintenir des emplois non productifs plut\u00f4t que de renoncer \u00e0 une promesse du communisme&#160;: le plein emploi. La d\u00e9couverte du ch\u00f4mage va plonger les Allemands de l\u2019Est dans le d\u00e9sespoir. La tension grimpe. Mon p\u00e8re vit se multiplier les manifestations aux portes de la <em>Treuhandanstalt<\/em>, accus\u00e9e de brader le pays et de mettre la main sur les p\u00e9pites de RDA. En r\u00e9alit\u00e9, une ligne directrice pr\u00e9voyait qu\u2019en cas de plusieurs candidats, le crit\u00e8re d\u00e9cisif n\u2019\u00e9tait pas celui qui offrait le plus mais celui qui sauvait le plus d\u2019emplois. Et il n\u2019y avait pas beaucoup de p\u00e9pites. <\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00ab&#160;Mon p\u00e8re vit se multiplier les manifestations aux portes de la <em>Treuhandanstalt<\/em>, accus\u00e9e de brader le pays et de mettre la main sur les p\u00e9pites de RDA.&#160;\u00bb<\/p><cite>G\u00e9raldine Schwarz<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Cependant, la <em>Treuhandanstalt<\/em>, plac\u00e9e sous l\u2019autorit\u00e9 du minist\u00e8re des Finances, commit des erreurs. Elle laissa passer des escrocs, vendit certains biens \u00e0 des prix absurdement bas, liquida des entreprises viables et fut entach\u00e9e par des scandales de corruption. \u00c0 son arriv\u00e9e, mon p\u00e8re fut choqu\u00e9 par le manque de personnel et d\u2019\u00e9quipement. Il manquait des machine \u00e0 \u00e9crire,  des stylos, et il n\u2019y avait que 5 ou 6 lignes t\u00e9l\u00e9phoniques. Mon p\u00e8re s\u2019est dit&#160;: \u00ab&#160;dans ces conditions c\u2019est s\u00fbr qu\u2019on est pas pr\u00eats de le construire ce IVe Reich tant redout\u00e9 par les Fran\u00e7ais&#160;\u00bb. Il travailla d\u2019arrache-pied et vendit 50 grosses entreprises en huit mois. Dans ces conditions, comment \u00e9viter les erreurs&#160;?<\/p>\n\n\n\n<p>Pendant des mois il d\u00fbt faire face \u00e0 une industrie ouest-allemande qui rechignait \u00e0 pr\u00eater ses experts, et \u00e0 un personnel minist\u00e9riel \u00e0 Bonn qui se d\u00e9sint\u00e9ressait de l\u2019Est. Ils sous-estim\u00e8rent la mission. S\u2019ils s\u2019\u00e9taient mobilis\u00e9s plus vite, des erreurs auraient pu \u00eatre \u00e9vit\u00e9es. Mais cela n\u2019aurait rien chang\u00e9 au fait qu\u2019il n\u2019y avait pas d\u2019alternative \u00e0 la liquidation d\u2019usines en ruine et d\u2019emplois non-productifs dans un pays o\u00f9 la productivit\u00e9 avait \u00e9t\u00e9 un tiers de celle de l\u2019Ouest. Maintenus dans le mensonge absolu d\u2019une propagande \u00e9tatique qui vendait la RDA comme la dixi\u00e8me puissance industrielle au monde, les Allemands de l\u2019Est ne voulaient pas croire \u00e0 l\u2019\u00c9tat r\u00e9el de leur \u00e9conomie. Certains continuent d\u2019entretenir le mythe d\u2019une ru\u00e9e des Allemands de l\u2019Ouest sur les pr\u00e9tendus tr\u00e9sors de RDA. Pour faire la lumi\u00e8re sur ce pass\u00e9, l\u2019ouverture des archives de la <em>Treuhandanstalt<\/em> vient d\u2019\u00eatre annonc\u00e9e.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/DOC-MUR-DE-BERLIN-Capture-4.jpg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"1920\"\n        data-pswp-height=\"1080\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/DOC-MUR-DE-BERLIN-Capture-4-330x186.jpg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/DOC-MUR-DE-BERLIN-Capture-4-690x388.jpg\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/DOC-MUR-DE-BERLIN-Capture-4-1340x754.jpg\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" alt=\"G\u00e9raldine Schwarz le Grand Continent\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/DOC-MUR-DE-BERLIN-Capture-4-125x70.jpg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Jesse Mazuch<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<p>Outre la perte de l\u2019emploi, les Allemands de l\u2019Est subirent un choc culturel. D\u2019une dictature o\u00f9 tout \u00e9tait dict\u00e9 par l\u2019\u00c9tat et o\u00f9 il y avait tr\u00e8s peu de marge de man\u0153uvre pour la responsabilit\u00e9 individuelle, ils durent s\u2019adapter \u00e0 une soci\u00e9t\u00e9 valorisant l\u2019initiative personnelle, la prise de position, la performance, la concurrence, la communication. Soudain, ce fut le grand chamboulement, les gens furent appel\u00e9s \u00e0 agir, \u00e0 choisir, \u00e0 donner leur avis. Certains durent recommencer leurs formations \u00e0 z\u00e9ro. Et surtout, ils durent apprendre la gestion des libert\u00e9s et la prise de responsabilit\u00e9 inh\u00e9rente \u00e0 une d\u00e9mocratie. Beaucoup se sentirent d\u00e9grad\u00e9s \u00e0 des Allemands de deuxi\u00e8me classe.<\/p>\n\n\n\n<p>Sur ce terreau traumatique va germer dans les ann\u00e9es 90 un fl\u00e9au qui aujourd\u2019hui a pris une ampleur inqui\u00e9tante en Allemagne de l\u2019Est&#160;: le n\u00e9onazisme. Le lynchage \u2013 parfois \u00e0 mort \u2013 d\u2019\u00e9trangers en pleine rue et les attaques de foyers de r\u00e9fugi\u00e9s devinrent une triste routine. Cela sous le regard apathique ou complice d\u2019une partie de la soci\u00e9t\u00e9 est-allemande. <\/p>\n\n\n\n<p>Aujourd\u2019hui, ce qui \u00e9tait visible dans les rues \u00e0 l\u2019Est dans les ann\u00e9es 90 s\u2019exprime aussi dans les urnes. Un parti d\u2019extr\u00eame droite et x\u00e9nophobe, l\u2019AfD, alli\u00e9 du parti de Marine Le Pen, a des scores deux \u00e0 trois fois plus \u00e9lev\u00e9s \u00e0 l\u2019Est qu\u2019\u00e0 l\u2019Ouest. Ce succ\u00e8s traduit d\u2019une part le ressentiment des Allemands de l\u2019Est \u00e0 l\u2019\u00e9gard de l\u2019Ouest h\u00e9rit\u00e9 des traumatismes de l\u2019apr\u00e8s-chute du Mur. Mais il est aussi un h\u00e9ritage de la RDA. Tandis qu\u2019en RFA, le travail de m\u00e9moire fut au c\u0153ur de la construction d\u00e9mocratique, en RDA on fit comme si personne n\u2019avait jamais \u00e9t\u00e9 nazi. La RDA fut fond\u00e9e sur un mythe&#160;: celui d\u2019\u00eatre le pays des communistes allemands ayant combattu le nazisme aupr\u00e8s des Russes. C\u2019\u00e9tait vrai pour ses dirigeants. Mais presque tous les autres avaient \u00e9t\u00e9 nazis avant que l\u2019Union sovi\u00e9tique ne les force \u00e0 devenir communistes. Pour leur inculquer l\u2019antifascisme, on les abreuva de pratiques comm\u00e9moratives. La m\u00e9moire \u00e9tait consacr\u00e9e aux h\u00e9ros communistes.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00ab&#160;La RDA fut fond\u00e9e sur un mythe&#160;: celui d\u2019\u00eatre le pays des communistes allemands ayant combattu le nazisme aupr\u00e8s des Russes.&#160;\u00bb<\/p><cite>G\u00e9raldine Schwarz<\/cite><\/blockquote><\/figure>\n\n\n\n<p>La Shoah \u00e9tait pass\u00e9 sous silence. \u00c0 ce manque de responsabilisation historique s\u2019ajoutait l\u2019absence de contact avec d\u2019autres cultures dans une soci\u00e9t\u00e9 condamn\u00e9e au cloisonnement. La propagande vendait une RDA \u00e9galitaire, mais aussi internationaliste, antiraciste et solidaire des peuples opprim\u00e9s par l\u2019imp\u00e9rialisme occidental. En r\u00e9alit\u00e9, le r\u00e9gime puisait largement dans le pathos patriotique et exploitait la main d\u2019\u0153uvre \u00e9trang\u00e8re, confin\u00e9e dans des ghettos. Le racisme et les n\u00e9onazis existaient d\u00e9j\u00e0 bien avant la chute du Mur. Cet h\u00e9ritage p\u00e8se lourd aujourd\u2019hui.<\/p>\n\n\n\n<p>Trente ans plus tard, cet h\u00e9ritage de la RDA et celui du choc de l\u2019apr\u00e8s\nchute du mur p\u00e8sent lourd. Peut-\u00eatre que le plus grand d\u00e9fi de la r\u00e9unification\nde l\u2019Allemagne, mais aussi de l\u2019Europe, n\u2019\u00e9tait pas la transition \u00e9conomique\nmais la transition d\u2019une dictature \u00e0 une soci\u00e9t\u00e9 d\u00e9mocratique et ouverte. Pour\nla faciliter, il faudrait que les Europ\u00e9ens de l\u2019Ouest montrent davantage\nd\u2019int\u00e9r\u00eat et d\u2019empathie pour le v\u00e9cu des populations de l\u2019Est. L\u2019arrogance et\nl\u2019ignorance d\u2019hommes politiques qui r\u00e9\u00e9crivent une histoire qu\u2019ils n\u2019ont m\u00eame\npas v\u00e9cu ne fait que creuser le foss\u00e9 qui nous s\u00e9pare.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre m\u00e9moire, essai et analyse, la perspective de G\u00e9raldine Schwarz sur la r\u00e9unification, les privatisations et cet h\u00e9ritage manqu\u00e9 qui creuse le foss\u00e9 qui nous s\u00e9pare.<\/p>\n","protected":false},"author":7,"featured_media":52090,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-angles.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":0,"footnotes":""},"categories":[1],"tags":[],"staff":[2147],"editorial_format":[4944],"serie":[],"audience":[],"geo":[],"class_list":["post-52064","post","type-post","status-publish","format-standard","hentry","category-uncategorised","staff-geraldine-schwarz","editorial_format-actu-longues"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":52090,"excerpt":"Entre m\u00e9moire, essai et analyse, la perspective de G\u00e9raldine Schwarz sur la r\u00e9unification, les privatisations et cet h\u00e9ritage manqu\u00e9 qui creuse le foss\u00e9 qui nous s\u00e9pare.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les espoirs perdus de la R\u00e9unification | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/09\/les-espoirs-perdus-de-la-reunification\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les espoirs perdus de la R\u00e9unification | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Entre m\u00e9moire, essai et analyse, la perspective de G\u00e9raldine Schwarz sur la r\u00e9unification, les privatisations et cet h\u00e9ritage manqu\u00e9 qui creuse le foss\u00e9 qui nous s\u00e9pare.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/09\/les-espoirs-perdus-de-la-reunification\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-09T20:02:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-10T11:55:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/000029927-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1316\" \/>\n\t<meta property=\"og:image:height\" content=\"645\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gilles Gressani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilles Gressani\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/09\/les-espoirs-perdus-de-la-reunification\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/09\/les-espoirs-perdus-de-la-reunification\/\",\"name\":\"Les espoirs perdus de la R\u00e9unification | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/09\/les-espoirs-perdus-de-la-reunification\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/09\/les-espoirs-perdus-de-la-reunification\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/000029927-1.jpg\",\"datePublished\":\"2019-11-09T20:02:34+00:00\",\"dateModified\":\"2019-11-10T11:55:19+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/cf5b9f219cfb8e49b2923ff0e192682b\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/09\/les-espoirs-perdus-de-la-reunification\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/09\/les-espoirs-perdus-de-la-reunification\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/09\/les-espoirs-perdus-de-la-reunification\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/000029927-1.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/000029927-1.jpg\",\"width\":1316,\"height\":645,\"caption\":\"G\u00e9raldine Schwarz\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/09\/les-espoirs-perdus-de-la-reunification\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les espoirs perdus de la R\u00e9unification\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/cf5b9f219cfb8e49b2923ff0e192682b\",\"name\":\"Gilles Gressani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ca9dca3417a297a024262b1a2d6d035a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ca9dca3417a297a024262b1a2d6d035a?s=96&d=mm&r=g\",\"caption\":\"Gilles Gressani\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les espoirs perdus de la R\u00e9unification | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/09\/les-espoirs-perdus-de-la-reunification\/","og_locale":"fr_FR","og_type":"article","og_title":"Les espoirs perdus de la R\u00e9unification | Le Grand Continent","og_description":"Entre m\u00e9moire, essai et analyse, la perspective de G\u00e9raldine Schwarz sur la r\u00e9unification, les privatisations et cet h\u00e9ritage manqu\u00e9 qui creuse le foss\u00e9 qui nous s\u00e9pare.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/09\/les-espoirs-perdus-de-la-reunification\/","og_site_name":"Le Grand Continent","article_published_time":"2019-11-09T20:02:34+00:00","article_modified_time":"2019-11-10T11:55:19+00:00","og_image":[{"width":1316,"height":645,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/000029927-1.jpg","type":"image\/jpeg"}],"author":"Gilles Gressani","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilles Gressani","Dur\u00e9e de lecture estim\u00e9e":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/09\/les-espoirs-perdus-de-la-reunification\/","url":"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/09\/les-espoirs-perdus-de-la-reunification\/","name":"Les espoirs perdus de la R\u00e9unification | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/09\/les-espoirs-perdus-de-la-reunification\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/09\/les-espoirs-perdus-de-la-reunification\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/000029927-1.jpg","datePublished":"2019-11-09T20:02:34+00:00","dateModified":"2019-11-10T11:55:19+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/cf5b9f219cfb8e49b2923ff0e192682b"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/09\/les-espoirs-perdus-de-la-reunification\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2019\/11\/09\/les-espoirs-perdus-de-la-reunification\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/09\/les-espoirs-perdus-de-la-reunification\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/000029927-1.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/000029927-1.jpg","width":1316,"height":645,"caption":"G\u00e9raldine Schwarz"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/09\/les-espoirs-perdus-de-la-reunification\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Les espoirs perdus de la R\u00e9unification"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/cf5b9f219cfb8e49b2923ff0e192682b","name":"Gilles Gressani","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ca9dca3417a297a024262b1a2d6d035a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ca9dca3417a297a024262b1a2d6d035a?s=96&d=mm&r=g","caption":"Gilles Gressani"}}]}},"lgc_categories":[{"id":1,"name":"Uncategorised","slug":"uncategorised"}],"lgc_author":{"id":2147,"name":"G\u00e9raldine Schwarz","slug":"geraldine-schwarz","description":"G\u00e9raldine Schwarz est une journaliste, autrice et documentariste franco-allemande. \u00a0Elle publie en 2017 \"Les amn\u00e9siques\" pour lequel elle re\u00e7oit le Prix du Livre europ\u00e9en 2018.","first_name":null,"last_name":null,"picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/10\/gc-Swarz.png","width":355,"height":340,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/000029927-1.jpg","width":1316,"height":645,"alt":"G\u00e9raldine Schwarz"},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/000029927-1.jpg","width":1316,"height":645,"alt":"G\u00e9raldine Schwarz"},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/52064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=52064"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/52064\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/52090"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=52064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=52064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=52064"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=52064"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=52064"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=52064"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=52064"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=52064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}