{"id":51127,"date":"2019-11-01T16:11:00","date_gmt":"2019-11-01T15:11:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=51127"},"modified":"2020-02-22T17:13:50","modified_gmt":"2020-02-22T16:13:50","slug":"ecologie-ou-croissance-faut-il-choisir","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/","title":{"rendered":"\u00c9cologie ou croissance&#160;: faut-il choisir&#160;?"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">1 &#8211; <strong>L\u2019\u00e9cologie, nouveau terme cl\u00e9 de l\u2019\u00e9quation politique europ\u00e9enne<\/strong><\/h3>\n\n\n\n<p>Les difficult\u00e9s d\u2019Ursula von der Leyen \u00e0 constituer la future Commission europ\u00e9enne et <a href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/10\/08\/green-new-deal-quatre-questions-a-frans-timmermans\/\">les impr\u00e9cisions de Frans Timmermans sur la feuille de route du Green Deal<\/a> ne doivent pas faire oublier l\u2019urgence politique \u00e0 laquelle l\u2019Union europ\u00e9enne s\u2019est solennellement engag\u00e9e \u00e0 r\u00e9pondre&#160;: la lutte contre le changement climatique. \u00c0 travers l\u2019annonce d\u2019une gouvernance articul\u00e9e autour du climat et d\u2019un objectif \u00e9loquent \u2013 devenir le premier continent neutre en carbone \u2013 la nouvelle Commission europ\u00e9enne a officialis\u00e9 la priorit\u00e9 de son mandat. Cet objectif s\u2019inscrit dans un contexte d\u2019attentes politiques et sociales fortes, apr\u00e8s des \u00e9lections europ\u00e9ennes o\u00f9 la th\u00e9matique environnementale a \u00e9t\u00e9 omnipr\u00e9sente et o\u00f9 les partis \u00e9cologistes de plusieurs pays europ\u00e9ens, parmi lesquels la France et l\u2019Allemagne, ont obtenu des scores records&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-51127' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/#easy-footnote-bottom-1-51127' title='&lt;a href=&quot;https:\/\/www.la-croix.com\/France\/Politique\/Elections-europeennes-Verts-succes-confirmer-duree-2019-05-27-1201024842&quot;&gt;\u201c\u00c9lections europ\u00e9ennes&amp;#160;: pour les Verts, un succ\u00e8s \u00e0 confirmer dans la dur\u00e9e\u201d&lt;\/a&gt;, B. Bouniol, &lt;em&gt;La Croix&lt;\/em&gt;, 27\/05\/2019'><sup>1<\/sup><\/a><\/span><\/span>. La vie politique europ\u00e9enne a ind\u00e9niablement pris la couleur de la lutte contre le changement climatique, et la Commission europ\u00e9enne entend s\u2019en saisir par la r\u00e9forme et l\u2019opportunit\u00e9.<\/p>\n\n\n\n<p>Les projets de taxe carbone aux fronti\u00e8res de l\u2019Union, d\u2019extension du march\u00e9 europ\u00e9en du carbone et de \u00ab&#160;Fonds pour une transition juste&#160;\u00bb tels qu\u2019annonc\u00e9s par Ursula von der Leyen dans son \u00ab&#160;Programme pour l\u2019Europe&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-51127' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/#easy-footnote-bottom-2-51127' title='&lt;a href=&quot;https:\/\/ec.europa.eu\/commission\/sites\/beta-political\/files\/political-guidelines-next-commission_fr.pdf&quot;&gt;\u201cUne Union plus ambitieuse. Mon programme pour l\u2019Europe\u201d&lt;\/a&gt;, Orientations politiques pour la prochaine Commission europ\u00e9enne 2019-2024, U. von der Leyen, Commission europ\u00e9enne'><sup>2<\/sup><\/a><\/span><\/span> disent une chose de la fa\u00e7on dont la transition \u00e9cologique est appr\u00e9hend\u00e9e par les institutions europ\u00e9ennes&#160;: comme une opportunit\u00e9 de croissance \u00ab&#160;verte&#160;\u00bb, et m\u00eame comme la condition n\u00e9cessaire de la p\u00e9rennit\u00e9 du syst\u00e8me \u00e9conomique et politique europ\u00e9en. Les modes d\u2019action privil\u00e9gi\u00e9s par l\u2019Union europ\u00e9enne sont, dans la droite lign\u00e9e des objectifs des COP, l\u2019adoption de mesures contraignantes de r\u00e9gulation ou de compensation des \u00e9missions de CO2 et l\u2019incorporation du facteur climat dans les outils \u00e9conomiques actuels que sont la taxe et le march\u00e9. \u00c0 cet \u00e9gard, l\u2019instauration d\u2019une taxe carbone aux fronti\u00e8res, la hausse du prix du carbone, et le durcissement des conditions d\u2019\u00e9change de quotas portent en th\u00e9orie la promesse de plus forte contrainte des acteurs \u00e9conomiques et industriels et donc d\u2019une d\u00e9marche syst\u00e9mique de l\u2019\u00e9conomie vers la sobri\u00e9t\u00e9, \u00e0 l\u2019abri par exemple de la tentation de d\u00e9localiser les \u00e9missions de CO2 dans les pays en d\u00e9veloppement. Il s\u2019agit en somme pour la Commission von der Leyen de positionner l\u2019Union europ\u00e9enne \u00e0 l\u2019initiative de mesures r\u00e9glementaires structurantes pour le commerce international&#160;: l&rsquo;adaptation de l&rsquo;Union \u00e0 ce nouveau paradigme de lutte contre le changement climatique peut lui \u00eatre profitable si tant est qu\u2019elle en d\u00e9finit les r\u00e8gles.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00ab&#160;La vie politique europ\u00e9enne a ind\u00e9niablement pris la couleur de la lutte contre le changement climatique, et la Commission europ\u00e9enne entend s\u2019en saisir par la r\u00e9forme et l\u2019opportunit\u00e9.&#160;\u00bb<\/p><cite>Cl\u00e9mence P\u00e8legrin<\/cite><\/blockquote><\/figure>\n\n\n\n<p>L&rsquo;approche de la nouvelle Commission s&rsquo;inscrit donc en faux contre les tenants d&rsquo;une \u00e9cologie politique de rupture \u2013 rupture avec le libre-\u00e9change, la recherche de croissance \u00e9conomique, et plus g\u00e9n\u00e9ralement l\u2019\u00e9conomie de march\u00e9. La mobilisation de capitaux publics, l\u2019incitation des pr\u00eateurs priv\u00e9s \u00e0 financer des projets et des infrastructures plus propres au d\u00e9triment des actifs les plus carbon\u00e9s, et le soutien financier et industriel aux nouvelles technologies, sont consid\u00e9r\u00e9es comme des outils privil\u00e9gi\u00e9s de la transition \u00e9cologique pens\u00e9e en tant que r\u00e9forme \u00e9conomique et sociale, davantage que r\u00e9volution politique.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2 &#8211; <strong>Le respect des objectifs de la COP21 n\u2019est pas une garantie de succ\u00e8s<\/strong><\/h3>\n\n\n\n<p>Selon le rapport sp\u00e9cial du <a href=\"https:\/\/legrandcontinent.eu\/fr\/2017\/11\/25\/nous-avons-rencontre-herve-le-treut\/\">Groupe d&rsquo;experts intergouvernemental sur l&rsquo;\u00e9volution du climat (GIEC)<\/a> sur le r\u00e9chauffement plan\u00e9taire de 1,5\u00b0C, \u00ab&#160;du point de vue des lois de la physique, il est techniquement possible de limiter le r\u00e9chauffement \u00e0 1,5 \u00b0C, mais cela impliquerait de r\u00e9duire les \u00e9missions mondiales de dioxyde de carbone d&rsquo;environ 45&#160;% par rapport aux niveaux de 2010 d&rsquo;ici \u00e0 2030 et d&rsquo;atteindre un bilan nul en 2050. Or, au rythme actuel des \u00e9missions, le seuil de 1,5 \u00b0C sera franchi entre 2030 et 2052 et le r\u00e9chauffement d\u00e9passera les 3-4 \u00b0C d&rsquo;ici 2100.&#160;\u00bb Pour respecter l\u2019objectif de limiter le r\u00e9chauffement climatique entre 1,5\u00b0C et 2\u00b0C, reconnu par les parties de la COP21 comme la trajectoire haute \u00e0 ne pas d\u00e9passer sous peine de subir les effets irr\u00e9versibles du changement climatique, le GIEC reconna\u00eet la n\u00e9cessit\u00e9 de donner un prix \u00e9lev\u00e9 au carbone, de d\u00e9carboner la production d\u2019\u00e9nergie et de r\u00e9orienter drastiquement les investissements des combustibles fossiles vers des sources d\u2019\u00e9nergie plus propres&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-51127' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/#easy-footnote-bottom-3-51127' title='&lt;a href=&quot;https:\/\/www.ipcc.ch\/sr15&quot;&gt;Special Report. Global Warming of 1.5 \u00baC&lt;\/a&gt;, chapter 2, IPCC'><sup>3<\/sup><\/a><\/span><\/span>, entre autres mesures.<\/p>\n\n\n\n<p>La mise en oeuvre de ces mesures et l\u2019infl\u00e9chissement effectif de la trajectoire de CO2 ne constituent n\u00e9anmoins pas une garantie de limiter le r\u00e9chauffement climatique, <a href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/09\/14\/rapport-du-giec-sur-les-terres-notre-securite-alimentaire-en-danger\/\">compte tenu notamment des incertitudes g\u00e9ologiques actuelles<\/a>&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-51127' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/#easy-footnote-bottom-4-51127' title='Voir notre analyse sur les risques du changement climatique sur la qualit\u00e9 des sols et la s\u00e9curit\u00e9 alimentaire &lt;a href=&quot;https:\/\/legrandcontinent.eu\/fr\/2019\/09\/14\/rapport-du-giec-sur-les-terres-notre-securite-alimentaire-en-danger\/&quot;&gt;https:\/\/legrandcontinent.eu\/fr\/2019\/09\/14\/rapport-du-giec-sur-les-terres-notre-securite-alimentaire-en-danger\/&lt;\/a&gt;'><sup>4<\/sup><\/a><\/span><\/span>. Comme l\u2019affirme le GIEC, <em>\u00ab&#160;even if this is achieved, temperatures would only be expected to remain below the 1.5\u00b0C threshold if the actual geophysical response ends up being towards the low end of the currently estimated uncertainty range&#160;\u00bb<\/em>&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-51127' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/#easy-footnote-bottom-5-51127' title='&lt;em&gt;Ibid.&lt;\/em&gt;'><sup>5<\/sup><\/a><\/span><\/span>. En effet, l\u2019une des principales inqui\u00e9tudes relatives au changement climatique r\u00e9side pr\u00e9cis\u00e9ment dans la pr\u00e9cipitation de \u00ab&#160;r\u00e9actions en cha\u00eene&#160;\u00bb au sein des \u00e9cosyst\u00e8mes&#160;: par exemple, la hausse de la temp\u00e9rature des oc\u00e9ans engendrerait des d\u00e9s\u00e9quilibres dans les \u00e9cosyst\u00e8mes marins avec un effet direct sur la production d\u2019oxyg\u00e8ne et la capacit\u00e9 de dissolution du CO2 des oc\u00e9ans, pouvant donner lieu \u00e0 l\u2019\u00e9puisement de certaines ressources halieutiques ou \u00e0 la pullulation de certaines esp\u00e8ces au d\u00e9triment d\u2019autres.<\/p>\n\n\n\n<p>\u00c0 titre d\u2019exemple, les \u00ab&#160;boucles de r\u00e9troaction&#160;\u00bb portent l\u2019une des caract\u00e9ristiques les plus fondamentales du changement climatique&#160;: les effets de ce dernier ne forment pas une s\u00e9quence causale lin\u00e9aire. La tendance au d\u00e9gel du permafrost dans les r\u00e9gions arctiques est d\u00e9j\u00e0 \u00e0 l\u2019\u0153uvre et conduira, \u00e0 terme, \u00e0 l\u2019\u00e9mission massive de m\u00e9thane, un gaz qui contribue largement plus que le CO2 \u00e0 l\u2019effet de serre. Le r\u00e9chauffement occasionn\u00e9 par la lib\u00e9ration de m\u00e9thane dans l\u2019atmosph\u00e8re pourrait \u00e0 son tour catalyser la fonte du permafrost, et en fin de boucle d\u00e9multiplier la lib\u00e9ration de m\u00e9thane elle-m\u00eame. Mais les boucles de r\u00e9troaction causale qui alertent les climatologues ne sont pas seulement g\u00e9ologiques ou biologiques&#160;; elles sont aussi sociales. Le r\u00e9chauffement climatique peut en effet donner lieu \u00e0 une amplification de ses propres effets, par le recours humain \u00e0 des strat\u00e9gies d\u2019accommodation, comme la climatisation, qui rejette de l\u2019air chaud en aval tout en augmentant consid\u00e9rablement la demande en \u00e9nergie.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00ab&#160;Le r\u00e9chauffement climatique peut donner lieu \u00e0 une amplification de ses propres effets, par le recours humain \u00e0 des strat\u00e9gies d\u2019accommodation, comme la climatisation, qui rejette de l\u2019air chaud en aval tout en augmentant consid\u00e9rablement la demande en \u00e9nergie.&#160;\u00bb<\/p><cite>Cl\u00e9mence P\u00e8legrin<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">3 &#8211; <strong>Existe-t-il une \u00ab&#160;injustice climatique&#160;\u00bb&#160;?<\/strong><\/h3>\n\n\n\n<p>Les espaces les plus pr\u00e9coc\u00e9ment vuln\u00e9rables face au changement climatique sont les pays en d\u00e9veloppement, et particuli\u00e8rement les petits \u00c9tats insulaires (<em>small island developing states<\/em> dans la terminologie des Objectifs de D\u00e9veloppement Durable des Nations Unies&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-51127' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/#easy-footnote-bottom-6-51127' title='&lt;a href=&quot;https:\/\/sustainabledevelopment.un.org\/topics\/sids&quot;&gt;\u201cSmall Island Developing States (SIDS)\u201d,&lt;\/a&gt; Division for Sustainable Development Goals, ONU'><sup>6<\/sup><\/a><\/span><\/span>), comme les Maldives ou le Vanuatu&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-7-51127' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/#easy-footnote-bottom-7-51127' title='&lt;a href=&quot;https:\/\/time.com\/5621885\/climate-change-population-growth\/&quot;&gt;\u201cThe 10 Countries Most Vulnerable to Climate Change Will Experience Population Booms in the Coming Decades\u201d&lt;\/a&gt;, C. Nugent, Time Magazine, 11\/07\/2017'><sup>7<\/sup><\/a><\/span><\/span>. Dans le cas des territoires insulaires, leur exposition au risque de mont\u00e9e du niveau des oc\u00e9ans, l\u2019intensification de certains ph\u00e9nom\u00e8nes climatiques, comme les temp\u00eates et les ouragans, et leurs effets g\u00e9omorphologiques comme l\u2019\u00e9rosion du littoral et des sols cultivables, sont autant de sympt\u00f4mes d\u00e9j\u00e0 bien visibles. Si les \u00c9tats membres de l\u2019OCDE sont ceux qui portent historiquement la plus grande part du bilan carbone de la plan\u00e8te,  malgr\u00e9 des trajectoires d\u2019\u00e9missions de CO2 prometteuses, ce sont aussi ceux qui sont les moins expos\u00e9s aux risques \u00e0 court terme du changement climatique. Cette id\u00e9e <em>d\u2019injustice<\/em> est l\u2019une des probl\u00e9matiques politiques les plus pressantes pos\u00e9es par le r\u00e9chauffement climatique. En effet, les \u00e9tudes sont formelles&#160;: il n\u2019affectera pas tous les territoires \u00e0 la m\u00eame vitesse ni de la m\u00eame fa\u00e7on.<\/p>\n\n\n\n<p>La responsabilit\u00e9 historique de l\u2019Europe et des \u00c9tats-Unis dans le bilan carbone mondial n\u2019est plus \u00e0 d\u00e9montrer, de m\u00eame que la capacit\u00e9 des \u00e9conomies \u00ab&#160;m\u00fbres&#160;\u00bb \u2013 o\u00f9 l\u2019industrie a d\u00e9clin\u00e9 depuis plusieurs d\u00e9cennies, laissant la place \u00e0 une \u00e9conomie de services, \u00e0 faire face au changement climatique. D\u00e8s lors, que r\u00e9pondre aux pays en d\u00e9veloppement comme la Chine ou l\u2019Inde qui, du fait du rythme de leur croissance \u00e9conomique et d\u00e9mographique et des besoins \u00e9nerg\u00e9tiques qui en d\u00e9coulent, demeurent bien loin de l\u2019accomplissement d\u2019une forme de d\u00e9couplage&#160;? C\u2019est l\u00e0 toute la teneur du dilemme repr\u00e9sent\u00e9 par la \u00ab&#160;responsabilit\u00e9 commune mais diff\u00e9renci\u00e9e&#160;\u00bb formul\u00e9e dans le principe 7 de la d\u00e9claration de Rio en 1992&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-8-51127' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/#easy-footnote-bottom-8-51127' title='&lt;a href=&quot;https:\/\/www.un.org\/french\/events\/rio92\/aconf15126vol1f.htm&quot;&gt;D\u00e9claration de Rio sur l\u2019environnement et le d\u00e9veloppement&lt;\/a&gt;, Assembl\u00e9e g\u00e9n\u00e9rale des Nations Unies, 12\/08\/1992'><sup>8<\/sup><\/a><\/span><\/span>&#160;: comment concilier croissance et transition \u00e9cologique, et d\u00e9corr\u00e9ler d\u00e9veloppement et empreinte CO2&#160;? Dans quelle mesure est-il l\u00e9gitime pour les pays du Nord de contraindre les modalit\u00e9s de la croissance des pays en d\u00e9veloppement qui, non contents d\u2019accueillir les cha\u00eenes de production d\u00e9localis\u00e9es des \u00e9conomies d\u00e9velopp\u00e9es, p\u00e2tissent cons\u00e9cutivement des \u00e9missions de carbone et de leurs effets collat\u00e9raux associ\u00e9s, comme la pollution de l\u2019air et des sols&#160;?<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00ab&#160;Comment concilier croissance et transition \u00e9cologique, et d\u00e9corr\u00e9ler d\u00e9veloppement et empreinte CO2&#160;?&#160;\u00bb<\/p><cite>Cl\u00e9mence P\u00e8legrin<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">4 &#8211; <strong>Qu\u2019est ce que le d\u00e9couplage&#160;?<\/strong><\/h3>\n\n\n\n<p>Derri\u00e8re la vision de la transition \u00e9cologique r\u00e9side une hypoth\u00e8se fondamentale&#160;: <em>le d\u00e9couplage entre croissance \u00e9conomique et \u00e9missions de carbone est possible<\/em>. Le d\u00e9couplage est ici consid\u00e9r\u00e9 comme la d\u00e9corr\u00e9lation entre les \u00e9missions de CO2 et la croissance du PIB, signifiant que la valeur \u00e9conomique est cr\u00e9\u00e9e par une meilleure efficacit\u00e9 \u00e9nerg\u00e9tique ou par des m\u00e9thodes plus propres. Pour la premi\u00e8re fois en 2001, l\u2019OCDE d\u00e9finit le d\u00e9couplage comme l\u2019un des principaux objectifs de la strat\u00e9gie environnementale mondiale au XXI\u00e8 si\u00e8cle&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-9-51127' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/#easy-footnote-bottom-9-51127' title='Environmental Strategy for the First Decade of the 21st Century, Policy Paper, OECD, 2001'><sup>9<\/sup><\/a><\/span><\/span>. Dix ans plus tard, dans un rapport sur l\u2019intensit\u00e9 \u00e9nerg\u00e9tique et environnementale de la croissance, le Programme Environnement des Nations Unies aborde de nouveau l\u2019id\u00e9e d\u00e9couplage comme imp\u00e9ratif politique dans la lutte contre le changement climatique&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-10-51127' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/#easy-footnote-bottom-10-51127' title='UNEP (2011) Decoupling natural resource use and environmental impacts from economic growth, A Report of the Working Group on Decoupling to the International Resource Panel. Fischer-Kowalski, M., Swilling, M., von Weizs\u00e4cker, E.U., Ren, Y., Moriguchi, Y., Crane, W., Krausmann, F., Eisenmenger, N., Giljum, S., Hennicke, P., Romero Lankao, P., Siriban Manalang, A., Sewerin, S.'><sup>10<\/sup><\/a><\/span><\/span>. La d\u00e9corr\u00e9lation entre d\u2019une part la croissance \u00e9conomique et l\u2019usage des ressources naturelles, et d\u2019autre part la croissance \u00e9conomique et l\u2019impact environnemental est la condition<em> sine qua non<\/em> de la durabilit\u00e9 de l\u2019\u00e9conomie mondiale.<\/p>\n\n\n\n<p>Il est important de distinguer le d\u00e9couplage <em>relatif<\/em> du d\u00e9couplage <em>absolu<\/em>&#160;; si le premier d\u00e9signe le ralentissement de la croissance des \u00e9missions de CO2 par rapport \u00e0 celui de la croissance \u00e9conomique, le second d\u00e9signe le recul de l\u2019impact environnemental dans le cadre d\u2019une hausse du PIB. Le d\u00e9couplage relatif est une r\u00e9alit\u00e9 d\u2019ores et d\u00e9j\u00e0 constat\u00e9e dans la zone OCDE, et t\u00e9moigne notamment des gains d\u2019efficacit\u00e9 dans la production d\u2019\u00e9nergie et le secteur manufacturier permis par l\u2019innovation technologique. Le second, en revanche, suscite davantage de scepticisme chez plusieurs \u00e9conomistes, qui le consid\u00e8rent impossible&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-11-51127' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/#easy-footnote-bottom-11-51127' title='Voir Laurent, \u00c9loi. \u00ab&amp;#160;Faut-il d\u00e9courager le d\u00e9couplage&amp;#160;?&amp;#160;\u00bb, Revue de l&amp;rsquo;OFCE, vol. 120, no. 1, 2012, pp. 235-257.'><sup>11<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-medium\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/De\u0301couplage-et-bien-e\u0302tre-humain-croissance-IDH.png\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"926\"\n        data-pswp-height=\"526\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/De\u0301couplage-et-bien-e\u0302tre-humain-croissance-IDH-330x187.png\"\r\n                media=\"(max-width:  374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/De\u0301couplage-et-bien-e\u0302tre-humain-croissance-IDH-690x392.png\"\r\n                media=\"(max-width:  989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/De\u0301couplage-et-bien-e\u0302tre-humain-croissance-IDH.png\"\r\n                media=\"(max-width: 1319px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/De\u0301couplage-et-bien-e\u0302tre-humain-croissance-IDH-690x392.png\"\r\n                media=\"(max-width: 1599px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/De\u0301couplage-et-bien-e\u0302tre-humain-croissance-IDH.png\"\r\n                media=\"(min-width: 1600px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/De\u0301couplage-et-bien-e\u0302tre-humain-croissance-IDH-125x71.png\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Source&#160;: Laurent, \u00c9loi. \u00ab&#160;Faut-il d\u00e9courager le d\u00e9couplage&#160;?&#160;\u00bb, Revue de l&rsquo;OFCE, vol. 120, no. 1, 2012, pp. 235-257. adapt\u00e9 de INR (2011)<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<h3 class=\"wp-block-heading\">5 &#8211; <strong>Pourquoi parler de d\u00e9couplage&#160;? <\/strong><\/h3>\n\n\n\n<p>La notion de d\u00e9couplage est aujourd\u2019hui fondamentale pour comprendre la fa\u00e7on dont les organisations internationales et l\u2019Union europ\u00e9enne con\u00e7oivent la transition \u00e9cologique. Depuis la formulation explicite du d\u00e9couplage comme objectif en 2001 par l\u2019OCDE, la Commission europ\u00e9enne et l\u2019ONU ont focalis\u00e9 leurs discours de lutte contre le changement climatique autour de la dissociation de l\u2019empreinte carbone et du d\u00e9veloppement.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00ab&#160;La notion de d\u00e9couplage est aujourd\u2019hui fondamentale pour comprendre la fa\u00e7on dont les organisations internationales et l\u2019Union europ\u00e9enne con\u00e7oivent la transition \u00e9cologique.&#160;\u00bb<\/p><cite>Cl\u00e9mence P\u00e8legrin<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Au sein de l\u2019Union europ\u00e9enne, les promoteurs du d\u00e9couplage en tiennent pour preuve que, depuis 1990, le rythme de la croissance \u00e9conomique a \u00e9t\u00e9 plus rapide que celui des \u00e9missions de gaz \u00e0 effet de serre. Selon l\u2019Agence internationale de l&rsquo;\u00e9nergie, entre 2000 et 2017, sur une base 100, le PIB \u00e0 parit\u00e9 de pouvoir d\u2019achat par habitant dans l\u2019Union europ\u00e9enne a augment\u00e9 de 23 points, l\u00e0 o\u00f9 les \u00e9missions de CO2 issues de l\u2019usage de combustibles ont diminu\u00e9 de 15 points&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-12-51127' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/#easy-footnote-bottom-12-51127' title='&lt;a href=&quot;https:\/\/www.iea.org\/statistics\/co2emissions\/&quot;&gt;CO2 Emissions Statistics&lt;\/a&gt;, &lt;a href=&quot;https:\/\/www.iea.org\/geco\/&quot;&gt;Global Energy &amp;amp; CO2 Status Report 2019&lt;\/a&gt;, International Energy Agency'><sup>12<\/sup><\/a><\/span><\/span>. Ce constat est partag\u00e9, bien que de fa\u00e7on moins marqu\u00e9e, aux \u00c9tats-Unis et plus g\u00e9n\u00e9ralement dans la zone OCDE. La tendance est inverse dans les pays du Moyen-Orient, o\u00f9 l\u2019empreinte carbone a augment\u00e9 de 103 points pour 26 points de PIB par habitant seulement sur la m\u00eame p\u00e9riode. \u00c0 l\u2019\u00e9chelle mondiale, depuis 2013, les \u00e9missions de CO2 augmentent l\u00e9g\u00e8rement moins vite que la croissance \u00e9conomique, mais cette tendance n\u2019est n\u00e9anmoins pas assez prononc\u00e9e pour apaiser les esprits. La corr\u00e9lation entre activit\u00e9 \u00e9conomique et impact carbone reste \u00e9lev\u00e9e, comme en t\u00e9moignent les chiffres de 2008, lorsque la crise \u00e9conomique mondiale a brutalement r\u00e9duit la demande \u00e9nerg\u00e9tique mondiale et par l\u00e0 m\u00eame les \u00e9missions de CO2. De m\u00eame,  les projections de l\u2019AIE pr\u00e9sentent un sc\u00e9nario de 50&#160;% d\u2019augmentation de la demande \u00e9nerg\u00e9tique d\u2019ici \u00e0 2040, augmentation due pour moiti\u00e9 \u00e0 l\u2019accroissement des besoins en climatisation, dans les villes et les pays \u00e9mergents notamment&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-13-51127' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/#easy-footnote-bottom-13-51127' title='&lt;a href=&quot;https:\/\/www.iea.org\/futureofcooling&quot;&gt;Future of Cooling. Opportunities for energy-efficient air conditioning&lt;\/a&gt;, International Energy Agency, 15\/05\/2018'><sup>13<\/sup><\/a><\/span><\/span>. La poursuite de cette tendance au d\u00e9couplage relatif repose donc sur le d\u00e9ploiement massif d\u2019\u00e9nergies propres, \u00e0 l\u2019abandon des sources de production d\u2019\u00e9nergie les plus polluantes et le gain constant d\u2019efficacit\u00e9 dans la production tant \u00e9nerg\u00e9tique que manufacturi\u00e8re.<\/p>\n\n\n\n<p>On peut opposer \u00e0 cette hypoth\u00e8se les analyses du rapport du Programme Environnement des Nations Unies de 2011, qui pr\u00e9sente trois sc\u00e9narios d\u2019\u00e9volution de l\u2019intensit\u00e9 \u00e9nerg\u00e9tique de la consommation mondiale. Parmi eux, le sc\u00e9nario 3 prend l\u2019hypoth\u00e8se d\u2019une \u00ab&#160;forte contraction de la consommation {de CO2} dans les pays d\u00e9velopp\u00e9s, qui convergent avec les autres pays&#160;\u00bb, la r\u00e9duction par les pays industrialis\u00e9s de leur consommation par habitant et\u00ab&#160;le maintien du niveau de consommation des autres pays \u00e0 leurs niveaux actuels&#160;\u00bb, pour une consommation moyenne de 6 tonnes de CO2 par habitant. Le rapport juge que ce sc\u00e9nario suppose un si grand nombre de restrictions qu\u2019il peut \u00ab&#160;difficilement \u00eatre envisag\u00e9 comme un objectif strat\u00e9gique potentiel&#160;\u00bb. Plus encore, au-del\u00e0 de sa difficile applicabilit\u00e9 politique, ce sc\u00e9nario maintient un niveau d\u2019\u00e9missions de CO2 trop \u00e9lev\u00e9 pour permettre un infl\u00e9chissement satisfaisant de la trajectoire carbone mondiale&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-14-51127' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/#easy-footnote-bottom-14-51127' title='UNEP (2011) Decoupling natural resource use and environmental impacts from economic growth, communiqu\u00e9 de presse en fran\u00e7ais'><sup>14<\/sup><\/a><\/span><\/span>. Le d\u00e9couplage relatif le plus marqu\u00e9 entre croissance du PIB et impact environnemental ne saurait donc suffire \u00e0 tenir les engagements pris dans l\u2019accord de Paris.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00ab&#160;La corr\u00e9lation entre activit\u00e9 \u00e9conomique et impact carbone reste \u00e9lev\u00e9e, comme en t\u00e9moignent les chiffres de 2008, lorsque la crise \u00e9conomique mondiale a brutalement r\u00e9duit la demande \u00e9nerg\u00e9tique mondiale et par l\u00e0 m\u00eame les \u00e9missions de CO2.&#160;\u00bb<\/p><cite>Cl\u00e9mence P\u00e8legrin<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">6 &#8211; <strong>26 000 milliards de dollars \u00e0 la cl\u00e9<\/strong><\/h3>\n\n\n\n<p>La Commission a choisi d\u2019adopter une approche r\u00e9formiste et incr\u00e9mentale pour appr\u00e9hender le r\u00e9chauffement climatique. Les institutions europ\u00e9ennes et internationales portent en effet un discours de r\u00e9conciliation de la croissance avec la transition \u00e9cologique, comme en t\u00e9moignent les communiqu\u00e9s de presse de l\u2019ONU \u00e0 l\u2019occasion du Sommet Action Climat du 23 septembre 2019. L\u2019opportunit\u00e9 de g\u00e9n\u00e9rer \u00ab&#160;au moins 26 000 milliards de dollars de gains \u00e9conomiques d\u2019ici \u00e0 2030&#160;\u00bb, mise en avant par l\u2019initiative \u00ab&#160;New Climate Economy&#160;\u00bb des Nations Unies&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-15-51127' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/#easy-footnote-bottom-15-51127' title='&lt;a href=&quot;http:\/\/www.newclimateeconomy.report\/2018&quot;&gt;The 2018 Report of the Global Commission on the Economy and Climate&lt;\/a&gt;, New Climate Economy, 08\/2018'><sup>15<\/sup><\/a><\/span><\/span>, est certes un argument de nature \u00e0 inciter les investisseurs \u00e0 acc\u00e9l\u00e9rer le report de leurs portefeuilles vers des actifs \u00ab&#160;verts&#160;\u00bb. Il s\u2019inscrit d\u2019ailleurs dans la droite lign\u00e9e du rapport Stern publi\u00e9 en 2006, qui mettait d\u00e9j\u00e0 en avant le co\u00fbt sup\u00e9rieur de l\u2019inaction par rapport \u00e0 des investissements consentis rapidement en faveur de la transition \u00e9cologique&#160;: selon le rapport, le co\u00fbt du changement climatique pourrait repr\u00e9senter l\u2019\u00e9quivalent de 5&#160;% \u00e0 20&#160;% du produit int\u00e9rieur brut (PIB) mondial de 2005 par an d\u2019ici \u00e0 2050, tandis que la stabilisation des \u00e9missions de CO2 ne co\u00fbterait que l\u2019\u00e9quivalent d\u20191&#160;% du PIB mondial par an&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-16-51127' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/#easy-footnote-bottom-16-51127' title='&lt;a href=&quot;http:\/\/mudancasclimaticas.cptec.inpe.br\/~rmclima\/pdfs\/destaques\/sternreview_report_complete.pdf&quot;&gt;Stern Review on the Economics of Climate Change&lt;\/a&gt;, 2006'><sup>16<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>Dans un contexte o\u00f9 des institutions publiques comme la Banque europ\u00e9enne d\u2019investissement d\u00e9laissent rapidement les \u00e9nergies fossiles et r\u00e9orientent leurs politiques de soutien vers les \u00e9nergies renouvelables, il s\u2019agit davantage d\u2019op\u00e9rer un d\u00e9placement de l\u2019action d\u2019investissement, action toujours motiv\u00e9e par l\u2019attente des m\u00eames formes de r\u00e9tribution. Il est l\u00e9gitime de poser la question d\u2019une part, de la pertinence du <em>business as usual <\/em>pour faire advenir la transition \u00e9cologique \u2013 par l\u2019attractivit\u00e9 financi\u00e8re des actifs, notamment de production d\u2019\u00e9nergie renouvelable \u2013 et d\u2019autre part, la question du p\u00e9rim\u00e8tre d\u2019analyse de l\u2019enjeu, c\u2019est-\u00e0-dire l\u00e0 o\u00f9 la transition \u00e9nerg\u00e9tique et <em>a fortiori<\/em> \u00e9cologique peut occasionner un changement plus profond dans le rapport \u00e0 l\u2019\u00e9nergie, \u00e0 la consommation et \u00e0 la croissance.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">7 &#8211; <strong>Un gramme de CO2 en vaut-il un autre&#160;?<\/strong><\/h3>\n\n\n\n<p>La vision d\u2019Ursula von der Leyen vise effectivement \u00e0 int\u00e9grer l\u2019enjeu \u00e9cologique dans le syst\u00e8me \u00e9conomique et politique tel que nous le connaissons et \u00e0 lui conf\u00e9rer un prix sur le march\u00e9. D\u2019o\u00f9 l\u2019importance conf\u00e9r\u00e9e au march\u00e9 et \u00e0 la taxe. Mais comme le mettent en avant plusieurs \u00e9cologues, comme Gilles Boeuf, il n\u2019est pas pertinent de consid\u00e9rer indiff\u00e9remment des volumes de carbone \u00e9mis ou absorb\u00e9s \u00e0 des endroits diff\u00e9rents du globe. En effet, ces \u00e9missions ont une mat\u00e9rialit\u00e9 qui annule toute \u00ab&#160;fongibilit\u00e9 spatiale&#160;\u00bb. En d\u2019autres termes, la p\u00e9rennit\u00e9 et la sauvegarde d\u2019un \u00e9cosyst\u00e8me ou d\u2019un puits de carbone naturel comme la for\u00eat d\u2019Amazonie ne peut compenser la perte d\u2019un autre \u00e9cosyst\u00e8me distant qui concentre de multiples interactions entre diff\u00e9rentes esp\u00e8ces du vivant. La comptabilit\u00e9 carbone est intrins\u00e8quement ancr\u00e9e dans et par la g\u00e9ographie des \u00e9missions et des absorptions de CO2. Si, \u00e0 l\u2019\u00e9chelle d\u2019une infrastructure, des mesures de compensation \u00e9cologique locales peuvent parfois se r\u00e9v\u00e9ler salvatrices lorsqu\u2019elles sont anticip\u00e9es et m\u00e9thodiques&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-17-51127' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/#easy-footnote-bottom-17-51127' title='&lt;a href=&quot;https:\/\/www.senat.fr\/rap\/r16-517-1\/r16-517-14.html&quot;&gt;Rapport n\u00b0 517 (2016-2017) de M. Ronan DANTEC&lt;\/a&gt;, fait au nom de la commission d&amp;rsquo;enqu\u00eate sur la r\u00e9alit\u00e9 des mesures de compensation des atteintes \u00e0 la biodiversit\u00e9 engag\u00e9es sur des grands projets d\u2019infrastructures, int\u00e9grant les mesures d\u2019anticipation, les \u00e9tudes pr\u00e9alables, les conditions de r\u00e9alisation et leur suivi, remis le 25 avril 2017, S\u00e9nat'><sup>17<\/sup><\/a><\/span><\/span>, elles le sont beaucoup moins lorsqu\u2019elles sont pens\u00e9es \u00e0 l\u2019\u00e9chelle d\u2019un pays ou d\u2019un ensemble r\u00e9gional comme l\u2019Union europ\u00e9enne. Or, la compensation \u00e9cologique est aujourd\u2019hui consid\u00e9r\u00e9e comme un moyen efficace et privil\u00e9gi\u00e9 \u2013 car quantifiable \u2013 de consolider le bilan carbone, comme par exemple \u00e0 travers le d\u00e9veloppement de puits de carbone artificiels, au m\u00eame titre que le d\u00e9veloppement des \u00e9nergies renouvelables.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00ab&#160;La comptabilit\u00e9 carbone est intrins\u00e8quement ancr\u00e9e dans et par la g\u00e9ographie des \u00e9missions et des absorptions de CO2.&#160;\u00bb<\/p><cite>Cl\u00e9mence P\u00e8legrin<\/cite><\/blockquote><\/figure>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-medium\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/02\/GEG_monde_environnement_performance-1.png\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"3646\"\n        data-pswp-height=\"2881\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/02\/GEG_monde_environnement_performance-1-330x261.png\"\r\n                media=\"(max-width:  374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/02\/GEG_monde_environnement_performance-1-690x545.png\"\r\n                media=\"(max-width:  989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/02\/GEG_monde_environnement_performance-1-990x782.png\"\r\n                media=\"(max-width: 1319px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/02\/GEG_monde_environnement_performance-1-690x545.png\"\r\n                media=\"(max-width: 1599px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/02\/GEG_monde_environnement_performance-1-990x782.png\"\r\n                media=\"(min-width: 1600px)\" \/>\r\n                <img decoding=\"async\" alt=\"L&#039;indice de performance environnementale, 2019\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/02\/GEG_monde_environnement_performance-1-125x99.png\" \/>\r\n        <\/picture>\r\n                            \n            <\/a>\n<\/figure>\n\n\n<p>Se pose alors la question de la pertinence d\u2019allouer un prix au vivant au m\u00eame titre qu\u2019une commodit\u00e9, c\u2019est \u00e0 dire d\u2019isoler et de consid\u00e9rer les \u00e9l\u00e9ments qui le composent comme interchangeables et \u00e9quivalents par-del\u00e0 la distance, tout en mesurant leurs b\u00e9n\u00e9fices indiff\u00e9remment de l\u2019\u00e9cosyst\u00e8me localis\u00e9 dans lequel ils s\u2019inscrivent. Selon <a href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/06\/03\/vers-la-transition-conversation-avec-rob-hopkins\/\">Rob Hopkins, fondateur du r\u00e9seau Transition dans un entretien donn\u00e9 au Grand Continent<\/a>, les sc\u00e9narios de neutralit\u00e9 carbone reposent sur une hypoth\u00e8se industrielle et technologique trop incertaine&#160;: \u00ab&#160;quand on regarde les objectifs de r\u00e9duction des \u00e9missions de CO2 \u2013 m\u00eame dans l\u2019Union europ\u00e9enne avec l\u2019objectif de 40&#160;% de r\u00e9duction avant 2030 \u2013 ils s\u2019appuient tous sur le concept de \u00ab&#160;technologies \u00e0 \u00e9missions n\u00e9gatives&#160;\u00bb avec l\u2019id\u00e9e qu\u2019on investira \u00e0 l\u2019avenir dans une machine capable de pi\u00e9ger le CO2 de l\u2019atmosph\u00e8re en grande quantit\u00e9, ce qui n\u2019existe pas encore. Et tant que nous continuerons \u00e0 nous leurrer avec ces choses qui ne sont pas une r\u00e9alit\u00e9, nous ne prendrons pas les mesures audacieuses et innovantes que nous devrions.&#160;\u00bb<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-medium\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/01\/Lindice-des-performances-environnementales-en-Europe.png\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"690\"\n        data-pswp-height=\"634\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/01\/Lindice-des-performances-environnementales-en-Europe-330x303.png\"\r\n                media=\"(max-width:  374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/01\/Lindice-des-performances-environnementales-en-Europe.png\"\r\n                media=\"(max-width:  989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/01\/Lindice-des-performances-environnementales-en-Europe.png\"\r\n                media=\"(max-width: 1319px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/01\/Lindice-des-performances-environnementales-en-Europe.png\"\r\n                media=\"(max-width: 1599px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/01\/Lindice-des-performances-environnementales-en-Europe.png\"\r\n                media=\"(min-width: 1600px)\" \/>\r\n                <img decoding=\"async\" alt=\"Les pays europ\u00e9ens, bon indice de performance environnementale\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2020\/01\/Lindice-des-performances-environnementales-en-Europe-125x115.png\" \/>\r\n        <\/picture>\r\n                            \n            <\/a>\n<\/figure>\n\n\n<p>La transition \u00e9cologique n\u2019est donc pas r\u00e9ductible \u00e0 l\u2019\u00e9tat d\u2019un bilan carbone global, et il n\u2019est pas ais\u00e9 de mesurer pr\u00e9cis\u00e9ment le solde de ce dernier, outre les indicateurs bien connus des \u00e9missions de CO2 induites par la combustion d\u2019\u00e9nergies fossiles et par la d\u00e9forestation. D\u00e8s lors, la transition envisag\u00e9e sous l\u2019angle d\u2019un corpus r\u00e9glementaire et normatif destin\u00e9 \u00e0 rationaliser l\u2019utilisation des ressources appara\u00eet insuffisant au regard des limites structurelles qu\u2019elle met en lumi\u00e8re, comme le soulignait d\u00e9j\u00e0 le rapport de Donella et Dennis Meadows <em>The Limits to Growth<\/em> en 1972&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-18-51127' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/#easy-footnote-bottom-18-51127' title='Donella Meadows, Dennis Meadows, Jorgen Randers, &lt;em&gt;Les limites \u00e0 la croissance&lt;\/em&gt;, pr\u00e9face de Jean-Marc Jancovici, \u00e9ditions Rue de l\u2019Echiquier, parution le 24 mai 2012'><sup>18<\/sup><\/a><\/span><\/span>. L\u00e0 o\u00f9 l\u2019abondance \u00e9nerg\u00e9tique et mat\u00e9rielle de l\u2019\u00e9poque moderne a pr\u00e9cipit\u00e9 le r\u00e9chauffement climatique, la question fondamentale r\u00e9side-t-elle vraiment dans l\u2019optimisation de l\u2019\u00e9quation ressource-durabilit\u00e9&#160;? La politique \u00e9cologique telle qu\u2019envisag\u00e9e aujourd\u2019hui par l\u2019Europe n\u2019est-elle pas une r\u00e9ponse \u00ab&#160;pragmatique&#160;\u00bb mais fondamentalement consensuelle au statu quo de l\u2019\u00e9conomie de croissance, \u00ab&#160;verte&#160;\u00bb ou pas&#160;? Comme le reconnaissait <a href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/03\/13\/nous-avons-rencontre-pierre-larrouturou\/\">Pierre Larrouturou dans un entretien au Grand Continent<\/a>, \u00ab&#160;l\u2019expression \u00ab&#160;croissance verte&#160;\u00bb est ambig\u00fce. On a l\u2019impression que l\u2019on continue sur le m\u00eame mod\u00e8le en mettant un peu de verdure. Mais ce n\u2019est pas le cas. De nombreux minist\u00e8res pensent \u00e0 tort que la croissance seule est la solution, mais pour le plus grand nombre, le progr\u00e8s ne s\u2019arr\u00eate pas \u00e0 cela. Au lieu d\u2019objectifs de croissance en taille, il faut plut\u00f4t penser en termes de relations, d\u2019interactions. C\u2019est ce que montrait d\u00e9j\u00e0 Jacques Delors en 1970 avec ses Indicateurs sociaux&#160;: le PIB ne veut rien dire, des activit\u00e9s qui d\u00e9t\u00e9riorent le bien-\u00eatre des populations peuvent tr\u00e8s bien faire augmenter le PIB&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-19-51127' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/#easy-footnote-bottom-19-51127' title='&lt;a href=&quot;https:\/\/legrandcontinent.eu\/fr\/2019\/03\/13\/nous-avons-rencontre-pierre-larrouturou&quot;&gt;https:\/\/legrandcontinent.eu\/fr\/2019\/03\/13\/nous-avons-rencontre-pierre-larrouturou&lt;\/a&gt;\/'><sup>19<\/sup><\/a><\/span><\/span>. En maintenant croissance et b\u00e9n\u00e9fices comme thermom\u00e8tres de la sant\u00e9 des soci\u00e9t\u00e9s, ne prolonge-t-on pas les \u00ab&#160;f\u00e9tiches h\u00e9rit\u00e9s de l\u2019\u00e2ge industriel&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-20-51127' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/#easy-footnote-bottom-20-51127' title='voir Charbonnier, Pierre. \u00ab&amp;#160;Les formes de l\u2019affect \u00e9cologiste. Des attachements \u00e0 la critique&amp;#160;\u00bb, Esprit, vol. janvier-f\u00e9vrier, no. 1, 2018, pp. 130-144.'><sup>20<\/sup><\/a><\/span><\/span>&#160;?<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00ab&#160;La transition envisag\u00e9e sous l\u2019angle d\u2019un corpus r\u00e9glementaire et normatif destin\u00e9 \u00e0 rationaliser l\u2019utilisation des ressources appara\u00eet insuffisant au regard des limites structurelles qu\u2019elle met en lumi\u00e8re.&#160;\u00bb<\/p><cite>Cl\u00e9mence P\u00e8legrin<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">8 &#8211; <strong>Perspectives<\/strong><\/h3>\n\n\n\n<p>Si le d\u00e9couplage est une id\u00e9e hypoth\u00e9tiquement juste consid\u00e9r\u00e9e \u00e0 l\u2019aune des vingt derni\u00e8res ann\u00e9es dans le contexte europ\u00e9en, comme le rapport entre croissance du PIB et solde d&rsquo;\u00e9missions carbone issues de la production d&rsquo;\u00e9nergie sur un territoire donn\u00e9, on comprend bien que sa coh\u00e9rence interne d\u00e9pend de beaucoup de pr\u00e9cautions. On occulte d\u00e8s lors les d\u00e9localisations d\u2019\u00e9missions, la couverture partielle de l\u2019empreinte carbone et la divergence d\u2019int\u00e9r\u00eats entre secteurs \u00e9conomiques.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00ab&#160;L\u2019Europe porte bien une partie cons\u00e9quente du bilan carbone historique de la plan\u00e8te, mais ses faibles ressources \u00e9nerg\u00e9tiques domestiques et son \u00e9conomie tertiaris\u00e9e favorisent la posture du  bon \u00e9l\u00e8ve dot\u00e9 d\u2019un pouvoir de prescripteur normatif au sujet d\u2019un enjeu dont elle n\u2019a pourtant pas le monopole du risque.&#160;\u00bb<\/p><cite>Cl\u00e9mence P\u00e8legrin<\/cite><\/blockquote><\/figure>\n\n\n\n<p>L\u2019Europe porte bien une partie cons\u00e9quente du bilan carbone historique de la plan\u00e8te, mais ses faibles ressources \u00e9nerg\u00e9tiques domestiques et son \u00e9conomie tertiaris\u00e9e favorisent la posture du  bon \u00e9l\u00e8ve dot\u00e9 d\u2019un pouvoir de prescripteur normatif au sujet d\u2019un enjeu dont elle n\u2019a pourtant pas le monopole du risque. Quand bien m\u00eame l\u2019id\u00e9e de d\u00e9couplage serait juste, et propre aux \u00e9conomies d\u00e9velopp\u00e9es et post-industrielles, il est difficilement concevable que des pays comme la Chine ou l\u2019Inde, qui concentrent la majorit\u00e9 de la demande \u00e9nerg\u00e9tique et de la croissance d\u00e9mographique des prochaines d\u00e9cennies, l\u2019adoptent suffisamment t\u00f4t pour respecter le temps imparti dans la lutte contre le changement climatique, estim\u00e9 \u00e0 12 ans selon le GIEC dans son rapport de 2018&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-21-51127' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/#easy-footnote-bottom-21-51127' title='&lt;a href=&quot;https:\/\/www.wri.org\/blog\/2018\/10\/according-new-ipcc-report-world-track-exceed-its-carbon-budget-12-years&quot;&gt;\u201cAccording to New IPCC Report, the World Is on Track to Exceed its \u201cCarbon Budget\u201d in 12 Years\u201d&lt;\/a&gt;, Levin K., World Resources Institute, 07\/10\/2018'><sup>21<\/sup><\/a><\/span><\/span>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comprendre l&rsquo;importance de l&rsquo;\u00e9cologie politique en Europe. En huit points.<\/p>\n","protected":false},"author":10,"featured_media":51238,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-angles.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":0,"_lgc_tts_audio_url":"","_lgc_tts_voice":"","_lgc_tts_publish":false,"_lgc_tts_history_item_id":"","_lgc_tts_generated_at":"","_lgc_tts_status":"","_lgc_tts_error":"","footnotes":""},"categories":[1730],"tags":[],"staff":[1611],"editorial_format":[4944],"serie":[],"audience":[],"geo":[1917],"class_list":["post-51127","post","type-post","status-publish","format-standard","hentry","category-energie-et-environnement","staff-clemence-pelegrin","editorial_format-actu-longues","geo-europe"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":51238,"excerpt":"Comprendre l'importance de l'\u00e9cologie politique en Europe. En huit points.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00c9cologie ou croissance : faut-il choisir\u00a0? | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9cologie ou croissance : faut-il choisir\u00a0? | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Comprendre l&#039;importance de l&#039;\u00e9cologie politique en Europe. En huit points.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-01T15:11:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-22T16:13:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Burgoyne-Diller.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1523\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matheo Malik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheo Malik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"22 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/\",\"name\":\"\u00c9cologie ou croissance : faut-il choisir\u00a0? | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Burgoyne-Diller.jpg\",\"datePublished\":\"2019-11-01T15:11:00+00:00\",\"dateModified\":\"2020-02-22T16:13:50+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Burgoyne-Diller.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Burgoyne-Diller.jpg\",\"width\":1200,\"height\":1523},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9cologie ou croissance&#160;: faut-il choisir&#160;?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\",\"name\":\"Matheo Malik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"caption\":\"Matheo Malik\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9cologie ou croissance : faut-il choisir\u00a0? | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9cologie ou croissance : faut-il choisir\u00a0? | Le Grand Continent","og_description":"Comprendre l'importance de l'\u00e9cologie politique en Europe. En huit points.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/","og_site_name":"Le Grand Continent","article_published_time":"2019-11-01T15:11:00+00:00","article_modified_time":"2020-02-22T16:13:50+00:00","og_image":[{"width":1200,"height":1523,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Burgoyne-Diller.jpg","type":"image\/jpeg"}],"author":"Matheo Malik","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Matheo Malik","Dur\u00e9e de lecture estim\u00e9e":"22 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/","url":"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/","name":"\u00c9cologie ou croissance : faut-il choisir\u00a0? | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Burgoyne-Diller.jpg","datePublished":"2019-11-01T15:11:00+00:00","dateModified":"2020-02-22T16:13:50+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Burgoyne-Diller.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Burgoyne-Diller.jpg","width":1200,"height":1523},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/11\/01\/ecologie-ou-croissance-faut-il-choisir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c9cologie ou croissance&#160;: faut-il choisir&#160;?"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45","name":"Matheo Malik","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","caption":"Matheo Malik"}}]}},"lgc_categories":[{"id":1730,"name":"\u00c9nergie et environnement","slug":"energie-et-environnement"}],"lgc_author":{"id":1611,"name":"Cl\u00e9mence P\u00e8legrin","slug":"clemence-pelegrin","description":"Cl\u00e9mence Pelegrin est charg\u00e9e de mission \u00e0 la Commission de r\u00e9gulation de l\u2019\u00e9nergie et co-r\u00e9dactrice en chef de la revue GREEN. Elle a notamment travaill\u00e9 comme consultante sp\u00e9cialis\u00e9e en \u00e9nergie et infrastructures chez PwC et comme analyste investissement chez Amundi Transition Energ\u00e9tique","first_name":"Cl\u00e9mence","last_name":"P\u00e8legrin","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/09\/gc-pelegrin.png","width":918,"height":882,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Burgoyne-Diller.jpg","width":1200,"height":1523,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/11\/Burgoyne-Diller.jpg","width":1200,"height":1523,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/51127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=51127"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/51127\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/51238"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=51127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=51127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=51127"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=51127"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=51127"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=51127"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=51127"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=51127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}