{"id":50944,"date":"2019-10-31T14:06:17","date_gmt":"2019-10-31T13:06:17","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=50944"},"modified":"2019-10-31T14:12:29","modified_gmt":"2019-10-31T13:12:29","slug":"le-coeur-de-langleterre","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2019\/10\/31\/le-coeur-de-langleterre\/","title":{"rendered":"Le c\u0153ur de l&rsquo;Angleterre"},"content":{"rendered":"\n<p>On tient de Coe lui-m\u00eame qu\u2019il a voulu \u00e9crire sur le Brexit&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-50944' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/10\/31\/le-coeur-de-langleterre\/#easy-footnote-bottom-1-50944' title='Voir le Pri\u00e8re d\u2019ins\u00e9rer plac\u00e9 \u00e0 la fin du roman.'><sup>1<\/sup><\/a><\/span><\/span>&#160;; qu\u2019il a voulu parler de l\u2019Angleterre des ann\u00e9es Brexit et de souvenirs d\u2019avant ces ann\u00e9es-l\u00e0&#160;; que ses amis et ses lecteurs lui ont conseill\u00e9 de poursuivre l\u2019histoire de la famille Trotter, laiss\u00e9e dans <em>Bienvenue au Club<\/em>, de Benjamin, de Lois, de leur p\u00e8re et de leurs enfants&#160;; et d\u2019une sombre histoire de famille qui ressurgit parfois du pass\u00e9. Aussit\u00f4t fait, les voici un soir de l\u2019an de gr\u00e2ce 2010, \u00e0 l\u2019enterrement de la m\u00e8re&#160;: disputes silencieuses en famille, BBC 4 en bruit de fond, alcool, maisons de campagne, amis d\u2019enfance. Voil\u00e0 le d\u00e9cor psychologique pos\u00e9, avant m\u00eame le germe d\u2019une histoire.<\/p>\n\n\n\n<p>Cette ouverture n\u2019est pas trompeuse&#160;: pas d\u2019autre intrigue que cette vie des personnages entre 2010 et 2018, singuli\u00e8rement orient\u00e9e autour de la figure de Benjamin Trotter, ermite \u00e9crivain \u2013 peut-\u00eatre, ou peut-\u00eatre pas, avatar de Coe lui-m\u00eame. Et pas d\u2019autre morceau de bravoure que ces deux prouesses&#160;: parler du Brexit, et en parler \u00e0 partir d\u2019intimit\u00e9s individuelles.<\/p>\n\n\n\n<p>Historiographe, Coe invente d\u2019abord, ou plut\u00f4t impose, une chronologie du Brexit, il qualifie une p\u00e9riode, il arr\u00eate le temps et l\u2019appelle Brexit. Tout ce qu\u2019on lit est encadr\u00e9 dans une p\u00e9riode chronologique donn\u00e9e&#160;; chaque d\u00e9tail a son importance calendaire, m\u00eame si l\u2019attention n\u2019est pas centr\u00e9e autour du temps. Coe ne fait pas la chronique du Brexit, mais il \u00e9crit sur le n\u00e9gatif de cette chronique.<\/p>\n\n\n\n<p>Le destin de ses personnages suit les changements politiques. En cela c\u2019est un roman politique, o\u00f9 le politique fait irruption, en disant ou en taisant son nom, avec plus ou moins de fracas, mais, et c\u2019est essentiel, dans l\u2019intimit\u00e9 des personnages. Le trait n\u2019est jamais <em>trop <\/em>gros&#160;; ou lorsqu\u2019on croit qu\u2019il l\u2019est, c\u2019est Coe qui nous amuse avec ces figures de farce, ces caricatures grossi\u00e8res, comme le communiquant Nigel, qui ignore le terme de <em>Brexit <\/em>\u2013 et ne conna\u00eet que le <em>Brixit<\/em> \u2013 ou encore Lionel Hampshire, figure de l\u2019\u00e9crivain populaire qui fr\u00e9quente les croisi\u00e8res. Coe n\u2019a pas les ambitions d\u2019Hugo&#160;: il ne fait pas la fiction de l\u2019Histoire, il est plus discret que cela. Le politique arrive dans la vie de Ian avec un passage \u00e0 tabac et un s\u00e9jour \u00e0 l\u2019h\u00f4pital, il arrive dans la vie de Sophie par des conversations avec sa belle-m\u00e8re&#160;; le politique, au fond, n\u2019a jamais quitt\u00e9 les Trotter, il les poursuit depuis longtemps. M\u00eame Benjamin, m\u00eame l\u2019ermite, finira par recueillir chez lui Charlie le clown, victime collat\u00e9rale du Brexit. Dans la vie de ce Benjamin Trotter, personnage houellebecquien au d\u00e9but du roman, la grande histoire s\u2019introduit d\u2019ailleurs dans la petite. Lorsque Houellebecq parle de la soci\u00e9t\u00e9 \u00e0 travers une trag\u00e9die personnelle, il ne se fie jamais \u00e0 la trame des \u00e9v\u00e9nements r\u00e9els de l\u2019histoire&#160;; chez Coe, et \u00e0 la loupe du personnage de Benjamin, \u00e9merge la possibilit\u00e9 d\u2019expliquer une \u00e9poque car il y a le sentiment diffus que, dans l\u2019Angleterre des ann\u00e9es Brexit, <em>il est en train de se passer quelque chose<\/em>.<\/p>\n\n\n\n<p>Il y aurait beaucoup \u00e0 dire sur l\u2019art de la narration de Jonathan Coe, et sa ma\u00eetrise de la construction des personnages, mais allons \u00e0 l\u2019essentiel&#160;: le Brexit n\u2019est pas <em>le<\/em> th\u00e8me de <em>Middle England<\/em>. Le th\u00e8me central du livre est la nostalgie. Leitmotiv touchant et po\u00e9tique, la voix aigu\u00eb et d\u00e9su\u00e8te de Shirley Collins fredonnant <em>Adieu To Old England<\/em> r\u00e9sonne dans \u00ab&#160;le moulin&#160;\u00bb, retraite tranquille o\u00f9 Benjamin Trotter peut recevoir, songer au pass\u00e9 ou \u00e9crire un roman fleuve au bord d\u2019une rivi\u00e8re tranquille. <em>Adieu To Old England<\/em> est cette ritournelle essentielle, semble-t-il, \u00e0 l\u2019\u00e9crivain, pour imprimer sur ses personnages la marque du passage du temps. Certains personnages du roman ont quarante ans de plus que les protagonistes d\u2019<em>Expo 58<\/em> ou de <em>Bienvenue au Club<\/em>. L\u2019\u00e2ge comme personnage&#160;: on voit vite comment Coe peut mettre \u00e0 profit cette figure dans l\u2019\u00e9criture du Brexit \u2013 il n\u2019y manque pas. Dans le temps biographique de la famille, la s\u00e9quence \u00ab&#160;Brexit&#160;\u00bb est encadr\u00e9e par la mort des parents.<\/p>\n\n\n\n<p>Reprenant les codes du feuilleton, Coe nourrit son lecteur \u00e0 la becqu\u00e9e, chapitre apr\u00e8s chapitre, sayn\u00e8te apr\u00e8s sayn\u00e8te&#160;: formellement, la geste des Trotter a des airs de Commedia dell\u2019Arte transpos\u00e9e dans l\u2019Angleterre post-industrielle. Des clowns s\u2019y livrent bataille&#160;; on s\u2019y pr\u00e9nomme Coriandre ou Aneeqa&#160;; on y meurt de vieillesse en bateau&#8230; Caricatures donc, mais fines. Il faut surtout saluer, outre l\u2019\u00e9conomie narrative parfaitement ma\u00eetris\u00e9e, la pr\u00e9cision dans les dialogues \u2013 g\u00e9n\u00e9ralement bien rendue par Jos\u00e9e Kamoun dans le texte fran\u00e7ais. Des dialogues dr\u00f4les et si bien men\u00e9s qu\u2019ils permettent \u00e0 l\u2019auteur de ne pas s\u2019embarrasser de descriptions physiques ou psychologiques des protagonistes. Comme certains personnages de la <em>Recherche<\/em>, les habitants du <em>C\u0153ur de l\u2019Angleterre <\/em>sont essentialis\u00e9s par leurs paroles, pas par les explications sociologiques de l\u2019auteur.<\/p>\n\n\n\n<p>La force de Coe est de ne pas forcer le Brexit. Il se sert en cela d\u2019une structure extr\u00eamement classique, qui gomme toutes les asp\u00e9rit\u00e9s formelles et narratives. Chez Coe \u2013 comme chez Boris Johnson, connaissance ou fant\u00f4me de jeunesse de Benjamin \u2013 c\u2019est la virtuosit\u00e9 de cette composition de premier de la classe qui vous prend par surprise. Il faut \u00eatre classique pour dire (ou faire) ce qui ne l\u2019est pas. <em>Middle England<\/em> n\u2019est pas un roman \u00e9l\u00e9gant ou audacieux, c\u2019est un roman poli, liss\u00e9, bien pens\u00e9, net comme le fronton d\u2019une maison georgienne et clair comme le parcours du British Museum&#160;; par bien des aspects, c\u2019est un roman facile&#160;; l\u2019assaisonnement y est particuli\u00e8rement juste. Mais c\u2019est de cette justesse virtuose seule que peut na\u00eetre la folie, et par suite, l\u2019\u00e9motion.<\/p>\n\n\n\n<p>L\u2019id\u00e9e de base est simple&#160;: aligner une succession horizontale d\u2019\u00e9v\u00e9nements (\u00e9meutes de 2011, Jeux Olympiques de Londres en 2012, campagne de 2015) avec un ensemble de personnages entretenant entre eux des liens amicaux ou familiaux. Peu de d\u00e9paysement, peu de personnages originaux&#160;; des figures attendues, et dont l\u2019exactitude pr\u00e9sente tout l\u2019int\u00e9r\u00eat. Certaines, comme Ian et sa m\u00e8re, pr\u00e9sent\u00e9s \u00e0 travers Sophie \u2013 elle a des airs, mais c\u2019est tr\u00e8s subjectif, de Sally Rooney \u2013, sont plus complexes. Beaucoup de rire, mais une profondeur tragique, marqu\u00e9e par le passage du temps et le th\u00e8me de la nostalgie. Le <em>c\u0153ur de l\u2019Angleterre<\/em> ne s\u2019est pas arr\u00eat\u00e9 de battre, mais il r\u00e9sonne depuis une autre \u00e9poque \u2013 laquelle, au juste&#160;? aucun des personnages n\u2019a la r\u00e9ponse. L\u2019une des trames de l\u2019intrigue, peut-\u00eatre la principale, puisque le suspense y est instill\u00e9 du d\u00e9but \u00e0 la fin, donne un condens\u00e9 du monde de Coe&#160;: il s\u2019agit de la rivalit\u00e9 de deux clowns, culminant en combat physique entre l\u2019un d\u2019eux <em>brexiter<\/em> et l\u2019autre, <em>remainer<\/em>. Bien s\u00fbr les choses ne sont jamais nomm\u00e9es telles quelles. Ce serait pr\u00e9tendre comprendre le Brexit en rangeant les gens dans des colonnes. Coe ne fait pas de sociologie \u00e9lectorale, ni de science politique, il fait de la peinture, il peint les absents du tableau, coloriste d\u2019entre les lignes du <em>Daily Mail<\/em> ou du <em>Telegraph<\/em>.<\/p>\n\n\n\n<p>Il faut dire enfin la grande qualit\u00e9 du livre&#160;: l\u2019auteur de la fiction y cr\u00e9e un monde, au total assez chaleureux, agr\u00e9able s\u00e9jour au lecteur qui n\u2019en conna\u00eet pourtant ni trop l\u2019\u00e9poque, ni trop l\u2019aire. Ce lieu, c\u2019est le <em>c\u0153ur de l\u2019Angleterre<\/em>, cette <em>middle England<\/em>, c\u2019est-\u00e0-dire un endroit de nostalgie&#160;: tant\u00f4t un caf\u00e9 de la station Temple, tant\u00f4t un moulin le long d\u2019une rivi\u00e8re, dans la campagne de Birmingham, ou un abri de jardin en plastique dans un immense magasin d\u2019ext\u00e9rieur. Dans ce lieu agr\u00e9able o\u00f9 Coe, anglais par les mani\u00e8res, russe par la truculence, et grec par l\u2019hospitalit\u00e9, nous invite \u00e0 s\u00e9journer, le Brexit arrive, sans qu\u2019on s\u2019en rende tout \u00e0 fait compte. Le Brexit arrive sans qu\u2019on en parle, sans que l\u2019on en rab\u00e2che les tenants et les aboutissements. Le Brexit point comme le soleil sur une peinture impressionniste.<\/p>\n\n\n\n<p>Alors en d\u00e9finitive, o\u00f9 nous emm\u00e8ne cet auteur discret, et rieur du coin des l\u00e8vres&#160;? Nul doute que, compte tenu de l\u2019amplitude des personnages d\u00e9crits \u2013 dans et hors de la famille Trotter \u2013 chaque lecteur pourra s\u2019identifier \u00e0 des personnages diff\u00e9rents. On veut croire que l\u2019auteur est attach\u00e9 \u00e0 Benjamin et \u00e0 Lois, tous deux \u00e2g\u00e9s \u00e0 la fin du roman. Mais on a particuli\u00e8rement aim\u00e9 le traitement de la g\u00e9n\u00e9ration suivante, incarn\u00e9e par le personnage de Sophie, ni\u00e8ce de Benjamin et figure europ\u00e9enne par excellence \u2013 elle travaille sur Dumas, tombe amoureuse \u00e0 Marseille, r\u00e9fl\u00e9chit \u00e0 sa vie sur une croisi\u00e8re en mer du Nord. On la retrouve \u00e0 la fin du roman \u2013 apr\u00e8s le r\u00e9f\u00e9rendum \u2013 dans la deuxi\u00e8me retraite Trotter, en Provence cette fois. Le Brexit et les effets diffus des d\u00e9bats politiques dans la soci\u00e9t\u00e9 \u2013 savamment distill\u00e9s \u2013 lui auront co\u00fbt\u00e9 son mariage\u2026 On aime voir dans Sophie, comme chez Coriandre \u2013 fille d\u2019un \u00e9ditorialiste d\u00e9sabus\u00e9 qui d\u00e9ambule dans sa maison de Chelsea, autre symbole de la nouvelle g\u00e9n\u00e9ration, victime collat\u00e9rale du Brexit en quelque sorte, mais pas pour autant \u00e9pargn\u00e9e par Coe \u2013 le personnage clef du <em>C\u0153ur de l\u2019Angleterre<\/em>&#160;: sa personnalit\u00e9, son r\u00e9seau et son parcours accident\u00e9 expliquent l\u2019inexplicable par les d\u00e9tours astucieux de la fiction.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Expliquer l&rsquo;inexplicable par la fiction&#160;&#160;: Coe diss\u00e8que le Brexit.<\/p>\n","protected":false},"author":10,"featured_media":50948,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-reviews.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":0,"footnotes":""},"categories":[1728],"tags":[],"staff":[1550],"editorial_format":[4868],"serie":[],"audience":[],"geo":[547],"class_list":["post-50944","post","type-post","status-publish","format-standard","hentry","category-arts","staff-matheo-malik","editorial_format-comptes-rendus","geo-nordiques"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":50948,"excerpt":"Expliquer l'inexplicable par la fiction : Coe diss\u00e8que le Brexit.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le c\u0153ur de l&#039;Angleterre | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/10\/31\/le-coeur-de-langleterre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le c\u0153ur de l&#039;Angleterre | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Expliquer l&#039;inexplicable par la fiction&#160;: Coe diss\u00e8que le Brexit.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2019\/10\/31\/le-coeur-de-langleterre\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-31T13:06:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-31T13:12:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/10\/Coeur-de-langleterre.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1654\" \/>\n\t<meta property=\"og:image:height\" content=\"2421\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matheo Malik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheo Malik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/10\/31\/le-coeur-de-langleterre\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/10\/31\/le-coeur-de-langleterre\/\",\"name\":\"Le c\u0153ur de l'Angleterre | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/10\/31\/le-coeur-de-langleterre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/10\/31\/le-coeur-de-langleterre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/10\/Coeur-de-langleterre.jpg\",\"datePublished\":\"2019-10-31T13:06:17+00:00\",\"dateModified\":\"2019-10-31T13:12:29+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/10\/31\/le-coeur-de-langleterre\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2019\/10\/31\/le-coeur-de-langleterre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/10\/31\/le-coeur-de-langleterre\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/10\/Coeur-de-langleterre.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/10\/Coeur-de-langleterre.jpg\",\"width\":1654,\"height\":2421},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/10\/31\/le-coeur-de-langleterre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le c\u0153ur de l&rsquo;Angleterre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\",\"name\":\"Matheo Malik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"caption\":\"Matheo Malik\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le c\u0153ur de l'Angleterre | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2019\/10\/31\/le-coeur-de-langleterre\/","og_locale":"fr_FR","og_type":"article","og_title":"Le c\u0153ur de l'Angleterre | Le Grand Continent","og_description":"Expliquer l'inexplicable par la fiction&#160;: Coe diss\u00e8que le Brexit.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2019\/10\/31\/le-coeur-de-langleterre\/","og_site_name":"Le Grand Continent","article_published_time":"2019-10-31T13:06:17+00:00","article_modified_time":"2019-10-31T13:12:29+00:00","og_image":[{"width":1654,"height":2421,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/10\/Coeur-de-langleterre.jpg","type":"image\/jpeg"}],"author":"Matheo Malik","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Matheo Malik","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/10\/31\/le-coeur-de-langleterre\/","url":"https:\/\/legrandcontinent.eu\/fr\/2019\/10\/31\/le-coeur-de-langleterre\/","name":"Le c\u0153ur de l'Angleterre | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/10\/31\/le-coeur-de-langleterre\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/10\/31\/le-coeur-de-langleterre\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/10\/Coeur-de-langleterre.jpg","datePublished":"2019-10-31T13:06:17+00:00","dateModified":"2019-10-31T13:12:29+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/10\/31\/le-coeur-de-langleterre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2019\/10\/31\/le-coeur-de-langleterre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/10\/31\/le-coeur-de-langleterre\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/10\/Coeur-de-langleterre.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/10\/Coeur-de-langleterre.jpg","width":1654,"height":2421},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/10\/31\/le-coeur-de-langleterre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Le c\u0153ur de l&rsquo;Angleterre"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45","name":"Matheo Malik","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","caption":"Matheo Malik"}}]}},"lgc_categories":[{"id":1728,"name":"Arts","slug":"arts"}],"lgc_author":{"id":1550,"name":"Math\u00e9o Malik","slug":"matheo-malik","description":"<span style=\"font-weight: 400\">Math\u00e9o Malik, r\u00e9dacteur en chef du Grand Continent, est secr\u00e9taire g\u00e9n\u00e9ral du Groupe d\u2019\u00e9tudes g\u00e9opolitiques.<\/span>","first_name":"Math\u00e9o","last_name":"Malik","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/08\/malik.png","width":521,"height":521,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/10\/Coeur-de-langleterre.jpg","width":1654,"height":2421,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/10\/Coeur-de-langleterre.jpg","width":1654,"height":2421,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/50944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=50944"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/50944\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/50948"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=50944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=50944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=50944"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=50944"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=50944"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=50944"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=50944"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=50944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}