{"id":4962,"date":"2018-07-01T22:00:19","date_gmt":"2018-07-01T20:00:19","guid":{"rendered":"https:\/\/lldl.eu\/?p=4962"},"modified":"2019-05-23T16:45:13","modified_gmt":"2019-05-23T14:45:13","slug":"exercices-militaires-entre-legypte-la-grece-et-chypre-en-mediterranee-orientale","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2018\/07\/01\/exercices-militaires-entre-legypte-la-grece-et-chypre-en-mediterranee-orientale\/","title":{"rendered":"Exercices militaires entre l&rsquo;\u00c9gypte, la Gr\u00e8ce et Chypre en M\u00e9diterran\u00e9e orientale"},"content":{"rendered":"\n<p><em>Cr\u00e8te<\/em>. Les forces arm\u00e9es et navales de l&rsquo;\u00c9gypte, de la Gr\u00e8ce et de Chypre ont entam\u00e9 le 25 juin une s\u00e9rie d&rsquo;exercices conjoints qui dureront plusieurs jours, au sud de l&rsquo;\u00eele grecque de Cr\u00e8te (<strong>4<\/strong>). Selon le minist\u00e8re \u00e9gyptien de la d\u00e9fense, les exercices militaires s&rsquo;inscrivent dans le cadre des op\u00e9rations \u00ab&#160;Medusa 6&#160;\u00bb, qui comprennent diverses activit\u00e9s, telles que la planification et la gestion d&rsquo;op\u00e9rations navales et a\u00e9riennes conjointes, ainsi que l&rsquo;\u00e9change d&rsquo;informations et d&rsquo;exp\u00e9riences de terrain entre les diff\u00e9rentes forces impliqu\u00e9es dans ces exercices, afin d&rsquo;accro\u00eetre leur exp\u00e9rience et leur expertise en termes d&rsquo;efficacit\u00e9, de pr\u00e9vention et de combat (<strong>1<\/strong>).<\/p>\n\n\n\n<p>Les exercices en question s&rsquo;inscrivent dans le cadre des accords de partenariat militaire et de coop\u00e9ration en mati\u00e8re de s\u00e9curit\u00e9 sign\u00e9s ces derni\u00e8res ann\u00e9es par l&rsquo;\u00c9gypte avec les pays c\u00f4tiers europ\u00e9ens (<strong>2<\/strong>). Au-del\u00e0 des exercices, les initiatives d\u00e9montrent une fois de plus l&rsquo;importance de l&rsquo;axe tripartite en M\u00e9diterran\u00e9e orientale, compos\u00e9 de l&rsquo;\u00c9gypte, de Chypre et de la Gr\u00e8ce qui, depuis 2014, c&rsquo;est-\u00e0-dire depuis que plusieurs puits <em>offshore<\/em> ont \u00e9t\u00e9 d\u00e9couverts dans les eaux levantines, ont men\u00e9 une coop\u00e9ration renforc\u00e9e en termes de s\u00e9curit\u00e9 \u00e9nerg\u00e9tique et militaire et de lutte contre l&rsquo;immigration irr\u00e9guli\u00e8re, dans le but de cr\u00e9er un groupe de travail conjoint avec l&rsquo;Europe et Isra\u00ebl (<strong>3<\/strong>). Les man\u0153uvres entre l&rsquo;Egypte, la Gr\u00e8ce et Chypre marquent un nouveau d\u00e9veloppement visant \u00e0 renforcer la dimension multilat\u00e9rale de ce projet, qui implique la plupart des pays de la rive sud-est et nord de la M\u00e9diterran\u00e9e&#160;: \u00e0 travers les dividendes \u00e9nerg\u00e9tiques provenant de l&rsquo;exploitation des ressources <em>offshore<\/em> des sites de Leviathan, Aphrodite et Zohr, l&rsquo;objectif est de promouvoir un processus de paix dans une r\u00e9gion historiquement agit\u00e9e, garantissant \u00e0 l&rsquo;Europe une alternative \u00e9nerg\u00e9tique aux routes russe et alg\u00e9rienne.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Perspectives&#160;:<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>L&rsquo;exercice \u00ab&#160;Medusa 6&#160;\u00bb d\u00e9montre \u00e9galement la renaissance de l&rsquo;activisme diplomatique de l&rsquo;\u00c9gypte, acteur g\u00e9opolitique et puissance militaire dans le monde arabo-islamique, qui organise chaque ann\u00e9e plusieurs exercices militaires avec des partenaires arabes, africains et occidentaux afin de renforcer la coop\u00e9ration militaire et de partager leur expertise, ainsi que d&rsquo;acqu\u00e9rir les outils n\u00e9cessaires pour combattre les menaces \u00e0 sa s\u00e9curit\u00e9 nationale.<\/li><li>Les exercices militaires donnent la mesure de l&rsquo;importance g\u00e9opolitique et strat\u00e9gique croissante que repr\u00e9sente ce quadrant de la M\u00e9diterran\u00e9e, tant dans le pr\u00e9sent que dans un avenir proche.<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Sources&#160;:<\/strong><\/h4>\n\n\n\n<ol class=\"wp-block-list\"><li>ELEIBA, Ahmed, <a href=\"http:\/\/english.ahram.org.eg\/NewsContent\/1\/64\/305470\/Egypt\/Politics-\/Egypt,-Greece-and-Cyprus-kick-off-joint-military-d.aspx\">Egypt, Greece and Cyprus kick off joint military drills in the Mediterranean<\/a>, Ahram online, 25 juin 2018.<\/li><li>MAHMOUD, Mohammed, <a href=\"https:\/\/www.aa.com.tr\/en\/middle-east\/egypt-greece-greek-cypriot-administration-hold-drills\/1187007\">Egypt, Greece, Greek Cypriot administration hold drills<\/a>, Anadolu Agency, 25 juin 2018.<\/li><li>SANZ Juan Carlos, <a href=\"https:\/\/elpais.com\/internacional\/2018\/06\/03\/actualidad\/1528051258_010725.html\">Greece, Egypt and Cyprus to hold joint exercise south of Crete<\/a>, El Pais, 22 juin, 2018.<\/li><li>State Information Service (SIS), <a href=\"http:\/\/www.sis.gov.eg\/Story\/132031\/?lang=en-us.\">Egypt, Greek, Cyprus holds joint exercise<\/a>, 26 juin 2018.<\/li><\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Les exercices militaires au large de la Cr\u00e8te men\u00e9s par l&rsquo;Egypte, la Gr\u00e8ce et Chypre s\u2019inscrivent dans le processus de coop\u00e9ration renforc\u00e9e en M\u00e9diterran\u00e9e orientale, li\u00e9 \u00e0 la d\u00e9couverte de champs \u00e9nerg\u00e9tiques offshore.  <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":0,"footnotes":""},"categories":[1732],"tags":[],"staff":[1646],"editorial_format":[4942],"serie":[],"audience":[],"geo":[543],"class_list":["post-4962","post","type-post","status-publish","format-standard","hentry","category-guerre","staff-giuseppe-dentice","editorial_format-actu-breves","geo-mediterranee"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":"","excerpt":"Les exercices militaires au large de la Cr\u00e8te men\u00e9s par l'Egypte, la Gr\u00e8ce et Chypre s\u2019inscrivent dans le processus de coop\u00e9ration renforc\u00e9e en M\u00e9diterran\u00e9e orientale, li\u00e9 \u00e0 la d\u00e9couverte de champs \u00e9nerg\u00e9tiques offshore.  ","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Exercices militaires entre l&#039;\u00c9gypte, la Gr\u00e8ce et Chypre en M\u00e9diterran\u00e9e orientale | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2018\/07\/01\/exercices-militaires-entre-legypte-la-grece-et-chypre-en-mediterranee-orientale\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exercices militaires entre l&#039;\u00c9gypte, la Gr\u00e8ce et Chypre en M\u00e9diterran\u00e9e orientale | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Les exercices militaires au large de la Cr\u00e8te men\u00e9s par l&#039;Egypte, la Gr\u00e8ce et Chypre s\u2019inscrivent dans le processus de coop\u00e9ration renforc\u00e9e en M\u00e9diterran\u00e9e orientale, li\u00e9 \u00e0 la d\u00e9couverte de champs \u00e9nerg\u00e9tiques offshore.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2018\/07\/01\/exercices-militaires-entre-legypte-la-grece-et-chypre-en-mediterranee-orientale\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-01T20:00:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-23T14:45:13+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2018\/07\/01\/exercices-militaires-entre-legypte-la-grece-et-chypre-en-mediterranee-orientale\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2018\/07\/01\/exercices-militaires-entre-legypte-la-grece-et-chypre-en-mediterranee-orientale\/\",\"name\":\"Exercices militaires entre l'\u00c9gypte, la Gr\u00e8ce et Chypre en M\u00e9diterran\u00e9e orientale | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"datePublished\":\"2018-07-01T20:00:19+00:00\",\"dateModified\":\"2019-05-23T14:45:13+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2018\/07\/01\/exercices-militaires-entre-legypte-la-grece-et-chypre-en-mediterranee-orientale\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2018\/07\/01\/exercices-militaires-entre-legypte-la-grece-et-chypre-en-mediterranee-orientale\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2018\/07\/01\/exercices-militaires-entre-legypte-la-grece-et-chypre-en-mediterranee-orientale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exercices militaires entre l&rsquo;\u00c9gypte, la Gr\u00e8ce et Chypre en M\u00e9diterran\u00e9e orientale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exercices militaires entre l'\u00c9gypte, la Gr\u00e8ce et Chypre en M\u00e9diterran\u00e9e orientale | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2018\/07\/01\/exercices-militaires-entre-legypte-la-grece-et-chypre-en-mediterranee-orientale\/","og_locale":"fr_FR","og_type":"article","og_title":"Exercices militaires entre l'\u00c9gypte, la Gr\u00e8ce et Chypre en M\u00e9diterran\u00e9e orientale | Le Grand Continent","og_description":"Les exercices militaires au large de la Cr\u00e8te men\u00e9s par l'Egypte, la Gr\u00e8ce et Chypre s\u2019inscrivent dans le processus de coop\u00e9ration renforc\u00e9e en M\u00e9diterran\u00e9e orientale, li\u00e9 \u00e0 la d\u00e9couverte de champs \u00e9nerg\u00e9tiques offshore.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2018\/07\/01\/exercices-militaires-entre-legypte-la-grece-et-chypre-en-mediterranee-orientale\/","og_site_name":"Le Grand Continent","article_published_time":"2018-07-01T20:00:19+00:00","article_modified_time":"2019-05-23T14:45:13+00:00","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2018\/07\/01\/exercices-militaires-entre-legypte-la-grece-et-chypre-en-mediterranee-orientale\/","url":"https:\/\/legrandcontinent.eu\/fr\/2018\/07\/01\/exercices-militaires-entre-legypte-la-grece-et-chypre-en-mediterranee-orientale\/","name":"Exercices militaires entre l'\u00c9gypte, la Gr\u00e8ce et Chypre en M\u00e9diterran\u00e9e orientale | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"datePublished":"2018-07-01T20:00:19+00:00","dateModified":"2019-05-23T14:45:13+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2018\/07\/01\/exercices-militaires-entre-legypte-la-grece-et-chypre-en-mediterranee-orientale\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2018\/07\/01\/exercices-militaires-entre-legypte-la-grece-et-chypre-en-mediterranee-orientale\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2018\/07\/01\/exercices-militaires-entre-legypte-la-grece-et-chypre-en-mediterranee-orientale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Exercices militaires entre l&rsquo;\u00c9gypte, la Gr\u00e8ce et Chypre en M\u00e9diterran\u00e9e orientale"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":""}]}},"lgc_categories":[{"id":1732,"name":"Guerre","slug":"guerre"}],"lgc_author":{"id":1646,"name":"Giuseppe Dentice","slug":"giuseppe-dentice","description":null,"first_name":null,"last_name":null,"picture":null},"feature_image_summary":null,"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/4962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=4962"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/4962\/revisions"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=4962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=4962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=4962"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=4962"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=4962"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=4962"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=4962"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=4962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}