{"id":45728,"date":"2019-08-27T17:05:43","date_gmt":"2019-08-27T15:05:43","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=45728"},"modified":"2019-08-31T08:57:28","modified_gmt":"2019-08-31T06:57:28","slug":"en-allemagne-lheure-des-tres-grandes-coalitions-a-sonne","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2019\/08\/27\/en-allemagne-lheure-des-tres-grandes-coalitions-a-sonne\/","title":{"rendered":"En Allemagne, l\u2019heure des Tr\u00e8s Grandes coalitions a sonn\u00e9"},"content":{"rendered":"\n<p><em>Dresde, Potsdam.<\/em> L\u2019\u00e9lection des parlements r\u00e9gionaux de Saxe et du Brandebourg le 1<sup>er<\/sup> septembre prochain s\u2019annonce comme un scrutin d\u00e9terminant pour l\u2019avenir de la culture parlementaire allemande. Difficile, pourtant, de d\u00e9gager les lignes de forces programmatiques autour desquelles s\u2019organise la confrontation. Les deux principales pr\u00e9occupations \u00e9voqu\u00e9es par l\u2019\u00e9lectorat \u00e0 la veille de l\u2019\u00e9lection (migration et asile, s\u00e9curit\u00e9)&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-45728' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/08\/27\/en-allemagne-lheure-des-tres-grandes-coalitions-a-sonne\/#easy-footnote-bottom-1-45728' title='EVELT Andreas,&lt;a href=&quot;https:\/\/www.spiegel.de\/politik\/deutschland\/sachsen-wahl-cdu-in-umfrage-knapp-vor-afd-a-1282747.html&quot;&gt; \u00a0CDU in Sachsen knapp vor AfD&lt;\/a&gt;, Spiegel, 20 ao\u00fbt 2019.'><sup>1<\/sup><\/a><\/span><\/span> contrastent ainsi significativement avec les comp\u00e9tences et les lignes de fractures r\u00e9gionales (politique \u00e9ducative, am\u00e9nagement). Dans les deux <em>L\u00e4nder<\/em> de l\u2019Est, c\u2019est surtout sur la nature de la coalition gouvernementale qui verra le jour \u00e0 la suite de ces \u00e9lections, que se concentrent les pr\u00e9occupations. Alors que les deux r\u00e9gions, malgr\u00e9 des profils politiques assez dissemblables, comptent parmi les plus favorables \u00e0 l\u2019Alternative pour l\u2019Allemagne (AfD, ENL), l\u2019affaiblissement significatif des Chr\u00e9tiens-d\u00e9mocrates et des Sociaux-d\u00e9mocrates \u2013 un ph\u00e9nom\u00e8ne national \u2013, y prend une ampleur particuli\u00e8re. Dans les deux cas, la coalition en place est assur\u00e9e de perdre assez largement sa majorit\u00e9&#160;: Michael Kretschmer (CDU, PPE) en Saxe et Dietmar Woidke (SPD, S&amp;D) au Brandebourg verront probablement leurs alliances respectives avec la SPD et le parti de la gauche radicale Die Linke (GUE\/NGL) recueillir de l\u2019ordre de 35 \u00e0 40&#160;% des voix.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-medium\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/08\/I1.png\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"854\"\n        data-pswp-height=\"480\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/08\/I1-330x185.png\"\r\n                media=\"(max-width:  374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/08\/I1-690x388.png\"\r\n                media=\"(max-width:  989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/08\/I1.png\"\r\n                media=\"(max-width: 1319px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/08\/I1-690x388.png\"\r\n                media=\"(max-width: 1599px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/08\/I1.png\"\r\n                media=\"(min-width: 1600px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/08\/I1-125x70.png\" \/>\r\n        <\/picture>\r\n                            \n            <\/a>\n<\/figure>\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00c0 Dresde, la coalition impossible&#160;?<\/strong><\/h4>\n\n\n\n<p>La situation est particuli\u00e8rement d\u00e9licate en Saxe. De tradition conservatrice, bastion \u00e9lectoral de l\u2019extr\u00eame-droite depuis le d\u00e9but des ann\u00e9es 2000 (le parti n\u00e9o-nazi NPD fit presque jeu \u00e9gal avec la SPD lors des \u00e9lections de 2004), la r\u00e9gion enregistre un taux de soutien \u00e0 l\u2019AfD de l\u2019ordre de 25&#160;%. Le parti n\u00e9o-nationaliste, en deuxi\u00e8me place derri\u00e8re les chr\u00e9tiens-d\u00e9mocrates cr\u00e9dit\u00e9s de 31&#160;%, remportera probablement un nombre significatif de mandats directs&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-45728' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/08\/27\/en-allemagne-lheure-des-tres-grandes-coalitions-a-sonne\/#easy-footnote-bottom-2-45728' title='Dans cette \u00e9lection \u00e0 un tour, les si\u00e8ges sont r\u00e9partis en deux temps&amp;#160;: le candidat ayant obtenu la majorit\u00e9 simple dans chaque circonscription est \u00e9lu (mandats directs, la moiti\u00e9 du parlement)&amp;#160;; puis des candidats issus des listes de chaque parti sont ajout\u00e9s afin de garantir la proportionnalit\u00e9 du r\u00e9sultat.'><sup>2<\/sup><\/a><\/span><\/span>. Il ne devrait donc pas p\u00e2tir de la limitation de sa liste r\u00e9gionale \u00e0 30 candidats (au lieu de 61), intervenue suite \u00e0 une erreur de proc\u00e9dure pour laquelle le parti a obtenu gain de cause partiel devant le tribunal constitutionnel de Leipzig&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-45728' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/08\/27\/en-allemagne-lheure-des-tres-grandes-coalitions-a-sonne\/#easy-footnote-bottom-3-45728' title='LEHMANN Timo,&lt;a href=&quot;https:\/\/www.spiegel.de\/politik\/deutschland\/afd-kandidatenliste-in-sachsen-was-bedeutet-das-neue-urteil-a-1282174.html&quot;&gt; Was bedeutet das neue Urteil zur AfD-Liste&amp;#160;?&lt;\/a&gt;, Spiegel, 16 ao\u00fbt 2019.'><sup>3<\/sup><\/a><\/span><\/span>. La SPD, qui n\u2019a jamais d\u00e9pass\u00e9 en Saxe les 12,6&#160;% obtenus en 2014, devrait se contenter d\u2019un score \u00e0 un seul chiffre&#160;; cet affaiblissement devrait partiellement profiter aux Verts, qui obtiendraient 14&#160;% des suffrages, soit autant que Die Linke. En r\u00e9alit\u00e9, plus que le score apparemment tr\u00e8s faible des sociaux-d\u00e9mocrates \u2013 mais conforme, dans les faits, \u00e0 sa moyenne dans une r\u00e9gion peu favorable \u2013, ce sont surtout les d\u00e9fections au centre-droit qui inqui\u00e8tent. H\u00e9g\u00e9monique dans les ann\u00e9es 1990, stable autour de 40&#160;% de 2004 \u00e0 2014, la CDU saxonne, fortement contest\u00e9e sur sa droite, ne recevrait plus que 31&#160;% des suffrages \u2013 plusieurs enqu\u00eates la donnaient m\u00eame en-de\u00e7\u00e0 des 30&#160;%, trois points seulement devant l\u2019AfD.<\/p>\n\n\n\n<p>\u00c0 cela s\u2019ajoute la d\u00e9sunion, d\u00e9sormais manifeste, au sein-m\u00eame de la section r\u00e9gionale du Parti chr\u00e9tien-d\u00e9mocrate. Le ministre-pr\u00e9sident Michael Kretschmer, repr\u00e9sentant de l\u2019aile mod\u00e9r\u00e9e du parti conservateur, a formellement exclu toute coop\u00e9ration avec les n\u00e9o-nationalistes&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-45728' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/08\/27\/en-allemagne-lheure-des-tres-grandes-coalitions-a-sonne\/#easy-footnote-bottom-4-45728' title='&lt;a href=&quot;https:\/\/www.dnn.de\/Nachrichten\/Politik\/Kretschmer-bekraeftigt-Keine-Koalition-und-Kooperation-mit-der-AfD&quot;&gt;Kretschmer bekr\u00e4ftigt&amp;#160;: Keine Koalition und Kooperation mit der AfD&lt;\/a&gt;, Dresdner Neueste Nachrichten, 8 ao\u00fbt 2019.'><sup>4<\/sup><\/a><\/span><\/span> et pr\u00e9pare d\u2019ores et d\u00e9j\u00e0 le terrain pour une coalition avec les Verts&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-45728' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/08\/27\/en-allemagne-lheure-des-tres-grandes-coalitions-a-sonne\/#easy-footnote-bottom-5-45728' title='LEHMANN Timo,&lt;a href=&quot;https:\/\/www.spiegel.de\/politik\/deutschland\/landtagswahl-in-sachsen-elefantenrunde-der-regionalzeitungen-a-1283079.html&quot;&gt; Der Elefant im Raum&lt;\/a&gt;, Spiegel, 21 ao\u00fbt 2019.'><sup>5<\/sup><\/a><\/span><\/span>.\u00a0Cette coalition \u00e0 trois (elle ne pourra pas faire l\u2019\u00e9conomie des voix du SPD) appara\u00eet comme la seule mani\u00e8re d\u2019\u00e9viter \u00e0 la fois un gouvernement minoritaire et une participation gouvernementale de l\u2019AfD&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-45728' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/08\/27\/en-allemagne-lheure-des-tres-grandes-coalitions-a-sonne\/#easy-footnote-bottom-6-45728' title='WORATSCHKA Rainer,&lt;a href=&quot;https:\/\/www.tagesspiegel.de\/politik\/regierungsoptionen-in-sachsen-kretschmer-braucht-die-gruenen\/24931274.html&quot;&gt; \u201eKretschmer braucht die Gr\u00fcnen\u201c&lt;\/a&gt;, Tagesspiegel, 22 ao\u00fbt 2019.'><sup>6<\/sup><\/a><\/span><\/span>. Tout en comparant l\u2019AfD avec le NPD, il s\u2019est dit ouvert le cas \u00e9ch\u00e9ant \u00e0 une \u00ab&#160;super-coalition&#160;\u00bb centriste incluant les Lib\u00e9raux (CDU, Verts, SPD, FDP) pour faire barrage \u00e0 l\u2019extr\u00eame-droite&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-7-45728' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/08\/27\/en-allemagne-lheure-des-tres-grandes-coalitions-a-sonne\/#easy-footnote-bottom-7-45728' title='JEDICKE Henriette,&lt;a href=&quot;https:\/\/www.focus.de\/politik\/deutschland\/wahl-am-1-september-wenn-sich-parteien-in-sachsen-gegen-die-afd-verbuenden-birgt-das-zwei-risiken_id_11003132.html&quot;&gt; Wenn sich Parteien in Sachsen gegen die AfD verb\u00fcnden, birgt das zwei Risiken&lt;\/a&gt;, Focus, 22 ao\u00fbt 2019.'><sup>7<\/sup><\/a><\/span><\/span>.\u00a0 Mais si elle a les faveurs de la direction f\u00e9d\u00e9rale et de l\u2019\u00e9lectorat urbain, la solution Kretscher peine \u00e0 convaincre la base r\u00e9solument conservatrice de la CDU saxonne, particuli\u00e8rement dans les zones rurales. En plein d\u00e9bat autour de l\u2019exclusion potentielle de Hans-Georg Maa\u00dfen, ex-chef du renseignement int\u00e9rieur et dor\u00e9navant figure de l\u2019aile droite, la WerteUnion (\u00ab&#160;union des valeurs&#160;\u00bb), qui regroupe les partisans d\u2019une forme de national-conservatisme favorables \u00e0 une coop\u00e9ration avec l\u2019AfD et hostiles aux coalitions noires-vertes, enregistre une forte hausse des adh\u00e9sions&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-8-45728' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/08\/27\/en-allemagne-lheure-des-tres-grandes-coalitions-a-sonne\/#easy-footnote-bottom-8-45728' title='&lt;a href=&quot;https:\/\/www.welt.de\/politik\/deutschland\/article197510897\/AfD-Werteunion-spricht-sich-gegen-Koalitionsverbot-aus.html&quot;&gt;Werteunion spricht sich gegen Kooperationsverbot mit AfD aus&lt;\/a&gt;, Welt, 26 juillet 2019.'><sup>8<\/sup><\/a><\/span><\/span>. \u00c0 l\u2019\u00e9chelle infra-r\u00e9gionale, les contacts semblent d\u00e9j\u00e0 nombreux&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-9-45728' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/08\/27\/en-allemagne-lheure-des-tres-grandes-coalitions-a-sonne\/#easy-footnote-bottom-9-45728' title='GARBE Sophie Madeleine,&lt;a href=&quot;https:\/\/www.spiegel.de\/politik\/deutschland\/cdu-und-afd-wo-sich-die-parteien-naeherkommen-a-1280726.html&quot;&gt; \u00a0Wo sich CDU und AfD n\u00e4herkommen&lt;\/a&gt;, Spiegel, 8 ao\u00fbt 2019.'><sup>9<\/sup><\/a><\/span><\/span>. La base conservatrice pourrait \u00eatre tent\u00e9e d\u2019apporter son soutien \u00e0 une option minoritaire CDU-FDP, qui s\u2019appuierait dans les faits sur la tol\u00e9rance de l\u2019AfD.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-medium\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/08\/grah2.png\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"849\"\n        data-pswp-height=\"477\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/08\/grah2-330x185.png\"\r\n                media=\"(max-width:  374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/08\/grah2-690x388.png\"\r\n                media=\"(max-width:  989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/08\/grah2.png\"\r\n                media=\"(max-width: 1319px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/08\/grah2-690x388.png\"\r\n                media=\"(max-width: 1599px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/08\/grah2.png\"\r\n                media=\"(min-width: 1600px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/08\/grah2-125x70.png\" \/>\r\n        <\/picture>\r\n                            \n            <\/a>\n<\/figure>\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00c0 Potsdam, l\u2019option de gauche favoris\u00e9e<\/strong><\/h4>\n\n\n\n<p>Dans le vaste mais peu dense Brandebourg, terre historique de la gauche est-allemande, la situation semble singuli\u00e8rement moins complexe. Certes, la SPD, stable autour de 30&#160;% depuis le d\u00e9but des ann\u00e9es 2000, tomberait \u00e0 21&#160;%, un point seulement devant l\u2019AfD. Ces pertes co\u00efncident cependant avec une croissance d\u2019ampleur \u00e9quivalente des Verts (14&#160;%, +8 pp). Et quoique Die Linke recule (14&#160;%), les r\u00e9sultats obtenus devraient suffire \u00e0 permettre l\u2019av\u00e8nement d\u2019une coalition rouge-rouge-verte (SPD-Linke-Verts) sous la direction de l\u2019actuel ministre-pr\u00e9sident Dietmar Woidke (SPD), cr\u00e9dit\u00e9 de 51&#160;% d\u2019opinions favorables&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-10-45728' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/08\/27\/en-allemagne-lheure-des-tres-grandes-coalitions-a-sonne\/#easy-footnote-bottom-10-45728' title='&lt;a href=&quot;https:\/\/www.spiegel.de\/politik\/deutschland\/infratest-cdu-in-sachsen-bei-30-prozent-spd-in-brandenburg-mit-afd-gleichauf-a-1283252.html&quot;&gt;CDU in Sachsen bei 30 Prozent, SPD zieht in Brandenburg mit AfD gleich&lt;\/a&gt;, Spiegel, 22 ao\u00fbt 2019.'><sup>10<\/sup><\/a><\/span><\/span>. Une issue qui se r\u00e9sumerait donc en une ouverture aux Verts de l\u2019actuelle coalition de gauche, sans v\u00e9ritable r\u00e9volution \u00e9lectorale. La bonne entente mise en sc\u00e8ne par Die Linke et la SPD derni\u00e8rement semble confirmer cette vision des choses&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-11-45728' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/08\/27\/en-allemagne-lheure-des-tres-grandes-coalitions-a-sonne\/#easy-footnote-bottom-11-45728' title='BREYTON Ricard et KUHL Philip,&lt;a href=&quot;https:\/\/www.welt.de\/politik\/deutschland\/article199195553\/SPD-und-Linke-Rot-rote-Annaeherung-in-Zeiten-des-Wahlkampfs.html?wtrid=onsite.onsitesearch&quot;&gt; Rot-rote Ann\u00e4herung in Zeiten des Wahlkampfs&lt;\/a&gt;, Welt, 26 ao\u00fbt 2019.'><sup>11<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>L\u2019\u00e9quilibre n\u2019en reste pas moins fragile. Si l\u2019un des trois coalitionnaires potentiels venait \u00e0 subir une contre-performance dans les urnes, l\u2019opportunit\u00e9 d\u2019une coalition SPD-CDU-Verts \u2013 celle-l\u00e0 m\u00eame voulue par Kretschmer en Saxe \u2013 pourrait \u00eatre relanc\u00e9e. La CDU brandebourgeoise, donn\u00e9e \u00e0 18&#160;%, un score historiquement faible, est en proie aux m\u00eames doutes que son <em>alter ego <\/em>dresdoise. Son chef Ingo Senftleben s\u2019est joint \u00e0 Michael Kretschmer pour refuser l\u2019\u00ab&#160;aide&#160;\u00bb que leur proposait Hans-Georg Maa\u00dfen lors de la campagne&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-12-45728' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/08\/27\/en-allemagne-lheure-des-tres-grandes-coalitions-a-sonne\/#easy-footnote-bottom-12-45728' title='&lt;a href=&quot;https:\/\/www.spiegel.de\/politik\/deutschland\/brandenburg-cdu-chef-ingo-senftleben-distanziert-sich-von-hans-georg-maassen-a-1283771.html&quot;&gt;Auch CDU-Landeschef Senftleben distanziert sich von Maa\u00dfen&lt;\/a&gt;, Spiegel, 26 ao\u00fbt 2019.'><sup>12<\/sup><\/a><\/span><\/span>, alors que les affinit\u00e9s n\u00e9o-nazies de la t\u00eate de liste de l\u2019AfD sont apparues au grand jour&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-13-45728' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/08\/27\/en-allemagne-lheure-des-tres-grandes-coalitions-a-sonne\/#easy-footnote-bottom-13-45728' title='&lt;a href=&quot;https:\/\/www.spiegel.de\/politik\/deutschland\/afd-andreas-kalbitz-war-offenbar-enger-mit-rechter-szene-vernetzt-a-1283317.html&quot;&gt;AfD-Spitzenkandidat Kalbitz erhielt E-Mail von HDJ-\u00ab&amp;#160;Bundesf\u00fchrer&lt;\/a&gt;, Spiegel, 23 ao\u00fbt 2019.'><sup>13<\/sup><\/a><\/span><\/span>. \u00c0 l\u2019inverse du cas saxon, la CDU ne semble pouvoir pr\u00e9tendre \u00e0 la direction d\u2019aucune coalition \u00e0 Potsdam, et l\u2019\u00ab&#160;union des droites&#160;\u00bb y serait sans majorit\u00e9. Elle pourrait donc se contenter, dans l\u2019hypoth\u00e8se d\u2019une nette d\u00e9faite de la SPD, de perturber la formation d\u2019une Tr\u00e8s Grande coalition, suivant l\u2019id\u00e9e \u00e9voqu\u00e9e par Senftleben d\u2019un r\u00e9f\u00e9rendum de la base sur le contrat de coalition&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-14-45728' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/08\/27\/en-allemagne-lheure-des-tres-grandes-coalitions-a-sonne\/#easy-footnote-bottom-14-45728' title='&lt;a href=&quot;https:\/\/www.spiegel.de\/politik\/deutschland\/landtagswahl-in-brandenburg-cdu-plant-mitgliederentscheid-ueber-koalitionsvertrag-a-1283244.html&quot;&gt;Brandenburgs CDU-Chef will Mitgliederentscheid \u00fcber Koalitionsvertrag&lt;\/a&gt;, Spiegel, 22 ao\u00fbt 2019.'><sup>14<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>La Tr\u00e8s Grande coalition \u00ab&#160;kenyane&#160;\u00bb, avenir de la Grande coalition&#160;?<\/strong><\/h4>\n\n\n\n<p>Avec la perte d\u2019influence des deux partis de masse historiques, la formation de coalitions tripartites est en passe de devenir une nouvelle norme. Il y a quelques mois, Le Grand Continent \u00e9voquait d\u00e9j\u00e0 dans ses colonnes cette \u00ab&#160;Tr\u00e8s Grande coalition&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-15-45728' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/08\/27\/en-allemagne-lheure-des-tres-grandes-coalitions-a-sonne\/#easy-footnote-bottom-15-45728' title='HUBLET Fran\u00e7ois et SCHLEYER Johanna,&lt;a href=&quot;https:\/\/legrandcontinent.eu\/fr\/2019\/04\/29\/lallemagne-ingouvernable-lere-des-tres-grandes-coalitions\/&quot;&gt; L\u2019\u00e8re des Tr\u00e8s Grandes Coalitions et l\u2019Allemagne ingouvernable&lt;\/a&gt;, Le Grand Continent, 29 avril 2019.'><sup>15<\/sup><\/a><\/span><\/span> dont la n\u00e9cessit\u00e9, n\u00e9e de la hausse du vote nationaliste conjugu\u00e9 \u00e0 l\u2019affaiblissement des deux grands blocs centraux au profit des anciens \u00ab&#160;petits partis&#160;\u00bb (particuli\u00e8rement les Verts), s\u2019imposait progressivement dans les diff\u00e9rents <em>L\u00e4nder <\/em>sous l\u2019effet de l\u2019arithm\u00e9tique \u00e9lectorale.<\/p>\n\n\n\n<p>Parmi les diff\u00e9rentes formules de \u00ab&#160;Tr\u00e8s Grande coalition&#160;\u00bb r\u00e9unissant la CDU, la SPD et l\u2019un des autres partis centraux, la coalition dite \u00ab&#160;kenyane&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-16-45728' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/08\/27\/en-allemagne-lheure-des-tres-grandes-coalitions-a-sonne\/#easy-footnote-bottom-16-45728' title='D&amp;rsquo;apr\u00e8s les couleurs (noir, rouge, vert) des partis la composant, qui sont aussi celles du drapeau du Kenya.'><sup>16<\/sup><\/a><\/span><\/span> incluant les Verts semble la plus \u00e0 m\u00eame de s\u2019imposer \u00e0 moyen terme. D\u00e9passant les Sociaux-d\u00e9mocrates dans la moiti\u00e9 des <em>L\u00e4nder<\/em>, les Verts ont capt\u00e9 simultan\u00e9ment une part de l\u2019aile centriste (urbaine, jeune et dipl\u00f4m\u00e9e) de la CDU et de nombreux d\u00e9\u00e7us de la social-d\u00e9mocratie. Tout se passe donc comme si, derri\u00e8re l\u2019\u00e9largissement de l\u2019alliance CDU-SPD (\u00ab&#160;Grande coalition&#160;\u00bb) \u00e0 une alliance CDU-SPD-Verts (\u00ab&#160;coalition kenyane&#160;\u00bb) et le renouvellement partiel de l\u2019offre programmatique et rh\u00e9torique par les \u00e9cologistes, les m\u00eames cat\u00e9gories d\u2019\u00e9lecteurs se trouvaient finalement repr\u00e9sent\u00e9s par le consensus gouvernemental.&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-17-45728' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/08\/27\/en-allemagne-lheure-des-tres-grandes-coalitions-a-sonne\/#easy-footnote-bottom-17-45728' title='Un ph\u00e9nom\u00e8ne similaire est probablement \u00e0 l\u2018\u0153uvre dans l\u2018\u00e9largissemement de la coalition SPD-Linke \u00e0 une coalition SPD-Verts-Linke, m\u00eame si la porosit\u00e9 entre Linke et AfD est r\u00e9elle.'><sup>17<\/sup><\/a><\/span><\/span> Il n\u2019en reste pas moins que la seule exp\u00e9rience r\u00e9gionale de ce type, celle du gouvernement form\u00e9 par Rainer Hasseloff en Saxe-Anhalt depuis 2016, n\u2019a d\u00e9j\u00e0 plus de majorit\u00e9 claire \u00e0 ce jour. En tous cas, l\u2019avenir de la coalition \u00ab&#160;kenyane&#160;\u00bb semble plus favorable que celui d\u2019une autre \u00ab&#160;Tr\u00e8s Grande coalition&#160;\u00bb, celle r\u00e9unissant la CDU, la SPD et les lib\u00e9raux du FDP, cependant que ces derniers oscillent dans la moiti\u00e9 des r\u00e9gions autour de la barre des 5&#160;% n\u00e9cessaires \u00e0 l\u2019obtention de si\u00e8ges au parlement.<\/p>\n\n\n\n<p>Alors que l\u2019effritement de la social-d\u00e9mocratie semble s\u2019effectuer en grande partie au profit des autres forces de gauche, Verts en t\u00eate, les pertes consenties par la CDU \u00e0 l\u2019AfD sont d\u2019une nature potentiellement plus explosive. Si l\u2019axe \u00ab&#160;mod\u00e9r\u00e9&#160;\u00bb Kretschmer-Senftleben ne parvient \u00e0 s\u2019imposer dans la formation gouvernementale qu\u2019au prix d\u2019un morcellement encore accru de son \u00e9lectorat, la d\u00e9cr\u00e9dibilisation qui pourrait s\u2019ensuivre pourrait encourager la fuite vers la droite d\u2019une partie encore plus importante de la base, voire du personnel politique. Un \u00ab&#160;parti Maa\u00dfen&#160;\u00bb susceptible d\u2019entrer en coalition avec l\u2019AfD (et peut-\u00eatre le FDP ou les \u00c9lecteurs libres) jouirait d\u2019une opportunit\u00e9 politique certaine dans les <em>nouveaux L\u00e4nder<\/em> de l\u2019Est.<\/p>\n\n\n\n<p><em>Le Grand Continent couvrira en direct les r\u00e9sultats des \u00e9lections en Saxe\net au Brandebourg le dimanche 1<sup>er<\/sup> septembre au soir.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les \u00e9lections r\u00e9gionales qui auront lieu en Saxe et au Brandebourg le 1er septembre devraient donner lieu \u00e0 des n\u00e9gociations de coalition complexes, entre \u00ab&#160;&#160;Tr\u00e8s Grande coalition&#160;&#160;\u00bb in\u00e9vitable et tensions dans le camp conservateur.<\/p>\n","protected":false},"author":175,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":0,"footnotes":""},"categories":[1731],"tags":[],"staff":[1637],"editorial_format":[4942],"serie":[],"audience":[],"geo":[536],"class_list":["post-45728","post","type-post","status-publish","format-standard","hentry","category-politique","staff-francois-hublet","editorial_format-actu-breves","geo-centres"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":"","excerpt":"Les \u00e9lections r\u00e9gionales qui auront lieu en Saxe et au Brandebourg le 1er septembre devraient donner lieu \u00e0 des n\u00e9gociations de coalition complexes, entre \u00ab Tr\u00e8s Grande coalition \u00bb in\u00e9vitable et tensions dans le camp conservateur.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>En Allemagne, l\u2019heure des Tr\u00e8s Grandes coalitions a sonn\u00e9 | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/08\/27\/en-allemagne-lheure-des-tres-grandes-coalitions-a-sonne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En Allemagne, l\u2019heure des Tr\u00e8s Grandes coalitions a sonn\u00e9 | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Les \u00e9lections r\u00e9gionales qui auront lieu en Saxe et au Brandebourg le 1er septembre devraient donner lieu \u00e0 des n\u00e9gociations de coalition complexes, entre \u00ab&#160;Tr\u00e8s Grande coalition&#160;\u00bb in\u00e9vitable et tensions dans le camp conservateur.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2019\/08\/27\/en-allemagne-lheure-des-tres-grandes-coalitions-a-sonne\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-27T15:05:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-31T06:57:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/08\/I1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"854\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Giovanni Collot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/08\/I1.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giovanni Collot\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/08\/27\/en-allemagne-lheure-des-tres-grandes-coalitions-a-sonne\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/08\/27\/en-allemagne-lheure-des-tres-grandes-coalitions-a-sonne\/\",\"name\":\"En Allemagne, l\u2019heure des Tr\u00e8s Grandes coalitions a sonn\u00e9 | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"datePublished\":\"2019-08-27T15:05:43+00:00\",\"dateModified\":\"2019-08-31T06:57:28+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/08\/27\/en-allemagne-lheure-des-tres-grandes-coalitions-a-sonne\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2019\/08\/27\/en-allemagne-lheure-des-tres-grandes-coalitions-a-sonne\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/08\/27\/en-allemagne-lheure-des-tres-grandes-coalitions-a-sonne\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En Allemagne, l\u2019heure des Tr\u00e8s Grandes coalitions a sonn\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef\",\"name\":\"Giovanni Collot\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g\",\"caption\":\"Giovanni Collot\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En Allemagne, l\u2019heure des Tr\u00e8s Grandes coalitions a sonn\u00e9 | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2019\/08\/27\/en-allemagne-lheure-des-tres-grandes-coalitions-a-sonne\/","og_locale":"fr_FR","og_type":"article","og_title":"En Allemagne, l\u2019heure des Tr\u00e8s Grandes coalitions a sonn\u00e9 | Le Grand Continent","og_description":"Les \u00e9lections r\u00e9gionales qui auront lieu en Saxe et au Brandebourg le 1er septembre devraient donner lieu \u00e0 des n\u00e9gociations de coalition complexes, entre \u00ab&#160;Tr\u00e8s Grande coalition&#160;\u00bb in\u00e9vitable et tensions dans le camp conservateur.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2019\/08\/27\/en-allemagne-lheure-des-tres-grandes-coalitions-a-sonne\/","og_site_name":"Le Grand Continent","article_published_time":"2019-08-27T15:05:43+00:00","article_modified_time":"2019-08-31T06:57:28+00:00","og_image":[{"width":854,"height":480,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/08\/I1.png","type":"image\/png"}],"author":"Giovanni Collot","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/08\/I1.png","twitter_misc":{"\u00c9crit par":"Giovanni Collot","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/08\/27\/en-allemagne-lheure-des-tres-grandes-coalitions-a-sonne\/","url":"https:\/\/legrandcontinent.eu\/fr\/2019\/08\/27\/en-allemagne-lheure-des-tres-grandes-coalitions-a-sonne\/","name":"En Allemagne, l\u2019heure des Tr\u00e8s Grandes coalitions a sonn\u00e9 | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"datePublished":"2019-08-27T15:05:43+00:00","dateModified":"2019-08-31T06:57:28+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/08\/27\/en-allemagne-lheure-des-tres-grandes-coalitions-a-sonne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2019\/08\/27\/en-allemagne-lheure-des-tres-grandes-coalitions-a-sonne\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/08\/27\/en-allemagne-lheure-des-tres-grandes-coalitions-a-sonne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"En Allemagne, l\u2019heure des Tr\u00e8s Grandes coalitions a sonn\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef","name":"Giovanni Collot","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g","caption":"Giovanni Collot"}}]}},"lgc_categories":[{"id":1731,"name":"Politique","slug":"politique"}],"lgc_author":{"id":1637,"name":"Fran\u00e7ois Hublet","slug":"francois-hublet","description":"Fran\u00e7ois Hublet est r\u00e9dacteur-en-chef des <em>Bulletins des \u00e9lections de l'Union Europ\u00e9enne<\/em> (BLUE), publication du Groupe d'\u00e9tudes g\u00e9opolitiques. Il est dipl\u00f4m\u00e9 de l'\u00c9cole polytechnique (Palaiseau) et de l'\u00c9cole polytechnique f\u00e9d\u00e9rale de Zurich.","first_name":"Fran\u00e7ois","last_name":"Hublet","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/10\/GC_Hublet.png","width":333,"height":331,"alt":""}},"feature_image_summary":null,"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/45728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=45728"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/45728\/revisions"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=45728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=45728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=45728"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=45728"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=45728"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=45728"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=45728"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=45728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}