{"id":45534,"date":"2019-08-19T22:34:36","date_gmt":"2019-08-19T20:34:36","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=45534"},"modified":"2019-08-27T17:40:10","modified_gmt":"2019-08-27T15:40:10","slug":"loffensive-sur-le-plage-de-salvini-et-la-campagne-electorale-permanente","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2019\/08\/19\/loffensive-sur-le-plage-de-salvini-et-la-campagne-electorale-permanente\/","title":{"rendered":"L&rsquo;offensive des plages de Salvini et la campagne \u00e9lectorale permanente"},"content":{"rendered":"\n<p><em>Ce texte a \u00e9t\u00e9 publi\u00e9 originellement dans l\u2019\u00e9dition 70 de La Lettre du Lundi, la newsletter op\u00e9rationnelle hebdomadaire du Grand Continent. Vous pouvez retrouver l\u2019\u00e9dition\u00a0compl\u00e8te\u00a0<\/em><a href=\"https:\/\/us14.campaign-archive.com\/?u=10762824cc6c812ec1f389f08&amp;id=53e93d1163\"><em>ici<\/em><\/a><em>.\u00a0Abonnez-vous par\u00a0<\/em><a href=\"https:\/\/gegeurope.us14.list-manage.com\/subscribe\/post?u=10762824cc6c812ec1f389f08&amp;id=54c71b157b\"><em>ici.<\/em><\/a><\/p>\n\n\n\n<p><em>Rome.<\/em> L\u2019Italie meuble \u00e0 elle seule une grande partie du vide de l\u2019actualit\u00e9 europ\u00e9enne de mi-ao\u00fbt. En t\u00e9moigne le taux d\u2019ouverture particuli\u00e8rement \u00e9lev\u00e9 de <em>La Lettre du lundi<\/em> chez les parlementaires italiens.<\/p>\n\n\n\n<p>Il s&rsquo;agit d&rsquo;une v\u00e9ritable \u00ab&#160;crise de Schr\u00f6dinger&#160;\u00bb&#160;: dans une situation assez floue et qui change chaque jour, l\u2019offensive de Salvini a \u00e9t\u00e9, pour le moment, d\u00e9samorc\u00e9e par l\u2019action conjointe du Parlement italien et le pr\u00e9sident de\u00a0la R\u00e9publique. Pour r\u00e9soudre\u00a0la\u00a0crise, plusieurs sc\u00e9narios sont maintenant possibles&#160;: un gouvernement provisoire suivie par des \u00e9lections, une alliance \u00ab&#160;de gauche&#160;\u00bb Mouvement Cinq \u00c9toiles-Parti D\u00e9mocrate-partis de gauche, une coalition \u00ab&#160;Ursula&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-45534' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/08\/19\/loffensive-sur-le-plage-de-salvini-et-la-campagne-electorale-permanente\/#easy-footnote-bottom-1-45534' title='&lt;a href=&quot;https:\/\/www.ilpost.it\/2019\/08\/12\/coalizione-ursula\/&quot;&gt;Cosa diavolo \u00e8 la \u201ccoalizione Ursula\u201d&lt;\/a&gt;, Il Post, 12 aout 2019'><sup>1<\/sup><\/a><\/span><\/span> (ainsi nomm\u00e9e car, en mettant ensemble le centre-gauche, le centre-droite berlusconien et les Cinq \u00c9toiles, elle r\u00e9p\u00e9terait \u00e0 niveau national la coalition qui a soutenu la candidature d&rsquo;Ursula von der Leyen \u00e0 la pr\u00e9sidence de la Commission europ\u00e9enne&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-45534' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/08\/19\/loffensive-sur-le-plage-de-salvini-et-la-campagne-electorale-permanente\/#easy-footnote-bottom-2-45534' title='&lt;a href=&quot;https:\/\/legrandcontinent.eu\/fr\/2019\/07\/16\/le-positionnement-von-der-leyen\/&quot;&gt;Le positionnement Von der Leyen&lt;\/a&gt;, Le Grand Continent, 16 juillet 2019'><sup>2<\/sup><\/a><\/span><\/span>) ou m\u00eame un nouveau gouvernement 5 \u00c9toiles-Ligue avec une nouvelle g\u00e9om\u00e9trie. De plus, les pr\u00e9occupations\u00a0concernant\u00a0la\u00a0situation \u00e9conomique et\u00a0la loi de finances italienne rendent\u00a0la\u00a0situation tr\u00e8s complexe.\u00a0<\/p>\n\n\n\n<p>M\u00eame si la situation actuelle est pleine d&rsquo;incertitudes, on peut dire que Salvini a fait un pari qui semble avoir, pour\u00a0la premi\u00e8re fois, montr\u00e9 quelques faiblesses dans sa strat\u00e9gie&#160;: selon Gianfranco Pasquino, professeur \u00e0 l&rsquo;Universit\u00e9 de Bologne, \u00ab&#160;Salvini a agi comme un joueur de poker&#160;: il a les voix, mais je ne parierais pas sur lui. Il s\u2019est montr\u00e9 capable dans ses campagnes sur les plages, moins comme homme de gouvernement.&#160;\u00bb<\/p>\n\n\n\n<p>En<strong> <\/strong>effet,\u00a0l\u2019objectif ultime de Salvini reste de convoquer des \u00e9lections, et il d\u00e9j\u00e0 a orient\u00e9 tous ses efforts vers une campagne \u00e9lectorale permanente, centr\u00e9e (\u00e0 nouveau) sur un argument unique&#160;:\u00a0la\u00a0lutte contre l\u2019immigration&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-45534' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/08\/19\/loffensive-sur-le-plage-de-salvini-et-la-campagne-electorale-permanente\/#easy-footnote-bottom-3-45534' title='FRENI Giuliana, &lt;a href=&quot;https:\/\/legrandcontinent.eu\/fr\/2019\/08\/12\/le-decret-securite-le-dernier-coup-de-foudre-de-matteo-salvini-en-vue-de-la-crise-de-gouvernement\/?utm_source=LLDL+-+Fran%C3%A7ais&amp;amp;utm_campaign=53e93d1163-EMAIL_CAMPAIGN_2019_08_18_02_30&amp;amp;utm_medium=email&amp;amp;utm_term=0_8dff9a737a-53e93d1163-123122823&amp;amp;mc_cid=53e93d1163&amp;amp;mc_eid=f9b412825a&quot;&gt;Le d\u00e9cret s\u00e9curit\u00e9, le dernier coup de foudre de Matteo Salvini en vue de la crise de gouvernement&amp;#160;?&lt;\/a&gt;, Le Grand Continent, 12 aout 2019'><sup>3<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>L\u2019immigration a justement \u00e9t\u00e9 l\u2019occasion d\u2019un \u00e9ni\u00e8me simulacre de scandale m\u00e9diatique de Salvini sur les r\u00e9seaux sociaux. Face \u00e0 l\u2019arriv\u00e9e du navire Open Arms, Salvini, totalement r\u00e9ticent, a trait\u00e9 la maire de Barcelone d\u2019\u00ab&#160;ang\u00e9liste&#160;\u00bb, alors qu\u2019elle lui rappelait son devoir d\u2019accueil, ce \u00e0 quoi l\u2019int\u00e9ress\u00e9e a r\u00e9pondu dans un autre tweet querelleur&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-45534' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/08\/19\/loffensive-sur-le-plage-de-salvini-et-la-campagne-electorale-permanente\/#easy-footnote-bottom-4-45534' title='COLAU Ada,&lt;a href=&quot;https:\/\/twitter.com\/adacolau\/status\/1162810269011206144?s=12&amp;amp;utm_source=LLDL+-+Fran%C3%A7ais&amp;amp;utm_campaign=53e93d1163-EMAIL_CAMPAIGN_2019_08_18_02_30&amp;amp;utm_medium=email&amp;amp;utm_term=0_8dff9a737a-53e93d1163-123122823&amp;amp;mc_cid=53e93d1163&amp;amp;mc_eid=f9b412825a&quot;&gt; Tweet du 16aout 2019&lt;\/a&gt;'><sup>4<\/sup><\/a><\/span><\/span>. Le ministre de l\u2019Int\u00e9rieur italien s\u2019est finalement r\u00e9solu \u00e0 accueillir 27 mineurs du navire \u00e0 Lampedusa ce samedi 17 ao\u00fbt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Italie meuble \u00e0 elle seule une grande partie du vide de l\u2019actualit\u00e9 europ\u00e9enne de mi-ao\u00fbt. Matteo Salvini a fait un pari qui semble avoir, pour la premi\u00e8re fois, montr\u00e9 quelques faiblesses dans sa strat\u00e9gie. <\/p>\n","protected":false},"author":175,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":0,"footnotes":""},"categories":[1731],"tags":[],"staff":[1644],"editorial_format":[4942],"serie":[],"audience":[],"geo":[543],"class_list":["post-45534","post","type-post","status-publish","format-standard","hentry","category-politique","staff-giovanni-collot","editorial_format-actu-breves","geo-mediterranee"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":"","excerpt":"L\u2019Italie meuble \u00e0 elle seule une grande partie du vide de l\u2019actualit\u00e9 europ\u00e9enne de mi-ao\u00fbt. Matteo Salvini a fait un pari qui semble avoir, pour la premi\u00e8re fois, montr\u00e9 quelques faiblesses dans sa strat\u00e9gie. ","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L&#039;offensive des plages de Salvini et la campagne \u00e9lectorale permanente | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/08\/19\/loffensive-sur-le-plage-de-salvini-et-la-campagne-electorale-permanente\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;offensive des plages de Salvini et la campagne \u00e9lectorale permanente | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"L\u2019Italie meuble \u00e0 elle seule une grande partie du vide de l\u2019actualit\u00e9 europ\u00e9enne de mi-ao\u00fbt. Matteo Salvini a fait un pari qui semble avoir, pour la premi\u00e8re fois, montr\u00e9 quelques faiblesses dans sa strat\u00e9gie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2019\/08\/19\/loffensive-sur-le-plage-de-salvini-et-la-campagne-electorale-permanente\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-19T20:34:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-27T15:40:10+00:00\" \/>\n<meta name=\"author\" content=\"Giovanni Collot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giovanni Collot\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/08\/19\/loffensive-sur-le-plage-de-salvini-et-la-campagne-electorale-permanente\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/08\/19\/loffensive-sur-le-plage-de-salvini-et-la-campagne-electorale-permanente\/\",\"name\":\"L'offensive des plages de Salvini et la campagne \u00e9lectorale permanente | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"datePublished\":\"2019-08-19T20:34:36+00:00\",\"dateModified\":\"2019-08-27T15:40:10+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/08\/19\/loffensive-sur-le-plage-de-salvini-et-la-campagne-electorale-permanente\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2019\/08\/19\/loffensive-sur-le-plage-de-salvini-et-la-campagne-electorale-permanente\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/08\/19\/loffensive-sur-le-plage-de-salvini-et-la-campagne-electorale-permanente\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&rsquo;offensive des plages de Salvini et la campagne \u00e9lectorale permanente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef\",\"name\":\"Giovanni Collot\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g\",\"caption\":\"Giovanni Collot\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'offensive des plages de Salvini et la campagne \u00e9lectorale permanente | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2019\/08\/19\/loffensive-sur-le-plage-de-salvini-et-la-campagne-electorale-permanente\/","og_locale":"fr_FR","og_type":"article","og_title":"L'offensive des plages de Salvini et la campagne \u00e9lectorale permanente | Le Grand Continent","og_description":"L\u2019Italie meuble \u00e0 elle seule une grande partie du vide de l\u2019actualit\u00e9 europ\u00e9enne de mi-ao\u00fbt. Matteo Salvini a fait un pari qui semble avoir, pour la premi\u00e8re fois, montr\u00e9 quelques faiblesses dans sa strat\u00e9gie.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2019\/08\/19\/loffensive-sur-le-plage-de-salvini-et-la-campagne-electorale-permanente\/","og_site_name":"Le Grand Continent","article_published_time":"2019-08-19T20:34:36+00:00","article_modified_time":"2019-08-27T15:40:10+00:00","author":"Giovanni Collot","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Giovanni Collot","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/08\/19\/loffensive-sur-le-plage-de-salvini-et-la-campagne-electorale-permanente\/","url":"https:\/\/legrandcontinent.eu\/fr\/2019\/08\/19\/loffensive-sur-le-plage-de-salvini-et-la-campagne-electorale-permanente\/","name":"L'offensive des plages de Salvini et la campagne \u00e9lectorale permanente | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"datePublished":"2019-08-19T20:34:36+00:00","dateModified":"2019-08-27T15:40:10+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/08\/19\/loffensive-sur-le-plage-de-salvini-et-la-campagne-electorale-permanente\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2019\/08\/19\/loffensive-sur-le-plage-de-salvini-et-la-campagne-electorale-permanente\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/08\/19\/loffensive-sur-le-plage-de-salvini-et-la-campagne-electorale-permanente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"L&rsquo;offensive des plages de Salvini et la campagne \u00e9lectorale permanente"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef","name":"Giovanni Collot","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g","caption":"Giovanni Collot"}}]}},"lgc_categories":[{"id":1731,"name":"Politique","slug":"politique"}],"lgc_author":{"id":1644,"name":"Giovanni Collot","slug":"giovanni-collot","description":"<span style=\"font-weight: 400\">Giovanni Collot est journaliste et expert de communication, s\u2019int\u00e9ressant particuli\u00e8rement aux affaires europ\u00e9ennes et \u00e0 la politique \u00e9trang\u00e8re. Depuis 2018, il est chef du projet Communication au European Committee for Standardization (CEN) et au European Committee for Electrotechnical Standardization (CENELEC). <\/span>","first_name":null,"last_name":null,"picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/07\/gc-giovanni-collot.jpg","width":450,"height":450,"alt":""}},"feature_image_summary":null,"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/45534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=45534"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/45534\/revisions"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=45534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=45534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=45534"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=45534"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=45534"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=45534"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=45534"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=45534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}