{"id":43220,"date":"2019-07-14T01:50:43","date_gmt":"2019-07-13T23:50:43","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=43220"},"modified":"2019-07-14T02:00:07","modified_gmt":"2019-07-14T00:00:07","slug":"le-peuple-politique","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2019\/07\/14\/le-peuple-politique\/","title":{"rendered":"Le peuple politique"},"content":{"rendered":"\n<p class=\"has-drop-cap\">L\u2019histoire politique de l\u2019 Europe moderne a commenc\u00e9 par l\u2019<em>\u00c9tat<\/em> \u2013 par l\u2019\u00c9tat implicitement ou inchoativement national \u2013 et elle est en train de s\u2019achever par l\u2019 \u00c9tat \u2013 par l\u2019\u00c9tat explicitement ou tendanciellement post-national que la terminologie officielle appelle les \u00ab&#160;institutions europ\u00e9ennes&#160;\u00bb. Entre ces deux bornes s\u2019est d\u00e9velopp\u00e9 un r\u00e9gime aussi fertile que fragile, le <em>gouvernement repr\u00e9sentatif<\/em>, dont la consolidation est ins\u00e9parable de la mont\u00e9e en puissance d\u2019un ph\u00e9nom\u00e8ne qui n\u2019a pas trouv\u00e9 de nom m\u00eame si on l\u2019enveloppe ordinairement dans la vaste et confortable couverture de la d\u00e9mocratie, et que j\u2019appellerai le <em>peuple politique<\/em>. Tels sont donc les trois ressorts constituants, si je puis dire, de l\u2019histoire politique de l\u2019Europe moderne&#160;: l\u2019\u00c9tat, le gouvernement repr\u00e9sentatif, le peuple politique, dont je vais consid\u00e9rer la relation dynamique, bien s\u00fbr tr\u00e8s sch\u00e9matiquement.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00ab&#160;Tels sont donc les trois ressorts constituants, si je puis dire, de l\u2019histoire politique de l\u2019Europe moderne&#160;: l\u2019\u00c9tat, le gouvernement repr\u00e9sentatif, le peuple politique, dont je vais consid\u00e9rer la relation dynamique, bien s\u00fbr tr\u00e8s sch\u00e9matiquement.&#160;\u00bb<\/p><cite>Pierre Manent<\/cite><\/blockquote><\/figure>\n\n\n\n<p>L\u2019\u00c9tat na\u00eet puis grandit sous l\u2019enveloppe protectrice d\u2019une r\u00e9alit\u00e9 politique famili\u00e8re et ordinaire, que seul le mot anglais <em>ruler<\/em> d\u00e9signe avec la g\u00e9n\u00e9ralit\u00e9 suffisante, et qui, dans notre contexte, se concr\u00e9tisa dans la figure du roi chr\u00e9tien. On t\u00e2tonna durant des si\u00e8cles pour pr\u00e9ciser en termes juridiques et politiques les caract\u00e8res de ce pouvoir, sans parvenir \u00e0 d\u00e9terminer s\u2019il existait ou non une constitution fran\u00e7aise digne du nom. En tout cas, sous cette figure concr\u00e8te et impossible \u00e0 cerner avec pr\u00e9cision, se d\u00e9veloppa une r\u00e9alit\u00e9 singuli\u00e8rement nouvelle, une r\u00e9alit\u00e9 que l\u2019on pouvait, elle, d\u00e9finir en termes abstraits et pr\u00e9cis, et qui m\u00eame tendait \u00e0 se conformer de plus en plus \u00e0 sa d\u00e9finition abstraite jusqu\u2019\u00e0 co\u00efncider tendanciellement avec elle. \u00c0 l\u2019enseigne du roi chr\u00e9tien grandit donc l\u2019\u00c9tat moderne, c\u2019est-\u00e0-dire ultimement une institution souveraine, garante et protectrice des droits \u00e9gaux des soci\u00e9taires. Au moment de la R\u00e9volution fran\u00e7aise, cet \u00c9tat se d\u00e9barrassa violemment de sa peau de serpent f\u00e9odale, pour reprendre une formule tr\u00e8s expressive de Marx, et d\u00e9ploya sa force en m\u00eame temps que sa nudit\u00e9 et sa vuln\u00e9rabilit\u00e9. Que faire en effet de cette position \u00e9minente et surplombante o\u00f9 il se trouvait soudain port\u00e9&#160;? Il devait certes garantir et prot\u00e9ger les droits de l\u2019homme qu\u2019il venait de proclamer, mais, cette finalit\u00e9 admise, qui allait d\u00e9lib\u00e9rer des moyens et les mettre en \u0153uvre&#160;? Ce furent donc les repr\u00e9sentants du peuple, ou, pour le dire en termes plus rigoureux, les institutions du gouvernement repr\u00e9sentatif que l\u2019on \u00e9labora et mit en \u0153uvre, non sans de grandes difficult\u00e9s, au cours du si\u00e8cle suivant.<\/p>\n\n\n\n<p>Dans l\u2019Ancien R\u00e9gime, l\u2019\u00c9tat et le gouvernement \u00e9taient en quelque sorte confondus par la t\u00eate. Comme Louis XIV est suppos\u00e9 l\u2019avoir dit avec autant de sobri\u00e9t\u00e9 que d\u2019exactitude&#160;: L\u2019\u00c9tat, c\u2019est moi. Sous le nouveau r\u00e9gime, \u00c9tat et gouvernement sont d\u00e9sormais distincts, mais fonctionnellement solidaires. Le gouvernement repr\u00e9sentatif emploie l\u2019\u00c9tat comme son instrument pour garantir et \u00e9tendre les droits des soci\u00e9taires, tandis que les citoyens, de plus en plus \u00e9galis\u00e9s, peuvent de mieux en mieux constituer ce que j\u2019ai appel\u00e9 un peuple politique, un peuple qui, en choisissant de plus en plus librement ses repr\u00e9sentants, se rend de plus en plus ind\u00e9pendant des pouvoirs sociaux. Ainsi&#160;: un gouvernement de plus en plus repr\u00e9sentatif, un \u00c9tat de plus en plus \u00e9galisateur, un peuple de plus en plus politique, c\u2019est la solidarit\u00e9 et l\u2019op\u00e9ration commune de ces trois ressorts qui produisirent ce qu\u2019on a appel\u00e9 le mouvement d\u00e9mocratique, avec les caract\u00e8res de radicalit\u00e9 et d\u2019irr\u00e9sistibilit\u00e9 qui frapp\u00e8rent tr\u00e8s t\u00f4t les observateurs. <\/p>\n\n\n\n<p>Chacun des trois grands ressorts a ses ressources de force et ses points de faiblesse. L\u2019\u00c9tat est un instrument immense, d\u00e8s longtemps install\u00e9, et dont le mandat \u00e0 lui confi\u00e9 \u00e9tend sans limite assignable le champ d\u2019intervention. Il souffre d\u2019une lourdeur et d\u2019une lenteur proportionnelles \u00e0 son volume et \u00e0 son poids. Le gouvernement repr\u00e9sentatif dispose de la force incluse dans le fait m\u00eame de gouverner, mais il d\u00e9pend de son instrument \u00e9tatique, et aussi du peuple dont la politisation est pour le gouvernement un principe de force ou de faiblesse selon les circonstances. Quant au peuple, sa m\u00e9fiance \u00e0 l\u2019\u00e9gard de ses repr\u00e9sentants et aussi la nature de ses besoins le conduisent \u00e0 chercher un appui \u00e0 sa faiblesse dans la force de l\u2019\u00c9tat. Hors les p\u00e9riodes de r\u00e9volution, sa force propre ne s\u2019actualise que par la confiance et l\u2019encouragement donn\u00e9s \u00e0 un gouvernement qui prend en compte, plus ou moins judicieusement, ses int\u00e9r\u00eats. Un coup d\u2019\u0153il jet\u00e9 sur notre histoire politique fait ais\u00e9ment mesurer combien fut variable le poids relatif des facteurs, et aussi le cr\u00e9dit g\u00e9n\u00e9ral accord\u00e9 au dispositif d\u2019ensemble.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00ab&#160;Sous le nouveau r\u00e9gime, \u00c9tat et gouvernement sont d\u00e9sormais distincts, mais fonctionnellement solidaires. Le gouvernement repr\u00e9sentatif emploie l\u2019\u00c9tat comme son instrument pour garantir et \u00e9tendre les droits des soci\u00e9taires, tandis que les citoyens, de plus en plus \u00e9galis\u00e9s, peuvent de mieux en mieux constituer ce que j\u2019ai appel\u00e9 un <em>peuple politique<\/em>.&#160;\u00bb<\/p><cite>Pierre Manent<\/cite><\/blockquote><\/figure>\n\n\n\n<p>En d\u00e9pit des variations de la force relative des facteurs, le pivot du dispositif reste n\u00e9cessairement le gouvernement repr\u00e9sentatif puisqu\u2019encore une fois c\u2019est lui qui gouverne. En tant que gouvernement, il vise \u00e0 bien gouverner. En tant que repr\u00e9sentatif, il vise \u00e0 \u00eatre\u2026 repr\u00e9sentatif, c\u2019est-\u00e0-dire \u00e0 faire en sorte que le peuple se reconnaisse en lui. Le postulat du r\u00e9gime moderne est bien s\u00fbr que les deux aspects tendent normalement \u00e0 co\u00efncider, mais ce qui est normal n\u2019est pas n\u00e9cessairement le plus fr\u00e9quent. En tout cas, le degr\u00e9 de repr\u00e9sentativit\u00e9 du gouvernement est un th\u00e8me sp\u00e9cifique et un ressort constant du r\u00e9gime repr\u00e9sentatif.  Selon sa tendance peut-\u00eatre la plus lourde, le travail de la repr\u00e9sentation consiste \u00e0 produire un gouvernement de plus en plus repr\u00e9sentatif d\u2019un peuple de plus en plus repr\u00e9sentable. Un peuple de plus en plus repr\u00e9sentable, je l\u2019ai indiqu\u00e9, c\u2019est un peuple de plus en plus \u00e9mancip\u00e9 des pouvoirs sociaux, c\u2019est-\u00e0-dire des pouvoirs non repr\u00e9sentatifs. Un gouvernement de plus en plus repr\u00e9sentatif, c\u2019est un gouvernement qui tend \u00e0 se regarder comme le peuple le regarde lui-m\u00eame, comme au service exclusif de ses droits et besoins tels que le peuple les con\u00e7oit. Le gouvernement tend alors \u00e0 se confondre avec l\u2019\u00c9tat gardien et facteur de l\u2019\u00e9galit\u00e9 des soci\u00e9taires, ou \u00e0 r\u00e9duire son action \u00e0 la mise en action de l\u2019\u00c9tat, ce que l\u2019on appellera l\u2019\u00c9tat-providence. \u00c0 ce stade, gouverner est devenu un caract\u00e8re r\u00e9cessif du gouvernement repr\u00e9sentatif, qui ne sait plus rien faire qu\u2019actionner et \u00e9tendre l\u2019\u00c9tat-providence. Quant au peuple politique, il est d\u00e9sormais enti\u00e8rement \u00e9mancip\u00e9 des pouvoirs sociaux, mais, ne voyant plus dans le gouvernement que l\u2019\u00c9tat protecteur des droits et pourvoyeur des services, l\u2019imagination du peuple est priv\u00e9e du ressort qui l\u2019\u00e9largissait aux dimensions du corps politique. Le peuple a cess\u00e9 d\u2019\u00eatre un peuple politique.<\/p>\n\n\n\n<p>Si le gouvernement repr\u00e9sentatif n\u2019est plus que l\u2019auxiliaire de l\u2019\u00c9tat des droits, ce dernier tend \u00e0 se rendre de plus en plus ind\u00e9pendant du gouvernement, et donc de l\u2019unit\u00e9 politique que formait le peuple politique organis\u00e9 selon ce r\u00e9gime. L\u2019\u00c9tat des droits tend \u00e0 se rendre de plus en plus ind\u00e9pendant des gouvernements nationaux et m\u00eame des appareils \u00e9tatiques constitu\u00e9s. Il se d\u00e9ploie en se ramifiant \u00e0 travers mille juridictions, commissions, comit\u00e9s, r\u00e8gles de bonne gouvernance, trait\u00e9s et pactes qui font p\u00e9n\u00e9trer l\u2019\u00c9tat des droits dans le m\u00e9tabolisme intime de la vie europ\u00e9enne, le pouvoir judiciaire, ainsi d\u00e9tach\u00e9 de tout gouvernement politique, s\u2019exer\u00e7ant d\u00e9sormais comme un pouvoir spirituel.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00ab&#160;L\u2019\u00c9tat des droits tend \u00e0 se rendre de plus en plus ind\u00e9pendant des gouvernements nationaux et m\u00eame des appareils \u00e9tatiques constitu\u00e9s.&#160;\u00bb<\/p><cite>Pierre Manent<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Si le gouvernement repr\u00e9sentatif s\u2019est impos\u00e9 dans l\u2019histoire europ\u00e9enne, c\u2019est parce que, en comparaison avec les concurrents \u00e9tablis ou candidats, il est apparu comme un meilleur gouvernement. Son caract\u00e8re repr\u00e9sentatif r\u00e9sidait alors en ceci qu\u2019il r\u00e9pondait mieux aux besoins objectifs d\u2019un peuple en voie de politisation, c\u2019est-\u00e0-dire de participation \u00e0 une action et une \u00e9ducation communes. La part de \u00ab&#160;r\u00e9flexion&#160;\u00bb, si t\u00f4t et si bien discern\u00e9e par Benjamin Constant, resta en r\u00e9alit\u00e9 longtemps comprim\u00e9e par l\u2019horizon d\u2019action collective qu\u2019impliquait l\u2019entr\u00e9e progressive des classes et groupes sociaux dans la r\u00e9publique en voie de d\u00e9mocratisation. Aujourd\u2019hui que la logique r\u00e9flexive de la repr\u00e9sentation et des jouissances priv\u00e9es bloque tout mouvement vers une action commune, la part repr\u00e9sentative du gouvernement repr\u00e9sentatif a d\u00e9vor\u00e9 sa part gouvernementale, ruinant ainsi le r\u00e9gime lui-m\u00eame. Il est donc oiseux de chercher les voies d\u2019une d\u00e9mocratie participative pour compl\u00e9ter la d\u00e9mocratie repr\u00e9sentative, puisque celle-ci a cess\u00e9 de fonctionner. La question est de savoir s\u2019il est encore possible de la faire revivre.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00ab&#160;Aujourd\u2019hui que la logique r\u00e9flexive de la repr\u00e9sentation et des jouissances priv\u00e9es bloque tout mouvement vers une action commune, la part repr\u00e9sentative du gouvernement repr\u00e9sentatif a d\u00e9vor\u00e9 sa part gouvernementale, ruinant ainsi le r\u00e9gime lui-m\u00eame.&#160;\u00bb<\/p><cite>Pierre Manent<\/cite><\/blockquote><\/figure>\n\n\n\n<p>L\u2019analyse que je viens d\u2019esquisser sugg\u00e8re qu\u2019il me semblera difficile de donner une r\u00e9ponse positive \u00e0 cette question. Je voudrais en tout cas donner une description un peu plus directe de la situation pr\u00e9sente. Les d\u00e9veloppements que j\u2019ai r\u00e9sum\u00e9s tr\u00e8s sch\u00e9matiquement ont conduit \u00e0 une division sociale et morale de grande ampleur entre d\u2019une part une classe transnationale qui s\u2019oriente sur les droits et les opportunit\u00e9s des individus sans \u00e9prouver le besoin ni le d\u00e9sir d\u2019une appartenance politique forte, d\u2019autre part des couches d\u00e9sign\u00e9es aujourd\u2019hui comme populistes, des peuples populistes si l\u2019on veut, c\u2019est-\u00e0-dire attach\u00e9s \u00e0 une forme de vie commune qui ne peut plus \u00eatre d\u00e9fendue politiquement puisqu\u2019il est impossible de l\u2019inscrire intelligiblement dans l\u2019espace de la gouvernance des r\u00e8gles et des droits. Non seulement ces deux ensembles sociaux et moraux ont les plus grandes peines \u00e0 communiquer, mais les uns comme les autres ont perdu tout int\u00e9r\u00eat v\u00e9ritable pour les grandeurs et les mis\u00e8res de la d\u00e9mocratie repr\u00e9sentative. La classe transnationale est satisfaite de la mani\u00e8re dont les r\u00e8gles sont aujourd\u2019hui administr\u00e9es, en tout cas de la mani\u00e8re dont les institutions europ\u00e9ennes orientent aujourd\u2019hui l\u2019administration des r\u00e8gles, et elle s\u2019\u00e9pargne tout effort un peu s\u00e9rieux pour ranimer un r\u00e9gime repr\u00e9sentatif qui exigerait de faire place \u00e0 un peuple qui lui semble priv\u00e9 de raison. Le peuple de tendance populiste de son c\u00f4t\u00e9, qui depuis longtemps ne rencontre que le m\u00e9pris de la classe transnationale et qui redoute par ailleurs les cons\u00e9quences politiques, sociales et morales d\u2019une immigration advenue sans d\u00e9lib\u00e9ration ni direction politique, est port\u00e9 \u00e0 une affirmation de soi d\u2019autant plus sommaire et protestataire que la soci\u00e9t\u00e9 dans son ensemble a perdu l\u2019usage et l\u2019emploi des projets collectifs un peu \u00e9labor\u00e9s, les droits individuels apparaissant comme la seule r\u00e9f\u00e9rence intelligible et l\u00e9gitime. Comment saurait-il faire entendre de mani\u00e8re un peu convaincante et pertinente ses inqui\u00e9tudes sur le sort commun quand le simple souci du commun a \u00e9t\u00e9 frapp\u00e9 d\u2019interdit au motif qu\u2019il n\u2019y a de souci l\u00e9gitime que de l\u2019homme en g\u00e9n\u00e9ral&#160;? En tout cas la classe transnationale trouve parfaitement l\u00e9gitime que l\u2019on ne tienne aucun compte des r\u00e9sultats de r\u00e9f\u00e9rendums organis\u00e9s pourtant dans des conditions de l\u00e9galit\u00e9 et de l\u00e9gitimit\u00e9 impeccables, elle reprend de plus en plus volontiers les attendus de l\u2019argumentaire censitaire, et souhaite de plus en plus explicitement que les d\u00e9cisions importantes pour la vie collective soient soustraites au vote d\u00e9mocratique. Le peuple populiste de son c\u00f4t\u00e9 semble de moins en moins dispos\u00e9 \u00e0 tenir compte du r\u00e9sultat d\u2019\u00e9lections parfaitement r\u00e9guli\u00e8res. On peut penser qu\u2019il sacrifierait sans trop de peine certains aspects au moins du r\u00e9gime d\u00e9mocratique s\u2019il recevait une proposition un peu convaincante et vigoureuse de tenir compte de certains de ses besoins fondamentaux, en premier lieu la pr\u00e9servation de la forme de vie qui est la sienne. Bref, les deux composantes de notre monde social-politique s\u2019\u00e9loignent l\u2019une de l\u2019autre, en m\u00eame temps qu\u2019elles s\u2019\u00e9loignent l\u2019une et l\u2019autre de la d\u00e9mocratie repr\u00e9sentative. La question pratique est de savoir si se feront jour des forces politiques, qui supposent des opinions politiques, capables de \u00ab&#160;moyenner&#160;\u00bb entre les deux parties, ou les deux partis, et, ce faisant, de ramener l\u2019un et l\u2019autre vers la d\u00e9mocratie repr\u00e9sentative.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00ab&#160;Comment le peuple populiste saurait-il faire entendre de mani\u00e8re un peu convaincante et pertinente ses inqui\u00e9tudes sur le sort commun quand le simple souci du commun a \u00e9t\u00e9 frapp\u00e9 d\u2019interdit au motif qu\u2019il n\u2019y a de souci l\u00e9gitime que de l\u2019homme en g\u00e9n\u00e9ral&#160;?&#160;\u00bb<\/p><cite>Pierre Manent<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Ce qui contribue \u00e0 rendre le pronostic peu favorable, c\u2019est que ces divisions et ces obstacles n\u2019affectent pas des r\u00e9gimes repr\u00e9sentatifs en voie de construction comme au XIX\u00e8me si\u00e8cle en France et dans beaucoup de pays europ\u00e9ens, mais un ensemble humain qui \u00e9tait parvenu dans la seconde moiti\u00e9 du XX\u00e8me si\u00e8cle \u00e0 \u00e9tablir des r\u00e9gimes repr\u00e9sentatifs que l\u2019on est tent\u00e9 de dire presque parfaits, si parfaits en tout cas que la fin de l\u2019histoire parut un temps avoir sonn\u00e9. On peut donc craindre que nous observions et subissions l\u2019\u00e9puisement du r\u00e9gime politique sous lequel l\u2019Europe, c\u2019est-\u00e0-dire l\u2019ensemble form\u00e9 par les nations europ\u00e9ennes, est parvenue au z\u00e9nith de sa puissance et de son \u00e9clat. Rappelons bri\u00e8vement le cahier des charges, l\u2019ampleur du travail accompli sous ce r\u00e9gime ou au long de l\u2019arc historique qui a culmin\u00e9 dans ce r\u00e9gime&#160;: surmonter les divisions religieuses par la force et la l\u00e9gitimit\u00e9 sup\u00e9rieures de l\u2019\u00c9tat souverain&#160;; faire de tous, fid\u00e8les de diff\u00e9rentes religions, habitants de diff\u00e9rentes r\u00e9gions, membres de groupes sociaux diff\u00e9rents, paysans, ouvriers, etc., faire de tous des citoyens \u00e9gaux en en faisant des Fran\u00e7ais tous \u00e9galement attach\u00e9s \u00e0 leur pays&#160;; les faire entrer dans une \u00e9ducation commune port\u00e9e par une r\u00e9publique qui r\u00e9clamait et m\u00e9ritait loyaut\u00e9 et adh\u00e9sion. La finalit\u00e9 de cette construction historique peut \u00eatre r\u00e9sum\u00e9e ainsi&#160;: participer avec une enti\u00e8re libert\u00e9 \u00e0 une chose commune qui a autorit\u00e9 pour donner forme \u00e0 la vie des citoyens. Cette perspective a \u00e9t\u00e9 progressivement abandonn\u00e9e au cours du dernier demi-si\u00e8cle. La seule perspective d\u2019action qui soit aujourd\u2019hui l\u00e9gitime, c\u2019est celle qui vise l\u2019administration des hommes en g\u00e9n\u00e9ral. Les subdivisions ou circonscriptions de l\u2019humanit\u00e9 n\u2019ont plus de sens actif \u00e0 nos yeux, ne sont plus des cadres ou des objets fondamentaux de notre action, nous ne les admettons que comme des motifs d\u2019affection, des th\u00e8mes sentimentaux, en aucun cas comme l\u2019objet d\u2019une loyaut\u00e9 exclusive et d\u2019un engagement spirituel. D\u00e8s lors, la t\u00e2che de ranimer la r\u00e9publique repr\u00e9sentative para\u00eet au-dessus de nos forces pour deux raisons&#160;: elle r\u00e9clame des moyens et une ambition d\u2019agir qui semblent bien nous faire d\u00e9faut&#160;; en outre, cet effort nous l\u2019avons fait, nous l\u2019avons laiss\u00e9 se d\u00e9faire, nous n\u2019avons pas le go\u00fbt de le refaire, il r\u00e9clamerait de nous une \u00ab&#160;na\u00efvet\u00e9&#160;\u00bb que nous avons perdue.  S\u2019il en est ainsi, nous sommes oblig\u00e9s de valider le diagnostic de Benjamin Constant&#160;: notre \u00ab&#160;r\u00e9flexion&#160;\u00bb nous emp\u00eache d\u2019agir. D\u00e8s lors les deux partis entre lesquels l\u2019opinion se divise, ces deux partis se tromperaient \u00e9galement&#160;: les uns croient que nous pourrions vivre sans une communaut\u00e9 politique d\u2019action&#160;; les autres croient que nous pourrions cr\u00e9er ou recr\u00e9er une telle communaut\u00e9 politique d\u2019action.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00ab&#160;La seule perspective d\u2019action qui soit aujourd\u2019hui l\u00e9gitime, c\u2019est celle qui vise l\u2019administration des hommes en g\u00e9n\u00e9ral.&#160;\u00bb<\/p><cite>Pierre MAnent<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Comment redonner plausibilit\u00e9, l\u00e9gitimit\u00e9, force \u00e0 une action commune dont l\u2019ensemble europ\u00e9en serait le cadre nourricier et dont les nations europ\u00e9ennes seraient les agents principaux&#160;?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab&#160;&#160;Les deux composantes de notre monde social-politique s\u2019\u00e9loignent l\u2019une de l\u2019autre, en m\u00eame temps qu\u2019elles s\u2019\u00e9loignent l\u2019une et l\u2019autre de la d\u00e9mocratie repr\u00e9sentative. La question pratique est de savoir si se feront jour des forces politiques [&#8230;] capables de \u00ab&#160;&#160;moyenner&#160;&#160;\u00bb entre les deux parties, ou les deux partis, et, ce faisant, de ramener l\u2019un et l\u2019autre vers la d\u00e9mocratie repr\u00e9sentative.&#160;&#160;\u00bb Par Pierre Manent<\/p>\n","protected":false},"author":10,"featured_media":43222,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-editorials.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":0,"footnotes":""},"categories":[1734],"tags":[],"staff":[2034],"editorial_format":[4941],"serie":[],"audience":[],"geo":[],"class_list":["post-43220","post","type-post","status-publish","format-standard","hentry","category-doctrines","staff-pierre-manent","editorial_format-doctrine"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":43222,"excerpt":"\u00ab\u00a0Les deux composantes de notre monde social-politique s\u2019\u00e9loignent l\u2019une de l\u2019autre, en m\u00eame temps qu\u2019elles s\u2019\u00e9loignent l\u2019une et l\u2019autre de la d\u00e9mocratie repr\u00e9sentative. La question pratique est de savoir si se feront jour des forces politiques [...] capables de \u00ab moyenner \u00bb entre les deux parties, ou les deux partis, et, ce faisant, de ramener l\u2019un et l\u2019autre vers la d\u00e9mocratie repr\u00e9sentative.\u00a0\u00bb Par Pierre Manent","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le peuple politique | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/07\/14\/le-peuple-politique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le peuple politique | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"\u00ab&#160;Les deux composantes de notre monde social-politique s\u2019\u00e9loignent l\u2019une de l\u2019autre, en m\u00eame temps qu\u2019elles s\u2019\u00e9loignent l\u2019une et l\u2019autre de la d\u00e9mocratie repr\u00e9sentative. La question pratique est de savoir si se feront jour des forces politiques [...] capables de \u00ab&#160;moyenner&#160;\u00bb entre les deux parties, ou les deux partis, et, ce faisant, de ramener l\u2019un et l\u2019autre vers la d\u00e9mocratie repr\u00e9sentative.&#160;\u00bb Par Pierre Manent\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2019\/07\/14\/le-peuple-politique\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-13T23:50:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-14T00:00:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/07\/Monet-montorgueil.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"847\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matheo Malik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheo Malik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/07\/14\/le-peuple-politique\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/07\/14\/le-peuple-politique\/\",\"name\":\"Le peuple politique | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/07\/14\/le-peuple-politique\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/07\/14\/le-peuple-politique\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/07\/Monet-montorgueil.jpeg\",\"datePublished\":\"2019-07-13T23:50:43+00:00\",\"dateModified\":\"2019-07-14T00:00:07+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/07\/14\/le-peuple-politique\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2019\/07\/14\/le-peuple-politique\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/07\/14\/le-peuple-politique\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/07\/Monet-montorgueil.jpeg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/07\/Monet-montorgueil.jpeg\",\"width\":847,\"height\":1400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/07\/14\/le-peuple-politique\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le peuple politique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\",\"name\":\"Matheo Malik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"caption\":\"Matheo Malik\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le peuple politique | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2019\/07\/14\/le-peuple-politique\/","og_locale":"fr_FR","og_type":"article","og_title":"Le peuple politique | Le Grand Continent","og_description":"\u00ab&#160;Les deux composantes de notre monde social-politique s\u2019\u00e9loignent l\u2019une de l\u2019autre, en m\u00eame temps qu\u2019elles s\u2019\u00e9loignent l\u2019une et l\u2019autre de la d\u00e9mocratie repr\u00e9sentative. La question pratique est de savoir si se feront jour des forces politiques [...] capables de \u00ab&#160;moyenner&#160;\u00bb entre les deux parties, ou les deux partis, et, ce faisant, de ramener l\u2019un et l\u2019autre vers la d\u00e9mocratie repr\u00e9sentative.&#160;\u00bb Par Pierre Manent","og_url":"https:\/\/legrandcontinent.eu\/fr\/2019\/07\/14\/le-peuple-politique\/","og_site_name":"Le Grand Continent","article_published_time":"2019-07-13T23:50:43+00:00","article_modified_time":"2019-07-14T00:00:07+00:00","og_image":[{"width":847,"height":1400,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/07\/Monet-montorgueil.jpeg","type":"image\/jpeg"}],"author":"Matheo Malik","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Matheo Malik","Dur\u00e9e de lecture estim\u00e9e":"15 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/07\/14\/le-peuple-politique\/","url":"https:\/\/legrandcontinent.eu\/fr\/2019\/07\/14\/le-peuple-politique\/","name":"Le peuple politique | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/07\/14\/le-peuple-politique\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/07\/14\/le-peuple-politique\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/07\/Monet-montorgueil.jpeg","datePublished":"2019-07-13T23:50:43+00:00","dateModified":"2019-07-14T00:00:07+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/07\/14\/le-peuple-politique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2019\/07\/14\/le-peuple-politique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/07\/14\/le-peuple-politique\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/07\/Monet-montorgueil.jpeg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/07\/Monet-montorgueil.jpeg","width":847,"height":1400},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/07\/14\/le-peuple-politique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Le peuple politique"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45","name":"Matheo Malik","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","caption":"Matheo Malik"}}]}},"lgc_categories":[{"id":1734,"name":"Livres","slug":"doctrines"}],"lgc_author":{"id":2034,"name":"Pierre Manent","slug":"pierre-manent","description":null,"first_name":null,"last_name":null,"picture":null},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/07\/Monet-montorgueil.jpeg","width":847,"height":1400,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/07\/Monet-montorgueil.jpeg","width":847,"height":1400,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/43220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=43220"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/43220\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/43222"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=43220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=43220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=43220"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=43220"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=43220"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=43220"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=43220"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=43220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}