{"id":39858,"date":"2019-06-07T12:53:18","date_gmt":"2019-06-07T10:53:18","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=39858"},"modified":"2019-06-07T12:56:20","modified_gmt":"2019-06-07T10:56:20","slug":"le-retrait-des-conseillers-strategiques-russes-du-venezuela-un-coup-porte-au-regime-de-maduro","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2019\/06\/07\/le-retrait-des-conseillers-strategiques-russes-du-venezuela-un-coup-porte-au-regime-de-maduro\/","title":{"rendered":"Le retrait des conseillers strat\u00e9giques russes du Venezuela&#160;: un coup port\u00e9 au r\u00e9gime de Maduro&#160;?"},"content":{"rendered":"\n<p><em>Moscou.<\/em> Le <em>Wall Street Journal, <\/em>puis le pr\u00e9sident am\u00e9ricain Donald Trump dans un tweet, ont indiqu\u00e9 au d\u00e9but du mois de juin que l\u2019aide russe au Venezuela touche \u00e0 fin&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-39858' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/06\/07\/le-retrait-des-conseillers-strategiques-russes-du-venezuela-un-coup-porte-au-regime-de-maduro\/#easy-footnote-bottom-1-39858' title='GROVE Thomas, &lt;a href=&quot;https:\/\/www.wsj.com\/articles\/in-a-blow-to-maduro-russia-withdraws-key-defense-support-to-venezuela-11559486826&quot;&gt;In a blow to Maduro, Russia Withdraws Key Defense Support to Venezuela&lt;\/a&gt;, The Wall Street Journal, 2 juin 2019.'><sup>1<\/sup><\/a><\/span><\/span>. Or, la Russie est un alli\u00e9 capital pour le r\u00e9gime du pr\u00e9sident Nicolas Maduro. Selon le journal am\u00e9ricain, le gouvernement de Nicolas Madura ne dispose plus des moyens \u00e9conomiques pour financer l\u2019achat d\u2019armes et recevoir de l\u2019aide de la Russie. ll est peu probable que le Venezuela puisse redevenir un client majeur pour la Russie dans le domaine militaire comme c\u2019\u00e9tait le cas par le pass\u00e9 sous l\u2019impulsion du pr\u00e9d\u00e9cesseur de Nicolas Maduro, Hugo Chavez. Ainsi, en l\u2019absence de paiement et d\u2019opportunit\u00e9s pour signer des nouveaux contrats dans un futur proche, Rostec, une compagnie \u00e9tatique russe charg\u00e9e d\u2019entra\u00eener les militaires v\u00e9n\u00e9zu\u00e9liens et de vendre des armes, aurait retir\u00e9 ses hommes de Caracas.<\/p>\n\n\n\n<p>En revanche, le gouvernement russe s\u2019est empress\u00e9 de r\u00e9affirmer son soutien \u00e0 Nicolas Maduro en indiquant que des troupes russes continuaient leurs coop\u00e9rations avec les troupes v\u00e9n\u00e9zu\u00e9liennes&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-39858' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/06\/07\/le-retrait-des-conseillers-strategiques-russes-du-venezuela-un-coup-porte-au-regime-de-maduro\/#easy-footnote-bottom-2-39858' title='&lt;a href=&quot;https:\/\/ria.ru\/20190603\/1555229373.html&quot;&gt;\u0422\u0440\u0430\u043c\u043f&amp;#160;: \u0420\u043e\u0441\u0441\u0438\u044f \u0437\u0430\u044f\u0432\u0438\u043b\u0430 \u043e \u0432\u044b\u0432\u043e\u0434\u0435 \u00ab&amp;#160;\u0431\u043e\u043b\u044c\u0448\u0438\u043d\u0441\u0442\u0432\u0430 \u0441\u0432\u043e\u0438\u0445 \u043b\u044e\u0434\u0435\u0439&amp;#160;\u00bb \u0438\u0437 \u0412\u0435\u043d\u0435\u0441\u0443\u044d\u043b\u044b&lt;\/a&gt;, \u0420\u0418\u0410 \u041d\u043e\u0432\u043e\u0441\u0442\u0438, 3 juin 2019.'><sup>2<\/sup><\/a><\/span><\/span>. Car, s\u2019il \u00e9tait av\u00e9r\u00e9, le retrait des conseillers de Rostec ne signifierait cependant pas que la Russie cesse de soutenir le gouvernement v\u00e9n\u00e9zu\u00e9lien. En effet, l\u2019arriv\u00e9e en mars de plus de 100 militaires russes, de 35 tonnes d\u2019\u00e9quipements ainsi que de personnel sp\u00e9cialis\u00e9 dans le domaine de la cyber-s\u00e9curit\u00e9 financ\u00e9 par le <em>Service F\u00e9d\u00e9ral pour la Coop\u00e9ration Militaire et Technique de la Russie<\/em> (FSVT) compense le d\u00e9part des sp\u00e9cialistes de Rostec&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-39858' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/06\/07\/le-retrait-des-conseillers-strategiques-russes-du-venezuela-un-coup-porte-au-regime-de-maduro\/#easy-footnote-bottom-3-39858' title='SPETALNICK Matt, &lt;a href=&quot;https:\/\/www.reuters.com\/article\/us-venezuela-politics-russians\/russian-deployment-in-venezuela-includes-cybersecurity-personnel-u-s-official-idUSKCN1R72FX?il=0&quot;&gt;Russian deployment in Venezuela includes &amp;lsquo;cybersecurity personnel&amp;rsquo;&amp;#160;: U.S. official&lt;\/a&gt;&lt;em&gt;, &lt;\/em&gt;Reuters, 26 mars 2019.'><sup>3<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>Il est n\u00e9cessaire de faire une distinction entre deux branches charg\u00e9es des ventes d\u2019armes russe&#160;:  Rostec, est une compagnie \u00e0 la recherche de profit, et le FSVT est un organe li\u00e9 au Minist\u00e8re de la D\u00e9fense. La compagnie Rostec, et sa filiale Rosoboronexport, per\u00e7oit des commissions sur les contrats de ventes d\u2019armes. Elle a donc tout int\u00e9r\u00eat \u00e0 signer des contrats avec des puissances stables \u00e9conomiquement et \u00e0 vendre des \u00e9quipements co\u00fbteux et sophistiqu\u00e9s. Rosoboronexport est ainsi parvenu \u00e0 signer un accord avec l\u2019Inde pour exporter un produit phare de la Russie, le syst\u00e8me de d\u00e9fense S-400&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-39858' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/06\/07\/le-retrait-des-conseillers-strategiques-russes-du-venezuela-un-coup-porte-au-regime-de-maduro\/#easy-footnote-bottom-4-39858' title='&lt;a href=&quot;https:\/\/rostec.ru\/en\/news\/rosoboronexport-contract-with-india-for-s-400-missile-systems-biggest-ever-deal-in-company-history\/&quot;&gt;Rosoboronexport&amp;#160;: Contract with India for S-400 Missile Systems \u2013 Biggest-ever Deal in Company History&lt;\/a&gt;, Rostec News, 5 october, 2018.'><sup>4<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>Lorsque le Venezuela \u00e9tait dans une p\u00e9riode de croissance \u00e9conomique sous Hugo Chavez, notamment de 2004 \u00e0 2013, Rostec multipliait la signature de contrats avec le Venezuela. C\u2019est ainsi qu\u2019en 2006 un contrat a \u00e9t\u00e9 sign\u00e9 entre la Russie, repr\u00e9sent\u00e9 par Rosoboronexport, et le gouvernement de Caracas pour assurer la construction d\u2019une usine de production de Kalachnikov AK-103&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-39858' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/06\/07\/le-retrait-des-conseillers-strategiques-russes-du-venezuela-un-coup-porte-au-regime-de-maduro\/#easy-footnote-bottom-5-39858' title='&lt;a href=&quot;https:\/\/russiabusinesstoday.com\/manufacturing\/venezuelan-factory-to-start-producing-kalashnikov-assault-rifles-next-year\/&quot;&gt;Venezuelan Factory to Start Producing Kalashnikov Assault Rifles Next Year&lt;\/a&gt;,Russia Business Today, 24 ao\u00fbt 2018. '><sup>5<\/sup><\/a><\/span><\/span>. Le Wall Street Journal indique dans l\u2019article publi\u00e9 d\u00e9but juin que la construction du site de production va \u00eatre interrompu \u00e0 cause de l\u2019incapacit\u00e9 de Caracas d\u2019assurer le paiement. En revanche, Rosoboronexport indiquait en janvier 2019 que l\u2019instabilit\u00e9 au Venezuela ne m\u00e8nerait pas \u00e0 l\u2019arr\u00eat de la construction de l\u2019usine. Rosoboronexpor tient \u00e0 respecter ses obligations contractuelles pour \u00eatre per\u00e7u comme un acteur fiable sur la sc\u00e8ne internationale.<\/p>\n\n\n\n<p>En revanche, puisque l\u2019\u00e9conomie v\u00e9n\u00e9zu\u00e9lienne est actuellement en chute libre, le r\u00e9gime de Maduro n\u2019a plus les moyens de signer de nouveaux contrats avec Rostec, une compagnie elle-m\u00eame en difficult\u00e9 \u00e9conomiquement. Il est donc peu \u00e9tonnant que la compagnie russe se retire pour laisser le soin au FSVTS d\u2019assurer la protection de Maduro. Contrairement \u00e0 Rostec, FSVTS est financ\u00e9 directement par le Kremlin. Les ventes de FSVTS ne sont pas motiv\u00e9es en premier lieu par la recherche du profit \u00e9conomique.  Cet organe \u00e9tatique a ainsi accept\u00e9 par exemple de pr\u00eater 50M$ \u00e0 Cuba pour des raisons strat\u00e9giques et g\u00e9opolitiques&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-39858' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/06\/07\/le-retrait-des-conseillers-strategiques-russes-du-venezuela-un-coup-porte-au-regime-de-maduro\/#easy-footnote-bottom-6-39858' title='&lt;a href=&quot;https:\/\/tass.ru\/armiya-i-opk\/6040113&quot;&gt;\u201c\u0420\u043e\u0441\u043e\u0431\u043e\u0440\u043e\u043d\u044d\u043a\u0441\u043f\u043e\u0440\u0442\u201d&amp;#160;: \u043a\u0440\u0438\u0437\u0438\u0441 \u0432 \u0412\u0435\u043d\u0435\u0441\u0443\u044d\u043b\u0435 \u043d\u0435 \u043f\u043e\u043c\u0435\u0448\u0430\u0435\u0442 \u043d\u0430\u043b\u0430\u0434\u0438\u0442\u044c \u0442\u0430\u043c \u0441\u0431\u043e\u0440\u043a\u0443 \u0430\u0432\u0442\u043e\u043c\u0430\u0442\u043e\u0432 \u0410\u041a-103&lt;\/a&gt;, TACC, 25 janvier 2019.'><sup>6<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>Les ventes d\u2019armes qui ont un faible int\u00e9r\u00eat \u00e9conomique mais un impact g\u00e9opolitique important sont g\u00e9n\u00e9ralement assur\u00e9 par le FSVTS et non par Rosoboronexpor. Il est vrai que le gouvernement russe contraint r\u00e9guli\u00e8rement des compagnies li\u00e9es au Kremlin, telle Rostec, \u00e0 d\u00e9fendre les int\u00e9r\u00eats strat\u00e9giques russe aux d\u00e9pens de leurs profits. En revanche, le PDG de Rostec, Sergue\u00ef Tchemezov, est un vieil ami de Vladimir Poutine. Les deux hommes se sont connus \u00e0 Dresde dans les ann\u00e9es 1980 alors que Vladimir Poutine et Sergue\u00ef Tchemezov servaient ensemble pour le KGB. Comme c\u2019est le cas en Russie dans diverses branches de l\u2019\u00e9conomie, les relations d\u2019amiti\u00e9 du Pr\u00e9sident d\u00e9terminent la conduite des affaires du pays et des relations internationales. Le Pr\u00e9sident russe autorise ainsi Rostec, et son ami Tchemezov, \u00e0 percevoir des commissions importantes sur les contrats repr\u00e9sentant une source de profit. En revanche, les organes \u00e9tatiques et le budget de la Russie doivent assurer les pr\u00eats de sommes importantes \u00e0 des pays peu stables et en d\u00e9clin \u00e9conomique.  <\/p>\n\n\n\n<p>Le remplacement de Rostec par le FSVTS indique une transition dans l\u2019approche adopt\u00e9e par la Russie \u00e0 l\u2019\u00e9gard du Venezuela. La pr\u00e9sence du FSVTS prouve l\u2019int\u00e9r\u00eat strat\u00e9gique que repr\u00e9sente le Venezuela pour Moscou. Premi\u00e8rement, le soutien du Kremlin \u00e0 Caracas repr\u00e9sente un moyen de s\u2019opposer aux \u00c9tats-Unis qui demandent le d\u00e9part de Maduro. Cela permet \u00e0 la Russie d&rsquo;appara\u00eetre comme une puissance majeure sur la sc\u00e8ne internationale, capable de s\u2019opposer \u00e0 Washington. Deuxi\u00e8mement, le gouvernement russe assure son soutien aux r\u00e9gimes dictatoriaux \u00e0 travers le monde, notamment en Syrie, afin de lutter contre \u00ab&#160;l\u2019imp\u00e9rialisme am\u00e9ricain&#160;\u00bb et de maintenir son pouvoir \u00e0 l\u2019\u00e9chelle domestique.<\/p>\n\n\n\n<p>Toutefois, il est n\u00e9cessaire de rappeler que la Russie fait face \u00e0 un ralentissement de son \u00e9conomie. Les sanctions \u00e9conomiques impos\u00e9s par les \u00c9tats-Unis et l\u2019Europe ont ralenti la croissance \u00e9conomique russe. La population russe proteste de plus en plus contre le faible niveau de vie et critique le co\u00fbt \u00e9conomique des interventions militaires russes en Syrie ou au Venezuela. Ainsi, bien que la Russie souhaite maintenir son soutien au r\u00e9gime de Maduro, le co\u00fbt \u00e9conomique de sa strat\u00e9gique \u00e9trang\u00e8re, qui est assur\u00e9 par l\u2019\u00c9tat lorsque des contacts sont sign\u00e9s avec des pays en d\u00e9clin \u00e9conomique et par des proches de Vladimir Poutine quand les contrats pr\u00e9sentent une opportunit\u00e9 d\u2019enrichissement, attise la col\u00e8re de la population russe et entame la popularit\u00e9 du pr\u00e9sident. Contrairement \u00e0 ce qu\u2019affirme le <em>Wall Street Journal<\/em>, le d\u00e9part des hommes de Rostec ne repr\u00e9sente donc pas un affaiblissement du soutien de la Russie au Venezuela&#160;: c\u2019est le signe que le r\u00e9gime de Vladimir Poutine parvient de moins en moins \u00e0 concilier ses ambitions internationales avec sa volont\u00e9 de garder le pouvoir et une popularit\u00e9 importante au niveau domestique.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-large\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/05\/GEG-Venezuela-01-1.png\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"1574\"\n        data-pswp-height=\"1008\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/05\/GEG-Venezuela-01-1-330x211.png\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/05\/GEG-Venezuela-01-1-690x442.png\"\r\n                media=\"(max-width: 989px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/05\/GEG-Venezuela-01-1-1340x858.png\"\r\n                media=\"(min-width: 990px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/05\/GEG-Venezuela-01-1-125x80.png\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">GEG &#8211; Cartographie pour Le Grand Continent <\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<h4 class=\"wp-block-heading\"><strong>Perspectives&#160;:<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>La coop\u00e9ration entre la Russie et le Venezuela va se poursuivre avec l\u2019ouverture d\u2019un bureau de la compagnie p\u00e9troli\u00e8re v\u00e9n\u00e9zu\u00e9lienne PDVSA \u00e0 Moscou fin juin. <\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Un article du Wall Street Journal r\u00e9v\u00e8le que la Russie a d\u00e9cid\u00e9 de retirer des conseillers strat\u00e9giques employ\u00e9s par la compagnie \u00e9tatique russe Rostec, vitaux pour la survie du r\u00e9gime du pr\u00e9sident v\u00e9n\u00e9zu\u00e9lien Nicolas Maduro. Cependant, Moscou s&rsquo;est empress\u00e9e de r\u00e9affirmer le soutien de Moscou \u00e0 Maduro. En r\u00e9alit\u00e9, le d\u00e9part des hommes de Rostec ne repr\u00e9sente pas un revers majeur pour le r\u00e9gime v\u00e9n\u00e9zu\u00e9lien mais davantage une transition dans l\u2019approche de la Russie envers le Venezuela. Le soutien militaire de la Russie sera dor\u00e9navant assur\u00e9 par le Service F\u00e9d\u00e9ral pour la Coop\u00e9ration Militaire et Technique de la Russie (FSVTS), signe d\u2019un int\u00e9r\u00eat g\u00e9opolitique et non plus \u00e9conomique.<\/p>\n","protected":false},"author":175,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":0,"footnotes":""},"categories":[1731],"tags":[],"staff":[1678],"editorial_format":[4942],"serie":[],"audience":[],"geo":[525,550],"class_list":["post-39858","post","type-post","status-publish","format-standard","hentry","category-politique","staff-milan-czerny","editorial_format-actu-breves","geo-ameriques","geo-russie"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":"","excerpt":"Un article du Wall Street Journal r\u00e9v\u00e8le que la Russie a d\u00e9cid\u00e9 de retirer des conseillers strat\u00e9giques employ\u00e9s par la compagnie \u00e9tatique russe Rostec, vitaux pour la survie du r\u00e9gime du pr\u00e9sident v\u00e9n\u00e9zu\u00e9lien Nicolas Maduro. Cependant, Moscou s'est empress\u00e9e de r\u00e9affirmer le soutien de Moscou \u00e0 Maduro. En r\u00e9alit\u00e9, le d\u00e9part des hommes de Rostec ne repr\u00e9sente pas un revers majeur pour le r\u00e9gime v\u00e9n\u00e9zu\u00e9lien mais davantage une transition dans l\u2019approche de la Russie envers le Venezuela. Le soutien militaire de la Russie sera dor\u00e9navant assur\u00e9 par le Service F\u00e9d\u00e9ral pour la Coop\u00e9ration Militaire et Technique de la Russie (FSVTS), signe d\u2019un int\u00e9r\u00eat g\u00e9opolitique et non plus \u00e9conomique.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le retrait des conseillers strat\u00e9giques russes du Venezuela : un coup port\u00e9 au r\u00e9gime de Maduro ? | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/06\/07\/le-retrait-des-conseillers-strategiques-russes-du-venezuela-un-coup-porte-au-regime-de-maduro\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le retrait des conseillers strat\u00e9giques russes du Venezuela : un coup port\u00e9 au r\u00e9gime de Maduro ? | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Un article du Wall Street Journal r\u00e9v\u00e8le que la Russie a d\u00e9cid\u00e9 de retirer des conseillers strat\u00e9giques employ\u00e9s par la compagnie \u00e9tatique russe Rostec, vitaux pour la survie du r\u00e9gime du pr\u00e9sident v\u00e9n\u00e9zu\u00e9lien Nicolas Maduro. Cependant, Moscou s&#039;est empress\u00e9e de r\u00e9affirmer le soutien de Moscou \u00e0 Maduro. En r\u00e9alit\u00e9, le d\u00e9part des hommes de Rostec ne repr\u00e9sente pas un revers majeur pour le r\u00e9gime v\u00e9n\u00e9zu\u00e9lien mais davantage une transition dans l\u2019approche de la Russie envers le Venezuela. Le soutien militaire de la Russie sera dor\u00e9navant assur\u00e9 par le Service F\u00e9d\u00e9ral pour la Coop\u00e9ration Militaire et Technique de la Russie (FSVTS), signe d\u2019un int\u00e9r\u00eat g\u00e9opolitique et non plus \u00e9conomique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2019\/06\/07\/le-retrait-des-conseillers-strategiques-russes-du-venezuela-un-coup-porte-au-regime-de-maduro\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-07T10:53:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-07T10:56:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/05\/GEG-Venezuela-01-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1574\" \/>\n\t<meta property=\"og:image:height\" content=\"1008\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Giovanni Collot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/05\/GEG-Venezuela-01-1.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giovanni Collot\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/06\/07\/le-retrait-des-conseillers-strategiques-russes-du-venezuela-un-coup-porte-au-regime-de-maduro\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/06\/07\/le-retrait-des-conseillers-strategiques-russes-du-venezuela-un-coup-porte-au-regime-de-maduro\/\",\"name\":\"Le retrait des conseillers strat\u00e9giques russes du Venezuela : un coup port\u00e9 au r\u00e9gime de Maduro ? | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"datePublished\":\"2019-06-07T10:53:18+00:00\",\"dateModified\":\"2019-06-07T10:56:20+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/06\/07\/le-retrait-des-conseillers-strategiques-russes-du-venezuela-un-coup-porte-au-regime-de-maduro\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2019\/06\/07\/le-retrait-des-conseillers-strategiques-russes-du-venezuela-un-coup-porte-au-regime-de-maduro\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/06\/07\/le-retrait-des-conseillers-strategiques-russes-du-venezuela-un-coup-porte-au-regime-de-maduro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le retrait des conseillers strat\u00e9giques russes du Venezuela&#160;: un coup port\u00e9 au r\u00e9gime de Maduro&#160;?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef\",\"name\":\"Giovanni Collot\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g\",\"caption\":\"Giovanni Collot\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le retrait des conseillers strat\u00e9giques russes du Venezuela : un coup port\u00e9 au r\u00e9gime de Maduro ? | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2019\/06\/07\/le-retrait-des-conseillers-strategiques-russes-du-venezuela-un-coup-porte-au-regime-de-maduro\/","og_locale":"fr_FR","og_type":"article","og_title":"Le retrait des conseillers strat\u00e9giques russes du Venezuela : un coup port\u00e9 au r\u00e9gime de Maduro ? | Le Grand Continent","og_description":"Un article du Wall Street Journal r\u00e9v\u00e8le que la Russie a d\u00e9cid\u00e9 de retirer des conseillers strat\u00e9giques employ\u00e9s par la compagnie \u00e9tatique russe Rostec, vitaux pour la survie du r\u00e9gime du pr\u00e9sident v\u00e9n\u00e9zu\u00e9lien Nicolas Maduro. Cependant, Moscou s'est empress\u00e9e de r\u00e9affirmer le soutien de Moscou \u00e0 Maduro. En r\u00e9alit\u00e9, le d\u00e9part des hommes de Rostec ne repr\u00e9sente pas un revers majeur pour le r\u00e9gime v\u00e9n\u00e9zu\u00e9lien mais davantage une transition dans l\u2019approche de la Russie envers le Venezuela. Le soutien militaire de la Russie sera dor\u00e9navant assur\u00e9 par le Service F\u00e9d\u00e9ral pour la Coop\u00e9ration Militaire et Technique de la Russie (FSVTS), signe d\u2019un int\u00e9r\u00eat g\u00e9opolitique et non plus \u00e9conomique.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2019\/06\/07\/le-retrait-des-conseillers-strategiques-russes-du-venezuela-un-coup-porte-au-regime-de-maduro\/","og_site_name":"Le Grand Continent","article_published_time":"2019-06-07T10:53:18+00:00","article_modified_time":"2019-06-07T10:56:20+00:00","og_image":[{"width":1574,"height":1008,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/05\/GEG-Venezuela-01-1.png","type":"image\/png"}],"author":"Giovanni Collot","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2019\/05\/GEG-Venezuela-01-1.png","twitter_misc":{"\u00c9crit par":"Giovanni Collot","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/06\/07\/le-retrait-des-conseillers-strategiques-russes-du-venezuela-un-coup-porte-au-regime-de-maduro\/","url":"https:\/\/legrandcontinent.eu\/fr\/2019\/06\/07\/le-retrait-des-conseillers-strategiques-russes-du-venezuela-un-coup-porte-au-regime-de-maduro\/","name":"Le retrait des conseillers strat\u00e9giques russes du Venezuela : un coup port\u00e9 au r\u00e9gime de Maduro ? | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"datePublished":"2019-06-07T10:53:18+00:00","dateModified":"2019-06-07T10:56:20+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/06\/07\/le-retrait-des-conseillers-strategiques-russes-du-venezuela-un-coup-porte-au-regime-de-maduro\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2019\/06\/07\/le-retrait-des-conseillers-strategiques-russes-du-venezuela-un-coup-porte-au-regime-de-maduro\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/06\/07\/le-retrait-des-conseillers-strategiques-russes-du-venezuela-un-coup-porte-au-regime-de-maduro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Le retrait des conseillers strat\u00e9giques russes du Venezuela&#160;: un coup port\u00e9 au r\u00e9gime de Maduro&#160;?"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef","name":"Giovanni Collot","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g","caption":"Giovanni Collot"}}]}},"lgc_categories":[{"id":1731,"name":"Politique","slug":"politique"}],"lgc_author":{"id":1678,"name":"Mil\u00e0n Czerny","slug":"milan-czerny","description":"Milan Czerny est chercheur sp\u00e9cialiste des relations entre Isra\u00ebl et la Russie. Il habite en Isra\u00ebl.","first_name":null,"last_name":null,"picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/10\/GC_Czerny.png","width":413,"height":451,"alt":""}},"feature_image_summary":null,"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/39858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=39858"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/39858\/revisions"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=39858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=39858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=39858"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=39858"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=39858"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=39858"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=39858"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=39858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}