{"id":38261,"date":"2019-05-28T13:59:04","date_gmt":"2019-05-28T11:59:04","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=38261"},"modified":"2019-05-31T15:34:26","modified_gmt":"2019-05-31T13:34:26","slug":"catalogne-lindependantisme-gagne-barcelone","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2019\/05\/28\/catalogne-lindependantisme-gagne-barcelone\/","title":{"rendered":"Catalogne&#160;: l\u2019ind\u00e9pendantisme gagne Barcelone"},"content":{"rendered":"\n<p><em>Barcelone<\/em>. A l\u2019ombre des \u00e9lections europ\u00e9ennes qui se sont d\u00e9roul\u00e9es dimanche 26 mai, la Catalogne vivait des \u00e9lections locales importantes dans la poursuite de la recomposition de son paysage politique. Ainsi, Barcelone a \u00e9t\u00e9 t\u00e9moin du renforcement structurel de l\u2019ind\u00e9pendantisme sur l\u2019ensemble du territoire. La victoire du candidat de la gauche r\u00e9publicaine ind\u00e9pendantiste (ERC), Ernest Maragall, est sans doute un acte politique fort dans l\u2019optique d\u2019une sortie de crise de la gouvernance catalane depuis le r\u00e9f\u00e9rendum sur l\u2019ind\u00e9pendance qui s\u2019est d\u00e9roul\u00e9 le 1<sup>er<\/sup> octobre 2017.<\/p>\n\n\n\n<p>Dimanche soir, la soir\u00e9e \u00e9lectorale a \u00e9t\u00e9 \u00e9lectrique du c\u00f4t\u00e9 de Barcelone. Tout d\u2019abord, le r\u00e9sultat du scrutin a \u00e9t\u00e9 particuli\u00e8rement serr\u00e9. Ainsi, le candidat de la gauche ind\u00e9pendantiste termine avec moins de 5 000 voix d\u2019avances sur sa concurrente de la gauche radicale et maire sortante, Ada Colau&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-38261' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/05\/28\/catalogne-lindependantisme-gagne-barcelone\/#easy-footnote-bottom-1-38261' title=' SU\u00d1E Ramon,&lt;a href=&quot;https:\/\/www.lavanguardia.com\/local\/barcelona\/20190527\/462490408114\/maragall-ya-se-siente-alcalde.html&quot;&gt; \u201cErnest Maragall ya se siente alcalde de Barcelona\u201d&lt;\/a&gt;, La Vanguardia, 27 mai 2019.'><sup>1<\/sup><\/a><\/span><\/span>. Pour ce parti historique de Catalogne, cette victoire est une premi\u00e8re depuis 1931. Pour autant, cette victoire hautement symbolique dans un contexte politique conflictuel avec Madrid ne masque pas les difficult\u00e9s \u00e0 venir pour le nouveau maire.<\/p>\n\n\n\n<p>En effet, Ernest Maragall devra composer avec un futur conseil municipal morcel\u00e9 obligeant son groupe politique \u00e0 former une coalition municipale. Les r\u00e9sultats de l\u2019\u00e9lection ont mis en t\u00eate Ernest Maragall en obtenant 10 si\u00e8ges, \u00e0 \u00e9galit\u00e9 avec Ada Colau (Barcelona En Com\u00fa), suivi de Jaume Collboni (PSC) avec 10 si\u00e8ges, Manuel Valls (Ciudadanos) &#8211; 6 si\u00e8ges&#160;; Elsa Artadi (Junts Per Catalunya) &#8211; 8  si\u00e8ges&#160;; et enfin Josep Bou (Partido Popular) &#8211; 2 si\u00e8ges&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-38261' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/05\/28\/catalogne-lindependantisme-gagne-barcelone\/#easy-footnote-bottom-2-38261' title='&lt;a href=&quot;https:\/\/beteve.cat\/eleccions-municipals-2019\/resultats-barcelona\/&quot;&gt;R\u00e9sultats des \u00e9lections municipales 2019&lt;\/a&gt;, Betev\u00e9, mai 2019.'><sup>2<\/sup><\/a><\/span><\/span>. Mis en perspective, ce morcellement annonce une gouvernance municipale aux \u00e9quilibres fragiles.<\/p>\n\n\n\n<p>Le futur maire r\u00e9publicain, \u00e2g\u00e9 de 76 ans, est confront\u00e9 \u00e0 un dilemme politique profond. Il doit op\u00e9rer un choix politique majeur entre une alliance ind\u00e9pendantiste, alors que la gauche radicale ind\u00e9pendantiste (<em>CUP<\/em>) n\u2019a obtenu aucun si\u00e8ge, et une large coalition de gauche. Pour la premi\u00e8re option, Ernest Maragall, se rendra \u00e0 la prison de Soto del Real \u00ab&#160;pour offrir un pacte de gouvernement \u00e0 Quim Forn, autre v\u00e9t\u00e9ran de la politique municipale&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-38261' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/05\/28\/catalogne-lindependantisme-gagne-barcelone\/#easy-footnote-bottom-3-38261' title='SIERRA Enric,&lt;a href=&quot;https:\/\/www.lavanguardia.com\/opinion\/20190527\/462488600372\/barcelona-ernest-maragall-ada-colau-jaume-collboni-quim-forn-elecciones.html&quot;&gt; \u201cLos dilemas de Maragall y Colau tras una noche de infarto\u201d&lt;\/a&gt;, La Vanguardia, 27 mai 2019.'><sup>3<\/sup><\/a><\/span><\/span>. Ce dernier, membre de Junts per Catalunya, attend son jugement concernant le proc\u00e8s sur les \u00e9v\u00e9nements du 1<sup>er<\/sup> octobre 2017. L\u2019alliance avec l\u2019autre parti ind\u00e9pendantiste est l\u2019option prioritaire. Cette alliance entend mettre en avant leur bataille commune qui est la lib\u00e9ration des prisonniers et le retour des exil\u00e9s en Catalogne. Quant \u00e0 la seconde hypoth\u00e8se, une alliance de gauche avec la maire sortante est une option envisageable. Mais la question de l\u2019ind\u00e9pendance constitue un point de discorde majeur entre ces deux partis. La gauche radicale En Comu Podem s\u2019est toujours tenue \u00e0 \u00e9quidistance entre le mouvement ind\u00e9pendantiste et la position de fermet\u00e9 du gouvernement espagnol.<\/p>\n\n\n\n<p>Pris dans un contexte g\u00e9n\u00e9ral, la future gouvernance de Barcelone est d\u00e9pendante de la r\u00e9silience du front ind\u00e9pendantiste liant Esquerra Republicana de Catalunya et Junts per Catalunya. Si le premier triomphe \u00e0 Barcelone, le second remporte un succ\u00e8s probant au niveau europ\u00e9en avec l\u2019\u00e9lection de Carles Puigdemont, ancien pr\u00e9sident de la Generalitat, actuellement exil\u00e9 en Belgique. Ind\u00e9niablement, le mouvement ind\u00e9pendantiste a \u00e9t\u00e9 consolid\u00e9 par les diff\u00e9rents scrutins tout en d\u00e9montrant sa pluralit\u00e9&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-38261' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/05\/28\/catalogne-lindependantisme-gagne-barcelone\/#easy-footnote-bottom-4-38261' title='Editorial,&lt;a href=&quot;https:\/\/www.ara.cat\/editorial\/Solidesa-independentista-fracas-dreta_0_2241375907.html&quot;&gt; \u201cSolidesa independentista i frac\u00e0s de la dreta\u201d&lt;\/a&gt;, ARA, 27 mai 2019.'><sup>4<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>Enfin, cette \u00e9lection marque l\u2019\u00e9chec du projet municipal de l\u2019ancien Premier ministre fran\u00e7ais Manuel Valls. Bien que sa liste centriste ait recueilli 13,2&#160;% des voix, il assume son \u00e9chec main n\u2019entend pas renoncer \u00e0 son r\u00f4le d\u2019opposant aux mouvements ind\u00e9pendantistes. Il si\u00e9gera dans l\u2019opposition et entend avoir un r\u00f4le actif au sein de l\u2019opposition municipale. Toutefois, il a annonc\u00e9 vouloir rompre avec Ciudadanos, si ces derniers devaient n\u00e9gocier un accord d\u2019alliance avec le parti d\u2019extr\u00eame-droite Vox dans certaines municipalit\u00e9s&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-38261' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2019\/05\/28\/catalogne-lindependantisme-gagne-barcelone\/#easy-footnote-bottom-5-38261' title='REGUE J\u00falia,&lt;a href=&quot;https:\/\/www.elperiodico.com\/es\/barcelona\/20190527\/valls-resultado-elecciones-municipales-7474564&quot;&gt; \u201cEl efecto Valls no cuaja y queda lejos de sus expectativas\u201d&lt;\/a&gt;, El Peri\u00f3dico, 27 mai 2019.'><sup>5<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Perspectives&#160;:<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>Cette \u00e9lection marque la solidit\u00e9 du mouvement ind\u00e9pendantiste en Catalogne. La prise de Barcelone par la gauche ind\u00e9pendantiste est un symbole fort dans le conflit l\u2019opposant \u00e0 l\u2019\u00c9tat espagnol.<\/li><li>Le futur maire doit d\u00e9sormais des n\u00e9gociations difficiles pour construire une coalition solide pour cette mandature de quatre ans.<\/li><li>Les futurs projets municipaux (la mobilit\u00e9 douce, la digitalisation ou la r\u00e9duction des in\u00e9galit\u00e9s socio-\u00e9conomiques) de la ville pourraient \u00eatre parasit\u00e9s par la lutte politique entre les ind\u00e9pendantistes et les constitutionnalistes.<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Le r\u00e9sultat du scrutin des \u00e9lections municipales \u00e0 Barcelone montre un renforcement du mouvement ind\u00e9pendantiste. L\u2019\u00e9lection d\u2019Ernest Maragall, fr\u00e8re de l\u2019ancien maire de Barcelone Pasqual Maragall (1982-1997), sous les couleurs de la gauche r\u00e9publicaine (Esquerra Republicana de Catalunya), ouvre une nouvelle \u00e8re pour le chef-lieu de la Catalogne.<\/p>\n","protected":false},"author":175,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":0,"footnotes":""},"categories":[1989,1731],"tags":[],"staff":[1633],"editorial_format":[4942],"serie":[],"audience":[],"geo":[543],"class_list":["post-38261","post","type-post","status-publish","format-standard","hentry","category-acces-libre","category-politique","staff-florian-vidal","editorial_format-actu-breves","geo-mediterranee"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":"","excerpt":"Le r\u00e9sultat du scrutin des \u00e9lections municipales \u00e0 Barcelone montre un renforcement du mouvement ind\u00e9pendantiste. L\u2019\u00e9lection d\u2019Ernest Maragall, fr\u00e8re de l\u2019ancien maire de Barcelone Pasqual Maragall (1982-1997), sous les couleurs de la gauche r\u00e9publicaine (Esquerra Republicana de Catalunya), ouvre une nouvelle \u00e8re pour le chef-lieu de la Catalogne.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Catalogne : l\u2019ind\u00e9pendantisme gagne Barcelone | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/05\/28\/catalogne-lindependantisme-gagne-barcelone\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Catalogne : l\u2019ind\u00e9pendantisme gagne Barcelone | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Le r\u00e9sultat du scrutin des \u00e9lections municipales \u00e0 Barcelone montre un renforcement du mouvement ind\u00e9pendantiste. L\u2019\u00e9lection d\u2019Ernest Maragall, fr\u00e8re de l\u2019ancien maire de Barcelone Pasqual Maragall (1982-1997), sous les couleurs de la gauche r\u00e9publicaine (Esquerra Republicana de Catalunya), ouvre une nouvelle \u00e8re pour le chef-lieu de la Catalogne.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2019\/05\/28\/catalogne-lindependantisme-gagne-barcelone\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-28T11:59:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-31T13:34:26+00:00\" \/>\n<meta name=\"author\" content=\"Giovanni Collot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giovanni Collot\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/05\/28\/catalogne-lindependantisme-gagne-barcelone\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/05\/28\/catalogne-lindependantisme-gagne-barcelone\/\",\"name\":\"Catalogne : l\u2019ind\u00e9pendantisme gagne Barcelone | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"datePublished\":\"2019-05-28T11:59:04+00:00\",\"dateModified\":\"2019-05-31T13:34:26+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/05\/28\/catalogne-lindependantisme-gagne-barcelone\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2019\/05\/28\/catalogne-lindependantisme-gagne-barcelone\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/05\/28\/catalogne-lindependantisme-gagne-barcelone\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Catalogne&#160;: l\u2019ind\u00e9pendantisme gagne Barcelone\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef\",\"name\":\"Giovanni Collot\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g\",\"caption\":\"Giovanni Collot\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Catalogne : l\u2019ind\u00e9pendantisme gagne Barcelone | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2019\/05\/28\/catalogne-lindependantisme-gagne-barcelone\/","og_locale":"fr_FR","og_type":"article","og_title":"Catalogne : l\u2019ind\u00e9pendantisme gagne Barcelone | Le Grand Continent","og_description":"Le r\u00e9sultat du scrutin des \u00e9lections municipales \u00e0 Barcelone montre un renforcement du mouvement ind\u00e9pendantiste. L\u2019\u00e9lection d\u2019Ernest Maragall, fr\u00e8re de l\u2019ancien maire de Barcelone Pasqual Maragall (1982-1997), sous les couleurs de la gauche r\u00e9publicaine (Esquerra Republicana de Catalunya), ouvre une nouvelle \u00e8re pour le chef-lieu de la Catalogne.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2019\/05\/28\/catalogne-lindependantisme-gagne-barcelone\/","og_site_name":"Le Grand Continent","article_published_time":"2019-05-28T11:59:04+00:00","article_modified_time":"2019-05-31T13:34:26+00:00","author":"Giovanni Collot","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Giovanni Collot","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/05\/28\/catalogne-lindependantisme-gagne-barcelone\/","url":"https:\/\/legrandcontinent.eu\/fr\/2019\/05\/28\/catalogne-lindependantisme-gagne-barcelone\/","name":"Catalogne : l\u2019ind\u00e9pendantisme gagne Barcelone | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"datePublished":"2019-05-28T11:59:04+00:00","dateModified":"2019-05-31T13:34:26+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/05\/28\/catalogne-lindependantisme-gagne-barcelone\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2019\/05\/28\/catalogne-lindependantisme-gagne-barcelone\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/05\/28\/catalogne-lindependantisme-gagne-barcelone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Catalogne&#160;: l\u2019ind\u00e9pendantisme gagne Barcelone"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef","name":"Giovanni Collot","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g","caption":"Giovanni Collot"}}]}},"lgc_categories":[{"id":1989,"name":"Acc\u00e8s libre","slug":"acces-libre"},{"id":1731,"name":"Politique","slug":"politique"}],"lgc_author":{"id":1633,"name":"Florian Vidal","slug":"florian-vidal","description":null,"first_name":null,"last_name":null,"picture":null},"feature_image_summary":null,"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/38261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=38261"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/38261\/revisions"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=38261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=38261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=38261"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=38261"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=38261"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=38261"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=38261"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=38261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}