{"id":38029,"date":"2019-05-27T02:01:01","date_gmt":"2019-05-27T00:01:01","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=38029"},"modified":"2019-05-27T02:01:04","modified_gmt":"2019-05-27T00:01:04","slug":"elections-europeennes-commentaire-sur-les-resultats-en-espagne","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2019\/05\/27\/elections-europeennes-commentaire-sur-les-resultats-en-espagne\/","title":{"rendered":"\u00c9lections europ\u00e9ennes&#160;: commentaire sur les r\u00e9sultats en Espagne"},"content":{"rendered":"\n<p><em>Madrid. <\/em>Pr\u00e8s d\u2019un mois apr\u00e8s les \u00e9lections l\u00e9gislatives du 28 avril, l\u2019Espagne votait aujourd\u2019hui pour ses 54 d\u00e9put\u00e9s (qui deviendront 59 apr\u00e8s le Brexit) au Parlement europ\u00e9en. Si la participation \u00e0 ces \u00e9lections europ\u00e9ennes, de 64,32&#160;%, est de pr\u00e8s de 10 points inf\u00e9rieure \u00e0 celle observ\u00e9e pour les \u00e9lections g\u00e9n\u00e9rales, elle est clairement en hausse par rapport aux \u00e9lections europ\u00e9ennes de 2014, lorsque 45,83&#160;% de l\u2019\u00e9lectorat s\u2019\u00e9taient rendus aux urnes. <\/p>\n\n\n\n<p>Les r\u00e9sultats confirment les tendances observ\u00e9es lors des \u00e9lections g\u00e9n\u00e9rales du 28 avril. C\u2019est une tr\u00e8s nette victoire du Parti socialiste ouvrier espagnol (PSOE) de Pedro S\u00e1nchez, qui obtient 20 si\u00e8ges au Parlement europ\u00e9en, largement devant le Partido Popular (PP) qui obtient 12 si\u00e8ges. Ciudadanos, le parti de centre-droit, constitue la troisi\u00e8me force politique espagnole au Parlement europ\u00e9en mais le parti fait moins bien que ce qu\u2019envisageaient les derniers sondages&#160;: en n\u2019obtenant que 7 si\u00e8ges, il est loin de d\u00e9passer le Partido Popular qui r\u00e9siste en partie \u00e0 un d\u00e9clin g\u00e9n\u00e9ral par rapport \u00e0 2014. <\/p>\n\n\n\n<p>Comme pr\u00e9vu dans les sondages, Vox, le parti d\u2019extr\u00eame droite de Santiago Abascal, entre au Parlement. Avec 6,5&#160;% des voix et 3 si\u00e8ges, Vox ne fait pas la perc\u00e9e \u00e0 laquelle on pouvait s\u2019attendre dans le contexte de l\u2019affirmation des tendances eurosceptiques en Europe et apr\u00e8s son affirmation en Andalousie \u00e0 l\u2019issue des \u00e9lections de d\u00e9cembre et \u00e0 l\u2019\u00e9chelle nationale lors des \u00e9lections du 28 avril, \u00e0 l\u2019issue desquelles le parti avait obtenu 10,3&#160;% des voix. \u00a0Il semble bien, au regard des r\u00e9sultats des \u00e9lections europ\u00e9ennes, municipales et aux parlements des communaut\u00e9s autonomes espagnoles, que Vox ait atteint un certain plafond et que l\u2019Espagne \u00e9chappe pour partie \u00e0 la vague nationaliste et eurosceptique qui agite l\u2019Union Europ\u00e9enne. Par comparaison, la perc\u00e9e de Podemos au Parlement europ\u00e9en en 2014 avait \u00e9t\u00e9 plus forte. Ces \u00e9lections europ\u00e9ennes sont aussi une victoire pour les ind\u00e9pendantistes catalans, puisque Ahora Rep\u00fablicas, coalition regroupant notamment la Gauche r\u00e9publicaine de Catalogne (ERC), obtient 3 si\u00e8ges, et Lliures per Europa (Junts), le parti de Carles Puigdemont, obtient 2 si\u00e8ges. \u00a0Se posera dans les prochaines semaines la question juridique de l\u2019investiture des d\u00e9put\u00e9s ind\u00e9pendantistes poursuivis par la justice espagnole. <\/p>\n\n\n\n<p>L\u2019Espagne a donc une position bien particuli\u00e8re en Europe&#160;: le pays apporte un fort contingent socialiste au Parlement europ\u00e9en et si la question \u00e9cologique faisait consensus pour les candidats pr\u00e9sents lors du d\u00e9bat t\u00e9l\u00e9vis\u00e9 du mercredi 22 mai, l\u2019Espagne ne compte pas de parti vert important.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tout au long de cette semaine \u00e9lectorale, Le Grand Continent vous propose une couverture in\u00e9dite des r\u00e9sultats du seul scrutin continental au monde. Suivez les analyses des r\u00e9sultats en direct&#160;&#160;: c&rsquo;est le tour de l&rsquo;Allemagne. <\/p>\n","protected":false},"author":175,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":0,"footnotes":""},"categories":[1989],"tags":[],"staff":[1803],"editorial_format":[4942],"serie":[],"audience":[],"geo":[543],"class_list":["post-38029","post","type-post","status-publish","format-standard","hentry","category-acces-libre","staff-laurine-manach","editorial_format-actu-breves","geo-mediterranee"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":"","excerpt":"Tout au long de cette semaine \u00e9lectorale, Le Grand Continent vous propose une couverture in\u00e9dite des r\u00e9sultats du seul scrutin continental au monde. Suivez les analyses des r\u00e9sultats en direct : c'est le tour de l'Allemagne. ","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00c9lections europ\u00e9ennes : commentaire sur les r\u00e9sultats en Espagne | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2019\/05\/27\/elections-europeennes-commentaire-sur-les-resultats-en-espagne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9lections europ\u00e9ennes : commentaire sur les r\u00e9sultats en Espagne | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Tout au long de cette semaine \u00e9lectorale, Le Grand Continent vous propose une couverture in\u00e9dite des r\u00e9sultats du seul scrutin continental au monde. Suivez les analyses des r\u00e9sultats en direct&#160;: c&#039;est le tour de l&#039;Allemagne.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2019\/05\/27\/elections-europeennes-commentaire-sur-les-resultats-en-espagne\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-27T00:01:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-27T00:01:04+00:00\" \/>\n<meta name=\"author\" content=\"Giovanni Collot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giovanni Collot\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/05\/27\/elections-europeennes-commentaire-sur-les-resultats-en-espagne\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/05\/27\/elections-europeennes-commentaire-sur-les-resultats-en-espagne\/\",\"name\":\"\u00c9lections europ\u00e9ennes : commentaire sur les r\u00e9sultats en Espagne | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"datePublished\":\"2019-05-27T00:01:01+00:00\",\"dateModified\":\"2019-05-27T00:01:04+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/05\/27\/elections-europeennes-commentaire-sur-les-resultats-en-espagne\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2019\/05\/27\/elections-europeennes-commentaire-sur-les-resultats-en-espagne\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2019\/05\/27\/elections-europeennes-commentaire-sur-les-resultats-en-espagne\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9lections europ\u00e9ennes&#160;: commentaire sur les r\u00e9sultats en Espagne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef\",\"name\":\"Giovanni Collot\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g\",\"caption\":\"Giovanni Collot\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9lections europ\u00e9ennes : commentaire sur les r\u00e9sultats en Espagne | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2019\/05\/27\/elections-europeennes-commentaire-sur-les-resultats-en-espagne\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9lections europ\u00e9ennes : commentaire sur les r\u00e9sultats en Espagne | Le Grand Continent","og_description":"Tout au long de cette semaine \u00e9lectorale, Le Grand Continent vous propose une couverture in\u00e9dite des r\u00e9sultats du seul scrutin continental au monde. Suivez les analyses des r\u00e9sultats en direct&#160;: c'est le tour de l'Allemagne.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2019\/05\/27\/elections-europeennes-commentaire-sur-les-resultats-en-espagne\/","og_site_name":"Le Grand Continent","article_published_time":"2019-05-27T00:01:01+00:00","article_modified_time":"2019-05-27T00:01:04+00:00","author":"Giovanni Collot","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Giovanni Collot","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/05\/27\/elections-europeennes-commentaire-sur-les-resultats-en-espagne\/","url":"https:\/\/legrandcontinent.eu\/fr\/2019\/05\/27\/elections-europeennes-commentaire-sur-les-resultats-en-espagne\/","name":"\u00c9lections europ\u00e9ennes : commentaire sur les r\u00e9sultats en Espagne | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"datePublished":"2019-05-27T00:01:01+00:00","dateModified":"2019-05-27T00:01:04+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/05\/27\/elections-europeennes-commentaire-sur-les-resultats-en-espagne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2019\/05\/27\/elections-europeennes-commentaire-sur-les-resultats-en-espagne\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2019\/05\/27\/elections-europeennes-commentaire-sur-les-resultats-en-espagne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c9lections europ\u00e9ennes&#160;: commentaire sur les r\u00e9sultats en Espagne"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/953192c3de3c2331be3997745a2f12ef","name":"Giovanni Collot","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d93cac37237065a8de4498df3db60dde?s=96&d=mm&r=g","caption":"Giovanni Collot"}}]}},"lgc_categories":[{"id":1989,"name":"Acc\u00e8s libre","slug":"acces-libre"}],"lgc_author":{"id":1803,"name":"Laurine Manac'h","slug":"laurine-manach","description":null,"first_name":null,"last_name":null,"picture":null},"feature_image_summary":null,"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/38029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=38029"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/38029\/revisions"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=38029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=38029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=38029"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=38029"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=38029"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=38029"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=38029"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=38029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}