{"id":3513,"date":"2017-09-15T10:29:24","date_gmt":"2017-09-15T08:29:24","guid":{"rendered":"https:\/\/legrandcontinent.eu\/?p=3513"},"modified":"2019-07-08T11:03:32","modified_gmt":"2019-07-08T09:03:32","slug":"nous-avons-rencontre-justin-vaisse","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2017\/09\/15\/nous-avons-rencontre-justin-vaisse\/","title":{"rendered":"La position de la France, une conversation avec Justin Va\u00efsse"},"content":{"rendered":"\n<p><em>Justin Va\u00efsse est historien, sp\u00e9cialiste de l\u2019histoire politique des \u00c9tats-Unis, des relations transatlantiques et de la politique ext\u00e9rieure europ\u00e9enne. Il dirige depuis 2013 le Centre d\u2019analyse, de pr\u00e9vision et de strat\u00e9gie (CAPS) au minist\u00e8re des Affaires \u00e9trang\u00e8res. Dans ce long entretien r\u00e9alis\u00e9 \u00e0 Paris le 12 juillet 2017, Justin Va\u00efsse s\u2019exprime en son nom propre et ses propos ne refl\u00e8tent pas n\u00e9cessairement les positions du minist\u00e8re de l\u2019Europe et des Affaires \u00e9trang\u00e8res.<\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La nouvelle d\u00e9nomination du minist\u00e8re de l\u2019Europe et des Affaires \u00e9trang\u00e8res ainsi que la pr\u00e9sence du th\u00e8me europ\u00e9en dans le discours de l\u2019\u00c9lys\u00e9e, font penser \u00e0 un recentrement de la strat\u00e9gie ext\u00e9rieure fran\u00e7aise sur l\u2019Europe. En tant que \u00ab&#160;strat\u00e8ge du Quai d\u2019Orsay&#160;\u00bb, comme vous a surnomm\u00e9 <a href=\"http:\/\/www.lemonde.fr\/international\/article\/2013\/02\/22\/le-stratege-du-quai-d-orsay_1837320_3210.html\"><em>Le Monde<\/em><\/a>, avez-vous senti ce recentrement, et en quoi concr\u00e8tement va-t-il se d\u00e9ployer&#160;?<\/h3>\n\n\n\n<p>Oui, certainement. Tout vient de la campagne. Avec Beno\u00eet Hamon, Emmanuel Macron \u00e9tait le seul \u00e0 insister explicitement sur un engagement en faveur de l\u2019Europe et de la solidarit\u00e9 europ\u00e9enne dans tous les sens du terme, contre un tr\u00e8s grand nombre de candidats qui \u00e9taient r\u00e9serv\u00e9s, voire partisans d\u2019une forme ou une autre de rupture. Avec l\u2019\u00e9lection est sorti du chapeau un pr\u00e9sident qui avait mis l\u2019Europe au c\u0153ur de sa campagne et qui faisait acclamer l\u2019Europe dans ses <em>meetings<\/em>, ce qui n\u2019est quand m\u00eame pas tr\u00e8s courant et un peu contre-intuitif pour beaucoup<em>. <\/em>Il n\u2019est pas \u00e9tonnant qu\u2019ensuite, une fois arriv\u00e9 au pouvoir, le Pr\u00e9sident respecte et poursuive cette ligne et qu\u2019il mette en effet l\u2019Europe au c\u0153ur de sa politique.<\/p>\n\n\n\n<p>\u00c9videmment, son engagement concret est un peu suspendu par le fait que les \u00e9lections allemandes n\u2019auront lieu que le 23 septembre, et qu\u2019il est difficile de vraiment bouger d\u2019ici l\u00e0. Le Conseil des ministres franco-allemand a du mal \u00e0 prendre des d\u00e9cisions audacieuses quand Angela Merkel est en campagne\u2026<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Quand croyez-vous que l\u2019on pourra y voir plus clair&#160;?<\/h3>\n\n\n\n<p>La phase de d\u00e9marrage, la phase de tractations aura lieu au moment du contrat de coalition, entre septembre et fin novembre, et le vrai d\u00e9marrage pourra avoir lieu au moment du Conseil europ\u00e9en de d\u00e9cembre et surtout d\u00e9but 2018.<\/p>\n\n\n\n<p>C\u2019est l\u00e0 qu\u2019on verra aussi la v\u00e9rit\u00e9 des chiffres, la grande question. La mat\u00e9rialit\u00e9 de l\u2019engagement europ\u00e9en du Pr\u00e9sident, c\u2019est en effet aussi le respect des disciplines qui est indispensable \u00e0 notre stature et \u00e0 notre capacit\u00e9 \u00e0 relancer les choses. L\u00e0, il faudra voir comment se passe l\u2019arbitrage en termes de r\u00e9duction des d\u00e9penses, d\u2019augmentation \u2013 ou de baisse \u2013 de la fiscalit\u00e9 et de respect des engagements europ\u00e9ens. Il est certain qu\u2019on joue une part de cr\u00e9dibilit\u00e9 importante  sur la tentative d\u2019\u00e9viter que l\u2019histoire ne se r\u00e9p\u00e8te. Or il me semble que l\u2019engagement europ\u00e9en s\u2019est d\u00e9j\u00e0 manifest\u00e9 par la volont\u00e9 d\u2019\u00e9viter que l\u2019histoire ne se r\u00e9p\u00e8te, ce qui implique le respect des engagements financiers.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00ab&#160;Il y a eu une sorte de cercle vicieux entre d\u2019une part, les probl\u00e8mes de l\u2019Europe et les diff\u00e9rentes crises que la construction europ\u00e9enne a subies et, d\u2019autre part, ce que j\u2019appellerai l\u2019effacement de la France \u00e0 Bruxelles en termes d\u2019influence.&#160;\u00bb<\/p><cite>Justin Va\u00efsse<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Le Pr\u00e9sident a aussi montr\u00e9 qu\u2019il souhaitait remettre l\u2019Europe au centre de la conversation diplomatique, notamment dans le cadre multilat\u00e9ral. Pourtant, cette mise en avant semble inexorablement devoir passer par la mise en avant de la France. Y a-t-il une fa\u00e7on d\u2019\u00e9chapper \u00e0 ce paradoxe&#160;?<\/h3>\n\n\n\n<p>Je pense qu\u2019il y a eu une sorte de cercle vicieux entre d\u2019une part, les probl\u00e8mes de l\u2019Europe et les diff\u00e9rentes crises que la construction europ\u00e9enne a subies et, d\u2019autre part, ce que j\u2019appellerai l\u2019effacement de la France \u00e0 Bruxelles en termes d\u2019influence.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Comment <strong>expliquez-vous<\/strong> cet effacement fran\u00e7ais \u00e0 Bruxelles&#160;?<\/h3>\n\n\n\n<p>C\u2019est un ph\u00e9nom\u00e8ne d\u00fb \u00e0 une multiplicit\u00e9 de facteurs. L\u2019\u00e9lection au Parlement europ\u00e9en de 25 d\u00e9put\u00e9s Front national a beaucoup affaibli la voix de la France \u00e0 Strasbourg. Le non-respect partiel des engagements financiers a amoindri la cr\u00e9dibilit\u00e9 de la France \u00e0 Bruxelles et Berlin. Ainsi qu&rsquo;une certaine ambivalence vis-\u00e0-vis du Service europ\u00e9en pour l\u2019Action ext\u00e9rieure, dont nous \u00e9tions pourtant parmi les plus importants concepteurs au cours des ann\u00e9es 2000, et qui tient \u00e0 la fois des rapports un peu compliqu\u00e9s avec Catherine Ashton et Federica Mogherini sur la d\u00e9finition m\u00eame de la politique \u00e9trang\u00e8re europ\u00e9enne, et sur la fa\u00e7on dont elle fabriqu\u00e9e.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Vous parliez d\u2019un cercle vicieux, comment pensez-vous qu\u2019il faudrait traiter la question de l\u2019articulation entre France et Europe&#160;?<\/h3>\n\n\n\n<p>Si je parle de cercle vicieux, c\u2019est parce que \u00e7a renforce l\u2019id\u00e9e que ce n\u2019est pas notre Europe. Donc je trouve qu\u2019il n\u2019y a pas du tout de contradiction entre le fait de vouloir reprendre les choses en main, de vouloir r\u00e9investir Bruxelles ou d\u2019y faire davantage entendre la voix fran\u00e7aise d\u2019un c\u00f4t\u00e9, et l\u2019engagement europ\u00e9en de l\u2019autre, au contraire. C\u2019est si nous n\u2019\u00e9tions que des \u00ab&#160;<em>takers<\/em>&#160;\u00bb, et plus jamais des \u00ab&#160;<em>makers<\/em>&#160;\u00bb qu\u2019\u00e0 mon avis l\u2019\u00e9lan europ\u00e9en en France risquerait de s\u2019atrophier. Pour moi les deux ph\u00e9nom\u00e8nes vont de pair.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00ab&#160;Je ne vois pas bien o\u00f9 l\u2019affirmation de la France contredit l\u2019\u00e9lan europ\u00e9en.&#160;\u00bb<\/p><cite>Justin Va\u00efsse<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Je ne pense pas qu\u2019il y ait une affirmation de la France qui se fasse <em>au d\u00e9triment <\/em>de l\u2019Union europ\u00e9enne. Ce n\u2019est pas juste s\u00e9mantique. C\u2019est que je ne vois pas bien o\u00f9 l\u2019affirmation de la France contredit l\u2019\u00e9lan europ\u00e9en. Bien s\u00fbr, cela suppose une Europe plus fran\u00e7aise. Mais \u00e7a je ne pense pas que ce soit mauvais, c\u2019est plut\u00f4t une reprise d\u2019importance \u00e0 Bruxelles qui est n\u00e9cessaire pour soutenir l\u2019effort europ\u00e9en sur le long terme.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mais le d\u00e9part probable du Royaume-Uni semble faire peur notamment \u00e0 l\u2019Est parce qu\u2019il laisse penser que la France va devenir un peu la voix monopolistique de l\u2019Europe en mati\u00e8re de d\u00e9fense et de projection des int\u00e9r\u00eats europ\u00e9ens \u00e0 l\u2019\u00e9tranger\u2026<\/h3>\n\n\n\n<p>Je ne suis pas s\u00fbr de ce diagnostic. Parce qu\u2019il y a l\u2019OTAN, tout de m\u00eame. Pour ces pays-l\u00e0, y compris pour l\u2019Allemagne, l\u2019OTAN reste principielle et fondamentale.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Et l\u2019OTAN elle-m\u00eame n\u2019est-elle pas un obstacle possible \u00e0 la construction d\u2019une Europe de la d\u00e9fense&#160;?<\/h3>\n\n\n\n<p>L\u00e0 on en arrive au sujet principal. L\u2019OTAN qui a tant contribu\u00e9 \u00e0 la d\u00e9fense de l\u2019Europe, au sens du territoire europ\u00e9en, a \u00e9t\u00e9 dans le m\u00eame temps le meilleur vaccin contre une d\u00e9fense europ\u00e9enne. L\u2019arbre \u00e9tait l\u00e0, qui a emp\u00each\u00e9 l\u2019apparition de jeunes pousses. Et c\u2019est toute l\u2019ambigu\u00eft\u00e9 de l\u2019appel de Trump, apr\u00e8s tous les autres pr\u00e9sidents am\u00e9ricains, tous les ministres de la d\u00e9fense am\u00e9ricains, \u00e0 d\u00e9penser plus et \u00e0 faire plus de choses pour la d\u00e9fense europ\u00e9enne quand en m\u00eame temps l\u2019Am\u00e9rique s\u2019investit massivement, via l\u2019OTAN ou de fa\u00e7on bilat\u00e9rale, dans la d\u00e9fense de l\u2019Europe.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00ab&#160;L\u2019OTAN qui a tant contribu\u00e9 \u00e0 la d\u00e9fense de l\u2019Europe, au sens du territoire europ\u00e9en, a \u00e9t\u00e9 dans le m\u00eame temps le meilleur vaccin contre une d\u00e9fense europ\u00e9enne.&#160;\u00bb<\/p><cite>Justin Va\u00efsse<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Et on peut d\u2019un c\u00f4t\u00e9 dire, c\u2019est tr\u00e8s g\u00e9n\u00e9reux, mais d\u2019un autre c\u00f4t\u00e9 cela a permis de garder un certain degr\u00e9 de contr\u00f4le, non seulement par les effets directs de commandement, mais aussi par les effets induits ou indirects, c\u2019est-\u00e0-dire l\u2019atrophie de la d\u00e9fense europ\u00e9enne dans un certain nombre de pays, y compris l\u2019Allemagne. Si on pousse la question th\u00e9orique jusqu\u2019au bout, alors on devrait penser que si Trump avait \u00e9t\u00e9 s\u00e9rieux dans le fait qu\u2019il consid\u00e9rait l\u2019OTAN comme obsol\u00e8te, l\u00e0 il y aurait une remise en cause fondamentale de l\u2019attachement \u00e0 l\u2019OTAN et donc une possibilit\u00e9 de changement de pied fondamental sur la d\u00e9fense europ\u00e9enne.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Certains Europ\u00e9ens l\u2019appelaient de leurs v\u0153ux.<\/h3>\n\n\n\n<p>C\u2019est ce dont on soup\u00e7onne les Fran\u00e7ais&#160;! En tout cas le moment clef a \u00e9t\u00e9 la fameuse <a href=\"http:\/\/www.politico.eu\/article\/what-angela-merkel-meant-at-the-munich-beer-hall\/\">d\u00e9claration<\/a> d\u2019Angela Merkel au Biergarten \u00e0 Munich o\u00f9 elle disait en substance qu\u2019on ne peut pas toujours \u00e0 100&#160;% s\u2019appuyer sur d\u2019autres pays pour assurer notre propre s\u00e9curit\u00e9, et elle avait bien s\u00fbr les Am\u00e9ricains en ligne de mire apr\u00e8s le sommet de l\u2019OTAN du 25 mai. En r\u00e9alit\u00e9, ce soup\u00e7on sur les \u00c9tats-Unis \u00e9tait exag\u00e9r\u00e9 parce que l\u2019OTAN est toujours tr\u00e8s pr\u00e9sente par le <em>hardware<\/em> et les troupes am\u00e9ricaines et ne va pas s\u2019en aller, et d\u2019autre part parce que Trump, une semaine plus tard, a r\u00e9affirm\u00e9 l\u2019importance de l\u2019article 5 et son attachement \u00e0 l\u2019OTAN, et par ailleurs n\u2019est pas revenu sur la d\u00e9pense suppl\u00e9mentaire de 1,4 milliard pour une brigade d\u2019infanterie m\u00e9canis\u00e9e en Pologne. Donc en fait la situation ne change pas vraiment. Il y a une interrogation plus grande qu\u2019auparavant mais dans les faits, rien ne change.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Peut-\u00eatre que \u00e7a ne change pas, mais la question que tout le monde semble vouloir \u00e9viter, c\u2019est de se demander s\u2019il est dans l\u2019int\u00e9r\u00eat de l\u2019Europe de se distancer de l\u2019OTAN pour pouvoir mener \u00e0 bien la construction d\u2019une Europe de la d\u00e9fense&#160;?<\/h3>\n\n\n\n<p>Oui, mais l\u00e0 on atteint des limites historiques, des limites structurelles. C\u2019est classique&#160;: quand il n\u2019y a pas de crise, on ne peut pas pr\u00e9tendre avoir les outils qui deviennent disponibles au moment d\u2019une crise parce qu\u2019il y a une urgence et le capital politique. Donc oui, je pense que l\u2019Europe de la d\u00e9fense au sens \u00e9tymologique, la d\u00e9fense de l\u2019Union europ\u00e9enne pourrait-on dire, se fera quand le parapluie am\u00e9ricain aura disparu.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Et seulement quand le parapluie am\u00e9ricain aura disparu&#160;?<\/h3>\n\n\n\n<p>Si l\u2019on parle d\u2019un changement fondamental, oui. Il y a des tas de choses qu\u2019on peut faire, qu\u2019on devrait faire et qu\u2019on fait, notamment ces derniers temps, tout en ayant le parapluie am\u00e9ricain, mais on voit bien que l\u2019incitation est moins forte que si, comme Trump l\u2019avait laiss\u00e9 entendre, le parapluie am\u00e9ricain disparaissait.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Vous avez \u00e9voqu\u00e9 rapidement l\u2019axe Paris-Berlin. On parle de sa r\u00e9activation&#160;; vous avez bien point\u00e9 que \u00e7a devait attendre le r\u00e9sultat des \u00e9lections. Est-ce que vous pensez que la r\u00e9activation de cet axe est une bonne id\u00e9e vis-\u00e0-vis des pays d\u2019Europe centrale et orientale, qui pourraient se sentir une nouvelle fois exclus du moteur de la construction europ\u00e9enne&#160;?<\/h3>\n\n\n\n<p>Je ne pense pas qu\u2019il faille juger l\u2019opportunit\u00e9 de r\u00e9activer le moteur par les effets induits potentiellement n\u00e9gatifs sur les pays d\u2019Europe de l\u2019Est. Ce n\u2019est pas la bonne perspective. Qu\u2019il y ait des effets secondaires non souhait\u00e9s, non souhaitables et qu\u2019il faille les g\u00e9rer, c\u2019est une chose&#160;; qu\u2019il soit d\u00e9sirable de relancer le moteur franco-allemand, c\u2019est un imp\u00e9ratif en soi. Tout simplement parce qu\u2019il s\u2019agit d\u2019ouvrir les yeux&#160;: il y a le Brexit, il y a Trump, il y a une Russie mena\u00e7ante. Bref, nous sommes dans un moment o\u00f9 nous n\u2019avons pas beaucoup de pays dont nous sommes proches, et nous avons rarement \u00e9t\u00e9 aussi proches de l\u2019Allemagne que maintenant. Nous avons des diff\u00e9rences de point de vue sur un certain nombre de sujets, mais il n\u2019emp\u00eache que quand on met tout en perspective, il y a vraiment une logique tr\u00e8s forte, et c\u2019est le moment de \u00ab&#160;mettre les chariots en cercle pour se d\u00e9fendre&#160;\u00bb, comme on dit dans une m\u00e9taphore du Far West, parce que le monde ressemble de plus en plus au Far West. Ou plus simplement de renforcer nos liens et de resserrer nos d\u00e9fenses.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00ab&#160;Il faut faire tr\u00e8s attention aux fractures, notamment aux fractures Est\/Ouest, encore plus que Nord\/Sud.&#160;\u00bb<\/p><cite>Justin Va\u00efsse<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Et l\u2019axe Paris-Berlin est pr\u00e9f\u00e9rable \u00e0 ce qu\u2019avait tent\u00e9 de faire le premier ministre italien Renzi l\u2019ann\u00e9e derni\u00e8re en r\u00e9unissant les ministres des six pays fondateurs&#160;? Ne s\u2019agit-il pas l\u00e0 d\u2019une piste envisageable&#160;?<\/h3>\n\n\n\n<p>Le mouvement initial ne venait pas de l\u2019Italie mais en fait de la Belgique, mais peu importe. La r\u00e9ponse est non&#160;: c\u2019est un format possible, mais c\u2019est un format qui est encore plus probl\u00e9matique par rapport aux pays de l\u2019Europe de l\u2019Est, pour le coup. L\u2019un des avantages, quand il y avait la Grande-Bretagne, c\u2019est qu\u2019on avait un spectre de positions vraiment tr\u00e8s large qui faisait que quand nous \u00e9tions d\u2019accord \u00e0 trois, tout le monde \u00e9tait d\u2019accord, mais on conserve un spectre tr\u00e8s large avec le franco-allemand. Nous pouvons quand m\u00eame entra\u00eener beaucoup de nos partenaires.<\/p>\n\n\n\n<p>Je pense qu\u2019il faut faire tr\u00e8s attention en effet aux fractures, notamment aux fractures Est\/Ouest, encore plus que Nord\/Sud, sans doute, mais enfin les deux sont importantes. La fracture Nord\/Sud porte surtout sur les questions mon\u00e9taires, financi\u00e8res, \u00e9conomiques en g\u00e9n\u00e9ral, la fracture Est\/Ouest porte sur des questions de souverainet\u00e9 et d\u2019identit\u00e9. Et on l\u2019a vu lors de la visite de Trump le 6 juillet \u00e0 Varsovie, avec cette crainte de r\u00e9activer <em>old Europe\/new Europe<\/em>. En r\u00e9alit\u00e9 cette vision propos\u00e9e par Trump est tr\u00e8s id\u00e9ologique mais on se demande quelles en sont les cons\u00e9quences et les incidences concr\u00e8tes. Et cela a plu au PiS et \u00e0 Kaczy\u0144ski [NDLR. Droit et justice (PiS), le parti majoritaire \u00e0 l\u2019Assembl\u00e9e polonaise, dirig\u00e9 par Jaroslaw Kaczy\u0144ski], mais enfin, apr\u00e8s tout, on ne sait pas jusqu\u2019o\u00f9 cela peut se traduire concr\u00e8tement, donc je ne suis pas tr\u00e8s inquiet.<\/p>\n\n\n\n<p>Je pense qu\u2019il y a beaucoup d\u2019effervescence en Europe de l\u2019Est, c\u2019est-\u00e0-dire qu\u2019il y a des mouvements tr\u00e8s identitaires, souverainistes, etc., mais qui savent qu\u2019ils ne peuvent pas rompre avec le moteur franco-allemand. Ils peuvent freiner, tra\u00eener des pieds, mettre des obstacles partiels, r\u00e2ler, etc. Mais, fondamentalement, \u00e0 cause des fonds structurels et des investissements, ils ne souhaitent pas rompre. De plus, il existe des forces politiques autres que le PiS. M\u00eame si le PiS est au pouvoir de fa\u00e7on assez solide, m\u00eame si Orban est au pouvoir de fa\u00e7on relativement solide \u2013 mais de moins en moins \u2013, il y a beaucoup d\u2019autres courants d\u2019opinion en Europe de l\u2019Est. Il y a beaucoup d\u2019autres forces, d\u2019autres types de forces, et donc je pense qu\u2019il ne faut pas oublier leur diversit\u00e9. On a \u00e9tudi\u00e9 sous toutes les coutures ce dissensus entre Est et Ouest, mais au bout du compte je pense que si on fait suffisamment attention, si on est suffisamment souple, on peut ne pas en p\u00e2tir. Par exemple, le front europ\u00e9en ne s\u2019est pas fissur\u00e9 face au Brexit.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Oui, c\u2019est m\u00eame peut-\u00eatre un motif de solidarit\u00e9 augment\u00e9e&#160;?<\/h3>\n\n\n\n<p>Ce n\u2019\u00e9tait pas \u00e9vident, parce que la Grande-Bretagne joue le jeu que n\u2019importe qui jouerait dans cette situation \u2013 ce n\u2019est pas la perfide Albion \u2013, c\u2019est vraiment l\u2019id\u00e9e qu\u2019il faut essayer de diviser pour avoir une meilleure position de n\u00e9gociation. Et elle a essay\u00e9 de le faire mais \u00e7a ne marche pas, heureusement. C\u2019est une des bonnes nouvelles de ces derni\u00e8res ann\u00e9es.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Vous avez parl\u00e9 de souplesse. L\u2019un des sc\u00e9narios mis en avant par le <a href=\"https:\/\/ec.europa.eu\/commission\/sites\/beta-political\/files\/white_paper_on_the_future_of_europe_en.pdf\">livre blanc<\/a> de la Commission europ\u00e9enne pour 2025, c\u2019est \u00ab&#160;<em>those who want to do more do more<\/em>&#160;\u00bb . Est-ce que vous pensez que cette Europe \u00ab&#160;souple&#160;\u00bb, \u00ab&#160;\u00e0 plusieurs vitesses&#160;\u00bb est d\u00e9finitivement la voie qui sera privil\u00e9gi\u00e9e dans les prochaines ann\u00e9es dans la construction europ\u00e9enne&#160;?<\/h3>\n\n\n\n<p>Mais l\u2019Europe a toujours \u00e9t\u00e9 flexible&#160;! On le sait bien, c\u2019est difficile \u00e0 \u00e9tudier, l\u2019Europe, parce que ce sont des institutions tr\u00e8s compliqu\u00e9es, y compris, pas seulement, mais y compris parce qu\u2019elles sont flexibles. C\u2019est-\u00e0-dire qu\u2019elles ne se recouvrent pas toujours. La zone Schengen ne recouvre pas la zone euro qui ne recouvre pas l\u2019Union qui ne recouvre pas le mandat d\u2019arr\u00eat europ\u00e9en qui ne recouvre pas d\u2019autres politiques, etc. Donc il y a toujours eu une dose de flexibilit\u00e9. Il y a toujours eu l\u2019id\u00e9e que les plus engag\u00e9s pouvaient aller de l\u2019avant. Je ne sais pas, au bout du compte, si cela ira tr\u00e8s loin. Il faut voir aussi que c\u2019est un instrument de n\u00e9gociation. Si on dit, nous on va aller de l\u2019avant, on va faire une coop\u00e9ration structur\u00e9e permanente par exemple sur la d\u00e9fense qui est pr\u00e9vue par le trait\u00e9, c\u2019est aussi une mani\u00e8re d\u2019inciter ceux qui sont un peu r\u00e9ticents \u00e0 accepter davantage. Parce qu\u2019ils ne veulent pas que le train parte sans eux. C\u2019est un objet compliqu\u00e9, l\u2019Europe flexible&#160;: \u00e7a existe d\u00e9j\u00e0, mais c\u2019est aussi un th\u00e8me pour faire avancer et pour n\u00e9gocier.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Donc pour vous ce n\u2019est pas forc\u00e9ment la seule possibilit\u00e9 pour l\u2019avanc\u00e9e de la construction europ\u00e9enne. Parce que dans le livre blanc, on cite en exergue la phrase de Schumann sur l\u2019Europe qui ne va se faire que par la r\u00e9alisation concr\u00e8te des objectifs, et l\u2019on met souvent en avant l\u2019id\u00e9e que l\u2019Europe ne peut que r\u00e9ussir par la r\u00e9ussite de projets ponctuels. <\/h3>\n\n\n\n<p>Oui. Ou par ses \u00e9checs, comme le disait Jean Monnet.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">N\u2019en a-t-elle pas d\u00e9j\u00e0 connu assez pour le moment&#160;?<\/h3>\n\n\n\n<p>Oui, mais enfin, ce qu\u2019il faut voir quand m\u00eame, c\u2019est exactement la r\u00e9alisation de la phrase de Monnet. Que l\u2019Europe avancera <em>par les crises<\/em>, qu\u2019elle sera la somme des r\u00e9ponses apport\u00e9es \u00e0 ces crises. Et en fait c\u2019est tr\u00e8s frappant&#160;: pourquoi est-ce qu\u2019on a maintenant un corps de garde-c\u00f4tes et de garde-fronti\u00e8res&#160;? Parce qu\u2019il y a une crise. Pourquoi est-ce qu\u2019on a une politique \u00e9trang\u00e8re, qui n\u2019est peut-\u00eatre pas encore formidable&#160;? Parce qu\u2019on a eu la crise des Balkans dans les ann\u00e9es 1990.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Donc l\u2019Europe est condamn\u00e9e \u00e0 rester dans une posture de r\u00e9activit\u00e9 par rapport aux crises qui surviennent&#160;? Il n\u2019est donc pas possible d\u2019avoir une construction spontan\u00e9e&#160;?<\/h3>\n\n\n\n<p>Si on regarde en tant qu\u2019organisme politique dans l\u2019histoire, ce n\u2019est pas forc\u00e9ment une mauvaise recette. Elle est model\u00e9e par les besoins, par la r\u00e9ponse aux crises. Regardez le m\u00e9canisme europ\u00e9en de stabilit\u00e9, l\u2019union bancaire\u2026 C\u2019est \u00e0 cause de la crise de l\u2019euro.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Et cela ne manque pas un peu de vision&#160;? Le Pr\u00e9sident a dit qu\u2019il faut faire r\u00eaver les peuples\u2026<\/h3>\n\n\n\n<p>Oui, j\u2019attends beaucoup des conventions d\u00e9mocratiques qui vont \u00eatre organis\u00e9es d\u2019ici la fin de l\u2019ann\u00e9e et qui vont commencer en 2018. J\u2019ai plut\u00f4t bon espoir&#160;; je pense que lorsqu\u2019on demande aux gens, surtout de fa\u00e7on assez nouvelle, toute une partie de la population  r\u00e9pond positivement. C\u2019est un peu la d\u00e9couverte de la campagne \u00e9lectorale d\u2019Obama. Les gens ont aussi une envie de faire de la politique un peu autrement. Il y a beaucoup de marges avec l\u2019Europe, avec une certaine relance de l\u2019id\u00e9e europ\u00e9enne.<\/p>\n\n\n\n<p>L\u2019id\u00e9e des conventions d\u00e9mocratiques, c\u2019est de travailler d\u2019abord entre nous, puis d\u2019en parler aux Allemands, ensuite \u00e0 la Commission europ\u00e9enne pour le Conseil de d\u00e9cembre. Par la suite, les pays qui le souhaitent organiseront des conventions selon un sch\u00e9ma souple qu\u2019ils adapteront \u00e0 leur propre pays. Voil\u00e0 l\u2019id\u00e9e&#160;: de poser des questions, consulter, \u00e9couter les id\u00e9es, les projets, les r\u00eaves \u00e9ventuellement, des gens pour l\u2019Europe. Il faut voir ce que \u00e7a va donner, mais je pense que le projet tient la route.<\/p>\n\n\n\n<p>Cela dit, si on prend une vision un peu moins prescriptive, optimiste, politique, etc., on peut simplement voir que les gouvernements finissent toujours par faire ce qu\u2019il faut pour que cela continue. J\u2019\u00e9tais \u00e0 Washington dans les ann\u00e9es 2008-2012, \u00e0 un moment o\u00f9 mes petits camarades am\u00e9ricains disaient que l\u2019euro allait dispara\u00eetre. Pas tous, mais une majorit\u00e9 des experts et observateurs qui regardaient l\u2019Union \u00e0 Washington, notamment vers 2010-2011, pronostiquaient la fin de l\u2019euro, et \u00e7a m\u2019a marqu\u00e9. Je leur disais&#160;: mais vous savez, il y a quand m\u00eame des raisons politiques fondamentales pour lesquelles la fin de l\u2019euro n\u2019aura pas lieu parce que \u00e7a serait la fin de l\u2019Europe, la fin de l\u2019Union, etc., parce que le d\u00e9mant\u00e8lement co\u00fbterait beaucoup plus cher que le maintien de l\u2019euro dans des conditions qui sont, il faut l\u2019admettre, mauvaises, parce que c\u2019est une construction qui a \u00e9t\u00e9 faite sur des compromis dans les ann\u00e9es 1990 pour quand il fait beau temps. Et quand il y a une temp\u00eate, la situation devient plus compliqu\u00e9e. Il faut alors r\u00e9parer le bateau. C\u2019est difficile, parce qu\u2019il faut \u00e0 la fois lui \u00e9viter de couler, si je file la m\u00e9taphore, et remanier le bateau sur le long terme, c\u2019est-\u00e0-dire, faire \u00e0 la fois le le r\u00e9parateur et l\u2019architecte.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00ab&#160;La politique \u00e9trang\u00e8re de l\u2019Union est commune, elle n\u2019est pas unique.&#160;\u00bb<\/p><cite>Justin Va\u00efsse<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">En acceptant que la difficult\u00e9 d\u2019avoir une monnaie unique pour des \u00e9conomies tr\u00e8s h\u00e9t\u00e9rog\u00e8nes subsiste encore aujourd\u2019hui.<\/h3>\n\n\n\n<p>Absolument. C\u2019est une question fondamentale, je suis d\u2019accord. Mais il faut voir la chose sur le long terme. La zone dollar a mis beaucoup de temps \u00e0 trouver son \u00e9quilibre, elle a connu un grand nombre de crises, et a failli dispara\u00eetre. Donc pourquoi l\u2019euro, qui a dix-sept ans, tout d\u2019un coup devrait \u00eatre une monnaie puissante, une monnaie de r\u00e9serve, solide, qui n\u2019ait pas de probl\u00e8me de transferts, qui n\u2019ait pas de probl\u00e8me de <em><a href=\"https:\/\/www.ecb.europa.eu\/paym\/t2\/html\/index.en.html\">Target-2 <\/a><\/em><em>(<\/em>NDLR&#160;: <em>syst\u00e8me de<\/em> r\u00e8glement<em> interbancaire de la zone euro)<\/em>, etc. Ce serait \u00e9tonnant.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Derni\u00e8re question sur ce premier th\u00e8me. Le retrait du Royaume-Uni, on en a d\u00e9j\u00e0 parl\u00e9, veut dire que l\u2019Europe va perdre un si\u00e8ge permanent au Conseil de S\u00e9curit\u00e9 de l\u2019ONU. Que va signifier pour l\u2019Europe ce monopole de la France sur la position au Conseil de l\u2019Europe et est-ce qu\u2019on envisage \u2013 c\u2019est h\u00e9r\u00e9tique et na\u00eff \u2013 la transformation progressive du si\u00e8ge de la France en si\u00e8ge europ\u00e9anis\u00e9&#160;?<\/h3>\n\n\n\n<p>Non. Parce qu\u2019au CSNU, on vote oui ou non \u2013 ou l\u2019on s\u2019abstient. La politique \u00e9trang\u00e8re de l\u2019Union est commune, mais elle n\u2019est pas unique. Il faut une politique unique pour pouvoir dire oui, non, ou abstention. C\u2019est aussi b\u00eate que cela. Donc tant qu\u2019on n\u2019a pas de politique \u00e9trang\u00e8re unique, il n\u2019y aura pas de si\u00e8ge europ\u00e9en parce que ce serait une perte d\u2019influence, y compris pour l\u2019Europe. M\u00eame quand les gens ne seront pas d\u2019accord avec les votes fran\u00e7ais, ce serait une perte d\u2019influence d\u2019avoir un vote qui soit toujours moyenneur. Donc je pense que le temps n\u2019est pas venu. En revanche ce qu\u2019il est possible de faire, et c\u2019est tout \u00e0 fait dans l\u2019id\u00e9e des autorit\u00e9s actuelles, c\u2019est, bien conscients du fait que c\u2019est le dernier membre permanent, discuter ensemble de nos positions. Il faut bien voir qu\u2019il y en a toujours, des Europ\u00e9ens au Conseil \u2013 sans droit de veto \u2013 mais ils comptent beaucoup parce que souvent ce sont des diplomaties comme l\u2019Allemagne, les Pays-Bas, l\u2019Espagne, des diplomaties solides avec qui l\u2019on peut travailler sur tous les sujets.<\/p>\n\n\n\n<p>L\u2019id\u00e9e c\u2019est plut\u00f4t&#160;: quelle coordination europ\u00e9enne pour les votes&#160;? On est plut\u00f4t dans l\u2019ordre de l\u2019am\u00e9nagement de la d\u00e9cision, de la consultation, parce qu\u2019aucun pr\u00e9sident ne d\u00e9cidera de soumettre le vote au CSNU \u00e0 l\u2019approbation des autres. On garde la d\u00e9cision en dernier ressort, en revanche c\u2019est sur la concertation et la d\u00e9cision en commun, ou la consultation des autres pour une d\u00e9cision en commun, autant qu\u2019il est possible, que l\u2019on peut faire des progr\u00e8s.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00ab&#160;L\u2019id\u00e9e qu\u2019il faudrait commencer par mettre en commun, par exemple le si\u00e8ge au Conseil de s\u00e9curit\u00e9, c\u2019est mettre la charrue avant les b\u0153ufs.&#160;\u00bb<\/p><cite>Justin Va\u00efsse<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Vous avez mis le doigt sur le probl\u00e8me. Vous avez dit&#160;: aucun pr\u00e9sident ne serait pr\u00eat \u00e0 le faire. Est-ce qu\u2019une vraie construction europ\u00e9enne est possible tant que les \u00c9tats-nations demeurent les acteurs privil\u00e9gi\u00e9s de cette construction&#160;?<\/h3>\n\n\n\n<p>Je crois qu\u2019il faut \u00eatre pragmatique. Si on veut \u00eatre th\u00e9orique, on peut dire que ce n\u2019est pas possible. Mais la construction europ\u00e9enne, ce n\u2019est pas un jardin \u00e0 la fran\u00e7aise. Il faut prendre compte des r\u00e9alit\u00e9s&#160;: la r\u00e9alit\u00e9 \u2013 et elle a \u00e9t\u00e9 r\u00e9affirm\u00e9e avec violence au cours des dix derni\u00e8res ann\u00e9es, depuis 2005 notamment \u2013 c\u2019est la persistance des \u00c9tats-nations, du sentiment national. Et donc toute la difficult\u00e9, c\u2019est de construire une Europe qui ne soit pas l\u2019<em>ennemie<\/em> des \u00c9tats-nations mais qui trouve sa place \u00e0 c\u00f4t\u00e9 d\u2019eux, \u00e0 la fois dans le c\u0153ur des gens, dans l\u2019identit\u00e9, dans le m\u00e9lange de l\u2019identit\u00e9 europ\u00e9enne et des identit\u00e9s nationales, et qui d\u2019autre part d\u2019un point de vue institutionnel parvienne \u00e0 prendre ce qu\u2019il y a de meilleur des deux c\u00f4t\u00e9s.<\/p>\n\n\n\n<p>Prenons un exemple dans la politique \u00e9trang\u00e8re. La politique \u00e9trang\u00e8re europ\u00e9enne est efficace, non pas quand c\u2019est Mogherini qui fait tout, non pas quand c\u2019est la France qui fait tout, mais quand c\u2019est un m\u00e9lange des forces et une alliance des forces. Typiquement quand on fait le E3 sur l\u2019Iran, typiquement quand on fait Normandie sur l\u2019Ukraine. \u00c7a n\u2019est pas contradictoire avec la construction europ\u00e9enne, c\u2019est juste la r\u00e9alit\u00e9 qui fait qu\u2019il y a des diplomaties fortes et qu\u2019on peut b\u00e2tir sur ces diplomaties-l\u00e0 pour construire une politique commune. Mais l\u2019id\u00e9e qu\u2019il faudrait commencer par mettre en commun, par exemple le si\u00e8ge au CS, c\u2019est mettre la charrue avant les b\u0153ufs. Et peut-\u00eatre que les b\u0153ufs n\u2019arriveront jamais devant la charrue, ou en tout cas de notre vivant. Peut-\u00eatre que si, mais je pense qu\u2019il faut prendre un pas de recul pour voir la persistance et la r\u00e9sistance des \u00c9tats-nations et du sentiment national. Je ne pense pas qu\u2019on construira l\u2019Europe contre \u00e7a. M\u00eame si, intellectuellement, certains voudraient bien faire un saut f\u00e9d\u00e9ral. Intellectuellement, c\u2019est tentant. Mais ce n\u2019est pas la r\u00e9alit\u00e9.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Maintenant pour \u00e9largir le cadre de la r\u00e9flexion, on parlait de la politique \u00e9trang\u00e8re et de s\u00e9curit\u00e9 commune, et je pense qu\u2019on sera d\u2019accord pour dire que pour en faire une qui fonctionne vraiment, qui ait une existence pertinente au niveau mondial, il faut d\u00e9finir des strat\u00e9gies communes pour des int\u00e9r\u00eats communs. Et on pourrait se demander \u00e0 quand, par exemple, une strat\u00e9gie commune europ\u00e9enne sur l\u2019Afrique, alors qu\u2019on assiste aujourd\u2019hui \u00e0 des int\u00e9r\u00eats nationaux qui tentent de grappiller ce qu\u2019ils peuvent sur le continent africain.<\/h3>\n\n\n\n<p>On a une strat\u00e9gie Chine, par exemple, qui est tr\u00e8s substantielle et normative.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tout en admettant qu\u2019il y ait une comp\u00e9tition entre la France et l\u2019Allemagne, entre la France et le Royaume-Uni.<\/h3>\n\n\n\n<p>Oui, mais je vois la comp\u00e9tition diminuer, et les processus de coop\u00e9ration et convergence prendre de l\u2019importance. C\u2019est \u00e7a le crit\u00e8re&#160;: ce n\u2019est pas une politique \u00e9trang\u00e8re unique, mais c\u2019est qu\u2019est-ce qu\u2019on peut trouver comme socle commun&#160;? Sur l\u2019Afrique, il y a une strat\u00e9gie Sahel, et il y a la strat\u00e9gie globale de l\u2019Union de l\u2019an dernier, sur laquelle j\u2019ai eu la chance de travailler, notamment sur le paragraphe qui concerne <em>autonomie strat\u00e9gique<\/em>, et d\u2019autres projets du m\u00eame acabit. On a \u00e9t\u00e9 tr\u00e8s actifs dans l\u2019\u00e9criture de cette strat\u00e9gie qui n\u2019est pas tr\u00e8s d\u00e9taill\u00e9e, mais enfin elle existe.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L\u00e0 encore, on a l\u2019impression que les autres pays europ\u00e9ens sont un peu emmen\u00e9s par <a href=\"http:\/\/www.defense.gouv.fr\/operations\/operations\/sahel\/dossier-de-presentation-de-l-operation-barkhane\/operation-barkhane\">Barkhane<\/a> et ses autres op\u00e9rations dans la r\u00e9gion, et on se demande dans quelle mesure il s\u2019agit juste d\u2019une justification cosm\u00e9tique ajout\u00e9e \u00e0 un engagement fran\u00e7ais.<\/h3>\n\n\n\n<p>Il y a plus de soldats allemands dans la Minusma que de soldats fran\u00e7ais, ce serait presque une op\u00e9ration allemande&#160;! C\u2019est surtout une op\u00e9ration de l\u2019ONU. On essaye de faire prendre conscience \u00e0 nos partenaires europ\u00e9ens que ce ne sont pas nos soi-disant projets n\u00e9ocoloniaux \u2013 comme certains nous en accusent \u2013 que l\u2019on sert quand on \u00e9vite qu\u2019un des plus grands \u00c9tats de l\u2019Afrique tombe aux mains des djihadistes et que les cons\u00e9quences et les implications n\u00e9gatives seraient ressenties par tout le monde, en termes de migration, en termes de terrorisme, en termes de sous-d\u00e9veloppement\u2026<\/p>\n\n\n\n<p>Il existe des diff\u00e9rences d\u00e9mographiques tr\u00e8s importantes qui ne vont pas forc\u00e9ment aboutir \u00e0 des migrations de masse vers l\u2019Europe mais qui vont au minimum mettre sous tension les infrastructures locales d\u2019\u00e9ducation, de sant\u00e9 et d\u2019emploi. Donc \u00e7a veut dire qu\u2019ils vont aller ailleurs, ces jeunes gens. Or ce n\u2019est pas une simple projection pour le futur&#160;: ils sont d\u00e9j\u00e0 n\u00e9s, ce sont des jeunes gens qui ont deux ans, quatre ans, huit ans, douze ans. Elles sont l\u00e0, d\u00e9j\u00e0, ces cohortes-l\u00e0, comme on dit en termes d\u00e9mographiques, et il va bien falloir qu\u2019elles aillent quelque part, alors elles vont aller, sans doute comme maintenant, en Afrique \u00e0 90&#160;%&#160;: les migrations sont d\u2019abord intra-africaines. Mais par ailleurs on va essayer, on essaye de faire en sorte d\u2019en fixer un maximum par l\u2019effort de d\u00e9veloppement. Et troisi\u00e8mement, il y en aura forc\u00e9ment une partie qui migrera, surtout s\u2019il y a des r\u00e9seaux de passeurs, des voies de passage facile, et des conflits. Donc pour conclure, c\u2019est sur tous ces points qu\u2019on essaie de convaincre nos partenaires.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mais on l\u2019impression, souvent, qu\u2019il y a une volont\u00e9, une vell\u00e9it\u00e9 d\u2019\u00eatre sur les grands dossiers internationaux&#160;: Iran, ou la crise actuelle dans le Golfe, avec le comportement un peu agressif de l\u2019Arabie saoudite entre autres, et souvent la position europ\u00e9enne passe par l\u2019interm\u00e9diaire d\u2019un pays europ\u00e9en. Sur le dossier iranien, par exemple, au bout d\u2019un certain moment, la position europ\u00e9enne s\u2019effrite, le pays qui la repr\u00e9sente est cong\u00e9di\u00e9 parce que ce n\u2019est qu\u2019un \u00c9tat-nation et que les autres pays sont la Chine, la Russie ou les \u00c9tats-Unis, par rapport auxquels un \u00c9tat-nation europ\u00e9en n\u2019a pas vraiment voix au chapitre. On a l\u2019impression que la mise en avant des positions europ\u00e9ennes ne fonctionne pas encore. Le Pr\u00e9sident a parl\u00e9 du r\u00f4le de m\u00e9diation que pouvait jouer l\u2019Europe entre les deux personnalit\u00e9s un peu impr\u00e9visibles que sont Poutine d\u2019un c\u00f4t\u00e9 et Trump de l\u2019autre. L\u2019Europe est toujours dans une posture de m\u00e9diation. Il n\u2019y a pas vraiment de construction autonome de son r\u00f4le. \u00cates-vous d\u2019accord avec ce constat, et quels seraient, le cas \u00e9ch\u00e9ant, les moyens d\u2019y rem\u00e9dier&#160;? <\/h3>\n\n\n\n<p>C\u2019est vrai qu\u2019il n\u2019y a pas, ou pas encore, une voix de l\u2019Europe forte et unifi\u00e9e sur la Syrie, la Libye, etc. Cela dit, il y a quand m\u00eame des progr\u00e8s, comme, par exemple, les sanctions contre la Russie, qui sont claires. Je pense que l\u00e0 o\u00f9 l\u2019Europe a un avantage comparatif, c\u2019est dans la politique structurelle, les choses qu\u2019on fait sur le long terme. Les sanctions sont un des rares outils de <em>hard power <\/em>que l\u2019Europe d\u00e9tient, et il ne faudrait pas en n\u00e9gliger l\u2019importance. Mais \u00e7a ne cr\u00e9e pas pour autant une unicit\u00e9, un Trump, un Poutine ou un Xi Jinping. Ce n\u2019est pas au m\u00eame niveau, parce que nous demeurons dans cet entre-deux, avec des \u00c9tats-nations importants et ind\u00e9pendants, comme la France et l\u2019Allemagne, sur l\u2019Ukraine par exemple.<\/p>\n\n\n\n<p>Quand Jean-Yves Le Drian part en mission dans le Golfe, il n\u2019a pas les meme atouts que Tillerson, mais il a quand m\u00eame une certaine marge de manoeuvre, et joue un r\u00f4le utile. L\u2019Europe, elle, ne peut pas, par exemple, d\u00e9ployer des soldats \u00e0 Raqqa. Raqqa sera bient\u00f4t lib\u00e9r\u00e9e, et il est difficile de concevoir que l\u2019Europe prenne en charge le maintien de la paix et la d\u00e9sescalade, etc., \u00e0 Raqqa. Donc il y a une question d\u2019outils, d\u2019instruments. L\u2019Europe repr\u00e9sente le long terme, avec notamment les programmes structurels d\u2019aide au d\u00e9veloppement, de projets de ce type, qui ne permettent cependant pas une diplomatie de mouvement, au jour le jour.<\/p>\n\n\n\n<p>Il y a aussi une question de temporalit\u00e9. Une question d\u2019efficacit\u00e9, de poids, d\u2019instruments&#160;: on ne joue pas sur la m\u00eame temporalit\u00e9. Par exemple, un accord commercial entre l\u2019Europe et le Japon serait un \u00e9v\u00e9nement majeur avec une influence sur les relations internationales et les normes qui les r\u00e9gissent.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Il est difficile d\u2019imaginer qu\u2019un tel accord puisse \u00eatre populaire.<\/h3>\n\n\n\n<p>Oui.  Cela va \u00eatre tr\u00e8s difficile d\u2019en faire la d\u00e9fense et l\u2019illustration, mais il n\u2019emp\u00eache que ce serait une r\u00e9alit\u00e9 au moment o\u00f9 Trump est en retrait et o\u00f9 Xi Jinping fait comprendre qu\u2019il veut prendre le leadership en Asie. Il est vraiment important que l\u2019UE et le Japon finalisent cet accord. Donc on est vraiment encore une fois dans un entre-deux. C\u2019est vrai, l\u2019Europe reste un nain g\u00e9opolitique, au milieu de g\u00e9ants. Mais en fait, sur un certain nombre de sujets, il ne faut pas non plus aller trop loin dans l\u2019auto-critique, et oublier de voir les instruments structurels et de moyen-terme de l\u2019Europe, et l\u2019impact qu\u2019ils peuvent avoir. M\u00eame si elle ne fait pas les gros titres des quotidiens \u2013 m\u00eame pas vraiment des hebdomadaires, elle devrait faire les gros titres des mensuels et des trimestriels.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab&#160;&#160;L\u2019OTAN qui a tant contribu\u00e9 \u00e0 la d\u00e9fense du territoire europ\u00e9en a dans le m\u00eame temps \u00e9t\u00e9 le meilleur vaccin contre une d\u00e9fense europ\u00e9enne&#160;&#160;\u00bb<\/p>\n","protected":false},"author":4,"featured_media":16448,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-interviews.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":0,"footnotes":""},"categories":[1732],"tags":[],"staff":[1910],"editorial_format":[4854],"serie":[],"audience":[],"geo":[536],"class_list":["post-3513","post","type-post","status-publish","format-standard","hentry","category-guerre","staff-daniel-montin","editorial_format-entretiens","geo-centres"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":16448,"excerpt":"\u00ab L\u2019OTAN qui a tant contribu\u00e9 \u00e0 la d\u00e9fense du territoire europ\u00e9en a dans le m\u00eame temps \u00e9t\u00e9 le meilleur vaccin contre une d\u00e9fense europ\u00e9enne \u00bb","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La position de la France, une conversation avec Justin Va\u00efsse | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2017\/09\/15\/nous-avons-rencontre-justin-vaisse\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La position de la France, une conversation avec Justin Va\u00efsse | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"\u00ab&#160;L\u2019OTAN qui a tant contribu\u00e9 \u00e0 la d\u00e9fense du territoire europ\u00e9en a dans le m\u00eame temps \u00e9t\u00e9 le meilleur vaccin contre une d\u00e9fense europ\u00e9enne&#160;\u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2017\/09\/15\/nous-avons-rencontre-justin-vaisse\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-15T08:29:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-08T09:03:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2017\/09\/2016_-_Portrait_Justin_Vaisse.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"820\" \/>\n\t<meta property=\"og:image:height\" content=\"1232\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"gegeurope\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"gegeurope\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"31 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2017\/09\/15\/nous-avons-rencontre-justin-vaisse\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2017\/09\/15\/nous-avons-rencontre-justin-vaisse\/\",\"name\":\"La position de la France, une conversation avec Justin Va\u00efsse | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2017\/09\/15\/nous-avons-rencontre-justin-vaisse\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2017\/09\/15\/nous-avons-rencontre-justin-vaisse\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2017\/09\/2016_-_Portrait_Justin_Vaisse.jpg\",\"datePublished\":\"2017-09-15T08:29:24+00:00\",\"dateModified\":\"2019-07-08T09:03:32+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/25753fbf57948f81eb98a2daaf0a1f44\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2017\/09\/15\/nous-avons-rencontre-justin-vaisse\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2017\/09\/15\/nous-avons-rencontre-justin-vaisse\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2017\/09\/15\/nous-avons-rencontre-justin-vaisse\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2017\/09\/2016_-_Portrait_Justin_Vaisse.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2017\/09\/2016_-_Portrait_Justin_Vaisse.jpg\",\"width\":820,\"height\":1232},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2017\/09\/15\/nous-avons-rencontre-justin-vaisse\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La position de la France, une conversation avec Justin Va\u00efsse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/25753fbf57948f81eb98a2daaf0a1f44\",\"name\":\"gegeurope\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/332bc77b348876050983d79aac818e16?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/332bc77b348876050983d79aac818e16?s=96&d=mm&r=g\",\"caption\":\"gegeurope\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La position de la France, une conversation avec Justin Va\u00efsse | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2017\/09\/15\/nous-avons-rencontre-justin-vaisse\/","og_locale":"fr_FR","og_type":"article","og_title":"La position de la France, une conversation avec Justin Va\u00efsse | Le Grand Continent","og_description":"\u00ab&#160;L\u2019OTAN qui a tant contribu\u00e9 \u00e0 la d\u00e9fense du territoire europ\u00e9en a dans le m\u00eame temps \u00e9t\u00e9 le meilleur vaccin contre une d\u00e9fense europ\u00e9enne&#160;\u00bb","og_url":"https:\/\/legrandcontinent.eu\/fr\/2017\/09\/15\/nous-avons-rencontre-justin-vaisse\/","og_site_name":"Le Grand Continent","article_published_time":"2017-09-15T08:29:24+00:00","article_modified_time":"2019-07-08T09:03:32+00:00","og_image":[{"width":820,"height":1232,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2017\/09\/2016_-_Portrait_Justin_Vaisse.jpg","type":"image\/jpeg"}],"author":"gegeurope","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"gegeurope","Dur\u00e9e de lecture estim\u00e9e":"31 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2017\/09\/15\/nous-avons-rencontre-justin-vaisse\/","url":"https:\/\/legrandcontinent.eu\/fr\/2017\/09\/15\/nous-avons-rencontre-justin-vaisse\/","name":"La position de la France, une conversation avec Justin Va\u00efsse | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2017\/09\/15\/nous-avons-rencontre-justin-vaisse\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2017\/09\/15\/nous-avons-rencontre-justin-vaisse\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2017\/09\/2016_-_Portrait_Justin_Vaisse.jpg","datePublished":"2017-09-15T08:29:24+00:00","dateModified":"2019-07-08T09:03:32+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/25753fbf57948f81eb98a2daaf0a1f44"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2017\/09\/15\/nous-avons-rencontre-justin-vaisse\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2017\/09\/15\/nous-avons-rencontre-justin-vaisse\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2017\/09\/15\/nous-avons-rencontre-justin-vaisse\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2017\/09\/2016_-_Portrait_Justin_Vaisse.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2017\/09\/2016_-_Portrait_Justin_Vaisse.jpg","width":820,"height":1232},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2017\/09\/15\/nous-avons-rencontre-justin-vaisse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"La position de la France, une conversation avec Justin Va\u00efsse"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/25753fbf57948f81eb98a2daaf0a1f44","name":"gegeurope","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/332bc77b348876050983d79aac818e16?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/332bc77b348876050983d79aac818e16?s=96&d=mm&r=g","caption":"gegeurope"}}]}},"lgc_categories":[{"id":1732,"name":"Guerre","slug":"guerre"}],"lgc_author":{"id":1910,"name":"Daniel Montin","slug":"daniel-montin","description":null,"first_name":null,"last_name":null,"picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/10\/gc-Montin.png","width":167,"height":154,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2017\/09\/2016_-_Portrait_Justin_Vaisse.jpg","width":820,"height":1232,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2017\/09\/2016_-_Portrait_Justin_Vaisse.jpg","width":820,"height":1232,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/3513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=3513"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/3513\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/16448"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=3513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=3513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=3513"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=3513"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=3513"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=3513"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=3513"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=3513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}