{"id":329108,"date":"2026-04-22T18:01:14","date_gmt":"2026-04-22T16:01:14","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=329108"},"modified":"2026-04-22T18:01:17","modified_gmt":"2026-04-22T16:01:17","slug":"suspension-des-exportations-de-petrole-kazakh-par-moscou-quelles-consequences-pour-lallemagne","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2026\/04\/22\/suspension-des-exportations-de-petrole-kazakh-par-moscou-quelles-consequences-pour-lallemagne\/","title":{"rendered":"Suspension des exportations de p\u00e9trole kazakh par Moscou&#160;: quelles cons\u00e9quences pour l\u2019Allemagne&#160;?"},"content":{"rendered":"\n<p>Le vice-Premier ministre russe Alexandre Novak a confirm\u00e9 aujourd\u2019hui, mercredi 22 avril, que Moscou allait suspendre \u00e0 compter du 1er mai le transport du p\u00e9trole depuis le Kazakhstan vers l\u2019Allemagne en raison de \u00ab&#160;contraintes techniques&#160;\u00bb. Les flux devraient \u00eatre redirig\u00e9s \u00ab&#160;vers d\u2019autres itin\u00e9raires&#160;\u00bb, selon Moscou&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-329108' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2026\/04\/22\/suspension-des-exportations-de-petrole-kazakh-par-moscou-quelles-consequences-pour-lallemagne\/#easy-footnote-bottom-1-329108' title='\u00ab&amp;#160;&lt;a href=&quot;https:\/\/tass.ru\/ekonomika\/27188279&quot;&gt;\u041d\u043e\u0432\u0430\u043a \u043e\u0431\u044a\u044f\u0432\u0438\u043b \u043e \u0441\u043c\u0435\u043d\u0435 \u043d\u0430\u043f\u0440\u0430\u0432\u043b\u0435\u043d\u0438\u0439 \u043f\u043e\u0441\u0442\u0430\u0432\u043e\u043a \u043d\u0435\u0444\u0442\u0438 \u041a\u0430\u0437\u0430\u0445\u0441\u0442\u0430\u043d\u0430 \u0438\u0437 \u00ab&amp;#160;\u0414\u0440\u0443\u0436\u0431\u044b&amp;#160;\u00bb \u0441 \u043c\u0430\u044f&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;TASS&lt;\/em&gt;, 22 avril 2026.'><sup>1<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le Kazakhstan a export\u00e9 l\u2019\u00e9quivalent de 43 000 barils de brut par jour en 2025 via l\u2019ol\u00e9oduc Droujba, qui passe par le territoire russe, soit environ 2,1 million de tonnes.<\/li>\n\n\n\n<li>Au total, le pays a fourni 10,3 millions de tonnes de p\u00e9trole \u00e0 l\u2019Allemagne l\u2019an dernier, ce qui fait d\u2019Astana le 4e fournisseur de p\u00e9trole du pays, derri\u00e8re la Norv\u00e8ge, les \u00c9tats-Unis et la Libye.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/GYHAJ\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>L\u2019arr\u00eat des flux via Droujba pourrait avoir un impact significatif sur l\u2019approvisionnement allemand en p\u00e9trole.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le brut kazakh transport\u00e9 via l\u2019ol\u00e9oduc repr\u00e9sente environ 17&#160;% du p\u00e9trole trait\u00e9 par la raffinerie PCK, l&rsquo;une des plus importantes du pays, situ\u00e9e dans la ville de Schwedt, \u00e0 80 kilom\u00e8tres au nord-est de Berlin.<\/li>\n\n\n\n<li>Le carburant qui sort de cette raffinerie permet d\u2019alimenter environ 90&#160;% des voitures en circulation dans la capitale allemande et dans le Land de Brandebourg.<\/li>\n\n\n\n<li>PCK assure \u00e9galement 90&#160;% de l\u2019approvisionnement de Berlin et du Brandebourg en k\u00e9ros\u00e8ne, en gazole et en fioul domestique.<\/li>\n<\/ul>\n\n\n\n<p>Le Kremlin n\u2019a pas donn\u00e9 de raison justifiant sa d\u00e9cision. Mercredi 22, le ministre kazakh de l\u2019\u00c9nergie a sugg\u00e9r\u00e9 que la suspension pourrait avoir \u00e9t\u00e9 provoqu\u00e9e par <a href=\"https:\/\/legrandcontinent.eu\/fr\/2026\/04\/20\/les-frappes-ukrainiennes-de-drones-imposent-un-cout-considerable-a-la-russie\/\">des frappes de drones ukrainiens<\/a> visant les infrastructures \u00e9nerg\u00e9tiques russes&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-329108' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2026\/04\/22\/suspension-des-exportations-de-petrole-kazakh-par-moscou-quelles-consequences-pour-lallemagne\/#easy-footnote-bottom-2-329108' title='Anastasia Stognei et Anne-Sylvaine Chassany, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.ft.com\/content\/3738ba48-b4e2-493d-96b1-0a80b4e2c4b8?shareType=nongift&amp;amp;syn-25a6b1a6=1&quot;&gt;Russia to suspend Kazakh oil flows through key pipeline supplying Berlin&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;Financial Times&lt;\/em&gt;, 22 avril 2026.'><sup>2<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>D\u00e9but mars, Vladimir Poutine avait menac\u00e9 d\u2019interrompre les livraisons de gaz \u00e0 l\u2019Europe en raison de l\u2019interdiction progressive mise en place par l\u2019Union d\u2019achats de gaz et de GNL russe&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-329108' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2026\/04\/22\/suspension-des-exportations-de-petrole-kazakh-par-moscou-quelles-consequences-pour-lallemagne\/#easy-footnote-bottom-3-329108' title='Guy Faulconbridge, Marina Bobrova et Vladimir Soldatkin, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.reuters.com\/business\/energy\/putin-suggests-russia-could-stop-supplying-gas-european-markets-now-2026-03-04\/&quot;&gt;Russia may halt gas supplies to Europe amid Iran energy spike, Putin says&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;Reuters&lt;\/em&gt;, 4 mars 2026.'><sup>3<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>\u00c0 partir du 25 avril, les \u00c9tats membres ne pourront plus acheter de GNL russe dans le cadre de contrats \u00e0 court terme conclus avant le 17 juin 2025. Pour les contrats \u00e0 long terme, cette interdiction s\u2019appliquera \u00e0 partir du 1er janvier 2027.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/UxQeO\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>La d\u00e9cision du Kremlin pourrait viser principalement \u00e0 exercer une pression suppl\u00e9mentaire sur l\u2019Allemagne, l\u2019un des principaux soutiens de l\u2019Ukraine. Mercredi dernier, le minist\u00e8re de la D\u00e9fense russe avait publi\u00e9 une liste d\u2019entreprises, principalement situ\u00e9es en Europe, d\u00e9crites comme des \u00ab&#160;cibles militaires potentielles&#160;\u00bb en raison de leur production suppos\u00e9e de drones utilis\u00e9s par l\u2019arm\u00e9e ukrainienne.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Berlin a convoqu\u00e9 lundi 20 l\u2019ambassadeur russe en Allemagne, d\u00e9non\u00e7ant des menaces \u00ab&#160;inacceptables&#160;\u00bb et condamnant les activit\u00e9s d\u2019espionnage russes.<\/li>\n\n\n\n<li>Le minist\u00e8re f\u00e9d\u00e9ral des Affaires \u00e9trang\u00e8res allemand avait \u00e9galement accus\u00e9 Moscou de chercher \u00e0 affaiblir le soutien en faveur de l\u2019Ukraine et de \u00ab&#160;mettre \u00e0 l\u2019\u00e9preuve&#160;\u00bb l\u2019unit\u00e9 europ\u00e9enne.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Direct threats from Russia against targets in Germany are an attempt to weaken our support for Ukraine and test our unity.<br>1\/2<\/p>&mdash; GermanForeignOffice (@GermanyDiplo) <a href=\"https:\/\/twitter.com\/GermanyDiplo\/status\/2046285104557740456?ref_src=twsrc%5Etfw\">April 20, 2026<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Selon des sources allemandes, le Kremlin aurait \u00e9t\u00e9 \u00ab&#160;furieux&#160;\u00bb de la pr\u00e9sence de Zelensky \u00e0 Berlin aux c\u00f4t\u00e9s de Merz le 14 avril&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-329108' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2026\/04\/22\/suspension-des-exportations-de-petrole-kazakh-par-moscou-quelles-consequences-pour-lallemagne\/#easy-footnote-bottom-4-329108' title='Michael Maier, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.berliner-zeitung.de\/article\/oel-stopp-aus-kasachstan-dreht-putin-deutschland-jetzt-den-oel-hahn-zu-10031803&quot;&gt;\u00d6l-Stopp aus Kasachstan&amp;#160;: Dreht Putin Deutschland jetzt den \u00d6l-Hahn zu&amp;#160;?&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;Berliner Zeitung&lt;\/em&gt;, 21 avril 2026.'><sup>4<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>Au cours de la rencontre, les deux dirigeants ont sign\u00e9 des accords de coop\u00e9ration en mati\u00e8re de d\u00e9fense, et notamment un accord portant sur la production de drones.<\/li>\n<\/ul>\n\n\n\n<p>Berlin pourrait accro\u00eetre les volumes d\u2019importation de p\u00e9trole depuis la Pologne pour compenser la perte du brut transport\u00e9 via Droujba. Au-del\u00e0 du potentiel impact sur le transport \u2014 dont le trafic a\u00e9rien de l&rsquo;a\u00e9roport de Berlin-Brandebourg \u2014, la raffinerie PCK constitue une infrastructure vitale pour le flanc Est de l\u2019OTAN. Bien que sous tutelle du gouvernement allemand depuis 2022, celle-ci est toujours d\u00e9tenue \u00e0 54&#160;% par le groupe p\u00e9trolier public russe Rosneft.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 partir du 1er mai, la Russie va mettre fin au transport de brut depuis le Kazakhstan vers l\u2019Allemagne via l\u2019ol\u00e9oduc Droujba, qui passe par le territoire russe. <\/p>\n<p>L\u2019arr\u00eat des flux pourrait avoir un impact significatif sur l\u2019approvisionnement allemand, et potentiellement fragiliser la posture de l\u2019OTAN sur le flanc Est de l\u2019Europe.<\/p>\n","protected":false},"author":2622,"featured_media":329110,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":4,"_lgc_tts_audio_url":"","_lgc_tts_voice":"","_lgc_tts_publish":false,"_lgc_tts_history_item_id":"","_lgc_tts_generated_at":"","_lgc_tts_status":"","_lgc_tts_error":"","footnotes":""},"categories":[1730],"tags":[],"staff":[],"editorial_format":[4942],"serie":[],"audience":[],"geo":[1917],"class_list":["post-329108","post","type-post","status-publish","format-standard","hentry","category-energie-et-environnement","editorial_format-actu-breves","geo-europe"],"acf":{"open_in_webview":false,"accent":"default","_thumbnail_id":329110,"excerpt":"\u00c0 partir du 1er mai, la Russie va mettre fin au transport de brut depuis le Kazakhstan vers l\u2019Allemagne via l\u2019ol\u00e9oduc Droujba, qui passe par le territoire russe. \r\n\r\nL\u2019arr\u00eat des flux pourrait avoir un impact significatif sur l\u2019approvisionnement allemand, et potentiellement fragiliser la posture de l\u2019OTAN sur le flanc Est de l\u2019Europe.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Moscou suspend les exportations de p\u00e9trole kazakh vers l\u2019Allemagne<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2026\/04\/22\/suspension-des-exportations-de-petrole-kazakh-par-moscou-quelles-consequences-pour-lallemagne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Moscou suspend les exportations de p\u00e9trole kazakh vers l\u2019Allemagne\" \/>\n<meta property=\"og:description\" content=\"\u00c0 partir du 1er mai, la Russie va mettre fin au transport de brut depuis le Kazakhstan vers l\u2019Allemagne via l\u2019ol\u00e9oduc Droujba, qui passe par le territoire russe.   L\u2019arr\u00eat des flux pourrait avoir un impact significatif sur l\u2019approvisionnement allemand, et potentiellement fragiliser la posture de l\u2019OTAN sur le flanc Est de l\u2019Europe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2026\/04\/22\/suspension-des-exportations-de-petrole-kazakh-par-moscou-quelles-consequences-pour-lallemagne\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-22T16:01:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-22T16:01:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/04\/gc-share-russie-coupe-droujba.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1782\" \/>\n\t<meta property=\"og:image:height\" content=\"998\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marin Saillofest\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/04\/gc-share-russie-coupe-droujba.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marin Saillofest\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/04\/22\/suspension-des-exportations-de-petrole-kazakh-par-moscou-quelles-consequences-pour-lallemagne\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/04\/22\/suspension-des-exportations-de-petrole-kazakh-par-moscou-quelles-consequences-pour-lallemagne\/\",\"name\":\"Moscou suspend les exportations de p\u00e9trole kazakh vers l\u2019Allemagne\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/04\/22\/suspension-des-exportations-de-petrole-kazakh-par-moscou-quelles-consequences-pour-lallemagne\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/04\/22\/suspension-des-exportations-de-petrole-kazakh-par-moscou-quelles-consequences-pour-lallemagne\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/04\/gc-russie-coupe-droujba.jpg\",\"datePublished\":\"2026-04-22T16:01:14+00:00\",\"dateModified\":\"2026-04-22T16:01:17+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/04\/22\/suspension-des-exportations-de-petrole-kazakh-par-moscou-quelles-consequences-pour-lallemagne\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2026\/04\/22\/suspension-des-exportations-de-petrole-kazakh-par-moscou-quelles-consequences-pour-lallemagne\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/04\/22\/suspension-des-exportations-de-petrole-kazakh-par-moscou-quelles-consequences-pour-lallemagne\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/04\/gc-russie-coupe-droujba.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/04\/gc-russie-coupe-droujba.jpg\",\"width\":1774,\"height\":986},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/04\/22\/suspension-des-exportations-de-petrole-kazakh-par-moscou-quelles-consequences-pour-lallemagne\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Suspension des exportations de p\u00e9trole kazakh par Moscou&#160;: quelles cons\u00e9quences pour l\u2019Allemagne&#160;?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833\",\"name\":\"Marin Saillofest\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g\",\"caption\":\"Marin Saillofest\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Moscou suspend les exportations de p\u00e9trole kazakh vers l\u2019Allemagne","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2026\/04\/22\/suspension-des-exportations-de-petrole-kazakh-par-moscou-quelles-consequences-pour-lallemagne\/","og_locale":"fr_FR","og_type":"article","og_title":"Moscou suspend les exportations de p\u00e9trole kazakh vers l\u2019Allemagne","og_description":"\u00c0 partir du 1er mai, la Russie va mettre fin au transport de brut depuis le Kazakhstan vers l\u2019Allemagne via l\u2019ol\u00e9oduc Droujba, qui passe par le territoire russe.   L\u2019arr\u00eat des flux pourrait avoir un impact significatif sur l\u2019approvisionnement allemand, et potentiellement fragiliser la posture de l\u2019OTAN sur le flanc Est de l\u2019Europe.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2026\/04\/22\/suspension-des-exportations-de-petrole-kazakh-par-moscou-quelles-consequences-pour-lallemagne\/","og_site_name":"Le Grand Continent","article_published_time":"2026-04-22T16:01:14+00:00","article_modified_time":"2026-04-22T16:01:17+00:00","og_image":[{"width":1782,"height":998,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/04\/gc-share-russie-coupe-droujba.jpg","type":"image\/jpeg"}],"author":"Marin Saillofest","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/04\/gc-share-russie-coupe-droujba.jpg","twitter_misc":{"\u00c9crit par":"Marin Saillofest","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2026\/04\/22\/suspension-des-exportations-de-petrole-kazakh-par-moscou-quelles-consequences-pour-lallemagne\/","url":"https:\/\/legrandcontinent.eu\/fr\/2026\/04\/22\/suspension-des-exportations-de-petrole-kazakh-par-moscou-quelles-consequences-pour-lallemagne\/","name":"Moscou suspend les exportations de p\u00e9trole kazakh vers l\u2019Allemagne","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2026\/04\/22\/suspension-des-exportations-de-petrole-kazakh-par-moscou-quelles-consequences-pour-lallemagne\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2026\/04\/22\/suspension-des-exportations-de-petrole-kazakh-par-moscou-quelles-consequences-pour-lallemagne\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/04\/gc-russie-coupe-droujba.jpg","datePublished":"2026-04-22T16:01:14+00:00","dateModified":"2026-04-22T16:01:17+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2026\/04\/22\/suspension-des-exportations-de-petrole-kazakh-par-moscou-quelles-consequences-pour-lallemagne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2026\/04\/22\/suspension-des-exportations-de-petrole-kazakh-par-moscou-quelles-consequences-pour-lallemagne\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2026\/04\/22\/suspension-des-exportations-de-petrole-kazakh-par-moscou-quelles-consequences-pour-lallemagne\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/04\/gc-russie-coupe-droujba.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/04\/gc-russie-coupe-droujba.jpg","width":1774,"height":986},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2026\/04\/22\/suspension-des-exportations-de-petrole-kazakh-par-moscou-quelles-consequences-pour-lallemagne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Suspension des exportations de p\u00e9trole kazakh par Moscou&#160;: quelles cons\u00e9quences pour l\u2019Allemagne&#160;?"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833","name":"Marin Saillofest","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g","caption":"Marin Saillofest"}}]}},"lgc_categories":[{"id":1730,"name":"\u00c9nergie et environnement","slug":"energie-et-environnement"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/04\/gc-russie-coupe-droujba.jpg","width":1774,"height":986,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/329108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/2622"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=329108"}],"version-history":[{"count":3,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/329108\/revisions"}],"predecessor-version":[{"id":329121,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/329108\/revisions\/329121"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/329110"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=329108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=329108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=329108"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=329108"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=329108"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=329108"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=329108"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=329108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}