{"id":321336,"date":"2026-03-10T19:00:00","date_gmt":"2026-03-10T18:00:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=321336"},"modified":"2026-04-14T09:40:56","modified_gmt":"2026-04-14T07:40:56","slug":"conversation-hartmut-rosa","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2026\/03\/10\/conversation-hartmut-rosa\/","title":{"rendered":"Comment reprendre le contr\u00f4le&#160;? Se panser dans la violence du monde avec Hartmut Rosa"},"content":{"rendered":"\n<p class=\"non-subscribers-only\"><em>Si vous nous lisez et que vous souhaitez soutenir une r\u00e9daction jeune et ind\u00e9pendante, d\u00e9couvrez <a href=\"https:\/\/legrandcontinent.eu\/fr\/offre-abonnement\/\" target=\"_blank\" rel=\"noreferrer noopener\">toutes nos offres pour s&rsquo;abonner au Grand Continent<\/a><\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Dans votre dernier ouvrage, vous soutenez que la modernit\u00e9 a chang\u00e9 notre mani\u00e8re de r\u00e9soudre des probl\u00e8mes quotidiens&#160;: si nous avons gagn\u00e9 \u00e0 la pr\u00e9visibilit\u00e9 que donne le respect des proc\u00e9dures, nous en souffririons aussi. En quoi avons-nous chang\u00e9&#160;?<\/h3>\n\n\n\n<p>La mani\u00e8re dont nous sommes dans le monde, dont nous agissons et interagissons, \u00e9volue de mani\u00e8re subtile \u2014 de sorte que nous ne sommes souvent pas conscients de ce changement.&nbsp;<\/p>\n\n\n\n<p>La th\u00e8se principale de mon livre est que nous sommes aujourd\u2019hui pass\u00e9s de l&rsquo;action \u00e0 l&rsquo;ex\u00e9cution. Aujourd\u2019hui, le sens du jugement, c&rsquo;est-\u00e0-dire la mani\u00e8re d&rsquo;agir face \u00e0 une situation donn\u00e9e, est en partie remplac\u00e9 par des r\u00e8gles m\u00e9caniques, bureaucratiques et abstraites que j&rsquo;appelle <em>constellation<\/em> et oppose \u00e0 la <em>situation<\/em>, en reprenant une distinction de Hermann Schmitz&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-321336' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2026\/03\/10\/conversation-hartmut-rosa\/#easy-footnote-bottom-1-321336' title='Hermann Schmitz, &lt;em&gt;Situationen und Konstellationen&amp;#160;: Wider die Ideologie totaler Vernetzung, &lt;\/em&gt;Freiburg\/Br. Alber, 2005.'><sup>1<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n\n\n<figure class=\"wp-block-image wp-block-image-small\"\n    data-shadow=\"false\"\n    data-use-original-file=\"false\">\n    <a\n        data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/03\/situation-und-konstellation-epub-hartmut-rosa.jpeg\"\n        class=\"inline-block gallery-item no-underline \"\n        data-pswp-width=\"1223\"\n        data-pswp-height=\"2000\">\n                                        <picture>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/03\/situation-und-konstellation-epub-hartmut-rosa-125x204.jpeg\"\r\n                media=\"(max-width: 374px)\" \/>\r\n                    <source\r\n                srcset=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/03\/situation-und-konstellation-epub-hartmut-rosa-330x540.jpeg\"\r\n                media=\"(min-width: 375px)\" \/>\r\n                <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/03\/situation-und-konstellation-epub-hartmut-rosa-125x204.jpeg\" \/>\r\n        <\/picture>\r\n                            \n                    <figcaption class=\"pswp-caption-content \">Hartmut Rosa, \u00ab&#160;&#160;Situation und Konstellation&#160;&#160;\u00bb, Suhrkamp, 2025.<\/figcaption>\n            <\/a>\n<\/figure>\n\n\n<h3 class=\"wp-block-heading\">Qu&rsquo;entendez-vous par l\u00e0&#160;?<\/h3>\n\n\n\n<p>Je donnerais un exemple de ce glissement. Avec deux coll\u00e8gues, j&rsquo;ai examin\u00e9 les raisons pour lesquelles le football est si attractif. Dans ce contexte, nous nous sommes int\u00e9ress\u00e9s \u00e0 l&rsquo;assistance vid\u00e9o \u00e0 l\u2019arbitrage (VAR) et avons r\u00e9dig\u00e9 un essai sur le sujet, en nous appuyant sur cette distinction entre situation et constellation.<\/p>\n\n\n\n<p>La mani\u00e8re dont un arbitre de football dirige le match d\u00e9pend de sa personnalit\u00e9. Il peut r\u00e9agir, se montrer intransigeant ou plus tol\u00e9rant. L&rsquo;action et le jugement situationnel sont toujours li\u00e9s.<\/p>\n\n\n\n<p>Dans le football, le fait qu&rsquo;un hors-jeu soit signal\u00e9 ou non d\u00e9pend de nombreux facteurs&#160;: la situation actuelle, le d\u00e9but ou la fin du match, mais aussi les spectateurs. Autrefois, on utilisait par exemple la notion de \u00ab&#160;m\u00eame hauteur&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-321336' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2026\/03\/10\/conversation-hartmut-rosa\/#easy-footnote-bottom-2-321336' title='Un joueur n\u2019est ainsi pas hors-jeu s\u2019il se trouve \u00e0 la m\u00eame hauteur que l\u2019avant-dernier adversaire, ou \u00e0 la m\u00eame hauteur que les deux derniers d\u00e9fenseurs.'><sup>2<\/sup><\/a><\/span><\/span>. L&rsquo;arbitre disposait alors d&rsquo;une certaine marge de man\u0153uvre pour prendre sa d\u00e9cision.<\/p>\n\n\n\n<p>Aujourd&rsquo;hui, la ligne trac\u00e9e par l\u2019assistance vid\u00e9o est utilis\u00e9e dans les cas d\u2019arbitrage. La <em>situation<\/em> n&rsquo;a donc plus aucune importance, pas plus que le fait que l&rsquo;arbitre ait d\u00e9j\u00e0 pris trois d\u00e9cisions en faveur d&rsquo;une \u00e9quipe. Il n&rsquo;y a plus qu&rsquo;une seule base de d\u00e9cision&#160;: cette ligne trac\u00e9e.<\/p>\n\n\n\n<p>La semaine derni\u00e8re, j&rsquo;ai discut\u00e9 avec des arbitres amateurs qui m&rsquo;ont dit qu&rsquo;ils avaient tendance \u00e0 ne pas signaler les petits hors-jeux lorsque le score est de 5-0 en faveur d&rsquo;une \u00e9quipe et que l&rsquo;autre attaque, afin de rendre le jeu un peu plus \u00e9quilibr\u00e9. La justice situationnelle est donc diff\u00e9rente de la justice constellative.<\/p>\n\n\n\n<p>C&rsquo;est ainsi que j&rsquo;en suis venu \u00e0 cette distinction entre situation et constellation. J&rsquo;ai ensuite constat\u00e9 qu&rsquo;elle s&rsquo;appliquait \u00e0 tous les domaines de la vie dans lesquels nous agissons.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Le syst\u00e8me capitaliste ne pourra changer que si nous, citoyens, nous consid\u00e9rons \u00e0 nouveau comme des acteurs et r\u00e9clamons des marges de man\u0153uvre.<\/p><cite>Hartmut Rosa<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Qu\u2019avons-nous perdu \u00e0 cette nouvelle approche&#160;?<\/h3>\n\n\n\n<p>Agir signifie que nous nous trouvons dans une situation et que nous essayons d&rsquo;y trouver la bonne fa\u00e7on d&rsquo;agir, avec discernement, tact et sur la base de notre exp\u00e9rience. L&rsquo;action et la situation s&rsquo;influencent toujours mutuellement. J&rsquo;ai toutefois remarqu\u00e9 que dans presque tout ce que nous faisons, nous passons d\u00e9sormais de ce type d&rsquo;action \u2014 une r\u00e9action \u00e0 des situations \u2014 \u00e0 une ex\u00e9cution \u2014 c&rsquo;est-\u00e0-dire finalement \u00e0 la mise en \u0153uvre de programmes.&nbsp;<\/p>\n\n\n\n<p>Voici un autre exemple tir\u00e9 de mon livre qui ne concerne ni la morale ni la bureaucratie&#160;: pour pr\u00e9parer un caf\u00e9 filtre, il faut faire preuve de doigt\u00e9 et de discernement. Si l&rsquo;on n&rsquo;en a jamais pr\u00e9par\u00e9, on ne sait pas combien de cuill\u00e8res de caf\u00e9 il faut mettre&#160;; si l&rsquo;on en pr\u00e9pare souvent, cela d\u00e9pend de l&rsquo;humeur du moment. Si l&rsquo;on souhaite \u00eatre en pleine forme et que l&rsquo;on a l&rsquo;impression de s&rsquo;\u00eatre couch\u00e9 tard la veille, on en ajoute une de plus. Si l&rsquo;on a l&rsquo;impression que sa tension art\u00e9rielle est d\u00e9j\u00e0 trop \u00e9lev\u00e9e, on en ajoute une de moins. Selon les personnes qui partagent le caf\u00e9, on le pr\u00e9pare plus ou moins fort.<\/p>\n\n\n\n<p>Le caf\u00e9 est ainsi adapt\u00e9 \u00e0 la situation et \u00e0 la personne. Lorsque les enfants viennent prendre leur petit-d\u00e9jeuner, ils peuvent reconna\u00eetre si c&rsquo;est leur m\u00e8re ou leur p\u00e8re qui a pr\u00e9par\u00e9 le caf\u00e9. Aujourd&rsquo;hui, il suffit d&rsquo;ins\u00e9rer les capsules dans la machine pour obtenir un caf\u00e9 toujours identique, peu importe qui le pr\u00e9pare et dans quelle situation.<\/p>\n\n\n\n<p>Il s&rsquo;agit d&rsquo;un exemple tout \u00e0 fait anodin, mais ce ph\u00e9nom\u00e8ne s&rsquo;\u00e9tend \u00e0 tous les domaines de la vie. Pour reprendre mon premier exemple, l&rsquo;arbitre est d\u00e9sormais assist\u00e9 par un assistant vid\u00e9o qui peut d\u00e9terminer avec une pr\u00e9cision de l&rsquo;ordre du centi\u00e8me de millim\u00e8tre si un joueur est hors-jeu ou non&#160;: l&rsquo;action avec discernement et doigt\u00e9 dispara\u00eet ainsi.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Vous mentionniez les travaux d\u2019Hermann Schmitz. Vos travaux doivent \u00e9galement beaucoup \u00e0 la th\u00e9orie critique&#160;: dans le cadre du travail de ce livre, comment articulez-vous ces diff\u00e9rents bagages th\u00e9oriques&#160;?<\/h3>\n\n\n\n<p>La distinction entre situation et constellation provient, comme je l&rsquo;ai mentionn\u00e9, de Hermann Schmitz, le fondateur de la nouvelle ph\u00e9nom\u00e9nologie. M\u00eame si celle-ci me semble parfois quelque peu sectaire et si je ne partage pas tout ce que Schmitz \u00e9crit \u00e0 ce sujet, il a \u00e9t\u00e9 une source d&rsquo;inspiration importante pour moi pour ces deux concepts.<\/p>\n\n\n\n<p>Cela peut \u00eatre quelque peu probl\u00e9matique, car la th\u00e9orie critique constitue un contexte important pour moi&#160;: j\u2019en suis issu. Walter Benjamin, Theodor W. Adorno et la tradition de la th\u00e9orie critique dans son ensemble m&rsquo;accompagnent en fait toujours et m&rsquo;ont fortement inspir\u00e9, mais pas en ce qui concerne cette distinction sp\u00e9cifique.&nbsp;<\/p>\n\n\n\n<p>Chez Walter Benjamin et Theodor W. Adorno, le terme \u00ab&#160;constellation&#160;\u00bb est utilis\u00e9 dans un autre sens, presque comme je comprends le terme \u00ab&#160;situation&#160;\u00bb, c&rsquo;est-\u00e0-dire comme l&rsquo;apparition de quelque chose entre les points constellatifs. Cela est bien s\u00fbr \u00e9galement possible.&nbsp;<\/p>\n\n\n\n<p>En passant par Kant, je suis m\u00eame remont\u00e9 jusqu&rsquo;\u00e0 Aristote qui fait une distinction particuli\u00e8rement int\u00e9ressante entre justice et \u00e9quit\u00e9&#160;: la justice, c&rsquo;est la r\u00e8gle abstraite, la loi, et l&rsquo;\u00e9quit\u00e9, c&rsquo;est ce qui est appropri\u00e9 \u00e0 la situation donn\u00e9e. Nous constatons ainsi que la r\u00e8gle ne devrait pas \u00eatre une r\u00e8gle.<\/p>\n\n\n\n<p>Cette id\u00e9e m&rsquo;a toujours guid\u00e9. En tant qu&rsquo;enseignant ou directeur d&rsquo;acad\u00e9mie, je m&rsquo;oppose toujours \u00e0 l&rsquo;expression \u00ab&#160;une r\u00e8gle est une r\u00e8gle&#160;\u00bb. Chaque situation est diff\u00e9rente et il y a une diff\u00e9rence entre rendre justice \u00e0 une situation ou \u00e0 une personne et appliquer une r\u00e8gle. On peut le constater chez Hannah Arendt, Kant et Aristote.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Le passage du r\u00f4le d&rsquo;acteur \u00e0 celui d&rsquo;ex\u00e9cutant est-il principalement observable dans nos soci\u00e9t\u00e9s occidentales&#160;? Ou s&rsquo;agit-il d&rsquo;un ph\u00e9nom\u00e8ne universel&#160;?<\/h3>\n\n\n\n<p>L&rsquo;acc\u00e8s \u00e0 la situation par le biais d&rsquo;une approche constellative est une tendance de la modernit\u00e9 occidentale, qui s&rsquo;est ensuite r\u00e9pandue dans le monde entier.&nbsp;<\/p>\n\n\n\n<p>Deux ph\u00e9nom\u00e8nes renforcent cette tendance&#160;: d&rsquo;une part, les r\u00e8gles et lois bureaucratiques, qui ont d&rsquo;ailleurs \u00e9galement un potentiel \u00e9mancipateur, garantissent l&rsquo;\u00e9galit\u00e9 de traitement, en \u00e9liminant la corruption et en pr\u00e9venant la discrimination. D&rsquo;autre part, la technique nous permet de traiter les choses. En d&rsquo;autres termes, l&rsquo;approche constellative rend le monde accessible.<\/p>\n\n\n\n<p>La mise \u00e0 disposition de ce monde est li\u00e9e au programme occidental de modernisation, mais elle s&rsquo;est aujourd&rsquo;hui \u00e9tendue \u00e0 l&rsquo;\u00e9chelle mondiale. Cependant, dans les cultures et les pays du \u00ab&#160;Sud global&#160;\u00bb, comme on les appelle parfois de mani\u00e8re simpliste, la conscience traditionnelle que la vie est plus riche que la solution constellative est encore aujourd&rsquo;hui plus aigu\u00eb.<\/p>\n\n\n\n<p>C&rsquo;est la raison pour laquelle, dans le dernier chapitre du livre, j&rsquo;ai utilis\u00e9 deux termes issus du \u00ab&#160;Sud global&#160;\u00bb, \u00e0 savoir le <em>jeitinho<\/em> br\u00e9silien et le <em>jugaad<\/em> indien. Le <em>jeitinho<\/em> d\u00e9signe une sorte de vertu ou d&rsquo;art de vivre, et signifie \u00ab&#160;le petit chemin&#160;\u00bb. Il s&rsquo;agit de trouver la bonne r\u00e9ponse \u00e0 des situations, m\u00eame en l&rsquo;absence de moyens techniques ou de r\u00e8gles bureaucratiques, et de cr\u00e9er ainsi l&rsquo;\u00e9quit\u00e9, selon Aristote. Dans la tradition hindoue, cela s&rsquo;appelle <em>jugaad<\/em>.<\/p>\n\n\n\n<p>Dans la modernit\u00e9 occidentale, nous n&rsquo;avons plus vraiment de termes pour cela, car nous consid\u00e9rons que si quelque chose n&rsquo;est pas techniquement et bureaucratiquement correct, il s&rsquo;agit d&rsquo;une erreur ou d&rsquo;une omission que nous devons corriger. C&rsquo;est l\u00e0 que r\u00e9side le v\u00e9ritable probl\u00e8me fondamental de notre soci\u00e9t\u00e9, qui se manifeste d&rsquo;ailleurs dans le probl\u00e8me de la bureaucratie.<\/p>\n\n\n\n<p>Je ne pr\u00e9tends pas que la bureaucratie soit toujours mauvaise. Le probl\u00e8me est toutefois que les situations de la vie d\u00e9passent toujours ce qui peut \u00eatre r\u00e9glement\u00e9. C&rsquo;est pourquoi il faut toujours une r\u00e8gle suppl\u00e9mentaire pour tenir compte des changements de situation, des situations nouvelles ou particuli\u00e8res. C&rsquo;est la raison pour laquelle les bureaucraties se d\u00e9veloppent de mani\u00e8re excessive dans le monde occidental.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La pression capitaliste en faveur de la croissance nous pousse donc \u00e0 essayer d&rsquo;optimiser notre vie de mani\u00e8re param\u00e9trique.<\/p><cite>Hartmut Rosa<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Quelle place accordez-vous aux progr\u00e8s technologiques, et plus pr\u00e9cis\u00e9ment \u00e0 l&rsquo;intelligence artificielle, dans cette \u00e9volution&#160;?<\/h3>\n\n\n\n<p>L&rsquo;intelligence artificielle est un excellent exemple de notre volont\u00e9 constante d&rsquo;optimiser le rendement et le r\u00e9sultat de nos actions. Elle montre \u00e9galement comment notre fa\u00e7on d&rsquo;\u00eatre au monde \u00e9volue.<\/p>\n\n\n\n<p>On peut le comprendre de mani\u00e8re tr\u00e8s concr\u00e8te \u00e0 travers la fa\u00e7on dont nous nous orientons dans une ville. Imaginons que nous arrivions dans une nouvelle ville, comme Bruxelles, Rome, Paris ou Berlin. Il est naturel pour l&rsquo;\u00eatre humain de vouloir se familiariser avec le lieu o\u00f9 il se trouve.<\/p>\n\n\n\n<p>Apr\u00e8s quelques heures, on d\u00e9veloppe une sorte de perception de la ville&#160;: on sait d\u00e9j\u00e0 o\u00f9 coule le fleuve, si l&rsquo;on se trouve au nord ou au sud de celui-ci, ou encore o\u00f9 se trouve le ch\u00e2teau. On s&rsquo;oriente entre le fleuve et le ch\u00e2teau, et l&rsquo;on sait que la cath\u00e9drale se trouve au centre, \u00e0 gauche.<\/p>\n\n\n\n<p>En parcourant la ville, on acquiert une perception de la mani\u00e8re dont on se d\u00e9place dans cet espace, dans cette situation. Aujourd&rsquo;hui, nous nous orientons avec Google Maps, et c&rsquo;est une action constellative&#160;: tout en empruntant un itin\u00e9raire \u2014 100 m\u00e8tres \u00e0 gauche, puis imm\u00e9diatement \u00e0 droite, puis sur le pont \u2014 nous n\u2019avons aucune id\u00e9e de l&rsquo;endroit o\u00f9 l&rsquo;on se trouve. Cet exemple trahit un changement notre mani\u00e8re d&rsquo;\u00eatre dans le monde et de se d\u00e9placer dans celui-ci.<\/p>\n\n\n\n<p>Ma th\u00e8se est la suivante&#160;: l&rsquo;intelligence artificielle intensifie l&rsquo;acc\u00e8s constellatif au monde, mais elle comporte le risque que nous n&rsquo;am\u00e9liorions plus nos actions. \u00c0 cet \u00e9gard, je tiens \u00e0 souligner une fois de plus que, par le biais de r\u00e8gles bureaucratiques, d&rsquo;instruments techniques et de technologies, nous avons cherch\u00e9 \u00e0 accro\u00eetre notre capacit\u00e9 d&rsquo;action, mais aussi \u00e0 garantir et \u00e0 cr\u00e9er des marges de man\u0153uvre dans lesquelles nous pouvons agir. Or, nous en sommes d\u00e9sormais arriv\u00e9s \u00e0 un point o\u00f9 l&rsquo;IA agit \u00e0 notre place. Nous rempla\u00e7ons ainsi l&rsquo;action par la technologie.<\/p>\n\n\n\n<p>L&rsquo;IA peut composer des morceaux de musique \u00e0 notre place&#160;: \u00e0 la fin, on peut encore pr\u00e9ciser si l&rsquo;on souhaite un tempo plus lent ou une forme plus classique. Nous constatons ainsi que le morceau de musique n&rsquo;est plus une forme d&rsquo;action, mais quelque chose qui nous est pr\u00e9sent\u00e9 et qui peut ensuite \u00eatre jug\u00e9, \u00e9valu\u00e9 et modifi\u00e9.<\/p>\n\n\n\n<p>L&rsquo;une de mes convictions principales est que la diff\u00e9rence entre agir et ex\u00e9cuter r\u00e9side dans le fait que nous sommes toujours ancr\u00e9s dans des situations. Celle-ci \u00e9volue constamment en fonction de nos actions et les influence en retour. En revanche, dans la constellation du monde, nous sommes toujours confront\u00e9s&#160;: cette constellation agit sur nous et nous r\u00e9agissons ensuite. L\u2019ordre chronologique n\u2019est pas direct.<\/p>\n\n\n\n<p>Le hors-jeu au football est int\u00e9ressant \u00e0 cet \u00e9gard. Lorsqu\u2019il doit prendre une d\u00e9cision, l\u2019arbitre consulte une image vid\u00e9o enregistr\u00e9e il y a une ou trois minutes, l&rsquo;\u00e9value, puis passe \u00e0 autre chose. Agir de mani\u00e8re constellative revient en fait toujours \u00e0 s&rsquo;arr\u00eater dans le monde, \u00e0 sortir de la situation.<\/p>\n\n\n\n<p>L&rsquo;IA modifie ainsi notre mani\u00e8re d&rsquo;\u00eatre au monde, que ce soit pour cuisiner, faire de la musique, peindre, raconter des histoires, naviguer ou faire de l&rsquo;astronomie&#160;: elle nous pr\u00e9sente le monde comme un vis-\u00e0-vis dans lequel nous ne sommes plus ancr\u00e9s.<\/p>\n\n\n\n<p>Ma pr\u00e9occupation concernant l&rsquo;IA est qu&rsquo;elle ne nous permet pas d&rsquo;am\u00e9liorer notre capacit\u00e9 d&rsquo;action dans le monde, mais qu&rsquo;elle la remplace par une ex\u00e9cution artificielle. Cela rend l&rsquo;existence humaine dans le monde difficile. Selon moi, c&rsquo;est l&rsquo;une des raisons pour lesquelles le burn-out et la solitude sont en augmentation.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Pourquoi&#160;?&nbsp;<\/h3>\n\n\n\n<p>La sociologue Eva Illouz m&rsquo;a fait prendre conscience d\u2019un possible lien&#160;: elle \u00e9crit que les \u00e9motions nous fournissent l&rsquo;\u00e9nergie n\u00e9cessaire pour agir, ce qui me para\u00eet tout \u00e0 fait plausible&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-321336' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2026\/03\/10\/conversation-hartmut-rosa\/#easy-footnote-bottom-3-321336' title='Eva Illouz, &lt;em&gt;Les \u00c9motions contre la d\u00e9mocratie&lt;\/em&gt;, trad. Fr\u00e9d\u00e9ric Joly, Paris, Premier Parall\u00e8le, 2022.'><sup>3<\/sup><\/a><\/span><\/span>. Le sociologue allemand Hans Joas et toute la tradition du pragmatisme ont \u00e9galement abond\u00e9 dans ce sens. Selon eux, agir ne consiste pas \u00e0 mettre en \u0153uvre un programme dans le monde, mais \u00e0 r\u00e9pondre et \u00e0 r\u00e9agir \u00e0 une situation.<\/p>\n\n\n\n<p>Lorsque vous voyez une personne allong\u00e9e dans la rue ou que vos parents \u00e2g\u00e9s ne peuvent plus subvenir \u00e0 leurs besoins chez eux, par exemple vous r\u00e9agissez \u00e9motionnellement. Vous identifiez le d\u00e9fi, essayez d&rsquo;aider, d&rsquo;agir et d&rsquo;intervenir. Au contraire, nous constatons que l&rsquo;ex\u00e9cution et la logique ex\u00e9cutive neutralisent compl\u00e8tement nos \u00e9motions&#160;: elles font que nous n\u2019agissons plus en fonction de nos sentiments, mais selon un programme, une r\u00e8gle ou des directives.&nbsp;<\/p>\n\n\n\n<p>Dans mon livre, je pr\u00e9sente toute une s\u00e9rie d&rsquo;exemples \u00e0 ce sujet. Les enseignants qui disposent d&rsquo;un catalogue de crit\u00e8res abstraits pour attribuer les notes peuvent parfois avoir le sentiment qu&rsquo;une bonne note serait importante pour encourager certains \u00e9l\u00e8ves, voire pourrait changer leur vie \u2014 selon les crit\u00e8res pourtant, cela n&rsquo;est pas possible. L&rsquo;enseignant se voit donc contraint d&rsquo;en attribuer une mauvaise.&nbsp;<\/p>\n\n\n\n<p>Il en va de m\u00eame pour l&rsquo;arbitre qui, au vu du d\u00e9roulement d\u2019un match, estimerait juste de ne pas signaler un l\u00e9ger hors-jeu en faveur de l&rsquo;\u00e9quipe A, pr\u00e9cis\u00e9ment parce qu&rsquo;il a d\u00e9j\u00e0 arbitr\u00e9 trois fois, lors de situations critiques, en faveur de l&rsquo;\u00e9quipe B. Selon la logique de l&rsquo;ex\u00e9cution constellative, un tel comportement n&rsquo;est pas non plus possible. Les \u00e9motions et la capacit\u00e9 de jugement n&rsquo;ont aucune importance&#160;; elles doivent \u00eatre ignor\u00e9es, voire contrari\u00e9es.<\/p>\n\n\n\n<p>C&rsquo;est pour cette raison que j&rsquo;affirme que nous coupons le lien entre l&rsquo;\u00e9motion et l&rsquo;action, m\u00eame lorsque nous pr\u00e9parons le caf\u00e9 le matin. Si je suis fatigu\u00e9 et que je mets une cuill\u00e8re de caf\u00e9 en plus dans le filtre, les \u00e9motions influencent directement l&rsquo;action. Avec la capsule, l&rsquo;\u00e9motion est mise en veille et je dois m\u00eame agir \u00e0 son encontre.<\/p>\n\n\n\n<p>Agir contre l&rsquo;\u00e9motion ou sans l&rsquo;\u00e9motion nous prive de notre pouvoir d&rsquo;action et entra\u00eene une perte d&rsquo;\u00e9nergie, voire un burn-out. Cependant, nous restons des \u00eatres affectifs, et les affects s&rsquo;accumulent alors, pouvant se transformer en col\u00e8re politique ou, sous un angle positif, en explosions d&rsquo;euphorie lors de matchs de football ou de concerts de rock.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La mise \u00e0 disposition du monde est li\u00e9e au programme occidental de modernisation, mais elle s&rsquo;est aujourd&rsquo;hui \u00e9tendue \u00e0 l&rsquo;\u00e9chelle mondiale.<\/p><cite>Hartmut Rosa<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Quelles sont les raisons qui expliquent le recul de l&rsquo;action au profit de l&rsquo;ex\u00e9cution&#160;? Pourquoi cette seconde approche s\u00e9duit-elle&#160;?<\/h3>\n\n\n\n<p>La situation est en partie attribuable \u00e0 la logique capitaliste et \u00e0 la qu\u00eate incessante de croissance de la modernit\u00e9, que j&rsquo;ai tent\u00e9 de mettre en \u00e9vidence dans mes pr\u00e9c\u00e9dents \u00e9crits. Partout o\u00f9 nous sommes confront\u00e9s \u00e0 la r\u00e9alit\u00e9 du capitalisme mondial, nous sommes constamment contraints de pr\u00e9server le statu quo, qu&rsquo;il s&rsquo;agisse des emplois, du syst\u00e8me de sant\u00e9, du syst\u00e8me de retraite, etc., par l&rsquo;acc\u00e9l\u00e9ration, la croissance et l&rsquo;innovation. \u00c0 partir d&rsquo;un certain point, la croissance n&rsquo;est plus possible que par une d\u00e9composition param\u00e9trique.<\/p>\n\n\n\n<p>Selon l&rsquo;ancien principe du taylorisme appliqu\u00e9 aux cha\u00eenes de montage, si le processus doit \u00eatre optimis\u00e9 au-del\u00e0 d&rsquo;un certain niveau, il faut le d\u00e9composer en ses diff\u00e9rents \u00e9l\u00e9ments afin d&rsquo;am\u00e9liorer chaque mouvement individuel. La pression capitaliste en faveur de la croissance nous pousse donc \u00e0 essayer d&rsquo;optimiser notre vie de mani\u00e8re param\u00e9trique. Nous commen\u00e7ons donc par la d\u00e9composer en param\u00e8tres individuels.<\/p>\n\n\n\n<p>Prenons l&rsquo;exemple de la sant\u00e9&#160;: nous pouvons mesurer la dur\u00e9e de notre sommeil, la profondeur de la phase REM, la dur\u00e9e du sommeil profond, le nombre de pas effectu\u00e9s dans la journ\u00e9e ou encore le nombre de calories consomm\u00e9es et br\u00fbl\u00e9es. Il s&rsquo;agit l\u00e0 de param\u00e8tres individuels qui doivent \u00eatre trait\u00e9s dans leur ensemble&#160;: il est possible d&rsquo;am\u00e9liorer le taux de m\u00e9latonine, de s\u00e9rotonine, d&rsquo;insuline, etc.<\/p>\n\n\n\n<p>La logique d&rsquo;optimisation et d&rsquo;am\u00e9lioration de la modernit\u00e9 est donc un facteur moteur central. Cependant, il en existe un deuxi\u00e8me facteur que j\u2019ai bri\u00e8vement mentionn\u00e9 que je tiens \u00e0 souligner&#160;: l\u2019approche constellative est \u00e9galement un projet \u00e9mancipateur. Avec le sociologue Georg Simmel, je dirais que la fixation bureaucratique et constellative des horaires de travail, des temps de repos et des mesures de protection fait \u00e9galement partie d&rsquo;un projet visant \u00e0 garantir l&rsquo;\u00e9galit\u00e9 de traitement. La corruption directe est l&rsquo;un des probl\u00e8mes qui obligent \u00e0 \u00e9tablir des constellations, \u00e0 surveiller, ou du moins \u00e0 r\u00e9glementer clairement les m\u00e9canismes subtils de favoritisme ou de discrimination. Sans une telle approche, les gar\u00e7ons obtiendraient \u00e0 nouveau des notes l\u00e9g\u00e8rement meilleures que les filles, ou bien les natifs auraient plus de chances d&rsquo;obtenir de l\u2019\u00c9tat une autorisation qui serait refus\u00e9e aux migrants.&nbsp;<\/p>\n\n\n\n<p>Je ne pr\u00e9tends donc pas dans mon livre que l&rsquo;approche constellative est toujours inappropri\u00e9e. Si je souhaite intervenir dans le monde ou prendre le contr\u00f4le d&rsquo;une situation, il est \u00e9vident que je dois d&rsquo;abord la d\u00e9composer en ses \u00e9l\u00e9ments constitutifs.<\/p>\n\n\n\n<p>La sant\u00e9, un ph\u00e9nom\u00e8ne particuli\u00e8rement complexe, en est un bon exemple. Il existe de nombreuses r\u00e9ponses possibles \u00e0 la question de savoir si l&rsquo;on est en bonne sant\u00e9. La m\u00e9decine a acquis sa puissance et son utilit\u00e9 gr\u00e2ce aux connaissances acquises gr\u00e2ce \u00e0 l&rsquo;approche constellative.<\/p>\n\n\n\n<p>L&rsquo;une des nombreuses constellations, que j&rsquo;appelle \u00e9galement param\u00e8tres, est par exemple la pression art\u00e9rielle. \u00c0 l&rsquo;h\u00f4pital, on mesure les valeurs sanguines, les valeurs h\u00e9patiques, le taux de s\u00e9rotonine, de m\u00e9latonine, ou encore le type d&rsquo;allergie \u00e0 une substance donn\u00e9e. Il s&rsquo;agit l\u00e0 de constatations qui peuvent ensuite \u00eatre trait\u00e9es de mani\u00e8re cibl\u00e9e et sur lesquelles on peut exercer une influence. Il est donc tout d&rsquo;abord logique d&rsquo;essayer cette approche. N\u00e9anmoins, cet acc\u00e8s constellatif s&rsquo;av\u00e8re \u00eatre en augmentation significative.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Dans cette param\u00e9trisation faite de la vie, quel soup\u00e7on p\u00e8se sur ce qui \u00e9chappe \u00e0 l\u2019optimisation et pourrait constituer une marge de man\u0153uvre&#160;?<\/h3>\n\n\n\n<p>Je r\u00e9pondrai \u00e0 cette question \u00e0 partir d\u2019un exemple important. Actuellement, les m\u00e9decins et les enseignants du monde entier sont tr\u00e8s pr\u00e9occup\u00e9s par l&rsquo;\u00e9tat de sant\u00e9 mentale des jeunes, souvent catastrophique. Jonathan Haidt, l&rsquo;auteur de <em>The Anxious Generation<\/em>, m&rsquo;a inspir\u00e9 cette id\u00e9e d\u2019une \u00ab&#160;herm\u00e9neutique du soup\u00e7on&#160;\u00bb&#160;: selon lui, ce sont les r\u00e9seaux sociaux et la num\u00e9risation qui en seraient responsables, ainsi que ce qu&rsquo;il appelle le <em>safetyism<\/em>.<\/p>\n\n\n\n<p>D\u2019apr\u00e8s ce que rapporte Haidt, au XIXe et au XXe si\u00e8cle, les parents laissaient leurs enfants jouer dehors et comptaient sur la pr\u00e9sence d&rsquo;un adulte pour les aider s&rsquo;ils rencontraient des difficult\u00e9s. S&rsquo;ils allaient ensuite trop loin ou faisaient des choses qu&rsquo;ils n&rsquo;auraient pas d\u00fb faire, un adulte les r\u00e9primandait et leur imposait des limites, mais cela venait <em>a posteriori<\/em>. En cons\u00e9quence, libres de se retrouver dans la rue, les enfants d\u00e9veloppaient leurs propres r\u00e8gles et leur sens du jugement, comme ils devaient apprendre \u00e0 g\u00e9rer les conflits&#160;: puis-je jouer avec ces gar\u00e7ons plus \u00e2g\u00e9s, ou sont-ils dangereux&#160;? Puis-je me laisser entra\u00eener dans cette situation&#160;?<\/p>\n\n\n\n<p>Aujourd&rsquo;hui, les parents, en particulier ceux de la classe moyenne mais pas seulement, essaient de donner \u00e0 leurs enfants des espaces bien d\u00e9finis dans lesquels ils font des choses bien d\u00e9finies, sont confront\u00e9s \u00e0 des r\u00e8gles bien d\u00e9finies et suivent des programmes de r\u00e9solution de conflits bien d\u00e9finis. Cela ne signifie pas que les enfants n&rsquo;ont plus de marge de man\u0153uvre, mais leur jeu a chang\u00e9. D\u00e9sormais, nous partons du principe que les adultes qui entrent en contact avec des enfants sont susceptibles de leur faire du mal ou d\u2019abuser d\u2019eux \u2014 notamment en ligne. Haidt d\u00e9crit ainsi comment l&rsquo;image de l&rsquo;adulte en contact avec un enfant est pass\u00e9e d&rsquo;une herm\u00e9neutique de la confiance \u00e0 une herm\u00e9neutique du soup\u00e7on.<\/p>\n\n\n\n<p>Apr\u00e8s avoir lu Haidt, j\u2019ai remarqu\u00e9 que ce ph\u00e9nom\u00e8ne \u00e9tait en r\u00e9alit\u00e9 tr\u00e8s r\u00e9pandu. Il appara\u00eet \u00e9galement dans le domaine des soins, o\u00f9 l\u2019herm\u00e9neutique du soup\u00e7on s\u2019est aussi install\u00e9e. Soigner signifie toujours se retrouver dans une situation qui nous met au d\u00e9fi de mani\u00e8re impr\u00e9visible&#160;: sans r\u00e8gles claires et sans contr\u00f4le pr\u00e9cis, il est sugg\u00e9r\u00e9 que les soignants ne font rien, facturent des montants \u00e9lev\u00e9s ou maltraitent les personnes dont ils s&rsquo;occupent.<\/p>\n\n\n\n<p>Un autre exemple&#160;: en Allemagne, un livre \u00e0 succ\u00e8s paru en 2017 s\u2019intitule <em>1000 ganz legale Steuertricks<\/em> (\u00ab&#160;<em>1 000 astuces fiscales tout \u00e0 fait l\u00e9gales<\/em>&#160;\u00bb)&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-321336' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2026\/03\/10\/conversation-hartmut-rosa\/#easy-footnote-bottom-4-321336' title='Franz Konz, &lt;em&gt;1000 ganz legale Steuertricks,&lt;\/em&gt; Munich, Droemer Knaur, 2017.'><sup>4<\/sup><\/a><\/span><\/span>. L&rsquo;id\u00e9e qui y est d\u00e9fendue est la suivante&#160;: \u00ab&#160;Exploitez toutes les marges de man\u0153uvre \u00e0 votre avantage&#160;!&#160;\u00bb L\u2019ouvrage ne propose pas de d\u00e9velopper son sens critique, son discernement et son intuition pour d\u00e9terminer ce qui serait juste, mais d&rsquo;exploiter toutes les marges, y compris l\u00e0 o\u00f9 cela n&rsquo;est pas pr\u00e9vu et o\u00f9 l&rsquo;on pourrait consid\u00e9rer que c&rsquo;est injuste, afin d&rsquo;en tirer profit. Le livre promeut donc \u00e0 son tour l&rsquo;herm\u00e9neutique du soup\u00e7on&#160;: toute marge de man\u0153uvre devient partiale et injuste.<\/p>\n\n\n\n<p>Ma th\u00e8se est donc que nous en sommes venus \u00e0 consid\u00e9rer, sur le plan culturel et social, que disposer d&rsquo;une marge de man\u0153uvre implique n\u00e9cessairement d&rsquo;en abuser.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Aujourd\u2019hui, le sens du jugement, c&rsquo;est-\u00e0-dire la mani\u00e8re d&rsquo;agir face \u00e0 une situation donn\u00e9e, est en partie remplac\u00e9 par des r\u00e8gles m\u00e9caniques, bureaucratiques et abstraites.<\/p><cite>Hartmut Rosa<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Dans quelle mesure nos d\u00e9sirs sont-ils modifi\u00e9s d\u00e8s lors que dispara\u00eet cette marge de man\u0153uvre&#160;?<\/h3>\n\n\n\n<p>Nous avons naturellement le sentiment que les nouvelles technologies nous permettent de faire ce que nous voulons. Cependant, nos d\u00e9sirs \u00e9voluent. Nos d\u00e9sirs, et notre sensibilit\u00e9 par la m\u00eame occasion, changent, tout comme ce \u00e0 quoi nous pr\u00eatons attention, car nous recherchons un rendement maximal. Ma question est donc la suivante&#160;: que souhaitons-nous r\u00e9ellement dans le monde&#160;?<\/p>\n\n\n\n<p>La cuisine est un bon exemple de ce d\u00e9placement des d\u00e9sirs suscit\u00e9 par la technologie. Nous souhaitons obtenir le r\u00e9sultat optimal que nous pouvons atteindre gr\u00e2ce \u00e0 une technologie moderne, comme un Thermomix qui fait tout \u00e0 notre place, et peut-\u00eatre m\u00eame mieux que si nous cuisinions nous-m\u00eames. De tels outils modifient la structure de notre volont\u00e9 et notre attention dans une perspective constellative.&nbsp;<\/p>\n\n\n\n<p>Dans le domaine de la sant\u00e9, ce changement est \u00e9galement \u00e9vident. Quand on se demande si on est en bonne sant\u00e9 ou comment on a dormi, il y a deux fa\u00e7ons de r\u00e9pondre \u00e0 la question. La premi\u00e8re, c&rsquo;est de regarder \u00e0 l&rsquo;int\u00e9rieur de soi. On peut se demander&#160;: \u00ab&#160;Comment je me sens&#160;?&#160;\u00bb. L&rsquo;autre possibilit\u00e9 consiste \u00e0 se tourner vers l&rsquo;ext\u00e9rieur&#160;: que dit mon tracker personnel&#160;? Combien d&rsquo;heures ai-je dormi&#160;? Quelle \u00e9tait la qualit\u00e9 de mon rythme de sommeil ou l&rsquo;efficacit\u00e9 de ma phase de sommeil&#160;?<\/p>\n\n\n\n<p>Si vous me demandez si je suis en bonne sant\u00e9, je peux r\u00e9pondre que ma tension art\u00e9rielle est bonne et que mes analyses sanguines sont normales, ou, au contraire, simplement que je me sens en bonne sant\u00e9. Il en va de m\u00eame pour la vie sociale. \u00c0 la question \u00ab&#160;Avez-vous de bons amis&#160;?&#160;\u00bb, je peux \u00e9galement r\u00e9pondre de mani\u00e8re constellative&#160;: \u00ab&#160;Oui, j&rsquo;ai de nombreux abonn\u00e9s sur Snapchat et Instagram.&#160;\u00bb<\/p>\n\n\n\n<p>Des \u00e9tudes en sciences sociales montrent d\u00e9sormais que le regard se d\u00e9tourne maintenant de la perception situationnelle pour se tourner vers la d\u00e9termination constellative. Nous ne sommes donc pas emp\u00each\u00e9s de faire ce que nous souhaitons, mais nous mettons \u00e0 souhaiter d\u2019autres choses.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Quelles sont les cons\u00e9quences politiques de ce changement&#160;?<\/h3>\n\n\n\n<p>De mani\u00e8re surprenante, dans le domaine de la politique, l\u2019approche constellative limite \u00e9galement notre capacit\u00e9 d&rsquo;action et notre perception des situations.<\/p>\n\n\n\n<p>Sur le plan politique, la soci\u00e9t\u00e9 est toujours prise dans une <em>situation<\/em> particuli\u00e8re. Nous sommes en 2026, une ann\u00e9e qui nous met au d\u00e9fi sur les plans d\u00e9mocratique, militaire, \u00e9cologique et \u00e9conomique. La question qui se pose alors est la suivante&#160;: que faisons-nous dans cette situation&#160;?<\/p>\n\n\n\n<p>Je constate que l\u2019approche constellative limite beaucoup les r\u00e9ponses \u00e0 cette question. Dans le cas de la guerre en Ukraine, par exemple, le discours en Allemagne portait toujours sur la question de savoir si nous devions fournir telle ou telle arme. Talk-show apr\u00e8s talk-show, d\u00e9bat parlementaire apr\u00e8s d\u00e9bat parlementaire, il n\u2019\u00e9tait pas question d\u2019autre chose. Il s&rsquo;agit l\u00e0 d&rsquo;un r\u00e9tr\u00e9cissement extr\u00eame.<\/p>\n\n\n\n<p>Je donnerai un autre exemple. Dans de nombreux pays, certaines forces politiques mod\u00e9r\u00e9es se demandent si elles seraient pr\u00eates \u00e0 former une coalition avec l&rsquo;extr\u00eame droite. Cette question doit toujours \u00eatre tranch\u00e9e \u00e0 l&rsquo;avance&#160;: il s&rsquo;agit de d\u00e9terminations constellatives qui peuvent entra\u00eener des probl\u00e8mes de situation.<\/p>\n\n\n\n<p>En Thuringe, un journaliste a interrog\u00e9 Katja Wolf, t\u00eate de liste de l&rsquo;Alliance Sahra Wagenknecht (BSW) et membre du gouvernement, en lui posant la question suivante&#160;: \u00ab&#160;Si l&rsquo;AfD d\u00e9pose une proposition raisonnable au Parlement, voterez-vous pour ou contre&#160;?&#160;\u00bb Mme Wolf a r\u00e9pondu que l&rsquo;AfD pr\u00e9sentait rarement de bonnes propositions, mais le journaliste a insist\u00e9&#160;: \u00ab&#160;Allez-vous alors voter pour ou contre&#160;?&#160;\u00bb<\/p>\n\n\n\n<p>Katja Wolf se trouvait ainsi confront\u00e9e au probl\u00e8me suivant&#160;: si elle r\u00e9pondait non, elle passerait pour antid\u00e9mocratique, car elle voterait contre une bonne proposition. Si elle r\u00e9pondait oui, cela signifierait que le BSW serait pr\u00eat \u00e0 former une coalition avec l&rsquo;extr\u00eame droite.<\/p>\n\n\n\n<p>Il s&rsquo;agit d&rsquo;un r\u00e9tr\u00e9cissement du discours politique, d&rsquo;un blocage et m\u00eame d&rsquo;une exacerbation qui rendent la t\u00e2che difficile aux politiciens et provoquent une grande frustration que nous sous-estimons. Nous savons que les \u00e9lecteurs sont souvent insatisfaits des partis \u00e9tablis, mais les politiciens souffrent tout autant de ne plus se percevoir comme capables d&rsquo;agir. Cela alimente la col\u00e8re politique.<\/p>\n\n\n\n<p>Comme nous l&rsquo;avons d\u00e9j\u00e0 mentionn\u00e9, nous sommes \u00e9motionnellement ali\u00e9n\u00e9s, voire paralys\u00e9s dans notre vie quotidienne&#160;; les \u00e9motions n\u2019y jouent plus aucun r\u00f4le. Cependant, elles se d\u00e9chargent lorsque nous regardons les informations. Certains expriment leur m\u00e9contentement envers les Verts, d&rsquo;autres envers Merz, S\u00f6der, l&rsquo;AfD, Poutine ou Trump. Ils manifestent alors leur frustration en parcourant leur appartement, les poings serr\u00e9s. Alors qu\u2019il n&rsquo;existe aucun contexte d&rsquo;action, cela conduit \u00e0 des manifestations politiques extr\u00eames dans la rue ou lors des \u00e9lections.&nbsp;<\/p>\n\n\n\n<p>Je pense que les partis populistes connaissent un grand succ\u00e8s parce qu&rsquo;ils promettent aux \u00e9lecteurs de revenir \u00e0 l&rsquo;action. Prenons l&rsquo;exemple du Brexit et du slogan \u00ab&#160;<em>Take back control<\/em>&#160;\u00bb&#160;: derri\u00e8re ce mot d\u2019ordre se cache l&rsquo;id\u00e9e de ne plus laisser Bruxelles ex\u00e9cuter, mais de redevenir des acteurs \u00e0 part enti\u00e8re.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Nous en sommes venus \u00e0 consid\u00e9rer, sur le plan culturel et social, que disposer d&rsquo;une marge de man\u0153uvre implique n\u00e9cessairement d&rsquo;en abuser.<\/p><cite>Hartmut Rosa<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Est-ce cette promesse d\u2019une reprise de contr\u00f4le qui explique l\u2019\u00e9lection de Trump \u00e0 la pr\u00e9sidence des \u00c9tats-Unis&#160;?<\/h3>\n\n\n\n<p>Je le pense. \u00c0 l&rsquo;\u00e9chelle mondiale, de nombreux sociologues et politologues se demandent actuellement comment Donald Trump a pu acc\u00e9der au pouvoir dans l&rsquo;une des plus anciennes d\u00e9mocraties du monde. Selon moi, les explications superficielles qui imputent son \u00e9lection \u00e0 un syst\u00e8me \u00e9ducatif d\u00e9faillant ou \u00e0 un syst\u00e8me m\u00e9diatique inefficace sont erron\u00e9es. Les \u00c9tats-Uniens ne sont pas tous peu \u00e9duqu\u00e9s et disposent de tr\u00e8s bons m\u00e9dias. Du reste, en Allemagne et ailleurs en Europe, nous rencontrons \u00e9galement des probl\u00e8mes en mati\u00e8re de d\u00e9mocratie similaires \u00e0 ceux des \u00c9tats-Unis, tout en ayant parfois des faiblesses diff\u00e9rentes.<\/p>\n\n\n\n<p>Dans mon livre, je tente de d\u00e9montrer que Trump a su promettre avec succ\u00e8s qu&rsquo;il agirait. Il le souligne encore aujourd&rsquo;hui dans ses interviews. Il ne se laisse arr\u00eater par aucun contrat, aucun conseil politique, aucun accord. La seule chose qui le retient, comme il le dit clairement, ce sont sa raison, son jugement et ses valeurs. C&rsquo;est cela, agir. Trump sugg\u00e8re qu&rsquo;il peut le faire avec efficacit\u00e9. D&rsquo;un trait de plume, il avait \u00e9tabli le DOGE dirig\u00e9 par Musk, pour \u00ab&#160;d\u00e9manteler la bureaucratie gouvernementale&#160;\u00bb \u2014 cette instance a \u00e9t\u00e9 mise en sourdine depuis.&nbsp;<\/p>\n\n\n\n<p>Lorsqu&rsquo;on conquiert et qu&rsquo;on utilise des marges de man\u0153uvre, on constate toutefois dans un premier temps qu&rsquo;il est possible d&rsquo;agir sans discernement, sans sens de la mesure et sans tact, d&rsquo;une mani\u00e8re qui ne rend pas justice \u00e0 la situation. Avoir une marge de man\u0153uvre, c&rsquo;est accepter les limites du contexte d&rsquo;action et trouver une bonne solution dans ce contexte-ci. Au contraire, Trump n&rsquo;exploite pas ces marges, mais <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/09\/24\/enshittification-la-nouvelle-doctrine-de-lempire-americain\/\">d\u00e9truit les situations<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Trump a donc exploit\u00e9 une faiblesse r\u00e9elle \u2014 la perte d\u2019une forme d\u2019initiative ressentie par de nombreux \u00e9lecteurs \u2014 pour proposer une solution populiste. Comment regagner une marge de man\u0153uvre sans c\u00e9der \u00e0 ces fausses promesses&#160;?<\/h3>\n\n\n\n<p>Il m\u2019est arriv\u00e9 d\u2019\u00e9crire des ouvrages tr\u00e8s pessimistes, mais le dernier se termine plut\u00f4t sur une note optimiste.&nbsp;<\/p>\n\n\n\n<p>J&rsquo;ai en effet constat\u00e9 que nous n&rsquo;en \u00e9tions pas encore arriv\u00e9s au point o\u00f9 nous ne faisions plus qu&rsquo;ex\u00e9cuter. Nous ne le pourrions d&rsquo;ailleurs pas, car la vie est toujours plus riche et nous confronte sans cesse \u00e0 des situations et des d\u00e9fis impr\u00e9vus, pour lesquels l&rsquo;appareil avec lequel nous r\u00e9agissons habituellement n&rsquo;est pas con\u00e7u.<\/p>\n\n\n\n<p>Le sociologue et historien Richard Sennett a constat\u00e9 il y a longtemps que les gens commencent \u00e0 se sentir vivants lorsque les instruments d&rsquo;ex\u00e9cution ne fonctionnent plus, lorsque les r\u00e8gles ne s&rsquo;appliquent plus ou lorsque l&rsquo;appareil tombe en panne&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-321336' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2026\/03\/10\/conversation-hartmut-rosa\/#easy-footnote-bottom-5-321336' title='Richard Sennett, &lt;em&gt;Le Travail sans qualit\u00e9s&amp;#160;: Les cons\u00e9quences humaines de la flexibilit\u00e9&lt;\/em&gt;, Paris, Albin Michel, 2000.'><sup>5<\/sup><\/a><\/span><\/span>. M\u00eame chez McDonald&rsquo;s, les employ\u00e9s commencent \u00e0 faire preuve de cr\u00e9ativit\u00e9 et \u00e0 agir de mani\u00e8re autonome lorsque les machines sont hors-service.<\/p>\n\n\n\n<p>Il est int\u00e9ressant de noter que nous faisons tout au long de la journ\u00e9e des choses que nous ne devrions pas faire \u00ab&#160;En r\u00e9alit\u00e9, nous avons d\u00e9j\u00e0 ferm\u00e9 le magasin, mais veuillez entrer, je vais vous servir.&#160;\u00bb \u00ab&#160;En r\u00e9alit\u00e9, vous avez utilis\u00e9 le mauvais formulaire pour ce probl\u00e8me, mais je vais tout de m\u00eame en tenir compte.&#160;\u00bb \u00ab&#160;En r\u00e9alit\u00e9, je devrais vous attribuer une mauvaise note pour ce m\u00e9moire, mais je vous attribue tout de m\u00eame une bonne note, car quelque chose m&rsquo;a convaincu.&#160;\u00bb. Ce constat s&rsquo;applique m\u00eame \u00e0 la technologie&#160;: \u00ab&#160;En r\u00e9alit\u00e9, ce programme n&rsquo;est pas con\u00e7u pour cela, mais j&rsquo;ai trouv\u00e9 un moyen de l&rsquo;utiliser.&#160;\u00bb Ce \u00ab&#160;en r\u00e9alit\u00e9&#160;\u00bb repr\u00e9sente notre marge de man\u0153uvre.<\/p>\n\n\n\n<p>Je termine ainsi mon livre par un plaidoyer en faveur de la subversion&#160;: il nous faut utiliser ces marges de man\u0153uvre, pour nous consid\u00e9rer comme des acteurs, notamment dans les administrations et au travail. Le sociologue Niklas Luhmann appelle cela \u00ab&#160;l&rsquo;ill\u00e9galit\u00e9 utile&#160;\u00bb, sujet sur lequel Stefan K\u00fchl, un coll\u00e8gue de Bielefeld, a \u00e9crit le livre <em>Brauchbare Illegalit\u00e4t&#160;: Vom Nutzen des Regelbruchs in Organisationen<\/em>&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-321336' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2026\/03\/10\/conversation-hartmut-rosa\/#easy-footnote-bottom-6-321336' title='Stefan K\u00fchl, &lt;em&gt;Brauchbare Illegalit\u00e4t&amp;#160;: Vom Nutzen des Regelbruchs in Organisationen&lt;\/em&gt;, Francfort, Campus, 2020.'><sup>6<\/sup><\/a><\/span><\/span>. Il y montre comment, pr\u00e9cis\u00e9ment dans les organisations, les entreprises et les soci\u00e9t\u00e9s, les directives ne sont pas syst\u00e9matiquement respect\u00e9es. Dans les pays du Sud, il existe pr\u00e9cis\u00e9ment pour cela les concepts que j&rsquo;ai d\u00e9j\u00e0 mentionn\u00e9s pr\u00e9c\u00e9demment.<\/p>\n\n\n\n<p>Je souhaite que nous puissions red\u00e9couvrir et exploiter les petites marges de man\u0153uvre. Cela nous permet \u00e9galement de sensibiliser davantage \u00e0 la n\u00e9cessit\u00e9 de <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/11\/18\/des-animaux-a-lia-lhumanite-est-elle-en-train-de-changer\/\">retrouver notre capacit\u00e9 d&rsquo;action \u00e0 grande \u00e9chelle<\/a>.<\/p>\n\n\n\n<p>Je pense que le syst\u00e8me capitaliste ne pourra changer que si nous, citoyens, nous consid\u00e9rons \u00e0 nouveau comme des acteurs et r\u00e9clamons ces marges. J&rsquo;esp\u00e8re que cette r\u00e9appropriation, \u00e0 notre niveau, nous permettra de passer \u00e0 l\u2019\u00e9chelle sup\u00e9rieure.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Juger sans justice. Arbitrer sans \u00e9quit\u00e9. S\u2019orienter sans conna\u00eetre son chemin.<\/p>\n<p>Dans son dernier livre <em>Situation und Konstellation<\/em>, le sociologue allemand d\u00e9crit un basculement silencieux de la modernit\u00e9&#160;&#160;: la disparition progressive de nos marges de man\u0153uvre.<\/p>\n<p>Face aux algorithmes et \u00e0 la bureaucratie, il propose un chemin pour reprendre l\u2019initiative.<\/p>\n","protected":false},"author":10,"featured_media":319610,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-interviews.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":26,"footnotes":""},"categories":[2246],"tags":[],"staff":[1999],"editorial_format":[4854],"serie":[],"audience":[],"geo":[1917],"class_list":["post-321336","post","type-post","status-publish","format-standard","hentry","category-anthropologie","staff-stefanie-buzmaniuk","editorial_format-entretiens","geo-europe"],"acf":{"open_in_webview":false,"accent":"default","_thumbnail_id":319610,"excerpt":"Juger sans justice. Arbitrer sans \u00e9quit\u00e9. S\u2019orienter sans conna\u00eetre son chemin.\r\n\r\nDans son dernier livre <em>Situation und Konstellation<\/em>, le sociologue allemand d\u00e9crit un basculement silencieux de la modernit\u00e9 : la disparition progressive de nos marges de man\u0153uvre.\r\n\r\nFace aux algorithmes et \u00e0 la bureaucratie, il propose un chemin pour reprendre l\u2019initiative.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Reprendre le contr\u00f4le : conversation avec Hartmut Rosa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2026\/03\/10\/conversation-hartmut-rosa\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reprendre le contr\u00f4le : conversation avec Hartmut Rosa\" \/>\n<meta property=\"og:description\" content=\"Juger sans justice. Arbitrer sans \u00e9quit\u00e9. S\u2019orienter sans conna\u00eetre son chemin.  Dans son dernier livre Situation und Konstellation, le sociologue allemand d\u00e9crit un basculement silencieux de la modernit\u00e9&#160;: la disparition progressive de nos marges de man\u0153uvre.  Face aux algorithmes et \u00e0 la bureaucratie, il propose un chemin pour reprendre l\u2019initiative.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2026\/03\/10\/conversation-hartmut-rosa\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-10T18:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-14T07:40:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/gc-rosa-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matheo Malik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/gc-rosa-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheo Malik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"26 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/03\/10\/conversation-hartmut-rosa\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/03\/10\/conversation-hartmut-rosa\/\",\"name\":\"Reprendre le contr\u00f4le : conversation avec Hartmut Rosa\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/03\/10\/conversation-hartmut-rosa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/03\/10\/conversation-hartmut-rosa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/Hartmut-Rosa.jpg\",\"datePublished\":\"2026-03-10T18:00:00+00:00\",\"dateModified\":\"2026-04-14T07:40:56+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/03\/10\/conversation-hartmut-rosa\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2026\/03\/10\/conversation-hartmut-rosa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/03\/10\/conversation-hartmut-rosa\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/Hartmut-Rosa.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/Hartmut-Rosa.jpg\",\"width\":1365,\"height\":2048,\"caption\":\"Hartmut Rosa par Balz Murer \u00a9 Balz Murer\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/03\/10\/conversation-hartmut-rosa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment reprendre le contr\u00f4le&#160;? Se panser dans la violence du monde avec Hartmut Rosa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\",\"name\":\"Matheo Malik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"caption\":\"Matheo Malik\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reprendre le contr\u00f4le : conversation avec Hartmut Rosa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2026\/03\/10\/conversation-hartmut-rosa\/","og_locale":"fr_FR","og_type":"article","og_title":"Reprendre le contr\u00f4le : conversation avec Hartmut Rosa","og_description":"Juger sans justice. Arbitrer sans \u00e9quit\u00e9. S\u2019orienter sans conna\u00eetre son chemin.  Dans son dernier livre Situation und Konstellation, le sociologue allemand d\u00e9crit un basculement silencieux de la modernit\u00e9&#160;: la disparition progressive de nos marges de man\u0153uvre.  Face aux algorithmes et \u00e0 la bureaucratie, il propose un chemin pour reprendre l\u2019initiative.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2026\/03\/10\/conversation-hartmut-rosa\/","og_site_name":"Le Grand Continent","article_published_time":"2026-03-10T18:00:00+00:00","article_modified_time":"2026-04-14T07:40:56+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/gc-rosa-scaled.jpg","type":"image\/jpeg"}],"author":"Matheo Malik","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/gc-rosa-scaled.jpg","twitter_misc":{"\u00c9crit par":"Matheo Malik","Dur\u00e9e de lecture estim\u00e9e":"26 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2026\/03\/10\/conversation-hartmut-rosa\/","url":"https:\/\/legrandcontinent.eu\/fr\/2026\/03\/10\/conversation-hartmut-rosa\/","name":"Reprendre le contr\u00f4le : conversation avec Hartmut Rosa","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2026\/03\/10\/conversation-hartmut-rosa\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2026\/03\/10\/conversation-hartmut-rosa\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/Hartmut-Rosa.jpg","datePublished":"2026-03-10T18:00:00+00:00","dateModified":"2026-04-14T07:40:56+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2026\/03\/10\/conversation-hartmut-rosa\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2026\/03\/10\/conversation-hartmut-rosa\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2026\/03\/10\/conversation-hartmut-rosa\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/Hartmut-Rosa.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/Hartmut-Rosa.jpg","width":1365,"height":2048,"caption":"Hartmut Rosa par Balz Murer \u00a9 Balz Murer"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2026\/03\/10\/conversation-hartmut-rosa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Comment reprendre le contr\u00f4le&#160;? Se panser dans la violence du monde avec Hartmut Rosa"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45","name":"Matheo Malik","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","caption":"Matheo Malik"}}]}},"lgc_categories":[{"id":2246,"name":"Anthropologie","slug":"anthropologie"}],"lgc_author":{"id":1999,"name":"Stefanie Buzmaniuk","slug":"stefanie-buzmaniuk","description":null,"first_name":null,"last_name":null,"picture":null},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/Hartmut-Rosa.jpg","width":1365,"height":2048,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/Hartmut-Rosa.jpg","width":1365,"height":2048,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/321336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=321336"}],"version-history":[{"count":43,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/321336\/revisions"}],"predecessor-version":[{"id":327257,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/321336\/revisions\/327257"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/319610"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=321336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=321336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=321336"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=321336"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=321336"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=321336"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=321336"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=321336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}