{"id":318105,"date":"2026-02-20T16:25:46","date_gmt":"2026-02-20T15:25:46","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=318105"},"modified":"2026-02-20T20:18:39","modified_gmt":"2026-02-20T19:18:39","slug":"la-plus-importante-defaite-juridique-de-trump-la-cour-supreme-declare-illegales-les-droits-de-douane-ieepa","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/20\/la-plus-importante-defaite-juridique-de-trump-la-cour-supreme-declare-illegales-les-droits-de-douane-ieepa\/","title":{"rendered":"La plus importante d\u00e9faite juridique de Trump&#160;? La Cour supr\u00eame d\u00e9clare ill\u00e9gaux les droits de douane IEEPA"},"content":{"rendered":"\n<p>La Cour supr\u00eame am\u00e9ricaine s\u2019est exprim\u00e9e aujourd\u2019hui, 20 f\u00e9vrier, sur la l\u00e9galit\u00e9 du recours par Donald Trump \u00e0 l\u2019International Emergency Economic Powers Act (IEEPA) pour imposer des droits de douane, y compris les tarifs dits \u00ab&#160;r\u00e9ciproques&#160;\u00bb annonc\u00e9s en avril 2025&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-318105' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2026\/02\/20\/la-plus-importante-defaite-juridique-de-trump-la-cour-supreme-declare-illegales-les-droits-de-douane-ieepa\/#easy-footnote-bottom-1-318105' title='Voir la d\u00e9cision &lt;a href=&quot;https:\/\/www.supremecourt.gov\/opinions\/25pdf\/24-1287_4gcj.pdf&quot;&gt;ici&lt;\/a&gt;.'><sup>1<\/sup><\/a><\/span><\/span>.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le juge conservateur John Roberts, nomm\u00e9 en 2005 par George W. Bush, a ainsi not\u00e9&#160;: \u00ab&#160;Le pr\u00e9sident revendique le pouvoir extraordinaire d\u2019imposer unilat\u00e9ralement des droits de douane d\u2019un montant, d\u2019une dur\u00e9e et d\u2019une port\u00e9e illimit\u00e9s. Compte tenu de l\u2019ampleur, de l\u2019histoire et du contexte constitutionnel de ce pouvoir revendiqu\u00e9, il doit identifier une autorisation claire du Congr\u00e8s pour l\u2019exercer&#160;\u00bb.<\/li>\n<\/ul>\n\n\n\n<p>Il pourrait s\u2019agir de la plus importante d\u00e9faite judiciaire de Trump depuis son retour \u00e0 la Maison-Blanche.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La Cour supr\u00eame estime ainsi que le pr\u00e9sident am\u00e9ricain a outrepass\u00e9 ses pouvoirs en invoquant une loi f\u00e9d\u00e9rale sur les pouvoirs d\u2019urgence pour instaurer ses droits de douane \u00ab&#160;r\u00e9ciproques&#160;\u00bb \u00e0 l\u2019\u00e9chelle mondiale, ainsi que des taxes cibl\u00e9es sur les importations que l\u2019administration affirme \u00eatre destin\u00e9es \u00e0 lutter contre le trafic de fentanyl.<\/li>\n\n\n\n<li>Il s\u2019agit d\u2019un revers significatif pour l\u2019administration r\u00e9publicaine. Cette d\u00e9cision pourrait toutefois ne pas se traduire par une baisse durable des droits de douane.<\/li>\n\n\n\n<li>Les responsables de la Maison-Blanche ont indiqu\u00e9 \u00e0 plusieurs reprises que l\u2019administration \u00e9tait pr\u00eate \u00e0 invoquer d\u2019autres pouvoirs ex\u00e9cutifs pour maintenir l\u2019essentiel de ces tarifs.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/xkGlL\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Quelques heures apr\u00e8s l&rsquo;annonce, lors d&rsquo;une conf\u00e9rence de presse \u00e0 la Maison-Blanche, Trump a d\u00e9clar\u00e9 qu&rsquo;il allait imposer un taux global de 10&#160;% sur l&rsquo;ensemble des pays, en vertu de la section 122 du Trade Act de 1974, qui autorise le pr\u00e9sident \u00e0 instaurer des mesures restrictives \u00e0 l&rsquo;importation pour une dur\u00e9e maximale de six mois.<\/li>\n\n\n\n<li>Il a \u00e9galement indiqu\u00e9 que l&rsquo;administration utiliserait la section 301 pour ouvrir des enqu\u00eates sur des pratiques commerciales d\u00e9loyales, ce qui pourrait entra\u00eener l&rsquo;imposition de droits de douane suppl\u00e9mentaires.<\/li>\n<\/ul>\n\n\n\n<p>Mais cette d\u00e9cision pourrait \u00e9galement donner \u00e0 l&rsquo;administration l&rsquo;occasion de mod\u00e9rer certains droits de douane sur des cat\u00e9gories de produits sp\u00e9cifiques, afin de r\u00e9pondre aux inqui\u00e9tudes croissantes concernant le pouvoir d&rsquo;achat.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Selon le Yale Budget Lab, sans les droits de douane IEEPA, le taux effectif moyen global des \u00c9tats-Unis s&rsquo;\u00e9tablirait \u00e0 9,1&#160;%, soit le plus \u00e9lev\u00e9 depuis 1946, \u00e0 l&rsquo;exception de 2025. Si les droits de douane IEEPA avaient \u00e9t\u00e9 maintenus, ce chiffre aurait \u00e9t\u00e9 de 16,9&#160;%.<\/li>\n<\/ul>\n\n\n\n<p>Une question clef qui se posera dans les prochains jours est celle du remboursement des tarifs douaniers d\u00e9j\u00e0 per\u00e7us \u2014 pour un montant de pr\u00e8s de 150 milliards de dollars.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le juge Brett Kavanaugh note&#160;: \u00ab&#160;La Cour ne se prononce pas aujourd&rsquo;hui sur la question de savoir si, et dans l&rsquo;affirmative, comment le gouvernement devrait proc\u00e9der pour restituer les milliards de dollars qu&rsquo;il a per\u00e7us aupr\u00e8s des importateurs&#160;\u00bb.<\/li>\n\n\n\n<li>Donald Trump a d\u00e9clar\u00e9&#160;: \u00ab&#160;Nous avons encaiss\u00e9 des centaines de milliards de dollars\u2026 vous ne pensez pas qu\u2019ils auraient ajout\u00e9 une phrase disant de garder l\u2019argent&#160;?&#160;\u00bb. \u00ab&#160;Ce n\u2019est pas abord\u00e9, nous allons probablement nous retrouver devant les tribunaux pendant les cinq prochaines ann\u00e9es.&#160;\u00bb<\/li>\n<\/ul>\n\n\n\n<p>Les droits de douane \u00ab&#160;r\u00e9ciproques&#160;\u00bb impos\u00e9s par l&rsquo;administration Trump avaient donn\u00e9 lieu \u00e0 plusieurs accords commerciaux, y compris avec l&rsquo;Union europ\u00e9enne, qui fait toujours face \u00e0 un taux de 15&#160;%. Il n&rsquo;est pas certain de la mani\u00e8re dont les diff\u00e9rents pays vont r\u00e9agir.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Donald Trump a d\u00e9clar\u00e9 que \u00ab&#160;beaucoup&#160;\u00bb des accords commerciaux conclus par les \u00c9tats-Unis resteraient en vigueur, tandis que d\u2019autres devraient \u00eatre modifi\u00e9s \u00e0 la suite de la d\u00e9cision de la Cour supr\u00eame&#160;: \u00ab&#160;Certains restent en place. Beaucoup restent en place. Certains ne resteront pas, et ils seront remplac\u00e9s&#160;\u00bb. <\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>La Cour supr\u00eame des \u00c9tats-Unis s\u2019est prononc\u00e9e contre une grande partie des droits de douane impos\u00e9s par le pr\u00e9sident Donald Trump depuis son retour \u00e0 la Maison Blanche, lors d\u2019une d\u00e9cision rendue aujourd\u2019hui, vendredi 20 f\u00e9vrier.<\/p>\n<p>Lors d&rsquo;une conf\u00e9rence de presse, Trump a d\u00e9j\u00e0 annonc\u00e9 son intention d&rsquo;imposer un taux global de 10&#160;% \u00e0 l&rsquo;ensemble des pays, en vertu de la section 122 du Trade Act de 1974, qui autorise le pr\u00e9sident \u00e0 instaurer des mesures restrictives \u00e0 l&rsquo;importation pour une dur\u00e9e maximale de six mois.<\/p>\n","protected":false},"author":40,"featured_media":318109,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":4,"_lgc_tts_audio_url":"","_lgc_tts_voice":"","_lgc_tts_publish":false,"_lgc_tts_history_item_id":"","_lgc_tts_generated_at":"","_lgc_tts_status":"","_lgc_tts_error":"","footnotes":""},"categories":[1727],"tags":[],"staff":[],"editorial_format":[4942],"serie":[],"audience":[],"geo":[525],"class_list":["post-318105","post","type-post","status-publish","format-standard","hentry","category-economie","editorial_format-actu-breves","geo-ameriques"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":318109,"excerpt":"La Cour supr\u00eame des \u00c9tats-Unis s\u2019est prononc\u00e9e contre une grande partie des droits de douane impos\u00e9s par le pr\u00e9sident Donald Trump depuis son retour \u00e0 la Maison Blanche, lors d\u2019une d\u00e9cision rendue aujourd\u2019hui, vendredi 20 f\u00e9vrier.\r\n\r\nLors d'une conf\u00e9rence de presse, Trump a d\u00e9j\u00e0 annonc\u00e9 son intention d'imposer un taux global de 10% \u00e0 l'ensemble des pays, en vertu de la section 122 du Trade Act de 1974, qui autorise le pr\u00e9sident \u00e0 instaurer des mesures restrictives \u00e0 l'importation pour une dur\u00e9e maximale de six mois.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La plus importante d\u00e9faite juridique de Trump ? La Cour supr\u00eame d\u00e9clare ill\u00e9gaux les droits de douane IEEPA | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/20\/la-plus-importante-defaite-juridique-de-trump-la-cour-supreme-declare-illegales-les-droits-de-douane-ieepa\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La plus importante d\u00e9faite juridique de Trump ? La Cour supr\u00eame d\u00e9clare ill\u00e9gaux les droits de douane IEEPA | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"La Cour supr\u00eame des \u00c9tats-Unis s\u2019est prononc\u00e9e contre une grande partie des droits de douane impos\u00e9s par le pr\u00e9sident Donald Trump depuis son retour \u00e0 la Maison Blanche, lors d\u2019une d\u00e9cision rendue aujourd\u2019hui, vendredi 20 f\u00e9vrier.  Lors d&#039;une conf\u00e9rence de presse, Trump a d\u00e9j\u00e0 annonc\u00e9 son intention d&#039;imposer un taux global de 10&#160;% \u00e0 l&#039;ensemble des pays, en vertu de la section 122 du Trade Act de 1974, qui autorise le pr\u00e9sident \u00e0 instaurer des mesures restrictives \u00e0 l&#039;importation pour une dur\u00e9e maximale de six mois.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/20\/la-plus-importante-defaite-juridique-de-trump-la-cour-supreme-declare-illegales-les-droits-de-douane-ieepa\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-20T15:25:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-20T19:18:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/Sans-titre-21.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1952\" \/>\n\t<meta property=\"og:image:height\" content=\"1106\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ramona Bloj\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/Sans-titre-21.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ramona Bloj\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/20\/la-plus-importante-defaite-juridique-de-trump-la-cour-supreme-declare-illegales-les-droits-de-douane-ieepa\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/20\/la-plus-importante-defaite-juridique-de-trump-la-cour-supreme-declare-illegales-les-droits-de-douane-ieepa\/\",\"name\":\"La plus importante d\u00e9faite juridique de Trump ? La Cour supr\u00eame d\u00e9clare ill\u00e9gaux les droits de douane IEEPA | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/20\/la-plus-importante-defaite-juridique-de-trump-la-cour-supreme-declare-illegales-les-droits-de-douane-ieepa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/20\/la-plus-importante-defaite-juridique-de-trump-la-cour-supreme-declare-illegales-les-droits-de-douane-ieepa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/Sans-titre-22.jpg\",\"datePublished\":\"2026-02-20T15:25:46+00:00\",\"dateModified\":\"2026-02-20T19:18:39+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/bee86896b403754f76b6b1515ff0b697\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/20\/la-plus-importante-defaite-juridique-de-trump-la-cour-supreme-declare-illegales-les-droits-de-douane-ieepa\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/20\/la-plus-importante-defaite-juridique-de-trump-la-cour-supreme-declare-illegales-les-droits-de-douane-ieepa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/20\/la-plus-importante-defaite-juridique-de-trump-la-cour-supreme-declare-illegales-les-droits-de-douane-ieepa\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/Sans-titre-22.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/Sans-titre-22.jpg\",\"width\":1950,\"height\":1088,\"caption\":\"Les leviers juridiques dont dispose l'administration Trump pour maintenir les droits de douane suite au jugement d\u00e9favorable de la Cour supr\u00eame\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/20\/la-plus-importante-defaite-juridique-de-trump-la-cour-supreme-declare-illegales-les-droits-de-douane-ieepa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La plus importante d\u00e9faite juridique de Trump&#160;? La Cour supr\u00eame d\u00e9clare ill\u00e9gaux les droits de douane IEEPA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/bee86896b403754f76b6b1515ff0b697\",\"name\":\"Ramona Bloj\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c1d91adb7c4c1eed266b81c0f9915707?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c1d91adb7c4c1eed266b81c0f9915707?s=96&d=mm&r=g\",\"caption\":\"Ramona Bloj\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La plus importante d\u00e9faite juridique de Trump ? La Cour supr\u00eame d\u00e9clare ill\u00e9gaux les droits de douane IEEPA | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/20\/la-plus-importante-defaite-juridique-de-trump-la-cour-supreme-declare-illegales-les-droits-de-douane-ieepa\/","og_locale":"fr_FR","og_type":"article","og_title":"La plus importante d\u00e9faite juridique de Trump ? La Cour supr\u00eame d\u00e9clare ill\u00e9gaux les droits de douane IEEPA | Le Grand Continent","og_description":"La Cour supr\u00eame des \u00c9tats-Unis s\u2019est prononc\u00e9e contre une grande partie des droits de douane impos\u00e9s par le pr\u00e9sident Donald Trump depuis son retour \u00e0 la Maison Blanche, lors d\u2019une d\u00e9cision rendue aujourd\u2019hui, vendredi 20 f\u00e9vrier.  Lors d'une conf\u00e9rence de presse, Trump a d\u00e9j\u00e0 annonc\u00e9 son intention d'imposer un taux global de 10&#160;% \u00e0 l'ensemble des pays, en vertu de la section 122 du Trade Act de 1974, qui autorise le pr\u00e9sident \u00e0 instaurer des mesures restrictives \u00e0 l'importation pour une dur\u00e9e maximale de six mois.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/20\/la-plus-importante-defaite-juridique-de-trump-la-cour-supreme-declare-illegales-les-droits-de-douane-ieepa\/","og_site_name":"Le Grand Continent","article_published_time":"2026-02-20T15:25:46+00:00","article_modified_time":"2026-02-20T19:18:39+00:00","og_image":[{"width":1952,"height":1106,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/Sans-titre-21.jpg","type":"image\/jpeg"}],"author":"Ramona Bloj","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/Sans-titre-21.jpg","twitter_misc":{"\u00c9crit par":"Ramona Bloj","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/20\/la-plus-importante-defaite-juridique-de-trump-la-cour-supreme-declare-illegales-les-droits-de-douane-ieepa\/","url":"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/20\/la-plus-importante-defaite-juridique-de-trump-la-cour-supreme-declare-illegales-les-droits-de-douane-ieepa\/","name":"La plus importante d\u00e9faite juridique de Trump ? La Cour supr\u00eame d\u00e9clare ill\u00e9gaux les droits de douane IEEPA | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/20\/la-plus-importante-defaite-juridique-de-trump-la-cour-supreme-declare-illegales-les-droits-de-douane-ieepa\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/20\/la-plus-importante-defaite-juridique-de-trump-la-cour-supreme-declare-illegales-les-droits-de-douane-ieepa\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/Sans-titre-22.jpg","datePublished":"2026-02-20T15:25:46+00:00","dateModified":"2026-02-20T19:18:39+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/bee86896b403754f76b6b1515ff0b697"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/20\/la-plus-importante-defaite-juridique-de-trump-la-cour-supreme-declare-illegales-les-droits-de-douane-ieepa\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2026\/02\/20\/la-plus-importante-defaite-juridique-de-trump-la-cour-supreme-declare-illegales-les-droits-de-douane-ieepa\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/20\/la-plus-importante-defaite-juridique-de-trump-la-cour-supreme-declare-illegales-les-droits-de-douane-ieepa\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/Sans-titre-22.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/Sans-titre-22.jpg","width":1950,"height":1088,"caption":"Les leviers juridiques dont dispose l'administration Trump pour maintenir les droits de douane suite au jugement d\u00e9favorable de la Cour supr\u00eame"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/20\/la-plus-importante-defaite-juridique-de-trump-la-cour-supreme-declare-illegales-les-droits-de-douane-ieepa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"La plus importante d\u00e9faite juridique de Trump&#160;? La Cour supr\u00eame d\u00e9clare ill\u00e9gaux les droits de douane IEEPA"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/bee86896b403754f76b6b1515ff0b697","name":"Ramona Bloj","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c1d91adb7c4c1eed266b81c0f9915707?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c1d91adb7c4c1eed266b81c0f9915707?s=96&d=mm&r=g","caption":"Ramona Bloj"}}]}},"lgc_categories":[{"id":1727,"name":"\u00c9conomie","slug":"economie"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/Sans-titre-22.jpg","width":1950,"height":1088,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/318105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=318105"}],"version-history":[{"count":27,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/318105\/revisions"}],"predecessor-version":[{"id":318217,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/318105\/revisions\/318217"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/318109"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=318105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=318105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=318105"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=318105"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=318105"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=318105"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=318105"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=318105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}