{"id":315647,"date":"2026-02-02T06:30:00","date_gmt":"2026-02-02T05:30:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=315647"},"modified":"2026-02-01T22:14:16","modified_gmt":"2026-02-01T21:14:16","slug":"le-plan-klingbeil-pour-une-europe-des-six","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/02\/le-plan-klingbeil-pour-une-europe-des-six\/","title":{"rendered":"Le plan Klingbeil pour une Europe des six\u00a0"},"content":{"rendered":"\n<p>Friedrich Merz et Lars Klingbeil ont annonc\u00e9 ce mardi 27 janvier lors d\u2019une conf\u00e9rence organis\u00e9e par Die Welt \u00e0 Berlin&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-315647' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2026\/02\/02\/le-plan-klingbeil-pour-une-europe-des-six\/#easy-footnote-bottom-1-315647' title='Karsten Seibel, Christoph Kapalschinski, Daniel-Dylan B\u00f6hmer, Thorsten Jungholt, Holger Zsch\u00e4pitz, Daniel Zwick, &lt;a href=&quot;https:\/\/www.welt.de\/wirtschaft\/article6978b1c7421b9660fac24451\/geduld-mit-europa-schwindet-im-kanzleramt-und-in-den-vorstandsetagen.html&quot;&gt;Geduld mit Europa schwindet \u2013 im Kanzleramt und in den Vorstandsetagen&lt;\/a&gt;, &lt;em&gt;Die Welt&lt;\/em&gt;, 27 janvier 2026.'><sup>1<\/sup><\/a><\/span><\/span> la mise en place d&rsquo;une nouvelle coop\u00e9ration renforc\u00e9e entre six pays volontaires&#160;: l&rsquo;Allemagne, la France, l&rsquo;Italie, l&rsquo;Espagne, la Pologne et les Pays-Bas. Les six repr\u00e9sentent ensemble environ 70&#160;% du PIB de l\u2019Union europ\u00e9enne.\u00a0<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Selon Klingbeil&#160;: \u00ab&#160;Il est d\u00e9sormais crucial de miser sur nos propres forces. L&rsquo;Allemagne, aux c\u00f4t\u00e9s de la France et d&rsquo;autres partenaires, prendra donc l&rsquo;initiative de rendre l&rsquo;Europe plus forte et plus ind\u00e9pendante&#160;\u00bb.\u00a0<\/li>\n\n\n\n<li>Le chancelier Merz a d\u00e9clar\u00e9&#160;: \u00ab&#160;L&rsquo;Europe doit devenir une puissance politique capable de fa\u00e7onner le monde, tant sur le plan \u00e9conomique que militaire&#160;\u00bb.\u00a0<\/li>\n<\/ul>\n\n\n\n<p>Une s\u00e9rie de priorit\u00e9s communes structureront cette initiative, appel\u00e9e \u00ab&#160;groupe des six&#160;\u00bb ou \u00ab&#160;format E6&#160;\u00bb&#160;: l&rsquo;union des march\u00e9s de capitaux, le r\u00f4le international de l&rsquo;euro \u2014 y compris la mise en place d&rsquo;un syst\u00e8me de paiement europ\u00e9en ind\u00e9pendant, la s\u00e9curit\u00e9 des mati\u00e8res premi\u00e8res et les investissements de d\u00e9fense.<\/p>\n\n\n\n<p>L&rsquo;objectif est de faire de l&rsquo;Europe une puissance capable d&rsquo;agir \u00e9conomiquement et militairement, quitte \u00e0 court-circuiter la Commission, tr\u00e8s critiqu\u00e9e ces derni\u00e8res semaines par le patronat et le gouvernement allemand pour leur incapacit\u00e9 \u00e0 avancer face \u00e0 l&rsquo;acc\u00e9l\u00e9ration g\u00e9opolitique du monde&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-315647' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2026\/02\/02\/le-plan-klingbeil-pour-une-europe-des-six\/#easy-footnote-bottom-2-315647' title='Christian Kraemer, Maria Martinez, &lt;a href=&quot;https:\/\/www.reuters.com\/world\/china\/german-french-ministers-aim-boost-eu-competitiveness-with-new-format-2026-01-27\/&quot;&gt;Germany pushes for &amp;lsquo;two-speed&amp;rsquo; Europe with new bloc of six leading economies&lt;\/a&gt;, &lt;em&gt;Reuters&lt;\/em&gt;, 27 janvier 2026.'><sup>2<\/sup><\/a><\/span><\/span>.\u00a0<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/tO9j8\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Un calendrier est d\u00e9j\u00e0 en place.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Une premi\u00e8re r\u00e9union, en amont de la s\u00e9ance de r\u00e9flexion informelle des dirigeants de l&rsquo;Union du 12 f\u00e9vrier, qui se tiendra \u00e0 Alden Biesen, en Belgique, a d\u00e9j\u00e0 eu lieu&#160;: une visioconf\u00e9rence a \u00e9t\u00e9 organis\u00e9e le 28 janvier.\u00a0<\/li>\n\n\n\n<li>Les ministres des Finances des six pays ont notamment abord\u00e9 la question du renforcement de la comp\u00e9titivit\u00e9 et des capacit\u00e9s de d\u00e9fense.\u00a0<\/li>\n\n\n\n<li>Klingbeil a d\u00e9clar\u00e9 apr\u00e8s la r\u00e9union&#160;: \u00ab&#160;En tant que six grandes \u00e9conomies europ\u00e9ennes, nous voulons d\u00e9sormais \u00eatre les moteurs&#160;\u00bb. \u00ab&#160;Nous donnons l&rsquo;impulsion, d&rsquo;autres peuvent se joindre \u00e0 nous. Ce qui importe, c&rsquo;est de renforcer notre comp\u00e9titivit\u00e9 et notre capacit\u00e9 de d\u00e9fense.&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-315647' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2026\/02\/02\/le-plan-klingbeil-pour-une-europe-des-six\/#easy-footnote-bottom-3-315647' title='Maria Martinez, Victoria Waldersee,&lt;a href=&quot;https:\/\/www.reuters.com\/business\/germany-hold-call-with-select-eu-states-push-twospeed-europe-2026-01-28\/&quot;&gt; Six European economies vow to drive progress on stalled projects&lt;\/a&gt;, &lt;em&gt;Reuters&lt;\/em&gt;, 28 janvier 2026.'><sup>3<\/sup><\/a><\/span><\/span>.<\/li>\n<\/ul>\n\n\n\n<p>L\u2019\u00ab&#160;Europe \u00e0 deux vitesses&#160;\u00bb, men\u00e9e par un noyau dur, est une vieille id\u00e9e en Allemagne. C&rsquo;est Sch\u00e4uble qui a formul\u00e9 l&rsquo;id\u00e9e d&rsquo;une \u00ab&#160;Europe \u00e0 deux vitesses&#160;\u00bb (KernEuropa) d\u00e8s 1994, alors que la construction europ\u00e9enne ne comptait que 12 \u00c9tats membres.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Fran\u00e7ois Hollande parlait lui, en 2015, de la cr\u00e9ation, \u00ab&#160;avec les pays qui en d\u00e9cideront&#160;\u00bb, d&rsquo;une \u00ab&#160;avant-garde&#160;\u00bb de l\u2019Union europ\u00e9enne.<\/li>\n\n\n\n<li>Emmanuel Macron d\u00e9clarait lui aussi, dans son discours \u00e0 la Sorbonne en 2017&#160;: \u00ab&#160;L\u2019Europe est d\u00e9j\u00e0 \u00e0 plusieurs vitesses, alors n\u2019ayons pas peur de le dire et de le vouloir&#160;!&#160;\u00bb. \u00ab&#160;Aucun \u00c9tat ne doit \u00eatre exclu de cette dynamique, mais aucun pays ne doit pouvoir bloquer ceux qui veulent avancer plus vite ou plus loin.&#160;\u00bb<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab&#160;&#160;Il s&rsquo;agit d\u00e9sormais de miser sur nos propres forces.&#160;&#160;\u00bb<\/p>\n<p>Le 27 janvier, lors d&rsquo;une conf\u00e9rence organis\u00e9e \u00e0 Berlin par le journal Die Welt, le ministre allemand des Finances et vice-chancelier du gouvernement de Friedrich Metz a annonc\u00e9 ce qui pourrait devenir une r\u00e9volution dans la gouvernance europ\u00e9enne&#160;&#160;: la poursuite active d&rsquo;une Europe \u00e0 deux vitesses pour avancer sur quelques sujets clefs. <\/p>\n","protected":false},"author":40,"featured_media":315649,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":3,"footnotes":""},"categories":[1731],"tags":[],"staff":[],"editorial_format":[4942],"serie":[],"audience":[],"geo":[1917],"class_list":["post-315647","post","type-post","status-publish","format-standard","hentry","category-politique","editorial_format-actu-breves","geo-europe"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":315649,"excerpt":"\u00abIl s'agit d\u00e9sormais de miser sur nos propres forces.\u00bb\r\n\r\nLe 27 janvier, lors d'une conf\u00e9rence organis\u00e9e \u00e0 Berlin par le journal Die Welt, le ministre allemand des Finances et vice-chancelier du gouvernement de Friedrich Metz a annonc\u00e9 ce qui pourrait devenir une r\u00e9volution dans la gouvernance europ\u00e9enne : la poursuite active d'une Europe \u00e0 deux vitesses pour avancer sur quelques sujets clefs. ","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le plan Klingbeil pour une Europe des six<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/02\/le-plan-klingbeil-pour-une-europe-des-six\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le plan Klingbeil pour une Europe des six\" \/>\n<meta property=\"og:description\" content=\"\u00ab&#160;Il s&#039;agit d\u00e9sormais de miser sur nos propres forces.&#160;\u00bb  Le 27 janvier, lors d&#039;une conf\u00e9rence organis\u00e9e \u00e0 Berlin par le journal Die Welt, le ministre allemand des Finances et vice-chancelier du gouvernement de Friedrich Metz a annonc\u00e9 ce qui pourrait devenir une r\u00e9volution dans la gouvernance europ\u00e9enne&#160;: la poursuite active d&#039;une Europe \u00e0 deux vitesses pour avancer sur quelques sujets clefs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/02\/le-plan-klingbeil-pour-une-europe-des-six\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-02T05:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/Capture-decran-2026-02-01-a-22.10.05.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1828\" \/>\n\t<meta property=\"og:image:height\" content=\"1038\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ramona Bloj\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/Capture-decran-2026-02-01-a-22.10.05.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ramona Bloj\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/02\/le-plan-klingbeil-pour-une-europe-des-six\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/02\/le-plan-klingbeil-pour-une-europe-des-six\/\",\"name\":\"Le plan Klingbeil pour une Europe des six\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/02\/le-plan-klingbeil-pour-une-europe-des-six\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/02\/le-plan-klingbeil-pour-une-europe-des-six\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/Capture-decran-2026-02-01-a-22.10.48.png\",\"datePublished\":\"2026-02-02T05:30:00+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/bee86896b403754f76b6b1515ff0b697\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/02\/le-plan-klingbeil-pour-une-europe-des-six\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/02\/le-plan-klingbeil-pour-une-europe-des-six\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/02\/le-plan-klingbeil-pour-une-europe-des-six\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/Capture-decran-2026-02-01-a-22.10.48.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/Capture-decran-2026-02-01-a-22.10.48.png\",\"width\":1814,\"height\":1012},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/02\/le-plan-klingbeil-pour-une-europe-des-six\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le plan Klingbeil pour une Europe des six\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/bee86896b403754f76b6b1515ff0b697\",\"name\":\"Ramona Bloj\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c1d91adb7c4c1eed266b81c0f9915707?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c1d91adb7c4c1eed266b81c0f9915707?s=96&d=mm&r=g\",\"caption\":\"Ramona Bloj\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le plan Klingbeil pour une Europe des six","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/02\/le-plan-klingbeil-pour-une-europe-des-six\/","og_locale":"fr_FR","og_type":"article","og_title":"Le plan Klingbeil pour une Europe des six","og_description":"\u00ab&#160;Il s'agit d\u00e9sormais de miser sur nos propres forces.&#160;\u00bb  Le 27 janvier, lors d'une conf\u00e9rence organis\u00e9e \u00e0 Berlin par le journal Die Welt, le ministre allemand des Finances et vice-chancelier du gouvernement de Friedrich Metz a annonc\u00e9 ce qui pourrait devenir une r\u00e9volution dans la gouvernance europ\u00e9enne&#160;: la poursuite active d'une Europe \u00e0 deux vitesses pour avancer sur quelques sujets clefs.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/02\/le-plan-klingbeil-pour-une-europe-des-six\/","og_site_name":"Le Grand Continent","article_published_time":"2026-02-02T05:30:00+00:00","og_image":[{"width":1828,"height":1038,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/Capture-decran-2026-02-01-a-22.10.05.png","type":"image\/png"}],"author":"Ramona Bloj","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/Capture-decran-2026-02-01-a-22.10.05.png","twitter_misc":{"\u00c9crit par":"Ramona Bloj","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/02\/le-plan-klingbeil-pour-une-europe-des-six\/","url":"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/02\/le-plan-klingbeil-pour-une-europe-des-six\/","name":"Le plan Klingbeil pour une Europe des six","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/02\/le-plan-klingbeil-pour-une-europe-des-six\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/02\/le-plan-klingbeil-pour-une-europe-des-six\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/Capture-decran-2026-02-01-a-22.10.48.png","datePublished":"2026-02-02T05:30:00+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/bee86896b403754f76b6b1515ff0b697"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/02\/le-plan-klingbeil-pour-une-europe-des-six\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2026\/02\/02\/le-plan-klingbeil-pour-une-europe-des-six\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/02\/le-plan-klingbeil-pour-une-europe-des-six\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/Capture-decran-2026-02-01-a-22.10.48.png","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/Capture-decran-2026-02-01-a-22.10.48.png","width":1814,"height":1012},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/02\/le-plan-klingbeil-pour-une-europe-des-six\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Le plan Klingbeil pour une Europe des six\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/bee86896b403754f76b6b1515ff0b697","name":"Ramona Bloj","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c1d91adb7c4c1eed266b81c0f9915707?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c1d91adb7c4c1eed266b81c0f9915707?s=96&d=mm&r=g","caption":"Ramona Bloj"}}]}},"lgc_categories":[{"id":1731,"name":"Politique","slug":"politique"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/Capture-decran-2026-02-01-a-22.10.48.png","width":1814,"height":1012,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/315647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=315647"}],"version-history":[{"count":2,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/315647\/revisions"}],"predecessor-version":[{"id":315651,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/315647\/revisions\/315651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/315649"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=315647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=315647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=315647"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=315647"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=315647"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=315647"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=315647"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=315647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}