{"id":315592,"date":"2026-02-01T06:00:00","date_gmt":"2026-02-01T05:00:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=315592"},"modified":"2026-02-02T12:00:04","modified_gmt":"2026-02-02T11:00:04","slug":"est-il-possible-de-rapprocher-trump-de-lordre-nazi-les-reponses-de-chapoutot","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/01\/est-il-possible-de-rapprocher-trump-de-lordre-nazi-les-reponses-de-chapoutot\/","title":{"rendered":"Est-il possible de rapprocher Trump de l\u2019ordre nazi&#160;? Les r\u00e9ponses de Chapoutot"},"content":{"rendered":"\n<p class=\"non-subscribers-only\"><em>Vous nous suivez, vous nous lisez pour essayer de comprendre ce qui se joue aujourd&rsquo;hui dans l&rsquo;ombre du spectacle de la cruaut\u00e9 de Washington \u00e0 Moscou en passant par P\u00e9kin&#160;? C&rsquo;est peut-\u00eatre le moment de sauter le pas pour nous soutenir et d\u00e9couvrir toute notre production <a href=\"https:\/\/legrandcontinent.eu\/fr\/offre-abonnement\/\">en s&rsquo;abonnant au Grand Continent<\/a><\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">De plus en plus d\u2019observateurs proposent des analogies entre le Troisi\u00e8me Reich et l\u2019Am\u00e9rique trumpiste \u2014 ou entre celle-ci et l\u2019Italie fasciste. Ces rapprochements sont-ils pertinents, ou bien r\u00e9v\u00e8lent-ils plut\u00f4t quelque chose de la mani\u00e8re dont les fascismes du XXe si\u00e8cle sont appr\u00e9hend\u00e9s au XXIe si\u00e8cle par la m\u00e9moire sociale&#160;?&nbsp;<\/h3>\n\n\n\n<p>Ce qui m\u2019interpelle aujourd\u2019hui, ce n\u2019est pas tant que les adversaires de Trump invoquent le Troisi\u00e8me Reich \u2014 le discours critique, d\u2019opposition, le fait r\u00e9guli\u00e8rement et non sans arguments \u2014 mais que certains des acteurs MAGA eux-m\u00eames revendiquent <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/12\/18\/nick-fuentes-maga\/\">une filiation explicite avec le nazisme<\/a>, dans leur langage, leur rh\u00e9torique, leur phras\u00e9ologie, voire leur apparence. Cela va jusqu\u2019\u00e0 la coupe de cheveux et au port de l\u2019uniforme. L\u2019exemple de Gregory Bovino, officier du DHS et de l\u2019ICE, est frappant&#160;: il adopte les codes visuels de la SA, et les affiche avec fiert\u00e9.<\/p>\n\n\n\n<p>Cela signifie une chose&#160;: pour une partie de l\u2019extr\u00eame droite am\u00e9ricaine contemporaine, le Troisi\u00e8me Reich est valoris\u00e9, admir\u00e9, per\u00e7u comme un mod\u00e8le. Ce n\u2019est pas une simple ignorance historique, mais une adh\u00e9sion partielle ou totale \u00e0 l\u2019imaginaire que les nazis ont su construire autour d\u2019eux. Cette autosc\u00e9narisation nazie \u2014 d\u00e9lib\u00e9r\u00e9e \u2014 a \u00e9t\u00e9 pens\u00e9e pour inscrire une forme de mythe nazi dans la longue dur\u00e9e.<\/p>\n\n\n\n<p>Goebbels le dit dans sa derni\u00e8re conf\u00e9rence de presse, fin avril 1945&#160;: \u00ab&#160;Nous allons mourir, mais nous vivrons pendant mille ans.&#160;\u00bb Le r\u00e9gime n\u2019a pas dur\u00e9 mille ans, mais le mythe, lui, a bien surv\u00e9cu. Et il infuse aujourd\u2019hui certains imaginaires politiques.<\/p>\n\n\n\n<p>On assiste \u00e0 une transmission m\u00e9morielle active, souvent d\u00e9form\u00e9e. Des figures comme Elon Musk ou Steve Bannon ont fait des saluts nazis, tenu des propos ou relay\u00e9 des symboles directement issus de cette culture politique.<\/p>\n\n\n\n<p><a href=\"https:\/\/legrandcontinent.eu\/fr\/2021\/11\/24\/etre-antimoderne-na-pas-grand-sens-une-conversation-avec-johann-chapoutot\/\">Le Troisi\u00e8me Reich est devenu une r\u00e9f\u00e9rence centrale<\/a>, y compris dans les discours de certains agents f\u00e9d\u00e9raux ou figures m\u00e9diatiques proches de l\u2019extr\u00eame droite. Il suffit aujourd\u2019hui de simuler une condamnation morale du nazisme tout en reprenant ses codes, pour que cela passe, ou de s\u2019offusquer de \u00ab&#160;l\u2019amalgame&#160;\u00bb d\u2019une \u00ab&#160;gauche&#160;\u00bb forc\u00e9ment de mauvaise foi quand elle reconna\u00eet un salut nazi dans le bras tendu d\u2019un supr\u00e9maciste blanc, connu pour ses sorties racistes, masculinistes et antis\u00e9mites, et pour avoir <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/11\/20\/pourquoi-grok-lia-du-reseau-social-delon-musk-x-ex-twitter-est-il-negationniste\/\">transform\u00e9 Twitter en un relais de l\u2019extr\u00eame-droite<\/a>.<\/p>\n\n\n\n<p>Dans ce contexte, l\u2019antis\u00e9mitisme pose moins probl\u00e8me que <a href=\"https:\/\/legrandcontinent.eu\/fr\/2020\/01\/24\/une-conversation-avec-annette-wieviorka\/\">la Shoah<\/a>, d\u00e9licate \u00e0 revendiquer ou \u00e0 \u00ab&#160;assumer&#160;\u00bb, selon un mot en vogue. La premi\u00e8re mani\u00e8re de se laver de cette macule est le n\u00e9gationnisme, toujours tr\u00e8s actif sur les marges, de plus en plus larges, de l\u2019extr\u00eame droite. La seconde, la plus f\u00e9conde ces temps-ci, est le r\u00e9visionnisme, au sens strict&#160;: il s\u2019agit de r\u00e9viser et de modifier l\u2019histoire du nazisme, en pr\u00e9tendant que celui-ci serait de gauche, pour faire porter la culpabilit\u00e9 sur autre chose que la droite et l\u2019extr\u00eame droite.<\/p>\n\n\n\n<p>D\u2019autres r\u00e9visionnismes sont aussi \u00e0 l&rsquo;\u0153uvre&#160;; certains disculpent Hitler de la Shoah en incriminant le grand mufti de J\u00e9rusalem. Ce sont des propos qu\u2019on peut entendre du c\u00f4t\u00e9 de l\u2019extr\u00eame droite isra\u00e9lienne, y compris dans la bouche de Benyamin Netanyahou. Le gouvernement f\u00e9d\u00e9ral allemand lui-m\u00eame avait d\u00fb intervenir pour r\u00e9futer ces atrocit\u00e9s.<\/p>\n\n\n\n<p>De mani\u00e8re g\u00e9n\u00e9rale, tous valorisent la vertu patriotique, les qualit\u00e9s techniques ou organisationnelles du r\u00e9gime, en minorant sa violence structurelle.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Il existe une m\u00e9moire sp\u00e9cifique du nazisme aux \u00c9tats-Unis. Depuis la chute du Troisi\u00e8me Reich, c\u2019est l\u2019un des pays o\u00f9 les n\u00e9o-nazis sont les plus visibles, notamment gr\u00e2ce \u00e0 la libert\u00e9 d\u2019expression. En parall\u00e8le, les \u00c9tats-Unis se pr\u00e9sentent aussi comme les grands vainqueurs du nazisme \u2014 dans la culture populaire, les manuels scolaires, les <em>comics<\/em>. Sentez-vous l\u2019empreinte de ces deux m\u00e9moires parall\u00e8les \u2014 et contradictoires \u2014 dans les discours trumpistes&#160;?<\/h3>\n\n\n\n<p>La Seconde Guerre mondiale est repr\u00e9sent\u00e9e de mani\u00e8re tr\u00e8s singuli\u00e8re aux \u00c9tats-Unis. On l\u2019a vu dans certaines d\u00e9clarations de Trump \u2014 par exemple lorsqu\u2019il dit au chancelier Friedrich Merz que le jour du D\u00e9barquement fut une \u00ab&#160;sale journ\u00e9e pour vous&#160;\u00bb. Ce dernier avait d\u00fb r\u00e9pondre vertement \u00e0 Trump que c\u2019\u00e9tait au contraire un jour de lib\u00e9ration\u2026<\/p>\n\n\n\n<p>La sortie du pr\u00e9sident am\u00e9ricain est r\u00e9v\u00e9latrice d\u2019un imaginaire propre \u00e0 l\u2019extr\u00eame droite am\u00e9ricaine dans lequel les nazis et les Allemands sont en quelque sorte dissoci\u00e9s&#160;: c\u2019est contre \u00ab&#160;les Allemands&#160;\u00bb que les \u00c9tats-Unis auraient combattu, mais aujourd\u2019hui, certains discours, y compris chez les officiels, n\u2019ont aucun mal \u00e0 valoriser les g\u00e9n\u00e9raux de Hitler, l\u2019efficacit\u00e9 militaire de la Wehrmacht, ou encore la bravoure de la SS.<\/p>\n\n\n\n<p>Cette confusion alimente une mythologie&#160;: celle d\u2019un r\u00e9gime total, puissant, efficace, qui aurait tenu t\u00eate au monde entier. Ce r\u00e9cit pla\u00eet \u00e9videmment \u00e0 la mouvance supr\u00e9maciste blanche, qui y trouve un mod\u00e8le de r\u00e9g\u00e9n\u00e9ration politique, raciale et civilisationnelle. L\u2019admiration pour la \u00ab&#160;grandeur&#160;\u00bb de l\u2019Allemagne nazie, d\u00e9barrass\u00e9e de ses crimes, devient ainsi un moteur identitaire.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Aujourd\u2019hui, certains des acteurs MAGA revendiquent une filiation explicite avec le nazisme \u2014 dans leur langage, leur rh\u00e9torique, leur phras\u00e9ologie, voire leur apparence.<\/p><cite>Johann Chapoutot<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Les nazis ont profess\u00e9 leur admiration pour ce qu&rsquo;ils se repr\u00e9sentaient des \u00c9tats-Unis&#160;: une nation de souche germanique, colonisant son biotope \u00e0 l\u2019\u00e9chelle d\u2019un continent, exterminant les autochtones, r\u00e9it\u00e9rant le geste antique de l\u2019esclavage, prot\u00e9geant son sang par la s\u00e9gr\u00e9gation\u2026 Comme le dit James Whitman, il y eut bien un \u00ab&#160;mod\u00e8le am\u00e9ricain d\u2019Hitler&#160;\u00bb. Pierre Birnbaum rappelle, dans <em>Les larmes de l\u2019histoire<\/em>, l&rsquo;importance qu&rsquo;a pu avoir le supr\u00e9macisme racial aux \u00c9tats-Unis \u2014 le darwinisme social, le racisme et l&rsquo;antis\u00e9mitisme en \u00e9tant les expressions les plus meurtri\u00e8res. Ces traits s&rsquo;observent encore aujourd&rsquo;hui.<\/p>\n\n\n\n<p>Aujourd&rsquo;hui, le philos\u00e9mitisme d\u2019une partie de la droite am\u00e9ricaine est en v\u00e9rit\u00e9 profond\u00e9ment antis\u00e9mite&#160;; si celle-ci t\u00e9moigne un soutien inconditionnel \u00e0 l\u2019extr\u00eame droite isra\u00e9lienne et \u00e0 ses crimes, son adh\u00e9sion aux proph\u00e9ties des \u00e9vang\u00e9listes commandant le soutien \u00e0 Isra\u00ebl occulte un fait fondamental&#160;: l&rsquo;accomplissement de ces proph\u00e9ties doit passer par la <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/10\/26\/le-nouvel-antisemitisme\/\">conversion des Juifs, qui est un trope de l&rsquo;antis\u00e9mitisme chr\u00e9tien<\/a>.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Pourriez-vous revenir sur le r\u00f4le que joue la violence dans l\u2019\u00e9laboration de l\u2019ordre nazi&#160;?&nbsp;<\/h3>\n\n\n\n<p>Tout d\u2019abord, il faut comprendre que le nazisme s\u2019emploie \u00e0 syst\u00e9matiquement violenter les normes juridiques et les institutions existantes. Cette volont\u00e9 de transgresser l\u2019ordre juridique lib\u00e9ral s\u2019exprime tr\u00e8s t\u00f4t, et de fa\u00e7on spectaculaire, dans l\u2019espace public allemand.<\/p>\n\n\n\n<p>Le paroxysme de la violence nazie dans la rue survient \u00e0 l\u2019\u00e9t\u00e9 1932, lors de la campagne \u00e9lectorale pour les \u00e9lections au Reichstag. Dans une volont\u00e9 de rapprochement tactique avec les nazis, le gouvernement lib\u00e9ral-autoritaire dirig\u00e9 par Franz von Papen, commet l\u2019erreur majeure de lever l\u2019interdiction qui pesait sur la SA et la SS, une mesure prise un mois plus t\u00f4t par le chancelier Br\u00fcning. Cette r\u00e9autorisation entra\u00eene une explosion de violences en juillet 1932, qui fait pr\u00e8s d\u2019une centaine de morts.<\/p>\n\n\n\n<p>Mais celle-ci n\u2019eut pas l\u2019effet escompt\u00e9. Loin de rapprocher les nazis du pouvoir, ces violences ont un impact \u00e9lectoral n\u00e9gatif, en particulier sur l\u2019\u00e9lectorat bourgeois, r\u00e9cemment acquis au NSDAP et avant tout soucieux d\u2019ordre, de stabilit\u00e9 et de prosp\u00e9rit\u00e9 \u00e9conomique. Le massacre d\u2019Altona, le 17 juillet 1932, au cours duquel dix-huit personnes trouvent la mort en une apr\u00e8s-midi, provoque une inqui\u00e9tude r\u00e9elle.&nbsp;<\/p>\n\n\n\n<p>Autrement dit, la violence n\u2019est pas d\u00e9terminante dans l\u2019entr\u00e9e d\u2019Hitler au gouvernement. Comme je l\u2019ai montr\u00e9 dans <em>Les Irresponsables<\/em>, l\u2019arriv\u00e9e d\u2019Hitler \u00e0 la chancellerie r\u00e9sulte d\u2019un calcul des forces conservatrices, en particulier de von Papen, qui estime que face \u00e0 la mont\u00e9e continue de la gauche, surtout des communistes, une alliance avec l\u2019extr\u00eame droite est strat\u00e9giquement pr\u00e9f\u00e9rable.<\/p>\n\n\n\n<p>Lorsque le gouvernement Hitler est form\u00e9 en janvier 1933, les nazis y occupent une place en r\u00e9alit\u00e9 tr\u00e8s limit\u00e9e. Le cabinet compte seulement deux ministres nazis sur neuf. Hitler est nomm\u00e9 chancelier, mais von Papen reste vice-chancelier. Wilhelm Frick h\u00e9rite du minist\u00e8re de l\u2019Int\u00e9rieur, une fonction relativement marginale \u00e0 l\u2019\u00e9chelle du Reich, la police relevant essentiellement des <em>L\u00e4nder<\/em>. \u00c0 ces neuf ministres s\u2019ajoute Hermann G\u00f6ring, qui n\u2019a pas de portefeuille, mais qui a l\u2019habilet\u00e9 de se faire nommer commissaire du Reich au minist\u00e8re de l\u2019Int\u00e9rieur en Prusse.<\/p>\n\n\n\n<p>C\u2019est essentiel car la Prusse constitue les deux tiers du territoire du Reich. Son minist\u00e8re de l\u2019Int\u00e9rieur supervise la principale force de police du pays, soit environ 90 000 agents, la moiti\u00e9 des effectifs policiers allemands.<\/p>\n\n\n\n<p>G\u00f6ring peut ainsi restructurer en profondeur l\u2019appareil administratif et policier prussien de mani\u00e8re m\u00e9thodique et cibl\u00e9e. Tous les r\u00e9publicains, y compris ceux qui ne sont pas de gauche, sont \u00e9vinc\u00e9s. Ils sont remplac\u00e9s par des fonctionnaires r\u00e9put\u00e9s fiables&#160;: on y trouve des opportunistes&#160;; des hommes qui ont d\u00e9j\u00e0 des liens avec le NSDAP, comme Arthur Nebe ou Rudolf Diels&#160;; et, \u00e9videmment, des membres du parti eux-m\u00eames.&nbsp;<\/p>\n\n\n\n<p>D\u00e8s f\u00e9vrier 1933, G\u00f6ring encourage explicitement l\u2019ensauvagement des forces de l\u2019ordre&#160;: en tant que chef, il assume l\u2019usage de la violence par ses hommes et leur assure leur couverture. Il affirme que toute balle tir\u00e9e par un policier prussien est une balle tir\u00e9e par lui-m\u00eame, que les bavures sont non seulement tol\u00e9r\u00e9es mais attendues, et que des sanctions ne frapperont que les cas de manque de violence, non les exc\u00e8s.<\/p>\n\n\n\n<p>Plusieurs circulaires incitent aussi la police \u00e0 coop\u00e9rer \u00e9troitement avec les organisations paramilitaires nationalistes \u2014 Stahlhelm, Jeunesses hitl\u00e9riennes, SA, SS \u2014 afin de r\u00e9primer sans d\u00e9lai, et avec un usage syst\u00e9matique des armes \u00e0 feu, toutes les associations qualifi\u00e9es d\u2019\u00ab&#160;anti-nationales&#160;\u00bb&#160;: syndicats, organisations social-d\u00e9mocrates ou communistes.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Les ann\u00e9es 1920 sont marqu\u00e9es par une sorte de frustration, une volont\u00e9 de rattrapage. L\u2019id\u00e9e se r\u00e9pand que la violence est la texture m\u00eame de l\u2019histoire et de la vie.<\/p><cite>Johann Chapoutot<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Cette orientation est formalis\u00e9e dans deux d\u00e9crets majeurs. Le premier, dat\u00e9 du 17 f\u00e9vrier 1933, instaure une forme de permis de tuer avec pr\u00e9somption de l\u00e9gitime d\u00e9fense et immunit\u00e9 totale pour les agents. Le second d\u00e9cret, celui du 22 f\u00e9vrier, organise le recrutement de 50 000 policiers auxiliaires en Prusse, tous issus des rangs de la SA et de la SS. Ces auxiliaires, rev\u00eatus de leurs uniformes nazis arborent un brassard blanc frapp\u00e9 de l\u2019inscription <em>Hilfspolizei<\/em> (\u00ab&#160;police auxiliaire&#160;\u00bb), re\u00e7oivent l\u2019ensemble des pouvoirs policiers.<\/p>\n\n\n\n<p>On imagine ais\u00e9ment ce que peut faire, dans un quartier, un SA ainsi l\u00e9gitim\u00e9, disposant de la force publique, face aux communistes ou sociaux-d\u00e9mocrates qu\u2019il peut identifier pour les avoir affront\u00e9s au cours de la d\u00e9cennie \u00e9coul\u00e9e. Ces deux d\u00e9crets catalysent une vague massive de violences.&nbsp;<\/p>\n\n\n\n<p>Durant la premi\u00e8re ann\u00e9e du nazisme au pouvoir, environ 100 000 personnes sont incarc\u00e9r\u00e9es, majoritairement dans des camps de concentration. Ces premiers camps sont dits <em>Wilde KL<\/em> (\u00ab&#160;camps sauvages&#160;\u00bb). Il peut s\u2019agir d\u2019un hangar, d\u2019une brasserie d\u00e9saffect\u00e9e, d\u2019un cin\u00e9ma r\u00e9quisitionn\u00e9 \u2014 o\u00f9 la SA enferme des prisonniers pour quelques jours, quelques semaines ou plusieurs mois. Ces d\u00e9tenus y sont tabass\u00e9s, parfois tu\u00e9s. Les chiffres fiables sur les morts manquent, mais les estimations tournent autour de 600 victimes pour 1933.<\/p>\n\n\n\n<p>D\u00e8s les premi\u00e8res semaines qui suivent l\u2019arriv\u00e9e d\u2019Hitler \u00e0 la chancellerie, le r\u00e9gime incite \u00e0 la violence, la l\u00e9galise de fait, et adresse des signaux clairs \u00e0 la justice pour qu\u2019elle s\u2019abstienne d\u2019intervenir. Et les parquets, tr\u00e8s rapidement, comprennent qu\u2019il n\u2019est pas opportun d\u2019enqu\u00eater. Cette d\u00e9mission morale des procureurs est un des faits marquants de 1933.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Dans sa s\u00e9rie de discours, G\u00f6ring prend sur lui la violence pratiqu\u00e9e par ses hommes&#160;; il la dit sienne. N\u2019est pas exactement le renversement op\u00e9r\u00e9 par Benito Mussolini le 3 janvier 1926, lors de son discours apr\u00e8s l&rsquo;assassinat de Matteotti&#160;: \u00ab&#160;Si le fascisme a \u00e9t\u00e9 une association de criminels, je suis le chef de cette association de criminels.&#160;\u00bb&#160;? Est-ce l\u00e0 une r\u00e9f\u00e9rence pour G\u00f6ring&#160;?<\/h3>\n\n\n\n<p>Ni les textes normatifs, ni les discours ne font de r\u00e9f\u00e9rence explicite \u00e0 Mussolini, ni ne le citent. Il s\u2019agit pourtant bien de la m\u00eame id\u00e9e, \u00e0 ceci pr\u00e8s que Mussolini fait sa d\u00e9claration a posteriori&#160;; il se met \u00e0 la t\u00eate d&rsquo;un mouvement qui a prosp\u00e9r\u00e9 sans lui et qu&rsquo;il r\u00e9cup\u00e8re pour \u00e9viter qu\u2019il ne lui \u00e9chappe.<\/p>\n\n\n\n<p>G\u00f6ring, lui, est \u00e0 l\u2019initiative&#160;: il l\u2019est d\u2019autant plus qu\u2019il sait tr\u00e8s bien qu&rsquo;en arrivant \u00e0 la t\u00eate de l&rsquo;administration prussienne, il est en territoire ennemi. La Prusse a \u00e9t\u00e9 gouvern\u00e9e pendant treize ans par la \u00ab&#160;coalition de Weimar&#160;\u00bb&#160;; le dernier ministre-pr\u00e9sident \u00e9tait un social-d\u00e9mocrate, Otto Braun, de m\u00eame que le pr\u00e9fet de police, le ministre de l&rsquo;Int\u00e9rieur, etc. De ce point de vue, l\u2019activisme de G\u00f6ring en 1933, est un rouage essentiel dans la \u00ab&#160;prise du pouvoir par les nazis&#160;\u00bb qui ne d\u00e9signe pas le 30 janvier, mais bien les mois qui vont de f\u00e9vrier \u00e0 juillet, o\u00f9 tout c\u00e8de, plie et se couche en Allemagne, sauf, comme le rel\u00e8ve l\u2019ambassadeur Andr\u00e9 Fran\u00e7ois-Poncet, les communistes.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Le discours de G\u00f6ring marque aussi une rupture dans l\u2019ordre rh\u00e9torique de la r\u00e9publique de Weimar. Au c\u0153ur m\u00eame de la rh\u00e9torique et de la pens\u00e9e nazie, on trouve au contraire l&rsquo;id\u00e9e que la violence a pour fonction de remodeler la soci\u00e9t\u00e9. Quelles sont les sources de cette doctrine cherchant \u00e0 fa\u00e7onner un \u00ab&#160;homme nouveau&#160;\u00bb, n\u00e9 de la violence&#160;?<\/h3>\n\n\n\n<p>Il faut remonter un peu plus haut pour comprendre cette id\u00e9e de violence&#160;; il convient de conduire une forme d\u2019anthropologie historique.<\/p>\n\n\n\n<p>La Grande Guerre est l&rsquo;avant-veille de la s\u00e9quence qui nous int\u00e9resse. Deux g\u00e9n\u00e9rations de nazis l\u2019ont connue, celle des v\u00e9t\u00e9rans, dont Hitler et G\u00f6ring font partie \u2014 le second \u00e9tant l\u2019un des rares titulaires de l\u2019ordre \u00ab&#160;Pour le M\u00e9rite&#160;\u00bb \u2014 et celle que les historiens appellent la g\u00e9n\u00e9ration de la jeunesse de guerre (<em>Kriegsjugendgeneration<\/em>). Himmler et Goebbels font partie de cette seconde g\u00e9n\u00e9ration, car ils \u00e9taient trop jeunes pour servir. Goebbels est handicap\u00e9 et d\u00e9clar\u00e9 inapte au service, et Himmler, en formation \u00e0 l\u2019\u00e9t\u00e9 1918, est d\u00e9mobilis\u00e9 avant d\u2019avoir rejoint le front.<\/p>\n\n\n\n<p>Les ann\u00e9es 1920 sont marqu\u00e9es par une sorte de frustration, une volont\u00e9 de rattrapage. L\u2019id\u00e9e se r\u00e9pand que la violence est la texture m\u00eame de l\u2019histoire et de la vie \u2014 une id\u00e9e que la Grande Guerre aurait confirm\u00e9e, notamment par les formes de socialisation qu\u2019elle a permises. Cette id\u00e9e-l\u00e0 rel\u00e8ve sans conteste d\u2019un certain darwinisme social. En un sens, elle est assez classique.<\/p>\n\n\n\n<p>L\u2019id\u00e9e que <a href=\"https:\/\/legrandcontinent.eu\/fr\/2021\/10\/06\/les-projets-europeens-de-lallemagne-nazie-et-de-litalie-fasciste\/\">la violence est l&rsquo;accoucheuse de l\u2019Histoire<\/a> n\u2019est pas propre aux nazis, mais eux se l\u2019approprient compl\u00e8tement. \u00c0 leurs yeux, la violence est l\u00e9gitime parce que leurs adversaires de gauche, en la condamnant ou en s\u2019en distanciant, se montrent hypocrites \u2014 et sont eux-m\u00eames violents.<\/p>\n\n\n\n<p>Le discours nazi est tr\u00e8s lamentatoire, lacrymal. C\u2019est une constante \u00e0 l\u2019extr\u00eame droite&#160;: les nazis se posent en victimes, en pers\u00e9cut\u00e9s, qu\u2019on a cherch\u00e9 \u00e0 exterminer. Ils mobilisent le vocabulaire de la juste vengeance, du juste retour des choses \u2014 ce que Trump, aujourd\u2019hui, appellerait <em>retribution<\/em>. Pour eux, les autres pensent la m\u00eame chose mais s\u2019en cachent&#160;; eux l\u2019assument et la mettent en actes.<\/p>\n\n\n\n<p>Dans <em>Le Meurtre de Weimar<\/em>&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-315592' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2026\/02\/01\/est-il-possible-de-rapprocher-trump-de-lordre-nazi-les-reponses-de-chapoutot\/#easy-footnote-bottom-1-315592' title='Johann Chapoutot, &lt;em&gt;Le Meurtre de Weimar, &lt;\/em&gt;Paris, PUF, 2015, r\u00e9\u00e9d. 2026.'><sup>1<\/sup><\/a><\/span><\/span>, je traite d\u2019une affaire de l\u2019\u00e9t\u00e9 1932, o\u00f9 cinq membres de la SA sont jug\u00e9s pour avoir tu\u00e9 un homme dans son sommeil. Pour d\u00e9fendre leurs assassins, les nazis rappellent qu\u2019ils contestent radicalement l\u2019\u00e9difice juridique existant \u2014 lib\u00e9ral, socialo-lib\u00e9ral ou jud\u00e9o-lib\u00e9ral, selon l\u2019accent qu\u2019ils veulent faire porter. Ils d\u00e9noncent cet ordre qui pr\u00e9tend \u00eatre objectif sans jamais y parvenir, et se disent eux-m\u00eames tr\u00e8s clairement partisans, sans objectivit\u00e9. Mais ils se vantent de leur sinc\u00e9rit\u00e9 et, \u00e0 l\u2019occasion de ce fait divers sordide, ils contestent non pas seulement la r\u00e8gle de droit concern\u00e9e, mais l\u2019\u00e9difice juridique dans son ensemble \u2014 en retour, ils disent ce qu\u2019ils sont pr\u00eats \u00e0 mettre \u00e0 la place.<\/p>\n\n\n\n<p>Ce qu\u2019ils veulent, c\u2019est remplacer l\u2019\u00e9difice l\u00e9gal existant par une loi du sang. Il s\u2019agit de d\u00e9molir un droit h\u00e9rit\u00e9 de la R\u00e9volution fran\u00e7aise, qu\u2019ils tiennent pour jud\u00e9o-lib\u00e9ral, lib\u00e9ral, individualiste. Ils veulent y substituer un autre principe&#160;: non plus l\u2019individu, mais la communaut\u00e9.<\/p>\n\n\n\n<p>On passe ainsi d\u2019un individualisme juridique \u00e0 un holisme m\u00e9thodologique et syst\u00e9matique. Les normes et le droit sont biologis\u00e9s, bellicis\u00e9s, la seule r\u00e9alit\u00e9 qui existe \u00e9tant celle d\u2019<a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/12\/29\/lebensraum-de-hitler-a-trump-sources-et-genealogie-dun-concept\/\">une guerre biologique<\/a>. Et d\u00e8s lors, le droit ne peut plus \u00eatre d\u00e9fini que comme \u00ab&#160;ce qui sert le peuple allemand&#160;\u00bb, selon la formule donn\u00e9e d\u00e8s 1933 par le juriste nazi Hans Frank.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Avant la prise du pouvoir, comment les diff\u00e9rentes forces politiques allemandes appr\u00e9hendent-elles la violence du parti nazi&#160;?&nbsp;<\/h3>\n\n\n\n<p>Le Parti national-socialiste des travailleurs allemands devient, au tournant de la d\u00e9cennie, la principale force de l\u2019extr\u00eame droite. Mais il n\u2019est pas seul. D\u2019autres formations, comme le Parti populaire national allemand (DNVP) d\u2019Alfred Hugenberg \u2014 un milliardaire des m\u00e9dias \u2014 imitent ou singent les codes du NSDAP. Les membres du DNVP se saluent ainsi d\u2019un \u00ab&#160;Heil Hugenberg&#160;\u00bb, arborent des chemises uniformis\u00e9es, s\u2019entourent d\u2019une garde pr\u00e9torienne\u2026 Ils ne pratiquent pas directement la violence, mais adoptent les postures de la virilit\u00e9 militante.<\/p>\n\n\n\n<p>Du c\u00f4t\u00e9 social-d\u00e9mocrate et communiste, on trouve depuis le d\u00e9but des ann\u00e9es 1920 des organisations paramilitaires associ\u00e9es aux partis&#160;: les Reichsbanner Schwarz-Rot-Gold pour le SPD, le Roter Frontk\u00e4mpferbund (Combattants du Front rouge) pour le KPD. Ces groupes affrontent r\u00e9guli\u00e8rement les SA dans la rue, avec \u00e0 la cl\u00e9 de nombreux bless\u00e9s, et des morts dans leurs rangs.<\/p>\n\n\n\n<p>Entre 1919 et 1922, on recense environ 400 morts li\u00e9s \u00e0 des affrontements politiques. Un tiers sont des nazis&#160;; les deux autres tiers sont des victimes des nazis. \u00c0 lui seul, l\u2019\u00e9t\u00e9 1932 fait cent morts \u2014 sans compter les bless\u00e9s.<\/p>\n\n\n\n<p>Le Zentrum, parti catholique, dispose de ses propres organisations de jeunesse \u2014 notamment confessionnelles \u2014 mais n\u2019a pas de milice comparable. La droite nationaliste, elle, entretient des liens avec une autre organisation paramilitaire&#160;: le Stahlhelm.<\/p>\n\n\n\n<p>Ce qu\u2019il se passe alors en Allemagne ne peut se comprendre sans \u00eatre mis en perspective avec l\u2019exp\u00e9rience de la Grande Guerre. Les dirigeants de la R\u00e9publique de Weimar sont issus d\u2019une g\u00e9n\u00e9ration pour laquelle la violence arm\u00e9e a \u00e9t\u00e9 une norme. La guerre a donn\u00e9 \u00e0 quelque 80 millions d\u2019hommes un permis de tuer, et souvent m\u00eame l\u2019injonction de le faire. L\u2019Allemagne a perdu 2,5 millions de soldats, et compte \u00e0 la sortie du conflit environ 12 millions d\u2019anciens combattants. Dans un pays satur\u00e9 d\u2019armes de guerre, la circulation de ces derni\u00e8res explose apr\u00e8s 1918.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Les nazis veulent remplacer l\u2019\u00e9difice l\u00e9gal existant en Allemagne par une loi du sang. Il s\u2019agit de d\u00e9molir un droit h\u00e9rit\u00e9 de la R\u00e9volution fran\u00e7aise, qu\u2019ils tiennent pour jud\u00e9o-lib\u00e9ral, lib\u00e9ral et individualiste.<\/p><cite>Johann Chapoutot<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Dans ce contexte, le recours \u00e0 la violence est per\u00e7u comme \u00e9tant quelque chose de sinon l\u00e9gitime, du moins de compr\u00e9hensible. C&rsquo;est l\u00e0 le propos de George L. Mosse&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-315592' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2026\/02\/01\/est-il-possible-de-rapprocher-trump-de-lordre-nazi-les-reponses-de-chapoutot\/#easy-footnote-bottom-2-315592' title='George L. Mosse, &lt;em&gt;De la grande guerre au totalitarisme, la brutalisation des soci\u00e9t\u00e9s europ\u00e9ennes&lt;\/em&gt;, Paris, Hachette Litt\u00e9ratures, 1999.'><sup>2<\/sup><\/a><\/span><\/span>&#160;: la soci\u00e9t\u00e9 europ\u00e9enne a connu un processus de brutalisation.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mais d\u2019autres pays europ\u00e9ens ont connu l\u2019exp\u00e9rience de la Premi\u00e8re Guerre mondiale, sans jamais vivre une situation comparable \u00e0 celle de l\u2019Allemagne. Cette diff\u00e9rence des trajectoires entre pays s\u2019expliquerait-elle par l&rsquo;exp\u00e9rience allemande de 1918-1919 \u2014 notamment l\u2019\u00e9crasement des r\u00e9volutions communistes&#160;?&nbsp;<\/h3>\n\n\n\n<p>Il faut aussi compter avec d\u2019autres conflits&#160;; \u00e0 l\u2019Est, la guerre se poursuit apr\u00e8s l\u2019armistice de novembre 1918. Les provinces baltiques de l\u2019Empire russe restent un point chaud jusqu&rsquo;en 1923, et la Sil\u00e9sie jusqu\u2019en 1921 au moins.<\/p>\n\n\n\n<p>L\u2019exp\u00e9rience de la bataille transforme profond\u00e9ment les combattants. Elle les marque \u00e0 un point tel que la d\u00e9mobilisation ne peut pas \u00eatre uniquement \u00e9conomique ou mat\u00e9rielle&#160;; elle est surtout psychique, culturelle \u2014 et elle s\u2019av\u00e8re autrement plus difficile sur ce plan. Pour rendre cela tangible, on peut penser au personnage de Rambo, v\u00e9t\u00e9ran de la guerre de Cor\u00e9e, incapable de retrouver une vie civile ordinaire. Ce que raconte <em>First Blood<\/em>, c\u2019est cela&#160;: le retour impossible \u00e0 la vie civile, \u00e0 la civilit\u00e9, \u00e0 la paix.<\/p>\n\n\n\n<p>Sur le front, les soldats se sont socialis\u00e9s autrement&#160;: dans l\u2019\u00e9preuve, dans la solidarit\u00e9, dans un entre-soi viril et militaire. Hitler l\u2019a souvent rappel\u00e9, c\u2019\u00e9tait selon lui la p\u00e9riode la plus heureuse de sa vie. Il y a connu les camarades, l\u2019unit\u00e9, une forme d\u2019union simple et totale.&nbsp;<\/p>\n\n\n\n<p>Cette socialisation-l\u00e0 ne dispara\u00eet pas avec l\u2019armistice. Elle se poursuit ailleurs, transpos\u00e9e dans les <em>Freikorps<\/em>, les corps francs, des formations paramilitaires de l\u2019apr\u00e8s-guerre compos\u00e9es d\u2019anciens soldats. Ceux-ci restent ensemble, non plus pour se battre contre la France ou l\u2019Angleterre, mais contre le communisme, contre l\u2019ennemi int\u00e9rieur, contre les ennemis de l\u2019Est \u2014 et cela jusqu\u2019en 1923. Ils restent soud\u00e9s, entre camarades, dans le groupe primaire de combat, et autour de celui \u00e0 qui ils ont fait confiance pour franchir le parapet de la tranch\u00e9e et monter au feu \u2014 leur officier, leur chef, qui a pour nom g\u00e9n\u00e9rique un terme qui m\u00e9tastasera plus tard, celui de \u00ab&#160;F\u00fchrer&#160;\u00bb.<\/p>\n\n\n\n<p>Il faut donc compter avec cette forme de continuit\u00e9 guerri\u00e8re. La guerre ne s\u2019arr\u00eate pas avec la paix. Ce que l\u2019on observe, c\u2019est une poursuite, une r\u00e9orientation de la violence&#160;: on reste en armes, on reste en groupe, on reste dans une logique d\u2019engagement total. La d\u00e9mobilisation psychique, culturelle, affective, n\u2019a pas lieu.<\/p>\n\n\n\n<p>Et \u00e0 cela s\u2019ajoute un autre facteur&#160;: l\u2019Allemagne est alors un pays d\u2019hommes jeunes. Ce n\u2019est pas anodin. Contrairement \u00e0 la France, qui a \u00e9t\u00e9 durablement saign\u00e9e par la guerre, l\u2019Allemagne dispose d\u2019une r\u00e9serve d\u00e9mographique consid\u00e9rable. La France, d\u00e9j\u00e0 vieillissante en 1914, compte alors environ 40 millions d\u2019habitants \u2014 c\u2019est \u00e0 peu pr\u00e8s la population de l\u2019Allemagne au moment de son unification en 1871. En 1914, l\u2019Allemagne, elle, compte 67 millions d\u2019habitants. En un peu plus de quarante ans, sa population a augment\u00e9 de 70&#160;%.<\/p>\n\n\n\n<p>Cela change tout. Le pays est jeune, d\u00e9mographiquement dynamique, et sa jeunesse a \u00e9t\u00e9 socialis\u00e9e par la guerre \u2014 et dans la guerre. Elle est nombreuse, disponible et souvent frustr\u00e9e&#160;; elle \u00e9volue dans une culture qui, plus encore que dans d\u2019autres soci\u00e9t\u00e9s europ\u00e9ennes, exalte la guerre&#160;: non pas comme une n\u00e9cessit\u00e9 ponctuelle, mais comme une vertu en soi et comme le substrat et la logique m\u00eames de l\u2019existence.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Apr\u00e8s l\u2019arriv\u00e9e au pouvoir des nazis, la violence qu\u2019exerce la police, ses suppl\u00e9tifs et les organisations nazies est-elle normalis\u00e9e&#160;? Comment r\u00e9agit la majorit\u00e9 de la population&#160;?<\/h3>\n\n\n\n<p>La violence des organisations nazies choque profond\u00e9ment l\u2019opinion, notamment en juillet 1932, bien avant l\u2019arriv\u00e9e des nazis au pouvoir \u2014 je reviens longuement sur ce point dans <em>Les Irresponsables<\/em>. \u00c0 ce moment-l\u00e0, le NSDAP est au sommet de sa popularit\u00e9 et de ses scores&#160;: 37&#160;% des voix aux \u00e9lections du Reichstag.&nbsp;<\/p>\n\n\n\n<p>Mais ce pic est imm\u00e9diatement suivi d\u2019un reflux. Les nazis perdent quatre points aux \u00e9lections suivantes, deux millions d\u2019\u00e9lecteurs, et trente-quatre si\u00e8ges. Et la tendance est encore plus marqu\u00e9e au niveau local&#160;: dans certains L\u00e4nder, le parti perd entre 10 et 40 points. \u00c0 l\u2019automne 1932, il arrive m\u00eame qu\u2019il perde toute repr\u00e9sentation politique dans certaines communes et cantons, comme ray\u00e9 de la carte \u00e9lectorale et du paysage politique.<\/p>\n\n\n\n<p>Ce recul s\u2019explique clairement par les \u00e9pisodes de violence. L\u2019\u00e9lectorat bourgeois ou petit-bourgeois, qui s\u2019\u00e9tait mis \u00e0 voter nazi par haine du marxisme, se met soudain \u00e0 craindre d\u2019en \u00eatre la cible. Il revient alors vers les partis de droite traditionnels, comme le DNVP, le DVP ou la Deutsche Staatspartei, voire le Zentrum et son par\u00e8dre bavarois (BVP).<\/p>\n\n\n\n<p>Face \u00e0 cette d\u00e9sapprobation g\u00e9n\u00e9rale, les nazis comprennent la le\u00e7on. Il en va de m\u00eame pour l\u2019antis\u00e9mitisme. Lui aussi les d\u00e9favorise dans les urnes. Les slogans antis\u00e9mites ou les incitations \u00e0 la violence peuvent s\u00e9duire une base radicalis\u00e9e, bien r\u00e9elle mais g\u00e9ographiquement circonscrite&#160;: la Franconie, une partie de la Bavi\u00e8re, la Thuringe. Mais ces discours sont contre-productifs ailleurs.<\/p>\n\n\n\n<p>Goebbels, entre autres, comprend ce probl\u00e8me et met en place ce qu\u2019il faut bien appeler une op\u00e9ration de marketing politique. On recentre le discours sur des th\u00e8mes plus f\u00e9d\u00e9rateurs, comme la lutte contre le marxisme \u2014 une cat\u00e9gorie fourre-tout dans laquelle les nazis rangent \u00e0 peu pr\u00e8s tout ce qui peut appara\u00eetre comme une menace pour l\u2019ordre social bourgeois&#160;: les communistes, les sociaux-d\u00e9mocrates, les syndicats, y compris les syndicats chr\u00e9tiens. Toute forme de contestation est tax\u00e9e de marxisme, ou de \u00ab&#160;bolchevisme culturel&#160;\u00bb.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Le discours nazi est tr\u00e8s lamentatoire et lacrymal&#160;; les nazis se posent en victimes, en pers\u00e9cut\u00e9s qu\u2019on a cherch\u00e9 \u00e0 exterminer. Ils mobilisent le vocabulaire de la juste vengeance.<\/p><cite>Johann Chapoutot<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Dans cette logique, les nazis mettent un b\u00e9mol sur la violence visible. Ils reprennent en main les SA, mod\u00e8rent leur expression publique, et taisent autant que possible l\u2019antis\u00e9mitisme. Mais cela ne dure qu\u2019un temps. Car apr\u00e8s leur arriv\u00e9e au pouvoir en janvier 1933, les choses changent.<\/p>\n\n\n\n<p>Il faut insister sur les termes&#160;: on parle bien d\u2019une arriv\u00e9e au pouvoir, pas d\u2019une prise de pouvoir. Le 30 janvier 1933, le pouvoir leur est donn\u00e9, alors m\u00eame qu\u2019ils n\u2019y croyaient plus. La prise de pouvoir r\u00e9elle, elle, s\u2019op\u00e8re dans les mois qui suivent \u2014 \u00e0 travers un processus m\u00e9thodique de p\u00e9n\u00e9tration des institutions et de suffocation de l\u2019\u00c9tat de droit.<\/p>\n\n\n\n<p>C\u2019est \u00e0 ce moment que la violence polici\u00e8re se d\u00e9cha\u00eene. Pour reprendre un terme contemporain, on pourrait dire que la police est ensauvag\u00e9e et encourag\u00e9e \u00e0 s\u2019ensauvager, traduction pratique et expression r\u00e9pressive de l\u2019ensauvagement d\u2019\u00e9lites patrimoniales qui ont fait le choix, \u00e9go\u00efste et brutal, de l\u2019alliance avec l\u2019extr\u00eame droite pour \u00e9viter la gauche, la d\u00e9truire, et pr\u00e9server un ordre social qui est le leur. Le pr\u00e9server \u00e0 tout prix&#160;: au prix de violences et de morts qui n\u2019\u00e9mouvaient gu\u00e8re la droite lib\u00e9rale-conservatrice et nationale-autoritaire. Apr\u00e8s tout, les ennemis des nazis \u00e9taient les siens&#160;: socialistes, communistes, syndicalistes et Juifs.<\/p>\n\n\n\n<p>La violence d\u00e9clench\u00e9e par les nazis choque une partie de la population. Les nazis cherchent donc un \u00e9v\u00e9nement qui la l\u00e9gitime.<\/p>\n\n\n\n<p>C\u2019est l\u2019incendie du Reichstag, le 27 f\u00e9vrier 1933. Nous savons aujourd\u2019hui qu\u2019il s\u2019agissait d\u2019un complot interne, con\u00e7u par une partie de la hi\u00e9rarchie nazie. G\u00f6ring y est impliqu\u00e9, tout comme les chefs de la SA de Berlin. Les communistes sont imm\u00e9diatement accus\u00e9s d\u2019\u00eatre les auteurs de l\u2019attentat.<\/p>\n\n\n\n<p>Mais cet incendie n\u2019a rien d\u2019improvis\u00e9. D\u00e8s les premiers jours de f\u00e9vrier, des rumeurs circulent dans les cercles inform\u00e9s \u2014 diplomatiques, politiques, mondains \u2014 \u00e0 propos d\u2019un projet de faux attentat contre Hitler, destin\u00e9 \u00e0 l\u00e9gitimer une vague de r\u00e9pression massive. Dans les journaux intimes, dans les rapports diplomatiques, dans les d\u00eeners en ville, on retrouve des \u00e9chos de cette rumeur. Le nom de code officieux du projet revient souvent&#160;: la \u00ab&#160;Nuit de la Saint-Barth\u00e9lemy&#160;\u00bb.<\/p>\n\n\n\n<p>Finalement, ce n\u2019est pas un faux attentat contre Hitler qui survient, mais l\u2019incendie du Reichstag.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Si le soutien \u00e9lectoral aux nazis est limit\u00e9, de quels autres ralliements ces derniers profitent-ils&#160;?<\/h3>\n\n\n\n<p>Le grand historien Peter Longerich, dans son livre r\u00e9cent <em>Unwillige Volksgenossen<\/em><br>&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-315592' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2026\/02\/01\/est-il-possible-de-rapprocher-trump-de-lordre-nazi-les-reponses-de-chapoutot\/#easy-footnote-bottom-3-315592' title='Peter Longerich, &lt;em&gt;Unwillige Volksgenossen. Wie die Deutschen zum NS-Regime standen. Eine Stimmungsgeschichte, &lt;\/em&gt;Munich, Siedler Verlag, 2025.'><sup>3<\/sup><\/a><\/span><\/span> (\u00ab&#160;Citoyens du Reich malgr\u00e9 eux&#160;\u00bb), montre bien que l\u2019adh\u00e9sion au r\u00e9gime nazi n\u2019\u00e9tait pas du tout ce qu\u2019on imagine g\u00e9n\u00e9ralement. Je partage ses conclusions pour le d\u00e9but de la p\u00e9riode. Si l\u2019on adopte une perspective macro-politique sur l\u2019ann\u00e9e 1933, un constat s\u2019impose&#160;: l\u2019extr\u00eame droite bute syst\u00e9matiquement sur un plafond \u00e9lectoral. Les nazis n\u2019ont jamais d\u00e9pass\u00e9 37&#160;% des suffrages exprim\u00e9s. \u00c0 aucun moment ils ne repr\u00e9sentent une majorit\u00e9, ni m\u00eame une majorit\u00e9 relative suffisante pour gouverner seuls ou faire alliance (le pacte envisag\u00e9 avec le Zentrum \u00e0 l\u2019\u00e9t\u00e9 1932, dans le Reich et en Prusse, achoppe sur les r\u00e9ticences catholiques, encore fortes \u00e0 ce moment-l\u00e0).<\/p>\n\n\n\n<p>L\u2019arriv\u00e9e au pouvoir ne r\u00e9sulte donc pas d\u2019une dynamique purement sociale ou \u00e9lectorale \u2014 celle-ci a des limites nettes \u2014 mais bien d\u2019une d\u00e9cision froide, d\u2019un calcul politique de certains cercles dirigeants. Ce sont eux qui, en janvier 1933, enclenchent la s\u00e9quence. Le basculement du grand capital se fait \u00e0 l\u2019automne 1932, et il est confirm\u00e9 le 20 f\u00e9vrier 1933 quand une trentaine de grands patrons r\u00e9unis autour de Hjalmar Schacht d\u00e9bloquent trois millions de reichsmarks (environ 25 millions d\u2019euros actuels) pour financer la campagne du NSDAP. Quant aux grands propri\u00e9taires terriens, ils sont d\u00e9j\u00e0 nazifi\u00e9s depuis 1930.<\/p>\n\n\n\n<p>Une fois Hitler nomm\u00e9 chancelier, le ralliement de l\u2019arm\u00e9e se fait tr\u00e8s vite. Il ne lui faut que quatre jours. Le 3 f\u00e9vrier 1933, il prononce devant les plus hauts responsables militaires un discours fondateur&#160;: il leur expose ses intentions de conqu\u00eate et de colonisation de l\u2019est europ\u00e9en, et leur promet des moyens in\u00e9dits.<\/p>\n\n\n\n<p>Un autre acteur, \u00e9litaire, aurait pu constituer un contre-pouvoir&#160;: l\u2019\u00c9glise catholique. Elle avait eu, dans le pass\u00e9, des gestes de r\u00e9ticence, voire de r\u00e9sistance, affirm\u00e9s face aux nazis \u2014 dont plusieurs condamnations claires du racisme biologique. Mais l\u2019\u00e9piscopat catholique se r\u00e9signe en un mois et demi, parall\u00e8lement \u00e0 la politique du Vatican, qui signe un concordat avec le Reich, et par l\u00e0, apporte une l\u00e9gitimit\u00e9 symbolique immense au nouveau r\u00e9gime.<\/p>\n\n\n\n<p>Voil\u00e0 pour les choix venus d\u2019en haut. Si l\u2019on regarde maintenant ce qu\u2019il en est de la population dans son ensemble, les donn\u00e9es disponibles <a href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/11\/08\/il-y-a-cent-ans-les-chances-de-succes-dhitler-etaient-fragiles-une-conversation-avec-ian-kershaw\/\">sont bien moins favorables au NSDAP<\/a>. Les \u00e9lections l\u00e9gislatives de janvier 1933 dans le plus petit Land d\u2019Allemagne, celui de Lippe-Detmold, sont brandies comme une victoire par les nazis. En r\u00e9alit\u00e9, leur score y est inf\u00e9rieur \u00e0 celui de juillet 1932.<\/p>\n\n\n\n<p>Quant aux \u00e9lections au Reichstag du 5 mars 1933, c\u2019est un simulacre. Beaucoup d\u2019ouvrages, encore aujourd\u2019hui, les pr\u00e9sentent comme un vote \u00e0 peu pr\u00e8s r\u00e9gulier. C\u2019est faux. Aucun parti n\u2019a pu r\u00e9ellement faire campagne. Dans certains bureaux, les SA accompagnaient les \u00e9lecteurs jusqu\u2019\u00e0 l\u2019isoloir. Le r\u00e9sultat est donc tout sauf libre.<\/p>\n\n\n\n<p>Il existe cependant un indicateur chiffr\u00e9 fiable, souvent n\u00e9glig\u00e9&#160;: les \u00e9lections professionnelles d\u2019avril 1933, organis\u00e9es dans tout le Reich. Les nazis, tr\u00e8s confiants, y engagent leur syndicat, le NSBO. R\u00e9sultat&#160;: ils obtiennent 11,7&#160;%. L\u2019Allgemeiner Deutscher Gewerkschaftsbund (ADGB), centrale syndicale social-d\u00e9mocrate, recueille 73&#160;%, auxquels il faut ajouter les 5&#160;% des communistes, traqu\u00e9s, pers\u00e9cut\u00e9s et assassin\u00e9s&#160;; c\u2019est consid\u00e9rable.<\/p>\n\n\n\n<p>Un autre indicateur de l\u2019hostilit\u00e9 relative de la population concerne le boycott des magasins, m\u00e9decins et avocats juifs, organis\u00e9 le 1er avril 1933. Sur la base d\u2019une vaste documentation \u2014 rapports de la police int\u00e9rieure, t\u00e9l\u00e9grammes diplomatiques, journaux intimes \u2014, je constate que ce boycott a \u00e9t\u00e9 un \u00e9chec&#160;: d\u00e9cid\u00e9ment, l\u2019antis\u00e9mitisme n\u2019est pas porteur. L\u2019\u00e9chec est tel que le boycott est suspendu le soir m\u00eame. Les nazis pr\u00e9tendent pourtant \u00e0 la victoire et annoncent que, gr\u00e2ce \u00e0 cette action, la propagande juive mondiale contre l\u2019Allemagne aurait cess\u00e9.&nbsp;<\/p>\n\n\n\n<p>Tout indique donc que les Allemands, dans leur majorit\u00e9, ne voulaient pas du nazisme. Ce refus ne durera pas, mais il est r\u00e9el dans les premiers mois de 1933. Ce qui change ensuite, ce sont les int\u00e9r\u00eats&#160;: des gens commencent \u00e0 r\u00e9fl\u00e9chir aux profits possibles, \u00e0 la spoliation, \u00e0 la rel\u00e9gation des concurrents, aux conditions de leur propre survie sociale.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>L\u2019autosc\u00e9narisation nazie \u2014 d\u00e9lib\u00e9r\u00e9e \u2014 a \u00e9t\u00e9 pens\u00e9e pour inscrire une forme de mythe nazi dans la longue dur\u00e9e.<\/p><cite>Johann Chapoutot<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Mais si l\u2019opinion peut entrer dans ce type de calcul, c\u2019est bien parce que les \u00e9lites ont c\u00e9d\u00e9 les premi\u00e8res. Andr\u00e9 Fran\u00e7ois-Poncet, ambassadeur de France \u00e0 Berlin en 1933, en donne un t\u00e9moignage accablant. Le 5 avril 1933, il envoie au Quai d\u2019Orsay un rapport politique tr\u00e8s lucide&#160;: il y d\u00e9crit un pays o\u00f9 tout le monde a capitul\u00e9, de la pire mani\u00e8re, sans opposer la moindre r\u00e9sistance. Il d\u00e9plore l\u2019absence totale de colonne vert\u00e9brale. Et il conclut que les seuls \u00e0 se battre, les seuls qui tiennent, ce sont les communistes.&nbsp;<\/p>\n\n\n\n<p>Je distingue une autre raison au manque de r\u00e9action d\u2019une grande majorit\u00e9 des \u00e9lites allemandes&#160;: pendant longtemps, les nazis n\u2019ont pas \u00e9t\u00e9 pris au s\u00e9rieux. Ni leur mouvement, ni leur hi\u00e9rarchie ne faisaient peur. On se moquait assez facilement de G\u00f6ring morphinomane, de Goebbels handicap\u00e9, ou de Hitler \u2014 cet homme venu du sud, \u00e0 l\u2019accent rural, qui semblait, selon l\u2019expression souvent reprise, \u00ab&#160;descendre de sa montagne&#160;\u00bb.<\/p>\n\n\n\n<p>Hitler, en effet, est tr\u00e8s \u00e9loign\u00e9 des standards aristocratiques des \u00e9lites patrimoniales allemandes, prussiennes ou austro-hongroises. Il n\u2019a ni titre nobiliaire, ni dipl\u00f4me universitaire, ni grade militaire \u00e9lev\u00e9. Il n\u2019a pas de nom, pas de lign\u00e9e, pas de fortune, pas de r\u00e9seau h\u00e9rit\u00e9. Il n\u2019a litt\u00e9ralement rien, et c\u2019est pour cette raison qu\u2019il est d\u00e9daign\u00e9 par les \u00e9lites traditionnelles, aussi bien conservatrices que progressistes. Du c\u00f4t\u00e9 de la gauche intellectuelle, on le m\u00e9prise&#160;; du c\u00f4t\u00e9 des Junkers ou de la haute fonction publique, on ne le voit pas comme un pair.<\/p>\n\n\n\n<p>Le 30 janvier 1933, quand Hitler est nomm\u00e9 chancelier, tr\u00e8s peu de journaux, en Allemagne ou \u00e0 l\u2019\u00e9tranger, titrent simplement \u00ab&#160;gouvernement Hitler&#160;\u00bb. Les unes affichent des formules comme \u00ab&#160;gouvernement Hitler, Papen, Hugenberg&#160;\u00bb \u2014 comme si Hitler n\u2019\u00e9tait qu\u2019un des \u00e9l\u00e9ments d\u2019un triumvirat. Il appara\u00eet alors comme un petit homme coinc\u00e9 entre deux g\u00e9ants&#160;: Franz von Papen, ancien chancelier, d\u00e9sormais vice-chancelier, et Alfred Hugenberg, magnat de la presse et chef du DNVP, nomm\u00e9 \u00e0 plusieurs minist\u00e8res dans ce m\u00eame gouvernement.<\/p>\n\n\n\n<p>Papen, en particulier, est convaincu que la situation tourne \u00e0 son avantage. Il pense avoir domestiqu\u00e9 les nazis, qu\u2019il consid\u00e8re comme affaiblis. Le fait que le NSDAP ait d\u00fb se contenter de deux minist\u00e8res et demi \u2014 alors qu\u2019il en r\u00e9clamait six, six mois plus t\u00f4t \u2014 est pour lui un signe de faiblesse. Il estime qu\u2019il saura contr\u00f4ler Hitler, en assistant \u00e0 tous ses rendez-vous avec le pr\u00e9sident Hindenburg en tant que vice-chancelier, et en gardant un \u0153il sur les affaires.<\/p>\n\n\n\n<p>Pour cela, Papen a exig\u00e9 d\u2019\u00eatre nomm\u00e9 commissaire du Reich en Prusse, une fonction normalement d\u00e9volue au chancelier depuis que le gouvernement social-d\u00e9mocrate prussien a \u00e9t\u00e9 suspendu en juillet 1932. Il y voit un signe de sa propre importance dans le gouvernement et de sa capacit\u00e9 \u00e0 contenir les d\u00e9bordements du NSDAP.<\/p>\n\n\n\n<p>C\u2019est dans ce contexte qu\u2019il prononce sa fameuse phrase, devenue tristement c\u00e9l\u00e8bre&#160;: \u00ab&#160;Dans deux mois, nous aurons tellement coinc\u00e9 Hitler qu\u2019il va couiner.&#160;\u00bb<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Si la conqu\u00eate du pouvoir est achev\u00e9e \u00e0 l\u2019\u00e9t\u00e9 1933, la nuit des longs couteaux, \u00e0 l\u2019\u00e9t\u00e9 1934, consolide encore le pouvoir d\u2019Hitler et de son entourage. Quelle est la gen\u00e8se de ce coup interne&#160;?&nbsp;<\/h3>\n\n\n\n<p>Les origines de la Nuit des longs couteaux sont tr\u00e8s int\u00e9ressantes de ce point de vue&#160;; elles montrent la faible adh\u00e9rence de la population au pouvoir \u2014 je ne parle m\u00eame pas d\u2019une adh\u00e9sion. Longerich le montre tr\u00e8s bien en travaillant sur rapports de police&#160;; Norbert Frei \u00e9galement, dans son livre <em>L&rsquo;\u00c9tat hitl\u00e9rien et la soci\u00e9t\u00e9 allemande<\/em>&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-315592' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2026\/02\/01\/est-il-possible-de-rapprocher-trump-de-lordre-nazi-les-reponses-de-chapoutot\/#easy-footnote-bottom-4-315592' title='Norbert Frei, &lt;em&gt;L&amp;rsquo;\u00c9tat hitl\u00e9rien et la soci\u00e9t\u00e9 allemande&lt;\/em&gt;, Paris, Seuil, 1999.'><sup>4<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>Une grande partie de la population vit tr\u00e8s mal qu\u2019une nouvelle caste de parvenus \u00e0 croix gamm\u00e9e s\u2019installe un peu partout&#160;; les nouveaux ma\u00eetres, rapportent les services de renseignement int\u00e9rieurs, font du bruit, sont ivres au restaurant, ne paient pas la note, traversent le village dans leurs bolides&#8230; ce sont des petites frappes qui prennent le pouvoir. La hi\u00e9rarchie nazie est v\u00e9cue comme une bande d\u2019apparatchiks, de profiteurs et de corrompus.<\/p>\n\n\n\n<p>\u00c0 partir du printemps 1934, le contexte devient plus d\u00e9licat encore, car le pr\u00e9sident Hindenburg est mourant. Il faut donc anticiper sa succession. L\u2019id\u00e9e d\u2019une fusion de la chancellerie et de la pr\u00e9sidence du Reich, est \u00e9voqu\u00e9e \u2014 autrement dit, qu\u2019Hitler cumule les deux fonctions&#160;; cela suppose l\u2019accord de l\u2019arm\u00e9e.<\/p>\n\n\n\n<p>Or, si l\u2019arm\u00e9e a bien \u00e9t\u00e9 ralli\u00e9e d\u00e8s le 3 f\u00e9vrier 1933 \u2014 lors du fameux discours o\u00f9 Hitler promet l\u2019expansion, la revanche, et une arm\u00e9e port\u00e9e \u00e0 plusieurs millions d\u2019hommes \u2013, elle reste n\u00e9anmoins vigilante. Elle s\u2019inqui\u00e8te s\u00e9rieusement des pr\u00e9tentions de R\u00f6hm, chef des SA, qui affirme que ses troupes incarnent la v\u00e9ritable arm\u00e9e populaire. En 1933, les SA passent de 400 000 \u00e0 3 millions d\u2019hommes. La question du monopole de la violence l\u00e9gitime se pose alors, y compris dans une dictature en voie de constitution.<\/p>\n\n\n\n<p>Qui contr\u00f4le les armes&#160;? Qui a autorit\u00e9 sur la force&#160;? Qui est, au fond, l\u2019arm\u00e9e&#160;? Ce sont les questions que posent les militaires, et ils exigent qu\u2019Hitler tranche rapidement.<\/p>\n\n\n\n<p>Mais R\u00f6hm ne se contente pas de ses ambitions militaires. Il incarne ce qu\u2019on appelle l\u2019aile sociale du NSDAP, celle qui parle d\u2019une \u00ab&#160;deuxi\u00e8me r\u00e9volution&#160;\u00bb. Pour lui, la premi\u00e8re r\u00e9volution \u2014 celle de la prise de pouvoir \u2014 est d\u00e9j\u00e0 faite. Mais les \u00ab&#160;r\u00e9actionnaires&#160;\u00bb seraient toujours l\u00e0&#160;: von Papen et tous les conservateurs ralli\u00e9s. Il faudrait donc parachever la r\u00e9volution nationale-socialiste en \u00e9cartant les \u00e9l\u00e9ments traditionnels.<\/p>\n\n\n\n<p>Or, pour Hitler, qui repr\u00e9sente l\u2019aile droite du mouvement, il est hors de question de suivre cette ligne. Elle inqui\u00e8te les milieux \u00e9conomiques, elle indispose l\u2019arm\u00e9e. Il d\u00e9cide donc de neutraliser R\u00f6hm et les SA.<\/p>\n\n\n\n<p>La purge est d\u00e9cid\u00e9e dans un petit groupe qui r\u00e9unit Hitler, G\u00f6ring \u2014 devenu depuis avril 1933 ministre-pr\u00e9sident de Prusse, c\u2019est-\u00e0-dire chef de l\u2019ex\u00e9cutif dans le plus grand <em>Land<\/em> du Reich \u2013, et les chefs de la SS, Himmler et Heydrich. Au sein m\u00eame des appareils nazis, la SS r\u00e8gle ainsi son principal probl\u00e8me de concurrence avec la SA, par le meurtre de masse.<\/p>\n\n\n\n<p>La Nuit des longs couteaux, qui s\u2019\u00e9tend du 30 juin au 3 juillet 1934, fait entre 200 et 300 morts. Ce sont, pour l\u2019essentiel, des cadres des SA, mais aussi des figures de la droite \u2014 anciens alli\u00e9s devenus encombrants.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Aux \u00c9tats-Unis, le Troisi\u00e8me Reich est devenu une r\u00e9f\u00e9rence centrale, y compris dans les discours de certains agents f\u00e9d\u00e9raux ou figures m\u00e9diatiques proches de l\u2019extr\u00eame droite.<\/p><cite>Johann Chapoutot<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Comment ont \u00e9t\u00e9 d\u00e9sign\u00e9s, \u00e0 droite, ceux qui devaient \u00eatre \u00e9limin\u00e9s&#160;?<\/h3>\n\n\n\n<p>Il s\u2019agissait d\u2019abord de se venger de tous ceux qui, autour de Kurt von Schleicher, dernier chancelier de la R\u00e9publique de Weimar avant Hitler, avaient tent\u00e9 d\u2019\u00e9viter l\u2019arriv\u00e9e des nazis au pouvoir. Ceux qui avaient tenu bon, ceux qui avaient encore une conscience, ceux qui avaient voulu l\u2019union des droites mais s\u2019\u00e9taient ravis\u00e9s apr\u00e8s les violences de l\u2019\u00e9t\u00e9 1932, jugeant que les nazis \u00e9taient trop instables, trop brutaux, non fiables.<\/p>\n\n\n\n<p>C\u2019est exactement la position de Schleicher. Il est abattu dans son salon, avec son \u00e9pouse. D\u2019autres figures de ce r\u00e9seau sont \u00e9galement liquid\u00e9es. Les plus proches conseillers de Franz von Papen sont \u00e9galement assassin\u00e9s \u2014 ceux-l\u00e0 m\u00eames qui pensaient avoir fait un judicieux calcul arithm\u00e9tique en ajoutant les 10&#160;% de la droite aux \u00e9lections de 1932 et les 33&#160;% des nazis, comme si la politique \u00e9tait une affaire de statique, et non de dynamique. Ils n\u2019avaient pas compris la dynamique de radicalisation et les ambitions nazies, et pensaient que la violence brune se limiterait \u00e0 brutaliser les ennemis communs \u2014 la gauche&#160;; que jamais elle ne d\u00e9borderait jusqu\u2019\u00e0 les frapper eux.<\/p>\n\n\n\n<p>Il est particuli\u00e8rement \u00e9clairant de revenir au discours que von Papen prononce \u00e0 l\u2019universit\u00e9 de Marbourg, le 17 juin 1934. Il est alors encore vice-chancelier. Dans cette intervention, il explique que les nazis sont all\u00e9s trop loin&#160;; que des abus ont \u00e9t\u00e9 commis&#160;; que ce n\u2019est pas pour cela que l\u2019on avait fait alliance avec eux.<\/p>\n\n\n\n<p>Ce discours est typiquement un discours de grand bourgeois. Papen ne s\u2019\u00e9meut pas des meurtres de communistes ou de sociaux-d\u00e9mocrates \u2014 ces violences ne troublent pas sa tranquillit\u00e9. Le d\u00e9mant\u00e8lement de la gauche ne l\u2019inqui\u00e8te pas. Ce qui l\u2019inqui\u00e8te, ce sont les attaques contre l\u2019\u00c9glise, les atteintes \u00e0 la presse bourgeoise, la d\u00e9sagr\u00e9gation de l\u2019ordre qu\u2019il croyait sauvegarder.<\/p>\n\n\n\n<p>Il le dit clairement&#160;: il voulait le bien-\u00eatre bourgeois, la pr\u00e9servation d\u2019un certain bonheur discret, non de brutaliser les gens bien et les gens de bien.<\/p>\n\n\n\n<p>\u00c0 la suite de ce discours, la r\u00e9action est imm\u00e9diate. Le texte est interdit de diffusion. Et deux des plus proches collaborateurs de Papen sont ex\u00e9cut\u00e9s durant la Nuit des longs couteaux, directement \u00e0 la chancellerie&#160;: l\u2019un est mitraill\u00e9 dans son bureau, l\u2019autre enlev\u00e9 sans laisser de trace. On ne retrouvera jamais son corps.<\/p>\n\n\n\n<p>Papen, lui, n\u2019est pas tu\u00e9. Il est plac\u00e9 en r\u00e9sidence surveill\u00e9e, sous \u00ab&#160;protection&#160;\u00bb de G\u00f6ring. Ce dernier convainc Hitler que Papen peut encore servir, car l\u2019homme a d\u00e9j\u00e0 beaucoup servi. Il a \u00e9t\u00e9 l\u2019artisan de la mise au pouvoir des nazis, d\u00e8s d\u00e9cembre 1932. Il a \u00e9t\u00e9 central dans la n\u00e9gociation du concordat avec le Vatican, sign\u00e9 avec le cardinal Pacelli, futur Pie XII \u2014 parce qu\u2019il est catholique, qu\u2019il dispose de relais puissants \u00e0 Rome, et d\u2019un solide r\u00e9seau diplomatique.<\/p>\n\n\n\n<p>Apr\u00e8s la nuit des longs couteaux, von Papen est nomm\u00e9 ambassadeur \u00e0 Vienne, avec une mission claire&#160;: pr\u00e9parer l\u2019Anschluss. Il conna\u00eet parfaitement l\u2019appareil catholique autrichien, les r\u00e9seaux conservateurs, les cercles national-catholiques. Il man\u0153uvre. Et l\u2019Anschluss a bien lieu.<\/p>\n\n\n\n<p>Mais apr\u00e8s l\u2019annexion, le gendre de von Papen est retrouv\u00e9 mort, lest\u00e9 d\u2019une pierre, au fond du Danube. Il a \u00e9t\u00e9 assassin\u00e9 par la SS. Et pourtant, Papen ne dira jamais rien&#160;; il continue \u00e0 servir. Plus tard encore, on l\u2019envoie en Turquie, pour tenter de s\u00e9curiser le front sud-est. Il y a conserv\u00e9 des r\u00e9seaux h\u00e9rit\u00e9s de la Premi\u00e8re Guerre mondiale&#160;; l\u00e0 encore, il rend service.<\/p>\n\n\n\n<p>Von Papen aura donc servi jusqu\u2019au bout, us\u00e9 jusqu\u2019\u00e0 la corde, ou juste avant la corde, car il ne sera pas condamn\u00e9 \u00e0 mort \u00e0 Nuremberg, comme d\u2019autres qui, comme lui, auront su exciper de leur parfaite \u00e9ducation, de leur ma\u00eetrise des langues \u00e9trang\u00e8res, de leurs r\u00e9seaux, pour \u00e9chapper \u00e0 la potence.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Par un travail d\u2019autosc\u00e9narisation, les nazis ont fourni aux extr\u00eames droites futures un mod\u00e8le de violence. <\/p>\n<p>Alors qu&rsquo;une partie de la droite MAGA d\u00e9clare sans filtre et ouvertement son admiration pour Adolf Hitler et le Troisi\u00e8me Reich, Johann Chapoutot explique la formation et le succ\u00e8s du \u00ab&#160;&#160;mythe nazi&#160;&#160;\u00bb.<\/p>\n","protected":false},"author":5931,"featured_media":315653,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-interviews.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":34,"footnotes":""},"categories":[2024],"tags":[],"staff":[1738],"editorial_format":[4854],"serie":[],"audience":[],"geo":[],"class_list":["post-315592","post","type-post","status-publish","format-standard","hentry","category-histoire","staff-baptiste-roger-lacan","editorial_format-entretiens"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":315653,"excerpt":"Par un travail d\u2019autosc\u00e9narisation, les nazis ont fourni aux extr\u00eames droites futures un mod\u00e8le de violence. \r\n\r\nAlors qu'une partie de la droite MAGA d\u00e9clare sans filtre et ouvertement son admiration pour Adolf Hitler et le Troisi\u00e8me Reich, Johann Chapoutot explique la formation et le succ\u00e8s du \u00abmythe nazi\u00bb.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Est-il possible de rapprocher Trump de l\u2019ordre nazi ? Les r\u00e9ponses de Chapoutot | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/01\/est-il-possible-de-rapprocher-trump-de-lordre-nazi-les-reponses-de-chapoutot\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Est-il possible de rapprocher Trump de l\u2019ordre nazi ? Les r\u00e9ponses de Chapoutot | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Par un travail d\u2019autosc\u00e9narisation, les nazis ont fourni aux extr\u00eames droites futures un mod\u00e8le de violence.   Alors qu&#039;une partie de la droite MAGA d\u00e9clare sans filtre et ouvertement son admiration pour Adolf Hitler et le Troisi\u00e8me Reich, Johann Chapoutot explique la formation et le succ\u00e8s du \u00ab&#160;mythe nazi&#160;\u00bb.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/01\/est-il-possible-de-rapprocher-trump-de-lordre-nazi-les-reponses-de-chapoutot\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-01T05:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-02T11:00:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/gc-iceblack-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"guillaumer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/gc-iceblack-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"guillaumer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"34 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/01\/est-il-possible-de-rapprocher-trump-de-lordre-nazi-les-reponses-de-chapoutot\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/01\/est-il-possible-de-rapprocher-trump-de-lordre-nazi-les-reponses-de-chapoutot\/\",\"name\":\"Est-il possible de rapprocher Trump de l\u2019ordre nazi ? Les r\u00e9ponses de Chapoutot | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/01\/est-il-possible-de-rapprocher-trump-de-lordre-nazi-les-reponses-de-chapoutot\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/01\/est-il-possible-de-rapprocher-trump-de-lordre-nazi-les-reponses-de-chapoutot\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/SIPA_sipahub60101457_000018.jpg\",\"datePublished\":\"2026-02-01T05:00:00+00:00\",\"dateModified\":\"2026-02-02T11:00:04+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/dac94607850a9fd046ae94ea4a56ddcd\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/01\/est-il-possible-de-rapprocher-trump-de-lordre-nazi-les-reponses-de-chapoutot\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/01\/est-il-possible-de-rapprocher-trump-de-lordre-nazi-les-reponses-de-chapoutot\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/01\/est-il-possible-de-rapprocher-trump-de-lordre-nazi-les-reponses-de-chapoutot\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/SIPA_sipahub60101457_000018.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/SIPA_sipahub60101457_000018.jpg\",\"width\":1549,\"height\":2400,\"caption\":\"\u00c0 New York le16 juillet 2025, des agents masqu\u00e9s de l'ICE et des agents f\u00e9d\u00e9raux cagoul\u00e9s arr\u00eatent des migrants apr\u00e8s des audiences judiciaires dans le cadre des politiques controvers\u00e9es de r\u00e9forme de l'immigration de l'administration Trump, au milieu d'une op\u00e9ration de d\u00e9portation massive au Jacob Javits Federal Building. \u00a9 Carol Guzy\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/01\/est-il-possible-de-rapprocher-trump-de-lordre-nazi-les-reponses-de-chapoutot\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Est-il possible de rapprocher Trump de l\u2019ordre nazi&#160;? Les r\u00e9ponses de Chapoutot\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/dac94607850a9fd046ae94ea4a56ddcd\",\"name\":\"guillaumer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/942e2a9aea4f24e4613a346804ae2836?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/942e2a9aea4f24e4613a346804ae2836?s=96&d=mm&r=g\",\"caption\":\"guillaumer\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Est-il possible de rapprocher Trump de l\u2019ordre nazi ? Les r\u00e9ponses de Chapoutot | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/01\/est-il-possible-de-rapprocher-trump-de-lordre-nazi-les-reponses-de-chapoutot\/","og_locale":"fr_FR","og_type":"article","og_title":"Est-il possible de rapprocher Trump de l\u2019ordre nazi ? Les r\u00e9ponses de Chapoutot | Le Grand Continent","og_description":"Par un travail d\u2019autosc\u00e9narisation, les nazis ont fourni aux extr\u00eames droites futures un mod\u00e8le de violence.   Alors qu'une partie de la droite MAGA d\u00e9clare sans filtre et ouvertement son admiration pour Adolf Hitler et le Troisi\u00e8me Reich, Johann Chapoutot explique la formation et le succ\u00e8s du \u00ab&#160;mythe nazi&#160;\u00bb.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/01\/est-il-possible-de-rapprocher-trump-de-lordre-nazi-les-reponses-de-chapoutot\/","og_site_name":"Le Grand Continent","article_published_time":"2026-02-01T05:00:00+00:00","article_modified_time":"2026-02-02T11:00:04+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/gc-iceblack-scaled.jpg","type":"image\/jpeg"}],"author":"guillaumer","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/gc-iceblack-scaled.jpg","twitter_misc":{"\u00c9crit par":"guillaumer","Dur\u00e9e de lecture estim\u00e9e":"34 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/01\/est-il-possible-de-rapprocher-trump-de-lordre-nazi-les-reponses-de-chapoutot\/","url":"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/01\/est-il-possible-de-rapprocher-trump-de-lordre-nazi-les-reponses-de-chapoutot\/","name":"Est-il possible de rapprocher Trump de l\u2019ordre nazi ? Les r\u00e9ponses de Chapoutot | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/01\/est-il-possible-de-rapprocher-trump-de-lordre-nazi-les-reponses-de-chapoutot\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/01\/est-il-possible-de-rapprocher-trump-de-lordre-nazi-les-reponses-de-chapoutot\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/SIPA_sipahub60101457_000018.jpg","datePublished":"2026-02-01T05:00:00+00:00","dateModified":"2026-02-02T11:00:04+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/dac94607850a9fd046ae94ea4a56ddcd"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/01\/est-il-possible-de-rapprocher-trump-de-lordre-nazi-les-reponses-de-chapoutot\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2026\/02\/01\/est-il-possible-de-rapprocher-trump-de-lordre-nazi-les-reponses-de-chapoutot\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/01\/est-il-possible-de-rapprocher-trump-de-lordre-nazi-les-reponses-de-chapoutot\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/SIPA_sipahub60101457_000018.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/SIPA_sipahub60101457_000018.jpg","width":1549,"height":2400,"caption":"\u00c0 New York le16 juillet 2025, des agents masqu\u00e9s de l'ICE et des agents f\u00e9d\u00e9raux cagoul\u00e9s arr\u00eatent des migrants apr\u00e8s des audiences judiciaires dans le cadre des politiques controvers\u00e9es de r\u00e9forme de l'immigration de l'administration Trump, au milieu d'une op\u00e9ration de d\u00e9portation massive au Jacob Javits Federal Building. \u00a9 Carol Guzy"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2026\/02\/01\/est-il-possible-de-rapprocher-trump-de-lordre-nazi-les-reponses-de-chapoutot\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Est-il possible de rapprocher Trump de l\u2019ordre nazi&#160;? Les r\u00e9ponses de Chapoutot"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/dac94607850a9fd046ae94ea4a56ddcd","name":"guillaumer","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/942e2a9aea4f24e4613a346804ae2836?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/942e2a9aea4f24e4613a346804ae2836?s=96&d=mm&r=g","caption":"guillaumer"}}]}},"lgc_categories":[{"id":2024,"name":"Histoire","slug":"histoire"}],"lgc_author":{"id":1738,"name":"Baptiste Roger-Lacan","slug":"baptiste-roger-lacan","description":"Agr\u00e9g\u00e9 et docteur en histoire, Baptiste Roger-Lacan est sp\u00e9cialiste des droites, des contre-r\u00e9volutions europ\u00e9ennes du XIXe si\u00e8cle \u00e0 nos jours.","first_name":"Baptiste","last_name":"Roger-Lacan","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/06\/Photo-Roger-Lacan.png","width":1412,"height":1392,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/SIPA_sipahub60101457_000018.jpg","width":1549,"height":2400,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2026\/02\/SIPA_sipahub60101457_000018.jpg","width":1549,"height":2400,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/315592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/5931"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=315592"}],"version-history":[{"count":40,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/315592\/revisions"}],"predecessor-version":[{"id":315680,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/315592\/revisions\/315680"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/315653"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=315592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=315592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=315592"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=315592"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=315592"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=315592"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=315592"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=315592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}