{"id":306880,"date":"2025-12-01T06:30:00","date_gmt":"2025-12-01T05:30:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=306880"},"modified":"2026-06-13T17:00:11","modified_gmt":"2026-06-13T15:00:11","slug":"tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/","title":{"rendered":"\u00ab&#160;Tout br\u00fbler jusqu\u2019\u00e0 la Manche&#160;\u00bb&#160;: face \u00e0 l\u2019Occident, la diplomatie russe appelle au sang"},"content":{"rendered":"\n<p class=\"intro non-subscribers-only\"><em>Pour soutenir le travail de veille de la premi\u00e8re jeune revue ind\u00e9pendante europ\u00e9enne, <a href=\"https:\/\/legrandcontinent.eu\/fr\/offre-abonnement\/\">abonnez-vous<\/a> au Grand Continent \u00e0 partir de 8 euros par mois.<\/em><\/p>\n\n\n\n<p class=\"intro\">Dans son num\u00e9ro d\u2019octobre, la revue <em>La Vie internationale<\/em>, publi\u00e9e par le minist\u00e8re des Affaires \u00e9trang\u00e8res de la F\u00e9d\u00e9ration de Russie, a pr\u00e9sent\u00e9 au public russe un article au titre \u00e9loquent&nbsp;&#160;: \u00ab&#160;Br\u00fbler jusqu\u2019\u00e0 la Manche&nbsp;&#160;? Quelles garanties de s\u00e9curit\u00e9 efficaces \u00e0 l\u2019heure d\u2019un affrontement historique entre la Russie et l\u2019Occident&#160;\u00bb.&nbsp;<\/p>\n\n\n\n<p class=\"intro\">Cette publication n\u2019a rien d\u2019un tablo\u00efd&#160;; elle est on ne peut plus s\u00e9rieuse. Publi\u00e9e depuis 1922, cette revue est d\u00e9sormais plac\u00e9e sous l\u2019\u00e9gide du ministre des Affaires \u00e9trang\u00e8res Sergue\u00ef Lavrov et accueille les publications d\u2019ambassadeurs, d\u2019anciens ministres et d\u2019experts li\u00e9s au minist\u00e8re.<\/p>\n\n\n\n<p class=\"intro\">Pourtant, l\u2019article tire son intitul\u00e9 d\u2019une chanson du groupe de rock <em>Arbal\u00e8te<\/em> qui figure sur l\u2019album de 2024 \u00ab&#160;N\u00e9 \u00e0 Stalingrad&#160;\u00bb. Cette chanson m\u00e9riterait \u00e0 elle seule un commentaire \u00e9tendu&nbsp;&#160;: elle \u00e9tablit un parall\u00e8le historique entre la guerre en Ukraine et les conflits ant\u00e9rieurs dans lesquels la Russie a affront\u00e9 des pays occidentaux, de la Pologne \u00e0 l\u2019Allemagne nazie.&nbsp;<\/p>\n\n\n\n<p class=\"intro\">Cette rh\u00e9torique militariste n\u2019oublie pas de mobiliser toutes les appellations x\u00e9nophobes en usage, d\u00e9signant tant\u00f4t les Allemands comme des \u00ab&#160;Teutons&#160;\u00bb (<em>Tevtoncy<\/em>), tant\u00f4t comme des \u00ab&#160;Fritz&#160;\u00bb (<em>Fricy<\/em>), tandis que les Ukrainiens d\u2019aujourd\u2019hui sont r\u00e9duits au rang de \u00ab&#160;band\u00e9ristes&#160;\u00bb et de \u00ab&#160;<em>UPy<\/em>&#160;\u00bb, membres de l\u2019Arm\u00e9e insurrectionnelle ukrainienne (<em>Ukrainskaja Povstan\u010deskaja armija<\/em> en russe) qui collabora avec le Troisi\u00e8me Reich et se rendit responsable de massacres pendant la Seconde Guerre mondiale. Les auteurs de ces paroles n\u2019en partagent pas moins certains traits avec leurs suppos\u00e9s ennemis, puisqu\u2019ils consid\u00e8rent, dans le cadre de leur lutte civilisationnelle, les \u00ab&#160;clubs gays&#160;\u00bb comme un signe de \u00ab&#160;d\u00e9g\u00e9n\u00e9rescence&#160;\u00bb. Enfin, le refrain de la chanson est des plus explicites quant aux ambitions politiques de la Russie contemporaine&nbsp;&#160;: apr\u00e8s avoir repouss\u00e9 les envahisseurs allemands, les Russes auraient d\u00fb \u00ab&#160;Tout br\u00fbler, br\u00fbler jusqu\u2019\u00e0 la Manche et au-del\u00e0&#160;\u00bb, impitoyablement, jusqu\u2019\u00e0 la Maison-Blanche.&nbsp;<\/p>\n\n\n\n<p class=\"intro\">Voil\u00e0 pour l\u2019apparat culturel dont se parent les grands noms de la diplomatie russe.<\/p>\n\n\n\n<p class=\"intro\">L\u2019article est sign\u00e9 de trois plumes&nbsp;&#160;: celle de Dmitri Demourine, vice-directeur du 2<sup>e<\/sup> D\u00e9partement des pays de la Communaut\u00e9 des \u00c9tats ind\u00e9pendants au sein du minist\u00e8re russe des Affaires \u00e9trang\u00e8res, celle d\u2019Anton Postigov, chef dudit d\u00e9partement, et celle de Timofe\u00ef Kholine, stagiaire de cette institution. Le premier des coauteurs s\u2019\u00e9tait d\u00e9j\u00e0 illustr\u00e9 en d\u00e9cembre dernier par un article dans la m\u00eame revue, affirmant sous l\u2019intitul\u00e9 \u00ab&#160;Pourquoi le conflit relatif \u00e0 l\u2019Ukraine pr\u00e9sente un caract\u00e8re existentiel&#160;\u00bb que \u00ab&#160;les ennemis de la Russie ne comprennent manifestement qu\u2019un seul argument&nbsp;&#160;: celui du soldat russe&#160;\u00bb.<\/p>\n\n\n\n<p class=\"intro\">Sur le fond, le papier avance une hypoth\u00e8se simple&nbsp;&#160;: la Russie n\u2019a jamais cess\u00e9 et ne cessera jamais d\u2019\u00eatre consid\u00e9r\u00e9e par l\u2019Occident comme une puissance \u00e0 contenir, d\u00e9membrer, voire annihiler. Les ennemis d\u2019aujourd\u2019hui \u2014 le \u00ab&#160;bloc occidental&#160;\u00bb \u2014 seraient donc les m\u00eames qu\u2019hier, de l\u2019Allemagne nazie \u00e0 la Grande-Bretagne de 1856 en passant par la France de 1918. Ils d\u00e9ploieraient, encore et toujours, le m\u00eame arsenal \u2014 des sanctions financi\u00e8res au blocus maritime en passant par la d\u00e9stabilisation interne. Les auteurs identifient la Russie d\u2019hier \u00e0 celle d\u2019aujourd\u2019hui au point de parler d\u2019un \u00ab&#160;nous&#160;\u00bb anhistorique, invariable d\u2019une \u00e9poque \u00e0 l\u2019autre. La conclusion n\u2019est pas plus complexe, puisqu\u2019elle revient \u00e0 affirmer que la Russie ne contraindra l\u2019Occident \u00e0 des n\u00e9gociations avantageuses pour elle qu\u2019au prix d\u2019une victoire sur le sol ukrainien \u2014 ou ailleurs, car, selon les auteurs, les Occidentaux seraient toujours plus prompts \u00e0 entendre les revendications de la Russie lorsque les troupes russes ont mis le pied \u00e0 Paris ou Berlin.<\/p>\n\n\n\n<p class=\"intro\">Si ces rapprochements historiques doivent \u00eatre lus pour ce qu\u2019ils sont&nbsp;\u2014 un d\u00e9raillement \u2014 ils n\u2019en constituent pas moins un sympt\u00f4me. Une partie de l\u2019\u00e9lite diplomatique et politique russe est pr\u00eate \u00e0 soutenir que la Russie m\u00e8ne une lutte \u00e9ternelle contre l\u2019Occident, lutte qui exigerait de tout \u00ab&#160;br\u00fbler jusqu\u2019\u00e0 la Manche&#160;\u00bb et la Maison-Blanche.&nbsp;<\/p>\n\n\n\n<p class=\"intro\">Loin de l\u2019alarmisme qui a pu se faire ressentir en Europe occidentale ces derni\u00e8res semaines, o\u00f9 il semblerait, \u00e0 entendre certains commentateurs, que les T-72 russes seraient aux portes des Ardennes, la menace russe est r\u00e9elle. On voit mal avec quelle arm\u00e9e la Russie ouvrirait un nouveau front si elle peine toujours \u00e0 prendre Pokrovsk (60 000 habitants avant la guerre), o\u00f9 elle a perdu 7 000 soldats au cours du seul mois de janvier dernier, soit des pertes sup\u00e9rieures \u00e0 l\u2019ensemble de la deuxi\u00e8me guerre de Tch\u00e9tch\u00e9nie. Pour autant, comme le rappelait <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/06\/07\/entretien-avec-serguei-karaganov-larchitecte-de-la-geopolitique-de-poutine\/\">Sergue\u00ef Karaganov<\/a> dans ces pages, pour le Kremlin et ses affid\u00e9s \u00ab&#160;<a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/06\/07\/entretien-avec-serguei-karaganov-larchitecte-de-la-geopolitique-de-poutine\/\">la guerre est dans les g\u00e8nes des Russes<\/a>&#160;\u00bb. Poutine parie d\u00e9finitivement sur une guerre \u00e9ternelle et sans limites pour se maintenir au pouvoir ind\u00e9finiment.<\/p>\n\n\n\n<p class=\"intro\">Il ne faut pas oublier, surtout, que les publications de ce type ne refl\u00e8tent pas n\u00e9cessairement une conviction sinc\u00e8re, mais peuvent aussi s\u2019ins\u00e9rer dans une strat\u00e9gie de carri\u00e8re de leurs auteurs.<\/p>\n\n\n\n<p class=\"intro\">Cette concession ne r\u00e9duit pas \u00e0 n\u00e9ant la signification de tels articles&nbsp;&#160;: si le fait d\u2019appeler \u00e0 br\u00fbler l\u2019Europe devient un moyen de monter en grade, si celui de citer des chansons vulgaires et x\u00e9nophobes permet de s\u2019attirer des faveurs politiques, c\u2019est bien qu\u2019il y a quelque chose de structurellement mena\u00e7ant dans la Russie de Poutine.&nbsp;<\/p>\n\n\n\n<p>Lors de son allocution du 18 novembre 2021 devant le coll\u00e8ge \u00e9largi du minist\u00e8re des Affaires \u00e9trang\u00e8res, le pr\u00e9sident de la F\u00e9d\u00e9ration de Russie, Vladimir Vladimirovitch Poutine, a insist\u00e9 sur le fait que l\u2019Occident persistait \u00e0 ignorer les pr\u00e9occupations russes en mati\u00e8re de s\u00e9curit\u00e9, \u00e9largissant l\u2019OTAN vers l\u2019Est, \u00ab&#160;aggravant la situation par des livraisons d\u2019armements modernes \u00e0 Kiev et multipliant les provocations militaires en mer Noire ainsi que dans d\u2019autres r\u00e9gions proches de nos fronti\u00e8res&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-306880' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/#easy-footnote-bottom-1-306880' title='&lt;a href=&quot;https:\/\/www.mid.ru\/ru\/foreign_policy\/news\/1786303\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;\u0412\u044b\u0441\u0442\u0443\u043f\u043b\u0435\u043d\u0438\u0435 \u041f\u0440\u0435\u0437\u0438\u0434\u0435\u043d\u0442\u0430 \u0420\u043e\u0441\u0441\u0438\u0439\u0441\u043a\u043e\u0439 \u0424\u0435\u0434\u0435\u0440\u0430\u0446\u0438\u0438 \u0412.\u0412.\u041f\u0443\u0442\u0438\u043d\u0430 \u043d\u0430 \u0440\u0430\u0441\u0448\u0438\u0440\u0435\u043d\u043d\u043e\u043c \u0437\u0430\u0441\u0435\u0434\u0430\u043d\u0438\u0438 \u043a\u043e\u043b\u043b\u0435\u0433\u0438\u0438 \u041c\u0438\u043d\u0438\u0441\u0442\u0435\u0440\u0441\u0442\u0432\u0430 \u0438\u043d\u043e\u0441\u0442\u0440\u0430\u043d\u043d\u044b\u0445 \u0434\u0435\u043b \u0420\u043e\u0441\u0441\u0438\u0438, \u041c\u043e\u0441\u043a\u0432\u0430, 18 \u043d\u043e\u044f\u0431\u0440\u044f 2021 \u0433\u043e\u0434\u0430&lt;\/a&gt;.'><sup>1<\/sup><\/a><\/span><\/span>. Il en concluait que la Russie devait n\u00e9cessairement \u00ab&#160;obtenir des garanties s\u00e9rieuses et durables en mati\u00e8re de sa s\u00e9curit\u00e9&#160;\u00bb.&nbsp;<\/p>\n\n\n\n<p>Deux semaines plus tard, le sommet minist\u00e9riel de l\u2019OSCE \u00e0 Stockholm a offert au ministre russe des Affaires \u00e9trang\u00e8res, Sergue\u00ef Viktorovitch Lavrov, l\u2019occasion de rappeler \u00e0 ses homologues \u00e9trangers qu\u2019il \u00e9tait \u00ab&#160;parfaitement inacceptable de transformer nos pays frontaliers en places fortes dirig\u00e9es contre la Russie et de d\u00e9ployer les forces de l\u2019OTAN \u00e0 proximit\u00e9 de r\u00e9gions essentielles \u00e0 notre s\u00e9curit\u00e9 sur le plan strat\u00e9gique&#160;\u00bb. Dans ce contexte, il appelait \u00e0 \u00ab&#160;passer des bonnes paroles aux actes, avec des garanties de s\u00e9curit\u00e9 \u00e0 la fois durables et juridiquement contraignantes&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-306880' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/#easy-footnote-bottom-2-306880' title='&lt;a href=&quot;https:\/\/www.mid.ru\/ru\/press_service\/video\/view\/1788501\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Vid\u00e9o&lt;\/a&gt;.'><sup>2<\/sup><\/a><\/span><\/span>.&nbsp;<\/p>\n\n\n\n<p>D\u00e8s le 15 d\u00e9cembre 2021, la Russie a transmis aux \u00c9tats-Unis plusieurs projets \u00e9labor\u00e9s par ses experts&nbsp;&#160;: celui d\u2019un <em>Trait\u00e9 sur les garanties de s\u00e9curit\u00e9 entre la F\u00e9d\u00e9ration de Russie et les \u00c9tats-Unis <\/em>et celui d\u2019un <em>Accord sur les mesures tendant \u00e0 garantir la s\u00e9curit\u00e9 de la F\u00e9d\u00e9ration de Russie et des \u00c9tats membres de l\u2019Organisation du trait\u00e9 de l\u2019Atlantique Nord<\/em>&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-306880' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/#easy-footnote-bottom-3-306880' title='&lt;a href=&quot;https:\/\/www.mid.ru\/ru\/foreign_policy\/news\/1790809\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;\u041e \u0440\u043e\u0441\u0441\u0438\u0439\u0441\u043a\u0438\u0445 \u043f\u0440\u043e\u0435\u043a\u0442\u0430\u0445 \u0434\u043e\u043a\u0443\u043c\u0435\u043d\u0442\u043e\u0432 \u043f\u043e \u043e\u0431\u0435\u0441\u043f\u0435\u0447\u0435\u043d\u0438\u044e \u043f\u0440\u0430\u0432\u043e\u0432\u044b\u0445 \u0433\u0430\u0440\u0430\u043d\u0442\u0438\u0439 \u0431\u0435\u0437\u043e\u043f\u0430\u0441\u043d\u043e\u0441\u0442\u0438 \u0441\u043e \u0441\u0442\u043e\u0440\u043e\u043d\u044b \u0421\u0428\u0410 \u0438 \u041d\u0410\u0422\u041e&lt;\/a&gt;.'><sup>3<\/sup><\/a><\/span><\/span>. Comme on le sait, nos partenaires occidentaux ont malgr\u00e9 tout refus\u00e9 d\u2019ouvrir un dialogue de fond sur ces questions. Peu apr\u00e8s, nous avons \u00e9t\u00e9 contraints de d\u00e9clencher une op\u00e9ration militaire sp\u00e9ciale en r\u00e9action \u00e0 une nouvelle agression \u2014 encourag\u00e9e par ces m\u00eames partenaires \u2014 du r\u00e9gime de Kiev envers les R\u00e9publiques populaires de Donetsk et de Lougansk. Ce faisant, la Russie remplissait ses obligations de protection des habitants du Donbass, conform\u00e9ment \u00e0 l\u2019article 51 de la Charte des Nations Unies.<\/p>\n\n\n\n<p>Les quatre ann\u00e9es pass\u00e9es ont d\u00e9cill\u00e9 les yeux de beaucoup d\u2019observateurs quant aux causes profondes de ces \u00e9v\u00e9nements. Elles nous ont beaucoup appris et, surtout, n\u2019ont plus laiss\u00e9 le moindre doute sur le fait que nous n\u2019affrontions pas, en Ukraine, cette simple marionnette qu\u2019est le r\u00e9gime de Kiev, mais bien la machine de guerre de l\u2019alliance occidentale dans son ensemble. Ainsi, une fois encore, l\u2019Occident se met en mouvement. Masquant ses ambitions derri\u00e8re des slogans de propagande, agitant la \u00ab&#160;menace russe&#160;\u00bb, il reprend sa marche vers l\u2019Est. Il ne cherche pas m\u00eame \u00e0 dissimuler le caract\u00e8re r\u00e9visionniste et revanchiste de cette \u00e9ni\u00e8me agression, comme l\u2019a montr\u00e9 cette ann\u00e9e la d\u00e9claration du nouveau chancelier allemand, Friedrich Merz, promettant devant le Parlement de faire de la Bundeswehr \u00ab&#160;la plus puissante arm\u00e9e d\u2019Europe, comme elle l\u2019avait \u00e9t\u00e9 par le pass\u00e9&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-306880' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/#easy-footnote-bottom-4-306880' title='&lt;a href=&quot;https:\/\/dserver.bundestag.de\/btp\/21\/21003.pdf#P.79&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Plenarprotokoll 21\/3&lt;\/a&gt;.'><sup>4<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n\n<div class=\"double-picture my-12 lg:my-20\" \n    data-images-sizes=\"half\"\n    data-same-height=\"true\"\n    data-reference-image=\"left\"\n>    <!-- Images -->\n    <div class=\"lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-1\/2\">\n                            <a \n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/SIPA_01239377_000010-scaled.jpg\" \n                    class=\"gallery-item no-underline  \" \n                    data-pswp-width=\"2560\" \n                    data-pswp-height=\"1707\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/SIPA_01239377_000010-scaled.jpg\" alt=\"Un militaire russe des troupes de d\u00e9fense radiologique, chimique et biologique du groupe de forces Tsentr. \u00a9 Stanislav Krasilnikov\" >\n                        <\/picture>\n                        <figcaption class=\"lg:hidden pswp-caption-content\">Un militaire russe des troupes de d\u00e9fense radiologique, chimique et biologique du groupe de forces Tsentr. \u00a9 Stanislav Krasilnikov<\/figcaption>                    <\/figure>\n                <\/a>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-1\/2\">\n                            <a\n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/SIPA_01239377_000009-scaled.jpg\" \n                    class=\"gallery-item no-underline  lg:!absolute lg:h-full lg:right-0 lg:left-2 overflow-hidden\" \n                    data-pswp-width=\"2560\" \n                    data-pswp-height=\"1707\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/SIPA_01239377_000009-scaled.jpg\" alt=\"\u00c0 Pokrovsk, sur la ligne de front, un militaire russe est photographi\u00e9 pendant une op\u00e9ration de brouillage des outils de reconnaissance de l'Ukraine \u00e0 l'aide d'\u00e9paisses fum\u00e9es. \u00a9 Stanislav Krasilnikov\" class=\"lg:!h-full object-cover\">\n                        <\/picture>\n                        <figcaption class=\"lg:hidden pswp-caption-content\">\u00c0 Pokrovsk, sur la ligne de front, un militaire russe est photographi\u00e9 pendant une op\u00e9ration de brouillage des outils de reconnaissance de l&rsquo;Ukraine \u00e0 l&rsquo;aide d&rsquo;\u00e9paisses fum\u00e9es. \u00a9 Stanislav Krasilnikov<\/figcaption>                    <\/figure>\n                <\/a>\n                    <\/div>\n    <\/div>\n    <!-- Captions -->\n    <div class=\"hidden lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-1\/2\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">\n                    <figcaption>Un militaire russe des troupes de d\u00e9fense radiologique, chimique et biologique du groupe de forces Tsentr. \u00a9 Stanislav Krasilnikov<\/figcaption>                <\/figure>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-1\/2\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">   \n                    <figcaption>\u00c0 Pokrovsk, sur la ligne de front, un militaire russe est photographi\u00e9 pendant une op\u00e9ration de brouillage des outils de reconnaissance de l&rsquo;Ukraine \u00e0 l&rsquo;aide d&rsquo;\u00e9paisses fum\u00e9es. \u00a9 Stanislav Krasilnikov<\/figcaption>                <\/figure>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<p>L\u2019histoire se r\u00e9p\u00e8te. Les ennemis auxquels nous faisons face aujourd\u2019hui sont les m\u00eames que ceux qui s\u2019en prenaient \u00e0 notre pays il y a 85, 100 ou 200 ans. La diff\u00e9rence tient au fait que, si la Russie affrontait autrefois des \u00c9tats isol\u00e9s ou des petites coalitions, notamment durant la guerre du Nord, la guerre patriotique de 1812, la guerre de Crim\u00e9e ou la Grande Guerre patriotique, elle se heurte aujourd\u2019hui \u00e0 l\u2019ensemble du bloc occidental ligu\u00e9 contre elle. La raison en tient \u00e0 un mot&nbsp;&#160;: la peur. La peur que la Russie s\u2019\u00e9mancipe d\u00e9finitivement de l\u2019influence occidentale. Et elle en est bien capable.<\/p>\n\n\n\n<p>La comparaison la plus \u00e9clairante en la mati\u00e8re reste celle de l\u2019intervention \u00e9trang\u00e8re d\u00e9clench\u00e9e apr\u00e8s octobre 1917. \u00c0 ce moment, non moins de quatorze puissances \u00e9trang\u00e8res, dont la Grande-Bretagne, la France, les \u00c9tats-Unis et le Japon, firent irruption sur le sol russe et envoy\u00e8rent leurs troupes soutenir les arm\u00e9es blanches. Il s\u2019agissait alors d\u2019emp\u00eacher la Russie de s\u2019\u00e9manciper de l\u2019influence occidentale et d\u2019entraver l\u2019\u00e9mergence du projet sovi\u00e9tique. Tandis que les forces exp\u00e9ditionnaires britanniques et am\u00e9ricaines prenaient le contr\u00f4le des ports de Mourmansk et d\u2019Arkhangelsk, les troupes fran\u00e7aises occupaient Odessa et la Crim\u00e9e, les Japonais s\u2019\u00e9tablissant quant \u00e0 eux \u00e0 Vladivostok. En parall\u00e8le, les forces alli\u00e9es faisaient parvenir \u00e0 des g\u00e9n\u00e9raux blancs comme Anton Denikine et Aleksandr Koltchak plusieurs milliers de tonnes d\u2019armes et de munitions ainsi que d\u2019importantes sommes d\u2019argent liquide.<\/p>\n\n\n\n<p>Il est d\u2019ailleurs significatif que les Anglais, moins int\u00e9ress\u00e9s par la lutte contre le bolch\u00e9visme que par la s\u00e9curisation de leurs positions en Asie, la r\u00e9duction de l\u2019influence russe en Europe centrale et orientale et la pr\u00e9servation du march\u00e9 russe (quitte \u00e0 tol\u00e9rer la R\u00e9volution), aient adopt\u00e9 en 1919 une strat\u00e9gie d\u2019attentisme opportuniste&nbsp;&#160;: soutenant discr\u00e8tement les antibolch\u00e9viques, ils attendaient de voir lequel des camps en pr\u00e9sence allait succomber au chaos qu\u2019ils avaient eux-m\u00eames contribu\u00e9 \u00e0 provoquer&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-306880' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/#easy-footnote-bottom-5-306880' title='Lev Danilkin, &lt;em&gt;Lenin. Pantokrator solne\u010dnykh pylinok&lt;\/em&gt;, Moskva, Molodaja gvardija, 2017, p. 214.'><sup>5<\/sup><\/a><\/span><\/span>. Cela ne vous rappelle rien&nbsp;&#160;?&nbsp;<\/p>\n\n\n\n<p>En ce d\u00e9but de XXIe si\u00e8cle, nous luttons contre les m\u00eames ennemis historiques. \u00c0 un moment ou un autre, nous devrons nous entendre avec eux sur une quelconque forme de paix. L\u2019histoire russe offre ici les exemples les plus vari\u00e9s&nbsp;&#160;: la Victoire triomphale de 1945, mais aussi des accords de paix conclus sous la contrainte ou en position de faiblesse, comme le trait\u00e9 de Portsmouth avec le Japon en 1905 ou le trait\u00e9 de Paris de 1856. \u00c0 l\u2019heure de ce nouveau tournant, il nous faut compulser les pages de notre histoire et syst\u00e9matiser tout ce que nous savons de nos ennemis, afin de d\u00e9terminer au mieux les objectifs et les attentes \u00e0 exprimer dans le cadre d\u2019\u00e9ventuelles n\u00e9gociations.<\/p>\n\n\n\n<p>Les vis\u00e9es agressives des dirigeants europ\u00e9ens \u00e0 l\u2019\u00e9gard de la Russie sont bien connues. Au d\u00e9but de l\u2019ann\u00e9e 1854, lord Palmerston, alors ministre de l\u2019Int\u00e9rieur et ancien Premier ministre britannique, \u00e9crivait d\u00e9j\u00e0&nbsp;&#160;:&nbsp;<\/p>\n\n\n\n<p><em>\u00ab&#160;Dans la guerre qui s\u2019appr\u00eate \u00e0 \u00e9clater avec la Russie, mon id\u00e9al est le suivant. Les \u00eeles \u00c5land et la Finlande seront rendues \u00e0 la Su\u00e8de. Certaines des provinces allemandes de la Russie sur la Baltique reviendront \u00e0 la Prusse. Le royaume de Pologne sera r\u00e9tabli et servira de barri\u00e8re entre l\u2019Allemagne et la Russie. La Valachie, la Moldavie et le delta du Danube iront \u00e0 l\u2019Autriche. La Lombardie et la V\u00e9n\u00e9tie seront \u00e9mancip\u00e9es de la tutelle autrichienne et deviendront des \u00c9tats ind\u00e9pendants ou seront rattach\u00e9es au Pi\u00e9mont. La Crim\u00e9e, la Circassie et la G\u00e9orgie seront arrach\u00e9es \u00e0 la Russie, au profit de la Turquie pour la Crim\u00e9e et la G\u00e9orgie, tandis que la Circassie se rendra ind\u00e9pendante ou passera sous la suzerainet\u00e9 du sultan.&#160;\u00bb<\/em>&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-306880' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/#easy-footnote-bottom-6-306880' title='&lt;a href=&quot;https:\/\/archive.org\/details\/in.ernet.dli.2015.176211\/page\/n325\/mode\/2up&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Lien&lt;\/a&gt;.'><sup>6<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p>Pr\u00e8s d\u2019un si\u00e8cle plus tard, Adolf Hitler s\u2019entretenait avec le vice-Premier ministre roumain et ministre des Affaires \u00e9trang\u00e8res Mihai Antonescu le 27 novembre 1941, et d\u00e9clara cette fois-ci&nbsp;&#160;:&nbsp;<\/p>\n\n\n\n<p><em>\u00ab&#160;L\u2019Europe de l\u2019avenir ne doit conna\u00eetre que deux races&nbsp;&#160;: la race latine et la race germanique. Ces deux races doivent travailler de concert en Russie pour \u00e9radiquer les Slaves. On ne peut affronter la Russie avec de simples formules juridiques ou politiques&nbsp;&#160;; le probl\u00e8me russe est bien plus s\u00e9rieux que beaucoup semblent le penser. Nous devons trouver les moyens de coloniser et d\u2019an\u00e9antir biologiquement les Slaves. Aussi tous les peuples europ\u00e9ens doivent-ils unir leurs forces dans la lutte contre les Slaves et la transformation de la Russie au profit de l\u2019Europe. Ma mission, si elle est couronn\u00e9e de succ\u00e8s, est d\u2019\u00e9liminer la slavit\u00e9.&#160;\u00bb<\/em>&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-7-306880' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/#easy-footnote-bottom-7-306880' title='&lt;a href=&quot;https:\/\/histrf.ru\/read\/articles\/v-rossii-vpervye-opublikovan-tekst-zayavleniya-gitlera-ob-unichtozhenii-slavyanskih-narodov&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;\u0412 \u0420\u043e\u0441\u0441\u0438\u0438 \u0432\u043f\u0435\u0440\u0432\u044b\u0435 \u043e\u043f\u0443\u0431\u043b\u0438\u043a\u043e\u0432\u0430\u043d \u0442\u0435\u043a\u0441\u0442 \u0437\u0430\u044f\u0432\u043b\u0435\u043d\u0438\u044f \u0413\u0438\u0442\u043b\u0435\u0440\u0430 \u043e\u0431 \u0443\u043d\u0438\u0447\u0442\u043e\u0436\u0435\u043d\u0438\u0438 \u0441\u043b\u0430\u0432\u044f\u043d\u0441\u043a\u0438\u0445 \u043d\u0430\u0440\u043e\u0434\u043e\u0432 | \u0427\u0438\u0442\u0430\u0442\u044c \u0441\u0442\u0430\u0442\u044c\u0438 \u043f\u043e \u0438\u0441\u0442\u043e\u0440\u0438\u0438 \u0420\u0424 \u0434\u043b\u044f \u0448\u043a\u043e\u043b\u044c\u043d\u0438\u043a\u043e\u0432 \u0438 \u0441\u0442\u0443\u0434\u0435\u043d\u0442\u043e\u0432&lt;\/a&gt;'><sup>7<\/sup><\/a><\/span><\/span><\/p>\n\n\n\n<p>Hitler avait r\u00e9solu d\u2019accomplir \u00ab&#160;ce dont toute l\u2019Europe r\u00eavait&#160;\u00bb, comme le rappelle le monologue final du film <em>Le Tigre blanc<\/em> de Karen Chakhnazarov. Il se montra cependant moins habile que les dirigeants europ\u00e9ens d\u2019aujourd\u2019hui, puisqu\u2019il ne sut jamais recouvrir son projet d\u2019un vernis propagandiste \u00ab&#160;politiquement correct&#160;\u00bb. Les Europ\u00e9ens d\u2019aujourd\u2019hui, qui nourrissent au fond les m\u00eames ambitions, se drapent d\u00e9sormais dans la toge des lib\u00e9rateurs et des protecteurs de l\u2019humanit\u00e9 face \u00e0 une Russie terrifiante, totalitaire, peupl\u00e9e d\u2019\u00eatres abominables, hostiles aux droits de l\u2019Homme et \u00e0 toute innovation venue d\u2019Occident. Cet emballage \u00e9l\u00e9gant n\u2019a qu\u2019une fonction&nbsp;&#160;: traduire dans un langage polic\u00e9 le mot <em>Untermenschen<\/em>. Sur le fond, rien n\u2019a chang\u00e9. Hitler qualifiait avec m\u00e9pris l\u2019URSS de \u00ab&#160;colosse aux pieds d\u2019argile&#160;\u00bb, assurant \u00e0 ses g\u00e9n\u00e9raux qu\u2019il suffirait de \u00ab&#160;donner un coup dans la porte pour que tout l\u2019\u00e9difice s\u2019effondre&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-8-306880' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/#easy-footnote-bottom-8-306880' title='&lt;a href=&quot;https:\/\/archive.org\/stream\/HalderWarJournal\/Halder%20War%20Journal_djvu.txt&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Full text of \u00ab&amp;#160;Halder War Journal (Halder War Diary)&amp;#160;\u00bb&lt;\/a&gt;'><sup>8<\/sup><\/a><\/span><\/span>. Sous Ronald Reagan, les \u00c9tats-Unis rebaptis\u00e8rent l\u2019Union sovi\u00e9tique \u00ab&#160;l\u2019Empire du mal&#160;\u00bb, tout en pr\u00e9tendant mener \u00ab&#160;une lutte pour la libert\u00e9 et la d\u00e9mocratie&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-9-306880' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-1'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/#easy-footnote-bottom-9-306880' title='&lt;a href=&quot;https:\/\/voicesofdemocracy.umd.edu\/ronald-reagan-evil-empire-speech-8-march-1983\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Ronald Reagan, \u00ab&amp;#160;Evil Empire Speech,&amp;#160;\u00bb 8 March 1983, Voices of Democracy&lt;\/a&gt;.'><sup>9<\/sup><\/a><\/span><\/span>. Aujourd\u2019hui, le pr\u00e9sident am\u00e9ricain Donald Trump parle de la Russie comme d\u2019un \u00ab&#160;tigre de papier&#160;\u00bb et menace d\u2019aider l\u2019Ukraine \u00e0 \u00ab&#160;reprendre ses territoires&#160;\u00bb avec l\u2019aide de l\u2019OTAN et de l\u2019UE.<\/p>\n\n\n<section class=\"dive print-block my-16   comment\" style=\"background-color:#ffffff;\">\n\t<div class=\"wrapper\">\n\t\t<div class=\"container mx-auto \">\n\t\t\t<div class=\"row flex flex-wrap relative pt-6 pb-16 lg:py-8\">\n\t\t\t\t<div class=\"col w-full xl:ml-1\/10\n\t\t\t\t\t md:w-2\/5 xl:w-2\/5 \t\t\t\t\t\">\n\t\t\t\t\t<a href=\"https:\/\/legrandcontinent.eu\/shop\/produit\/empire-de-lombre\/\" style=\"color:#0a0a0a;\" class=\"font-display font-normal text-4xl leading-9 mb-5 text-white no-underline\">\n\t\t\t\t\t\tCe que veut vraiment Poutine\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<div style=\"color:#0a0a0a;\" class=\"text-base leading-none font-sans\">\n\t\t\t\t\t\t\t<p>Pour comprendre la doctrine du Kremlin, retrouvez un in\u00e9dit comment\u00e9 de Vladislav Sourkov<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"mt-12 dive-list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a  style=\"color:#dd203c;\" class=\"no-underline block border-t border-grey-darker py-2 flex\"\n\t\t\t\t\t\t\t\t   href=\"https:\/\/legrandcontinent.eu\/shop\/produit\/empire-de-lombre\/\"><span class=\"font-sans font-semibold pr-4\">\u2192<\/span> Commandez le num\u00e9ro<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col w-full md:w-3\/5 xl:w-2\/5  md:px-0 relative overflow-hidden mt-8 md:mt-0 macron-img\">\n\t\t\t\t\t\t\t\t<a class=\"!absolute !bg-none w-full h-full pin-t pin-l\" href=\"https:\/\/legrandcontinent.eu\/shop\/produit\/empire-de-lombre\/\" class=\"no-underline\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" style=\"object-fit: contain; width: 100%; height: 100%;\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/04\/mediamodifier_image-17-990x660.png\" \/>\n\t\t\t\t\t\t\t\t<\/a> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n<p>Pour les Russes avertis, ces sentiments vis-\u00e0-vis de notre pays n\u2019ont jamais \u00e9t\u00e9 un secret. En avril 1854, [le po\u00e8te et diplomate russe] Fiodor Tiouttchev \u00e9crivait, comme en r\u00e9plique \u00e0 Palmerston&nbsp;&#160;:&nbsp;<\/p>\n\n\n\n<p><em>\u00ab&#160;On pouvait pr\u00e9voir depuis bien longtemps que cette haine enrag\u00e9e, semblable \u00e0 celle d\u2019un chien contre sa laisse, cette haine de la Russie qui n\u2019a cess\u00e9 de cro\u00eetre depuis trente ans, finirait par se d\u00e9cha\u00eener. Ce moment est enfin venu. Ce que l\u2019on propose aujourd\u2019hui \u00e0 la Russie n\u2019est rien d\u2019autre qu\u2019un suicide, un renoncement aux fondements m\u00eames de son existence, la reconnaissance solennelle qu\u2019elle n\u2019est dans le monde qu\u2019un ph\u00e9nom\u00e8ne sauvage et monstrueux qu\u2019il faut corriger&#160;\u00bb.&nbsp;<\/em><\/p>\n\n\n\n<p>Ces mots ont r\u00e9sonn\u00e9 une nouvelle fois en mars 2022 lorsqu\u2019ils ont \u00e9t\u00e9 cit\u00e9s par Tatiana Dovgalenko, repr\u00e9sentante-adjointe de la Russie, lors d\u2019une r\u00e9union du Conseil ex\u00e9cutif de l\u2019UNESCO \u00e0 Paris, suscitant aussit\u00f4t un vif \u00e9moi m\u00e9diatique&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-10-306880' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/#easy-footnote-bottom-10-306880' title='&lt;a href=&quot;https:\/\/rutube.ru\/video\/7fd1fd65438d20f2d34631c56038e838\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Vid\u00e9o&lt;\/a&gt;.'><sup>10<\/sup><\/a><\/span><\/span>. En septembre 2023, ils ont \u00e9t\u00e9 comment\u00e9s une nouvelle fois par le ministre des Affaires \u00e9trang\u00e8res Sergue\u00ef Lavrov devant le corps diplomatique r\u00e9uni \u00e0 Moscou pour les 220 ans de la naissance du po\u00e8te&nbsp;&#160;:&nbsp;<\/p>\n\n\n\n<p><em>\u00ab&#160;Ces mots ont \u00e9t\u00e9 \u00e9crits en 1854. Pourtant, si on fait abstraction des dates, des comm\u00e9morations, ils d\u00e9crivent parfaitement la politique de l\u2019Occident vis-\u00e0-vis de la Russie d\u2019aujourd\u2019hui. Fiodor Ivanovitch fut un diplomate clairvoyant et, \u00e0 bien des \u00e9gards, un vrai homme d\u2019\u00c9tat. Aussi tout ce que nous accomplissons aujourd\u2019hui, tous les efforts de notre pr\u00e9sident, de notre arm\u00e9e, de notre soci\u00e9t\u00e9, de notre \u00c9tat, tout cela n\u2019a qu\u2019un but&nbsp;&#160;: emp\u00eacher que ces pr\u00e9dictions d\u2019il y a deux cents ans ne se r\u00e9alisent.&#160;\u00bb<\/em>&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-11-306880' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/#easy-footnote-bottom-11-306880' title='&lt;a href=&quot;https:\/\/www.mid.ru\/ru\/press_service\/minister_speeches\/1906609\/&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;\u0412\u0441\u0442\u0443\u043f\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u0435 \u0441\u043b\u043e\u0432\u043e \u041c\u0438\u043d\u0438\u0441\u0442\u0440\u0430 \u0438\u043d\u043e\u0441\u0442\u0440\u0430\u043d\u043d\u044b\u0445 \u0434\u0435\u043b \u0420\u043e\u0441\u0441\u0438\u0438 \u0421.\u0412.\u041b\u0430\u0432\u0440\u043e\u0432\u0430 \u043d\u0430 \u0446\u0435\u0440\u0435\u043c\u043e\u043d\u0438\u0438 \u043e\u0442\u043a\u0440\u044b\u0442\u0438\u044f \u00ab&amp;#160;\u041b\u0438\u0442\u0435\u0440\u0430\u0442\u0443\u0440\u043d\u043e\u0439 \u0433\u043e\u0441\u0442\u0438\u043d\u043e\u0439. \u041f\u043e\u0441\u043b\u044b \u0440\u0443\u0441\u0441\u043a\u043e\u0439 \u043a\u0443\u043b\u044c\u0442\u0443\u0440\u044b&amp;#160;\u00bb, \u043f\u043e\u0441\u0432\u044f\u0449\u0435\u043d\u043d\u043e\u0439 \u0436\u0438\u0437\u043d\u0438 \u0438 \u0442\u0432\u043e\u0440\u0447\u0435\u0441\u0442\u0432\u0443 \u0424.\u0418.\u0422\u044e\u0442\u0447\u0435\u0432\u0430, \u041c\u043e\u0441\u043a\u0432\u0430, 27 \u0441\u0435\u043d\u0442\u044f\u0431\u0440\u044f 2023 \u0433\u043e\u0434\u0430&lt;\/a&gt;'><sup>11<\/sup><\/a><\/span><\/span>.&nbsp;<\/p>\n\n\n\n<p>Les colonisateurs occidentaux ont toujours eu des vues sur la Russie, la consid\u00e9rant comme un simple r\u00e9servoir de ressources naturelles et humaines, un corridor de transport et une zone-tampon \u00e0 conqu\u00e9rir ou placer sous tutelle politique et \u00e9conomique. Diverses strat\u00e9gies ont \u00e9t\u00e9 d\u00e9ploy\u00e9es \u00e0 cette fin au cours de l\u2019histoire&nbsp;&#160;:&nbsp;<\/p>\n\n\n\n<p>1 \u2014 La guerre \u00ab&#160;classique&#160;\u00bb, sur terre ou sur mer. Significativement, les historiens font remonter les premi\u00e8res agressions occidentales contre la Rus\u2019 \u00e0 la campagne du roi polonais Boleslas, en 1018, soutenu alors par les chevaliers germaniques. Au XIII<sup>e <\/sup>si\u00e8cle, une nouvelle offensive germanique contre la Rus\u2019 fut m\u00eame b\u00e9nie par le pape \u2014 sans que cela lui assure davantage de succ\u00e8s. Les Allemands n\u2019ont manifestement retir\u00e9 aucun enseignement de ces revers, ni d\u2019ailleurs des suivants.<\/p>\n\n\n\n<p>2 \u2014 Le blocus maritime. On ignore souvent que, pendant la guerre de Crim\u00e9e, les flottes britannique et fran\u00e7aise s\u2019en sont pris aux navires et aux fortifications c\u00f4ti\u00e8res russes non seulement dans la mer Noire, mais aussi dans la Baltique, la mer Blanche, la mer de Barents, et m\u00eame dans le Pacifique. Au XX<sup>e <\/sup>si\u00e8cle, le cas le plus notable, magistralement d\u00e9crit par Valentin Pikoul, reste sans doute celui des sous-marins allemands luttant contre les convois alli\u00e9s en Arctique&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-12-306880' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/#easy-footnote-bottom-12-306880' title='Valentin Pikoul, &lt;em&gt;Patrouille oc\u00e9anique&lt;\/em&gt;, 1954 et &lt;em&gt;Requiem pour le convoi PQ-17&lt;\/em&gt; (1970).'><sup>12<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>3 \u2014 Les mesures financi\u00e8res, \u00e9conomiques et commerciales que nos adversaires appellent aujourd\u2019hui des \u00ab&#160;sanctions&#160;\u00bb pour leur donner un semblant de l\u00e9gitimit\u00e9. Pendant la guerre de Crim\u00e9e, l\u2019un des objectifs strat\u00e9giques de la Grande-Bretagne consistait d\u00e9j\u00e0 \u00e0 priver la Russie du contr\u00f4le du commerce du grain en mer Noire qui aurait permis \u00e0 Saint-P\u00e9tersbourg d\u2019influer sur les approvisionnements alimentaires europ\u00e9ens&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-13-306880' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/#easy-footnote-bottom-13-306880' title='&lt;a href=&quot;https:\/\/statehistory.ru\/books\/Styuart-Ross-Tompston_Rossiyskaya-vneshnyaya-torgovlya-XIX---nachala-XX-v--Organizatsiya-i-finansirovanie\/4&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;1.2. \u0412\u043d\u0435\u0448\u043d\u044f\u044f \u0442\u043e\u0440\u0433\u043e\u0432\u043b\u044f \u0420\u043e\u0441\u0441\u0438\u0438, 1855\u20141914 \u0433\u0433.&lt;\/a&gt;'><sup>13<\/sup><\/a><\/span><\/span>. En 1919, le Conseil supr\u00eame de l\u2019Entente interdit toute relation commerciale et \u00e9conomique avec la Russie. C\u2019est d\u2019ailleurs \u00e0 cette \u00e9poque que le pr\u00e9sident du Conseil Clemenceau popularisa l\u2019expression \u00ab&#160;rideau de fer&#160;\u00bb. En 1925, \u00ab&#160;l\u2019embargo sur l\u2019or&#160;\u00bb impos\u00e9 par les pays d\u2019Europe et les \u00c9tats-Unis dans les relations commerciales avec l\u2019URSS nous for\u00e7a \u00e0 vendre du bl\u00e9 et du p\u00e9trole pour acqu\u00e9rir les \u00e9quipements n\u00e9cessaires \u00e0 l\u2019industrialisation. Cinq ans plus tard, l\u2019interdiction fut \u00e9tendue \u00e0 l\u2019ensemble des produits sovi\u00e9tiques, \u00e0 l\u2019exception du bl\u00e9. Cette mesure con\u00e7ue comme un frein \u00e0 l\u2019industrialisation en marche fut aussi l\u2019une des sources de la grande famine de 1932-1933. Pendant la Guerre froide, les \u00c9tats-Unis et leurs alli\u00e9s instaur\u00e8rent un embargo commercial strict sur les produits de haute technologie afin d\u2019entraver notre d\u00e9veloppement industriel et militaire. L\u2019amendement Jackson-Vanik de 1974 lia directement le commerce am\u00e9ricano-sovi\u00e9tique \u00e0 la question de l\u2019\u00e9migration juive, entravant ainsi les relations \u00e9conomiques au nom de la d\u00e9fense des droits de l\u2019Homme&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-14-306880' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/#easy-footnote-bottom-14-306880' title='&lt;a href=&quot;https:\/\/www.vavt.ru\/wto\/wto\/Jackson-VanikAmendment&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;https:\/\/www.vavt.ru\/wto\/wto\/Jackson-VanikAmendment&lt;\/a&gt;'><sup>14<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n\n<div class=\"double-picture my-12 lg:my-20\" \n    data-images-sizes=\"half\"\n    data-same-height=\"true\"\n    data-reference-image=\"left\"\n>    <!-- Images -->\n    <div class=\"lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-1\/2\">\n                            <a \n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/SIPA_01239377_000012-scaled.jpg\" \n                    class=\"gallery-item no-underline  \" \n                    data-pswp-width=\"2560\" \n                    data-pswp-height=\"1707\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/SIPA_01239377_000012-scaled.jpg\" alt=\"Autour de Pokrovsk, une ville de 60 000 habitants mais qui occupe une place strat\u00e9gique sur le front ukrainien, l'arm\u00e9e russe a perdu 7000 hommes au cours du seul mois de janvier. \u00a9 Stanislav Krasilnikov\" >\n                        <\/picture>\n                        <figcaption class=\"lg:hidden pswp-caption-content\">Autour de Pokrovsk, une ville de 60 000 habitants mais qui occupe une place strat\u00e9gique sur le front ukrainien, l&rsquo;arm\u00e9e russe a perdu 7000 hommes au cours du seul mois de janvier. \u00a9 Stanislav Krasilnikov<\/figcaption>                    <\/figure>\n                <\/a>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-1\/2\">\n                            <a\n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/SIPA_01239377_000011-scaled.jpg\" \n                    class=\"gallery-item no-underline  lg:!absolute lg:h-full lg:right-0 lg:left-2 overflow-hidden\" \n                    data-pswp-width=\"2560\" \n                    data-pswp-height=\"1750\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/SIPA_01239377_000011-scaled.jpg\" alt=\"Le cerveau g\u00e9opolitique du Kremlin Sergue\u00ef Karaganov rappelait dans ces pages, pour Moscou \u00abla guerre est dans les g\u00e8nes des Russes\u00bb. Poutine parie d\u00e9finitivement sur une guerre \u00e9ternelle et sans limites pour se maintenir au pouvoir ind\u00e9finiment. \u00a9 Stanislav Krasilnikov\" class=\"lg:!h-full object-cover\">\n                        <\/picture>\n                        <figcaption class=\"lg:hidden pswp-caption-content\">Le cerveau g\u00e9opolitique du Kremlin Sergue\u00ef Karaganov rappelait dans ces pages, pour Moscou \u00ab&#160;la guerre est dans les g\u00e8nes des Russes&#160;\u00bb. Poutine parie d\u00e9finitivement sur une guerre \u00e9ternelle et sans limites pour se maintenir au pouvoir ind\u00e9finiment. \u00a9 Stanislav Krasilnikov<\/figcaption>                    <\/figure>\n                <\/a>\n                    <\/div>\n    <\/div>\n    <!-- Captions -->\n    <div class=\"hidden lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-1\/2\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">\n                    <figcaption>Autour de Pokrovsk, une ville de 60 000 habitants mais qui occupe une place strat\u00e9gique sur le front ukrainien, l&rsquo;arm\u00e9e russe a perdu 7000 hommes au cours du seul mois de janvier. \u00a9 Stanislav Krasilnikov<\/figcaption>                <\/figure>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-1\/2\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">   \n                    <figcaption>Le cerveau g\u00e9opolitique du Kremlin Sergue\u00ef Karaganov rappelait dans ces pages, pour Moscou \u00ab&#160;la guerre est dans les g\u00e8nes des Russes&#160;\u00bb. Poutine parie d\u00e9finitivement sur une guerre \u00e9ternelle et sans limites pour se maintenir au pouvoir ind\u00e9finiment. \u00a9 Stanislav Krasilnikov<\/figcaption>                <\/figure>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<p>4 \u2014 Financer l\u2019agresseur. Au cours de la guerre russo-japonaise, les milieux financiers am\u00e9ricains accord\u00e8rent \u00e0 Tokyo des pr\u00eats faramineux&nbsp;&#160;: le banquier new-yorkais Jacob Schiff y engagea \u00e0 lui seul 200 millions de dollars, l\u2019\u00e9quivalent actuel de 4,5 milliards de dollars&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-15-306880' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/#easy-footnote-bottom-15-306880' title='Gary Dean Best, \u201cFinancing a Foreign War&amp;#160;: Jacob H. Schiff and Japan, 1904\u201305,\u201d &lt;em&gt;American Jewish Historical Quarterly&lt;\/em&gt; 61, no. 4 (1972), 313-324.'><sup>15<\/sup><\/a><\/span><\/span>. Le message \u00e9tait on ne peut plus clair&nbsp;&#160;: l\u2019Occident accueillerait favorablement et g\u00e9n\u00e9reusement toute initiative tendant \u00e0 r\u00e9duire la sph\u00e8re d\u2019influence de la Russie. Ce n\u2019est pas non plus un hasard si l\u2019arriv\u00e9e de Hitler au pouvoir rencontra si peu de r\u00e9sistance dans l\u2019Occident des ann\u00e9es 1930&nbsp;&#160;: \u00e0 Londres comme \u00e0 Washington, beaucoup voyaient au contraire dans l\u2019Allemagne nazie une force capable d\u2019abattre l\u2019URSS&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-16-306880' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/#easy-footnote-bottom-16-306880' title='Charles Higham, &lt;em&gt;Trading with the Enemy&amp;#160;: The Nazi-American Money Plot, 1933-1949&lt;\/em&gt;, New York, Delacorte Press, 1983.'><sup>16<\/sup><\/a><\/span><\/span>. Apr\u00e8s 1945, nos alli\u00e9s d\u2019un jour redeviendraient nos adversaires, pr\u00eats une fois encore \u00e0 soutenir toute force hostile \u00e0 la Russie, des moudjahidines afghans aux formations terroristes du Caucase du Nord&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-17-306880' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/#easy-footnote-bottom-17-306880' title='Steve Coll, &lt;em&gt;Ghost Wars&amp;#160;: The Secret History of the CIA, Afghanistan, and Bin Laden&lt;\/em&gt;, London, Penguin, 2004&amp;#160;; Ali H. Soufan, &lt;em&gt;The Black Banners&amp;#160;: The Inside Story of 9\/11 and the War Against al-Qaeda&lt;\/em&gt;, New York, W. W. Norton &amp;amp; Company, 2011.'><sup>17<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>5 \u2014 D\u00e9stabiliser le pays de l\u2019int\u00e9rieur. Des archives d\u00e9classifi\u00e9es ont r\u00e9v\u00e9l\u00e9 qu\u2019en 1918 les dirigeants britanniques, dont le Premier ministre David Lloyd George et le ministre de la Guerre Winston Churchill, projetaient d\u2019isoler Moscou en cr\u00e9ant une s\u00e9rie d\u2019\u00c9tats-tampons, dont une Pologne reconstitu\u00e9e et une Ukraine ind\u00e9pendante, sur les d\u00e9combres de l\u2019Empire russe. Tout au long de la Guerre froide, les services secrets occidentaux soutinrent ouvertement divers mouvements dissidents et s\u00e9paratistes en URSS et dans le bloc de l\u2019Est, tout en consacrant des ressources consid\u00e9rables \u00e0 la guerre informationnelle, notamment \u00e0 travers les radios <em>Voice of America<\/em> et <em>Radio Free Europe<\/em>&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-18-306880' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/#easy-footnote-bottom-18-306880' title='National Archives, UK. &lt;a href=&quot;https:\/\/discovery.nationalarchives.gov.uk\/details\/r\/C134183&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Cabinet Papers&amp;#160;: Russia. Discussions on Buffer States&lt;\/a&gt; (1918)&amp;#160;; Central Intelligence Agency, &lt;a href=&quot;https:\/\/www.cia.gov\/readingroom\/document\/0005317783&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Covert Action in the Cold War&amp;#160;: Support for Dissidents in the USSR and Eastern Europe&lt;\/a&gt;. Washington, D.C.&amp;#160;: CIA, declassified report, 1999.'><sup>18<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>Or que constatons-nous aujourd\u2019hui&nbsp;&#160;? L\u2019affrontement qui nous oppose \u00e0 l\u2019Occident reproduit trait pour trait la quasi-totalit\u00e9 des conflits et des guerres du pass\u00e9. Voil\u00e0 quatre ans que nous faisons face en Ukraine \u00e0 des mercenaires et conseillers militaires \u00e9trangers, tandis que les sabotages visant la flotte \u00ab&#160;fant\u00f4me&#160;\u00bb de tankers et la militarisation de la mer Noire, de la Baltique et de l\u2019Arctique par les pays de l\u2019OTAN, avec un recours massif aux drones et navires sans \u00e9quipage, pr\u00e9parent les conditions d\u2019un v\u00e9ritable blocus maritime. Les mesures financi\u00e8res, commerciales et \u00e9conomiques impos\u00e9es \u00e0 notre pays sont d\u2019une ampleur sans pr\u00e9c\u00e9dent et ne semblent pouvoir \u00eatre lev\u00e9es dans un avenir proche sans un profond renouvellement des \u00e9lites dirigeantes en Occident. Le financement des marionnettes de Kiev et la militarisation \u00e0 marche forc\u00e9e des \u00c9tats frontaliers de la Russie permettent aux fauteurs de guerre de nous combattre par procuration tout en d\u00e9veloppant leurs propres complexes militaro-industriels. Sur notre territoire comme au sein de la diaspora, des agents d\u2019influence s\u2019appliquent \u00e0 orchestrer la d\u00e9stabilisation du pays, tandis qu\u2019une guerre informationnelle totale d\u00e9verse des flots de contenus destin\u00e9s \u00e0 emp\u00eacher toute appr\u00e9ciation objective des faits et des perspectives qui nous seraient favorables. Dans le m\u00eame temps, on nous oblige \u00e0 combattre sur plusieurs fronts en attisant ou ranimant des foyers de tension dans les pays baltes, autour de la Transnistrie, dans le Caucase du Sud (du conflit entre l\u2019Arm\u00e9nie et l\u2019Azerba\u00efdjan \u00e0 l\u2019affaiblissement de notre partenaire strat\u00e9gique iranien) et en Asie centrale (o\u00f9 les flux d\u2019islamistes radicaux ont explos\u00e9 apr\u00e8s la chute du r\u00e9gime d\u2019Assad en Syrie).<\/p>\n\n\n\n<p>Dans sa doctrine strat\u00e9gique, l\u2019Occident a assign\u00e9 \u00e0 la Russie le statut d\u2019agresseur, de menace pour la s\u00e9curit\u00e9 globale et de principal adversaire&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-19-306880' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/#easy-footnote-bottom-19-306880' title='\u00ab&amp;#160;Russia is the most significant and direct threat to Allies\u2019 security and to peace and stability in the Euro-Atlantic area&amp;#160;\u00bb, concept strat\u00e9gique de l\u2019OTAN adopt\u00e9 \u00e0 Madrid le 29 juin 2022&amp;#160;; \u00ab&amp;#160;Today\u2019s Russia is for now the most significant threat to peace and security in the Euro-Atlantic area&amp;#160;\u00bb. National Security Strategy of the Federal Republic of Germany. 2023. p. 16&lt;br&gt;'><sup>19<\/sup><\/a><\/span><\/span>. Aussi s\u2019empresse-t-il d\u2019augmenter ses budgets militaires, de mettre ses \u00e9conomies sur le pied de guerre et de pr\u00e9parer un blocus total de la Russie, allant jusqu\u2019au verrouillage complet de ses fronti\u00e8res, tout en soumettant ses propres populations \u00e0 une propagande russophobe d\u2019une rare brutalit\u00e9. Nous assistons bien \u00e0 la pr\u00e9paration m\u00e9thodique d\u2019une guerre de grande ampleur contre notre pays, avec la perspective tr\u00e8s concr\u00e8te d\u2019un nouveau \u00ab&#160;rideau de fer&#160;\u00bb \u00e0 l\u2019horizon. Cette strat\u00e9gie se donne \u00e9galement \u00e0 voir dans la confiscation annonc\u00e9e des avoirs russes et la pr\u00e9paration d\u2019un renoncement complet \u00e0 nos ressources \u00e9nerg\u00e9tiques. Une fois encore, la logique est claire&nbsp;&#160;: faute de parvenir \u00e0 infliger une d\u00e9faite strat\u00e9gique \u00e0 la Russie, l\u2019Europe ne pourra pas conserver ses positions sur l\u2019\u00e9chiquier mondial et perdra de ce fait la \u00ab&#160;rente de l\u2019h\u00e9g\u00e9mon&#160;\u00bb dont elle b\u00e9n\u00e9ficiait jusqu\u2019alors&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-20-306880' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/#easy-footnote-bottom-20-306880' title='&lt;a href=&quot;https:\/\/www.mk.ru\/politics\/2025\/09\/26\/evropa-poteryala-strakh-istorik-shishkin-nazval-prichinu-antirossiyskogo-kursa-starogo-sveta.html&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;\u00ab&amp;#160;\u0415\u0432\u0440\u043e\u043f\u0430 \u043f\u043e\u0442\u0435\u0440\u044f\u043b\u0430 \u0441\u0442\u0440\u0430\u0445&amp;#160;\u00bb&amp;#160;: \u0438\u0441\u0442\u043e\u0440\u0438\u043a \u0428\u0438\u0448\u043a\u0438\u043d \u043d\u0430\u0437\u0432\u0430\u043b \u043f\u0440\u0438\u0447\u0438\u043d\u0443 \u0430\u043d\u0442\u0438\u0440\u043e\u0441\u0441\u0438\u0439\u0441\u043a\u043e\u0433\u043e \u043a\u0443\u0440\u0441\u0430 \u0421\u0442\u0430\u0440\u043e\u0433\u043e \u0421\u0432\u0435\u0442\u0430 &amp;#8211; \u041c\u041a&lt;\/a&gt;'><sup>20<\/sup><\/a><\/span><\/span>. \u00c0 cette raison s\u2019ajoute encore la profonde crise interne que traversent nombre de pays occidentaux \u2014 une situation que, par le pass\u00e9, l\u2019Occident a volontiers cherch\u00e9 \u00e0 r\u00e9soudre par la guerre.<\/p>\n\n\n\n<p>La conclusion s\u2019impose donc d\u2019elle-m\u00eame&nbsp;&#160;: \u00e0 moins d\u2019arracher la victoire ou des conditions militaires et politiques per\u00e7ues sans \u00e9quivoque comme une victoire, en Russie comme \u00e0 l\u2019\u00e9tranger, nous ne parviendrons pas \u00e0 contraindre l\u2019Occident \u00e0 n\u00e9gocier. Les exp\u00e9riences pass\u00e9es montrent que les pays occidentaux sont toujours mieux dispos\u00e9s \u00e0 \u00e9couter nos propositions de refonte de l\u2019architecture de s\u00e9curit\u00e9 (ou de simples garanties de s\u00e9curit\u00e9) lorsque les troupes russes mettent le pied \u00e0 Paris ou \u00e0 Berlin. \u00c0 l\u2019inverse, tout signe de bonne volont\u00e9 de notre part a toujours \u00e9t\u00e9 interpr\u00e9t\u00e9 en Occident comme une marque de faiblesse, incitant nos adversaires \u00e0 redoubler d\u2019exigences et \u00e0 se montrer plus obstin\u00e9s et agressifs encore, poursuivant leurs int\u00e9r\u00eats propres sans le moindre \u00e9gard pour les n\u00f4tres. Il n\u2019y a donc aucune place ici pour le <em>wishful thinking<\/em> et l\u2019optimisme b\u00e9at, qui ne peuvent que faire obstacle \u00e0 nos destin\u00e9es.<\/p>\n\n\n\n<p>Cela signifie-t-il pour autant que nous, diplomates, n\u2019ayons aucune marge d\u2019action&nbsp;&#160;? Bien au contraire. Forts de cette exp\u00e9rience historique et de notre analyse de la configuration g\u00e9opolitique, nous devons faire comprendre \u00e0 nos adversaires l\u2019ampleur des risques auxquels ils exposent leurs \u00c9tats et leurs populations s\u2019ils persistent \u00e0 aggraver le conflit avec la Russie. Telle est, en particulier, la politique \u00e0 tenir vis-\u00e0-vis des pays \u00ab&#160;suivistes&#160;\u00bb, ceux qui ont accept\u00e9 de s\u2019embarquer dans une aventure qui n\u2019\u00e9tait pas la leur et qui ne comprendront qu\u2019au terme de la guerre, lorsque leurs alli\u00e9s reculeront devant la pouss\u00e9e de l\u2019arm\u00e9e russe, qu\u2019ils avaient \u00e9t\u00e9 utilis\u00e9s tout du long comme un atout de second ordre. Les Finlandais, les Hongrois et les Roumains l\u2019ont bien senti en 1944, ce qui leur a sans doute permis d\u2019\u00e9viter le pire un an plus tard. Remarquons d\u2019ailleurs qu\u2019ils s\u2019en sont tir\u00e9s \u00e0 bon compte \u2014 en particulier les Finlandais qui, aujourd\u2019hui, violent avec insolence les articles militaires du trait\u00e9 de paix de Paris de 1947.<\/p>\n\n\n\n<p>Par ailleurs, nous devons mettre \u00e0 profit l\u2019exp\u00e9rience de la diplomatie sovi\u00e9tique d\u2019apr\u00e8s-guerre, lorsqu\u2019elle s\u2019appliquait \u00e0 tirer parti des tensions entre les grandes puissances pour mieux briser l\u2019unit\u00e9 du bloc de l\u2019Ouest. C\u2019est ainsi qu\u2019en f\u00e9vrier 1945, \u00e0 la conf\u00e9rence de Yalta, Staline insista pour que la France devienne membre permanent du Conseil de s\u00e9curit\u00e9 de l\u2019ONU, affaiblissant de la sorte le monopole anglo-am\u00e9ricain et introduisant un facteur suppl\u00e9mentaire de concurrence au sein du camp occidental. Il joua ensuite adroitement de la rivalit\u00e9 traditionnelle entre la Grande-Bretagne et les \u00c9tats-Unis, \u00e0 un moment o\u00f9 Churchill s\u2019imaginait pr\u00e9server la grandeur de l\u2019Empire britannique et redoutait la mont\u00e9e en puissance de l\u2019Am\u00e9rique, tandis que Washington aspirait \u00e0 d\u00e9tr\u00f4ner Londres. Comme l\u2019a signal\u00e9 l\u2019historien britannique Geoffrey Roberts&nbsp;&#160;: \u00ab&#160;Staline voyait les divergences entre les alli\u00e9s non comme un obstacle, mais comme une ressource \u00e0 exploiter pour servir les int\u00e9r\u00eats de l\u2019URSS&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-21-306880' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/#easy-footnote-bottom-21-306880' title='Geoffrey Roberts, &lt;em&gt;Stalin\u2019s Wars&amp;#160;: From World War to Cold War, 1939\u20131953&lt;\/em&gt;, New Haven, Yale University Press, 2006.'><sup>21<\/sup><\/a><\/span><\/span>. Et, de fait, cette tactique porta ses fruits. On parvint d\u2019un c\u00f4t\u00e9 \u00e0 instaurer un syst\u00e8me de s\u00e9curit\u00e9 internationale favorable \u00e0 Moscou (l\u2019Organisation des Nations Unies avec un droit de veto des grandes puissances), et de l\u2019autre \u00e0 renforcer l\u2019influence sovi\u00e9tique sur l\u2019Europe de l\u2019Est. Enfin, c\u2019est pr\u00e9cis\u00e9ment ce jeu subtil avec les contradictions parmi les alli\u00e9s qui permit de maintenir une forme d\u2019\u00e9quilibre dans le monde jusqu\u2019\u00e0 la fin des ann\u00e9es 1970&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-22-306880' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote note-digits-2'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/#easy-footnote-bottom-22-306880' title='Jurij \u017dukov, &lt;em&gt;Stalin. Tajny vlasti&lt;\/em&gt;, Moskva, Ve\u010de, 2005.'><sup>22<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>S\u2019il y a un enseignement \u00e0 tirer de l\u2019histoire, c\u2019est qu\u2019il est parfois plus utile de briser une coalition ennemie que de chercher \u00e0 l\u2019affronter en bloc. Comme l\u2019\u00e9crivait justement \u00e0 ce propos Fiodor Tiouttchev le 26 juin 1864&nbsp;&#160;:&nbsp;<\/p>\n\n\n\n<p><em>\u00ab&#160;Vis-\u00e0-vis des puissances occidentales, la seule et unique politique naturelle de la Russie ne doit pas \u00eatre l\u2019alliance avec telle ou telle de ces puissances, mais leur d\u00e9sunion, leur division. Ce n\u2019est que dans cet \u00e9tat de d\u00e9sunion et de division qu\u2019elles cessent de se montrer hostiles envers nous \u2014 par impuissance. Cette dure v\u00e9rit\u00e9 pourra heurter les \u00e2mes sensibles, mais elle reste, en derni\u00e8re analyse, la loi fondamentale de notre existence&#160;\u00bb.&nbsp;<\/em><\/p>\n\n\n\n<p>Nous n\u2019oublierons pas les le\u00e7ons du pass\u00e9. L\u2019Occident n\u2019a jamais voulu de la Russie en qualit\u00e9 de partenaire puissant et ind\u00e9pendant&nbsp;&#160;; s\u2019il la tol\u00e8re, c\u2019est comme victime ou comme troph\u00e9e. L\u2019heure est venue d\u2019agir avec fermet\u00e9, assurance et d\u00e9termination&nbsp;&#160;: c\u2019est seulement alors que nous parviendrons \u00e0 garantir notre s\u00e9curit\u00e9 et obtenir une paix durable \u00e0 des conditions avantageuses pour nous. Toute h\u00e9sitation et tout signe de compromis seront interpr\u00e9t\u00e9s par nos ennemis comme une invitation \u00e0 redoubler d\u2019agressivit\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Poutine ne veut pas n\u00e9gocier avec l\u2019Ukraine \u2014 il veut avancer en Europe.<\/p>\n","protected":false},"author":10,"featured_media":306881,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-speeches.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":25,"_lgc_tts_audio_url":"","_lgc_tts_voice":"","_lgc_tts_publish":false,"_lgc_tts_history_item_id":"","_lgc_tts_generated_at":"","_lgc_tts_status":"","_lgc_tts_error":"","footnotes":""},"categories":[3715],"tags":[],"staff":[2655],"editorial_format":[4943],"serie":[],"audience":[],"geo":[550],"class_list":["post-306880","post","type-post","status-publish","format-standard","hentry","category-doctrines-de-la-russie-de-poutine","staff-guillaume-lancereau","editorial_format-discours","geo-russie"],"acf":{"open_in_webview":false,"accent":"default","_thumbnail_id":306881,"excerpt":"Poutine ne veut pas n\u00e9gocier avec l\u2019Ukraine \u2014 il veut avancer en Europe.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00abTout br\u00fbler jusqu\u2019\u00e0 la Manche\u00bb : la diplomatie russe appelle au sang<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00abTout br\u00fbler jusqu\u2019\u00e0 la Manche\u00bb : la diplomatie russe appelle au sang\" \/>\n<meta property=\"og:description\" content=\"Poutine ne veut pas n\u00e9gocier avec l\u2019Ukraine \u2014 il veut avancer en Europe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-01T05:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-13T15:00:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/gc-russie-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1477\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matheo Malik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/gc-russie-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheo Malik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"25 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/\",\"name\":\"\u00abTout br\u00fbler jusqu\u2019\u00e0 la Manche\u00bb : la diplomatie russe appelle au sang\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/SIPA_01239377_000013-scaled.jpg\",\"datePublished\":\"2025-12-01T05:30:00+00:00\",\"dateModified\":\"2026-06-13T15:00:11+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/SIPA_01239377_000013-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/SIPA_01239377_000013-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Un militaire russe des troupes de d\u00e9fense radiologique, chimique et biologique du groupe de forces Tsentr est photographi\u00e9 dans un \u00e9cran de fum\u00e9e a\u00e9rosol utilis\u00e9 pour dissimuler les unit\u00e9s \u00e0 la reconnaissance lors d'exercices visant \u00e0 faire fonctionner les complexes robotiques terrestres Courier sur un terrain d'entra\u00eenement dans le secteur de Pokrovsk sur la ligne de front. \u00a9 Stanislav Krasilnikov\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00ab&#160;Tout br\u00fbler jusqu\u2019\u00e0 la Manche&#160;\u00bb&#160;: face \u00e0 l\u2019Occident, la diplomatie russe appelle au sang\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\",\"name\":\"Matheo Malik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"caption\":\"Matheo Malik\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00abTout br\u00fbler jusqu\u2019\u00e0 la Manche\u00bb : la diplomatie russe appelle au sang","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00abTout br\u00fbler jusqu\u2019\u00e0 la Manche\u00bb : la diplomatie russe appelle au sang","og_description":"Poutine ne veut pas n\u00e9gocier avec l\u2019Ukraine \u2014 il veut avancer en Europe.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/","og_site_name":"Le Grand Continent","article_published_time":"2025-12-01T05:30:00+00:00","article_modified_time":"2026-06-13T15:00:11+00:00","og_image":[{"width":2560,"height":1477,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/gc-russie-scaled.jpg","type":"image\/jpeg"}],"author":"Matheo Malik","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/gc-russie-scaled.jpg","twitter_misc":{"\u00c9crit par":"Matheo Malik","Dur\u00e9e de lecture estim\u00e9e":"25 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/","url":"https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/","name":"\u00abTout br\u00fbler jusqu\u2019\u00e0 la Manche\u00bb : la diplomatie russe appelle au sang","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/SIPA_01239377_000013-scaled.jpg","datePublished":"2025-12-01T05:30:00+00:00","dateModified":"2026-06-13T15:00:11+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/SIPA_01239377_000013-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/SIPA_01239377_000013-scaled.jpg","width":2560,"height":1707,"caption":"Un militaire russe des troupes de d\u00e9fense radiologique, chimique et biologique du groupe de forces Tsentr est photographi\u00e9 dans un \u00e9cran de fum\u00e9e a\u00e9rosol utilis\u00e9 pour dissimuler les unit\u00e9s \u00e0 la reconnaissance lors d'exercices visant \u00e0 faire fonctionner les complexes robotiques terrestres Courier sur un terrain d'entra\u00eenement dans le secteur de Pokrovsk sur la ligne de front. \u00a9 Stanislav Krasilnikov"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/12\/01\/tout-bruler-jusqua-la-manche-face-a-loccident-la-diplomatie-russe-appelle-au-sang\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00ab&#160;Tout br\u00fbler jusqu\u2019\u00e0 la Manche&#160;\u00bb&#160;: face \u00e0 l\u2019Occident, la diplomatie russe appelle au sang"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45","name":"Matheo Malik","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","caption":"Matheo Malik"}}]}},"lgc_categories":[{"id":3715,"name":"Doctrines de la Russie de Poutine","slug":"doctrines-de-la-russie-de-poutine"}],"lgc_author":{"id":2655,"name":"Guillaume Lancereau","slug":"guillaume-lancereau","description":"Guillaume Lancereau est chercheur associ\u00e9 au Democracy Institute de la Central European University (Budapest) et au Centre de recherches historiques de l'EHESS. Sp\u00e9cialiste de la R\u00e9volution fran\u00e7aise et de son historiographie, ses recherches actuelles portent sur l'histoire de la technocratie et de la contre-r\u00e9volution au XIXe si\u00e8cle.","first_name":"Guillaume","last_name":"Lancereau","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/03\/GL.jpg","width":2335,"height":2231,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/SIPA_01239377_000013-scaled.jpg","width":2560,"height":1707,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/SIPA_01239377_000013-scaled.jpg","width":2560,"height":1707,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/306880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=306880"}],"version-history":[{"count":42,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/306880\/revisions"}],"predecessor-version":[{"id":340225,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/306880\/revisions\/340225"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/306881"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=306880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=306880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=306880"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=306880"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=306880"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=306880"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=306880"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=306880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}