{"id":304091,"date":"2025-11-04T13:14:07","date_gmt":"2025-11-04T12:14:07","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=304091"},"modified":"2025-11-20T10:19:16","modified_gmt":"2025-11-20T09:19:16","slug":"laudience-de-nick-fuentes-a-ete-presque-multipliee-par-deux-depuis-lassassinat-de-charlie-kirk","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2025\/11\/04\/laudience-de-nick-fuentes-a-ete-presque-multipliee-par-deux-depuis-lassassinat-de-charlie-kirk\/","title":{"rendered":"L\u2019audience de Nick Fuentes a \u00e9t\u00e9 presque multipli\u00e9e par deux depuis l\u2019assassinat de Charlie Kirk"},"content":{"rendered":"\n<p>Nick Fuentes, l\u2019influenceur MAGA supr\u00e9maciste blanc connu pour ses propos antis\u00e9mites, n\u00e9gationnistes, sexistes et sa sympathie vis-\u00e0-vis du r\u00e9gime nazi, a consid\u00e9rablement b\u00e9n\u00e9fici\u00e9 de <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/09\/11\/qui-etait-charlie-kirk-le-militant-trumpiste-assassine-dans-lutah\/\">l\u2019assassinat de Charlie Kirk<\/a>, le 10 septembre. Bien que controvers\u00e9 au sein m\u00eame de la base du parti, il est d\u00e9sormais l&rsquo;un des commentateurs les plus scrut\u00e9s par l\u2019administration Trump pour suivre les courants rassemblant ses \u00e9lecteurs.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Fuentes est entr\u00e9 la semaine derni\u00e8re dans une nouvelle phase de sa popularit\u00e9 lorsqu&rsquo;il a \u00e9t\u00e9 invit\u00e9 au podcast de Tucker Carlson, le 2e plus \u00e9cout\u00e9 sur Spotify aux \u00c9tats-Unis apr\u00e8s Joe Rogan.<\/li>\n\n\n\n<li>Son audience a \u00e9t\u00e9 multipli\u00e9e par deux sur Rumble, une plateforme conservatrice de streaming en partie financ\u00e9e par Peter Thiel, Vivek Ramaswamy et J.D. Vance, passant d\u2019environ 250 000 abonn\u00e9s \u00e0 la fin de l\u2019\u00e9t\u00e9 \u00e0 plus de 470 000 aujourd\u2019hui.<\/li>\n\n\n\n<li>Sur X (anciennement Twitter), le r\u00e9seau social rachet\u00e9 par Elon Musk \u00e0 l\u2019automne 2022, son ascension est \u00e9galement fulgurante&#160;: Fuentes affiche d\u00e9sormais plus d\u2019un million d\u2019abonn\u00e9s, contre moins de 500 000 au d\u00e9but de l\u2019ann\u00e9e.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/WJ4tX\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Si Nick Fuentes n\u2019est pas une personnalit\u00e9 <em>mainstream <\/em>au sein de l\u2019univers MAGA \u2014 son audience demeure bien inf\u00e9rieure aux poids lourds de l\u2019extr\u00eame-droite am\u00e9ricaine comme Tucker Carlson (17 millions d\u2019abonn\u00e9s sur X), Ben Shapiro (8 millions) ou encore Candace Owens (7 millions) \u2014, il occupe une place de plus en plus importante aupr\u00e8s <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/23\/tiktok-et-joe-rogan-comment-donald-trump-sest-attire-les-faveurs-de-la-jeunesse-surtout-masculine-americaine-depuis-2016\/\">des jeunes \u00e9lecteurs masculins<\/a> du Parti r\u00e9publicain, comblant le vide laiss\u00e9 par <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/09\/20\/les-purges-menees-par-ladministration-trump-et-le-mouvement-maga-apres-lassassinat-de-charlie-kirk-un-premier-bilan\/\">la mort de Kirk<\/a>. Ses partisans sont appel\u00e9s des \u00ab&#160;Groypers&#160;\u00bb.<\/p>\n\n\n\n<p>Selon l\u2019\u00e9ditorialiste <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/08\/11\/entretien-rod-dreher\/\">Rod Dreher, un proche de J.D. Vance<\/a>, 30 \u00e0 40&#160;% des assistants d\u2019\u00e9lus r\u00e9publicains \u00e2g\u00e9s de moins de 30 ans travaillant \u00e0 Washington seraient des Groypers.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Bien qu\u2019il ait lanc\u00e9 son programme <em>America First<\/em> en 2017, ann\u00e9e marqu\u00e9e par l\u2019arriv\u00e9e au pouvoir de Trump, Fuentes est rest\u00e9 dans l\u2019ombre du mouvement, streamant r\u00e9guli\u00e8rement pour une audience de quelques dizaines de milliers de personnes.<\/li>\n\n\n\n<li>Apr\u00e8s avoir particip\u00e9 aux rassemblements ayant d\u00e9bouch\u00e9 sur l\u2019assaut du Capitole, le 6 janvier 2021, il a \u00e9t\u00e9 banni de nombreux r\u00e9seaux sociaux et plateformes lui permettant de mon\u00e9tiser ses contenus \u2014 DLive, Twitter, PayPal, Patreon\u2026 \u2014 en raison de son discours haineux et de ses propos racistes et antis\u00e9mites.<\/li>\n\n\n\n<li>C\u2019est en mai 2024 que Twitter permet son retour durable sur la plateforme, suite \u00e0 une r\u00e9activation momentan\u00e9e de son compte en janvier 2023 qui n\u2019aura dur\u00e9 que quelques heures \u2014 Fuentes ayant profit\u00e9 de celle-ci pour d\u00e9clarer&#160;: \u00ab&#160;Les Juifs contr\u00f4lent les m\u00e9dias&#160;\u00bb.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/sufi9\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Fuentes \u00e9tait l\u2019un des principaux critiques de Charlie Kirk, qu\u2019il accusait de ne pas \u00eatre assez radical vis-\u00e0-vis de l\u2019immigration ou des personnes LGBT.<\/li>\n\n\n\n<li>L\u2019\u00e9mergence de rumeurs quant \u00e0 l\u2019implication d\u2019un Groyper dans l\u2019assassinat de Kirk lui a conf\u00e9r\u00e9 une audience nationale.<\/li>\n\n\n\n<li>Les donn\u00e9es Google indiquent une explosion des recherches pour Nick Fuentes \u00e0 la mi-septembre.<\/li>\n<\/ul>\n\n\n\n<p>L\u2019inverview r\u00e9cente de Fuentes par Tucker Carlson et le blanc-seing octroy\u00e9 \u00e0 celle-ci par <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/11\/03\/kevin-roberts-projet-2025-changement-de-regime\/\">Kevin Roberts, le pr\u00e9sident de la Heritage Foundation<\/a>, pourrait signaler une \u00e9volution radicale du Parti r\u00e9publicain, r\u00e9activant un antis\u00e9mitisme conservateur incarn\u00e9 par des figures comme Charles Lindbergh ou, plus r\u00e9cemment, David Duke \u2014 qui a particip\u00e9 en 2024 \u00e0 un rally de l\u2019America First Political Action Conference \u00e0 D\u00e9troit, aux c\u00f4t\u00e9s de Fuentes.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Dans sa prise de position sur Fuentes, Roberts a appel\u00e9 les \u00e9lecteurs conservateurs \u00e0 \u00ab&#160;se concentrer sur nos adversaires politiques de gauche, plut\u00f4t que d\u2019attaquer nos amis de droite&#160;\u00bb.<\/li>\n\n\n\n<li>Il s\u2019agit d\u2019une r\u00e8gle de plus en plus tenue par certains conservateurs, r\u00e9sum\u00e9e dans la formule \u00ab&#160;No Enemies To The Right&#160;\u00bb (\u00ab&#160;Pas d\u2019adversaire \u00e0 droite&#160;\u00bb).<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">There has been speculation that <a href=\"https:\/\/twitter.com\/Heritage?ref_src=twsrc%5Etfw\">@Heritage<\/a> is distancing itself from <a href=\"https:\/\/twitter.com\/TuckerCarlson?ref_src=twsrc%5Etfw\">@TuckerCarlson<\/a> over the past 24 hours.<br><br>I want to put that to rest right now\u2014here are my thoughts&#160;: <a href=\"https:\/\/t.co\/F8bcxBIqKI\">pic.twitter.com\/F8bcxBIqKI<\/a><\/p>&mdash; Kevin Roberts (@KevinRobertsTX) <a href=\"https:\/\/twitter.com\/KevinRobertsTX\/status\/1983958755613262324?ref_src=twsrc%5Etfw\">October 30, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En octobre, J.D. Vance avait minimis\u00e9 l\u2019importance de messages racistes, antis\u00e9mites et homophobes envoy\u00e9s sur un groupe Telegram par plusieurs jeunes responsables du Parti r\u00e9publicain. Des captures d\u2019\u00e9cran faisaient \u00e9galement \u00e9tat de blagues sur les chambres \u00e0 gaz, l&rsquo;esclavage et le viol.<\/li>\n\n\n\n<li>Le vice-pr\u00e9sident am\u00e9ricain avait d\u00e9clar\u00e9&#160;: \u00ab&#160;La r\u00e9alit\u00e9, c&rsquo;est que les enfants font des b\u00eatises, surtout les jeunes gar\u00e7ons. Ils racontent des blagues provocantes et blessantes. C&rsquo;est normal chez les enfants. Et je ne veux vraiment pas que nous vivions dans un pays o\u00f9 un enfant qui raconte une blague stupide, une blague tr\u00e8s blessante et stupide, voit sa vie ruin\u00e9e \u00e0 cause de cela&#160;\u00bb.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Sur Rumble, la plateforme conservatrice qui h\u00e9berge l\u2019\u00e9mission en ligne <em>America First<\/em>, Nick Fuentes affiche d\u00e9sormais pr\u00e8s de 500 000 abonn\u00e9s \u2014 contre 250 000 \u00e0 la fin de l\u2019\u00e9t\u00e9, avant l\u2019assassinat de Charlie Kirk.<\/p>\n<p>L\u2019influenceur, qui incarne une frange antis\u00e9mite de la coalition MAGA, occupe une place de plus en plus importante aupr\u00e8s des jeunes \u00e9lecteurs masculins du Parti r\u00e9publicain.<\/p>\n","protected":false},"author":2622,"featured_media":304098,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":4,"footnotes":""},"categories":[1731],"tags":[],"staff":[],"editorial_format":[4942],"serie":[],"audience":[],"geo":[525],"class_list":["post-304091","post","type-post","status-publish","format-standard","hentry","category-politique","editorial_format-actu-breves","geo-ameriques"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":304098,"excerpt":"Sur Rumble, la plateforme conservatrice qui h\u00e9berge l\u2019\u00e9mission en ligne <em>America First<\/em>, Nick Fuentes affiche d\u00e9sormais pr\u00e8s de 500 000 abonn\u00e9s \u2014 contre 250 000 \u00e0 la fin de l\u2019\u00e9t\u00e9, avant l\u2019assassinat de Charlie Kirk.\r\n\r\nL\u2019influenceur, qui incarne une frange antis\u00e9mite de la coalition MAGA, occupe une place de plus en plus importante aupr\u00e8s des jeunes \u00e9lecteurs masculins du Parti r\u00e9publicain.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L\u2019audience de Nick Fuentes a doubl\u00e9 depuis l&#039;assassinat de Kirk<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/11\/04\/laudience-de-nick-fuentes-a-ete-presque-multipliee-par-deux-depuis-lassassinat-de-charlie-kirk\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019audience de Nick Fuentes a doubl\u00e9 depuis l&#039;assassinat de Kirk\" \/>\n<meta property=\"og:description\" content=\"Sur Rumble, la plateforme conservatrice qui h\u00e9berge l\u2019\u00e9mission en ligne America First, Nick Fuentes affiche d\u00e9sormais pr\u00e8s de 500 000 abonn\u00e9s \u2014 contre 250 000 \u00e0 la fin de l\u2019\u00e9t\u00e9, avant l\u2019assassinat de Charlie Kirk.  L\u2019influenceur, qui incarne une frange antis\u00e9mite de la coalition MAGA, occupe une place de plus en plus importante aupr\u00e8s des jeunes \u00e9lecteurs masculins du Parti r\u00e9publicain.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2025\/11\/04\/laudience-de-nick-fuentes-a-ete-presque-multipliee-par-deux-depuis-lassassinat-de-charlie-kirk\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-04T12:14:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-20T09:19:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/gc-share-nick-fuentes-audience.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1882\" \/>\n\t<meta property=\"og:image:height\" content=\"1050\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Marin Saillofest\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/gc-share-nick-fuentes-audience.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marin Saillofest\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/11\/04\/laudience-de-nick-fuentes-a-ete-presque-multipliee-par-deux-depuis-lassassinat-de-charlie-kirk\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/11\/04\/laudience-de-nick-fuentes-a-ete-presque-multipliee-par-deux-depuis-lassassinat-de-charlie-kirk\/\",\"name\":\"L\u2019audience de Nick Fuentes a doubl\u00e9 depuis l'assassinat de Kirk\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/11\/04\/laudience-de-nick-fuentes-a-ete-presque-multipliee-par-deux-depuis-lassassinat-de-charlie-kirk\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/11\/04\/laudience-de-nick-fuentes-a-ete-presque-multipliee-par-deux-depuis-lassassinat-de-charlie-kirk\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/gc-nick-fuentes-audience.png\",\"datePublished\":\"2025-11-04T12:14:07+00:00\",\"dateModified\":\"2025-11-20T09:19:16+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/11\/04\/laudience-de-nick-fuentes-a-ete-presque-multipliee-par-deux-depuis-lassassinat-de-charlie-kirk\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2025\/11\/04\/laudience-de-nick-fuentes-a-ete-presque-multipliee-par-deux-depuis-lassassinat-de-charlie-kirk\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/11\/04\/laudience-de-nick-fuentes-a-ete-presque-multipliee-par-deux-depuis-lassassinat-de-charlie-kirk\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/gc-nick-fuentes-audience.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/gc-nick-fuentes-audience.png\",\"width\":1872,\"height\":1044},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/11\/04\/laudience-de-nick-fuentes-a-ete-presque-multipliee-par-deux-depuis-lassassinat-de-charlie-kirk\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019audience de Nick Fuentes a \u00e9t\u00e9 presque multipli\u00e9e par deux depuis l\u2019assassinat de Charlie Kirk\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833\",\"name\":\"Marin Saillofest\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g\",\"caption\":\"Marin Saillofest\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019audience de Nick Fuentes a doubl\u00e9 depuis l'assassinat de Kirk","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2025\/11\/04\/laudience-de-nick-fuentes-a-ete-presque-multipliee-par-deux-depuis-lassassinat-de-charlie-kirk\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019audience de Nick Fuentes a doubl\u00e9 depuis l'assassinat de Kirk","og_description":"Sur Rumble, la plateforme conservatrice qui h\u00e9berge l\u2019\u00e9mission en ligne America First, Nick Fuentes affiche d\u00e9sormais pr\u00e8s de 500 000 abonn\u00e9s \u2014 contre 250 000 \u00e0 la fin de l\u2019\u00e9t\u00e9, avant l\u2019assassinat de Charlie Kirk.  L\u2019influenceur, qui incarne une frange antis\u00e9mite de la coalition MAGA, occupe une place de plus en plus importante aupr\u00e8s des jeunes \u00e9lecteurs masculins du Parti r\u00e9publicain.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2025\/11\/04\/laudience-de-nick-fuentes-a-ete-presque-multipliee-par-deux-depuis-lassassinat-de-charlie-kirk\/","og_site_name":"Le Grand Continent","article_published_time":"2025-11-04T12:14:07+00:00","article_modified_time":"2025-11-20T09:19:16+00:00","og_image":[{"width":1882,"height":1050,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/gc-share-nick-fuentes-audience.png","type":"image\/png"}],"author":"Marin Saillofest","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/gc-share-nick-fuentes-audience.png","twitter_misc":{"\u00c9crit par":"Marin Saillofest","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/11\/04\/laudience-de-nick-fuentes-a-ete-presque-multipliee-par-deux-depuis-lassassinat-de-charlie-kirk\/","url":"https:\/\/legrandcontinent.eu\/fr\/2025\/11\/04\/laudience-de-nick-fuentes-a-ete-presque-multipliee-par-deux-depuis-lassassinat-de-charlie-kirk\/","name":"L\u2019audience de Nick Fuentes a doubl\u00e9 depuis l'assassinat de Kirk","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/11\/04\/laudience-de-nick-fuentes-a-ete-presque-multipliee-par-deux-depuis-lassassinat-de-charlie-kirk\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/11\/04\/laudience-de-nick-fuentes-a-ete-presque-multipliee-par-deux-depuis-lassassinat-de-charlie-kirk\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/gc-nick-fuentes-audience.png","datePublished":"2025-11-04T12:14:07+00:00","dateModified":"2025-11-20T09:19:16+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/11\/04\/laudience-de-nick-fuentes-a-ete-presque-multipliee-par-deux-depuis-lassassinat-de-charlie-kirk\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2025\/11\/04\/laudience-de-nick-fuentes-a-ete-presque-multipliee-par-deux-depuis-lassassinat-de-charlie-kirk\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/11\/04\/laudience-de-nick-fuentes-a-ete-presque-multipliee-par-deux-depuis-lassassinat-de-charlie-kirk\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/gc-nick-fuentes-audience.png","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/gc-nick-fuentes-audience.png","width":1872,"height":1044},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/11\/04\/laudience-de-nick-fuentes-a-ete-presque-multipliee-par-deux-depuis-lassassinat-de-charlie-kirk\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"L\u2019audience de Nick Fuentes a \u00e9t\u00e9 presque multipli\u00e9e par deux depuis l\u2019assassinat de Charlie Kirk"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833","name":"Marin Saillofest","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g","caption":"Marin Saillofest"}}]}},"lgc_categories":[{"id":1731,"name":"Politique","slug":"politique"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/gc-nick-fuentes-audience.png","width":1872,"height":1044,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/304091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/2622"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=304091"}],"version-history":[{"count":5,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/304091\/revisions"}],"predecessor-version":[{"id":305547,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/304091\/revisions\/305547"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/304098"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=304091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=304091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=304091"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=304091"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=304091"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=304091"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=304091"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=304091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}