{"id":301754,"date":"2025-10-18T07:00:00","date_gmt":"2025-10-18T05:00:00","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=301754"},"modified":"2025-10-17T17:10:50","modified_gmt":"2025-10-17T15:10:50","slug":"en-chine-des-cette-annee-les-ventes-de-couches-pour-adultes-devraient-depasser-celles-des-couches-pour-bebes","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2025\/10\/18\/en-chine-des-cette-annee-les-ventes-de-couches-pour-adultes-devraient-depasser-celles-des-couches-pour-bebes\/","title":{"rendered":"En Chine, d\u00e8s cette ann\u00e9e, les ventes de couches pour adultes devraient d\u00e9passer celles des couches pour b\u00e9b\u00e9s"},"content":{"rendered":"\n<p>Comme de nombreux pays, dont <a href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/07\/12\/plus-de-la-moitie-des-pays-europeens-ont-deja-atteint-leur-pic-de-population\/\">plus de la moiti\u00e9 des \u00c9tats europ\u00e9ens<\/a>, la Chine a atteint son pic de population en 2021, avec 1,426 milliards d\u2019habitants. Le pays devrait ainsi perdre des habitants chaque ann\u00e9e jusqu\u2019\u00e0 la fin du si\u00e8cle, lorsqu\u2019il devrait atteindre une population estim\u00e9e \u00e0 633 millions \u2014 soit moins de la moiti\u00e9 de sa taille actuelle.<\/p>\n\n\n\n<p>La structure m\u00eame de la population chinoise devrait, dans le m\u00eame temps, consid\u00e9rablement \u00e9voluer.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>D\u00e8s l&rsquo;ann\u00e9e prochaine, il y aura plus de personnes \u00e2g\u00e9es de 65 ans que de personnes \u00e2g\u00e9es de 0 \u00e0 14 ans en Chine.<\/li>\n\n\n\n<li>En 2086, la part des personnes \u00e2g\u00e9es devrait repr\u00e9senter pr\u00e8s de la moiti\u00e9 (47,8&#160;%) de la population du pays, soit pr\u00e8s de 380 millions de personnes.<\/li>\n\n\n\n<li>Il y aura ainsi plus de seniors en Chine que d\u2019habitants dans l\u2019Union europ\u00e9enne (dont la population devrait \u00eatre d\u2019environ 360 millions d\u2019ici 2086) \u2014 sous r\u00e9serve qu\u2019aucun nouvel \u00c9tat ne rejoigne le bloc.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/3p5te\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>La reconfiguration d\u00e9mographique de la Chine est un ph\u00e9nom\u00e8ne anticip\u00e9 par de nombreux industriels. L\u2019un des march\u00e9s les plus touch\u00e9s par le vieillissement de la population est celui des couches, un secteur qui repr\u00e9sente environ dix milliards d\u2019euros par an.<\/p>\n\n\n\n<p>Or, si les produits pour b\u00e9b\u00e9s repr\u00e9sentaient jusqu\u2019\u00e0 pr\u00e9sent la majorit\u00e9 des ventes, le march\u00e9 devrait \u00eatre domin\u00e9 d\u00e8s cette ann\u00e9e par les couches pour adultes.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L\u2019entreprise de recherche CLSA estime que le march\u00e9 des couches pour adultes devrait repr\u00e9senter environ 16 milliards de dollars par an d\u2019ici la fin de la d\u00e9cennie et 30 milliards d\u2019ici 2040 \u2014 contre seulement 800 millions en 2020&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-301754' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/10\/18\/en-chine-des-cette-annee-les-ventes-de-couches-pour-adultes-devraient-depasser-celles-des-couches-pour-bebes\/#easy-footnote-bottom-1-301754' title='Leo Lewis et Edward White, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.ft.com\/content\/6fc578dd-72b3-40a9-b906-324e7ae2c91a&quot;&gt;Nappy manufacturers shift focus in China from infants to elderly&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;Financial Times&lt;\/em&gt;, 29 novembre 2021.'><sup>1<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>Le march\u00e9 des couches pour b\u00e9b\u00e9s devrait quant \u00e0 lui se contracter en raison de la baisse du taux de fertilit\u00e9 et de la population infantile au cours des prochaines ann\u00e9es.<\/li>\n\n\n\n<li>Ce ph\u00e9nom\u00e8ne s\u2019accompagne aussi d\u2019<a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/03\/14\/dici-2030-la-chine-devrait-avoir-deux-fois-plus-danimaux-de-compagnie-que-denfants-en-bas-age-pourquoi\/\">une augmentation de la population d\u2019animaux domestiqu\u00e9s<\/a>, qui devraient atteindre dans le pays le double du nombre d\u2019enfants en bas-\u00e2ge d\u00e8s la fin de la d\u00e9cennie.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/HlDjq\/\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>La Chine n\u2019est pas le seul pays \u00e0 franchir ce point de bascule. On estime que plus de couches pour adultes que de couches pour enfant sont vendues au Japon depuis le d\u00e9but des ann\u00e9es 2010&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-301754' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/10\/18\/en-chine-des-cette-annee-les-ventes-de-couches-pour-adultes-devraient-depasser-celles-des-couches-pour-bebes\/#easy-footnote-bottom-2-301754' title='Mariko Oi, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.bbc.com\/news\/business-68672186&quot;&gt;Japan nappy maker shifts from babies to adults&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;BBC&lt;\/em&gt;, 27 mars 2024.'><sup>2<\/sup><\/a><\/span><\/span>, tandis que la Cor\u00e9e du Sud serait \u00e9galement sur le point de rejoindre ce club restreint de pays&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-301754' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/10\/18\/en-chine-des-cette-annee-les-ventes-de-couches-pour-adultes-devraient-depasser-celles-des-couches-pour-bebes\/#easy-footnote-bottom-3-301754' title='Jung Sang-hyuk, Kim Seo-young et Kim Mi-geon, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.chosun.com\/english\/long-reads-en\/2025\/01\/23\/IP3EAH2GOZHL3FHCH5HJPRB534\/&quot;&gt;In S. Korea&amp;rsquo;s super-aged society, diapers are no longer just for babies&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;The Chosun Daily&lt;\/em&gt;, 23 janvier 2025.'><sup>3<\/sup><\/a><\/span><\/span>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Chine devrait rejoindre cette ann\u00e9e le club restreint des pays \u2014 parmi lesquels figure notamment le Japon \u2014 qui vendent plus de couches pour adultes que pour b\u00e9b\u00e9s chaque ann\u00e9e.<\/p>\n<p>Ce point de bascule traduit l\u2019\u00e9volution de la composition d\u00e9mographique chinoise \u2014 d\u2019ici 2086, les seniors devraient repr\u00e9senter pr\u00e8s de la moiti\u00e9 de la population du pays.<\/p>\n","protected":false},"author":2622,"featured_media":301758,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":3,"footnotes":""},"categories":[3468],"tags":[],"staff":[],"editorial_format":[4942],"serie":[],"audience":[],"geo":[531],"class_list":["post-301754","post","type-post","status-publish","format-standard","hentry","category-donnees-qui-changent-la-donne","editorial_format-actu-breves","geo-chine"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":301758,"excerpt":"La Chine devrait rejoindre cette ann\u00e9e le club restreint des pays \u2014 parmi lesquels figure notamment le Japon \u2014 qui vendent plus de couches pour adultes que pour b\u00e9b\u00e9s chaque ann\u00e9e.\r\n\r\nCe point de bascule traduit l\u2019\u00e9volution de la composition d\u00e9mographique chinoise \u2014 d\u2019ici 2086, les seniors devraient repr\u00e9senter pr\u00e8s de la moiti\u00e9 de la population du pays.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Plus de couches pour adulte sont vendues en Chine que pour b\u00e9b\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/10\/18\/en-chine-des-cette-annee-les-ventes-de-couches-pour-adultes-devraient-depasser-celles-des-couches-pour-bebes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plus de couches pour adulte sont vendues en Chine que pour b\u00e9b\u00e9\" \/>\n<meta property=\"og:description\" content=\"La Chine devrait rejoindre cette ann\u00e9e le club restreint des pays \u2014 parmi lesquels figure notamment le Japon \u2014 qui vendent plus de couches pour adultes que pour b\u00e9b\u00e9s chaque ann\u00e9e.  Ce point de bascule traduit l\u2019\u00e9volution de la composition d\u00e9mographique chinoise \u2014 d\u2019ici 2086, les seniors devraient repr\u00e9senter pr\u00e8s de la moiti\u00e9 de la population du pays.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2025\/10\/18\/en-chine-des-cette-annee-les-ventes-de-couches-pour-adultes-devraient-depasser-celles-des-couches-pour-bebes\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-18T05:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/10\/gc-share-couches-adultes-chine.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1868\" \/>\n\t<meta property=\"og:image:height\" content=\"1054\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Marin Saillofest\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/10\/gc-share-couches-adultes-chine.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marin Saillofest\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/10\/18\/en-chine-des-cette-annee-les-ventes-de-couches-pour-adultes-devraient-depasser-celles-des-couches-pour-bebes\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/10\/18\/en-chine-des-cette-annee-les-ventes-de-couches-pour-adultes-devraient-depasser-celles-des-couches-pour-bebes\/\",\"name\":\"Plus de couches pour adulte sont vendues en Chine que pour b\u00e9b\u00e9\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/10\/18\/en-chine-des-cette-annee-les-ventes-de-couches-pour-adultes-devraient-depasser-celles-des-couches-pour-bebes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/10\/18\/en-chine-des-cette-annee-les-ventes-de-couches-pour-adultes-devraient-depasser-celles-des-couches-pour-bebes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/10\/gc-couches-adultes-chine.png\",\"datePublished\":\"2025-10-18T05:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/10\/18\/en-chine-des-cette-annee-les-ventes-de-couches-pour-adultes-devraient-depasser-celles-des-couches-pour-bebes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2025\/10\/18\/en-chine-des-cette-annee-les-ventes-de-couches-pour-adultes-devraient-depasser-celles-des-couches-pour-bebes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/10\/18\/en-chine-des-cette-annee-les-ventes-de-couches-pour-adultes-devraient-depasser-celles-des-couches-pour-bebes\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/10\/gc-couches-adultes-chine.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/10\/gc-couches-adultes-chine.png\",\"width\":1884,\"height\":1050},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/10\/18\/en-chine-des-cette-annee-les-ventes-de-couches-pour-adultes-devraient-depasser-celles-des-couches-pour-bebes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En Chine, d\u00e8s cette ann\u00e9e, les ventes de couches pour adultes devraient d\u00e9passer celles des couches pour b\u00e9b\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833\",\"name\":\"Marin Saillofest\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g\",\"caption\":\"Marin Saillofest\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plus de couches pour adulte sont vendues en Chine que pour b\u00e9b\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2025\/10\/18\/en-chine-des-cette-annee-les-ventes-de-couches-pour-adultes-devraient-depasser-celles-des-couches-pour-bebes\/","og_locale":"fr_FR","og_type":"article","og_title":"Plus de couches pour adulte sont vendues en Chine que pour b\u00e9b\u00e9","og_description":"La Chine devrait rejoindre cette ann\u00e9e le club restreint des pays \u2014 parmi lesquels figure notamment le Japon \u2014 qui vendent plus de couches pour adultes que pour b\u00e9b\u00e9s chaque ann\u00e9e.  Ce point de bascule traduit l\u2019\u00e9volution de la composition d\u00e9mographique chinoise \u2014 d\u2019ici 2086, les seniors devraient repr\u00e9senter pr\u00e8s de la moiti\u00e9 de la population du pays.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2025\/10\/18\/en-chine-des-cette-annee-les-ventes-de-couches-pour-adultes-devraient-depasser-celles-des-couches-pour-bebes\/","og_site_name":"Le Grand Continent","article_published_time":"2025-10-18T05:00:00+00:00","og_image":[{"width":1868,"height":1054,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/10\/gc-share-couches-adultes-chine.png","type":"image\/png"}],"author":"Marin Saillofest","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/10\/gc-share-couches-adultes-chine.png","twitter_misc":{"\u00c9crit par":"Marin Saillofest","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/10\/18\/en-chine-des-cette-annee-les-ventes-de-couches-pour-adultes-devraient-depasser-celles-des-couches-pour-bebes\/","url":"https:\/\/legrandcontinent.eu\/fr\/2025\/10\/18\/en-chine-des-cette-annee-les-ventes-de-couches-pour-adultes-devraient-depasser-celles-des-couches-pour-bebes\/","name":"Plus de couches pour adulte sont vendues en Chine que pour b\u00e9b\u00e9","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/10\/18\/en-chine-des-cette-annee-les-ventes-de-couches-pour-adultes-devraient-depasser-celles-des-couches-pour-bebes\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/10\/18\/en-chine-des-cette-annee-les-ventes-de-couches-pour-adultes-devraient-depasser-celles-des-couches-pour-bebes\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/10\/gc-couches-adultes-chine.png","datePublished":"2025-10-18T05:00:00+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/10\/18\/en-chine-des-cette-annee-les-ventes-de-couches-pour-adultes-devraient-depasser-celles-des-couches-pour-bebes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2025\/10\/18\/en-chine-des-cette-annee-les-ventes-de-couches-pour-adultes-devraient-depasser-celles-des-couches-pour-bebes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/10\/18\/en-chine-des-cette-annee-les-ventes-de-couches-pour-adultes-devraient-depasser-celles-des-couches-pour-bebes\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/10\/gc-couches-adultes-chine.png","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/10\/gc-couches-adultes-chine.png","width":1884,"height":1050},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/10\/18\/en-chine-des-cette-annee-les-ventes-de-couches-pour-adultes-devraient-depasser-celles-des-couches-pour-bebes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"En Chine, d\u00e8s cette ann\u00e9e, les ventes de couches pour adultes devraient d\u00e9passer celles des couches pour b\u00e9b\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833","name":"Marin Saillofest","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g","caption":"Marin Saillofest"}}]}},"lgc_categories":[{"id":3468,"name":"Donn\u00e9es qui changent la donne","slug":"donnees-qui-changent-la-donne"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/10\/gc-couches-adultes-chine.png","width":1884,"height":1050,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/301754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/2622"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=301754"}],"version-history":[{"count":6,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/301754\/revisions"}],"predecessor-version":[{"id":301762,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/301754\/revisions\/301762"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/301758"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=301754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=301754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=301754"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=301754"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=301754"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=301754"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=301754"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=301754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}