{"id":296897,"date":"2025-09-07T16:29:22","date_gmt":"2025-09-07T14:29:22","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=296897"},"modified":"2025-09-07T20:27:40","modified_gmt":"2025-09-07T18:27:40","slug":"videos-lia-qui-fait-parler-les-morts-de-la-guerre-de-poutine","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2025\/09\/07\/videos-lia-qui-fait-parler-les-morts-de-la-guerre-de-poutine\/","title":{"rendered":"Vid\u00e9os&#160;: l\u2019IA qui fait parler les morts de la guerre de Poutine"},"content":{"rendered":"\n<p class=\"intro\">Dans la lign\u00e9e des slavophiles du XIXe si\u00e8cle et des nationalistes religieux du si\u00e8cle suivant, les id\u00e9ologues de la Russie d\u2019aujourd\u2019hui mettent volontiers l\u2019accent sur la spiritualit\u00e9 exceptionnelle des Russes, p\u00e9trie par des si\u00e8cles d\u2019orthodoxie et de contemplation d\u2019espaces infinis, face \u00e0 un Occident mat\u00e9rialiste et d\u00e9g\u00e9n\u00e9r\u00e9.<\/p>\n\n\n\n<p class=\"intro\">La derni\u00e8re tendance num\u00e9rique en Russie est cependant plus proche d\u2019un \u00e9pisode de <em>Black Mirror<\/em> que du monde des ermites stylites du christianisme orthodoxe ou des cosmistes du d\u00e9but du si\u00e8cle dernier.<\/p>\n\n\n\n<p class=\"intro\">Il s\u2019agit, en l\u2019esp\u00e8ce, d\u2019un service de production num\u00e9rique par intelligence artificielle proposant aux familles en deuil de mettre en sc\u00e8ne leurs derniers adieux, sous forme de vid\u00e9o, \u00e0 leurs proches tomb\u00e9s sur le front ukrainien.&nbsp;<\/p>\n\n\n\n<p class=\"intro\">Pour 1&nbsp;500 roubles (16 euros), on obtient ainsi un court montage d\u2019une \u00e9treinte et un geste d\u2019adieu avec son fils, son p\u00e8re ou son \u00e9poux.<\/p>\n\n\n\n<p class=\"intro\">Pour 500 roubles de plus, le disparu tant\u00f4t se retrouve affubl\u00e9 d\u2019ailes d\u2019ange, tant\u00f4t grimpe un escalier lumineux vers l\u2019au-del\u00e0.&nbsp;<\/p>\n\n\n\n<p class=\"intro\">Pour 3 000 ou 4 000, il est \u00e9galement possible d\u2019incruster la voix r\u00e9elle du d\u00e9funt \u00e0 partir d\u2019un enregistrement et de faire lire un texte \u00e0 l\u2019intelligence artificielle.<\/p>\n\n\n\n<p class=\"intro\">Particuli\u00e8rement bon march\u00e9, ce service semble soumis \u00e0 une forte demande, puisqu\u2019il existe \u00e0 l\u2019heure actuelle une liste d\u2019attente pour les familles d\u00e9sireuses d\u2019y recourir.<\/p>\n\n\n\n<p class=\"intro\">Nous pr\u00e9sentons ci-dessous le r\u00e9sultat de ces cr\u00e9ations, souvent agr\u00e9ment\u00e9es de chansons pop \u00e0 caract\u00e8re plus ou moins lyrique, dont nous traduisons les paroles.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00ab&#160;La v\u00e9rit\u00e9 est \u00e0 nos c\u00f4t\u00e9s&#160;\u00bb<\/h2>\n\n\n\n<p><em>Debout<\/em><\/p>\n\n\n\n<p><em>Tant que nous vivons encore,&nbsp;<\/em><\/p>\n\n\n\n<p><em>Tant que la v\u00e9rit\u00e9 est \u00e0 nos c\u00f4t\u00e9s,&nbsp;<\/em><\/p>\n\n\n\n<p><em>L\u00e0-haut, quelqu\u2019un veille sur nous&nbsp;<\/em><\/p>\n\n\n\n<p><em>D\u2019un regard familier, d\u2019un sourire d\u2019enfant<\/em><\/p>\n\n\n\n<p><em>Et s\u2019avance vers le ciel&nbsp;<\/em><\/p>\n\n\n\n<p><em>Debout&nbsp;<\/em><\/p>\n\n\n\n    <div class='mux-player-wrapper' style=\"aspect-ratio:16\/9;\" data-gif-at=\"\">\n        <div\n            class='mux-player-placeholder' \n            style=\"background-image:url('https:\/\/image.mux.com\/62Xyr3Ice142OHt9Mw65lEJpe9eGbifGSwnRNB5jo9k\/thumbnail.png?width=800&#038;height=600&#038;time=');\"\n\n        >\n        <\/div>\n        <mux-player\n            playback-id=\"62Xyr3Ice142OHt9Mw65lEJpe9eGbifGSwnRNB5jo9k\"\n            accent-color=\"#dd203c\"\n            metadata-video-title=\"\"\n            metadata-viewer-user-id=\"user-wp\"\n            style=\"\" \n             \n                    >\n        <\/mux-player>\n    <\/div>\n\n\n\n<p class=\"comment\">La chanson de fond est \u00ab&#160;Vstanem&#160;\u00bb (\u00ab&#160;Debout&#160;\u00bb ou \u00ab&#160;Levons-nous&#160;\u00bb) de Shaman, chanteur pop sous sanctions d\u2019une s\u00e9rie de pays (Union, Canada, Ukraine) pour son engagement actif dans la propagande russe en faveur de la guerre en Ukraine.&nbsp;<\/p>\n\n\n\n<p class=\"comment\">Le couplet comprend l\u2019expression \u00ab&#160;<em>pravda za nami<\/em>&#160;\u00bb, \u00ab&#160;la v\u00e9rit\u00e9 est de notre c\u00f4t\u00e9&#160;\u00bb ou \u00ab&#160;la v\u00e9rit\u00e9 combat avec nous&#160;\u00bb&nbsp;&#160;: slogan militariste tr\u00e8s en vogue depuis l\u2019invasion de l\u2019Ukraine. Si la chanson de Shaman a souvent \u00e9t\u00e9 interpr\u00e9t\u00e9e comme un hommage aux soldats tomb\u00e9s sur le front ukrainien, elle a en r\u00e9alit\u00e9 \u00e9t\u00e9 publi\u00e9e en ligne la veille de l\u2019invasion.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00ab&#160;Tout va bien se passer&#160;\u00bb<\/h2>\n\n\n\n<p><em>Ma ch\u00e8re Olenka, ma bien-aim\u00e9e, ma courageuse, je t\u2019en prie, ne sois pas triste. Je suis l\u00e0, je serai toujours pr\u00e8s de toi. Embrasse pour moi les enfants, Sacha et Katia. Dis-leur \u00e0 quel point je les aime. Tout va bien se passer, mon amour. Tu es la plus douce, la plus forte, la plus vraie. Merci pour tout ce que nous avons v\u00e9cu. Je vous aime tous tr\u00e8s fort. Pour toujours avec vous, Vitali.<\/em><\/p>\n\n\n\n    <div class='mux-player-wrapper' style=\"aspect-ratio:16\/9;\" data-gif-at=\"\">\n        <div\n            class='mux-player-placeholder' \n            style=\"background-image:url('https:\/\/image.mux.com\/PQd26SaCzmCRILaJZ4jnHKRxFyV8MC9USdBml2f7Bg4\/thumbnail.png?width=800&#038;height=600&#038;time=');\"\n\n        >\n        <\/div>\n        <mux-player\n            playback-id=\"PQd26SaCzmCRILaJZ4jnHKRxFyV8MC9USdBml2f7Bg4\"\n            accent-color=\"#dd203c\"\n            metadata-video-title=\"\"\n            metadata-viewer-user-id=\"user-wp\"\n            style=\"\" \n             \n                    >\n        <\/mux-player>\n    <\/div>\n\n\n\n<p class=\"comment\">Dans cette vid\u00e9o, le p\u00e8re prononce quelques mots d\u2019adieux \u00e0 sa femme \u2014 les l\u00e8vres sont mal synchronis\u00e9es avec le propos&nbsp;&#160;; le moment o\u00f9 la parole semble h\u00e9siter, sous l\u2019effet de la douleur, est compl\u00e8tement rat\u00e9 et surjou\u00e9 \u2014, les ailes s\u2019ouvrent et s\u2019affiche le texte d\u2019une lettre avec une \u00e9criture d\u2019enfant.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00ab&#160;Les Anges&#160;\u00bb<\/h2>\n\n\n\n<p><em>Je sais que tu nous vois et nous entends<\/em><\/p>\n\n\n\n<p><em>Chaque minute, chaque seconde, chaque heure.<\/em><\/p>\n\n\n\n<p><em>Tu restes vivant, quoi qu\u2019il arrive<\/em><\/p>\n\n\n\n<p><em>Tu as place en mon c\u0153ur pour toujours.<\/em><\/p>\n\n\n\n<p><em>Tu restes vivant, mais ainsi en a d\u00e9cid\u00e9 le sort.&nbsp;<\/em><\/p>\n\n\n\n<p><em>Tu restes vivant, et les anges s\u2019\u00e9l\u00e8vent avec toi<\/em><\/p>\n\n\n\n<p><em>L\u00e9gers, haut, si haut dans le ciel<\/em><\/p>\n\n\n\n    <div class='mux-player-wrapper' style=\"aspect-ratio:16\/9;\" data-gif-at=\"\">\n        <div\n            class='mux-player-placeholder' \n            style=\"background-image:url('https:\/\/image.mux.com\/vE4hveyjWZ5wM00BzSmG8bRZb00bLJBBE1WcOUVHsBlok\/thumbnail.png?width=800&#038;height=600&#038;time=');\"\n\n        >\n        <\/div>\n        <mux-player\n            playback-id=\"vE4hveyjWZ5wM00BzSmG8bRZb00bLJBBE1WcOUVHsBlok\"\n            accent-color=\"#dd203c\"\n            metadata-video-title=\"\"\n            metadata-viewer-user-id=\"user-wp\"\n            style=\"\" \n             \n                    >\n        <\/mux-player>\n    <\/div>\n\n\n\n<p class=\"comment\">La chanson est \u00ab&#160;Angely&#160;\u00bb (les anges) de Maksim Fadeev. Chanson sortie en 2018 en hommage aux 64 victimes (dont 41 enfants) de l\u2019incendie du centre commercial Zimnjaja Vi\u0161nja de Kemerovo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00ab&#160;Je suis parti en H\u00e9ros&#160;\u00bb<\/h2>\n\n\n\n<p><em>Maman, pardonne-moi<\/em><\/p>\n\n\n\n<p><em>Ne pleure pas en vain sur mon sort<\/em><\/p>\n\n\n\n<p><em>Je suis parti en H\u00e9ros<\/em><\/p>\n\n\n\n<p><em>Pr\u00e8s de mes amis, dans le m\u00eame rang<\/em><\/p>\n\n\n\n<p><em>Je suis la voix au fond de ton \u00e2me&nbsp;<\/em><\/p>\n\n\n\n<p><em>Et ainsi, jamais je ne m\u2019\u00e9teindrai&nbsp;<\/em><\/p>\n\n\n\n<p><em>Chante pour moi, maman, ta berceuse<\/em><\/p>\n\n\n\n<p><em>Maman, pardonne-moi<\/em><\/p>\n\n\n\n<p><em>De t\u2019avoir quitt\u00e9e en silence<\/em><\/p>\n\n\n\n    <div class='mux-player-wrapper' style=\"aspect-ratio:16\/9;\" data-gif-at=\"\">\n        <div\n            class='mux-player-placeholder' \n            style=\"background-image:url('https:\/\/image.mux.com\/2cGaUvVeS27WTuHvF3y1lqve00MxUZmQ4qP6AOCPa2WI\/thumbnail.png?width=800&#038;height=600&#038;time=');\"\n\n        >\n        <\/div>\n        <mux-player\n            playback-id=\"2cGaUvVeS27WTuHvF3y1lqve00MxUZmQ4qP6AOCPa2WI\"\n            accent-color=\"#dd203c\"\n            metadata-video-title=\"\"\n            metadata-viewer-user-id=\"user-wp\"\n            style=\"\" \n             \n                    >\n        <\/mux-player>\n    <\/div>\n\n\n\n<p class=\"comment\">Si on trouve les paroles de cette musique sur VKontakte et Instagram, il n\u2019est pas s\u00fbr qu&rsquo;il s&rsquo;agisse d&rsquo;une v\u00e9ritable chanson. Elle pourrait avoir \u00e9t\u00e9 produite directement par une IA.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00ab&#160;J&rsquo;ai tant envie de vivre&#160;\u00bb<\/h2>\n\n\n\n<p><em>Tu sais, j\u2019ai tant envie de vivre<\/em><\/p>\n\n\n\n<p><em>De savourer le pourpre de l\u2019aube.&nbsp;<\/em><\/p>\n\n\n\n<p><em>Vivre simplement pour aimer&nbsp;<\/em><\/p>\n\n\n\n<p><em>Tous ceux qui partagent notre vie.<\/em><\/p>\n\n\n\n    <div class='mux-player-wrapper' style=\"aspect-ratio:16\/9;\" data-gif-at=\"\">\n        <div\n            class='mux-player-placeholder' \n            style=\"background-image:url('https:\/\/image.mux.com\/X5iGCZS02QoQfeHLHNWHFjKS5msy15vdXcCFN00B1RPHg\/thumbnail.png?width=800&#038;height=600&#038;time=');\"\n\n        >\n        <\/div>\n        <mux-player\n            playback-id=\"X5iGCZS02QoQfeHLHNWHFjKS5msy15vdXcCFN00B1RPHg\"\n            accent-color=\"#dd203c\"\n            metadata-video-title=\"\"\n            metadata-viewer-user-id=\"user-wp\"\n            style=\"\" \n             \n                    >\n        <\/mux-player>\n    <\/div>\n\n\n\n<p class=\"comment\">Il s\u2019agit de la chanson \u00ab&#160;Tak kho\u010detsja \u017eit\u2019&#160;\u00bb du groupe Ro\u017edestvo. Le site du groupe pr\u00e9cise que la chanson a \u00e9t\u00e9 interpr\u00e9t\u00e9e en 2013 au Kremlin \u00e0 l\u2019occasion de la \u00ab&#160;Journ\u00e9e de la Police&#160;\u00bb en pr\u00e9sence (entre autres) de Vladimir Poutine \u2014 toute la salle se serait lev\u00e9e en l\u2019entendant.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alors que Poutine se croit immortel, en Russie, on propose d\u00e9sormais aux familles de soldats tu\u00e9s en Ukraine un paradis <em>cheap<\/em>.<\/p>\n<p>Pour quelques roubles, une IA g\u00e9n\u00e8re des contenus morbides&#160;&#160;: les visages et les voix de soldats morts faisant un dernier adieu \u00e0 leur famille.<\/p>\n<p>Au pays de Sourkov, la technologie sert \u00e0 fa\u00e7onner une r\u00e9alit\u00e9 alternative m\u00eame apr\u00e8s la vie \u2014 et toujours, comme nous le montrons dans ces traductions comment\u00e9es \u2014 pour servir la propagande du r\u00e9gime.<\/p>\n","protected":false},"author":10,"featured_media":296914,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-speeches.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":5,"footnotes":""},"categories":[3412],"tags":[],"staff":[2655],"editorial_format":[4943],"serie":[],"audience":[],"geo":[550],"class_list":["post-296897","post","type-post","status-publish","format-standard","hentry","category-puissances-de-lia","staff-guillaume-lancereau","editorial_format-discours","geo-russie"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":296914,"excerpt":"Alors que Poutine se croit immortel, en Russie, on propose d\u00e9sormais aux familles de soldats tu\u00e9s en Ukraine un paradis <em>cheap<\/em>.\r\n\r\nPour quelques roubles, une IA g\u00e9n\u00e8re des contenus morbides : les visages et les voix de soldats morts faisant un dernier adieu \u00e0 leur famille.\r\n\r\nAu pays de Sourkov, la technologie sert \u00e0 fa\u00e7onner une r\u00e9alit\u00e9 alternative m\u00eame apr\u00e8s la vie \u2014 et toujours, comme nous le montrons dans ces traductions comment\u00e9es \u2014 pour servir la propagande du r\u00e9gime.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vid\u00e9os : l\u2019IA qui fait parler les morts de la guerre de Poutine | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/09\/07\/videos-lia-qui-fait-parler-les-morts-de-la-guerre-de-poutine\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vid\u00e9os : l\u2019IA qui fait parler les morts de la guerre de Poutine | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Alors que Poutine se croit immortel, en Russie, on propose d\u00e9sormais aux familles de soldats tu\u00e9s en Ukraine un paradis cheap.  Pour quelques roubles, une IA g\u00e9n\u00e8re des contenus morbides&#160;: les visages et les voix de soldats morts faisant un dernier adieu \u00e0 leur famille.  Au pays de Sourkov, la technologie sert \u00e0 fa\u00e7onner une r\u00e9alit\u00e9 alternative m\u00eame apr\u00e8s la vie \u2014 et toujours, comme nous le montrons dans ces traductions comment\u00e9es \u2014 pour servir la propagande du r\u00e9gime.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2025\/09\/07\/videos-lia-qui-fait-parler-les-morts-de-la-guerre-de-poutine\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-07T14:29:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-07T18:27:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/09\/RussesIA-990x562.png\" \/>\n\t<meta property=\"og:image:width\" content=\"990\" \/>\n\t<meta property=\"og:image:height\" content=\"562\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Matheo Malik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheo Malik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/09\/07\/videos-lia-qui-fait-parler-les-morts-de-la-guerre-de-poutine\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/09\/07\/videos-lia-qui-fait-parler-les-morts-de-la-guerre-de-poutine\/\",\"name\":\"Vid\u00e9os : l\u2019IA qui fait parler les morts de la guerre de Poutine | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/09\/07\/videos-lia-qui-fait-parler-les-morts-de-la-guerre-de-poutine\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/09\/07\/videos-lia-qui-fait-parler-les-morts-de-la-guerre-de-poutine\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/09\/RussesIA.png\",\"datePublished\":\"2025-09-07T14:29:22+00:00\",\"dateModified\":\"2025-09-07T18:27:40+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/09\/07\/videos-lia-qui-fait-parler-les-morts-de-la-guerre-de-poutine\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2025\/09\/07\/videos-lia-qui-fait-parler-les-morts-de-la-guerre-de-poutine\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/09\/07\/videos-lia-qui-fait-parler-les-morts-de-la-guerre-de-poutine\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/09\/RussesIA.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/09\/RussesIA.png\",\"width\":3970,\"height\":2252},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/09\/07\/videos-lia-qui-fait-parler-les-morts-de-la-guerre-de-poutine\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vid\u00e9os&#160;: l\u2019IA qui fait parler les morts de la guerre de Poutine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\",\"name\":\"Matheo Malik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"caption\":\"Matheo Malik\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vid\u00e9os : l\u2019IA qui fait parler les morts de la guerre de Poutine | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2025\/09\/07\/videos-lia-qui-fait-parler-les-morts-de-la-guerre-de-poutine\/","og_locale":"fr_FR","og_type":"article","og_title":"Vid\u00e9os : l\u2019IA qui fait parler les morts de la guerre de Poutine | Le Grand Continent","og_description":"Alors que Poutine se croit immortel, en Russie, on propose d\u00e9sormais aux familles de soldats tu\u00e9s en Ukraine un paradis cheap.  Pour quelques roubles, une IA g\u00e9n\u00e8re des contenus morbides&#160;: les visages et les voix de soldats morts faisant un dernier adieu \u00e0 leur famille.  Au pays de Sourkov, la technologie sert \u00e0 fa\u00e7onner une r\u00e9alit\u00e9 alternative m\u00eame apr\u00e8s la vie \u2014 et toujours, comme nous le montrons dans ces traductions comment\u00e9es \u2014 pour servir la propagande du r\u00e9gime.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2025\/09\/07\/videos-lia-qui-fait-parler-les-morts-de-la-guerre-de-poutine\/","og_site_name":"Le Grand Continent","article_published_time":"2025-09-07T14:29:22+00:00","article_modified_time":"2025-09-07T18:27:40+00:00","og_image":[{"width":990,"height":562,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/09\/RussesIA-990x562.png","type":"image\/png"}],"author":"Matheo Malik","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Matheo Malik","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/09\/07\/videos-lia-qui-fait-parler-les-morts-de-la-guerre-de-poutine\/","url":"https:\/\/legrandcontinent.eu\/fr\/2025\/09\/07\/videos-lia-qui-fait-parler-les-morts-de-la-guerre-de-poutine\/","name":"Vid\u00e9os : l\u2019IA qui fait parler les morts de la guerre de Poutine | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/09\/07\/videos-lia-qui-fait-parler-les-morts-de-la-guerre-de-poutine\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/09\/07\/videos-lia-qui-fait-parler-les-morts-de-la-guerre-de-poutine\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/09\/RussesIA.png","datePublished":"2025-09-07T14:29:22+00:00","dateModified":"2025-09-07T18:27:40+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/09\/07\/videos-lia-qui-fait-parler-les-morts-de-la-guerre-de-poutine\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2025\/09\/07\/videos-lia-qui-fait-parler-les-morts-de-la-guerre-de-poutine\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/09\/07\/videos-lia-qui-fait-parler-les-morts-de-la-guerre-de-poutine\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/09\/RussesIA.png","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/09\/RussesIA.png","width":3970,"height":2252},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/09\/07\/videos-lia-qui-fait-parler-les-morts-de-la-guerre-de-poutine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Vid\u00e9os&#160;: l\u2019IA qui fait parler les morts de la guerre de Poutine"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45","name":"Matheo Malik","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","caption":"Matheo Malik"}}]}},"lgc_categories":[{"id":3412,"name":"Puissances de l'IA","slug":"puissances-de-lia"}],"lgc_author":{"id":2655,"name":"Guillaume Lancereau","slug":"guillaume-lancereau","description":"Il est Max Weber Fellow \u00e0 l'Institut universitaire europ\u00e9en. Sp\u00e9cialiste de la R\u00e9volution fran\u00e7aise et de son historiographie, il co-anime le blog d\u2019histoire du XVIIIe si\u00e8cle \u00c9chos des Lumi\u00e8res","first_name":null,"last_name":null,"picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/03\/GL.jpg","width":2335,"height":2231,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/09\/RussesIA.png","width":3970,"height":2252,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/09\/RussesIA.png","width":3970,"height":2252,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/296897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=296897"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/296897\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/296914"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=296897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=296897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=296897"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=296897"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=296897"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=296897"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=296897"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=296897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}