{"id":293016,"date":"2025-08-16T00:54:40","date_gmt":"2025-08-15T22:54:40","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=293016"},"modified":"2025-08-16T01:37:39","modified_gmt":"2025-08-15T23:37:39","slug":"la-conference-de-presse-trump-poutine-a-commence-en-alaska","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2025\/08\/16\/la-conference-de-presse-trump-poutine-a-commence-en-alaska\/","title":{"rendered":"La conf\u00e9rence de presse Trump-Poutine a commenc\u00e9"},"content":{"rendered":"\n<p><em><a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/08\/16\/sommet-en-alaska-pas-de-deal-pour-trump-un-succes-pour-poutine-la-guerre-continue\/\" target=\"_blank\" rel=\"noreferrer noopener\">L&rsquo;analyse \u00e0 chaud de la conf\u00e9rence de presse (avec la traduction des passages clefs) est ici<\/a><\/em><\/p>\n\n\n\n<p>La tenue m\u00eame d\u2019une conf\u00e9rence de presse conjointe constitue en soi un signal&#160;: Trump y verra n\u00e9cessairement un motif de pr\u00e9senter le sommet comme un succ\u00e8s.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Trump avait d\u00e9clar\u00e9 qu&rsquo;il lui faudrait quelques minutes pour savoir si Poutine \u00e9tait s\u00e9rieux au sujet d&rsquo;un \u00e9ventuel accord sur l&rsquo;Ukraine, et avait menac\u00e9 de quitter la r\u00e9union ou de tenir une conf\u00e9rence de presse seul si les discussions tournaient mal.<\/li>\n\n\n\n<li>Il s&rsquo;agit de la premi\u00e8re conf\u00e9rence de presse conjointe entre un pr\u00e9sident am\u00e9ricain et un pr\u00e9sident russe depuis celle d&rsquo;Helsinki en 2018, au cours de laquelle Trump avait paru privil\u00e9gier la parole de Poutine \u00e0 celle des agences de renseignement am\u00e9ricaines concernant l&rsquo;ing\u00e9rence russe en 2016.<\/li>\n<\/ul>\n\n\n\n<p>Du c\u00f4t\u00e9 russe, la rencontre est per\u00e7ue de mani\u00e8re tr\u00e8s positive.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Dans une vid\u00e9o publi\u00e9e sur Telegram, le ministre russe de la D\u00e9fense, <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/08\/15\/qui-sont-les-hommes-de-poutine-en-alaska-prosopographie-de-la-delegation-russe\/\">Andre\u00ef Belousov<\/a>, interrog\u00e9 par l\u2019agence Tass au sujet de son ressenti apr\u00e8s la rencontre entre Trump et Poutine r\u00e9pond simplement&#160;: \u00ab&#160;Excellent&#160;\u00bb.<\/li>\n\n\n\n<li>L\u2019ambassadeur de Russie aux \u00c9tats-Unis a d\u00e9clar\u00e9 \u00e0 la t\u00e9l\u00e9vision russe que l\u2019atmosph\u00e8re \u00e9tait globalement positive, mais a reconnu qu\u2019il n\u2019y avait \u00ab&#160;pas encore de perc\u00e9e&#160;\u00bb dans la restauration des relations bilat\u00e9rales entre les deux pays.<\/li>\n<\/ul>\n\n\n\n<p>Vladimir Poutine a commenc\u00e9 la conf\u00e9rence de presse en \u00e9voquant la relation historique entre la Russie et les \u00c9tats-Unis.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Avant la r\u00e9union, le r\u00e9cit officiel du Kremlin mettait surtout en avant l\u2019id\u00e9e que les \u00c9tats-Unis et la Russie sont deux grandes nations qui doivent entretenir de bonnes relations, ind\u00e9pendamment des conflits locaux.<\/li>\n\n\n\n<li>Des responsables russes ont \u00e9galement mis en avant l&rsquo;un des th\u00e8mes <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/08\/15\/vladimir-poutine-et-donald-trump-se-rencontrent-en-alaska-premiers-signaux-faibles\/\">les plus chers de la propagande russe<\/a>&#160;: la Seconde Guerre mondiale. Avant la rencontre en Alaska, Poutine s&rsquo;est rendu \u00e0 un m\u00e9morial en Russie rendant hommage \u00e0 la coop\u00e9ration entre l&rsquo;Union sovi\u00e9tique et les \u00c9tats-Unis durant le conflit et dans une vid\u00e9o, on le voit d\u00e9poser des fleurs au monument de Magadan qui rappelle la route a\u00e9rienne Alaska-Sib\u00e9rie.<\/li>\n\n\n\n<li>Vladimir Poutine affirme que les \u00ab&#160;racines&#160;\u00bb des pr\u00e9occupations russes en Ukraine \u2014 \u00e0 savoir le retrait du gouvernement Zelensky \u2014 doivent \u00eatre \u00e9limin\u00e9es avant qu&rsquo;un accord de paix complet puisse \u00eatre conclu. <\/li>\n<\/ul>\n\n\n\n<p>La rencontre entre les deux hommes a d\u00e9but\u00e9 sur la base militaire d&rsquo;Elmendorf-Richardson, \u00e0 Anchorage, vers 21h30, heure de Paris, et s&rsquo;est conclue trois heures plus tard.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/s3vKd\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Contrairement \u00e0 ce qui avait \u00e9t\u00e9 annonc\u00e9 pr\u00e9c\u00e9demment, la rencontre bilat\u00e9rale entre Donald Trump et Vladimir Poutine a \u00e9t\u00e9 remplac\u00e9e par une r\u00e9union \u00e9largie.<\/li>\n\n\n\n<li>Le pr\u00e9sident am\u00e9ricain avait d\u00e9clar\u00e9 que <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/08\/15\/quoi-attendre-du-sommet-trump-poutine-en-alaska\/\">son objectif<\/a> \u00e9tait d\u2019obtenir un cessez-le-feu et une deuxi\u00e8me rencontre qui inclurait aussi Zelensky.\u00a0<\/li>\n\n\n\n<li>Dans la journ\u00e9e, le d\u00e9partement du Tr\u00e9sor am\u00e9ricain avait suspendu temporairement certaines sanctions contre la Russie jusqu\u2019au 20 ao\u00fbt. \u00c0 noter&#160;: une seule personne de <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/08\/15\/qui-sont-les-hommes-de-poutine-en-alaska-prosopographie-de-la-delegation-russe\/\">a d\u00e9l\u00e9gation russe<\/a> n&rsquo;\u00e9tait pas sous le coup de sanctions am\u00e9ricaines.<\/li>\n\n\n\n<li>La proposition de Poutine en amont de la r\u00e9union concernait surtout un nouveau trait\u00e9 de contr\u00f4le des armements et plusieurs responsables russes avaient insist\u00e9 sur le fait que la position de la Russie concernant le conflit en Ukraine et ses demandes maximalistes n&rsquo;avait pas chang\u00e9.<\/li>\n<\/ul>\n\n\n\n<p>Il s\u2019agit de la premi\u00e8re rencontre entre un pr\u00e9sident am\u00e9ricain et un pr\u00e9sident russe depuis 2021 \u2014 et la premi\u00e8re visite sur le sol am\u00e9ricain de Poutine depuis 10 ans.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s trois heures de discussions en Alaska, les deux chefs d&rsquo;\u00c9tat ont commenc\u00e9 leur conf\u00e9rence de presse.<\/p>\n<p>Il semblerait que les deux hommes se soient d\u00e9j\u00e0 accord\u00e9s pour un deuxi\u00e8me rendez-vous.<\/p>\n<p>Nous vous proposons une analyse \u00e0 chaud de cette conf\u00e9rence de presse.<\/p>\n","protected":false},"author":7,"featured_media":293057,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":3,"footnotes":""},"categories":[3116],"tags":[],"staff":[],"editorial_format":[4942],"serie":[],"audience":[],"geo":[525],"class_list":["post-293016","post","type-post","status-publish","format-standard","hentry","category-la-guerre-en-ukraine-au-jour-le-jour","editorial_format-actu-breves","geo-ameriques"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":293057,"excerpt":"Apr\u00e8s trois heures de discussions en Alaska, les deux chefs d'\u00c9tat ont commenc\u00e9 leur conf\u00e9rence de presse.\r\n\r\nIl semblerait que les deux hommes se soient d\u00e9j\u00e0 accord\u00e9s pour un deuxi\u00e8me rendez-vous.\r\n\r\nNous vous proposons une analyse \u00e0 chaud de cette conf\u00e9rence de presse.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La conf\u00e9rence de presse Trump-Poutine a commenc\u00e9 | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/08\/16\/la-conference-de-presse-trump-poutine-a-commence-en-alaska\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La conf\u00e9rence de presse Trump-Poutine a commenc\u00e9 | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s trois heures de discussions en Alaska, les deux chefs d&#039;\u00c9tat ont commenc\u00e9 leur conf\u00e9rence de presse.  Il semblerait que les deux hommes se soient d\u00e9j\u00e0 accord\u00e9s pour un deuxi\u00e8me rendez-vous.  Nous vous proposons une analyse \u00e0 chaud de cette conf\u00e9rence de presse.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2025\/08\/16\/la-conference-de-presse-trump-poutine-a-commence-en-alaska\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-15T22:54:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-15T23:37:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/08\/Alaska-Poutine-Trump-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1102\" \/>\n\t<meta property=\"og:image:height\" content=\"602\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gilles Gressani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/08\/Alaska-Poutine-Trump-.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilles Gressani\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/08\/16\/la-conference-de-presse-trump-poutine-a-commence-en-alaska\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/08\/16\/la-conference-de-presse-trump-poutine-a-commence-en-alaska\/\",\"name\":\"La conf\u00e9rence de presse Trump-Poutine a commenc\u00e9 | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/08\/16\/la-conference-de-presse-trump-poutine-a-commence-en-alaska\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/08\/16\/la-conference-de-presse-trump-poutine-a-commence-en-alaska\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/08\/SIPA_shutterstock41308055_000002-scaled.jpg\",\"datePublished\":\"2025-08-15T22:54:40+00:00\",\"dateModified\":\"2025-08-15T23:37:39+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/cf5b9f219cfb8e49b2923ff0e192682b\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/08\/16\/la-conference-de-presse-trump-poutine-a-commence-en-alaska\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2025\/08\/16\/la-conference-de-presse-trump-poutine-a-commence-en-alaska\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/08\/16\/la-conference-de-presse-trump-poutine-a-commence-en-alaska\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/08\/SIPA_shutterstock41308055_000002-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/08\/SIPA_shutterstock41308055_000002-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Le pr\u00e9sident russe Vladimir Poutine s'exprime sous le regard du pr\u00e9sident Donald Trump lors d'une conf\u00e9rence de presse conjointe apr\u00e8s leur rencontre \u00e0 la base militaire Elmendorf-Richardson \u00e0 Anchorage, en Alaska, le vendredi 15 ao\u00fbt 2025.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/08\/16\/la-conference-de-presse-trump-poutine-a-commence-en-alaska\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La conf\u00e9rence de presse Trump-Poutine a commenc\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/cf5b9f219cfb8e49b2923ff0e192682b\",\"name\":\"Gilles Gressani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ca9dca3417a297a024262b1a2d6d035a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ca9dca3417a297a024262b1a2d6d035a?s=96&d=mm&r=g\",\"caption\":\"Gilles Gressani\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La conf\u00e9rence de presse Trump-Poutine a commenc\u00e9 | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2025\/08\/16\/la-conference-de-presse-trump-poutine-a-commence-en-alaska\/","og_locale":"fr_FR","og_type":"article","og_title":"La conf\u00e9rence de presse Trump-Poutine a commenc\u00e9 | Le Grand Continent","og_description":"Apr\u00e8s trois heures de discussions en Alaska, les deux chefs d'\u00c9tat ont commenc\u00e9 leur conf\u00e9rence de presse.  Il semblerait que les deux hommes se soient d\u00e9j\u00e0 accord\u00e9s pour un deuxi\u00e8me rendez-vous.  Nous vous proposons une analyse \u00e0 chaud de cette conf\u00e9rence de presse.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2025\/08\/16\/la-conference-de-presse-trump-poutine-a-commence-en-alaska\/","og_site_name":"Le Grand Continent","article_published_time":"2025-08-15T22:54:40+00:00","article_modified_time":"2025-08-15T23:37:39+00:00","og_image":[{"width":1102,"height":602,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/08\/Alaska-Poutine-Trump-.png","type":"image\/png"}],"author":"Gilles Gressani","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/08\/Alaska-Poutine-Trump-.png","twitter_misc":{"\u00c9crit par":"Gilles Gressani","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/08\/16\/la-conference-de-presse-trump-poutine-a-commence-en-alaska\/","url":"https:\/\/legrandcontinent.eu\/fr\/2025\/08\/16\/la-conference-de-presse-trump-poutine-a-commence-en-alaska\/","name":"La conf\u00e9rence de presse Trump-Poutine a commenc\u00e9 | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/08\/16\/la-conference-de-presse-trump-poutine-a-commence-en-alaska\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/08\/16\/la-conference-de-presse-trump-poutine-a-commence-en-alaska\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/08\/SIPA_shutterstock41308055_000002-scaled.jpg","datePublished":"2025-08-15T22:54:40+00:00","dateModified":"2025-08-15T23:37:39+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/cf5b9f219cfb8e49b2923ff0e192682b"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/08\/16\/la-conference-de-presse-trump-poutine-a-commence-en-alaska\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2025\/08\/16\/la-conference-de-presse-trump-poutine-a-commence-en-alaska\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/08\/16\/la-conference-de-presse-trump-poutine-a-commence-en-alaska\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/08\/SIPA_shutterstock41308055_000002-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/08\/SIPA_shutterstock41308055_000002-scaled.jpg","width":2560,"height":1707,"caption":"Le pr\u00e9sident russe Vladimir Poutine s'exprime sous le regard du pr\u00e9sident Donald Trump lors d'une conf\u00e9rence de presse conjointe apr\u00e8s leur rencontre \u00e0 la base militaire Elmendorf-Richardson \u00e0 Anchorage, en Alaska, le vendredi 15 ao\u00fbt 2025."},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/08\/16\/la-conference-de-presse-trump-poutine-a-commence-en-alaska\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"La conf\u00e9rence de presse Trump-Poutine a commenc\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/cf5b9f219cfb8e49b2923ff0e192682b","name":"Gilles Gressani","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ca9dca3417a297a024262b1a2d6d035a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ca9dca3417a297a024262b1a2d6d035a?s=96&d=mm&r=g","caption":"Gilles Gressani"}}]}},"lgc_categories":[{"id":3116,"name":"La guerre en Ukraine au jour le jour","slug":"la-guerre-en-ukraine-au-jour-le-jour"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/08\/SIPA_shutterstock41308055_000002-scaled.jpg","width":2560,"height":1707,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/293016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=293016"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/293016\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/293057"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=293016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=293016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=293016"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=293016"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=293016"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=293016"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=293016"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=293016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}