{"id":290204,"date":"2025-07-30T15:57:19","date_gmt":"2025-07-30T13:57:19","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=290204"},"modified":"2025-08-16T06:14:21","modified_gmt":"2025-08-16T04:14:21","slug":"face-a-trump-leurope-ramasse-les-coquillages-une-conversation-avec-giuliano-da-empoli","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/30\/face-a-trump-leurope-ramasse-les-coquillages-une-conversation-avec-giuliano-da-empoli\/","title":{"rendered":"\u00ab&#160;Face \u00e0 Trump, l\u2019Europe ramasse les coquillages&#160;\u00bb, une conversation avec Giuliano da Empoli"},"content":{"rendered":"\n<p><em>Le dernier volume papier du Grand Continent <em>paru sous la direction de Giuliano da Empoli<\/em><\/em> <em>\u2014 <\/em>L\u2019Empire de l\u2019ombre&#160;: guerre et terre au temps de l\u2019IA \u2014<em> est disponible <\/em><a href=\"https:\/\/legrandcontinent.eu\/shop\/produit\/empire-de-lombre\/\"><em>par ici<\/em><\/a><em>, ainsi <\/em><a href=\"https:\/\/legrandcontinent.eu\/fr\/offre-legc-x\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>qu&rsquo;en abonnement<\/em><\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Quelle est votre lecture de la s\u00e9quence ouverte dimanche par <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/27\/lunion-europeenne-cede-a-trump-analyse-a-chaud-du-traite-inegal-quimpose-15-de-droits-de-douane\/\">l\u2019annonce d\u2019une sorte de trait\u00e9 in\u00e9gal<\/a> entre l\u2019Europe et les \u00c9tats-Unis&#160;?<\/strong>&nbsp;<\/h3>\n\n\n\n<p>En regardant les images de cette rencontre humiliante, je me suis souvenu d&rsquo;un r\u00e9cit de Su\u00e9tone.<\/p>\n\n\n\n<p>Dans <em>La Vie des douze C\u00e9sars<\/em>, on peut lire l&rsquo;histoire d&rsquo;un empereur qui concentre toutes ses troupes, centralise tous les pouvoirs, \u00e9limine tous ses ennemis&#8230;<\/p>\n\n\n\n<p>Une fois qu&rsquo;il a pris le contr\u00f4le total de Rome et qu&rsquo;il est le seul ma\u00eetre, l&#8217;empereur conduit son immense arm\u00e9e au bord de la mer et lui ordonne de ramasser les coquillages.<\/p>\n\n\n\n<p>On ne peut s&#8217;emp\u00eacher de faire la comparaison avec Von der Leyen.<\/p>\n\n\n\n<p>De mani\u00e8re tr\u00e8s efficace, la pr\u00e9sidente de la Commission a progressivement \u00e9limin\u00e9 tous ses adversaires, \u00e9cart\u00e9 les commissaires qui la d\u00e9rangeaient et concentr\u00e9 toutes les proc\u00e9dures entre ses mains.<\/p>\n\n\n\n<p>Mais cette centralisation extraordinaire du pouvoir aboutit \u00e0 la sc\u00e8ne \u00e0 laquelle nous avons p\u00e9niblement assist\u00e9 dimanche en \u00c9cosse.&nbsp;<\/p>\n\n\n\n<p>Seulement, \u00e0 la place des coquillages, il y avait les balles de golf du nouveau complexe clinquant de Donald Trump.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Mais au-del\u00e0 des coquillages, l&rsquo;Union disposait-elle vraiment d&rsquo;une arm\u00e9e&#160;?<\/strong><\/h3>\n\n\n\n<p>En un sens, oui. Mais il faut sortir un instant de cette analogie et \u2014 m\u00eame si c&rsquo;est un peu compliqu\u00e9 en cette p\u00e9riode tr\u00e8s bizarre \u2014 essayer de comprendre ce que fait r\u00e9ellement le pr\u00e9sident des \u00c9tats-Unis.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Quelle est sa strat\u00e9gie&#160;?<\/strong><\/h3>\n\n\n\n<p>L&rsquo;offensive de Trump contre l&rsquo;Europe a une double dimension. D&rsquo;une part, il y a un aspect, pour ainsi dire, rationnel&#160;; d&rsquo;autre part, un mouvement purement politique et id\u00e9ologique.<\/p>\n\n\n\n<p>La dimension \u00ab&#160;rationnelle&#160;\u00bb d\u00e9coule d&rsquo;un postulat. Depuis la seconde moiti\u00e9 du XXe si\u00e8cle, les \u00c9tats-Unis auraient fourni \u00e0 l&rsquo;Europe un exc\u00e9dent de biens communs&#160;: comme une certaine s\u00e9curit\u00e9, la protection militaire, le dollar, des infrastructures commerciales, ainsi que, plus r\u00e9cemment, le num\u00e9rique.<\/p>\n\n\n\n<p>Aujourd&rsquo;hui, Trump cherche \u00e0 obtenir beaucoup plus de revenus et de valeur de la part de ses interlocuteurs europ\u00e9ens que ce que les \u00c9tats-Unis leur fournissent. Bien que cette id\u00e9e ne soit pas formul\u00e9e exactement en ces termes, il me semble que la dimension \u00ab&#160;rationnelle&#160;\u00bb de l&rsquo;offensive am\u00e9ricaine contre l&rsquo;Europe se donne cet objectif&#160;: extraire d&rsquo;une alliance d\u00e9sormais totalement d\u00e9s\u00e9quilibr\u00e9e et asym\u00e9trique le plus grand nombre possible d&rsquo;avantages.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Trump serait-il en train de mener une \u00ab&#160;<em>enshittification<\/em>&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-290204' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/07\/30\/face-a-trump-leurope-ramasse-les-coquillages-une-conversation-avec-giuliano-da-empoli\/#easy-footnote-bottom-1-290204' title='En \u00e9conomie, l\u2019expression est utilis\u00e9e pour d\u00e9crire le cycle d&amp;rsquo;\u00e9volution de certaines plateformes num\u00e9riques. Elles voient le jour dans le but d&amp;rsquo;attirer le plus grand nombre de clients \u2014 particuliers mais aussi annonceurs \u2014 gr\u00e2ce \u00e0 un service exceptionnel. Une fois les clients attir\u00e9s et une position dominante acquise, les co\u00fbts sont r\u00e9duits et tout ce qui peut \u00eatre tir\u00e9 des clients, des vendeurs et des annonceurs est exploit\u00e9, malgr\u00e9 une baisse importante de la qualit\u00e9 du service.'><sup>1<\/sup><\/a><\/span><\/span> de l&#8217;empire am\u00e9ricain&#160;? Ayant atteint l\u2019h\u00e9g\u00e9monie et ne pouvant plus s&rsquo;\u00e9tendre davantage sur les m\u00eames bases, les \u00c9tats-Unis se r\u00e9duisent \u00e0 extraire toute la valeur restante de leur position dominante, en comprimant les co\u00fbts, sacrifiant leurs alliances et risquant ainsi de compromettre les conditions m\u00eames de leur supr\u00e9matie&#8230;<\/strong><\/h3>\n\n\n\n<p>Cela ne fait aucun doute, m\u00eame s&rsquo;il faut dire que les \u00c9tats-Unis n&rsquo;ont jamais eu beaucoup de scrupules \u00e0 tirer une rente colossale de l&rsquo;Europe. Certes, ils le faisaient de mani\u00e8re plus discr\u00e8te, plus rationnelle, plus efficace. Trump, qui est un pr\u00e9dateur, veut pousser cette politique \u00e0 l&rsquo;extr\u00eame, d\u00e9truisant tout ce qui a \u00e9t\u00e9 construit.<\/p>\n\n\n\n<p>Sur ce plan, l&rsquo;humiliation de l&rsquo;Europe est in\u00e9vitable. Notre manque de souverainet\u00e9, notamment dans le domaine militaire, mais aussi dans de nombreux autres domaines, se r\u00e9percute sur ces accords commerciaux et sur tout le reste.&nbsp;<\/p>\n\n\n\n<p>Le seul crit\u00e8re d&rsquo;\u00e9valuation sur ce front est la direction prise&#160;: il s\u2019agit de comprendre si l&rsquo;on commence \u00e0 jeter les bases pour sortir de cet \u00e9tat d&rsquo;humiliation, ou non.<\/p>\n\n\n<section class=\"dive print-block my-16\" style=\"background-color:#ffffff;\">\n\t<div class=\"wrapper\">\n\t\t<div class=\"container mx-auto \">\n\t\t\t<div class=\"row flex flex-wrap relative pt-6 pb-16 lg:py-8\">\n\t\t\t\t<div class=\"col w-full xl:ml-1\/10\n\t\t\t\t\t md:w-2\/5 xl:w-2\/5 \t\t\t\t\t\">\n\t\t\t\t\t<a href=\"https:\/\/legrandcontinent.eu\/shop\/produit\/empire-de-lombre\/\" style=\"color:#0a0a0a;\" class=\"font-display font-normal text-4xl leading-9 mb-5 text-white no-underline\">\n\t\t\t\t\t\tL\u2019Empire de l\u2019ombre. Guerre et terre au temps de l\u2019IA\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<div style=\"color:#0a0a0a;\" class=\"text-base leading-none font-sans\">\n\t\t\t\t\t\t\t<p>Sous la direction de Giuliano da Empoli. Postface par Benjam\u00edn Labatut.<\/p>\n<p>Avec les contributions de Daron Acemo\u011flu, Sam Altman, Marc Andreessen, Lorenzo Castellani, Adam Curtis, Mario Draghi, He Jiayan, Marietje Schaake, Vladislav Sourkov, Peter Thiel, Svetlana Tikhanovska\u00efa, Jianwei Xun et Curtis Yarvin.<\/p>\n<p>\u00c0 d\u00e9couvrir en librairie et en s&rsquo;abonnant \u00e0 la revue.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"mt-12 dive-list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a  style=\"color:#dd203c;\" class=\"no-underline block border-t border-grey-darker py-2 flex\"\n\t\t\t\t\t\t\t\t   href=\"https:\/\/legrandcontinent.eu\/shop\/produit\/empire-de-lombre\/\"><span class=\"font-sans font-semibold pr-4\">\u2192<\/span> Commandez le num\u00e9ro<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a  style=\"color:#dd203c;\" class=\"no-underline block border-t border-grey-darker py-2 flex\"\n\t\t\t\t\t\t\t\t   href=\"https:\/\/legrandcontinent.eu\/fr\/offre-legc\/\"><span class=\"font-sans font-semibold pr-4\">\u2192<\/span> D\u00e9couvrez comment vous abonner<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div style=\"color:#0a0a0a;\" class=\"dive-footer font-sans text-xs border-t border-grey-darker py-2 leading-4\">\n\t\t\t\t\t\t\t<p><strong><a href=\"https:\/\/legrandcontinent.eu\/shop\/produit\/empire-de-lombre\/\"><span style=\"text-decoration: underline\">Commandez le nouveau num\u00e9ro papier<\/span><\/a> du Grand Continent chez Gallimard ou <span style=\"text-decoration: underline\"><a href=\"https:\/\/legrandcontinent.eu\/fr\/offre-legc\/\">cliquez ici pour vous abonner et recevoir l\u2019int\u00e9gralit\u00e9 de nos produits<\/a><\/span>.<\/strong><\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col w-full md:w-3\/5 xl:w-2\/5  md:px-0 relative overflow-hidden mt-8 md:mt-0 macron-img\">\n\t\t\t\t\t\t\t\t<a class=\"!absolute !bg-none w-full h-full pin-t pin-l\" href=\"https:\/\/legrandcontinent.eu\/shop\/produit\/empire-de-lombre\/\" class=\"no-underline\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" style=\"object-fit: contain; width: 100%; height: 100%;\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/04\/mediamodifier_image-17-990x660.png\" \/>\n\t\t\t\t\t\t\t\t<\/a> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Et dans quelle direction va l\u2019annonce de l\u2019accord de dimanche&#160;?<\/strong><\/h3>\n\n\n\n<p>Je dirais qu\u2019elle semble clairement aller dans le sens d\u2019une humiliation permanente plut\u00f4t que d&rsquo;une sortie de celle-ci.<\/p>\n\n\n\n<p>Les services num\u00e9riques \u00e9taient hors du champ de ce premier <em>round<\/em> de n\u00e9gociations, mais il semble difficile d&rsquo;imaginer que, lorsque le moment de la discussion sera venu, on puisse aboutir \u00e0 un r\u00e9sultat diff\u00e9rent, compte tenu des pr\u00e9misses.<\/p>\n\n\n\n<p>On pourrait en dire autant du plan militaire, d\u00e9j\u00e0 incarn\u00e9 dans la ligne de capitulation franchement embarrassante exprim\u00e9e par l&rsquo;ancien Premier ministre Rutte et ses \u00ab&#160;<em>daddy issues<\/em>&#160;\u00bb pour reprendre une formule de <a href=\"https:\/\/5dlew.r.ah.d.sendibm5.com\/mk\/mr\/sh\/SMJz09SDriOHW03GbFcbYnviOaId\/Fx2e84JioWXK\"><em>la Lettre du dimanche<\/em><\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Vous parliez d&rsquo;une deuxi\u00e8me dimension plus id\u00e9ologique, moins rationnelle&#160;?<\/strong><\/h3>\n\n\n\n<p>Oui, tout cela n&rsquo;est que le premier aspect de l&rsquo;offensive de Trump.<\/p>\n\n\n\n<p>Le deuxi\u00e8me \u2013 que Ursula von der Leyen et tous les autres dirigeants europ\u00e9ens semblent incroyablement ignorer \u2013 consiste en une offensive politico-id\u00e9ologique, extraordinairement violente et quotidienne, \u00e0 travers laquelle la Maison-Blanche vise \u00e0 imposer un mod\u00e8le politique radicalement alternatif&#160;: le d\u00e9passement de la d\u00e9mocratie lib\u00e9rale, le contournement de l&rsquo;\u00c9tat de droit et l&rsquo;imposition d&rsquo;un syst\u00e8me mixte, une sorte de technoc\u00e9sarisme.&nbsp;<\/p>\n\n\n\n<p>Le projet qui se met en place \u00e0 Washington est \u00e9vident pour tous et il a des cons\u00e9quences \u00e9videntes sur nos institutions et nos syst\u00e8mes politiques de plus en plus soumis \u00e0 une pression qui vise au changement de r\u00e9gime.<\/p>\n\n\n\n<p>Sur ce plan, la r\u00e9ponse devrait \u00eatre tr\u00e8s ferme et sans aucune marge d&rsquo;h\u00e9sitation, ce qui n&#8217;emp\u00eacherait nullement de continuer \u00e0 discuter sur le premier plan.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Pourquoi la r\u00e9ponse est-elle totalement absente sur le plan politique&#160;?<\/strong><\/h3>\n\n\n\n<p>Von der Leyen et les autres ne comprennent pas la puissance des symboles.<\/p>\n\n\n\n<p>Le monde technocratique, dans lequel \u00e9volue la quasi-totalit\u00e9 de la politique europ\u00e9enne \u2013 non seulement \u00e0 Bruxelles, mais aussi dans les autres capitales \u2013 ignore compl\u00e8tement la dimension politique, id\u00e9ologique, des principes et de tout ce qui n\u2019est pas quantifiable.<\/p>\n\n\n\n<p>Et de ce point de vue, la d\u00e9faite est dramatique et doublement humiliante.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>En politique, ignorer les symboles peut \u00eatre tr\u00e8s risqu\u00e9&#160;: on peut tr\u00e8s vite en devenir un \u00e0 son d\u00e9triment\u2026<\/strong><\/h3>\n\n\n\n<p>Oui, c\u2019est ainsi qu\u2019on finit par se mettre dans des positions humiliantes, par prendre des photos ridicules avec le pouce lev\u00e9 et un sourire absurde, ou par accumuler des d\u00e9clarations et des tweets franchement path\u00e9tiques.&nbsp;<\/p>\n\n\n\n<p>Von der Leyen n&rsquo;est pas la seule responsable de cette capitulation, de tr\u00e8s nombreux gouvernements europ\u00e9ens <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/29\/accord-union-trump-geographie-interne-dun-echec-cartes-exclusives\/\">le sont \u00e9galement<\/a>, mais elle s&rsquo;est mise en position de devenir le symbole, presque trop parfait, de la <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/02\/05\/contre-la-vassalisation-heureuse-il-est-temps-dagir-lappel-de-sergio-mattarella\/\">vassalisation heureuse<\/a>&#160;: cela ressemble presque \u00e0 une forme de justice po\u00e9tique&#8230;<\/p>\n\n\n\n<p>Trump, lui, conna\u00eet la valeur des symboles, son parcours en est jalonn\u00e9&#160;: du certificat de naissance d&rsquo;Obama au mur, en passant par le mythe du \u00ab&#160;deal&#160;\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Revenons aux symboles et aux coquillages. Vous disiez qu&rsquo;il existait peut-\u00eatre pas une arm\u00e9e comme celle de l&#8217;empereur d\u00e9crit par Su\u00e9tone, mais en tout cas une \u00e9nergie politique constitu\u00e9e de nombreux citoyens souhaitant autre chose que de subir quotidiennement ce spectacle humiliant. Est-ce bien cela&#160;?<\/strong><\/h3>\n\n\n\n<p>Cela me semble \u00e9vident.<\/p>\n\n\n\n<p>Je pense qu&rsquo;il existe aujourd&rsquo;hui un espace impressionnant pour un leader europ\u00e9en qui souhaiterait activer cette \u00e9nergie symbolique.<\/p>\n\n\n\n<p>Les chiffres le montrent clairement. <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/03\/20\/les-europeens-face-a-la-guerre-et-trump-10-points-sur-un-sondage-exclusif\/\">Le sondage Eurobazooka<\/a> publi\u00e9 dans ces pages est tr\u00e8s explicite et souligne l&rsquo;existence de cette arm\u00e9e sans g\u00e9n\u00e9ral, qui attend d&rsquo;\u00eatre mobilis\u00e9e sur un certain nombre de fronts.<\/p>\n\n\n\n<p>Le probl\u00e8me, c&rsquo;est que le temps qui reste n&rsquo;est pas infini et que cette \u00e9nergie peut facilement prendre une direction destructrice.<\/p>\n\n\n\n<p>Mais personne ne dit rien.<\/p>\n\n\n\n<p>C&rsquo;est vraiment le plus surprenant.<\/p>\n\n\n\n<p>Aucun leader europ\u00e9en n&rsquo;a eu jusqu\u2019ici le courage de prendre ce drapeau et de prononcer un discours de v\u00e9rit\u00e9 sur la v\u00e9ritable nature de l\u2019offensive \u00e0 laquelle nous faisons face.&nbsp;<\/p>\n\n\n\n<p>Pour dire que ce que nous voyons tous chaque jour correspond \u00e0 ce qui se passe r\u00e9ellement&#160;: un risque existentiel. Nous ne vivrons probablement plus comme avant et il y a des choix difficiles \u00e0 faire.<\/p>\n\n\n\n<p>Il n&rsquo;est pas certain que nous y parviendrons et il est tout \u00e0 fait possible que le XXIe si\u00e8cle soit celui de la grande humiliation europ\u00e9enne. Mais ce n&rsquo;est pas encore dit, car nous sommes l\u00e0 et nous sommes pr\u00eats.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Au fond, vous \u00eates convaincu que l&rsquo;heure des pr\u00e9dateurs ne sonnera que lorsque celle des invert\u00e9br\u00e9s aura retenti&#160;?<\/strong><\/h3>\n\n\n\n<p>C&rsquo;est \u00e0 peu pr\u00e8s \u00e7a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En assistant, dimanche, \u00e0 l\u2019humiliation de la pr\u00e9sidente Von der Leyen par Donald Trump, l\u2019auteur du succ\u00e8s de l\u2019\u00e9t\u00e9, <em>L\u2019Heure des pr\u00e9dateurs<\/em>, a imm\u00e9diatement pens\u00e9 \u00e0 Su\u00e9tone et aux coquillages d\u2019un empereur romain.<\/p>\n<p>\nEntretien.<\/p>\n","protected":false},"author":7,"featured_media":290210,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-interviews.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":8,"footnotes":""},"categories":[4259],"tags":[],"staff":[1553],"editorial_format":[4854],"serie":[],"audience":[],"geo":[1917],"class_list":["post-290204","post","type-post","status-publish","format-standard","hentry","category-leurope-face-a-trump-que-faire","staff-gilles-gressani","editorial_format-entretiens","geo-europe"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":290210,"excerpt":"En assistant, dimanche, \u00e0 l\u2019humiliation de la pr\u00e9sidente Von der Leyen par Donald Trump, l\u2019auteur du succ\u00e8s de l\u2019\u00e9t\u00e9, <em>L\u2019Heure des pr\u00e9dateurs<\/em>, a imm\u00e9diatement pens\u00e9 \u00e0 Su\u00e9tone et aux coquillages d\u2019un empereur romain.\r\n<br>\r\nEntretien.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00abFace \u00e0 Trump, l\u2019Europe ramasse les coquillages\u00bb, une conversation avec Giuliano da Empoli | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/30\/face-a-trump-leurope-ramasse-les-coquillages-une-conversation-avec-giuliano-da-empoli\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Da Empoli : \u00abFace \u00e0 Trump, l\u2019Europe ramasse les coquillages\u00bb\" \/>\n<meta property=\"og:description\" content=\"En assistant, dimanche, \u00e0 l\u2019humiliation de la pr\u00e9sidente Von der Leyen par Donald Trump, l\u2019auteur du succ\u00e8s de l\u2019\u00e9t\u00e9, L\u2019Heure des pr\u00e9dateurs, a imm\u00e9diatement pens\u00e9 \u00e0 Su\u00e9tone et aux coquillages d\u2019un empereur romain.  Entretien.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/30\/face-a-trump-leurope-ramasse-les-coquillages-une-conversation-avec-giuliano-da-empoli\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-30T13:57:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-16T04:14:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/Grand-Continent-Giuliano-da-Empoli-share.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1138\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gilles Gressani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Da Empoli : \u00abFace \u00e0 Trump, l\u2019Europe ramasse les coquillages\u00bb\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/Grand-Continent-Giuliano-da-Empoli-share.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilles Gressani\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/30\/face-a-trump-leurope-ramasse-les-coquillages-une-conversation-avec-giuliano-da-empoli\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/30\/face-a-trump-leurope-ramasse-les-coquillages-une-conversation-avec-giuliano-da-empoli\/\",\"name\":\"\u00abFace \u00e0 Trump, l\u2019Europe ramasse les coquillages\u00bb, une conversation avec Giuliano da Empoli | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/30\/face-a-trump-leurope-ramasse-les-coquillages-une-conversation-avec-giuliano-da-empoli\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/30\/face-a-trump-leurope-ramasse-les-coquillages-une-conversation-avec-giuliano-da-empoli\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/SIPA_01109864_000010-scaled.jpg\",\"datePublished\":\"2025-07-30T13:57:19+00:00\",\"dateModified\":\"2025-08-16T04:14:21+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/cf5b9f219cfb8e49b2923ff0e192682b\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/30\/face-a-trump-leurope-ramasse-les-coquillages-une-conversation-avec-giuliano-da-empoli\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/30\/face-a-trump-leurope-ramasse-les-coquillages-une-conversation-avec-giuliano-da-empoli\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/30\/face-a-trump-leurope-ramasse-les-coquillages-une-conversation-avec-giuliano-da-empoli\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/SIPA_01109864_000010-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/SIPA_01109864_000010-scaled.jpg\",\"width\":1707,\"height\":2560,\"caption\":\"L'\u00e9crivain Giuliano da Empoli pose lors d'une s\u00e9ance photo \u00e0 Madrid, en Espagne, pour la parution de la traduction espagnole de son roman \u00ab Le Mage du Kremlin \u00bb. Atilano Garcia \/ SOPA Images\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/30\/face-a-trump-leurope-ramasse-les-coquillages-une-conversation-avec-giuliano-da-empoli\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00ab&#160;Face \u00e0 Trump, l\u2019Europe ramasse les coquillages&#160;\u00bb, une conversation avec Giuliano da Empoli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/cf5b9f219cfb8e49b2923ff0e192682b\",\"name\":\"Gilles Gressani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ca9dca3417a297a024262b1a2d6d035a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ca9dca3417a297a024262b1a2d6d035a?s=96&d=mm&r=g\",\"caption\":\"Gilles Gressani\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00abFace \u00e0 Trump, l\u2019Europe ramasse les coquillages\u00bb, une conversation avec Giuliano da Empoli | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/30\/face-a-trump-leurope-ramasse-les-coquillages-une-conversation-avec-giuliano-da-empoli\/","og_locale":"fr_FR","og_type":"article","og_title":"Da Empoli : \u00abFace \u00e0 Trump, l\u2019Europe ramasse les coquillages\u00bb","og_description":"En assistant, dimanche, \u00e0 l\u2019humiliation de la pr\u00e9sidente Von der Leyen par Donald Trump, l\u2019auteur du succ\u00e8s de l\u2019\u00e9t\u00e9, L\u2019Heure des pr\u00e9dateurs, a imm\u00e9diatement pens\u00e9 \u00e0 Su\u00e9tone et aux coquillages d\u2019un empereur romain.  Entretien.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/30\/face-a-trump-leurope-ramasse-les-coquillages-une-conversation-avec-giuliano-da-empoli\/","og_site_name":"Le Grand Continent","article_published_time":"2025-07-30T13:57:19+00:00","article_modified_time":"2025-08-16T04:14:21+00:00","og_image":[{"width":1138,"height":640,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/Grand-Continent-Giuliano-da-Empoli-share.png","type":"image\/png"}],"author":"Gilles Gressani","twitter_card":"summary_large_image","twitter_title":"Da Empoli : \u00abFace \u00e0 Trump, l\u2019Europe ramasse les coquillages\u00bb","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/Grand-Continent-Giuliano-da-Empoli-share.png","twitter_misc":{"\u00c9crit par":"Gilles Gressani","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/30\/face-a-trump-leurope-ramasse-les-coquillages-une-conversation-avec-giuliano-da-empoli\/","url":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/30\/face-a-trump-leurope-ramasse-les-coquillages-une-conversation-avec-giuliano-da-empoli\/","name":"\u00abFace \u00e0 Trump, l\u2019Europe ramasse les coquillages\u00bb, une conversation avec Giuliano da Empoli | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/30\/face-a-trump-leurope-ramasse-les-coquillages-une-conversation-avec-giuliano-da-empoli\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/30\/face-a-trump-leurope-ramasse-les-coquillages-une-conversation-avec-giuliano-da-empoli\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/SIPA_01109864_000010-scaled.jpg","datePublished":"2025-07-30T13:57:19+00:00","dateModified":"2025-08-16T04:14:21+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/cf5b9f219cfb8e49b2923ff0e192682b"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/30\/face-a-trump-leurope-ramasse-les-coquillages-une-conversation-avec-giuliano-da-empoli\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2025\/07\/30\/face-a-trump-leurope-ramasse-les-coquillages-une-conversation-avec-giuliano-da-empoli\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/30\/face-a-trump-leurope-ramasse-les-coquillages-une-conversation-avec-giuliano-da-empoli\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/SIPA_01109864_000010-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/SIPA_01109864_000010-scaled.jpg","width":1707,"height":2560,"caption":"L'\u00e9crivain Giuliano da Empoli pose lors d'une s\u00e9ance photo \u00e0 Madrid, en Espagne, pour la parution de la traduction espagnole de son roman \u00ab Le Mage du Kremlin \u00bb. Atilano Garcia \/ SOPA Images"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/30\/face-a-trump-leurope-ramasse-les-coquillages-une-conversation-avec-giuliano-da-empoli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00ab&#160;Face \u00e0 Trump, l\u2019Europe ramasse les coquillages&#160;\u00bb, une conversation avec Giuliano da Empoli"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/cf5b9f219cfb8e49b2923ff0e192682b","name":"Gilles Gressani","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ca9dca3417a297a024262b1a2d6d035a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ca9dca3417a297a024262b1a2d6d035a?s=96&d=mm&r=g","caption":"Gilles Gressani"}}]}},"lgc_categories":[{"id":4259,"name":"L'Europe face \u00e0 Trump&#160;: que faire&#160;?","slug":"leurope-face-a-trump-que-faire"}],"lgc_author":{"id":1553,"name":"Gilles Gressani","slug":"gilles-gressani","description":"Gilles Gressani, directeur du Grand Continent, il pr\u00e9side le Groupe d\u2019\u00e9tudes g\u00e9opolitiques et enseigne \u00e0 Sciences Po. <a href=\"https:\/\/legrandcontinent.eu\/shop\/produit\/portrait-dun-monde-casse\/\"><em>Portrait d'un monde cass\u00e9<\/em><\/a> (Gallimard 2024) est en librairie. \r\n","first_name":"Gilles","last_name":"Gressani","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/portrait-gilles-1-e1669480105797.jpg","width":416,"height":416,"alt":"Directeur Grand Continent"}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/SIPA_01109864_000010-scaled.jpg","width":1707,"height":2560,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/SIPA_01109864_000010-scaled.jpg","width":1707,"height":2560,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/290204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=290204"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/290204\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/290210"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=290204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=290204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=290204"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=290204"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=290204"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=290204"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=290204"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=290204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}