{"id":288369,"date":"2025-07-20T18:21:56","date_gmt":"2025-07-20T16:21:56","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=288369"},"modified":"2025-07-20T23:23:32","modified_gmt":"2025-07-20T21:23:32","slug":"je-suis-sur-le-point-de-vous-dire-lindicible-mais-je-passe-ma-vie-a-craindre-quon-frappe-a-ma-porte-une-conversation-avec-enrique-vila-matas","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/20\/je-suis-sur-le-point-de-vous-dire-lindicible-mais-je-passe-ma-vie-a-craindre-quon-frappe-a-ma-porte-une-conversation-avec-enrique-vila-matas\/","title":{"rendered":"\u00ab&#160;Je suis sur le point de vous dire l&rsquo;indicible \u2014 mais je passe ma vie \u00e0 craindre qu&rsquo;on frappe \u00e0 ma porte&#160;\u00bb, une conversation avec Enrique Vila-Matas"},"content":{"rendered":"\n<p><em>Paul Auster avait l\u2019habitude de dire qu\u2019avec Enrique Vila-Matas on ne craint rien, on peut se laisser porter \u2014 car on est \u00ab&#160;entre les mains d&rsquo;un ma\u00eetre.&#160;\u00bb&nbsp;<\/em><\/p>\n\n\n\n<p><em>Son nouveau roman, <\/em>Canon de c\u00e1mara oscura<em> (\u00ab&#160;Canon de chambre noire&#160;\u00bb) publi\u00e9 en Espagne par Seix Barral, est une sorte d\u2019objet litt\u00e9raire non-identifi\u00e9.&nbsp;<\/em><\/p>\n\n\n\n<p><em>Vidal Escabia, le protagoniste principal, est un robot.<\/em><\/p>\n\n\n\n<p><em>Plus exactement, c\u2019est un \u00ab&#160;Denver-7&#160;\u00bb. Mais il est en tout \u2014 ou presque \u2014 pareil \u00e0 un \u00eatre humain. D\u2019autant plus qu\u2019il est un grand lecteur&#160;; il \u00e9crit et se fixe une grande mission&#160;: \u00e9tablir son propre \u00ab&#160;Canon&#160;\u00bb personnel et intime de la litt\u00e9rature mondiale.&nbsp;<\/em><\/p>\n\n\n\n<p><em>Tous les matins, cet andro\u00efde choisit un livre dont un extrait int\u00e9grera la pi\u00e8ce, la \u00ab&#160;chambre noire&#160;\u00bb, dans laquelle prend forme le fameux canon au quotidien, au fur et mesure de la lecture \u2014 et d\u2019une \u00e9criture qui semble simultan\u00e9e et elle-m\u00eame influenc\u00e9e par les textes choisis.<\/em><\/p>\n\n\n\n<p><em>Dans un \u00e9l\u00e9gant concert de citations et r\u00e9f\u00e9rences parfaitement \u00e9quilibr\u00e9es, Vila-Matas nous emm\u00e8ne dans l\u2019univers de ses sujets de pr\u00e9dilection&#160;: la fiction, le simulacre, le double, l\u2019\u00e9criture, le narrateur\/auteur \u2014 cette figure avec laquelle l\u2019\u00e9crivain catalan aime jouer \u2014 l\u2019absurde mais aussi l\u2019absence.<\/em><\/p>\n\n\n\n<p><em>Vila-Matas est bien un ma\u00eetre, un virtuose dans l\u2019art de la narration \u2014 et ce <\/em>Canon de c\u00e1mara oscura<em> en est la plus belle illustration.<\/em><\/p>\n\n\n\n<p class=\"non-subscribers-only\"><em>Pour recevoir chaque dimanche un nouvel entretien litt\u00e9raire, <a href=\"https:\/\/legrandcontinent.eu\/fr\/offre-legc-x\/\" target=\"_blank\" rel=\"noreferrer noopener\">abonnez-vous au Grand Continent<\/a><\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Pourrait-on dire que cet excellent livre est votre grand hommage \u00e0 l&rsquo;\u00e9criture et \u00e0 la lecture, c&rsquo;est-\u00e0-dire \u00e0 la litt\u00e9rature&#160;?<\/h3>\n\n\n\n<p>Que ceux qui veulent le voir ainsi pensent que c&rsquo;est effectivement le cas.<\/p>\n\n\n\n<p>Mais qu&rsquo;ils consid\u00e8rent alors \u00e9galement que cela repr\u00e9sente absolument tout, tout sauf un monument fun\u00e9raire.<\/p>\n\n\n\n<p>Car il n&rsquo;y a pas de plus grande joie pour moi que de voir que j&rsquo;ai su assembler ces diverses pi\u00e8ces mentales pour construire \u2014 et je veux vous confier que c&rsquo;est in\u00e9dit \u2014 cet <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/06\/nous-navons-encore-pas-tout-lu-une-conversation-fleuve-avec-herve-le-tellier\/\">artifice litt\u00e9raire<\/a>. Un Canon ouvert aux quatre vents.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Le \u00ab&#160;canon de la chambre noire&#160;\u00bb n&rsquo;est-il pas, en fin de compte, ce roman lui-m\u00eame sous la forme d&rsquo;un grand palimpseste&#160;?<\/h3>\n\n\n\n<p>Il peut \u00eatre lu ainsi, comme un manuscrit ancien qui conserve les traces d&rsquo;une \u00e9criture ant\u00e9rieure, effac\u00e9e artificiellement.&nbsp;<\/p>\n\n\n\n<p>Il peut \u00eatre lu ainsi, oui. Je n&rsquo;y avais pas pens\u00e9, mais c&rsquo;est magnifique que nous puissions le voir de la sorte.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Au chapitre 40, le narrateur expose la condition de non-lieu de sa biblioth\u00e8que. Le \u00ab&#160;canon de la chambre noire&#160;\u00bb pourrait-il \u00eatre n&rsquo;importe quel bon livre qui, par son absence de lieu, permet de voyager vers d&rsquo;autres lieux \u2014 en pensant m\u00eame \u00e0 une remotivation po\u00e9tique des \u00ab&#160;non-lieux&#160;\u00bb de Marc Aug\u00e9 \u2014 dans lesquels \u00ab&#160;on s&rsquo;interroge n\u00e9cessairement sur l&rsquo;errance, la dispersion, la diaspora, tout ce qui est rel\u00e9gu\u00e9, tout ce qui nous montre en silence le peu qui reste du monde&#160;\u00bb&#160;?<\/h3>\n\n\n\n<p>Et aussi de ce qui reste de la litt\u00e9rature, n&rsquo;est-ce pas&#160;?&nbsp;<\/p>\n\n\n\n<p>Car on peut penser ici aux r\u00eanes l\u00e2ch\u00e9es quand est mentionn\u00e9 dans le livre le grand r\u00e9cit de <a href=\"https:\/\/legrandcontinent.eu\/fr\/themes\/arts\/litterature\/kafka-le-proces-100-ans-apres\/\">Kafka<\/a>, <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/04\/27\/kafka-genese-du-proces-une-conversation-avec-florence-bancaud\/\">\u00ab&#160;R\u00eave de devenir un Indien&#160;\u00bb<\/a>, dans lequel le d\u00e9sir du protagoniste de voler, de s&rsquo;\u00e9lancer, de fuir absolument est justement tr\u00e8s important.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>L&rsquo;obscurit\u00e9 est l&rsquo;essence m\u00eame de la chambre.<\/p><cite>Enrique Vila-Matas<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Comment d\u00e9finiriez-vous ou caract\u00e9riseriez-vous le r\u00f4le \u2014 paradoxal peut-\u00eatre \u2014 de l&rsquo;obscurit\u00e9 dans le roman&#160;? Dans le dernier paragraphe du chapitre 55, on peut lire&#160;: \u00ab&#160;Je ris, par exemple, du paradoxe comique que je d\u00e9tecte dans le fait que pour un Denver-7 qui pr\u00e9voit de se venger, <em>sortir \u00e0 la lumi\u00e8re<\/em> et d\u00e9ployer sa ranc\u0153ur contre \u2014 pour prendre un exemple de sujet duquel se venger \u2014 son ancien propri\u00e9taire peut lui co\u00fbter la vie alors que s&rsquo;il jouit d&rsquo;une longue vie, c&rsquo;est pr\u00e9cis\u00e9ment gr\u00e2ce \u00e0 une coupure d&rsquo;\u00e9lectricit\u00e9.&#160;\u00bb<\/h3>\n\n\n\n<p>L&rsquo;obscurit\u00e9 est l&rsquo;essence m\u00eame de la chambre, c&rsquo;est ce que recherche le livre ou l&rsquo;extrait choisi avec ce jeu de lumi\u00e8re \u00e0 travers la fen\u00eatre de la fameuse pi\u00e8ce \u2014 et cette obscurit\u00e9 est finalement ce qui permet, en effet, au narrateur de vivre.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00ab&#160;Rien ne semblait lui faire autant plaisir que l&rsquo;obscurit\u00e9&#160;\u00bb, dit le narrateur en parlant d&rsquo;Altobelli, avant que celui-ci n&rsquo;ajoute&#160;: \u00ab&#160;Et parce que, sans les ombres, les livres que nous aimons tant ne seraient rien.&#160;\u00bb Qu&rsquo;est-ce que l&rsquo;obscurit\u00e9 permet dans la litt\u00e9rature que la lumi\u00e8re emp\u00eacherait&#160;?&nbsp;<\/h3>\n\n\n\n<p>Beaucoup de choses. Il suffit de fermer les yeux. Regardons.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Il y a un jeu presque syst\u00e9matique qui s&rsquo;installe dans la dialectique toujours complexe et floue entre l&rsquo;auteur (ou \u00ab&#160;Auctor&#160;\u00bb) et le narrateur&#160;: ce dernier se moque du premier et celui-ci, en donnant au narrateur la possibilit\u00e9 de se moquer, montre paradoxalement qu&rsquo;il contr\u00f4le tout. \u00c0 un moment donn\u00e9, le narrateur \u00ab&#160;soup\u00e7onne&#160;\u00bb que \u00ab&#160;l&rsquo;Auteur, cette figure qui plane sur la vie de nombreux narrateurs&#160;\u00bb est intervenu dans le r\u00e9cit. On parle d&rsquo;une voix pr\u00e9sente, \u00e9trang\u00e8re, d&rsquo;un \u00ab&#160;occupant&#160;\u00bb. Qui est la figure omnipotente dans ce cas&#160;: le narrateur ou l&rsquo;auteur&#160;?<\/h3>\n\n\n\n<p><em>Canon de c\u00e1mara oscura<\/em> soul\u00e8ve des questions comme la v\u00f4tre et laisse au lecteur le soin d&rsquo;y r\u00e9pondre, s&rsquo;il le souhaite, comme il le pr\u00e9f\u00e8re.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00cates-vous \u00ab&#160;l&rsquo;un d&rsquo;entre eux&#160;\u00bb \u2014 un <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/06\/08\/nos-livres-sont-plus-intelligents-que-nous-une-conversation-avec-rosa-montero\/\">Denver-7<\/a>&#160;?&nbsp;<\/h3>\n\n\n\n<p>Bien s\u00fbr. Mais si vous souhaitez en douter, libre \u00e0 vous de le faire&#160;!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Et diriez-vous aussi, comme le dit le narrateur au chapitre 56, que vous \u00eates \u00ab&#160;un \u00e9crivain de cave&#160;\u00bb en parlant de votre cabinet et en faisant r\u00e9f\u00e9rence \u00e0 \u00ab&#160;K&#160;\u00bb&#160;? Nous revenons d\u2019ailleurs au th\u00e8me de l&rsquo;obscurit\u00e9.&nbsp;<\/h3>\n\n\n\n<p>Celui qui dit cela dans l&rsquo;extrait que vous citez le dit avec beaucoup de conviction.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">En parlant de Kafka, on trouve dans l&rsquo;\u0153uvre du ma\u00eetre de Prague tout un imaginaire qui tourne autour <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/04\/27\/kafka-genese-du-proces-une-conversation-avec-florence-bancaud\/\">du couteau et du corps fragment\u00e9<\/a>, ce qui peut faire penser \u00e0 son style et \u00e0 sa m\u00e9thode d&rsquo;\u00e9criture. \u00c9crivez-vous \u00e9galement par fragments, par morceaux de texte qu&rsquo;il faut ensuite assembler pour obtenir le texte final&#160;?&nbsp;<\/h3>\n\n\n\n<p>Exactement.<\/p>\n\n\n\n<p>Et le narrateur\/auteur revendique avec une grande conviction le fragment d\u00e8s les premiers instants de cet artifice qu\u2019est le Canon. \u00ab&#160;Les fragments&#160;! Ils ne sont pas, comme on le croit souvent, une partie du tout, mais une partie tr\u00e8s importante du tout. C&rsquo;est pourquoi ils doivent avoir suffisamment de puissance pour que nous puissions ouvrir un livre \u00e0 n&rsquo;importe quelle page et lire sans avoir besoin de savoir ce qui s&rsquo;est pass\u00e9 avant ou ce qui se passera apr\u00e8s.&#160;\u00bb<\/p>\n\n\n\n<p>Ce sont des fragments qui me rappellent ce type de livres sans couverture, parce qu&rsquo;ils sont ouverts et libres, et qu&rsquo;on peut \u00e9crire avant et apr\u00e8s eux.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>J\u2019\u00e9cris toujours en pensant que je suis plong\u00e9 dans un fragment.<\/p><cite>Enrique Vila-Matas<\/cite><\/blockquote><\/figure>\n\n\n\n<p>\u00ab&#160;Le fragment a quelque chose d\u2019une puissance pr\u00e9sente qui n&rsquo;a besoin ni du pass\u00e9 ni du futur&#160;\u00bb, \u00e9crit dans son livre <em>Biblioteca<\/em> le Portugais Gon\u00e7alo M. Tavares (dans l&rsquo;obscurit\u00e9 de la chambre noire, attendant le Canon), un auteur auquel on peut appliquer ce qu&rsquo;il dit, dans ce m\u00eame livre, de Ludwig Wittgenstein, qu&rsquo;il qualifie de \u00ab&#160;mentalement d\u00e9plac\u00e9, comme tous les individus int\u00e9ressants&#160;\u00bb.<\/p>\n\n\n\n<p>J&rsquo;aimerais que Ryo d\u00e9crive un jour mon Canon ainsi&#160;: \u00ab&#160;Mentalement d\u00e9plac\u00e9 et intempestif, comme tous les canons int\u00e9ressants&#160;\u00bb.<\/p>\n\n\n\n<p>Une note sur Ryo&#160;: c&rsquo;est la fille de l&rsquo;andro\u00efde, c&rsquo;est-\u00e0-dire du responsable du Canon de l&rsquo;Andro\u00efde.<\/p>\n\n\n\n<p>Et une derni\u00e8re remarque&#160;: j&rsquo;\u00e9cris toujours en pensant que je suis plong\u00e9 dans un fragment. Mais si, lorsque je termine ce fragment, je constate qu&rsquo;il est li\u00e9 au c\u0153ur du livre, cela ne me bouleverse pas du tout. Au contraire, je pense que je suis sur la bonne voie, peut-\u00eatre parce que je me sens de plus en plus proche du <em>Grand Chemin<\/em> dont parlait Julien Gracq.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/25\/le-secret-de-jorge-luis-borges-une-conversation-avec-jean-pierre-dupuy\/\">Borges<\/a> est bien s\u00fbr cit\u00e9 dans le roman. Le <em>Canon de la chambre noire <\/em>donne l&rsquo;impression d&rsquo;\u00eatre dans une sorte de Biblioth\u00e8que de Babel, un labyrinthe infini \u00ab&#160;sans savoir o\u00f9 tout a commenc\u00e9 ni m\u00eame pourquoi cela a commenc\u00e9&#160;\u00bb (chapitre 7) \u2014 sans savoir non plus n\u00e9cessairement o\u00f9 cela finit\u2026 Je pense ici aussi \u00e0 la magnifique phrase de Val\u00e9ry cit\u00e9e dans le chapitre 18 du livre&#160;: \u00ab&#160;L&rsquo;infini\u2026 est une affaire d&rsquo;\u00e9criture. L&rsquo;univers n&rsquo;existe que sur le papier.&#160;\u00bb&nbsp;<\/h3>\n\n\n\n<p>Je ne me souviens pas pr\u00e9cis\u00e9ment quand <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/06\/nous-navons-encore-pas-tout-lu-une-conversation-fleuve-avec-herve-le-tellier\/\">Borges appara\u00eet<\/a>, peut-\u00eatre parce que c&rsquo;est un auteur qui est pr\u00e9sent \u00e0 tout moment.&nbsp;<\/p>\n\n\n\n<p>Le fait est que je le cite souvent dans les entretiens d\u00e8s qu&rsquo;on me parle de lui. Et si je le cite, c&rsquo;est pour clarifier un malentendu. Ou simplement pour rappeler que le nouveau genre fantastique de la litt\u00e9rature, c&rsquo;est la litt\u00e9rature elle-m\u00eame.<\/p>\n\n\n\n<p>C&rsquo;est le mat\u00e9riau avec lequel je travaille et dont on m&rsquo;accuse parfois de travailler. C&rsquo;est un mat\u00e9riau \u2014 le mat\u00e9riau litt\u00e9raire \u2014 que je place dans cet ordre fantastique tel que le voyait Borges lui-m\u00eame.<\/p>\n\n\n\n<p>Je ne pense pas devoir le r\u00e9p\u00e9ter, <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/06\/nous-navons-encore-pas-tout-lu-une-conversation-fleuve-avec-herve-le-tellier\/\">n&rsquo;importe quelle IA<\/a> est capable de savoir par c\u0153ur quelque chose d&rsquo;aussi simple que le fait que Borges a incorpor\u00e9 des r\u00e9f\u00e9rences \u00e0 d&rsquo;autres \u0153uvres litt\u00e9raires, philosophiques et culturelles, cr\u00e9ant ainsi un r\u00e9seau de connexions qui n&rsquo;ont fait qu&rsquo;enrichir ses histoires.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Le nouveau genre fantastique de la litt\u00e9rature, c&rsquo;est la litt\u00e9rature elle-m\u00eame.<\/p><cite>Enrique Vila-Matas<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">En lisant votre livre, on d\u00e9c\u00e8le une tension autour de la simultan\u00e9it\u00e9 \u2014 un terme qui appara\u00eet plusieurs fois. Cet excellent passage le symbolise parfaitement&#160;: \u00ab&#160;J&rsquo;entre dans la maison et me dirige presque imm\u00e9diatement vers le cabinet, o\u00f9 je m&rsquo;installe dans le fauteuil pivotant o\u00f9 je me suis vu assis \u00e0 tant de moments de la f\u00eate, et o\u00f9 je suis en r\u00e9alit\u00e9 assis depuis un moment \u00e0 d\u00e9crire au pr\u00e9sent certains \u00e9v\u00e9nements de cette nuit&#160;\u00bb (chapitre 42). Cherchez-vous \u00e0 faire perdurer le pr\u00e9sent, \u00e0 le prolonger, \u00e0 le r\u00e9p\u00e9ter, \u00e0 le d\u00e9former comme seule l&rsquo;\u00e9criture le permet&#160;? Quelques lignes plus loin, le narrateur semble proposer une hypoth\u00e8se de lecture&#160;: \u00ab&#160;il est \u00e9vident que celui qui vit dans le pr\u00e9sent peut, s&rsquo;il le souhaite, r\u00e9p\u00e9ter le pr\u00e9sent qui n&rsquo;existe plus, mais seulement en \u00e9crivant.&#160;\u00bb<\/h3>\n\n\n\n<p>Cet extrait permet de confirmer que, d\u00e8s la premi\u00e8re ligne du livre, le narrateur raconte au pr\u00e9sent et qu&rsquo;\u00e0 ce moment pr\u00e9cis, il est en train de vivre l&rsquo;\u00e9criture dans deux lieux identiques et diff\u00e9rents \u00e0 la fois. L&rsquo;\u00e9criture hors de l&rsquo;espace et du temps&#160;? C&rsquo;est un plaisir d&rsquo;essayer de l&rsquo;\u00e9crire et de la vivre ainsi.<\/p>\n\n\n\n<p>J&rsquo;ajouterais ici que la litt\u00e9rature rend presque tout possible, voire tout, elle rend absolument tout possible \u2014 \u00e0 condition que nous puissions faire confiance \u00e0 notre esprit \u2014 et \u00e0 condition de bien le manier aussi.<\/p>\n\n\n\n<p>\u00ab&#160;Y a-t-il quelque chose qui ne soit pas dans ma t\u00eate&#160;?&#160;\u00bb, se demandait Wittgenstein.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Pour poursuivre sur la simultan\u00e9it\u00e9, \u00eates-vous un \u00e9crivain qui vit puis \u00e9crit \u2014&nbsp; Camus disait&#160;: \u00ab&#160;Il y a un temps pour vivre et un temps pour t\u00e9moigner de vivre&#160;\u00bb, <em>Noces<\/em> \u2014 ou essayez-vous de faire les deux en m\u00eame temps, pour ainsi dire&#160;?<\/h3>\n\n\n\n<p>Dans mon propre Canon, on vit en direct comme j&rsquo;\u00e9cris en vivant.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ressentez-vous aussi, lorsque vous voulez \u00e9crire, ce souffle dont parle le grand \u00e9crivain p\u00e9ruvien Julio Ram\u00f3n Ribeyro, qui passe, s&rsquo;\u00e9chappe et finit par dispara\u00eetre sans que vous ayez pu l&rsquo;attraper&#160;?&nbsp;<\/h3>\n\n\n\n<p>Cela ne m&rsquo;est arriv\u00e9 qu&rsquo;une seule fois, lorsque je vivais \u00e0 Paris dans les ann\u00e9es 1970. Le diable en personne s&rsquo;est infiltr\u00e9 dans ma mansarde et m&rsquo;a donn\u00e9 une histoire extraordinaire pour un roman.<\/p>\n\n\n\n<p>Mais comme \u00e0 l&rsquo;\u00e9poque j&rsquo;\u00e9tais d\u00e9j\u00e0 plus int\u00e9ress\u00e9 par l&rsquo;essai, je n&rsquo;y ai pas pr\u00eat\u00e9 beaucoup d&rsquo;attention.<\/p>\n\n\n\n<p>Et quand j&rsquo;ai finalement d\u00e9cid\u00e9 de m&#8217;emparer de l&rsquo;histoire que me racontait mon visiteur et avec laquelle j&rsquo;aurais sans doute domin\u00e9 le monde, on a frapp\u00e9 \u00e0 la porte et tout s&rsquo;est effondr\u00e9 d&rsquo;un coup \u2014 ce qui m&rsquo;a procur\u00e9 un soulagement extraordinaire.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>L&rsquo;\u00e9criture hors de l&rsquo;espace et du temps&#160;? C&rsquo;est un plaisir d&rsquo;essayer de l&rsquo;\u00e9crire et de la vivre ainsi.<\/p><cite>Enrique Vila-Matas<\/cite><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">La grande t\u00e2che \u2014 et la frustration, aussi \u2014 de l&rsquo;\u00e9crivain est de dire l&rsquo;indicible. C&rsquo;est d&rsquo;ailleurs ainsi que commence le roman. Comment peut-on s&rsquo;approcher de l&rsquo;indicible&#160;? Faut-il le repr\u00e9senter par des images comme le faisait Flaubert, l&rsquo;entourer comme Proust avec ses longues phrases ou citer tous les grands anciens qui se sont pos\u00e9 le m\u00eame probl\u00e8me dans le pass\u00e9, comme vous le faites, en citant Cort\u00e1zar sur ce m\u00eame sujet dans <em>Marelle<\/em>&#160;: \u00ab&#160;Mais ce que je voudrais te dire me para\u00eet justement indicible. Il faut tourner autour comme un chien qui cherche \u00e0 attraper sa queue.&nbsp; [&#8230;] Je ne renonce \u00e0 rien, simplement je fais tout mon possible pour que les choses renoncent \u00e0 moi.&#160;\u00bb&#160;?<\/h3>\n\n\n\n<p>Je crois que je suis sur le point de vous dire l&rsquo;indicible.&nbsp;<\/p>\n\n\n\n<p>Mais je passe ma vie \u00e0 craindre qu&rsquo;on frappe \u00e0 ma porte.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Comme le dit Altobelli, \u00ab&#160;pour \u00eatre vraiment contemporain, faut-il \u00eatre l\u00e9g\u00e8rement inactuel&#160;\u00bb&#160;?<\/h3>\n\n\n\n<p>Absolument. Rien n\u2019est plus clair \u00e0 mes yeux.&nbsp;<\/p>\n\n\n\n<p>Je sais seulement que face \u00e0 la vague de livres qui confondent le politique et le conjoncturel \u2014 c\u2019est la logique du march\u00e9 \u2014 mon \u0153uvre recherche ce que <a href=\"https:\/\/legrandcontinent.eu\/es\/2025\/04\/20\/el-papa-francisco-es-el-loco-de-dios-por-antonomasia-y-este-es-el-libro-mas-loco-que-he-escrito-una-conversacion-con-javier-cercas\/\">Nietzsche criait avant de s&rsquo;effondrer \u00e0 Turin<\/a>&#160;: pour \u00eatre vraiment contemporain, il faut \u00eatre intempestif, l\u00e9g\u00e8rement inactuel. J\u2019ajoute ici&#160;: comme le Canon de l&rsquo;andro\u00efde.&nbsp;<\/p>\n\n\n\n<p>C&rsquo;est \u00e0 partir de cette position d\u00e9cal\u00e9e que nous offre le langage que s&rsquo;ouvre \u2014 \u00e0 la mani\u00e8re d&rsquo;un parallaxe \u2014 la distance critique qui nous permet d&rsquo;esquisser une divergence politique face au pr\u00e9sent.&nbsp;<\/p>\n\n\n\n<p>C&rsquo;est tout ce que je sais.<\/p>\n\n\n\n<p>Et encore.<\/p>\n\n\n\n<p>Ne croyez pas que je sache quoi que ce soit.<\/p>\n\n\n\n<p>Tout au plus, je sais, peut-\u00eatre, survivre \u00e0 un entretien aussi difficile \u2014 et par moments, amusant \u2014 que celui-ci.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un andro\u00efde. <\/p>\n<p>Une chambre obscure. <\/p>\n<p>Toute la litt\u00e9rature mondiale jamais \u00e9crite.<\/p>\n<p>On pourrait r\u00e9sumer ainsi le sujet du nouveau roman d\u2019Enrique Vila-Matas \u2014 mais on passerait \u00e0 c\u00f4t\u00e9 de l\u2019essentiel&#160;&#160;: tout le reste.<\/p>\n<p>Pour achever notre saison d\u2019entretiens litt\u00e9raires, nous recueillons les fulgurances du ma\u00eetre catalan.<\/p>\n","protected":false},"author":10,"featured_media":288371,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-interviews.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":11,"footnotes":""},"categories":[4344],"tags":[],"staff":[1631],"editorial_format":[4854],"serie":[],"audience":[],"geo":[1917],"class_list":["post-288369","post","type-post","status-publish","format-standard","hentry","category-litterature","staff-florent-zemmouche","editorial_format-entretiens","geo-europe"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":288371,"excerpt":"Un andro\u00efde. \r\n\r\nUne chambre obscure. \r\n\r\nToute la litt\u00e9rature mondiale jamais \u00e9crite.\r\n\r\nOn pourrait r\u00e9sumer ainsi le sujet du nouveau roman d\u2019Enrique Vila-Matas \u2014 mais on passerait \u00e0 c\u00f4t\u00e9 de l\u2019essentiel: tout le reste.\r\n\r\nPour achever notre saison d\u2019entretiens litt\u00e9raires, nous recueillons les fulgurances du ma\u00eetre catalan.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Enrique Vila-Matas: je suis sur le point de vous dire l&#039;indicible<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/20\/je-suis-sur-le-point-de-vous-dire-lindicible-mais-je-passe-ma-vie-a-craindre-quon-frappe-a-ma-porte-une-conversation-avec-enrique-vila-matas\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enrique Vila-Matas: je suis sur le point de vous dire l&#039;indicible\" \/>\n<meta property=\"og:description\" content=\"Un andro\u00efde.   Une chambre obscure.   Toute la litt\u00e9rature mondiale jamais \u00e9crite.  On pourrait r\u00e9sumer ainsi le sujet du nouveau roman d\u2019Enrique Vila-Matas \u2014 mais on passerait \u00e0 c\u00f4t\u00e9 de l\u2019essentiel&#160;: tout le reste.  Pour achever notre saison d\u2019entretiens litt\u00e9raires, nous recueillons les fulgurances du ma\u00eetre catalan.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/20\/je-suis-sur-le-point-de-vous-dire-lindicible-mais-je-passe-ma-vie-a-craindre-quon-frappe-a-ma-porte-une-conversation-avec-enrique-vila-matas\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-20T16:21:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-20T21:23:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/gc-vilamatas-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matheo Malik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/gc-vilamatas-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheo Malik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/20\/je-suis-sur-le-point-de-vous-dire-lindicible-mais-je-passe-ma-vie-a-craindre-quon-frappe-a-ma-porte-une-conversation-avec-enrique-vila-matas\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/20\/je-suis-sur-le-point-de-vous-dire-lindicible-mais-je-passe-ma-vie-a-craindre-quon-frappe-a-ma-porte-une-conversation-avec-enrique-vila-matas\/\",\"name\":\"Enrique Vila-Matas: je suis sur le point de vous dire l'indicible\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/20\/je-suis-sur-le-point-de-vous-dire-lindicible-mais-je-passe-ma-vie-a-craindre-quon-frappe-a-ma-porte-une-conversation-avec-enrique-vila-matas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/20\/je-suis-sur-le-point-de-vous-dire-lindicible-mais-je-passe-ma-vie-a-craindre-quon-frappe-a-ma-porte-une-conversation-avec-enrique-vila-matas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/SIPA_00793213_000002-scaled.jpg\",\"datePublished\":\"2025-07-20T16:21:56+00:00\",\"dateModified\":\"2025-07-20T21:23:32+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/20\/je-suis-sur-le-point-de-vous-dire-lindicible-mais-je-passe-ma-vie-a-craindre-quon-frappe-a-ma-porte-une-conversation-avec-enrique-vila-matas\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/20\/je-suis-sur-le-point-de-vous-dire-lindicible-mais-je-passe-ma-vie-a-craindre-quon-frappe-a-ma-porte-une-conversation-avec-enrique-vila-matas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/20\/je-suis-sur-le-point-de-vous-dire-lindicible-mais-je-passe-ma-vie-a-craindre-quon-frappe-a-ma-porte-une-conversation-avec-enrique-vila-matas\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/SIPA_00793213_000002-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/SIPA_00793213_000002-scaled.jpg\",\"width\":1707,\"height\":2560,\"caption\":\"L'\u00e9crivain espagnol Enrique Vila-Matas photographi\u00e9 \u00e0 Madrid en 2017. \u00a9 Fernando Alvarado\/EFE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/20\/je-suis-sur-le-point-de-vous-dire-lindicible-mais-je-passe-ma-vie-a-craindre-quon-frappe-a-ma-porte-une-conversation-avec-enrique-vila-matas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00ab&#160;Je suis sur le point de vous dire l&rsquo;indicible \u2014 mais je passe ma vie \u00e0 craindre qu&rsquo;on frappe \u00e0 ma porte&#160;\u00bb, une conversation avec Enrique Vila-Matas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\",\"name\":\"Matheo Malik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"caption\":\"Matheo Malik\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Enrique Vila-Matas: je suis sur le point de vous dire l'indicible","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/20\/je-suis-sur-le-point-de-vous-dire-lindicible-mais-je-passe-ma-vie-a-craindre-quon-frappe-a-ma-porte-une-conversation-avec-enrique-vila-matas\/","og_locale":"fr_FR","og_type":"article","og_title":"Enrique Vila-Matas: je suis sur le point de vous dire l'indicible","og_description":"Un andro\u00efde.   Une chambre obscure.   Toute la litt\u00e9rature mondiale jamais \u00e9crite.  On pourrait r\u00e9sumer ainsi le sujet du nouveau roman d\u2019Enrique Vila-Matas \u2014 mais on passerait \u00e0 c\u00f4t\u00e9 de l\u2019essentiel&#160;: tout le reste.  Pour achever notre saison d\u2019entretiens litt\u00e9raires, nous recueillons les fulgurances du ma\u00eetre catalan.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/20\/je-suis-sur-le-point-de-vous-dire-lindicible-mais-je-passe-ma-vie-a-craindre-quon-frappe-a-ma-porte-une-conversation-avec-enrique-vila-matas\/","og_site_name":"Le Grand Continent","article_published_time":"2025-07-20T16:21:56+00:00","article_modified_time":"2025-07-20T21:23:32+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/gc-vilamatas-scaled.jpg","type":"image\/jpeg"}],"author":"Matheo Malik","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/gc-vilamatas-scaled.jpg","twitter_misc":{"\u00c9crit par":"Matheo Malik","Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/20\/je-suis-sur-le-point-de-vous-dire-lindicible-mais-je-passe-ma-vie-a-craindre-quon-frappe-a-ma-porte-une-conversation-avec-enrique-vila-matas\/","url":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/20\/je-suis-sur-le-point-de-vous-dire-lindicible-mais-je-passe-ma-vie-a-craindre-quon-frappe-a-ma-porte-une-conversation-avec-enrique-vila-matas\/","name":"Enrique Vila-Matas: je suis sur le point de vous dire l'indicible","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/20\/je-suis-sur-le-point-de-vous-dire-lindicible-mais-je-passe-ma-vie-a-craindre-quon-frappe-a-ma-porte-une-conversation-avec-enrique-vila-matas\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/20\/je-suis-sur-le-point-de-vous-dire-lindicible-mais-je-passe-ma-vie-a-craindre-quon-frappe-a-ma-porte-une-conversation-avec-enrique-vila-matas\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/SIPA_00793213_000002-scaled.jpg","datePublished":"2025-07-20T16:21:56+00:00","dateModified":"2025-07-20T21:23:32+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/20\/je-suis-sur-le-point-de-vous-dire-lindicible-mais-je-passe-ma-vie-a-craindre-quon-frappe-a-ma-porte-une-conversation-avec-enrique-vila-matas\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2025\/07\/20\/je-suis-sur-le-point-de-vous-dire-lindicible-mais-je-passe-ma-vie-a-craindre-quon-frappe-a-ma-porte-une-conversation-avec-enrique-vila-matas\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/20\/je-suis-sur-le-point-de-vous-dire-lindicible-mais-je-passe-ma-vie-a-craindre-quon-frappe-a-ma-porte-une-conversation-avec-enrique-vila-matas\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/SIPA_00793213_000002-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/SIPA_00793213_000002-scaled.jpg","width":1707,"height":2560,"caption":"L'\u00e9crivain espagnol Enrique Vila-Matas photographi\u00e9 \u00e0 Madrid en 2017. \u00a9 Fernando Alvarado\/EFE"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/20\/je-suis-sur-le-point-de-vous-dire-lindicible-mais-je-passe-ma-vie-a-craindre-quon-frappe-a-ma-porte-une-conversation-avec-enrique-vila-matas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00ab&#160;Je suis sur le point de vous dire l&rsquo;indicible \u2014 mais je passe ma vie \u00e0 craindre qu&rsquo;on frappe \u00e0 ma porte&#160;\u00bb, une conversation avec Enrique Vila-Matas"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45","name":"Matheo Malik","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","caption":"Matheo Malik"}}]}},"lgc_categories":[{"id":4344,"name":"Litt\u00e9rature","slug":"litterature"}],"lgc_author":{"id":1631,"name":"Florent Zemmouche","slug":"florent-zemmouche","description":"Florent Zemmouche dirige l'\u00e9dition en espagnol du Grand Continent, coordonne les s\u00e9minaires hebdomadaires de la revue \u00e0 Madrid, les <em>Mi\u00e9rcoles del GC.<\/em>","first_name":"Florent","last_name":"Zemmouche","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2023\/06\/gc-elzemmouche.jpg","width":399,"height":531,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/SIPA_00793213_000002-scaled.jpg","width":1707,"height":2560,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/SIPA_00793213_000002-scaled.jpg","width":1707,"height":2560,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/288369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=288369"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/288369\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/288371"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=288369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=288369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=288369"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=288369"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=288369"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=288369"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=288369"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=288369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}