{"id":287779,"date":"2025-07-16T15:08:39","date_gmt":"2025-07-16T13:08:39","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=287779"},"modified":"2025-07-16T15:08:42","modified_gmt":"2025-07-16T13:08:42","slug":"les-nouvelles-livraisons-darmes-a-lukraine-pourraient-elles-inclure-des-missiles-de-croisiere-susceptibles-datteindre-moscou","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/16\/les-nouvelles-livraisons-darmes-a-lukraine-pourraient-elles-inclure-des-missiles-de-croisiere-susceptibles-datteindre-moscou\/","title":{"rendered":"Les nouvelles livraisons d\u2019armes \u00e0 l\u2019Ukraine pourraient-elles inclure des missiles de croisi\u00e8re susceptibles d\u2019atteindre Moscou&#160;?"},"content":{"rendered":"\n<p>Les propos entre Trump et Zelensky rapport\u00e9s hier, mardi 15 juillet, par le <em>Financial Times <\/em>concernant de potentielles frappes ukrainiennes en Russie \u00e0 l\u2019aide d\u2019armes am\u00e9ricaines ont \u00e9t\u00e9 accueillis avec beaucoup de prudence au Kremlin.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Lors d\u2019un appel le 4 juillet, le pr\u00e9sident am\u00e9ricain aurait demand\u00e9 \u00e0 son homologue ukrainien&#160;: \u00ab&#160;Volodymyr, pouvez-vous frapper Moscou \u2026&#160;? Pouvez-vous frapper Saint-P\u00e9tersbourg aussi&#160;?&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-287779' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/07\/16\/les-nouvelles-livraisons-darmes-a-lukraine-pourraient-elles-inclure-des-missiles-de-croisiere-susceptibles-datteindre-moscou\/#easy-footnote-bottom-1-287779' title='Christopher Miller, Henry Foy, Max Seddon et Lauren Fedor, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.ft.com\/content\/b66f03b5-e295-4f8c-92ba-516a527d588c&quot;&gt;Donald Trump asked Volodymyr Zelenskyy if Ukraine could hit Moscow, say people briefed on call&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;Financial Times&lt;\/em&gt;, 15 juillet 2025.'><sup>1<\/sup><\/a><\/span><\/span><\/li>\n\n\n\n<li>La Maison-Blanche a depuis ni\u00e9 ces informations et d\u00e9clar\u00e9 que l\u2019Ukraine \u00ab&#160;ne devrait pas viser Moscou&#160;\u00bb.<\/li>\n\n\n\n<li>Lundi 14 juillet, le pr\u00e9sident am\u00e9ricain a d\u00e9clar\u00e9 qu\u2019il autoriserait l\u2019envoi de nouveaux syst\u00e8mes \u00e0 l\u2019Ukraine \u00ab&#160;pour plusieurs milliards de dollars&#160;\u00bb, financ\u00e9s par des pays de l\u2019OTAN.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/CCgts\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Moscou s\u2019est pour le moment content\u00e9 de \u00ab&#160;condamner&#160;\u00bb les livraisons occidentales \u00e0 Kiev et a \u00ab&#160;soulign\u00e9 que celles-ci prolongeront le conflit&#160;\u00bb, tout en n\u2019emp\u00eachant pas la Russie d\u2019atteindre ses objectifs de guerre&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-287779' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/07\/16\/les-nouvelles-livraisons-darmes-a-lukraine-pourraient-elles-inclure-des-missiles-de-croisiere-susceptibles-datteindre-moscou\/#easy-footnote-bottom-2-287779' title='\u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.rbc.ru\/politics\/14\/07\/2025\/6874d4209a7947460759937c&quot;&gt;\u041f\u0435\u0441\u043a\u043e\u0432 \u043e\u0446\u0435\u043d\u0438\u043b \u043f\u043b\u0430\u043d\u044b \u0422\u0440\u0430\u043c\u043f\u0430 \u043e\u0442\u043f\u0440\u0430\u0432\u0438\u0442\u044c \u0423\u043a\u0440\u0430\u0438\u043d\u0435 \u043e\u0440\u0443\u0436\u0438\u0435 \u0437\u0430 \u0441\u0447\u0435\u0442 \u0415\u0432\u0440\u043e\u043f\u044b&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;\u0420\u0411\u041a&lt;\/em&gt;, 14 juillet 2025.'><sup>2<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<p>Le porte-parole du Kremlin Dmitri Peskov a minimis\u00e9 l\u2019importance de ces fuites et d\u00e9clar\u00e9 que ces derni\u00e8res s\u2019av\u00e9raient g\u00e9n\u00e9ralement \u00eatre \u00ab&#160;fausses&#160;\u00bb, arguant que&#160;: \u00ab&#160;Ce genre de discours circule depuis un certain temps d\u00e9j\u00e0&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-287779' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/07\/16\/les-nouvelles-livraisons-darmes-a-lukraine-pourraient-elles-inclure-des-missiles-de-croisiere-susceptibles-datteindre-moscou\/#easy-footnote-bottom-3-287779' title='\u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.rbc.ru\/rbcfreenews\/6876238f9a794707b891afee?from=from_main_9&quot;&gt;\u041f\u0435\u0441\u043a\u043e\u0432 \u0441\u0432\u044f\u0437\u0430\u043b \u0441 \u0444\u0435\u0439\u043a\u0430\u043c\u0438 \u0441\u043e\u043e\u0431\u0449\u0435\u043d\u0438\u044f \u043e \u043f\u0440\u0438\u0437\u044b\u0432\u0435 \u0422\u0440\u0430\u043c\u043f\u0430 \u00ab&amp;#160;\u043d\u0430\u0434\u0430\u0432\u0438\u0442\u044c \u043d\u0430 \u041c\u043e\u0441\u043a\u0432\u0443&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;\u0420\u0411\u041a&lt;\/em&gt;, 15 juillet 2025.'><sup>3<\/sup><\/a><\/span><\/span>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L\u2019administration Biden <a href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/10\/20\/que-peuvent-les-missiles-atacms-recemment-livres-a-lukraine\/\">avait d\u00e9j\u00e0 envoy\u00e9 des ATACMS \u00e0 Kiev en 2023<\/a>, ce qui avait permis \u00e0 l\u2019Ukraine de frapper des cibles situ\u00e9es dans des r\u00e9gions frontali\u00e8res russes, comme l\u2019oblast de Briansk et de Koursk en novembre dernier.<\/li>\n\n\n\n<li>En r\u00e9action, la Russie avait frapp\u00e9 la ville ukrainienne de Dnipro <a href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/11\/22\/le-message-du-missile-oreshnik-comprendre-la-rhetorique-nucleaire-de-poutine-traduction-inedite\/\">avec un missile Oreshnik<\/a>, capable de transporter une ogive nucl\u00e9aire, afin d\u2019envoyer un avertissement \u00e0 Kiev quant \u00e0 des frappes longue distance en territoire russe.<\/li>\n\n\n\n<li>Les m\u00e9dias d\u2019\u00c9tat russe diffusaient alors \u00e0 la t\u00e9l\u00e9vision des estimations du temps de trajet requis pour <a href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/12\/03\/avec-poutine-et-trump-le-monde-sapprete-t-il-a-entrer-dans-un-age-nucleaire\/\">qu\u2019un missile Oreshnik atteigne les capitales europ\u00e9ennes<\/a>&#160;: 12 minutes pour Varsovie, 15 pour Berlin, 20 pour Londres et Paris.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/sVT9x\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>L\u2019Ukraine a frapp\u00e9 \u00e0 plusieurs reprises le territoire russe en profondeur depuis f\u00e9vrier 2022 en utilisant des drones longue port\u00e9e qui ont cibl\u00e9 des bases militaires, des a\u00e9rodromes, des raffineries et r\u00e9serves de p\u00e9trole, ou bien des m\u00e9tropoles. En mai 2023, deux drones ukrainiens avaient atteint le toit du Kremlin, au c\u0153ur de Moscou, avant d\u2019\u00eatre abattus par les d\u00e9fenses russes.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Selon les donn\u00e9es d\u2019ACLED, on recense plus de 25 000 frappes ukrainiennes en territoire russe depuis f\u00e9vrier 2022, la majeure partie correspondant \u00e0 des drones de courte et moyenne port\u00e9e visant les oblasts russes frontaliers&#160;: Belgorod, Koursk, Briansk et, dans une moindre mesure, Rostov et Voronej.<\/li>\n\n\n\n<li>Moscou et sa m\u00e9tropole ont \u00e9t\u00e9 vis\u00e9es \u00e0 plus de 80 reprises, Saint-P\u00e9tersbourg 4 fois. Les villes de Kazan, Samara, Volgograd ou encore Krasnodar ont \u00e9galement \u00e9t\u00e9 cibl\u00e9es.\u00a0<\/li>\n<\/ul>\n\n\n\n<p>La potentielle livraison par Washington de missiles Tomahawk placerait la capitale russe ainsi que Saint-P\u00e9tersbourg \u00e0 port\u00e9e de Kiev, les deux villes se situant respectivement \u00e0 500 et 850 kilom\u00e8tres des fronti\u00e8res de l\u2019Ukraine. Dans l\u2019attente d\u2019une d\u00e9cision am\u00e9ricaine, Kiev aurait lanc\u00e9 en novembre la production de masse de missiles balistiques de conception ukrainienne Hrim-2, dont la port\u00e9e maximale pourrait atteindre 500 kilom\u00e8tres.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La Russie esp\u00e8re certainement pouvoir dissuader la Maison-Blanche d\u2019autoriser la vente de nouveaux syst\u00e8mes offensifs, qui pourraient inclure des missiles de croisi\u00e8re Tomahawk (d\u2019une port\u00e9e de 1 600 km) ou bien ATACMS (300 km).<\/li>\n\n\n\n<li>Vladimir Poutine avait menac\u00e9 les soutiens de l\u2019Ukraine de \u00ab&#160;lourdes cons\u00e9quences&#160;\u00bb lors de pr\u00e9c\u00e9dentes annonces de livraisons de chars am\u00e9ricains Abrams, britanniques Challenger et allemands L\u00e9opards en 2023.<\/li>\n\n\n\n<li>Le pr\u00e9sident russe avait laiss\u00e9 entendre qu\u2019il pourrait consid\u00e9rer cette assistance comme relevant d\u2019une \u00ab&#160;cobellig\u00e9rance&#160;\u00bb. Il n\u2019a toutefois jamais mis ses menaces \u00e0 ex\u00e9cution, bien qu\u2019il ait <a href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/11\/19\/nucleaire-russe-que-change-la-nouvelle-doctrine-poutine\/\">r\u00e9vis\u00e9 la doctrine russe<\/a> en mati\u00e8re d\u2019utilisation de son arsenal atomique en novembre.<\/li>\n\n\n\n<li>Ces menaces semblent toutefois avoir contribu\u00e9 \u00e0 dissuader l\u2019Allemagne de livrer des missiles Taurus \u00e0 l\u2019Ukraine. En avril, la porte-parole du minist\u00e8re des Affaires \u00e9trang\u00e8res russe avait d\u00e9clar\u00e9 que Moscou consid\u00e9rerait des frappes par l\u2019Ukraine de ces missiles en territoire russe comme une implication \u00ab&#160;directe&#160;\u00bb de Berlin.<\/li>\n\n\n\n<li>Si Friedrich Merz avait d\u00e9clar\u00e9 <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/01\/24\/leurope-apres-donald-trump-selon-friedrich-merz\/\">\u00eatre favorable \u00e0 la livraison de Taurus<\/a> \u2014 un sujet tabou pour le pr\u00e9c\u00e9dent gouvernement Scholz \u2014, le ministre de la D\u00e9fense allemand Pistorius a toutefois indiqu\u00e9 dans une interview donn\u00e9e le 13 juillet que Berlin ne livrerait pas ces missiles \u00e0 Kiev.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Le Kremlin a minimis\u00e9 l\u2019importance des fuites de la conversation entre Trump et Zelensky du 4 juillet, au cours de laquelle le pr\u00e9sident am\u00e9ricain aurait demand\u00e9 si Kiev pouvait \u00ab&#160;&#160;frapper Moscou&#160;&#160;\u00bb.<\/p>\n<p>La potentielle livraison par Washington de missiles Tomahawk placerait la capitale russe ainsi que Saint-P\u00e9tersbourg \u00e0 port\u00e9e de Kiev, les deux villes se situant respectivement \u00e0 500 et 850 kilom\u00e8tres des fronti\u00e8res de l\u2019Ukraine.<\/p>\n","protected":false},"author":2622,"featured_media":287782,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":4,"footnotes":""},"categories":[3116],"tags":[],"staff":[],"editorial_format":[4942],"serie":[],"audience":[],"geo":[1917],"class_list":["post-287779","post","type-post","status-publish","format-standard","hentry","category-la-guerre-en-ukraine-au-jour-le-jour","editorial_format-actu-breves","geo-europe"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":287782,"excerpt":"Le Kremlin a minimis\u00e9 l\u2019importance des fuites de la conversation entre Trump et Zelensky du 4 juillet, au cours de laquelle le pr\u00e9sident am\u00e9ricain aurait demand\u00e9 si Kiev pouvait \u00abfrapper Moscou\u00bb.\r\n\r\nLa potentielle livraison par Washington de missiles Tomahawk placerait la capitale russe ainsi que Saint-P\u00e9tersbourg \u00e0 port\u00e9e de Kiev, les deux villes se situant respectivement \u00e0 500 et 850 kilom\u00e8tres des fronti\u00e8res de l\u2019Ukraine.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump va-t-il livrer des armes \u00e0 Kiev capables d&#039;atteindre Moscou ?<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/16\/les-nouvelles-livraisons-darmes-a-lukraine-pourraient-elles-inclure-des-missiles-de-croisiere-susceptibles-datteindre-moscou\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump va-t-il livrer des armes \u00e0 Kiev capables d&#039;atteindre Moscou ?\" \/>\n<meta property=\"og:description\" content=\"Le Kremlin a minimis\u00e9 l\u2019importance des fuites de la conversation entre Trump et Zelensky du 4 juillet, au cours de laquelle le pr\u00e9sident am\u00e9ricain aurait demand\u00e9 si Kiev pouvait \u00ab&#160;frapper Moscou&#160;\u00bb.  La potentielle livraison par Washington de missiles Tomahawk placerait la capitale russe ainsi que Saint-P\u00e9tersbourg \u00e0 port\u00e9e de Kiev, les deux villes se situant respectivement \u00e0 500 et 850 kilom\u00e8tres des fronti\u00e8res de l\u2019Ukraine.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/16\/les-nouvelles-livraisons-darmes-a-lukraine-pourraient-elles-inclure-des-missiles-de-croisiere-susceptibles-datteindre-moscou\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-16T13:08:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-16T13:08:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/gc-share-trump-tomahawk-ukraine.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1906\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marin Saillofest\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/gc-share-trump-tomahawk-ukraine.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marin Saillofest\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/16\/les-nouvelles-livraisons-darmes-a-lukraine-pourraient-elles-inclure-des-missiles-de-croisiere-susceptibles-datteindre-moscou\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/16\/les-nouvelles-livraisons-darmes-a-lukraine-pourraient-elles-inclure-des-missiles-de-croisiere-susceptibles-datteindre-moscou\/\",\"name\":\"Trump va-t-il livrer des armes \u00e0 Kiev capables d'atteindre Moscou ?\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/16\/les-nouvelles-livraisons-darmes-a-lukraine-pourraient-elles-inclure-des-missiles-de-croisiere-susceptibles-datteindre-moscou\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/16\/les-nouvelles-livraisons-darmes-a-lukraine-pourraient-elles-inclure-des-missiles-de-croisiere-susceptibles-datteindre-moscou\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/gc-trump-tomahawk-ukraine.jpg\",\"datePublished\":\"2025-07-16T13:08:39+00:00\",\"dateModified\":\"2025-07-16T13:08:42+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/16\/les-nouvelles-livraisons-darmes-a-lukraine-pourraient-elles-inclure-des-missiles-de-croisiere-susceptibles-datteindre-moscou\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/16\/les-nouvelles-livraisons-darmes-a-lukraine-pourraient-elles-inclure-des-missiles-de-croisiere-susceptibles-datteindre-moscou\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/16\/les-nouvelles-livraisons-darmes-a-lukraine-pourraient-elles-inclure-des-missiles-de-croisiere-susceptibles-datteindre-moscou\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/gc-trump-tomahawk-ukraine.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/gc-trump-tomahawk-ukraine.jpg\",\"width\":1896,\"height\":1054,\"caption\":\"Screenshot\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/16\/les-nouvelles-livraisons-darmes-a-lukraine-pourraient-elles-inclure-des-missiles-de-croisiere-susceptibles-datteindre-moscou\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les nouvelles livraisons d\u2019armes \u00e0 l\u2019Ukraine pourraient-elles inclure des missiles de croisi\u00e8re susceptibles d\u2019atteindre Moscou&#160;?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833\",\"name\":\"Marin Saillofest\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g\",\"caption\":\"Marin Saillofest\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump va-t-il livrer des armes \u00e0 Kiev capables d'atteindre Moscou ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/16\/les-nouvelles-livraisons-darmes-a-lukraine-pourraient-elles-inclure-des-missiles-de-croisiere-susceptibles-datteindre-moscou\/","og_locale":"fr_FR","og_type":"article","og_title":"Trump va-t-il livrer des armes \u00e0 Kiev capables d'atteindre Moscou ?","og_description":"Le Kremlin a minimis\u00e9 l\u2019importance des fuites de la conversation entre Trump et Zelensky du 4 juillet, au cours de laquelle le pr\u00e9sident am\u00e9ricain aurait demand\u00e9 si Kiev pouvait \u00ab&#160;frapper Moscou&#160;\u00bb.  La potentielle livraison par Washington de missiles Tomahawk placerait la capitale russe ainsi que Saint-P\u00e9tersbourg \u00e0 port\u00e9e de Kiev, les deux villes se situant respectivement \u00e0 500 et 850 kilom\u00e8tres des fronti\u00e8res de l\u2019Ukraine.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/16\/les-nouvelles-livraisons-darmes-a-lukraine-pourraient-elles-inclure-des-missiles-de-croisiere-susceptibles-datteindre-moscou\/","og_site_name":"Le Grand Continent","article_published_time":"2025-07-16T13:08:39+00:00","article_modified_time":"2025-07-16T13:08:42+00:00","og_image":[{"width":1906,"height":1066,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/gc-share-trump-tomahawk-ukraine.jpg","type":"image\/jpeg"}],"author":"Marin Saillofest","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/gc-share-trump-tomahawk-ukraine.jpg","twitter_misc":{"\u00c9crit par":"Marin Saillofest","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/16\/les-nouvelles-livraisons-darmes-a-lukraine-pourraient-elles-inclure-des-missiles-de-croisiere-susceptibles-datteindre-moscou\/","url":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/16\/les-nouvelles-livraisons-darmes-a-lukraine-pourraient-elles-inclure-des-missiles-de-croisiere-susceptibles-datteindre-moscou\/","name":"Trump va-t-il livrer des armes \u00e0 Kiev capables d'atteindre Moscou ?","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/16\/les-nouvelles-livraisons-darmes-a-lukraine-pourraient-elles-inclure-des-missiles-de-croisiere-susceptibles-datteindre-moscou\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/16\/les-nouvelles-livraisons-darmes-a-lukraine-pourraient-elles-inclure-des-missiles-de-croisiere-susceptibles-datteindre-moscou\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/gc-trump-tomahawk-ukraine.jpg","datePublished":"2025-07-16T13:08:39+00:00","dateModified":"2025-07-16T13:08:42+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/16\/les-nouvelles-livraisons-darmes-a-lukraine-pourraient-elles-inclure-des-missiles-de-croisiere-susceptibles-datteindre-moscou\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2025\/07\/16\/les-nouvelles-livraisons-darmes-a-lukraine-pourraient-elles-inclure-des-missiles-de-croisiere-susceptibles-datteindre-moscou\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/16\/les-nouvelles-livraisons-darmes-a-lukraine-pourraient-elles-inclure-des-missiles-de-croisiere-susceptibles-datteindre-moscou\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/gc-trump-tomahawk-ukraine.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/gc-trump-tomahawk-ukraine.jpg","width":1896,"height":1054,"caption":"Screenshot"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/16\/les-nouvelles-livraisons-darmes-a-lukraine-pourraient-elles-inclure-des-missiles-de-croisiere-susceptibles-datteindre-moscou\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Les nouvelles livraisons d\u2019armes \u00e0 l\u2019Ukraine pourraient-elles inclure des missiles de croisi\u00e8re susceptibles d\u2019atteindre Moscou&#160;?"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833","name":"Marin Saillofest","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g","caption":"Marin Saillofest"}}]}},"lgc_categories":[{"id":3116,"name":"La guerre en Ukraine au jour le jour","slug":"la-guerre-en-ukraine-au-jour-le-jour"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/gc-trump-tomahawk-ukraine.jpg","width":1896,"height":1054,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/287779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/2622"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=287779"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/287779\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/287782"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=287779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=287779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=287779"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=287779"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=287779"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=287779"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=287779"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=287779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}