{"id":287209,"date":"2025-07-11T14:20:19","date_gmt":"2025-07-11T12:20:19","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=287209"},"modified":"2025-07-11T14:31:40","modified_gmt":"2025-07-11T12:31:40","slug":"sur-terre-larmee-ukrainienne-se-robotise-pour-compenser-son-desavantage-numerique","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/11\/sur-terre-larmee-ukrainienne-se-robotise-pour-compenser-son-desavantage-numerique\/","title":{"rendered":"Sur terre, l\u2019arm\u00e9e ukrainienne se robotise pour compenser son d\u00e9savantage num\u00e9rique"},"content":{"rendered":"\n<p>Depuis 2022, la Russie et l\u2019Ukraine se sont engag\u00e9es dans une course \u00e0 l\u2019innovation particuli\u00e8rement visible dans le domaine des syst\u00e8mes sans pilotes. Les drones sont ainsi devenus en l\u2019espace de trois ans, dans les airs comme en mer, un \u00e9l\u00e9ment central dans les tactiques de combat des deux arm\u00e9es. Sur terre, ces syst\u00e8mes demeurent toutefois rarement utilis\u00e9s.<\/p>\n\n\n\n<p>Cette situation pourrait n\u00e9anmoins \u00e9voluer au cours des prochains mois, alors que l\u2019arm\u00e9e ukrainienne vient de mener son deuxi\u00e8me assaut enti\u00e8rement robotis\u00e9.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Les premi\u00e8res apparitions de v\u00e9hicules terrestres sans pilotes sur les champs de bataille remontent au moins \u00e0 la Premi\u00e8re Guerre mondiale, avec les robots \u00e9lectriques fran\u00e7ais t\u00e9l\u00e9op\u00e9r\u00e9s Torpille Gabet &amp; Aubriot.<\/li>\n\n\n\n<li>Dans les d\u00e9cennies 1930-1940, l\u2019arm\u00e9e sovi\u00e9tique a test\u00e9 le d\u00e9ploiement au combat de \u00ab&#160;Teletanks&#160;\u00bb&#160;: des engins blind\u00e9s sans pilotes \u00e9quip\u00e9s de mitrailleuses et de lance-flammes, qui ont notamment \u00e9t\u00e9 utilis\u00e9s durant la guerre d&rsquo;Hiver de 1939-1940.<\/li>\n\n\n\n<li>Ces engins terrestres ont toutefois \u00e9t\u00e9 largement d\u00e9laiss\u00e9s au cours des d\u00e9cennies suivantes, les technologies permettant \u00e0 des robots de se d\u00e9placer au sol sur des terrains accident\u00e9s \u00e9tant trop peu fiables pour justifier des investissements&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-287209' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/07\/11\/sur-terre-larmee-ukrainienne-se-robotise-pour-compenser-son-desavantage-numerique\/#easy-footnote-bottom-1-287209' title='\u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.economist.com\/the-economist-explains\/2024\/04\/19\/the-growing-role-of-fighting-robots-on-the-ground-in-ukraine&quot;&gt;The growing role of fighting robots on the ground in Ukraine&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;The Economist&lt;\/em&gt;, 19 avril 2024.'><sup>1<\/sup><\/a><\/span><\/span>.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/8Q91F\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Souffrant d\u2019un rapport de force d\u00e9favorable sur le front, l\u2019arm\u00e9e ukrainienne a d\u00e9velopp\u00e9 plusieurs dizaines de syst\u00e8mes terrestres autonomes depuis 2022&#160;: des robots d\u00e9mineurs ou poseurs de mines (comme le \u0422\u0430rgan), de transport de mat\u00e9riel (TermIT), d\u2019\u00e9vacuation de bless\u00e9s (Veprik), mais \u00e9galement des mod\u00e8les dot\u00e9s de capacit\u00e9s d\u2019attaque comme le drone suicide Ratel S ou l\u2019Ironclad, un robot \u00e0 quatre roues dot\u00e9 d\u2019une tourelle t\u00e9l\u00e9command\u00e9e qui peut \u00eatre \u00e9quip\u00e9e d\u2019une mitrailleuse ou d\u2019un lance-grenades.<\/p>\n\n\n\n\n<div class=\"double-picture my-12 lg:my-20\" \n    data-images-sizes=\"half\"\n    data-same-height=\"true\"\n    data-reference-image=\"left\"\n>    <!-- Images -->\n    <div class=\"lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-1\/2\">\n                            <a \n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/06-scaled-1.png\" \n                    class=\"gallery-item no-underline  \" \n                    data-pswp-width=\"2048\" \n                    data-pswp-height=\"1292\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/06-scaled-1.png\" alt=\"De gauche \u00e0 droite : Targan, TermIT, Ardal.\" >\n                        <\/picture>\n                        <figcaption class=\"lg:hidden pswp-caption-content\">De gauche \u00e0 droite&#160;: Targan, TermIT, Ardal.<\/figcaption>                    <\/figure>\n                <\/a>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-1\/2\">\n                            <a\n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/03-scaled-1.png\" \n                    class=\"gallery-item no-underline  lg:!absolute lg:h-full lg:right-0 lg:left-2 overflow-hidden\" \n                    data-pswp-width=\"2048\" \n                    data-pswp-height=\"1363\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/03-scaled-1.png\" alt=\"Robot d'attaque Lyut.\u00a9 \u0410\u0440\u0442\u0435\u043c\u0430 \u0413\u0432\u043e\u0437\u0434\u043a\u043e\u0432\u0430, 1 \u0446\u0435\u043d\u0442\u0440 \u0456\u043d\u0444\u043e\u0440\u043c\u0430\u0446\u0456\u0439\u043d\u043e-\u043a\u043e\u043c\u0443\u043d\u0456\u043a\u0430\u0446\u0456\u0439\u043d\u043e\u0457 \u043f\u0456\u0434\u0442\u0440\u0438\u043c\u043a\u0438 \u0421\u0443\u0445\u043e\u043f\u0443\u0442\u043d\u0438\u0445 \u0432\u0456\u0439\u0441\u044c\u043a\" class=\"lg:!h-full object-cover\">\n                        <\/picture>\n                        <figcaption class=\"lg:hidden pswp-caption-content\">Robot d&rsquo;attaque Lyut.<br><br>\u00a9 \u0410\u0440\u0442\u0435\u043c\u0430 \u0413\u0432\u043e\u0437\u0434\u043a\u043e\u0432\u0430, 1 \u0446\u0435\u043d\u0442\u0440 \u0456\u043d\u0444\u043e\u0440\u043c\u0430\u0446\u0456\u0439\u043d\u043e-\u043a\u043e\u043c\u0443\u043d\u0456\u043a\u0430\u0446\u0456\u0439\u043d\u043e\u0457 \u043f\u0456\u0434\u0442\u0440\u0438\u043c\u043a\u0438 \u0421\u0443\u0445\u043e\u043f\u0443\u0442\u043d\u0438\u0445 \u0432\u0456\u0439\u0441\u044c\u043a<\/figcaption>                    <\/figure>\n                <\/a>\n                    <\/div>\n    <\/div>\n    <!-- Captions -->\n    <div class=\"hidden lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-1\/2\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">\n                    <figcaption>De gauche \u00e0 droite&#160;: Targan, TermIT, Ardal.<\/figcaption>                <\/figure>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-1\/2\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">   \n                    <figcaption>Robot d&rsquo;attaque Lyut.<br><br>\u00a9 \u0410\u0440\u0442\u0435\u043c\u0430 \u0413\u0432\u043e\u0437\u0434\u043a\u043e\u0432\u0430, 1 \u0446\u0435\u043d\u0442\u0440 \u0456\u043d\u0444\u043e\u0440\u043c\u0430\u0446\u0456\u0439\u043d\u043e-\u043a\u043e\u043c\u0443\u043d\u0456\u043a\u0430\u0446\u0456\u0439\u043d\u043e\u0457 \u043f\u0456\u0434\u0442\u0440\u0438\u043c\u043a\u0438 \u0421\u0443\u0445\u043e\u043f\u0443\u0442\u043d\u0438\u0445 \u0432\u0456\u0439\u0441\u044c\u043a<\/figcaption>                <\/figure>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En d\u00e9cembre 2024, l\u2019arm\u00e9e ukrainienne menait avec succ\u00e8s son premier assaut enti\u00e8rement robotis\u00e9 autour de Lyptsi, dans le ra\u00efon de Kharkiv.<\/li>\n\n\n\n<li>L\u2019op\u00e9ration avait impliqu\u00e9 des dizaines de drones terrestres \u00e9quip\u00e9s de mitrailleuses ainsi que des drones kamikazes terrestres, mais \u00e9galement des drones FPV et des h\u00e9licopt\u00e8res multirotors t\u00e9l\u00e9op\u00e9r\u00e9s&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-287209' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/07\/11\/sur-terre-larmee-ukrainienne-se-robotise-pour-compenser-son-desavantage-numerique\/#easy-footnote-bottom-2-287209' title='\u00ab&amp;#160;&lt;a href=&quot;https:\/\/armyinform.com.ua\/2024\/12\/20\/psyhichna-ataka-droyidiv-na-harkivshhyni-v-ataku-pishla-rota-ukrayinskyh-robotiv\/&quot;&gt;\u041f\u0441\u0438\u0445\u0456\u0447\u043d\u0430 \u0430\u0442\u0430\u043a\u0430 \u0434\u0440\u043e\u0457\u0434\u0456\u0432&amp;#160;: \u043d\u0430 \u0425\u0430\u0440\u043a\u0456\u0432\u0449\u0438\u043d\u0456 \u0432 \u0430\u0442\u0430\u043a\u0443 \u043f\u0456\u0448\u043b\u0430 \u0440\u043e\u0442\u0430 \u0443\u043a\u0440\u0430\u0457\u043d\u0441\u044c\u043a\u0438\u0445 \u0440\u043e\u0431\u043e\u0442\u0456\u0432&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;ArmyInform&lt;\/em&gt;, 20 d\u00e9cembre 2024.'><sup>2<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>Mercredi 9 juillet, la 3e brigade d&rsquo;assaut de Kiev a publi\u00e9 une vid\u00e9o montrant une nouvelle attaque enti\u00e8rement robotis\u00e9e sur des positions russes, l\u00e0 encore dans la r\u00e9gion de Kharkiv.<\/li>\n\n\n\n<li>On peut notamment y voir des complexes robotis\u00e9s terrestre kamikaze (<em>\u041d\u0420\u041a-\u043a\u0430\u043c\u0456\u043a\u0430\u0434\u0437\u0435<\/em>) exploser pr\u00e8s de tranch\u00e9es et fortifications russes, ainsi que des combattants russes se rendant \u00e0 des drones FPV ukrainiens&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-287209' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/07\/11\/sur-terre-larmee-ukrainienne-se-robotise-pour-compenser-son-desavantage-numerique\/#easy-footnote-bottom-3-287209' title='&lt;a href=&quot;https:\/\/www.facebook.com\/watch\/?v=671023495990476&quot;&gt;Vid\u00e9o publi\u00e9e sur Facebook par 3 \u043e\u043a\u0440\u0435\u043c\u0430 \u0448\u0442\u0443\u0440\u043c\u043e\u0432\u0430 \u0431\u0440\u0438\u0433\u0430\u0434\u0430&lt;\/a&gt;, 9 juillet 2025.'><sup>3<\/sup><\/a><\/span><\/span>.<\/li>\n<\/ul>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/r5p2d\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>L\u2019Ukraine veut d\u00e9ployer 15 000 robots terrestres sur le front d\u2019ici la fin de l\u2019ann\u00e9e, ouvrant la perspective d\u2019une multiplication des assauts robotis\u00e9s dans certains secteurs du front&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-287209' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/07\/11\/sur-terre-larmee-ukrainienne-se-robotise-pour-compenser-son-desavantage-numerique\/#easy-footnote-bottom-4-287209' title='Iona Cleave, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.telegraph.co.uk\/world-news\/2025\/04\/22\/ukraine-robot-army-drones-future-warfare-russia\/&quot;&gt;Ukraine\u2019s robot army is a glimpse of future warfare&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;The Telegraph&lt;\/em&gt;, 22 avril 2025.'><sup>4<\/sup><\/a><\/span><\/span>. De son c\u00f4t\u00e9, l\u2019arm\u00e9e russe avait investi avant le lancement de l\u2019invasion de 2022 dans plusieurs syst\u00e8mes comme l\u2019Uran-9 ou le Marker, d\u2019imposants engins dont le co\u00fbt unitaire est toutefois trop \u00e9lev\u00e9 pour \u00eatre d\u00e9ploy\u00e9s en nombre sur le front.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L\u2019arm\u00e9e russe avait n\u00e9anmoins men\u00e9 au moins un assaut robotis\u00e9 en mars 2024 en utilisant des Courier (\u041a\u0443\u0440\u044c\u0435\u0440)&#160;: des robots chenill\u00e9s capables de poser des mines, d\u2019op\u00e9rer une mitrailleuse ou de lancer des grenades&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-287209' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/07\/11\/sur-terre-larmee-ukrainienne-se-robotise-pour-compenser-son-desavantage-numerique\/#easy-footnote-bottom-5-287209' title='\u00ab&amp;#160;&lt;a href=&quot;https:\/\/tass.ru\/ekonomika\/22257529&quot;&gt;\u0412 \u0437\u043e\u043d\u0443 \u0421\u0412\u041e \u043f\u043e\u0441\u0442\u0430\u0432\u0438\u043b\u0438 \u043f\u0435\u0440\u0432\u044b\u0445 \u0440\u043e\u0431\u043e\u0442\u043e\u0432 \u00ab&amp;#160;\u041a\u0443\u0440\u044c\u0435\u0440&amp;#160;\u00bb&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;TACC&lt;\/em&gt;, 29 octobre 2024.'><sup>5<\/sup><\/a><\/span><\/span>.<\/li>\n\n\n\n<li>Leur d\u00e9ploiement semble toutefois limit\u00e9, tandis que l\u2019Ukraine revendique avoir \u00e9quip\u00e9 22 de ses unit\u00e9s de combat avec des syst\u00e8mes robotis\u00e9s terrestres.<\/li>\n\n\n\n<li>La majeure partie de ces robots (47&#160;%) r\u00e9alisent des missions de logistique et d\u2019\u00e9vacuation, tandis que seulement 12&#160;% sont envoy\u00e9s au combat.\u00a0<\/li>\n\n\n\n<li>Contrairement \u00e0 des syst\u00e8mes d\u2019armes utilis\u00e9s \u00e0 grande \u00e9chelle sur le front et pour prot\u00e9ger les villes ukrainiennes comme les Patriot, la quasi-totalit\u00e9 (99&#160;%) de ces robots terrestres sont produits en Ukraine&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-287209' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/07\/11\/sur-terre-larmee-ukrainienne-se-robotise-pour-compenser-son-desavantage-numerique\/#easy-footnote-bottom-6-287209' title='\u00ab&amp;#160;&lt;a href=&quot;https:\/\/armyinform.com.ua\/2025\/07\/11\/zaminyty-pihotu-perspektyvy-nazemnyh-droniv-predstavyly-u-suhoputnyh-vijskah\/&quot;&gt;\u0417\u0430\u043c\u0456\u043d\u0438\u0442\u0438 \u043f\u0456\u0445\u043e\u0442\u0443&amp;#160;: \u043f\u0435\u0440\u0441\u043f\u0435\u043a\u0442\u0438\u0432\u0438 \u043d\u0430\u0437\u0435\u043c\u043d\u0438\u0445 \u0434\u0440\u043e\u043d\u0456\u0432 \u043f\u0440\u0435\u0434\u0441\u0442\u0430\u0432\u0438\u043b\u0438 \u0443 \u0421\u0443\u0445\u043e\u043f\u0443\u0442\u043d\u0438\u0445 \u0432\u0456\u0439\u0441\u044c\u043a\u0430\u0445&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;ArmyInform, &lt;\/em&gt;11 juillet 2025.'><sup>6<\/sup><\/a><\/span><\/span>.<\/li>\n<\/ul>\n\n\n\n<p>Bien qu\u2019il n\u2019existe aucun chiffre officiel r\u00e9cent, on estime que l\u2019arm\u00e9e ukrainienne dispose actuellement d\u2019environ 250 000 hommes d\u00e9ploy\u00e9s sur la ligne de front, contre environ 400 000 pour l\u2019arm\u00e9e russe&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-7-287209' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/07\/11\/sur-terre-larmee-ukrainienne-se-robotise-pour-compenser-son-desavantage-numerique\/#easy-footnote-bottom-7-287209' title='Helene Cooper, \u00ab&amp;#160;&lt;a href=&quot;https:\/\/www.nytimes.com\/2025\/06\/03\/us\/politics\/russia-ukraine-troop-casualties.html&quot;&gt;Troop Casualties in Ukraine War Near 1.4 Million, Study Finds&lt;\/a&gt;&amp;#160;\u00bb, &lt;em&gt;The New York Times&lt;\/em&gt;, 3 juin 2025.'><sup>7<\/sup><\/a><\/span><\/span>. Dans certains secteurs du front, Kiev dispose de trois fois moins de combattants que Moscou.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans certains secteurs du front, des combattants ukrainiens font face \u00e0 trois assaillants russes. Afin de pallier cet \u00e9cart dans le rapport de force, Kiev compte d\u00e9ployer jusqu\u2019\u00e0 15 000 syst\u00e8mes robotiques terrestres d\u2019ici la fin de l\u2019ann\u00e9e, tout en continuant d\u2019investir massivement dans la production domestique de drones a\u00e9riens.<\/p>\n<p>Depuis d\u00e9cembre 2024, deux assauts enti\u00e8rement robotis\u00e9s (sur terre et dans les airs) ont \u00e9t\u00e9 men\u00e9s avec succ\u00e8s par les forces ukrainiennes dans la r\u00e9gion de Kharkiv.<\/p>\n","protected":false},"author":2622,"featured_media":287216,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-briefings.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":4,"footnotes":""},"categories":[3116],"tags":[],"staff":[],"editorial_format":[4942],"serie":[],"audience":[],"geo":[1917],"class_list":["post-287209","post","type-post","status-publish","format-standard","hentry","category-la-guerre-en-ukraine-au-jour-le-jour","editorial_format-actu-breves","geo-europe"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":287216,"excerpt":"Dans certains secteurs du front, des combattants ukrainiens font face \u00e0 trois assaillants russes. Afin de pallier cet \u00e9cart dans le rapport de force, Kiev compte d\u00e9ployer jusqu\u2019\u00e0 15 000 syst\u00e8mes robotiques terrestres d\u2019ici la fin de l\u2019ann\u00e9e, tout en continuant d\u2019investir massivement dans la production domestique de drones a\u00e9riens.\r\n\r\nDepuis d\u00e9cembre 2024, deux assauts enti\u00e8rement robotis\u00e9s (sur terre et dans les airs) ont \u00e9t\u00e9 men\u00e9s avec succ\u00e8s par les forces ukrainiennes dans la r\u00e9gion de Kharkiv.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L\u2019arm\u00e9e ukrainienne se robotise pour pallier son manque de soldats<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/11\/sur-terre-larmee-ukrainienne-se-robotise-pour-compenser-son-desavantage-numerique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019arm\u00e9e ukrainienne se robotise pour pallier son manque de soldats\" \/>\n<meta property=\"og:description\" content=\"Dans certains secteurs du front, des combattants ukrainiens font face \u00e0 trois assaillants russes. Afin de pallier cet \u00e9cart dans le rapport de force, Kiev compte d\u00e9ployer jusqu\u2019\u00e0 15 000 syst\u00e8mes robotiques terrestres d\u2019ici la fin de l\u2019ann\u00e9e, tout en continuant d\u2019investir massivement dans la production domestique de drones a\u00e9riens.  Depuis d\u00e9cembre 2024, deux assauts enti\u00e8rement robotis\u00e9s (sur terre et dans les airs) ont \u00e9t\u00e9 men\u00e9s avec succ\u00e8s par les forces ukrainiennes dans la r\u00e9gion de Kharkiv.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/11\/sur-terre-larmee-ukrainienne-se-robotise-pour-compenser-son-desavantage-numerique\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-11T12:20:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-11T12:31:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/gc-share-robotisation-armee-ukr.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1884\" \/>\n\t<meta property=\"og:image:height\" content=\"1050\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Marin Saillofest\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/gc-share-robotisation-armee-ukr.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marin Saillofest\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/11\/sur-terre-larmee-ukrainienne-se-robotise-pour-compenser-son-desavantage-numerique\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/11\/sur-terre-larmee-ukrainienne-se-robotise-pour-compenser-son-desavantage-numerique\/\",\"name\":\"L\u2019arm\u00e9e ukrainienne se robotise pour pallier son manque de soldats\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/11\/sur-terre-larmee-ukrainienne-se-robotise-pour-compenser-son-desavantage-numerique\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/11\/sur-terre-larmee-ukrainienne-se-robotise-pour-compenser-son-desavantage-numerique\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/gc-robotisation-armee-ukr.png\",\"datePublished\":\"2025-07-11T12:20:19+00:00\",\"dateModified\":\"2025-07-11T12:31:40+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/11\/sur-terre-larmee-ukrainienne-se-robotise-pour-compenser-son-desavantage-numerique\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/11\/sur-terre-larmee-ukrainienne-se-robotise-pour-compenser-son-desavantage-numerique\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/11\/sur-terre-larmee-ukrainienne-se-robotise-pour-compenser-son-desavantage-numerique\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/gc-robotisation-armee-ukr.png\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/gc-robotisation-armee-ukr.png\",\"width\":1870,\"height\":1048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/11\/sur-terre-larmee-ukrainienne-se-robotise-pour-compenser-son-desavantage-numerique\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sur terre, l\u2019arm\u00e9e ukrainienne se robotise pour compenser son d\u00e9savantage num\u00e9rique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833\",\"name\":\"Marin Saillofest\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g\",\"caption\":\"Marin Saillofest\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019arm\u00e9e ukrainienne se robotise pour pallier son manque de soldats","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/11\/sur-terre-larmee-ukrainienne-se-robotise-pour-compenser-son-desavantage-numerique\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019arm\u00e9e ukrainienne se robotise pour pallier son manque de soldats","og_description":"Dans certains secteurs du front, des combattants ukrainiens font face \u00e0 trois assaillants russes. Afin de pallier cet \u00e9cart dans le rapport de force, Kiev compte d\u00e9ployer jusqu\u2019\u00e0 15 000 syst\u00e8mes robotiques terrestres d\u2019ici la fin de l\u2019ann\u00e9e, tout en continuant d\u2019investir massivement dans la production domestique de drones a\u00e9riens.  Depuis d\u00e9cembre 2024, deux assauts enti\u00e8rement robotis\u00e9s (sur terre et dans les airs) ont \u00e9t\u00e9 men\u00e9s avec succ\u00e8s par les forces ukrainiennes dans la r\u00e9gion de Kharkiv.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/11\/sur-terre-larmee-ukrainienne-se-robotise-pour-compenser-son-desavantage-numerique\/","og_site_name":"Le Grand Continent","article_published_time":"2025-07-11T12:20:19+00:00","article_modified_time":"2025-07-11T12:31:40+00:00","og_image":[{"width":1884,"height":1050,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/gc-share-robotisation-armee-ukr.png","type":"image\/png"}],"author":"Marin Saillofest","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/gc-share-robotisation-armee-ukr.png","twitter_misc":{"\u00c9crit par":"Marin Saillofest","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/11\/sur-terre-larmee-ukrainienne-se-robotise-pour-compenser-son-desavantage-numerique\/","url":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/11\/sur-terre-larmee-ukrainienne-se-robotise-pour-compenser-son-desavantage-numerique\/","name":"L\u2019arm\u00e9e ukrainienne se robotise pour pallier son manque de soldats","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/11\/sur-terre-larmee-ukrainienne-se-robotise-pour-compenser-son-desavantage-numerique\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/11\/sur-terre-larmee-ukrainienne-se-robotise-pour-compenser-son-desavantage-numerique\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/gc-robotisation-armee-ukr.png","datePublished":"2025-07-11T12:20:19+00:00","dateModified":"2025-07-11T12:31:40+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/11\/sur-terre-larmee-ukrainienne-se-robotise-pour-compenser-son-desavantage-numerique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2025\/07\/11\/sur-terre-larmee-ukrainienne-se-robotise-pour-compenser-son-desavantage-numerique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/11\/sur-terre-larmee-ukrainienne-se-robotise-pour-compenser-son-desavantage-numerique\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/gc-robotisation-armee-ukr.png","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/gc-robotisation-armee-ukr.png","width":1870,"height":1048},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/07\/11\/sur-terre-larmee-ukrainienne-se-robotise-pour-compenser-son-desavantage-numerique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Sur terre, l\u2019arm\u00e9e ukrainienne se robotise pour compenser son d\u00e9savantage num\u00e9rique"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/e4f85f52220fc7b4cc3cfdb86d88e833","name":"Marin Saillofest","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/87088698b4d967390c49ae6d4f1aa459?s=96&d=mm&r=g","caption":"Marin Saillofest"}}]}},"lgc_categories":[{"id":3116,"name":"La guerre en Ukraine au jour le jour","slug":"la-guerre-en-ukraine-au-jour-le-jour"}],"lgc_author":null,"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/07\/gc-robotisation-armee-ukr.png","width":1870,"height":1048,"alt":""},"feature_image_cover":null,"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/287209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/2622"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=287209"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/287209\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/287216"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=287209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=287209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=287209"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=287209"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=287209"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=287209"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=287209"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=287209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}