{"id":282686,"date":"2025-06-10T17:48:51","date_gmt":"2025-06-10T15:48:51","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=282686"},"modified":"2025-06-11T13:57:09","modified_gmt":"2025-06-11T11:57:09","slug":"gagner-la-guerre-dindependance-numerique-europeenne","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2025\/06\/10\/gagner-la-guerre-dindependance-numerique-europeenne\/","title":{"rendered":"Gagner la guerre d\u2019ind\u00e9pendance num\u00e9rique europ\u00e9enne"},"content":{"rendered":"\n<p class=\"has-drop-cap\">Lors de son discours de r\u00e9ception du prix Charlemagne \u00e0 Aix-la-Chapelle, la pr\u00e9sidente de la Commission europ\u00e9enne, Ursula von der Leyen, a appel\u00e9 de ses v\u0153ux une \u00ab&#160;ind\u00e9pendance europ\u00e9enne&#160;\u00bb. Selon elle, il serait possible de r\u00e9aliser une telle ambition en augmentant les d\u00e9penses de d\u00e9fense, en acc\u00e9l\u00e9rant l&rsquo;int\u00e9gration de l&rsquo;Ukraine dans l&rsquo;Union, en soutenant une capacit\u00e9 d&rsquo;innovation technologique autonome et en renfor\u00e7ant la d\u00e9mocratie. En \u00e9num\u00e9rant ces priorit\u00e9s, la pr\u00e9sidente sugg\u00e8re sans doute qu&rsquo;elles sont intimement li\u00e9es entre elles, comme autant de conditions de la libert\u00e9 des Europ\u00e9ens.<\/p>\n\n\n\n<p>En parall\u00e8le de la diffusion disruptive et transformatrice des technologies num\u00e9riques, un \u00e9cosyst\u00e8me m\u00e9diatique d\u2019un nouveau genre s&rsquo;est en effet d\u00e9velopp\u00e9. S\u2019il alimente un certain d\u00e9veloppement \u00e9conomique et une circulation des connaissances n\u00e9cessaires aux citoyens dans les d\u00e9mocraties, il est aussi devenu l\u2019instrument privil\u00e9gi\u00e9 d\u2019une guerre cognitive.<\/p>\n\n\n\n<p>C\u2019est la raison pour laquelle, sans ind\u00e9pendance num\u00e9rique, il ne pourra pas y avoir d&rsquo;ind\u00e9pendance europ\u00e9enne.<\/p>\n\n\n\n<p>Mais l&rsquo;ind\u00e9pendance num\u00e9rique ne se d\u00e9clare pas.<\/p>\n\n\n\n<p>Elle se con\u00e7oit et se r\u00e9alise avec \u00e9nergie, de mani\u00e8re innovante et pr\u00e9par\u00e9e, au service d\u2019une vision globale.<\/p>\n\n\n\n<p>Elle ne s\u2019atteint pas avec quelques ajustements&#160;: gagner l&rsquo;ind\u00e9pendance num\u00e9rique suppose un nouveau d\u00e9part.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Un imp\u00e9ratif europ\u00e9en&#160;: repenser la politique des plateformes<\/h2>\n\n\n\n<p>En une vingtaine d&rsquo;ann\u00e9es, entre 2007 et 2025, l&rsquo;Europe a accord\u00e9 aux grandes plateformes am\u00e9ricaines un v\u00e9ritable monopole sur les infrastructures num\u00e9riques qui organisent l&rsquo;\u00e9conomie de la connaissance.&nbsp;<\/p>\n\n\n\n<p>Elles b\u00e9n\u00e9ficient d&rsquo;un puissant effet de r\u00e9seau qui les favorise en emp\u00eachant toute concurrence. Elles sont d\u00e9sormais capables de contr\u00f4ler les march\u00e9s sur lesquels elles op\u00e8rent en capturant d&rsquo;\u00e9normes ressources \u00e9conomiques et financi\u00e8res. Dans le m\u00eame temps, elles concentrent une immense quantit\u00e9 de donn\u00e9es sur les personnes, les organisations, leurs relations, leurs comportements, leurs valeurs. Cette manne les rend d&rsquo;autant plus performantes dans l&rsquo;utilisation de grands mod\u00e8les de langage (LLMs) et dans les applications d&rsquo;intelligence artificielle g\u00e9n\u00e9rative.<\/p>\n\n\n\n<p>Mais ce n&rsquo;est pas tout.<\/p>\n\n\n\n<p>L&rsquo;importance \u00e9conomique et technologique des entreprises qui contr\u00f4lent les grandes plateformes se traduit d\u00e9sormais par une prise de pouvoir politique qui ne peut plus \u00eatre ignor\u00e9e \u2014&nbsp;et qui, de relativement occulte, est devenue manifeste avec l\u2019arriv\u00e9e des techno-c\u00e9saristes de la Silicon Valley \u00e0 Washington.<\/p>\n\n\n<section class=\"dive print-block my-16\" style=\"background-color:;\">\n\t<div class=\"wrapper\">\n\t\t<div class=\"container mx-auto \">\n\t\t\t<div class=\"row flex flex-wrap relative pt-6 pb-16 lg:py-8\">\n\t\t\t\t<div class=\"col w-full xl:ml-1\/10\n\t\t\t\t\t md:w-2\/5 xl:w-2\/5 \t\t\t\t\t\">\n\t\t\t\t\t<a href=\"https:\/\/legrandcontinent.eu\/shop\/produit\/empire-de-lombre\/\" style=\"color:#000000;\" class=\"font-display font-normal text-4xl leading-9 mb-5 text-white no-underline\">\n\t\t\t\t\t\tLe coup d&rsquo;\u00c9tat permanent de la Silicon Valley\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<div style=\"color:#000000;\" class=\"text-base leading-none font-sans\">\n\t\t\t\t\t\t\t<p>Sous la direction de Giuliano da Empoli. Postface par Benjam\u00edn Labatut.<\/p>\n<p>Avec les contributions de Daron Acemo\u011flu, Sam Altman, Marc Andreessen, Lorenzo Castellani, Adam Curtis, Mario Draghi, He Jiayan, Marietje Schaake, Vladislav Sourkov, Peter Thiel, Svetlana Tikhanovska\u00efa, Jianwei Xun et Curtis Yarvin.<\/p>\n<p>En librairie ou sur abonnement.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"mt-12 dive-list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a  style=\"color:#dd203c;\" class=\"no-underline block border-t border-grey-darker py-2 flex\"\n\t\t\t\t\t\t\t\t   href=\"https:\/\/legrandcontinent.eu\/shop\/produit\/empire-de-lombre\/\"><span class=\"font-sans font-semibold pr-4\">\u2192<\/span> Commandez le num\u00e9ro<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a  style=\"color:#dd203c;\" class=\"no-underline block border-t border-grey-darker py-2 flex\"\n\t\t\t\t\t\t\t\t   href=\"https:\/\/legrandcontinent.eu\/fr\/offre-legc\/\"><span class=\"font-sans font-semibold pr-4\">\u2192<\/span> D\u00e9couvrez toutes nos offres<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div style=\"color:#000000;\" class=\"dive-footer font-sans text-xs border-t border-grey-darker py-2 leading-4\">\n\t\t\t\t\t\t\t<p><strong><a href=\"https:\/\/legrandcontinent.eu\/shop\/produit\/empire-de-lombre\/\"><span style=\"text-decoration: underline\">Commandez le nouveau num\u00e9ro papier<\/span><\/a> du Grand Continent chez Gallimard ou <span style=\"text-decoration: underline\"><a href=\"https:\/\/legrandcontinent.eu\/fr\/offre-legc\/\">cliquez ici pour vous abonner et recevoir l\u2019int\u00e9gralit\u00e9 de nos produits<\/a><\/span>.<\/strong><\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"col w-full md:w-3\/5 xl:w-2\/5  md:px-0 relative overflow-hidden mt-8 md:mt-0 macron-img\">\n\t\t\t\t\t\t\t\t<a class=\"!absolute !bg-none w-full h-full pin-t pin-l\" href=\"https:\/\/legrandcontinent.eu\/shop\/produit\/empire-de-lombre\/\" class=\"no-underline\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" style=\"object-fit: contain; width: 100%; height: 100%;\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/04\/mediamodifier_image-15-990x660.png\" \/>\n\t\t\t\t\t\t\t\t<\/a> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n<p>Certes, l&rsquo;Europe a depuis quelques ann\u00e9es fait \u00e9voluer son cadre r\u00e9glementaire en introduisant des r\u00e9formes profondes qui imposent aux grandes plateformes \u2014 dites \u00ab&#160;<em>gatekeepers<\/em>&#160;\u00bb \u2014 de prendre leurs responsabilit\u00e9s sur un certain nombre de fronts importants concernant le respect des droits humains, la pr\u00e9servation de la comp\u00e9titivit\u00e9 des march\u00e9s, l&rsquo;\u00e9quit\u00e9 des \u00e9changes d&rsquo;informations et le respect des droits d&rsquo;auteur.&nbsp;<\/p>\n\n\n\n<p>Cette production normative europ\u00e9enne a d\u00e9but\u00e9 avec le r\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es (RGPD) et s&rsquo;est ensuite d\u00e9velopp\u00e9e avec la loi sur les services num\u00e9riques (DSA), la loi sur les march\u00e9s num\u00e9riques (DMA) et <a href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/01\/05\/les-modeles-les-plus-avances-dia-font-peser-un-risque-systemique-une-conversation-avec-brando-benifei-sur-lai-act\/\">l&rsquo;AI Act<\/a>.<\/p>\n\n\n\n<p>L&rsquo;Union a \u00e9galement investi des dizaines de milliards dans la recherche et les infrastructures destin\u00e9es \u00e0 rattraper notre retard en mati\u00e8re d&rsquo;intelligence artificielle. Elle a \u00e9galement lanc\u00e9 une discussion sur l&rsquo;ensemble de la cha\u00eene de valeur de l\u2019industrie num\u00e9rique \u2014 de la production de puces \u00e0 la relance des entreprises de t\u00e9l\u00e9communications et de la fabrication de produits \u00e9lectroniques.<\/p>\n\n\n\n<p>Mais malgr\u00e9 ces efforts, l&rsquo;Union n&rsquo;a pas encore \u00e9labor\u00e9 de strat\u00e9gie pour s&rsquo;attaquer au c\u0153ur du probl\u00e8me pos\u00e9 par les plateformes&#160;: leur pouvoir semble d\u00e9pourvu de contrepoids r\u00e9els.&nbsp;<\/p>\n\n\n\n<p>Cette toute-puissance a bien entendu des cons\u00e9quences profondes sur les personnes qui les utilisent mais \u00e9galement sur les march\u00e9s sur lesquels elles op\u00e8rent et sur les \u00c9tats qui tentent de les r\u00e9glementer. En effet s&rsquo;il est possible, en th\u00e9orie, d\u2019intervenir sur le comportement des plateformes existantes, leur puissance est aujourd&rsquo;hui telle que de nombreuses mesures prises \u00e0 leur encontre s&rsquo;av\u00e8rent parfaitement inefficaces.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>L&rsquo;Union n&rsquo;a pas encore \u00e9labor\u00e9 de strat\u00e9gie pour s&rsquo;attaquer au c\u0153ur du probl\u00e8me pos\u00e9 par les plateformes&#160;: leur pouvoir semble d\u00e9pourvu de contrepoids r\u00e9els.&nbsp;<\/p><cite>Luca de Biase<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Il est donc clair que la meilleure fa\u00e7on de limiter le pouvoir des <em>Big Tech<\/em> serait de cr\u00e9er en Europe des plateformes alternatives et sup\u00e9rieures \u00e0 celles qui existent d\u00e9j\u00e0. Sur ces nouvelles plateformes, le public pourrait trouver des services de qualit\u00e9, respectueux des droits humains, mieux adapt\u00e9s \u00e0 la d\u00e9fense et \u00e0 la valorisation du mode de vie, de production, de consommation et de d\u00e9bat des Europ\u00e9ens.<\/p>\n\n\n\n<p>\u00c0 premi\u00e8re vue, une telle cr\u00e9ation <em>ex novo<\/em> semble tr\u00e8s difficile, voire impossible \u2014 pr\u00e9cis\u00e9ment pour la raison m\u00eame qui nous incite \u00e0 r\u00e9fl\u00e9chir \u00e0 leur \u00e9mergence&#160;: le pouvoir des plateformes existantes.&nbsp;<\/p>\n\n\n\n<p>Pourtant, Internet est peut-\u00eatre encore l&rsquo;un des rares domaines o\u00f9 il n&rsquo;est jamais tr\u00e8s avis\u00e9 de sous-estimer notre capacit\u00e9 de disrupter un syst\u00e8me.<\/p>\n\n\n\n<p>Cet article examine les possibilit\u00e9s de d\u00e9velopper des plateformes num\u00e9riques europ\u00e9ennes innovantes et susceptibles de restaurer un \u00e9cosyst\u00e8me m\u00e9diatique sain en amor\u00e7ant une phase d&rsquo;\u00e9volution vers un mieux-\u00eatre culturel, technologique, \u00e9conomique, politique, social et d\u00e9mocratique<\/p>\n\n\n\n<p>Une bonne m\u00e9thode peut \u00eatre de partir des d\u00e9fauts des plateformes existantes tels qu\u2019ils sont ressentis et v\u00e9cus par les utilisateurs. Ces failles peuvent servir de base \u00e0 la cr\u00e9ation de solutions alternatives qui en seraient purg\u00e9es.<\/p>\n\n\n\n<p>La premi\u00e8re \u00e9tape, pour explorer ces possibilit\u00e9s, serait de r\u00e9introduire une v\u00e9ritable concurrence dans le domaine du num\u00e9rique en Europe.<\/p>\n\n\n\n\n<div class=\"double-picture my-12 lg:my-20\" \n    data-images-sizes=\"smallsx\"\n    data-same-height=\"true\"\n    data-reference-image=\"left\"\n>    <!-- Images -->\n    <div class=\"lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-1\/3\">\n                            <a \n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/06\/SIPA_rex40331973_000016-scaled.jpg\" \n                    class=\"gallery-item no-underline  \" \n                    data-pswp-width=\"2058\" \n                    data-pswp-height=\"2560\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/06\/SIPA_rex40331973_000016-scaled.jpg\" alt=\"\" >\n                        <\/picture>\n                                            <\/figure>\n                <\/a>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-2\/3\">\n                            <a\n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/06\/SIPA_rex40331973_000022-scaled.jpg\" \n                    class=\"gallery-item no-underline  lg:!absolute lg:h-full lg:right-0 lg:left-2 overflow-hidden\" \n                    data-pswp-width=\"2560\" \n                    data-pswp-height=\"2041\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/06\/SIPA_rex40331973_000022-scaled.jpg\" alt=\"\" class=\"lg:!h-full object-cover\">\n                        <\/picture>\n                                            <\/figure>\n                <\/a>\n                    <\/div>\n    <\/div>\n    <!-- Captions -->\n    <div class=\"hidden lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-1\/3\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">\n                                    <\/figure>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-2\/3\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">   \n                                    <\/figure>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">O\u00f9 en sommes-nous&#160;?<\/h2>\n\n\n\n<p>Il est l\u00e9gitime de se demander si la tenaille monopolistique \u2014 ou, pour \u00eatre plus pr\u00e9cis, oligopolistique (mais les effets sont les m\u00eames) \u2014 <a href=\"https:\/\/legrandcontinent.eu\/fr\/2023\/03\/24\/bifurquer-le-parti-communiste-chinois-et-la-silicon-valley-travaillent-a-un-avenir-posthumain\/\">constitu\u00e9e par les visions dystopiques de la Silicon Valley et du Parti communiste chinois<\/a> dans le domaine des plateformes num\u00e9riques est vraiment appel\u00e9e \u00e0 perdurer pour toujours.&nbsp;<\/p>\n\n\n\n<p>Plusieurs raisons permettent de le croire.<\/p>\n\n\n\n<p>La puissance technologique des plateformes existantes est gigantesque en raison du nombre d&rsquo;utilisateurs et de donn\u00e9es qu&rsquo;elles collectent, mais leur pouvoir vient aussi de la quantit\u00e9 colossale de capitaux dont elles disposent pour d\u00e9velopper leurs strat\u00e9gies.<\/p>\n\n\n\n<p>En face, nous ne disposons pas, en Europe, de ressources comparables. Qui plus est, selon de nombreux observateurs, nous aurions la f\u00e2cheuse manie de nous concentrer davantage sur la r\u00e9gulation que sur l&rsquo;innovation.<\/p>\n\n\n\n<p>Enfin, les sanctions europ\u00e9ennes sont trop lentes \u00e0 \u00eatre mises en place par rapport \u00e0 la vitesse d&rsquo;innovation des plateformes et aux dommages qu&rsquo;elles peuvent causer \u00e0 court terme. La menace du droit europ\u00e9en ne semble donc pas \u00eatre, pour l\u2019instant, une \u00e9p\u00e9e de Damocl\u00e8s particuli\u00e8rement efficace pour modifier les choix strat\u00e9giques des g\u00e9ants du web.<\/p>\n\n\n\n<p>\u00c0 ces consid\u00e9rations s&rsquo;ajoute l&rsquo;absence de sentiment d&rsquo;urgence sur cette question.&nbsp;<\/p>\n\n\n\n<p>Tout se passe en effet comme si les Europ\u00e9ens avaient passivement accept\u00e9 le pr\u00e9jug\u00e9 selon lequel le monopole des plateformes serait le r\u00e9sultat l\u00e9gitime de leur comp\u00e9titivit\u00e9. Ces consid\u00e9rations paraissent toutefois bien faibles d\u00e8s lors qu\u2019on prend conscience que les plateformes sont aujourd\u2019hui bien plus et bien autre chose que de simples services&#160;: ce sont des lieux depuis lesquels s\u2019exercent le pouvoir.<\/p>\n\n\n\n<p>Pourtant, c\u2019est cette concentration massive du pouvoir qui fait que les raisons d&rsquo;esp\u00e9rer pouvoir changer le cours des choses sont aussi nombreuses.<\/p>\n\n\n\n<p>D&rsquo;une part, les plateformes am\u00e9ricaines extraient une part importante de la valeur de l&rsquo;\u00e9conomie europ\u00e9enne sans restituer autant en termes d&rsquo;investissements dans la recherche, les comp\u00e9tences, les recettes fiscales et la disponibilit\u00e9 des donn\u00e9es.<\/p>\n\n\n\n<p>D&rsquo;autre part, la conception des plateformes am\u00e9ricaines est d\u00e9sormais clairement et manifestement associ\u00e9e \u00e0 une d\u00e9t\u00e9rioration du bien-\u00eatre des adolescents et \u00e0 une d\u00e9gradation g\u00e9n\u00e9ralis\u00e9e de la qualit\u00e9 de l&rsquo;information.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Les plateformes sont aujourd\u2019hui bien plus et bien autre chose que de simples services&#160;: ce sont des lieux depuis lesquels s\u2019exercent le pouvoir.<\/p><cite>Luca de Biase<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Enfin, l\u2019influence exerc\u00e9e par des puissances \u00e9trang\u00e8res sur ces plateformes sur lesquelles s&rsquo;effectue une grande partie de la communication des Europ\u00e9ens et qui constituent le th\u00e9\u00e2tre de la guerre cognitive, n&rsquo;est pas compatible avec l&rsquo;ind\u00e9pendance europ\u00e9enne en mati\u00e8re de d\u00e9fense.<\/p>\n\n\n\n<p>C\u2019est pourquoi les raisons qui permettent de penser qu&rsquo;un changement radical est possible sont tout aussi \u00e9videntes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Une voie europ\u00e9enne pour la cr\u00e9ation de plateformes<\/h2>\n\n\n\n<p>Premi\u00e8rement, le paysage g\u00e9opolitique a chang\u00e9.<\/p>\n\n\n\n<p>Alors que les alliances traditionnelles ne sont plus fiables, une ressource strat\u00e9gique telle que l&rsquo;infrastructure num\u00e9rique fait d\u00e9sormais partie int\u00e9grante de toute perspective d&rsquo;ind\u00e9pendance pour un syst\u00e8me politique. Les r\u00e9glementations europ\u00e9ennes ont chang\u00e9 et permettent d&rsquo;ouvrir une nouvelle phase dans la transition num\u00e9rique europ\u00e9enne.<\/p>\n\n\n\n<p>Deuxi\u00e8mement, les Europ\u00e9ens ont l\u2019opportunit\u00e9 de reprendre la main dans la course \u00e0 l\u2019IA.&nbsp;<\/p>\n\n\n\n<p>Pour ce faire, loin de chercher \u00e0 imiter les Am\u00e9ricains, ils devraient s&rsquo;orienter vers des mod\u00e8les fond\u00e9s sur des architectures diff\u00e9rentes \u2014 moins gourmandes en \u00e9nergie et s&rsquo;appuyant sur des connaissances plus fiables, telles que les donn\u00e9es produites en permanence par la robotique industrielle et l&rsquo;industrie manufacturi\u00e8re europ\u00e9enne.<\/p>\n\n\n\n<p>La science europ\u00e9enne est de plus en plus consciente de sa force. Selon les donn\u00e9es de la Fondation Bertelsmann, elle d\u00e9passe la science am\u00e9ricaine en nombre de publications dans un moment o\u00f9 celle-ci est par ailleurs mise en difficult\u00e9 par l\u2019administration Trump.<\/p>\n\n\n\n<p>Un momentum s\u2019ouvre&#160;: la probabilit\u00e9 que les Europ\u00e9ens puissent intervenir pour aider \u00e0 la cr\u00e9ation de plateformes europ\u00e9ennes serait en train d\u2019augmenter.<\/p>\n\n\n\n<p>En effet, alors que les Europ\u00e9ens cherchent \u00e0 devenir autonomes en mati\u00e8re de d\u00e9fense, ils ne peuvent y parvenir sans \u00e9tendre les investissements n\u00e9cessaires aux technologies qui servent \u00e0 d\u00e9fendre la s\u00e9curit\u00e9 des citoyens dans la guerre cognitive.<\/p>\n\n\n\n<p>De m\u00eame, alors qu&rsquo;ils sont amen\u00e9s \u00e0 prendre des d\u00e9cisions fondamentales pour les grands d\u00e9fis du si\u00e8cle \u2014 du climat aux migrations en passant par les in\u00e9galit\u00e9s sociales \u2014 ils ne peuvent d\u00e9lib\u00e9rer d\u00e9mocratiquement en s\u2019appuyant sur des plateformes con\u00e7ues pour un environnement am\u00e9ricain et op\u00e9r\u00e9es depuis les \u00c9tats-Unis.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Alors que les Europ\u00e9ens cherchent \u00e0 devenir autonomes en mati\u00e8re de d\u00e9fense, ils ne peuvent y parvenir sans \u00e9tendre les investissements n\u00e9cessaires aux technologies qui servent \u00e0 d\u00e9fendre la s\u00e9curit\u00e9 des citoyens dans la guerre cognitive.<\/p><cite>Luca de Biase<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Les valeurs europ\u00e9ennes, fond\u00e9es sur des droits humains et assum\u00e9es par l&rsquo;\u00c9tat-providence, de la sant\u00e9 \u00e0 l&rsquo;\u00e9ducation, ne sont pas compatibles avec l&rsquo;hyper-comp\u00e9titivit\u00e9, la manipulation et la <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/02\/05\/trump-destruction-spectaculaire\/\">destruction spectaculaire<\/a> qui pr\u00e9valent sur les r\u00e9seaux sociaux actuels.<\/p>\n\n\n\n<p>La colonisation cognitive que nous avons laiss\u00e9e advenir en c\u00e9dant notre ind\u00e9pendance aux Am\u00e9ricains, avait peut-\u00eatre un sens \u00e0 l&rsquo;\u00e9poque o\u00f9 le leadership culturel \u00e9tait d\u00e9tenu par un pays qui \u00e9tait notre alli\u00e9 strat\u00e9gique et qui partageait nos valeurs d\u00e9mocratiques.&nbsp;<\/p>\n\n\n\n<p>Mais l&rsquo;alliance s&rsquo;est effondr\u00e9e \u2014 et la d\u00e9mocratie en Am\u00e9rique pourrait \u00eatre en train d\u2019exhaler son dernier souffle.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Des propositions concr\u00e8tes<\/h2>\n\n\n\n<p>\u00c0 la suite de l\u2019\u00e9lection de Trump, plusieurs propositions europ\u00e9ennes ont \u00e9merg\u00e9 pour se saisir de cette question.<\/p>\n\n\n\n<p>Le rapport EuroStack&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-1-282686' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/06\/10\/gagner-la-guerre-dindependance-numerique-europeenne\/#easy-footnote-bottom-1-282686' title='&lt;a href=&quot;https:\/\/www.euro-stackreport.info\/&quot;&gt;EuroStack&lt;\/a&gt;, rapport dirig\u00e9 par Francesca Bria, 2025.'><sup>1<\/sup><\/a><\/span><\/span> propose ainsi de lutter contre la d\u00e9pendance technologique en cr\u00e9ant une infrastructure num\u00e9rique souveraine europ\u00e9enne qui permettrait \u00e0 l&rsquo;Europe d&rsquo;\u00eatre autonome tout au long de la cha\u00eene d&rsquo;approvisionnement \u2014 ce qui est, \u00e0 l&rsquo;heure actuelle, loin d&rsquo;\u00eatre une r\u00e9alit\u00e9.<\/p>\n\n\n\n<p>Car il n&rsquo;en a pas toujours \u00e9t\u00e9 ainsi.<\/p>\n\n\n\n<p>Jusqu&rsquo;en 2007, c\u2019est en Europe qu\u2019\u00e9taient produits la plupart des appareils num\u00e9riques les plus importants au monde&#160;: <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/27\/reindustrialiser-leurope-un-nouveau-logiciel\/\">les t\u00e9l\u00e9phones portables<\/a>.<\/p>\n\n\n\n<p>Ce sont les Europ\u00e9ens qui \u00e9taient alors le plus strat\u00e9giquement positionn\u00e9s dans toute la cha\u00eene d&rsquo;approvisionnement \u2014 des composants \u00e9lectroniques pour les communications mobiles aux technologies de r\u00e9seau, en passant par les logiciels d&rsquo;exploitation. \u00c0 elle seule, l&rsquo;entreprise Nokia avait atteint une part de march\u00e9 mondial de 41&#160;% des t\u00e9l\u00e9phones portables. Ericsson, Alcatel et Siemens compl\u00e9taient la domination europ\u00e9enne dans ce secteur.<\/p>\n\n\n\n<p>Cet exemple montre bien que sur le plan technologique, \u00e9conomique et scientifique, l&rsquo;Europe n&rsquo;est pas condamn\u00e9e \u00e0 \u00eatre \u00e0 la tra\u00eene. Mais en termes de pouvoir politique, les <em>Big Tech<\/em> am\u00e9ricaines jouent dans une autre cat\u00e9gorie \u2014 m\u00eame par rapport aux meilleures entreprises europ\u00e9ennes.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Jusqu&rsquo;en 2007, c\u2019est en Europe qu\u2019\u00e9taient produits la plupart des appareils num\u00e9riques les plus importants au monde&#160;: les t\u00e9l\u00e9phones portables.<\/p><cite>Luca de Biase<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Incontestablement, le point le plus fort des \u00c9tats-Unis est la disponibilit\u00e9 de ressources financi\u00e8res pouvant \u00eatre investies pour pr\u00e9server le pouvoir absolu des grandes plateformes.<\/p>\n\n\n\n<p>Il y a au moins deux raisons \u00e0 cela. D\u2019une part, les techno-c\u00e9saristes sont capables de g\u00e9n\u00e9rer des profits colossaux sur les march\u00e9s qu&rsquo;ils contr\u00f4lent. D\u2019autre part, l\u2019argent inject\u00e9 dans l&rsquo;\u00e9conomie am\u00e9ricaine au cours de l&rsquo;assouplissement quantitatif qui a suivi la crise de 2007-2008, puis apr\u00e8s la crise pand\u00e9mique \u2014 estim\u00e9 \u00e0 7 000 milliards de dollars \u2014 est all\u00e9 moins \u00e0 l&rsquo;\u00e9conomie r\u00e9elle qu&rsquo;\u00e0 la finance. La polarisation du march\u00e9 financier a fini par favoriser les grandes entreprises num\u00e9riques dans la course \u00e0 l&rsquo;attraction de ces capitaux importants.&nbsp;<\/p>\n\n\n\n<p>Bien s\u00fbr, nous avions \u00e9galement, en Europe, mis en \u0153uvre des politiques similaires \u00e0 l&rsquo;assouplissement quantitatif. Mais nous ne disposions pas d&rsquo;entreprises aussi habiles pour concentrer les ressources inject\u00e9es dans le syst\u00e8me. Et nous n\u2019avons pas r\u00e9ussi \u00e0 emp\u00eacher qu&rsquo;\u00e0 long terme les capitaux inject\u00e9s ne finissent eux aussi sur le march\u00e9 am\u00e9ricain, <a href=\"https:\/\/multimedia.europarl.europa.eu\/fr\/video\/rapport-draghi-le-parlement-europeen-debat-dun-plan-qui-vise-a-stimuler-leconomie-de-lue_N01_AFPS_240923_DRAG_WEEK38\" target=\"_blank\" rel=\"noreferrer noopener\">comme le montre bien le rapport Draghi<\/a>.<\/p>\n\n\n\n<p>On conna\u00eet d\u00e9sormais les cons\u00e9quences de cette asym\u00e9trie.<\/p>\n\n\n\n<p>Comme le montrent de nombreuses recherches \u2014 de celles consacr\u00e9es \u00e0 la question de la surveillance soulev\u00e9e par Shoshana Zuboff&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-2-282686' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/06\/10\/gagner-la-guerre-dindependance-numerique-europeenne\/#easy-footnote-bottom-2-282686' title='Shoshana Zuboff, &lt;em&gt;The age of surveillance capitalism&amp;#160;: the fight for the future at the new frontier of power&lt;\/em&gt;, Faber and Faber, 2019.'><sup>2<\/sup><\/a><\/span><\/span>, au coup d&rsquo;\u00c9tat num\u00e9rique d\u00e9nonc\u00e9 par Marietje Schaake&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-3-282686' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/06\/10\/gagner-la-guerre-dindependance-numerique-europeenne\/#easy-footnote-bottom-3-282686' title='Marietje Schaake, &lt;em&gt;The Tech Coup. How to Save Democracy from Silicon Valley&lt;\/em&gt;, Princeton University Press, 2024.'><sup>3<\/sup><\/a><\/span><\/span>, en passant par les strat\u00e9gies num\u00e9riques des autocraties reconstitu\u00e9es par Anne Applebaum&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-4-282686' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/06\/10\/gagner-la-guerre-dindependance-numerique-europeenne\/#easy-footnote-bottom-4-282686' title='Anne Applebaum, &lt;em&gt;Autocracy, Inc&amp;#160;: The Dictators Who Want to Run the World&lt;\/em&gt;, Allen Lane, 2024.'><sup>4<\/sup><\/a><\/span><\/span> \u2014 le succ\u00e8s des <em>Big Tech<\/em> s&rsquo;est traduit par un renforcement du pouvoir politique de structures hors de tout contr\u00f4le.<\/p>\n\n\n\n<p>Ce pouvoir redessine les syst\u00e8mes dans lesquels il parvient \u00e0 s&rsquo;imposer avec un projet de compression des droits humains, de limitation de la concurrence par des pratiques monopolistiques, de fragmentation des agr\u00e9gats sociaux et de privatisation de fonctions qui \u00e9taient autrefois la pr\u00e9rogative des \u00c9tats \u2014 du voyage dans l&rsquo;espace \u00e0 l&rsquo;\u00e9mission de la monnaie.<\/p>\n\n\n\n<p>En miroir, l\u2019Union continue de d\u00e9fendre les droits humains, poursuit ses efforts en mati\u00e8re de droit de la concurrence pour limiter les monopoles, croit \u00e0 l&rsquo;\u00c9tat social et, surtout, investit d&rsquo;importantes ressources publiques pour favoriser le d\u00e9veloppement de l&rsquo;\u00e9conomie dans une direction compatible avec les grands objectifs de ses populations.<\/p>\n\n\n\n<p>Comme l\u2019affirment les rapporteurs du <em>European Democracy Shield<\/em>&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-5-282686' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/06\/10\/gagner-la-guerre-dindependance-numerique-europeenne\/#easy-footnote-bottom-5-282686' title='&lt;a href=&quot;https:\/\/www.europarl.europa.eu\/RegData\/etudes\/BRIE\/2024\/767153\/EPRS_BRI(2024)767153_EN.pdf&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Information integrity online and the European democracy shield&lt;\/a&gt;, Parlement europ\u00e9en, D\u00e9cembre 2024.'><sup>5<\/sup><\/a><\/span><\/span>, cette approche est la bonne et doit \u00eatre d\u00e9fendue contre la d\u00e9sinformation et les diff\u00e9rentes formes d&rsquo;ing\u00e9rence \u00e9trang\u00e8re dans l&rsquo;\u00e9cosyst\u00e8me de l&rsquo;information europ\u00e9en. Il s\u2019agit non seulement de d\u00e9fendre les acteurs traditionnels de la production d&rsquo;information mais aussi de chercher \u00e0 r\u00e9duire la toute-puissance des plateformes existantes \u2014 c&rsquo;est-\u00e0-dire en les rappelant \u00e0 leurs responsabilit\u00e9s.<\/p>\n\n\n\n<p>C&rsquo;est l\u00e0 qu&rsquo;intervient la proposition de la <em>Social Data Science Alliance<\/em> (SDSA)&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-6-282686' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/06\/10\/gagner-la-guerre-dindependance-numerique-europeenne\/#easy-footnote-bottom-6-282686' title='&lt;a href=&quot;https:\/\/informationdemocracy.org\/wp-content\/uploads\/2025\/04\/EU-has-a-unique-chance-to-establish-local-social-media-platforms.pdf&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Europe has a unique chance to establish local social media platforms, to counter the new US technopolitics&lt;\/a&gt;, Social Data Science Alliance, 2025.'><sup>6<\/sup><\/a><\/span><\/span> pour une strat\u00e9gie favorisant la cr\u00e9ation de nouvelles plateformes en Europe. Elles seraient organis\u00e9es de mani\u00e8re \u00e0 ne pas entraver la libre expression des id\u00e9es et \u00e0 accro\u00eetre les espaces de circulation d&rsquo;informations de qualit\u00e9, actuellement \u00e9touff\u00e9s par les plateformes am\u00e9ricaines.<\/p>\n\n\n\n\n<div class=\"double-picture my-12 lg:my-20\" \n    data-images-sizes=\"smalldx\"\n    data-same-height=\"true\"\n    data-reference-image=\"left\"\n>    <!-- Images -->\n    <div class=\"lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-2\/3\">\n                            <a \n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/06\/SIPA_rex40331973_000001-scaled-e1749569971807.jpg\" \n                    class=\"gallery-item no-underline  \" \n                    data-pswp-width=\"2560\" \n                    data-pswp-height=\"2042\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/06\/SIPA_rex40331973_000001-scaled-e1749569971807.jpg\" alt=\"\" >\n                        <\/picture>\n                                            <\/figure>\n                <\/a>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-1\/3\">\n                            <a\n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/06\/SIPA_rex40331973_000007-scaled.jpg\" \n                    class=\"gallery-item no-underline  lg:!absolute lg:h-full lg:right-0 lg:left-2 overflow-hidden\" \n                    data-pswp-width=\"2066\" \n                    data-pswp-height=\"2560\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/06\/SIPA_rex40331973_000007-scaled.jpg\" alt=\"\" class=\"lg:!h-full object-cover\">\n                        <\/picture>\n                                            <\/figure>\n                <\/a>\n                    <\/div>\n    <\/div>\n    <!-- Captions -->\n    <div class=\"hidden lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-2\/3\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">\n                                    <\/figure>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-1\/3\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">   \n                                    <\/figure>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<p>Le point central de la proposition est que nous pouvons favoriser un type d&rsquo;entrepreneuriat visant \u00e0 lancer de nouvelles plateformes \u00e0 condition qu&rsquo;elles soient interop\u00e9rables et structur\u00e9es de mani\u00e8re \u00e0 garantir la libre circulation des personnes entre les plateformes elles-m\u00eames.<\/p>\n\n\n\n<p>Les plateformes europ\u00e9ennes ne seraient ainsi pas orient\u00e9es de mani\u00e8re organique vers la monopolisation de leur zone d&rsquo;influence mais dessineraient un \u00e9cosyst\u00e8me innovant, libre, concurrentiel, pluraliste, sans concentration excessive de valeur ajout\u00e9e et de pouvoir.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Nous pouvons favoriser un type d&rsquo;entrepreneuriat visant \u00e0 lancer de nouvelles plateformes, \u00e0 condition qu&rsquo;elles soient interop\u00e9rables et structur\u00e9es de mani\u00e8re \u00e0 garantir la libre circulation des personnes entre les plateformes elles-m\u00eames.<\/p><cite>Luca de Biase<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Cette proposition s\u2019attaque au c\u0153ur du probl\u00e8me&#160;: le pouvoir exorbitant des plateformes g\u00e9n\u00e9r\u00e9 par l\u2019absence de toute concurrence.&nbsp;<\/p>\n\n\n\n<p>Le passage \u00e0 un syst\u00e8me de plateformes interop\u00e9rables rendrait ainsi moins contraignant l&rsquo;effet de r\u00e9seau des grandes plateformes existantes et faciliterait la cr\u00e9ation de nouvelles plateformes alternatives.&nbsp;<\/p>\n\n\n\n<p>Cela ne serait bien s\u00fbr pas suffisant, mais le rapport de la <em>Social Data Science Alliance<\/em> observe que si les grandes plateformes n&rsquo;acceptaient pas les r\u00e8gles europ\u00e9ennes en mati\u00e8re de concurrence, elles pourraient \u00e9galement se voir infliger des sanctions importantes \u2014 non seulement des amendes, mais aussi la fermeture temporaire de leurs activit\u00e9s comme cela s&rsquo;est produit par le pass\u00e9 au Br\u00e9sil \u00e0 l&rsquo;encontre de X et comme les \u00c9tats-Unis ont menac\u00e9 de le faire pour TikTok.&nbsp;<\/p>\n\n\n\n<p>En bref, la concurrence se d\u00e9fend avec des r\u00e8gles&#160;: en l&rsquo;absence de r\u00e8gles qui la prot\u00e8gent, en particulier dans l\u2019environnement num\u00e9rique, les plus forts deviennent toujours plus forts et emp\u00eachent l\u2019\u00e9mergence de toute concurrence.<\/p>\n\n\n\n<p>Parall\u00e8lement \u00e0 l\u2019application drastique du droit de la concurrence, il faut investir pour favoriser l&rsquo;\u00e9mergence des plateformes alternatives n\u00e9cessaires \u00e0 la r\u00e9alisation des objectifs syst\u00e9miques.<\/p>\n\n\n\n<p><em>Reimagine Europa<\/em>&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-7-282686' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/06\/10\/gagner-la-guerre-dindependance-numerique-europeenne\/#easy-footnote-bottom-7-282686' title='&lt;a href=&quot;https:\/\/re-imagine.eu\/building-a-european-media-infrastructure-to-strengthen-democracy-in-the-ai-era&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;Building a European infrastructure to support media and democracy in the AI Age&lt;\/a&gt;, Reimagine Europa, 16 janvier 2025.'><sup>7<\/sup><\/a><\/span><\/span> a \u00e9labor\u00e9 une proposition visant \u00e0 convaincre les institutions de l&rsquo;Union de s&rsquo;engager \u00e0 mettre en place une infrastructure permettant la cr\u00e9ation de nouvelles plateformes.<\/p>\n\n\n\n<p>Le contexte qui peut permettre ce type d&rsquo;engagement de l&rsquo;Europe est celui qui a conduit \u00e0 la d\u00e9finition d&rsquo;une strat\u00e9gie pour l\u2019IA. Les entreprises europ\u00e9ennes, y compris dans ce secteur, semblent nettement en retard par rapport aux g\u00e9ants am\u00e9ricains.&nbsp;<\/p>\n\n\n\n<p>De ce point de vue, l\u2019Union ne s&rsquo;est pas d\u00e9fil\u00e9e.<\/p>\n\n\n\n<p>Elle est convaincue que la question de l&rsquo;intelligence artificielle laisse place \u00e0 diff\u00e9rentes interpr\u00e9tations de la technologie \u2014 certaines mieux adapt\u00e9es au syst\u00e8me europ\u00e9en, qui a ses propres points forts. La robotique industrielle, la capacit\u00e9 de production et la science europ\u00e9ennes sont plus avanc\u00e9es que celles des \u00c9tats-Unis. Elles peuvent constituer une base pour le d\u00e9veloppement d&rsquo;intelligences artificielles efficaces et \u00e9conomiquement viables.&nbsp;<\/p>\n\n\n\n<p>L&rsquo;Europe a trouv\u00e9 le moyen de soutenir cette hypoth\u00e8se en investissant dans des infrastructures pertinentes&#160;: les supercalculateurs, les centres de donn\u00e9es, les AI Factory et les AI Gigafactory sont des infrastructures publiques que les centres de recherche, les entreprises et les start-ups europ\u00e9ens peuvent utiliser gratuitement pour former leurs mod\u00e8les sans disposer des capitaux priv\u00e9s dont b\u00e9n\u00e9ficient les entreprises am\u00e9ricaines.<\/p>\n\n\n\n<p>Ce mod\u00e8le pourrait \u00e9galement servir de base \u00e0 une strat\u00e9gie.<\/p>\n\n\n\n<p>Des infrastructures publiques essentielles, au r\u00f4le de facilitatrices, seraient ainsi capables de garantir la d\u00e9fense des droits et de la s\u00e9curit\u00e9 des citoyens en favorisant l&rsquo;\u00e9mergence de plateformes alternatives \u00e0 celles des Am\u00e9ricains.&nbsp;<\/p>\n\n\n\n<p>En n&rsquo;absorbant pas la majeure partie des ressources, elles laisseraient par ailleurs une grande valeur ajout\u00e9e aux nouvelles plateformes applicatives qui, \u00e0 leur tour, devraient se faire concurrence dans un contexte d&rsquo;interop\u00e9rabilit\u00e9, en innovant sans esp\u00e9rer conqu\u00e9rir un monopole, mais dans le but d&rsquo;offrir des services que les gens veulent vraiment utiliser. Dans ce contexte, les chances de voir na\u00eetre des plateformes engag\u00e9es dans l&rsquo;am\u00e9lioration de la qualit\u00e9 de l&rsquo;information en circulation sont \u00e9galement plus grandes.<\/p>\n\n\n\n<p>La comparaison entre le d\u00e9veloppement de l&rsquo;intelligence artificielle et l\u2019\u00e9volution des r\u00e9seaux sociaux est assez pertinente.<\/p>\n\n\n\n<p>Ceux-ci sont en effet d\u00e9sormais englob\u00e9s dans le \u00ab&#160;monde&#160;\u00bb de l&rsquo;intelligence artificielle. Non seulement parce que les contenus sont de plus en plus souvent cr\u00e9\u00e9s \u00e0 partir de mod\u00e8les g\u00e9n\u00e9ratifs et parce qu&rsquo;ils servent \u00e0 collecter une multitude de donn\u00e9es essentielles au d\u00e9veloppement des mod\u00e8les g\u00e9n\u00e9ratifs, mais aussi et surtout parce que le trafic y est g\u00e9r\u00e9 et manipul\u00e9 par des IA qui appliquent de mani\u00e8re personnalis\u00e9e des algorithmes de recommandation.&nbsp;<\/p>\n\n\n\n<p>On sait depuis des ann\u00e9es maintenant combien ces algorithmes se sont r\u00e9v\u00e9l\u00e9s socialement dangereux&#160;: con\u00e7us pour cr\u00e9er des contenus clivants <em>by design<\/em>, ils ont accru la polarisation, la radicalisation et la fragmentation des opinions des citoyens.<\/p>\n\n\n\n\n<div class=\"double-picture my-12 lg:my-20\" \n    data-images-sizes=\"smallsx\"\n    data-same-height=\"true\"\n    data-reference-image=\"left\"\n>    <!-- Images -->\n    <div class=\"lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-1\/3\">\n                            <a \n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/06\/SIPA_rex40331973_000032-scaled.jpg\" \n                    class=\"gallery-item no-underline  \" \n                    data-pswp-width=\"2055\" \n                    data-pswp-height=\"2560\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/06\/SIPA_rex40331973_000032-scaled.jpg\" alt=\"\" >\n                        <\/picture>\n                                            <\/figure>\n                <\/a>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-2\/3\">\n                            <a\n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/06\/SIPA_rex40331973_000006-scaled.jpg\" \n                    class=\"gallery-item no-underline  lg:!absolute lg:h-full lg:right-0 lg:left-2 overflow-hidden\" \n                    data-pswp-width=\"2560\" \n                    data-pswp-height=\"2052\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/06\/SIPA_rex40331973_000006-scaled.jpg\" alt=\"\" class=\"lg:!h-full object-cover\">\n                        <\/picture>\n                                            <\/figure>\n                <\/a>\n                    <\/div>\n    <\/div>\n    <!-- Captions -->\n    <div class=\"hidden lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-1\/3\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">\n                                    <\/figure>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-2\/3\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">   \n                                    <\/figure>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<p>De m\u00eame, les algorithmes de recommandation sont souvent responsables du succ\u00e8s de messages \u00e9motionnellement engageants, m\u00eame s&rsquo;ils sont compl\u00e8tement faux&#160;: les organisations qui produisent de la d\u00e9sinformation connaissent \u00e9galement cette circonstance et l&rsquo;exploitent pour attaquer les pays adverses, en diffusant des informations qui mettent en difficult\u00e9 les d\u00e9mocraties.<\/p>\n\n\n\n<p>Or la d\u00e9sinformation ne peut \u00eatre vaincue en opposant une v\u00e9rification des faits \u00e0 chaque fausse information en circulation&#160;: elle se combat par l&rsquo;\u00e9ducation, mais aussi en luttant contre les algorithmes de recommandation et la centralit\u00e9 des plateformes qui les proposent aux utilisateurs souvent inconscients du danger.&nbsp;<\/p>\n\n\n\n<p>La mise en place d&rsquo;alternatives sans syst\u00e8mes de recommandation \u2014 ou avec des syst\u00e8mes de recommandation visant \u00e0 am\u00e9liorer le service, par exemple en contextualisant les informations ou en pr\u00e9sentant diff\u00e9rents points de vue \u2014 pourrait r\u00e9duire la force de la d\u00e9sinformation, notamment parce qu&rsquo;elle favoriserait la circulation d&rsquo;informations diff\u00e9rentes, peut-\u00eatre bien document\u00e9es et fiables, capables de contextualiser ou d&rsquo;apporter des points de vue alternatifs, et \u00e9rodant globalement le pouvoir des quelques plateformes actuelles.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La d\u00e9sinformation se combat par l&rsquo;\u00e9ducation, mais aussi en luttant contre les algorithmes de recommandation et la centralit\u00e9 des plateformes qui les proposent aux utilisateurs souvent inconscients du danger.&nbsp;<\/p><cite>Luca de Biase<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Le RGPD fournit d\u00e9j\u00e0 un point de d\u00e9part pour la mise en place de ces infrastructures essentielles&#160;: les citoyens europ\u00e9ens sont titulaires d\u2019un droit de t\u00e9l\u00e9charger toutes leurs donn\u00e9es personnelles depuis les plateformes qu&rsquo;ils utilisent, de les enregistrer dans un format standard sur des serveurs sous leur contr\u00f4le et de les utiliser pour acc\u00e9der \u00e0 des plateformes concurrentes.&nbsp;<\/p>\n\n\n\n<p>Ce concept, d\u00e9j\u00e0 d\u00e9velopp\u00e9 en Inde, est actuellement \u00e0 l&rsquo;\u00e9tude en Europe.<\/p>\n\n\n\n<p>Si les citoyens contr\u00f4lent leurs donn\u00e9es personnelles \u00e0 travers un syst\u00e8me unique de certification d\u2019identit\u00e9 qu\u2019ils contr\u00f4lent et qu&rsquo;ils peuvent utiliser pour acc\u00e9der \u00e0 n&rsquo;importe quelle plateforme, les conditions pr\u00e9alables \u00e0 l&rsquo;interop\u00e9rabilit\u00e9 sont r\u00e9unies.&nbsp;<\/p>\n\n\n\n<p>Ce portefeuille contenant des documents d&rsquo;identit\u00e9 et des donn\u00e9es personnelles \u2014 voire m\u00eame les euros num\u00e9riques qui pourraient demain \u00eatre mis en circulation \u2014 pourrait \u00eatre un instrument fondamental de libert\u00e9 dans le monde num\u00e9rique, \u00e0 condition que les donn\u00e9es soient contr\u00f4l\u00e9es par les citoyens et non par des entreprises priv\u00e9es ou des autorit\u00e9s publiques.<\/p>\n\n\n\n<p>Une premi\u00e8re application d\u2019un tel portefeuille pourrait servir \u00e0 corriger les probl\u00e8mes que les r\u00e9seaux sociaux causent aux citoyens mineurs.&nbsp;<\/p>\n\n\n\n<p>En juillet, l&rsquo;Union lancera une application de v\u00e9rification de l&rsquo;\u00e2ge, con\u00e7ue pour renforcer la protection des mineurs en ligne. Cet outil permettra de confirmer l&rsquo;\u00e2ge des utilisateurs sans qu&rsquo;ils soient oblig\u00e9s de fournir des donn\u00e9es personnelles aux plateformes. Bien que l&rsquo;Union n&rsquo;impose pas de m\u00e9thode unique de v\u00e9rification, elle exige que les sites traitant des contenus sensibles prennent des mesures appropri\u00e9es.<\/p>\n\n\n\n<p>Cette application, qui pr\u00e9c\u00e8de le portefeuille d&rsquo;identit\u00e9 num\u00e9rique pr\u00e9vu pour 2026, donnera \u00e0 l&rsquo;Union un moyen suppl\u00e9mentaire d&rsquo;exiger plus de rigueur de la part des plateformes. Henna Virkkunen, la commissaire europ\u00e9enne charg\u00e9e du num\u00e9rique, a soulign\u00e9 dans un entretien au <em>Financial Times<\/em>&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-8-282686' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/06\/10\/gagner-la-guerre-dindependance-numerique-europeenne\/#easy-footnote-bottom-8-282686' title='Barbara Moens, &lt;a href=&quot;https:\/\/www.ft.com\/content\/6b672468-a085-47dc-b195-daa98d6a591b&quot; target=&quot;_blank&quot; rel=&quot;noreferrer noopener&quot;&gt;EU to launch age-check app as pressure builds on Big Tech&lt;\/a&gt;, &lt;em&gt;Financial Times&lt;\/em&gt;, 30 mai 2025.'><sup>8<\/sup><\/a><\/span><\/span> que la protection des mineurs devait \u00eatre une priorit\u00e9 et que les grandes entreprises du secteur num\u00e9rique devaient redoubler d&rsquo;efforts.<\/p>\n\n\n\n<p>\u00c0 partir du portefeuille pour les donn\u00e9es personnelles, la solution pourrait se poursuivre avec la mise en place de plateformes de publication, y compris en source ouverte, qui pourraient \u00eatre utilis\u00e9es pour g\u00e9n\u00e9rer des r\u00e9seaux de relations num\u00e9riques innovants, distribu\u00e9s, \u00e0 valeur locale ou sectorielle pour les participants.<\/p>\n\n\n\n<p>Une infrastructure fond\u00e9e sur ces principes ne mobiliserait qu\u2019une des ressources des plateformes applicatives, qui pourraient ainsi fonctionner avec des mod\u00e8les \u00e9conomiques moins co\u00fbteux.&nbsp;<\/p>\n\n\n\n<p>Cela peut multiplier le nombre d&rsquo;initiatives et permettre \u00e9galement des applications moins industrielles et de meilleure qualit\u00e9 pour les utilisateurs \u2014 notamment au service de l&rsquo;innovation sociale \u2014 pour des initiatives \u00e9ducatives et culturellement significatives, pour des informations de qualit\u00e9 au service de la sant\u00e9 ou des transports, etc.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Si les citoyens contr\u00f4lent leurs donn\u00e9es personnelles \u00e0 travers un syst\u00e8me unique de certification d\u2019identit\u00e9 et qu&rsquo;ils peuvent l&rsquo;utiliser pour acc\u00e9der \u00e0 n&rsquo;importe quelle plateforme, les conditions pr\u00e9alables \u00e0 l&rsquo;interop\u00e9rabilit\u00e9 sont r\u00e9unies.&nbsp;<\/p><cite>Luca de Biase<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Des start-ups sp\u00e9cialis\u00e9es dans la gestion de connaissances de qualit\u00e9 bas\u00e9es sur des donn\u00e9es contr\u00f4l\u00e9es pourraient \u00e9merger gr\u00e2ce aux vastes possibilit\u00e9s offertes par une intelligence artificielle ind\u00e9pendante. Elles serviraient \u00e0 contextualiser les informations, \u00e0 traduire, \u00e0 g\u00e9n\u00e9rer des informations bas\u00e9es sur des donn\u00e9es quantitatives, etc. Des r\u00e9seaux de nouvelle g\u00e9n\u00e9ration, faciles \u00e0 utiliser mais aussi \u00e0 cr\u00e9er, verraient le jour pour tout type d&rsquo;innovation sociale et culturelle, avec un mod\u00e8le \u00e9conomique rationnel&#160;: non pas une nouvelle plateforme gigantesque \u2014 mais un nombre gigantesque de nouvelles plateformes \u2014 pour transformer un syst\u00e8me monopolis\u00e9 par quelques g\u00e9ants en un march\u00e9 concurrentiel ouvert et riche en innovations.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Les doutes europ\u00e9ens<\/h2>\n\n\n\n<p>Ce constat pos\u00e9, qu&rsquo;est-ce qui explique la r\u00e9ticence des autorit\u00e9s \u00e0 s&rsquo;engager en faveur de la cr\u00e9ation de plateformes alternatives europ\u00e9ennes autonomes&#160;?&nbsp;<\/p>\n\n\n\n<p>L&rsquo;hypoth\u00e8se selon laquelle elles n&rsquo;en verraient pas l&rsquo;importance est sans doute erron\u00e9e&#160;: l&rsquo;Union a largement l\u00e9gif\u00e9r\u00e9 au cours de la derni\u00e8re l\u00e9gislature pour limiter le pouvoir des plateformes existantes.<\/p>\n\n\n\n<p>Une deuxi\u00e8me hypoth\u00e8se est que <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/02\/11\/ia-que-peut-leurope-face-a-lempire-numerique-de-donald-trump-une-conversation-avec-anu-bradford\/\" target=\"_blank\" rel=\"noreferrer noopener\">la Commission estime qu&rsquo;il serait, au fond, trop difficile de battre les plateformes am\u00e9ricaines<\/a>&#160;: concurrencer les monopoles am\u00e9ricains, consid\u00e9r\u00e9s comme tr\u00e8s puissants, tr\u00e8s riches et tr\u00e8s performants sur le plan technologique, serait un \u00e9chec certain.&nbsp;<\/p>\n\n\n\n<p>Les plateformes qui b\u00e9n\u00e9ficient de l&rsquo;effet r\u00e9seau sont imbattables. Mais comme l&rsquo;a d\u00e9montr\u00e9 Bernardo Huberman dans ses \u00e9tudes sur les \u00ab&#160;lois du web&#160;\u00bb&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-9-282686' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/06\/10\/gagner-la-guerre-dindependance-numerique-europeenne\/#easy-footnote-bottom-9-282686' title='Bernardo Huberman, &lt;em&gt;The Laws of the Web&amp;#160;: Patterns in the Ecology of Information, &lt;\/em&gt;The MIT Press, 2001.'><sup>9<\/sup><\/a><\/span><\/span>, l&rsquo;effet de r\u00e9seau s&rsquo;applique \u00e0 toutes les cat\u00e9gories de services. Autrement dit, il est toujours possible de cr\u00e9er des plateformes qui offrent un service diff\u00e9rent de ceux qui existent d\u00e9j\u00e0. Il ne s&rsquo;agit pas de refaire Google ou Instagram mais de cr\u00e9er des plateformes compl\u00e8tement diff\u00e9rentes \u2014 qui puissent toutefois attirer l&rsquo;attention avec des propositions plus sens\u00e9es et rationnelles sur le plan humain que celles des plateformes am\u00e9ricaines.<\/p>\n\n\n\n<p>Une troisi\u00e8me hypoth\u00e8se pourrait puiser dans des raisons plus id\u00e9ologiques&#160;: dans les couloirs de la Commission pourrait encore pr\u00e9valoir l&rsquo;id\u00e9e que les activit\u00e9s concurrentielles des plateformes devraient \u00eatre r\u00e9gl\u00e9es par le march\u00e9 \u2014 c&rsquo;est-\u00e0-dire par les entrepreneurs et les particuliers \u2014 plut\u00f4t que par l&rsquo;\u00c9tat.<\/p>\n\n\n\n<p>Au plan purement th\u00e9orique, il est vrai qu&rsquo;il s&rsquo;agit d&rsquo;une activit\u00e9 \u00e9conomique qui ne se d\u00e9roule pas dans des conditions de d\u00e9faillance du march\u00e9, tout comme il est vrai qu&rsquo;il est assez compliqu\u00e9 d&rsquo;intervenir politiquement dans le monde des m\u00e9dias sans risquer d&rsquo;aggraver la situation d\u00e9mocratique et la libert\u00e9 d&rsquo;expression.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Dans les couloirs de la Commission pourrait encore pr\u00e9valoir l&rsquo;id\u00e9e que les activit\u00e9s concurrentielles des plateformes devraient \u00eatre r\u00e9gl\u00e9es par le march\u00e9 \u2014 c&rsquo;est-\u00e0-dire par les entrepreneurs et les particuliers \u2014 plut\u00f4t que par l&rsquo;\u00c9tat.<\/p><cite>Luca de Biase<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Il faut toutefois admettre que cela entrerait en contradiction avec le fait ind\u00e9niable que de nombreux pays d\u00e9mocratiques europ\u00e9ens disposent d&rsquo;un syst\u00e8me public de radiodiffusion, qui fournit un service public au nom de la d\u00e9mocratie, du pluralisme et de l&rsquo;information en tant que service universel.&nbsp;<\/p>\n\n\n\n<p>Autrement dit, cette approche part d&rsquo;un postulat erron\u00e9&#160;: le monde des r\u00e9seaux sociaux n&rsquo;est pas parfaitement concurrentiel. On pourrait m\u00eame dire qu&rsquo;en emp\u00eachant tout nouvel acteur d&rsquo;\u00e9merger, il peut \u00eatre consid\u00e9r\u00e9 comme un march\u00e9 d\u00e9faillant.<\/p>\n\n\n\n<p>Il y aurait une quatri\u00e8me hypoth\u00e8se&#160;: celle qui voit les politiciens et les parties prenantes ne pas s&rsquo;attaquer \u00e0 un outil qui est encore, pour eux, un formidable instrument de propagande.&nbsp;<\/p>\n\n\n\n<p>C&rsquo;est un sujet qui int\u00e9resse davantage les politiciens extr\u00e9mistes, qui sont ceux qui tirent le meilleur parti des r\u00e9seaux sociaux. Les politiciens qui ne pourraient se passer des r\u00e9seaux sociaux actuels sont ceux qui vivent de la polarisation, qui n&rsquo;approfondissent pas les sujets, qui se contentent d&rsquo;intercepter toute forme de m\u00e9contentement. Les r\u00e9seaux sociaux actuels accentuent la visibilit\u00e9 des messages purement \u00e9motionnels et invisibilisent les informations document\u00e9es, exigeantes et rationnelles. L\u2019Union devrait toutefois veiller \u00e0 accro\u00eetre l&rsquo;attention que les citoyens europ\u00e9ens accordent \u00e0 des informations de meilleure qualit\u00e9 et plus approfondies que celles qui pr\u00e9valent sur les r\u00e9seaux sociaux.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Une communaut\u00e9 d\u2019intentions<\/h2>\n\n\n\n<p>Une nouvelle strat\u00e9gie europ\u00e9enne pour les r\u00e9seaux sociaux est possible.<\/p>\n\n\n\n<p>Il faut trouver les motifs d&rsquo;unit\u00e9 politique dans un monde num\u00e9rique qui a tout fait pour diviser les populations et fragmenter les groupes sociaux, jusqu&rsquo;\u00e0 g\u00e9n\u00e9rer une v\u00e9ritable \u00e9pid\u00e9mie de solitude.<\/p>\n\n\n\n<p>Il s&rsquo;agit de penser \u00e0 des choses qui n&rsquo;ont pas encore \u00e9t\u00e9 faites, d&rsquo;introduire dans le syst\u00e8me m\u00e9diatique des logiques d&rsquo;innovation qui, sans imposer de contenus sp\u00e9cifiques, alimentent des m\u00e9thodes permettant de faire de l&rsquo;information un service public. Les diff\u00e9rentes formes de crise de la d\u00e9mocratie \u2014 de la baisse de la participation \u00e9lectorale \u00e0 l&rsquo;explosion des mouvements extr\u00e9mistes et antisyst\u00e8mes en passant la circulation d&rsquo;informations destructrices \u2014 sont des ph\u00e9nom\u00e8nes compatibles avec une conception des r\u00e9seaux sociaux qui se r\u00e9v\u00e8le particuli\u00e8rement adapt\u00e9e \u00e0 \u00eatre exploit\u00e9e par des puissances \u00e9trang\u00e8res souhaitant exercer une influence sur l&rsquo;Union europ\u00e9enne.<\/p>\n\n\n\n<p>Or il est vrai que, jusqu&rsquo;\u00e0 pr\u00e9sent, l&rsquo;Europe a r\u00e9ussi \u00e0 aller de l&rsquo;avant malgr\u00e9 un \u00e9cosyst\u00e8me m\u00e9diatique d\u00e9grad\u00e9. Mais une nouveaut\u00e9 pourrait acc\u00e9l\u00e9rer le processus d\u00e9cisionnel. <\/p>\n\n\n\n<p>L&rsquo;Union a d\u00e9couvert qu&rsquo;il est n\u00e9cessaire de se doter d&rsquo;une d\u00e9fense commune. Cela n&rsquo;implique pas seulement la n\u00e9cessit\u00e9 d&rsquo;investir dans des armements pour une guerre physique hypoth\u00e9tique. Cela implique d&rsquo;investir dans des solutions d\u00e9fensives pour la guerre cognitive d\u00e9j\u00e0 en cours.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Les diff\u00e9rentes formes de crise de la d\u00e9mocratie sont des ph\u00e9nom\u00e8nes compatibles avec une conception des r\u00e9seaux sociaux qui se r\u00e9v\u00e8le particuli\u00e8rement adapt\u00e9e \u00e0 \u00eatre exploit\u00e9e par des puissances \u00e9trang\u00e8res souhaitant exercer une influence sur l&rsquo;Union europ\u00e9enne.<\/p><cite>Luca de Biase<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Selon David Colon et Anne Applebaum&nbsp;<span class='whitespace-nowrap'><span id='easy-footnote-10-282686' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/legrandcontinent.eu\/fr\/2025\/06\/10\/gagner-la-guerre-dindependance-numerique-europeenne\/#easy-footnote-bottom-10-282686' title='Anne Applebaum, &lt;em&gt;Autocracy, Inc&amp;#160;: The Dictators Who Want to Run the World&lt;\/em&gt;, Allen Lane, 2024&amp;#160;; David Colon, &lt;em&gt;La guerre de l\u2019information. Les \u00c9tats \u00e0 la conqu\u00eate de nos esprits&lt;\/em&gt;, Taillandier, 2023.'><sup>10<\/sup><\/a><\/span><\/span>, les puissances \u00e9trang\u00e8res qui la d\u00e9veloppent sur le \u00ab&#160;th\u00e9\u00e2tre digital&#160;\u00bb europ\u00e9en sont les autocraties int\u00e9ress\u00e9es par la d\u00e9stabilisation de l&rsquo;Union et par la conqu\u00eate de nouveaux espaces en Europe et en Afrique. Elles ont appris le concept m\u00eame de guerre cognitive des \u00c9tats-Unis, qui l&rsquo;ont d\u00e9velopp\u00e9 au fil du temps en Europe&#160;: depuis l&rsquo;\u00e9poque de la strat\u00e9gie de la tension dans les pays qui avaient d&rsquo;importants partis communistes jusqu&rsquo;au d\u00e9ploiement massif de la surveillance num\u00e9rique, dont l&rsquo;un des exemples les plus connus et document\u00e9s \u00e9tait le cas de l&rsquo;espionnage de la chanceli\u00e8re allemande Angela Merkel, r\u00e9v\u00e9l\u00e9 au public par des enqu\u00eates sur les activit\u00e9s de la NSA lanc\u00e9es \u00e0 la suite des r\u00e9v\u00e9lations d&rsquo;Edward Snowden.<\/p>\n\n\n\n<p>Les \u00c9tats-Unis ont invent\u00e9 la guerre cognitive \u2014 cette forme de conflit mettant en \u0153uvre un ensemble complexe d&rsquo;actions de d\u00e9sinformation, de surveillance granulaire, de strat\u00e9gie de la tension, de soft power, de construction de plateformes et de contr\u00f4le de l&rsquo;Internet. C&rsquo;est de Washington que les Russes et les Chinois ont appris pour riposter avec l&rsquo;efficacit\u00e9 dont peuvent faire preuve les autocraties dans ce domaine.&nbsp;<\/p>\n\n\n\n\n<div class=\"double-picture my-12 lg:my-20\" \n    data-images-sizes=\"half\"\n    data-same-height=\"true\"\n    data-reference-image=\"left\"\n>    <!-- Images -->\n    <div class=\"lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-1\/2\">\n                            <a \n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/06\/SIPA_rex40331973_000008-scaled.jpg\" \n                    class=\"gallery-item no-underline  \" \n                    data-pswp-width=\"2027\" \n                    data-pswp-height=\"2560\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/06\/SIPA_rex40331973_000008-scaled.jpg\" alt=\"\" >\n                        <\/picture>\n                                            <\/figure>\n                <\/a>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-1\/2\">\n                            <a\n                    href=\"#\"\n                    data-pswp-src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/06\/SIPA_rex40331973_000007-scaled.jpg\" \n                    class=\"gallery-item no-underline  lg:!absolute lg:h-full lg:right-0 lg:left-2 overflow-hidden\" \n                    data-pswp-width=\"2066\" \n                    data-pswp-height=\"2560\"\n                >\n                    <figure class=\"wp-block-image h-full -mx-2 lg:mx-0 !my-0\">\n                        <picture class=\"block h-full\">\n                            <img decoding=\"async\" src=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/06\/SIPA_rex40331973_000007-scaled.jpg\" alt=\"\" class=\"lg:!h-full object-cover\">\n                        <\/picture>\n                                            <\/figure>\n                <\/a>\n                    <\/div>\n    <\/div>\n    <!-- Captions -->\n    <div class=\"hidden lg:flex\">\n        <div class=\"relative lg:pr-2 mb-7 lg:mb-0 lg:w-1\/2\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">\n                                    <\/figure>\n                    \n        <\/div>\n        <div class=\"relative lg:pl-2 lg:w-1\/2\">\n                            <figure class=\"wp-block-image -mx-2 lg:mx-0 !my-0\">   \n                                    <\/figure>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<p>Du d\u00e9but \u00e0 la fin, l&rsquo;Union a subi.<\/p>\n\n\n\n<p>La strat\u00e9gie du chaos russe et la surveillance am\u00e9ricaine, les ing\u00e9rences chinoises, iraniennes et isra\u00e9liennes&#160;: nous avons \u00e9t\u00e9 la premi\u00e8re victime collat\u00e9rale de cette guerre parce que nous n\u2019avions aucun contr\u00f4le sur les plateformes. C\u2019est fort de ce constat que nous pouvons peut-\u00eatre nous r\u00e9unir autour d\u2019une communaut\u00e9 d&rsquo;intention&#160;: notre ind\u00e9pendance passe <em>d\u2019abord <\/em>par notre ind\u00e9pendance num\u00e9rique.<\/p>\n\n\n\n<p>Les solutions que nous apporterons devront \u00eatre profond\u00e9ment attach\u00e9es \u00e0 la d\u00e9fense des droits humains et de nos libert\u00e9s&#160;: la guerre cognitive se gagne avec les technologies de la communication, mais aussi et surtout avec l&rsquo;esprit et le respect des r\u00e8gles et des personnes qui les utilisent.<\/p>\n\n\n\n<p class=\"has-text-align-center\">*<\/p>\n\n\n\n<p>Bien s\u00fbr, il ne s\u2019agit l\u00e0 que de quelques id\u00e9es \u2014 n\u00e9cessaires mais sans doute pas suffisantes \u2014 pour lancer la contre-offensive num\u00e9rique dont l\u2019Europe a besoin.<\/p>\n\n\n\n<p>Mais force est aujourd\u2019hui de constater que le plus grand frein \u00e0 la reprise europ\u00e9enne est certainement la conviction qu&rsquo;il n&rsquo;y aurait finalement rien de concret \u00e0 faire contre le pouvoir des plateformes am\u00e9ricaines.<\/p>\n\n\n\n<p>Leur puissance n\u2019est pourtant pas in\u00e9luctable&#160;: jusqu\u2019\u00e0 temps que nous ne nous y opposons pas, nous l\u2019acceptons.<\/p>\n\n\n\n<p>En Russie, en Cor\u00e9e du Sud, en Chine, les plateformes les plus utilis\u00e9es sont locales.<\/p>\n\n\n\n<p>Au Japon, en Indon\u00e9sie et au Br\u00e9sil, il existe des plateformes locales suffisamment fortes pour faire concurrence aux am\u00e9ricaines.&nbsp;<\/p>\n\n\n\n<p>En Inde, il existe une strat\u00e9gie forte et tr\u00e8s visionnaire pour la construction d&rsquo;une infrastructure locale pour l&rsquo;identit\u00e9 num\u00e9rique locale \u2014&nbsp;<a href=\"https:\/\/legrandcontinent.eu\/fr\/2024\/05\/17\/aadhaar-en-inde-un-identifiant-numerique-omnipresent-menace-la-democratie\/\" target=\"_blank\" rel=\"noreferrer noopener\">qui pr\u00e9sente toutefois des limites sur le plan du droit<\/a>.&nbsp;<\/p>\n\n\n\n<p>En bref, l&rsquo;Europe semble \u00eatre la seule grande r\u00e9gion qui n&rsquo;ait pas encore combattu sa guerre d\u2019ind\u00e9pendance num\u00e9rique.<\/p>\n\n\n\n<p>Il est temps de la mener \u2014 la victoire est possible.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Europe a internalis\u00e9 un blocage&#160;&#160;: elle est aujourd\u2019hui le seul endroit du monde en dehors des \u00c9tats-Unis o\u00f9 la toute-puissance des GAFAM semble in\u00e9vitable.<\/p>\n<p>Pour Luca de Biase, il faut changer de strat\u00e9gie en revenant aux fondamentaux&#160;&#160;: un droit de la concurrence bien appliqu\u00e9 et des infrastructures essentielles.<\/p>\n<p>Affirmer une ind\u00e9pendance num\u00e9rique europ\u00e9enne ne passera pas la constitution d\u2019une nouvelle plateforme gigantesque face aux Big Tech \u2014 mais par un nombre gigantesque de nouvelles plateformes europ\u00e9ennes.<\/p>\n","protected":false},"author":36974,"featured_media":282673,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-angles.php","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":26,"footnotes":""},"categories":[1729],"tags":[],"staff":[4485],"editorial_format":[4944],"serie":[],"audience":[],"geo":[1917],"class_list":["post-282686","post","type-post","status-publish","format-standard","hentry","category-numerique","staff-luca-debiase","editorial_format-actu-longues","geo-europe"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":282673,"excerpt":"L\u2019Europe a internalis\u00e9 un blocage : elle est aujourd\u2019hui le seul endroit du monde en dehors des \u00c9tats-Unis o\u00f9 la toute-puissance des GAFAM semble in\u00e9vitable.\r\n\r\nPour Luca de Biase, il faut changer de strat\u00e9gie en revenant aux fondamentaux: un droit de la concurrence bien appliqu\u00e9 et des infrastructures essentielles.\r\n\r\nAffirmer une ind\u00e9pendance num\u00e9rique europ\u00e9enne ne passera pas la constitution d\u2019une nouvelle plateforme gigantesque face aux Big Tech \u2014 mais par un nombre gigantesque de nouvelles plateformes europ\u00e9ennes.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gagner la guerre d\u2019ind\u00e9pendance num\u00e9rique europ\u00e9enne | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/06\/10\/gagner-la-guerre-dindependance-numerique-europeenne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gagner la guerre d\u2019ind\u00e9pendance num\u00e9rique europ\u00e9enne | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"L\u2019Europe a internalis\u00e9 un blocage&#160;: elle est aujourd\u2019hui le seul endroit du monde en dehors des \u00c9tats-Unis o\u00f9 la toute-puissance des GAFAM semble in\u00e9vitable.  Pour Luca de Biase, il faut changer de strat\u00e9gie en revenant aux fondamentaux&#160;: un droit de la concurrence bien appliqu\u00e9 et des infrastructures essentielles.  Affirmer une ind\u00e9pendance num\u00e9rique europ\u00e9enne ne passera pas la constitution d\u2019une nouvelle plateforme gigantesque face aux Big Tech \u2014 mais par un nombre gigantesque de nouvelles plateformes europ\u00e9ennes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2025\/06\/10\/gagner-la-guerre-dindependance-numerique-europeenne\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-10T15:48:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-11T11:57:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/06\/gc-war-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"zelief\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/06\/gc-war-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"zelief\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"26 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/06\/10\/gagner-la-guerre-dindependance-numerique-europeenne\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/06\/10\/gagner-la-guerre-dindependance-numerique-europeenne\/\",\"name\":\"Gagner la guerre d\u2019ind\u00e9pendance num\u00e9rique europ\u00e9enne | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/06\/10\/gagner-la-guerre-dindependance-numerique-europeenne\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/06\/10\/gagner-la-guerre-dindependance-numerique-europeenne\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/06\/SIPA_rex40331973_000002-scaled.jpg\",\"datePublished\":\"2025-06-10T15:48:51+00:00\",\"dateModified\":\"2025-06-11T11:57:09+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/97de4c53b1269600dc2fed829ae3db38\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/06\/10\/gagner-la-guerre-dindependance-numerique-europeenne\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2025\/06\/10\/gagner-la-guerre-dindependance-numerique-europeenne\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/06\/10\/gagner-la-guerre-dindependance-numerique-europeenne\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/06\/SIPA_rex40331973_000002-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/06\/SIPA_rex40331973_000002-scaled.jpg\",\"width\":2560,\"height\":2057,\"caption\":\"\u00a9 Brendan Fitzpatrick\/REX\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/06\/10\/gagner-la-guerre-dindependance-numerique-europeenne\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gagner la guerre d\u2019ind\u00e9pendance num\u00e9rique europ\u00e9enne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/97de4c53b1269600dc2fed829ae3db38\",\"name\":\"zelief\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3a59c963eac7257350708fa43658e859?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3a59c963eac7257350708fa43658e859?s=96&d=mm&r=g\",\"caption\":\"zelief\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gagner la guerre d\u2019ind\u00e9pendance num\u00e9rique europ\u00e9enne | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2025\/06\/10\/gagner-la-guerre-dindependance-numerique-europeenne\/","og_locale":"fr_FR","og_type":"article","og_title":"Gagner la guerre d\u2019ind\u00e9pendance num\u00e9rique europ\u00e9enne | Le Grand Continent","og_description":"L\u2019Europe a internalis\u00e9 un blocage&#160;: elle est aujourd\u2019hui le seul endroit du monde en dehors des \u00c9tats-Unis o\u00f9 la toute-puissance des GAFAM semble in\u00e9vitable.  Pour Luca de Biase, il faut changer de strat\u00e9gie en revenant aux fondamentaux&#160;: un droit de la concurrence bien appliqu\u00e9 et des infrastructures essentielles.  Affirmer une ind\u00e9pendance num\u00e9rique europ\u00e9enne ne passera pas la constitution d\u2019une nouvelle plateforme gigantesque face aux Big Tech \u2014 mais par un nombre gigantesque de nouvelles plateformes europ\u00e9ennes.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2025\/06\/10\/gagner-la-guerre-dindependance-numerique-europeenne\/","og_site_name":"Le Grand Continent","article_published_time":"2025-06-10T15:48:51+00:00","article_modified_time":"2025-06-11T11:57:09+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/06\/gc-war-scaled.jpg","type":"image\/jpeg"}],"author":"zelief","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/06\/gc-war-scaled.jpg","twitter_misc":{"\u00c9crit par":"zelief","Dur\u00e9e de lecture estim\u00e9e":"26 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/06\/10\/gagner-la-guerre-dindependance-numerique-europeenne\/","url":"https:\/\/legrandcontinent.eu\/fr\/2025\/06\/10\/gagner-la-guerre-dindependance-numerique-europeenne\/","name":"Gagner la guerre d\u2019ind\u00e9pendance num\u00e9rique europ\u00e9enne | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/06\/10\/gagner-la-guerre-dindependance-numerique-europeenne\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/06\/10\/gagner-la-guerre-dindependance-numerique-europeenne\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/06\/SIPA_rex40331973_000002-scaled.jpg","datePublished":"2025-06-10T15:48:51+00:00","dateModified":"2025-06-11T11:57:09+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/97de4c53b1269600dc2fed829ae3db38"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/06\/10\/gagner-la-guerre-dindependance-numerique-europeenne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2025\/06\/10\/gagner-la-guerre-dindependance-numerique-europeenne\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/06\/10\/gagner-la-guerre-dindependance-numerique-europeenne\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/06\/SIPA_rex40331973_000002-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/06\/SIPA_rex40331973_000002-scaled.jpg","width":2560,"height":2057,"caption":"\u00a9 Brendan Fitzpatrick\/REX"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/06\/10\/gagner-la-guerre-dindependance-numerique-europeenne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Gagner la guerre d\u2019ind\u00e9pendance num\u00e9rique europ\u00e9enne"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/97de4c53b1269600dc2fed829ae3db38","name":"zelief","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3a59c963eac7257350708fa43658e859?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3a59c963eac7257350708fa43658e859?s=96&d=mm&r=g","caption":"zelief"}}]}},"lgc_categories":[{"id":1729,"name":"Num\u00e9rique","slug":"numerique"}],"lgc_author":{"id":4485,"name":"Luca De Biase","slug":"luca-debiase","description":"Luca De Biase est journaliste et \u00e9crivain. Il est le fondateur et r\u00e9dacteur en chef de N\u00f2va, la rubrique multiplateforme science et technologie d'Il Sole 24 Ore.","first_name":"Luca ","last_name":"De Biase","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/Luca-De-Biase-Dizionario-del-Cambiamento-FEDU-1000x1000-1.png","width":509,"height":509,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/06\/SIPA_rex40331973_000002-scaled.jpg","width":2560,"height":2057,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/06\/SIPA_rex40331973_000002-scaled.jpg","width":2560,"height":2057,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/282686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/36974"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=282686"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/282686\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/282673"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=282686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=282686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=282686"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=282686"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=282686"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=282686"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=282686"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=282686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}