{"id":280015,"date":"2025-05-19T16:23:54","date_gmt":"2025-05-19T14:23:54","guid":{"rendered":"https:\/\/legrandcontinent.eu\/fr\/?p=280015"},"modified":"2025-05-19T18:50:51","modified_gmt":"2025-05-19T16:50:51","slug":"roumanie-le-coup-de-semonce-simion-ne-doit-pas-rester-sans-consequences","status":"publish","type":"post","link":"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/19\/roumanie-le-coup-de-semonce-simion-ne-doit-pas-rester-sans-consequences\/","title":{"rendered":"Roumanie&#160;: le coup de semonce Simion ne doit pas rester sans cons\u00e9quences"},"content":{"rendered":"\n<p class=\"has-drop-cap\">Dimanche 18 mai s\u2019est tenu le <a href=\"https:\/\/legrandcontinent.eu\/fr\/themes\/elections\/election-presidentielle-en-roumanie\/\">second tour de l&rsquo;\u00e9lection pr\u00e9sidentielle roumaine<\/a>. Le maire centriste de Bucarest <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/18\/nicusor-dan-devient-president-de-la-roumanie-une-election-historique\/\">Nicusor Dan l\u2019a finalement emport\u00e9 sur George Simion<\/a>, le <a href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/05\/qui-est-george-simion-du-complotisme-covid-19-a-la-nostalgie-de-ceausescu-10-phrases-choc-de-lhomme-fort-de-lextreme-droite-roumaine\/\">candidat d\u2019extr\u00eame droite pro-Trump et pro-Poutine<\/a>.<\/p>\n\n\n\n<p>Pour l\u2019avenir de l\u2019Union europ\u00e9enne, c\u2019est \u00e9videmment une bonne nouvelle.&nbsp;<\/p>\n\n\n\n<p>Mais le coup n\u2019est pas pass\u00e9 loin&nbsp;&#160;: la mont\u00e9e en puissance de l\u2019extr\u00eame droite en Europe centrale et orientale montre que l\u2019Union doit imp\u00e9rativement se r\u00e9former d\u2019urgence si elle veut pouvoir survivre et faire face aux agressions et aux ing\u00e9rences du Kremlin et de la Maison-Blanche<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pourquoi l\u2019extr\u00eame-droite poutinienne est-elle si forte en Roumanie et dans l\u2019Est de l\u2019Europe&nbsp;&#160;?<\/h2>\n\n\n\n<p>Comme dans tous les pays du bloc de l\u2019Est, il n\u2019y a pas eu en Roumanie apr\u00e8s la Seconde Guerre mondiale de r\u00e9el travail approfondi sur le fascisme et le racisme dans une soci\u00e9t\u00e9 roumaine qui \u00e9tait d\u00e9j\u00e0 domin\u00e9e par l\u2019extr\u00eame droite avant m\u00eame l\u2019occupation allemande \u2014 avec la Garde de Fer, de sinistre m\u00e9moire, et la dictature d\u2019Antonescu.<\/p>\n\n\n\n<p>L\u2019antifascisme est ainsi apparu essentiellement comme un discours officiel impos\u00e9 de l\u2019ext\u00e9rieur par l\u2019occupant sovi\u00e9tique puis par la terrible dictature de Nicolae Ceau\u0219escu \u00e0 une soci\u00e9t\u00e9 qui lui est rest\u00e9e en r\u00e9alit\u00e9 largement imperm\u00e9able dans ses profondeurs.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/jjrxX\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Apr\u00e8s la chute du mur, les Roumains comme les autres habitants de l\u2019Est de l\u2019Europe, ont aussi v\u00e9cu les d\u00e9cennies suivantes comme celle d\u2019une conqu\u00eate imp\u00e9riale, bien que pacifique, par des Europ\u00e9ens de l\u2019Ouest, avides et arrogants, qui se sont appropri\u00e9s les richesses du pays. Ce sentiment de d\u00e9possession a probablement \u00e9t\u00e9 encore plus marqu\u00e9 en Roumanie, un pays rest\u00e9 tr\u00e8s rural, que dans d\u2019autres comme la Tch\u00e9quie qui avaient malgr\u00e9 tout d\u00e9j\u00e0 une r\u00e9elle culture industrielle et scientifique \u00e0 faire valoir.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/syJFa\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>La Roumanie a beau \u00eatre le deuxi\u00e8me pays de l\u2019Union o\u00f9 le PIB par habitant a le plus progress\u00e9 entre 2000 et 2024 derri\u00e8re la Lituanie, cela ne compense pas ce sentiment d\u2019une humiliation prolong\u00e9e subie depuis trente-cinq ans&#160;: elle reste toujours malgr\u00e9 cette progression le second pays le plus pauvre des 27 devant la Bulgarie.<\/p>\n\n\n\n<p>De plus, elle figure aussi parmi les pays d\u2019Europe qui ont perdu le plus de population avec une chute d\u00e9mographique de 18&#160;% entre 1990 et 2024&#160;: un Roumain sur cinq manque d\u00e9sormais \u00e0 l\u2019appel notamment du fait de l\u2019\u00e9migration.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/jHnhu\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Autrement dit, il n\u2019y a pas de quoi donner le sentiment qu\u2019un avenir radieux se pr\u00e9pare pour la Roumanie dans le cadre de l\u2019Union.<\/p>\n\n\n\n<p>Dans le contexte de la guerre contre l\u2019Ukraine, la Russie n&rsquo;appara\u00eet pas seulement aux Roumains comme un empire mena\u00e7ant.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/DJjKA\" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<p>Dans un pays rest\u00e9 d\u2019autant plus conservateur que ses jeunes sont partis, Moscou fait aussi volontiers figure de Mecque orthodoxe, susceptible de prot\u00e9ger des valeurs traditionnelles menac\u00e9es par une civilisation mat\u00e9rialiste occidentale d\u00e9prav\u00e9e. Ce sentiment, sur lequel la propagande poutinienne joue \u00e0 fond, est tr\u00e8s r\u00e9pandu dans l\u2019Europe orthodoxe.&nbsp;<\/p>\n\n\n\n<p>De plus, la guerre, l\u2019inflation et la crise \u00e9nerg\u00e9tique qu\u2019elle a suscit\u00e9es, ont particuli\u00e8rement touch\u00e9 des Roumains, rest\u00e9s comme beaucoup de leurs voisins de l\u2019Est de l\u2019Europe, tr\u00e8s d\u00e9pendants des combustibles fossiles russes. Entre le d\u00e9but 2022 et mars 2025, les prix ont augment\u00e9 de quasiment 30&#160;% en Roumanie, soit deux fois plus que dans la zone euro. L\u2019afflux de r\u00e9fugi\u00e9s ukrainiens a par ailleurs cr\u00e9\u00e9 des difficult\u00e9s suppl\u00e9mentaires pour les Roumains en mati\u00e8re de logement ou de march\u00e9 du travail. En janvier dernier, on d\u00e9nombrait 179&nbsp;200 r\u00e9fugi\u00e9s ukrainiens en Roumanie contre 55&nbsp;700 en France \u2014 c\u2019est moins de 0,1&#160;% de la population fran\u00e7aise mais 0,9&#160;% de la population roumaine, soit 10 fois plus.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>On voit mal comment la r\u00e9sistance de l\u2019Union face \u00e0 Trump et Poutine aurait pu survivre au basculement du domino roumain.<\/p><cite>Guillaume Duval<\/cite><\/blockquote><\/figure>\n\n\n\n<p>Enfin, l\u2019ouverture du march\u00e9 europ\u00e9en aux produits ukrainiens, notamment agricoles, sans droit de douane, d\u00e9cid\u00e9e pour soutenir l\u2019\u00e9conomie du pays pendant la guerre, a beaucoup affect\u00e9 les agricultures des pays limitrophes. Plus g\u00e9n\u00e9ralement la relative g\u00e9n\u00e9rosit\u00e9 europ\u00e9enne vis-\u00e0-vis de l\u2019Ukraine en guerre passe mal dans un pays qui reste l\u2019un des plus pauvres des 27. Les Roumains se sentent aujourd\u2019hui volontiers d\u00e9laiss\u00e9s par Bruxelles au profit des Ukrainiens. Sans oublier, comme en Hongrie, les s\u00e9quelles de vieux litiges frontaliers mal r\u00e9gl\u00e9s avec l\u2019Ukraine qui agitent les nostalgiques de la grande Roumanie d\u2019avant la seconde guerre mondiale.&nbsp;<\/p>\n\n\n\n<p>Bref, il est moins surprenant qu\u2019il peut y para\u00eetre de prime abord que l\u2019extr\u00eame droite pro-Poutine se renforce autant en Roumanie et dans d\u2019autres pays de l\u2019Est de l\u2019Europe.<\/p>\n\n\n\n<p>On rel\u00e8ve n\u00e9anmoins une donn\u00e9e int\u00e9ressante \u00e0 partir du vote de la diaspora&#160;: lorsqu\u2019on est un Roumain \u00e0 l\u2019\u00e9tranger, on a plus vot\u00e9 pour Simion \u00e0 l\u2019Ouest de l\u2019Europe qu\u2019\u00e0 l\u2019Est.<\/p>\n\n\n\n<div class=\"iframe-container wp-block-image wp-block-image-medium  iframe-dw\">\n\t<div>\n\t\t<iframe class=\"absolute w-full h-full pin-t pin-l\" title=\"titolo\" aria-label=\"Interactive line chart\" src=\"\/\/datawrapper.dwcdn.net\/AgDfi\/ \" scrolling=\"no\" frameborder=\"0\"><\/iframe>\n\t<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Le \u00ab&#160;coup de chaud&#160;\u00bb du 18 mai 2024<\/h2>\n\n\n\n<p>Avec la d\u00e9faite de l\u2019extr\u00eame droite en Roumanie, l\u2019Union a eu chaud.<\/p>\n\n\n\n<p>Avec 19 millions d&rsquo;habitants, c&rsquo;est un poids lourd d\u00e9mographique&#160;: le sixi\u00e8me pays de l&rsquo;Union par sa population derri\u00e8re l\u2019Allemagne, la France, l\u2019Italie, la Pologne et l\u2019Espagne. Aux c\u00f4t\u00e9s de Viktor Orban en Hongrie et Robert Fico en Slovaquie, l&rsquo;\u00e9lection de George Simion aurait transform\u00e9 tout le flanc sud-est de l&rsquo;Union, voisin direct de l\u2019Ukraine, en bastion pro-Trump et pro-Poutine.<\/p>\n\n\n\n<p>Certes, le Pr\u00e9sident Roumain ne dispose pas d\u2019autant de pouvoirs qu\u2019un Pr\u00e9sident de la R\u00e9publique fran\u00e7aise et l\u2019extr\u00eame droite n&rsquo;est pas encore majoritaire au Parlement roumain.<\/p>\n\n\n\n<p>Mais c&rsquo;est lui qui repr\u00e9sente le pays au Conseil des chefs d&rsquo;\u00c9tats et de gouvernement europ\u00e9ens. Et c&rsquo;est lui aussi qui propose le futur premier ministre roumain.&nbsp;<\/p>\n\n\n\n<p>Avec Orban et Fico, Simion aurait donc dispos\u00e9 des moyens de bloquer les d\u00e9cisions qui doivent \u00eatre prises \u00e0 l\u2019unanimit\u00e9 dans le cadre du Conseil europ\u00e9en \u2014 notamment celles qui touchent \u00e0 la politique \u00e9trang\u00e8re et de s\u00e9curit\u00e9 de l\u2019Union comme les sanctions contre la Russie de Poutine qui doivent \u00eatre renouvel\u00e9es au cours des prochaines semaines.&nbsp;<\/p>\n\n\n\n<p>Depuis 2022, l&rsquo;Union avait \u00e0 peu pr\u00e8s r\u00e9ussi \u00e0 circonvenir Viktor Orban \u2014 moyennant des concessions co\u00fbteuses \u00e0 chaque fois qu\u2019il faisait du chantage au blocage fonctionnel des institutions. Cela avait continu\u00e9 bon an mal an d&rsquo;\u00eatre le cas m\u00eame lorsqu\u2019il avait \u00e9t\u00e9 renforc\u00e9 par l&rsquo;arriv\u00e9e de Robert Fico autour de la table du Conseil europ\u00e9en en 2023. Mais on voit mal comment la r\u00e9sistance de l\u2019Union face \u00e0 Trump et Poutine aurait pu survivre au basculement du domino roumain.&nbsp;<\/p>\n\n\n\n<p>Elle aurait \u00e9t\u00e9 soumise \u00e0 rude \u00e9preuve par un dysfonctionnement de cette ampleur dans un contexte surd\u00e9termin\u00e9 par un contexte g\u00e9opolitique qui remet les Europ\u00e9ens face \u00e0 des questions existentielles&#160;: la guerre ou la paix&#160;; la vie ou la mort.<\/p>\n\n\n\n<p>Certes, jusqu\u2019ici la politique \u00e9trang\u00e8re et de d\u00e9fense a toujours jou\u00e9 un r\u00f4le subalterne. L\u2019essentiel des politiques communes europ\u00e9ennes tournent depuis bient\u00f4t soixante-dix ans autour de l\u2019\u00e9conomie&#160;: de l\u2019agriculture au commerce, en passant par la monnaie, la concurrence et les multiples r\u00e8gles \u00e0 respecter sur son march\u00e9 int\u00e9rieur\u2026 Ce sont des domaines dans lesquels les \u00c9tats membres de l&rsquo;Union ont consenti des abandons de souverainet\u00e9 consid\u00e9rables.<\/p>\n\n\n\n<p>La politique \u00e9trang\u00e8re et de d\u00e9fense est rest\u00e9e de la comp\u00e9tence des \u00c9tats qui ont tout juste accept\u00e9 d&rsquo;essayer de les coordonner \u00e0 l\u2019\u00e9chelle europ\u00e9enne, \u00e0 condition de respecter la r\u00e8gle de l\u2019unanimit\u00e9.&nbsp;<\/p>\n\n\n\n<p>Malgr\u00e9 ces apparences, le positionnement g\u00e9opolitique de l\u2019Europe dans les affrontements mondiaux a toujours \u00e9t\u00e9 en r\u00e9alit\u00e9 d\u00e9terminant pour le processus d&rsquo;int\u00e9gration europ\u00e9enne.<\/p>\n\n\n\n<p>S\u2019il s&rsquo;est enclench\u00e9 autour de l\u2019\u00e9conomie avec la CECA en 1950 puis la Communaut\u00e9 \u00e9conomique europ\u00e9enne en 1957, c\u2019est parce que les Europ\u00e9ens, \u00e9puis\u00e9s par deux guerres mondiales successives, voulaient garantir la paix entre eux en d\u00e9veloppant leurs interd\u00e9pendances \u00e9conomiques. Mais c\u2019est aussi \u2014 et probablement surtout dans la t\u00eate de la plupart des acteurs \u2014 parce que les dirigeants de l\u2019Europe de l\u2019Ouest voulaient serrer les rangs afin \u2014 d\u00e9j\u00e0 \u2014 de r\u00e9sister \u00e0 la menace russe. Tous consid\u00e9raient en effet l&rsquo;expansionnisme sovi\u00e9tique comme un danger mortel pour leur pays et les valeurs d\u00e9mocratiques qu\u2019ils d\u00e9fendaient.&nbsp;<\/p>\n\n\n\n<p>Ce regroupement s\u2019est fait autour de l\u2019\u00e9conomie plut\u00f4t que de la d\u00e9fense parce que, dix ans apr\u00e8s la fin de la Seconde Guerre mondiale, il \u00e9tait inimaginable de construire une arm\u00e9e europ\u00e9enne o\u00f9 des g\u00e9n\u00e9raux allemands auraient command\u00e9 \u00e0 des soldats fran\u00e7ais. La question de la s\u00e9curit\u00e9 en tant que telle \u00e9tait d\u2019ailleurs d\u00e9j\u00e0 r\u00e9gl\u00e9e \u00e0 l&rsquo;\u00e9poque par un \u00ab&#160;&nbsp;parapluie am\u00e9ricain&nbsp;&#160;\u00bb cr\u00e9dible. Il fallait surtout d\u00e9montrer que, sur le plan du d\u00e9veloppement \u00e9conomique et du bien-\u00eatre social, l&rsquo;ouest de l&rsquo;Europe pouvait faire beaucoup mieux que l&rsquo;est.<\/p>\n\n\n\n<p>Pour autant, si la construction europ\u00e9enne a \u00e9t\u00e9 possible, si tous ces abandons de souverainet\u00e9 successifs ont \u00e9t\u00e9 consentis sur le terrain de l\u2019\u00e9conomie, c\u2019est bien parce qu\u2019il existait ce consensus fondamental entre les Etats membres de l\u2019Union sur leur positionnement g\u00e9opolitique. Un consensus qui \u00e9tait partag\u00e9 y compris par le G\u00e9n\u00e9ral de Gaulle m\u00eame s\u2019il \u00e9tait nettement moins atlantiste que les autres Europ\u00e9ens.<\/p>\n\n\n\n<p>Apr\u00e8s la chute du mur, l&rsquo;Union a poursuivi sur sa lanc\u00e9e avec le march\u00e9 unique puis la monnaie unique.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Lorsqu\u2019on est un Roumain \u00e0 l\u2019\u00e9tranger, on a plus vot\u00e9 pour Simion \u00e0 l\u2019Ouest de l\u2019Europe qu\u2019\u00e0 l\u2019Est.<\/p><cite>Guillaume Duval<\/cite><\/blockquote><\/figure>\n\n\n\n<p>La question russe ne se posait plus vraiment mais le consensus des Europ\u00e9ens sur leur positionnement dans le monde \u00e9tait en r\u00e9alit\u00e9 maintenu autour d&rsquo;une croyance alors largement partag\u00e9e en une \u00ab&#160;fin de l&rsquo;histoire&#160;\u00bb o\u00f9 capitalisme et d\u00e9mocratie l&rsquo;auraient d\u00e9finitivement emport\u00e9&nbsp;<\/p>\n\n\n\n<p>Depuis le d\u00e9but des ann\u00e9es 2000, avec la mont\u00e9e en puissance de la Chine autocratique, les aventures am\u00e9ricaines en Irak et les tensions au sein du monde musulman, l&rsquo;agressivit\u00e9 croissante de Poutine, la premi\u00e8re pr\u00e9sidence Trump et les premi\u00e8res attaques contre l&rsquo;Europe&#160;; la question du positionnement g\u00e9opolitique de l&rsquo;Union avait fait un retour fracassant au premier plan du d\u00e9bat public europ\u00e9en.&nbsp;<\/p>\n\n\n\n<p>Cette interrogation est devenue existentielle avec la guerre d&rsquo;agression lanc\u00e9e par Vladimir Poutine contre l&rsquo;Ukraine et, d\u00e9sormais, la trahison ouverte de Donald Trump et J. D. Vance \u00e0 l&rsquo;\u00e9gard de l&rsquo;Europe.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Des polarisations internes \u00e0 l\u2019absence d\u2019un consensus sur la position g\u00e9opolitique de l\u2019Union<\/h2>\n\n\n\n<p>Mais il n&rsquo;existe plus de consensus aujourd&rsquo;hui entre Europ\u00e9ens sur la position \u00e0 adopter face \u00e0 leurs ennemis.<\/p>\n\n\n\n<p>On le constate en Hongrie et en Slovaquie mais aussi en Roumanie et en Bulgarie et \u00e0 l\u2019ext\u00e9rieur en Moldavie et dans les pays des Balkans, suppos\u00e9s rejoindre l\u2019Union prochainement. Ce dissensus est manifestement profond et massif dans tout un sous-ensemble de pays situ\u00e9s dans une r\u00e9gion strat\u00e9gique pour l&rsquo;Union.<\/p>\n\n\n\n<p>S\u2019il persistait, ce dissensus n&#8217;emp\u00eacherait pas seulement l&rsquo;Union de se doter d&rsquo;une politique ext\u00e9rieure et de d\u00e9fense digne de ce nom \u2014 et donc d&rsquo;exister en tant qu&rsquo;acteur g\u00e9opolitique sur la sc\u00e8ne mondiale \u2014 il risquerait aussi d&rsquo;entra\u00eener la remise en cause des autres politiques communes.<\/p>\n\n\n\n<p>Pourquoi continuer \u00e0 transf\u00e9rer des fonds vers des pays qui trahissent les int\u00e9r\u00eats et les valeurs de l&rsquo;Union au profit de ses adversaires&#160;?<\/p>\n\n\n\n<p>Pourquoi tol\u00e9rer plus longtemps le <em>dumping<\/em> \u2014 social et fiscal \u2014 qu&rsquo;ils exercent au sein de l&rsquo;Union&#160;?<\/p>\n\n\n\n<p>Pourquoi les laisser servir de t\u00eate de pont pour les firmes et les autres acteurs de nos ennemis au sein du march\u00e9 unique&#160;?<\/p>\n\n\n\n<p>Cette absence de consensus sur le positionnement g\u00e9opolitique de l&rsquo;Union risque bien d&rsquo;entra\u00eener \u00e0 terme la chute de l&rsquo;ensemble de la construction europ\u00e9enne.<\/p>\n\n\n\n<p>Pour \u00e9viter de voir l&rsquo;Union se d\u00e9faire, il faut tout d\u2019abord prendre pleinement conscience des risques que comporte l\u2019\u00e9volution de la situation dans beaucoup de pays d\u2019Europe centrale et orientale, ce qui est encore loin d&rsquo;\u00eatre le cas pour l&rsquo;instant.&nbsp;<\/p>\n\n\n\n<p>Et il faut ensuite en tirer les cons\u00e9quences, en ce qui concerne les politiques sp\u00e9cifiques \u00e0 mener vis-\u00e0-vis de ces pays, qui n\u2019entendent plus d\u00e9sormais s\u2019en laisser compter par les pays de l\u2019Ouest de l\u2019Europe \u2014 comme en ce qui concerne l&rsquo;urgence de r\u00e9former en profondeur les r\u00e8gles institutionnelles qui r\u00e9gissent l&rsquo;Union pour \u00e9viter sa paralysie, malgr\u00e9 tous les risques et complications que suppose un tel processus.<\/p>\n\n\n\n<p>Le fait que l\u2019\u00e9lection d\u2019un pr\u00e9sident roumain pro-Trump et pro-Poutine ait pu \u00eatre \u00e9vit\u00e9e cette fois-ci ne dispense pas l\u2019Union de cette remise en cause indispensable. Au contraire.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dimanche soir, l\u2019Union europ\u00e9enne est pass\u00e9e \u00e0 900 000 voix de basculer.<\/p>\n<p>Si, pour Guillaume Duval, il faut se r\u00e9jouir d\u2019avoir vu Nicusor Dan l\u2019emporter, le fait qu\u2019un candidat ouvertement t\u00e9l\u00e9guid\u00e9 par Washington et Moscou ait pu s\u2019approcher \u00e0 ce point du pouvoir dans un pays aussi vital pour la s\u00e9curit\u00e9 du continent est une alerte s\u00e9rieuse.<\/p>\n","protected":false},"author":10,"featured_media":280016,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/post-angles.php","format":"standard","meta":{"_acf_changed":true,"_trash_the_other_posts":false,"_yoast_wpseo_estimated-reading-time-minutes":10,"footnotes":""},"categories":[4462],"tags":[],"staff":[4180],"editorial_format":[4944],"serie":[],"audience":[],"geo":[1917],"class_list":["post-280015","post","type-post","status-publish","format-standard","hentry","category-election-presidentielle-en-roumanie","staff-guillaume-duval","editorial_format-actu-longues","geo-europe"],"acf":{"open_in_webview":false,"accent":false,"_thumbnail_id":280016,"excerpt":"Dimanche soir, l\u2019Union europ\u00e9enne est pass\u00e9e \u00e0 900 000 voix de basculer.\r\n\r\nSi, pour Guillaume Duval, il faut se r\u00e9jouir d\u2019avoir vu Nicusor Dan l\u2019emporter, le fait qu\u2019un candidat ouvertement t\u00e9l\u00e9guid\u00e9 par Washington et Moscou ait pu s\u2019approcher \u00e0 ce point du pouvoir dans un pays aussi vital pour la s\u00e9curit\u00e9 du continent est une alerte s\u00e9rieuse.","display_date":"","new_abstract":true},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Roumanie\u00a0: le coup de semonce Simion ne doit pas rester sans cons\u00e9quences | Le Grand Continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/19\/roumanie-le-coup-de-semonce-simion-ne-doit-pas-rester-sans-consequences\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Roumanie\u00a0: le coup de semonce Simion ne doit pas rester sans cons\u00e9quences | Le Grand Continent\" \/>\n<meta property=\"og:description\" content=\"Dimanche soir, l\u2019Union europ\u00e9enne est pass\u00e9e \u00e0 900 000 voix de basculer.  Si, pour Guillaume Duval, il faut se r\u00e9jouir d\u2019avoir vu Nicusor Dan l\u2019emporter, le fait qu\u2019un candidat ouvertement t\u00e9l\u00e9guid\u00e9 par Washington et Moscou ait pu s\u2019approcher \u00e0 ce point du pouvoir dans un pays aussi vital pour la s\u00e9curit\u00e9 du continent est une alerte s\u00e9rieuse.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/19\/roumanie-le-coup-de-semonce-simion-ne-doit-pas-rester-sans-consequences\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Grand Continent\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-19T14:23:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-19T16:50:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/gc-simion-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matheo Malik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/gc-simion-1-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheo Malik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/19\/roumanie-le-coup-de-semonce-simion-ne-doit-pas-rester-sans-consequences\/\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/19\/roumanie-le-coup-de-semonce-simion-ne-doit-pas-rester-sans-consequences\/\",\"name\":\"Roumanie\u00a0: le coup de semonce Simion ne doit pas rester sans cons\u00e9quences | Le Grand Continent\",\"isPartOf\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/19\/roumanie-le-coup-de-semonce-simion-ne-doit-pas-rester-sans-consequences\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/19\/roumanie-le-coup-de-semonce-simion-ne-doit-pas-rester-sans-consequences\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_ap22958728_000009-scaled.jpg\",\"datePublished\":\"2025-05-19T14:23:54+00:00\",\"dateModified\":\"2025-05-19T16:50:51+00:00\",\"author\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\"},\"breadcrumb\":{\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/19\/roumanie-le-coup-de-semonce-simion-ne-doit-pas-rester-sans-consequences\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/19\/roumanie-le-coup-de-semonce-simion-ne-doit-pas-rester-sans-consequences\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/19\/roumanie-le-coup-de-semonce-simion-ne-doit-pas-rester-sans-consequences\/#primaryimage\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_ap22958728_000009-scaled.jpg\",\"contentUrl\":\"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_ap22958728_000009-scaled.jpg\",\"width\":2560,\"height\":1706,\"caption\":\"\u00a9 AP Photo\/Vadim Ghirda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/19\/roumanie-le-coup-de-semonce-simion-ne-doit-pas-rester-sans-consequences\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/legrandcontinent.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Roumanie&#160;: le coup de semonce Simion ne doit pas rester sans cons\u00e9quences\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#website\",\"url\":\"https:\/\/legrandcontinent.eu\/fr\/\",\"name\":\"Le Grand Continent\",\"description\":\"L&#039;\u00e9chelle pertinente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45\",\"name\":\"Matheo Malik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g\",\"caption\":\"Matheo Malik\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Roumanie\u00a0: le coup de semonce Simion ne doit pas rester sans cons\u00e9quences | Le Grand Continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/19\/roumanie-le-coup-de-semonce-simion-ne-doit-pas-rester-sans-consequences\/","og_locale":"fr_FR","og_type":"article","og_title":"Roumanie\u00a0: le coup de semonce Simion ne doit pas rester sans cons\u00e9quences | Le Grand Continent","og_description":"Dimanche soir, l\u2019Union europ\u00e9enne est pass\u00e9e \u00e0 900 000 voix de basculer.  Si, pour Guillaume Duval, il faut se r\u00e9jouir d\u2019avoir vu Nicusor Dan l\u2019emporter, le fait qu\u2019un candidat ouvertement t\u00e9l\u00e9guid\u00e9 par Washington et Moscou ait pu s\u2019approcher \u00e0 ce point du pouvoir dans un pays aussi vital pour la s\u00e9curit\u00e9 du continent est une alerte s\u00e9rieuse.","og_url":"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/19\/roumanie-le-coup-de-semonce-simion-ne-doit-pas-rester-sans-consequences\/","og_site_name":"Le Grand Continent","article_published_time":"2025-05-19T14:23:54+00:00","article_modified_time":"2025-05-19T16:50:51+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/gc-simion-1-scaled.jpg","type":"image\/jpeg"}],"author":"Matheo Malik","twitter_card":"summary_large_image","twitter_image":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/gc-simion-1-scaled.jpg","twitter_misc":{"\u00c9crit par":"Matheo Malik","Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/19\/roumanie-le-coup-de-semonce-simion-ne-doit-pas-rester-sans-consequences\/","url":"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/19\/roumanie-le-coup-de-semonce-simion-ne-doit-pas-rester-sans-consequences\/","name":"Roumanie\u00a0: le coup de semonce Simion ne doit pas rester sans cons\u00e9quences | Le Grand Continent","isPartOf":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/19\/roumanie-le-coup-de-semonce-simion-ne-doit-pas-rester-sans-consequences\/#primaryimage"},"image":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/19\/roumanie-le-coup-de-semonce-simion-ne-doit-pas-rester-sans-consequences\/#primaryimage"},"thumbnailUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_ap22958728_000009-scaled.jpg","datePublished":"2025-05-19T14:23:54+00:00","dateModified":"2025-05-19T16:50:51+00:00","author":{"@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45"},"breadcrumb":{"@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/19\/roumanie-le-coup-de-semonce-simion-ne-doit-pas-rester-sans-consequences\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/legrandcontinent.eu\/fr\/2025\/05\/19\/roumanie-le-coup-de-semonce-simion-ne-doit-pas-rester-sans-consequences\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/19\/roumanie-le-coup-de-semonce-simion-ne-doit-pas-rester-sans-consequences\/#primaryimage","url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_ap22958728_000009-scaled.jpg","contentUrl":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_ap22958728_000009-scaled.jpg","width":2560,"height":1706,"caption":"\u00a9 AP Photo\/Vadim Ghirda"},{"@type":"BreadcrumbList","@id":"https:\/\/legrandcontinent.eu\/fr\/2025\/05\/19\/roumanie-le-coup-de-semonce-simion-ne-doit-pas-rester-sans-consequences\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/legrandcontinent.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Roumanie&#160;: le coup de semonce Simion ne doit pas rester sans cons\u00e9quences"}]},{"@type":"WebSite","@id":"https:\/\/legrandcontinent.eu\/fr\/#website","url":"https:\/\/legrandcontinent.eu\/fr\/","name":"Le Grand Continent","description":"L&#039;\u00e9chelle pertinente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legrandcontinent.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/a1c2123a1ef5abd663fcde8f63063d45","name":"Matheo Malik","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/legrandcontinent.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62cbadb9f7f0804282928747d8d2051d?s=96&d=mm&r=g","caption":"Matheo Malik"}}]}},"lgc_categories":[{"id":4462,"name":"\u00c9lection pr\u00e9sidentielle en Roumanie","slug":"election-presidentielle-en-roumanie"}],"lgc_author":{"id":4180,"name":"Guillaume Duval","slug":"guillaume-duval","description":"Guillaume Duval est ancien speechwriter du HR\/VP Josep Borrell, ancien r\u00e9dacteur en chef d'Alternatives \u00c9conomiques et conseiller aupr\u00e8s de l'Institut Jacques Delors. Il est l'auteur de \"Made in Germany, le mod\u00e8le allemand au del\u00e0 des mythes\" aux \u00e9ditions du Seuil.","first_name":"Guillaume","last_name":"Duval","picture":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2024\/12\/gc-GuillaumeDuval-1.png","width":222,"height":222,"alt":""}},"feature_image_summary":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_ap22958728_000009-scaled.jpg","width":2560,"height":1706,"alt":""},"feature_image_cover":{"url":"https:\/\/legrandcontinent.eu\/fr\/wp-content\/uploads\/sites\/2\/2025\/05\/SIPA_ap22958728_000009-scaled.jpg","width":2560,"height":1706,"alt":""},"term_position_data":null,"_links":{"self":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/280015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/comments?post=280015"}],"version-history":[{"count":0,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/posts\/280015\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media\/280016"}],"wp:attachment":[{"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/media?parent=280015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/categories?post=280015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/tags?post=280015"},{"taxonomy":"staff","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/staff?post=280015"},{"taxonomy":"editorial_format","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/editorial_format?post=280015"},{"taxonomy":"serie","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/serie?post=280015"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/audience?post=280015"},{"taxonomy":"geo","embeddable":true,"href":"https:\/\/legrandcontinent.eu\/fr\/wp-json\/wp\/v2\/geo?post=280015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}